{"id":78457,"date":"2019-02-08T10:32:55","date_gmt":"2019-02-08T10:32:55","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/08\/leurope-emportee-dans-son-tourbillon-crisique\/"},"modified":"2019-02-08T10:32:55","modified_gmt":"2019-02-08T10:32:55","slug":"leurope-emportee-dans-son-tourbillon-crisique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/08\/leurope-emportee-dans-son-tourbillon-crisique\/","title":{"rendered":"L&rsquo;Europe emport\u00e9e dans son \u201ctourbillon crisique\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;Europe emport\u00e9e dans son \u00ab\u00a0tourbillon crisique\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Il est manifeste que le pays aujourd&rsquo;hui le plus \u00e0 l&rsquo;aise en Europe pour la man&oelig;uvre politique pouvant amener des gains consid\u00e9rables, c&rsquo;est sans aucun doute l&rsquo;Italie. Son terrain d&rsquo;essai favori, son \u00ab\u00a0souffre-douleur\u00a0\u00bb principal, c&rsquo;est sans aucun doute la France : l&rsquo;Italie de Di Maio-Salvini joue avec la France de Macron comme un chat avec une souris, &ndash; et cela quoi qu&rsquo;on pense des gains ou des pertes tactiques de la politique suivie par l&rsquo;un ou l&rsquo;autre leader italien ; <a href=\"http:\/\/www.dedefensa.org\/article\/litalie-base-arriere-des-gj\">l&rsquo;essentiel<\/a> est bien dans <strong><a href=\"http:\/\/www.dedefensa.org\/article\/notes-de-salvini-a-macron\">l&rsquo;affrontement<\/a> du \u00ab\u00a0mod\u00e8le populiste italien\u00a0\u00bb et du \u00ab\u00a0mod\u00e8le antipopuliste fran\u00e7ais\u00a0\u00bb assi\u00e9g\u00e9 par le populisme fran\u00e7ais<\/strong>.<\/p>\n<\/p>\n<p><p>(Il existe par ailleurs un contentieux important entre Fran\u00e7ais et Italiens dans les affaires internationales : les relations avec la Russie, la Libye en 2011, les migrants, etc., tout un ensemble que rappelle <em>WSWS.org <\/em>dans un article de ce <a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/02\/08\/pers-f08.html\">8 f\u00e9vrier 2019<\/a>. Mais pour notre compte, nous pensons que l&rsquo;enjeu qui prime tout, balaye toutes les autres consid\u00e9rations et concerne directement les deux pays, y compris dans le m\u00eame sens, est <strong>la situation totalement nouvelle cr\u00e9\u00e9e par le gouvernement populiste \u00e0 Rome et la crise des Gilets-Jaunes en France<\/strong>.)<\/p>\n<\/p>\n<p><p>Le triumvirat italien joue sa pi\u00e8ce \u00e0 merveille. Di Maio, le Vice-Premier du M5S, joue \u00e0 fond les Gilets-Jaunes parce qu&rsquo;il trouve en eux une r\u00e9plique parfaite des m\u00e9thodes d&rsquo;action des 5 Etoiles, dans cette d\u00e9marche de \u00ab\u00a0d\u00e9mocratie par le bas\u00a0\u00bb et juge que c&rsquo;est ainsi renforcer son mouvement en Italie, en perte de vitesse vis-\u00e0-vis de <em>La Liga<\/em>. Salvini, lui, travaille au niveau europ\u00e9en, pour r\u00e9aliser un rassemblement populiste. <strong>Les deux partis populistes sont concurrents en un sens mais ils ont pour l&rsquo;instant tout int\u00e9r\u00eat \u00e0 travailler de conserve, contre les croutes diverses qui peuplent le rassemblement devenu grotesque de l&rsquo;UE<\/strong>. L&rsquo;\u00e9l\u00e9gant Premier ministre Conte est certes une potiche, mais il n&rsquo;est nullement inutile quand les circonstances le permettent, en prodiguant aupr\u00e8s des pays \u00e9trangers qui se sentent touch\u00e9s par ces remous des bonnes paroles que l&rsquo;on finit en g\u00e9n\u00e9ral par entendre&#8230;<\/p>\n<\/p>\n<p><p>La derni\u00e8re intervention pol\u00e9mique <a href=\"https:\/\/francais.rt.com\/france\/58835-luigi-di-maio-annonce-avoir-rencontre-leader-gilets-jaunes-conteste-sein-mouvement\">est celle de Di Maio<\/a>, avec des Gilets-Jaunes eux-m\u00eames objets de contestation en France (ce dont Di Maio n&rsquo;a cure, puisqu&rsquo;il ne consid\u00e8re que l&rsquo;aspect symbolique des  GJ contre la direction fran\u00e7aise)&#8230; &laquo; <em>Luigi Di Maio, vice-pr\u00e9sident du Conseil des ministres italien, s&rsquo;est f\u00e9licit\u00e9, dans un tweet publi\u00e9 ce 5 f\u00e9vrier, d&rsquo;avoir rencontr\u00e9 \u00ab\u00a0le leader des gilets jaunes Christophe Chalen\u00e7on et les candidats aux \u00e9lections europ\u00e9ennes de la liste RIC d&rsquo;Ingrid Levavasseur\u00a0\u00bb. \u00ab\u00a0Le vent du changement a travers\u00e9 les Alpes.\u00a0\u00bb a-t-il comment\u00e9<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Le leader du mouvement 5 \u00e9toiles ne tarit pas d&rsquo;enthousiasme dans sa publication et pour cause, cette rencontre s&rsquo;inscrit dans un contexte \u00e9lectoral europ\u00e9en imminent. De fait, la liste de \u00ab\u00a0ralliement d&rsquo;initiative citoyenne\u00a0\u00bb (RIC), compos\u00e9e de Gilets jaunes, a \u00e9t\u00e9 <a href=\"https:\/\/francais.rt.com\/france\/58329-gilets-jaunes-vont-presenter-liste-europeennes\">confirm\u00e9e le 24 janvier dernier<\/a>, quatre mois avant les \u00e9lections europ\u00e9ennes. Si la d\u00e9marche est salu\u00e9e par Luigi Di Maio, il est \u00e0 noter qu&rsquo;elle peine \u00e0 susciter l&rsquo;engouement du mouvement citoyen. Les choix politiques pass\u00e9s de certains des premiers membres de la liste &lsquo;RIC&rsquo; inqui\u00e8tent particuli\u00e8rement les Gilets jaunes<\/em>. <\/p>\n<\/p>\n<p><p>&raquo; <em>R\u00e9agissant au tweet de Luigi Di Maio, le journaliste de Lib\u00e9ration Vincent Glad a not\u00e9 la pr\u00e9sence sur la photo d&rsquo;une autre figure contest\u00e9e au sein des Gilets jaunes, celle de Marc Doyer. \u00ab\u00a0On retrouve m\u00eame \u00e0 gauche sur la photo Marc Doyer, l&rsquo;ancien macroniste devenu gilet jaune avant de se retirer de la liste RIC sous la pression de la base\u00a0\u00bb commente-t-il<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette fois, ou dans tous les cas pour l&rsquo;instant, l&rsquo;intervention de Conte n&rsquo;a pas r\u00e9ussi \u00e0 voir se lever un orage s\u00e9v\u00e8re entre la Franc et l&rsquo;Italie \u00e0 la suite de l&rsquo;initiative de Di Maio, &ndash; ou bien disons qu&rsquo;elle n&rsquo;a pas encore le temps de faire sentir ses effets puisqu&rsquo;elle n&rsquo;a pas eu lieu officiellement. La France a rappel\u00e9 son ambassadeur \u00e0 Rome, pour la premi\u00e8re fois <a href=\"https:\/\/francais.rt.com\/international\/58869-france-rappelle-son-ambassadeur-italie\">depuis 70 ans<\/a>, c&rsquo;est-\u00e0-dire depuis la chute de Mussolini et l&rsquo;installation de l&rsquo;actuel r\u00e9gime d\u00e9mocratique.<\/p>\n<\/p>\n<p><p>&laquo; <em>Le minist\u00e8re des Affaires \u00e9trang\u00e8res fran\u00e7ais <a href=\"https:\/\/www.diplomatie.gouv.fr\/fr\/dossiers-pays\/italie\/evenements\/article\/italie-rappel-de-l-ambassadeur-de-france-pour-consultations-07-02-19\" target=\"_blank\">a annonc\u00e9<\/a> avoir rappel\u00e9 son ambassadeur en Italie pour des \u00ab\u00a0consultations\u00a0\u00bb ce 7 f\u00e9vrier, d\u00e9non\u00e7ant des \u00ab\u00a0accusations r\u00e9p\u00e9t\u00e9es, d<\/em>[es]<em>attaques sans fondements, d<\/em>[es] <em>d\u00e9clarations outranci\u00e8res\u00a0\u00bb qui n&rsquo;ont \u00ab\u00a0pas de pr\u00e9c\u00e9dent depuis la fin de la guerre\u00a0\u00bb. Le communiqu\u00e9 du Quai d&rsquo;Orsay pointe \u00e9galement du doigt &laquo;les derni\u00e8res ing\u00e9rences&raquo; italiennes qui &laquo;constituent une provocation suppl\u00e9mentaire et inacceptable&raquo;, faisant certainement r\u00e9f\u00e9rence <a href=\"https:\/\/francais.rt.com\/france\/58835-luigi-di-maio-annonce-avoir-rencontre-leader-gilets-jaunes-conteste-sein-mouvement\">\u00e0 la rencontre<\/a>, le 5 f\u00e9vrier, entre le vice-pr\u00e9sident du Conseil italien Luigi di Maio et des repr\u00e9sentants de Gilets jaunes. Une rencontre d\u00e9j\u00e0 qualifi\u00e9e de \u00ab\u00a0provocation\u00a0\u00bb d\u00e8s le 6 f\u00e9vrier<\/em>[par le Quai d&rsquo;Orsay]<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Tous ces actes cr\u00e9ent une situation grave qui interroge les intentions du gouvernement italien vis-\u00e0-vis de sa relation avec la France\u00a0\u00bb, estime en outre le Quai d&rsquo;Orsay, avant d&rsquo;annoncer sa d\u00e9cision de rappeler l&rsquo;ambassadeur de France en Italie, Christian Masset. Le communiqu\u00e9 se conclut par un appel \u00e0 son voisin italien \u00e0 \u00ab\u00a0retrouver la relation d&rsquo;amiti\u00e9 et de respect r\u00e9ciproque\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Les relations entre la France et l&rsquo;Italie ont ainsi <strong>atteint un point de tensions sans pr\u00e9c\u00e9dent entre deux &Eacute;tats-Membres de l&rsquo;UE<\/strong>, et cela nullement sur un contentieux objectif, sur une question de forme de type institutionnel ou organisationnel, <strong>mais certes sur une question de fond qui constitue le cioeur de notre Grande Crise d&rsquo;Effondrement du Syst\u00e8me<\/strong>. Nous disons \u00ab\u00a0point de tension\u00a0\u00bb et nullement \u00ab\u00a0point de rupture\u00a0\u00bb puisque nous sommes au sein de l&rsquo;UE et cela impose des liens et des affrontements excluant la rupture au sens classique de la diplomatie. Cette situation engendre des effets particuliers. L&rsquo;appartenance commune \u00e0 l&rsquo;UE n&rsquo;implique nullement dans ce cas un m\u00e9canisme d&rsquo;apaisement venant surmonter l&rsquo;affrontement ; au contraire, en maintenant ces liens particuliers \u00e0 l&rsquo;UE, y compris avec rappel d&rsquo;ambassadeur, <strong>cette situation permet \u00e0 l&rsquo;affrontement de se poursuivre, donc de s&rsquo;aggraver, si l&rsquo;un ou l&rsquo;autre des protagonistes l&rsquo;entend ainsi<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cet affrontement entre l&rsquo;Italie et la France nous appara&icirc;t justement exceptionnel par sa gravit\u00e9 formelle et politique \u00e0 la fois, entre deux pays d&rsquo;une Union si vant\u00e9e pour sa coh\u00e9sion et dans laquelle la coh\u00e9sion porteuse d&rsquo;une n\u00e9cessaire marche vers l&rsquo;int\u00e9gration repr\u00e9sente un enjeu central de la stabilit\u00e9 de l&rsquo;ensemble, <strong>et tout cela plus encore entre deux pays du noyau initial de l&rsquo;Europe<\/strong>. D&rsquo;autre part, il faut consid\u00e9rer combien cette exceptionnalit\u00e9 de l&rsquo;affrontement France-Italie correspond en v\u00e9rit\u00e9 \u00e0 un affrontement politique fondamental et compl\u00e8tement exemplaire du grand affrontement en cours au c&oelig;ur du Syst\u00e8me entre deux pays exemplaire par leurs caract\u00e8res autant que par leurs poids politiques respectifs :<\/p>\n<\/p>\n<p><p>&bull; La France de Macron, particuli\u00e8rement et exceptionnellement dans le chef de ce pr\u00e9sident, se trouve \u00eatre selon nous dans les circonstances pr\u00e9sentes le pays du <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> <strong>le plus soumis au Syst\u00e8me du fait de la subversion cherchant \u00e0 susciter un effondrement de sa psychologie collective <\/strong>conduite sous une pression d&rsquo;une force sans pr\u00e9c\u00e9dent par une \u00e9quipe dont l&rsquo;entreprise est sans aucun doute de type d\u00e9moniaque. Dans ce cas, la France appara&icirc;t comme le pays le plus engag\u00e9 dans la voie de la soumission au Syst\u00e8me dans sa transcription op\u00e9rationnelle, par ses voies \u00e0 elle qui prennent en g\u00e9n\u00e9ral l&rsquo;allure qu&rsquo;on conna&icirc;t d\u00e9j\u00e0 d&rsquo;une soumission \u00e0 l&rsquo;Allemagne.  (Voir le texte de R\u00e9gis de Castelnau, du <a href=\"http:\/\/www.vududroit.com\/2019\/01\/macron-lexecution-de-feuille-de-route-prix-de-nos-libertes\/\">31 janvier 2019<\/a> sur <em>VuduDroit<\/em>.) Bien entendu et en contrepartie radicale qui fait heureusement constater que l&rsquo;attaque du Syst\u00e8me se fait dans une situation absolument effervescente du fait de cette attaque, ce m\u00eame pays est l&rsquo;objet <strong>d&rsquo;un mouvement de r\u00e9sistance antiSyst\u00e8me d&rsquo;une puissance et d&rsquo;une originalit\u00e9 consid\u00e9rables, \u00e0 mesure de l&rsquo;orientation satanique <\/strong>impos\u00e9e par sa direction.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;Italie de Di Maio-Salvini constitue le premier pays d&rsquo;une r\u00e9elle puissance, et d&rsquo;un poids incontestable, qui s&rsquo;est structur\u00e9 selon les conceptions populistes qui l&rsquo;orientent n\u00e9cessairement vers l&rsquo;antiSyst\u00e8me, sans rencontrer au niveau national d&rsquo;opposition-Syst\u00e8me r\u00e9ellement efficace, notamment dans le champ d&rsquo;affrontement de la communication. Selon cette logique d&rsquo;affrontement dans le cadre de l&rsquo;activisme Syst\u00e8me-antiSyst\u00e8me, <strong>l&rsquo;Italie semble suivre une politique d&rsquo;agression ouverte contre la France<\/strong>, toujours selon les normes du temps qui privil\u00e9gient le terrain de la communication bien s&ucirc;r. En un sens, <strong>l&rsquo;affrontement France-Italie a une importance symbolique exceptionnelle au c&oelig;ur de l&rsquo;Europe et au c&oelig;ur du Syst\u00e8me<\/strong> ; et dans cet affrontement, l&rsquo;Italie attaque la France de fa\u00e7on ouverte, comme si elle identifiait le pays dont la direction suit la voie la plus d\u00e9moniaque, donc n\u00e9cessitant une attaque frontale.<\/p>\n<\/p>\n<p><p>Du c\u00f4t\u00e9 des institutions europ\u00e9ennes, <strong>on n&rsquo;est pas en reste dans une situation d&rsquo;extr\u00eame tension<\/strong>, m\u00eame si les attitudes d&rsquo;une extr\u00eame inqui\u00e9tude sont conduites d&rsquo;une fa\u00e7on beaucoup plus structur\u00e9e, en un sens dans une forme beaucoup plus stable et retenue que les affrontements entre les &Eacute;tats-Membres. Pour autant, la gravit\u00e9 des conflits en cours n&rsquo;est pas moindre, et <strong>peut-\u00eatre est-elle m\u00eame r\u00e9alis\u00e9e dans toute leur extr\u00eame gravit\u00e9 beaucoup plus que dans les &Eacute;tats-Membres impliqu\u00e9s<\/strong>.<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on tr\u00e8s imag\u00e9e et pour rester dans le registre \u00e9sot\u00e9rique, nous dirions que l&rsquo;\u00e9tat d&rsquo;esprit des directions institutionnelles d\u00e9bat autour de la question de l&rsquo;enfer&#8230; Effectivement, on se bouscule au portillon pour savoir qui, dans la direction europ\u00e9enne, est <a href=\"https:\/\/www.rt.com\/news\/450835-juncker-hell-brexit-tusk\/\">le plus proche de l&rsquo;enfer<\/a>. Pour le pr\u00e9sident Donald Tusk, le Royaume-Uni, totalement \u00e0 la d\u00e9rive pour le <em>Brexit<\/em>, navigue sur les rives de l&rsquo;Enfer. A c\u00f4t\u00e9 de cela, son complice Jean-Claude Juncker philosophe dans le m\u00eame sens, mais pour son propre compte.<\/p>\n<\/p>\n<p><p><strong>Donc, si pour Tusk l&rsquo;enfer c&rsquo;est les autres, &ndash; les Anglais, &ndash; pour Juncker, l&rsquo;enfer c&rsquo;est lui-m\u00eame, &ndash; c&rsquo;est-\u00e0-dire, le travail qu&rsquo;il fait, l&rsquo;action de la Commission<\/strong>&#8230;  &laquo; <em>Je me demandais \u00e0 quoi ressemblait cet endroit sp\u00e9cial en enfer pour ceux qui ont promu le Brexit sans m\u00eame un sch\u00e9ma d&rsquo;un plan pour le r\u00e9aliser en toute s\u00e9curit\u00e9<\/em> &raquo;, a d\u00e9clar\u00e9 Tusk, sugg\u00e9rant que maintenant il sait, car il n&rsquo;y a qu&rsquo;\u00e0 regarder le Royaume-Unis dans tous ses \u00e9bats et ses n\u00e9gociations avec Cerb\u00e8re. L\u00e0-dessus, Juncker a rench\u00e9ri mais dans le sens o&ugrave; l&rsquo;enfer c&rsquo;est lui-m\u00eame, comme s&rsquo;il \u00e9tait son propre Cerb\u00e8re, une chope \u00e0 la main : &laquo; <em>Je suis moins catholique que mon bon ami Donald. Il croit fermement au paradis et par opposition \u00e0 l&rsquo;enfer. Je crois au paradis et je n&rsquo;ai jamais vu l&rsquo;enfer, mis \u00e0 part le temps o&ugrave; je faisais mon travail ici, &ndash; car ici c&rsquo;est bien l&rsquo;enfer<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Actuellement, des sources dans les institutions europ\u00e9ennes signalent un changement remarquable dans la forme des pr\u00e9occupations gravissimes en cours. La situation habituelle a toujours \u00e9t\u00e9 que les institutions tenaient une ligne plut\u00f4t id\u00e9ologique optimiste et pleine d&rsquo;allant, confiant dans leur puissance et leur capacit\u00e9 pour conduire les &Eacute;tats-Membres \u00e0 cesser leur contestations, leurs querelles, etc. <strong>pour se regrouper dans l&rsquo;ensemble institutionnel qu&rsquo;offre l&rsquo;UE<\/strong>. Les passages difficiles dans tel(s) et tel(s) &Eacute;tats-Membres \u00e9taient consid\u00e9r\u00e9s en g\u00e9n\u00e9ral avec un r\u00e9alisme id\u00e9oilogique optimiste parce qu&rsquo;un \u00e9v\u00e9nement institutionnel marquait la limite de la crise et nul ne doutait dans la bureaucratie bruxelloise que le retour aux normes europ\u00e9ennes l&#8217;emporterait. Aujourd&rsquo;hui, <strong>le r\u00e9alisme id\u00e9ologique bruxellois alimente plut\u00f4t un profond pessimisme<\/strong>, notamment dans deux crises, &ndash; celle du <em>Brexit <\/em>avec le Royaume-Uni et celle des Gilets-Jaunes et toutes les incertitudes satellites dont la France est secou\u00e9e.<\/p>\n<\/p>\n<p><p>La position tr\u00e8s dure de l&rsquo;UE dans le <em>Brexit <\/em>a moins \u00e0 voir avec un compte \u00e0 r\u00e9gler avec le Royaume-Uni, et une victoire \u00e0 emporter pour l&rsquo;UE, qu&rsquo;avec la crainte-panique \u00e0 Bruxelles qu&rsquo;un <em>Brexit <\/em>r\u00e9ussi gr\u00e2ce \u00e0 des concessions de l&rsquo;UE donnerait \u00e0 d&rsquo;autres pays l&rsquo;id\u00e9e de tenter \u00e0 leur tour la sortie de l&rsquo;UE. Selon le jugement de John Laughland, &laquo; <em>l&rsquo;UE doit tout faire pour que le Brexit \u00e9choue et que la s\u00e9paration se fasse dans le chaos, pour \u00e9viter une r\u00e9action en cha&icirc;ne avec d&rsquo;autres pays membres<\/em> &raquo;. Dans le cas fran\u00e7ais qui est l&rsquo;autre crise qui les inqui\u00e8te, \u00e0 Bruxelles centre de l&rsquo;Europe, l&rsquo;id\u00e9e d&rsquo;un r\u00e9f\u00e9rendum pour sanctionner le \u00ab\u00a0Grand D\u00e9bat\u00a0\u00bb en cours, destin\u00e9 \u00e0 mettre un terme \u00e0 la crise des GJ est loin de rassurer la bureaucratie. Nul ne sait si cette crise peut \u00eatre arr\u00eat\u00e9e de cette fa\u00e7on, et nul ne sait surtout si un r\u00e9f\u00e9rendum (sur quoi ? Sur quelle(s) question(s) ? Etc.) <strong>ne donnerait pas l&rsquo;effet contraire d&rsquo;acc\u00e9l\u00e9rer la crise<\/strong>. Les pr\u00e9c\u00e9dents extr\u00eamement r\u00e9cents et encore presque br&ucirc;lants <strong>sont terriblement f\u00e2cheux<\/strong> : c&rsquo;est l&rsquo;id\u00e9e de Cameron de soumettre l&rsquo;id\u00e9e du <em>Brexit <\/em>\u00e0 r\u00e9f\u00e9rendum (juin 2016) pour liquider l&rsquo;id\u00e9e, qui a abouti au r\u00e9sultat inverse ; c&rsquo;est un r\u00e9f\u00e9rendum sur une r\u00e9forme constitutionnelle (d\u00e9cembre 2016)  qui a eu la peau de Matteo Renzi et a ouvert la crise italienne accouchant du premier gouvernement populiste G5S-<em>Liga.<\/em><\/p>\n<\/p>\n<p><p>Jusqu&rsquo;ici si assur\u00e9e de sa puissance, l&rsquo;UE a, aujourd&rsquo;hui, brusquement peur de son destin.<\/p>\n<\/p>\n<p><p>Mis en ligne le 8 f\u00e9vrier 2019 \u00e0 10H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Europe emport\u00e9e dans son \u00ab\u00a0tourbillon crisique\u00a0\u00bb Il est manifeste que le pays aujourd&rsquo;hui le plus \u00e0 l&rsquo;aise en Europe pour la man&oelig;uvre politique pouvant amener des gains consid\u00e9rables, c&rsquo;est sans aucun doute l&rsquo;Italie. Son terrain d&rsquo;essai favori, son \u00ab\u00a0souffre-douleur\u00a0\u00bb principal, c&rsquo;est sans aucun doute la France : l&rsquo;Italie de Di Maio-Salvini joue avec la France&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12496,3631,5315,12692,5892,2687,18606,3442,4614,18599,1225,12563,2828],"class_list":["post-78457","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-brexit","tag-bruxelles","tag-cameron","tag-di","tag-enfer","tag-france","tag-gilets-jaunes","tag-italie","tag-juncker","tag-maio","tag-referendum","tag-renzi","tag-tusk"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78457"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78457\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}