{"id":78461,"date":"2019-02-10T10:56:07","date_gmt":"2019-02-10T10:56:07","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/10\/la-brute\/"},"modified":"2019-02-10T10:56:07","modified_gmt":"2019-02-10T10:56:07","slug":"la-brute","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/10\/la-brute\/","title":{"rendered":"La Brute"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">La Brute<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">&laquo;Je suis le fruit d&rsquo;une forme de brutalit\u00e9 de l&rsquo;Histoire.&raquo; (*)<\/h3>\n<\/p>\n<p><p>Certes, l&rsquo;Etat d\u00e9finit bien ce Moloch qui dispose du monopole de la violence l\u00e9gale : mais pour quoi faire? Sauf ir\u00e9nisme radical, la nature humaine \u00e9tant ce qu&rsquo;elle est, il n&rsquo;est en effet pas question d&rsquo;imaginer un monde dans lequel on n&rsquo;aurait plus besoin d&rsquo;arm\u00e9e ou de police, de tribunaux ou de prisons, de loi et de droit. Si l&rsquo;on estime qu&rsquo;un violeur n&rsquo;est pas un viol\u00e9, un agresseur un agress\u00e9, un voleur un vol\u00e9, un pilleur un pill\u00e9, un frappeur un frapp\u00e9, il faut bien qu&rsquo;une s\u00e9rie de m\u00e9caniques sociales permette d&rsquo;appr\u00e9hender le violeur, l&rsquo;agresseur, le vol\u00e9, le frappeur afin de le d\u00e9f\u00e9rer aux tribunaux qui jugent des faits en regard de la loi et du droit, et envoient la personne jug\u00e9e coupable purger sa peine au nom de la r\u00e9paration du viol\u00e9, de l&rsquo;agress\u00e9, du vol\u00e9, du pill\u00e9, du frapp\u00e9, mais aussi dans la perspective de prot\u00e9ger d&rsquo;autres citoyens de la dangerosit\u00e9 de ces d\u00e9linquants. Qu&rsquo;il existe des circonstances aggravantes ou att\u00e9nuantes, que chacun, quel que soit ce qu&rsquo;on lui reproche, ait droit \u00e0 la d\u00e9fense, puis \u00e0 la r\u00e9paration une fois la peine accomplie, tout cela est acquis.<\/p>\n<\/p>\n<p><p>La violence l\u00e9gale suppose qu&rsquo;elle puisse \u00eatre utilis\u00e9e afin de maintenir la l\u00e9galit\u00e9 &ndash; ce devrait \u00eatre une lapalissade&#8230; Or, quand, mi-septembre 2018, les Gilets jaunes font savoir, au d\u00e9but de leur col\u00e8re, que leur pouvoir d&rsquo;achat ne leur permettra pas de payer des taxes suppl\u00e9mentaires que le pouvoir inflige en augmentant le prix des carburants \u00e0 la pompe, ils ne mettent pas en p\u00e9ril la d\u00e9mocratie et la R\u00e9publique puisqu&rsquo;ils en appellent aux articles 13 et 14 de la D\u00e9claration des droits de l&rsquo;homme et, ne l&rsquo;oublions pas, du citoyen. Par leur mouvement, ils revendiquent l&rsquo;un de ces droits que ce texte majeur leur accorde. Je l&rsquo;ai d\u00e9j\u00e0 signal\u00e9, mais rappelons en effet que l&rsquo;article 13 de la D\u00e9claration des droits de l&rsquo;homme dit ceci: &laquo;Pour l&rsquo;entretien de la force publique, et pour les d\u00e9penses de l&rsquo;administration, une contribution commune est indispensable; elle doit \u00eatre \u00e9galement r\u00e9partie entre tous les citoyens, en raison de leurs facult\u00e9s.&raquo; Et l&rsquo;article suivant, ceci: &laquo;Les citoyens ont le droit de constater par eux-m\u00eames ou par leurs repr\u00e9sentants, la n\u00e9cessit\u00e9 de la contribution publique, de la consentir librement, d&rsquo;en suivre l&#8217;emploi et d&rsquo;en d\u00e9terminer la quotit\u00e9, l&rsquo;assiette, le recouvrement et la dur\u00e9e.&raquo;<\/p>\n<\/p>\n<p><p>Les Gilets jaunes n&rsquo;ont pas refus\u00e9 l&rsquo;imp\u00f4t, comme la propagande m\u00e9diatique le rab\u00e2che depuis des semaines afin de les assimiler aux populismes fascisants, mais ils font juste savoir qu&rsquo;ils n&rsquo;ont plus financi\u00e8rement les moyens de les payer! D&rsquo;un point de vue gouvernemental, une r\u00e9ponse appropri\u00e9e aurait permis d&rsquo;\u00e9touffer la col\u00e8re dans l&rsquo;&oelig;uf. Au lieu de cela, la riposte a \u00e9t\u00e9 tout de suite belliqueuse : c&rsquo;est l&rsquo;origine de la violence.<\/p>\n<\/p>\n<p><p>Ce bellicisme a pris la forme que l&rsquo;on sait : des \u00e9l\u00e9ments de langage du pouvoir macronien ont \u00e9t\u00e9 fournis puis abondamment relay\u00e9s par les &laquo;\u00e9lites&raquo; : le mouvement des Gilets jaunes \u00e9tait une jacquerie d&rsquo;extr\u00eame-droite, une revendication populiste qui sentait sa chemise brune, un mouvement qui puait le &laquo;facho&raquo;. BHL le fit savoir illico en m\u00eame temps que&hellip; M\u00e9lenchon et Cl\u00e9mentine Autain, Coquerel et la CGT qui rejoignaient ainsi dans leur concert populicide tous les \u00e9ditorialistes de la presse maastrichtienne.<\/p>\n<\/p>\n<p><p>Macron n&rsquo;est pas bien malin, car Pompidou mit fin \u00e0 Mai 68 avec un cynisme qui aurait pu l&rsquo;inspirer : deux inconnus \u00e0 l&rsquo;\u00e9poque, il s&rsquo;agit d&rsquo;Henri Krasucki de la CGT, donc du PCF, et Jacques Chirac, alors secr\u00e9taire d&rsquo;Etat \u00e0 l&#8217;emploi aupr\u00e8s du ministre des Affaires sociales, se rencontrent dans le cabinet d&rsquo;un avocat communiste. Chirac dira qu&rsquo;il s&rsquo;agissait d&rsquo;une chambre de bonne et pr\u00e9tendra qu&rsquo;il s&rsquo;y \u00e9tait rendu arm\u00e9&hellip; Il y aura plusieurs r\u00e9unions avant qu&rsquo;officiellement le s\u00e9cr\u00e9taire g\u00e9n\u00e9ral de la CGT, Georges S\u00e9guy, et les autres syndicats ne rencontrent Chirac et&hellip; Balladur, alors conseiller de Chirac, pour pr\u00e9parer ce qui deviendra les Accords de Grenelle. La n\u00e9gociation a grandement pay\u00e9 : hausse des salaires spectaculaires, augmentation du SMIC sans pr\u00e9c\u00e9dant, r\u00e9duction de la dur\u00e9e hebdomadaire du temps de travail, \u00e9largissement du droit syndical, coup de pouce aux allocations familiales, augmentation de la prestation offerte aux personnes \u00e2g\u00e9es, paiement des journ\u00e9es de gr\u00e8ve, baisse du ticket mod\u00e9rateur de la s\u00e9cu. La CGT revient aupr\u00e8s de sa base avec ces propositions : les ouvriers refusent ; les accords sign\u00e9s unilat\u00e9ralement par le pouvoir sont tout de m\u00eame appliqu\u00e9s &ndash; d\u00e9j\u00e0 la collusion des pouvoirs gouvernementaux et syndicaux, les fameux corps interm\u00e9diaires. Le travail reprend quelques jours plus tard. Le pouvoir joue sur l&rsquo;inflation: deux ou trois ans apr\u00e8s, les avantages consentis disparaissent avec l&rsquo;augmentation du co&ucirc;t de la vie. Exit Mai 68! Le\u00e7on de cynisme politique, mais \u00e9galement le\u00e7on sur le cynisme de ce qu&rsquo;il est donc convenu d&rsquo;appeler les corps interm\u00e9diaires : le pouvoir n\u00e9o-gaulliste et le pouvoir n\u00e9o-communiste se s\u00e9paraient moins sur leurs options politiques qu&rsquo;ils ne se rassemblaient sur ce fromage qu&rsquo;est toujours la repr\u00e9sentation qui permet de laisser croire au peuple qu&rsquo;on travaille pour lui alors qu&rsquo;on &oelig;uvre bien souvent \u00e0 ses d\u00e9pens pour sa seule boutique.<\/p>\n<\/p>\n<p><p>Revenons aux Gilets jaunes: Macron fait annoncer par son Premier ministre <a href=\"https:\/\/francais.rt.com\/france\/56192-gilets-jaunes-matignon-recoit-chefs-parti-representants-mouvement-crise\">un moratoire sur le prix de l&rsquo;essence d\u00e9but d\u00e9cembre<\/a>. Mais un moratoire est la formule qui permet de reculer pour mieux sauter &ndash; en l&rsquo;occurrence : sauter par-dessus les \u00e9lections europ\u00e9ennes pour lesquelles, chacun l&rsquo;a d\u00e9sormais bien compris, le pr\u00e9sident de la R\u00e9publique est en campagne. C&rsquo;est la raison pour laquelle il instrumentalise la crise des Gilets jaunes pour son propre compte et celui du camp maastrichtien. Il n&rsquo;y a pas d&rsquo;autres raisons \u00e0 son grand d\u00e9bat national puisqu&rsquo;il a bien pris soin d&rsquo;en donner la r\u00e8gle du jeu d\u00e8s le d\u00e9part : on parle &ndash; enfin: il parle &ndash;, mais pas question de changer de cap. Pourquoi donc parler? A quoi bon? Pour quoi faire?<\/p>\n<\/p>\n<p><p>Apr\u00e8s l&rsquo;annonce d&rsquo;un moratoire pour signifier qu&rsquo;on accorde un d\u00e9lai avant d&rsquo;actionner tout de m\u00eame la guillotine, premi\u00e8re violence symbolique, il y a eu l&rsquo;assimilation par le pr\u00e9sident de la R\u00e9publique des Gilets jaunes \u00e0 <a href=\"https:\/\/francais.rt.com\/france\/57434-voeux-nouvel-an-tres-delicat-exercice-emmanuel-macron-face-gilets-jaunes\">&laquo;une foule haineuse&raquo; <\/a>constitu\u00e9e d&rsquo;antis\u00e9mites, d&rsquo;homophobes, de racistes lors des v&oelig;ux de 2019, ce fut la deuxi\u00e8me violence symbolique. Elle a \u00e9t\u00e9 suivie par une troisi\u00e8me avec cette annonce de LA solution avec un grand d\u00e9bat national doubl\u00e9 du refus d&rsquo;un changement de cap. D&rsquo;autres violences sont depuis r\u00e9guli\u00e8rement inflig\u00e9es. Ainsi avec cette s\u00e9rie de gifles distribu\u00e9es au gr\u00e8s de ses apparitions publiques : une quatri\u00e8me \u00e0 la galette des rois quand le prince fait savoir que <a href=\"https:\/\/francais.rt.com\/france\/57769-macron-estime-que-beaucoup-francais-oublient-sens-effort-opposition-s-insurge\">tous les Fran\u00e7ais n&rsquo;ont pas le go&ucirc;t de l&rsquo;effort en laissant entendre que c&rsquo;est le cas des Gilets jaunes<\/a> (11 janvier 2019) ; une cinqui\u00e8me lors d&rsquo;un meeting pr\u00e9sent\u00e9 comme un d\u00e9bat, quand il affirme, que, parmi certains qui touchent les minimas sociaux, <a href=\"https:\/\/francais.rt.com\/france\/57955-macronjuge-q-partie-gens-situation-difficulte-deconnent-critiques-fusent\">&laquo;il y en a qui d\u00e9connent&raquo;<\/a>(15 janvier 2019) en n&rsquo;ignorant pas que cette cat\u00e9gorie sociologique est surrepr\u00e9sent\u00e9e chez les Gilets jaunes ; une sixi\u00e8me en faisant savoir de fa\u00e7on quelque peu m\u00e9prisante, toujours lors d&rsquo;un de ces meetings de campagne maastrichtien, que &laquo;la vraie r\u00e9forme, elle va avec la contrainte, les enfants! C&rsquo;est pas open bar. Le bar, c&rsquo;est le n\u00f4tre&raquo; (24 janvier 2019 \u00e0 Bourg-de-P\u00e9age) &ndash; la vraie r\u00e9forme, c&rsquo;est donc la sienne, pas celle des Gilets jaunes ; les &laquo;enfants&raquo; qu&rsquo;on toise de fa\u00e7on m\u00e9prisante, ce sont ces m\u00eames Gilets jaunes ; et la mention du bar, c&rsquo;est encore aux GJ que l&rsquo;image s&rsquo;adresse, on ne peut mieux dire que, pour le chef de l&rsquo;Etat, les Gilets jaunes sont de faux r\u00e9formateurs qui pensent comme des enfants assimil\u00e9s \u00e0 des piliers de bistrot&hellip;  <\/p>\n<\/p>\n<p><p>Ces violences symboliques sont copieusement d\u00e9multipli\u00e9es par le pouvoir m\u00e9diatique maastrichtien. On l&rsquo;a vu. Il s&rsquo;agit d&rsquo;assimiler les Gilets jaunes \u00e0 des gens violents et tout ce qui peut illustrer cette th\u00e8se se trouve savamment mis en images et en mots par les m\u00e9dias qui se contentent de relayer les \u00e9l\u00e9ments de langage venus de la cellule communication de l&rsquo;Elys\u00e9e, de celle de Matignon ou bien encore de celle du minist\u00e8re de l&rsquo;Int\u00e9rieur. Macron est un enfant-roi col\u00e9rique et intol\u00e9rant \u00e0 la frustration, Edouard Philippe un animal \u00e0 sang froid bien cravat\u00e9, propre sur lui et poli, Castaner un gouailleur ayant gard\u00e9 quelques habitudes de son ancienne fr\u00e9quentation du milieu marseillais, mais c&rsquo;est le m\u00eame discours : les Gilets jaunes sont violents, ils attaquent la R\u00e9publique, <a href=\"https:\/\/francais.rt.com\/france\/57602-manifestants-defoncent-porte-secretariat-etat-benjamin-griveaux-video-choc\">y compris avec un transpalette<\/a>moins gros qu&rsquo;une voiture sans permis, ils mettent en p\u00e9ril la d\u00e9mocratie, ils annoncent une r\u00e9volution n\u00e9o-fasciste&hellip; BHL pr\u00eate sa chemise \u00e0 ces discours. Les \u00e9ditorialistes pensent comme cette chemise. D&rsquo;autres &laquo;intellectuels&raquo; offrent une partie de leur anatomie \u00e0 cette m\u00eame chemise.<\/p>\n<\/p>\n<p><p>Cette violence symbolique, dont le bras arm\u00e9 est constitu\u00e9 par les m\u00e9dias du syst\u00e8me, se double d&rsquo;une violence polici\u00e8re. On sait que les mots tuent, mais pour ce faire, il leur faut des acteurs violents : le pouvoir en dispose avec un certain nombre de gens de justice et de gens de la police qui, sachant qu&rsquo;ils b\u00e9n\u00e9ficient d&rsquo;une couverture venue du minist\u00e8re de l&rsquo;Int\u00e9rieur, donc de Matignon, donc de l&rsquo;Elys\u00e9e, donc d&rsquo;Emmanuel Macron, s&rsquo;en donnent \u00e0 c&oelig;ur joie.<\/p>\n<\/p>\n<p><p>Je me suis retrouv\u00e9 sur un plateau de t\u00e9l\u00e9vision avec Jean-Marc Michaud, qui a perdu un &oelig;il \u00e0 cause d&rsquo;un tir de flash-ball. Il a dit toute sa col\u00e8re contre le tireur &ndash; et je le comprends. C&rsquo;est le premier mouvement, quand on a \u00e9t\u00e9 violent\u00e9, de vouloir riposter de la m\u00eame mani\u00e8re. On re\u00e7oit un coup, on n&rsquo;a pas envie d&rsquo;autre chose que de le rendre au centuple. Le cerveau reptilien fait la loi tant que le cortex n&rsquo;effectue pas son travail.<\/p>\n<\/p>\n<p><p>Certes, il y a une responsabilit\u00e9 du tireur : mais si ce tireur sait qu&rsquo;il aura des comptes \u00e0 rendre \u00e0 la justice si sa hi\u00e9rarchie lui reproche de s&rsquo;\u00eatre mal comport\u00e9 en ne respectant pas les proc\u00e9dures &ndash; dont celle, majeure, de ne jamais viser la t\u00eate&hellip;&ndash;, alors il se comportera probablement autrement. Mais, quand on sait pouvoir b\u00e9n\u00e9ficier de l&rsquo;impunit\u00e9 du pouvoir, alors on tire ou on tabasse sans \u00e9tat d&rsquo;\u00e2me et, pour l&rsquo;avoir constat\u00e9 par moi-m\u00eame \u00e0 Caen, avec certains spectateurs de ces op\u00e9rations, une jubilation non feinte \u00e0 cogner, taper, tabasser, projeter violemment au sol, menotter, mais aussi, dans certains cas sur lesquels je me penche ces temps-ci : d\u00e9nuder et palper&hellip; J&rsquo;ai d\u00e9j\u00e0 dit ailleurs que je supposais que certains policiers noyautaient les casseurs pour nourrir la th\u00e8se du pouvoir selon laquelle tous les Gilets jaunes sont violents. Apr\u00e8s que j&rsquo;ai donn\u00e9 cette information, d&rsquo;aucun parmi les Gilets jaunes m&rsquo;ont fait savoir par courrier qu&rsquo;ils en d\u00e9tenaient les preuves. Je reviendrai sur ce sujet le moment venu.  <\/p>\n<\/p>\n<p><p>Mais sans se focaliser sur ce cas particulier, il suffit de lire, sous la plume du maire divers droite, donc pas un gauchiste, Xavier Lemoine, une int\u00e9ressante information. Il affirme dans Le Figaro qu&rsquo;en tant que maire de Montfermeil, il a constat\u00e9 que &laquo;la police a moins r\u00e9prim\u00e9 les \u00e9meutes en banlieues en 2005 que les Gilets Jaunes&raquo; (29 janvier 2019). Tout est dit. <\/p>\n<\/p>\n<p><p>Le maire constate qu&rsquo;en 2005 il n&rsquo;y a eu aucun mort et peu de bless\u00e9s parmi les \u00e9meutiers bien que ces derniers aient choisi la violence comme unique moyen d&rsquo;expression. Il en donne la raison : la police avait alors choisi une op\u00e9ration de maintien de l&rsquo;ordre et non, comme Macron, une logique de r\u00e9pression. Or, maintenir l&rsquo;ordre n&rsquo;est pas r\u00e9primer. Ce sont deux choix politiques extr\u00eamement diff\u00e9rents id\u00e9ologiquement, politiquement, strat\u00e9giquement, tactiquement &ndash; et aussi moralement. Emmanuel Macron a sciemment choisi de r\u00e9primer et non pas de maintenir l&rsquo;ordre. Le chef de l&rsquo;Etat n&rsquo;a donc pas voulu contenir les violences revendicatives mais d\u00e9cha&icirc;ner les violences d&rsquo;Etat. C&rsquo;est \u00e0 dessein.<\/p>\n<\/p>\n<p><p>Xavier Lemoine constate que le choix du maintien de l&rsquo;ordre vise, comme les mots l&rsquo;indiquent, \u00e0 chercher avant tout \u00e0 maintenir l&rsquo;ordre, donc \u00e0 \u00e9viter le d\u00e9sordre. J&rsquo;y reviens : on ne me fera pas croire que laisser d\u00e9paver l&rsquo;avenue des Champs-Elys\u00e9es sous les objectifs des cam\u00e9ras de BFMTV pendant presque une heure ne t\u00e9moigne pas du fait que le forces de l&rsquo;ordre n&rsquo;avaient pas eu pour consigne d&#8217;emp\u00eacher le d\u00e9sordre, c&rsquo;\u00e9tait facile \u00e0 faire sans violence, mais, au contraire, de le favoriser en laissant ces pav\u00e9s devenir des projectiles en attente de leurs cibles humaines ou mat\u00e9rielles&hellip;<\/p>\n<\/p>\n<p><p>Parlant de sa ville, Xavier Lemoine dit : &laquo;En 2005, la totalit\u00e9 [sic] des revendications se sont exprim\u00e9es par la violence. Or, \u00e0 l&rsquo;\u00e9poque, les forces de l&rsquo;ordre ont adopt\u00e9 le mode d&rsquo;intervention le plus appropri\u00e9 qui soit pour faire retomber cette violence. D&rsquo;un point de vue technique, leur attaque a \u00e9t\u00e9 souple et remarquable. Alors qu&rsquo;ils \u00e9taient pris pour cibles par les \u00e9meutiers, policiers et gendarmes ont montr\u00e9 une grande retenue dans l&rsquo;usage de la force. Aujourd&rsquo;hui, au contraire, nul ne peut pr\u00e9tendre que toutes les revendications des &quot;Gilets jaunes&quot; s&rsquo;expriment par la violence. En outre, en 2005, il n&rsquo;y avait aucune femme parmi les \u00e9meutiers, alors que les femmes sont pr\u00e9sentes massivement dans les rangs des &quot;Gilets jaunes&quot;. Ne pas le prendre en compte, c&rsquo;est se priver d&rsquo;un \u00e9l\u00e9ment d&rsquo;analyse fondamental. Contrairement \u00e0 ce que la puissance des images peut laisser penser, la majorit\u00e9 des &quot;Gilets jaunes&quot; ne participe pas aux violences condamnables commises lors de ce mouvement. Pourtant, depuis le samedi 8 d\u00e9cembre, les forces de l&rsquo;ordre privil\u00e9gient la r\u00e9pression, et non le maintien de l&rsquo;ordre.&raquo; Au journaliste qui lui demande de pr\u00e9ciser ce qui distingue maintien de l&rsquo;ordre et r\u00e9pression, Xavier Lemoine r\u00e9pond: &laquo;Le maintien de l&rsquo;ordre consiste d&rsquo;une part \u00e0 permettre \u00e0 une manifestation de s&rsquo;\u00e9couler de la mani\u00e8re la plus pacifique qui soit, et d&rsquo;autre part contenir la violence en vue de la faire diminuer. Cet objectif n&rsquo;interdit pas aux policiers d&rsquo;intervenir contre des personnes d\u00e9termin\u00e9es \u00e0 des actes de violence&raquo; &ndash; je songe \u00e0 ceux qui d\u00e9pavent l&rsquo;avenue des Champs Elys\u00e9es&hellip; Il poursuit : &laquo;Mais il est toujours laiss\u00e9 aux manifestants pacifiques des portes de sortie. Les int\u00e9ress\u00e9s peuvent ainsi quitter les lieux quand \u00e7a d\u00e9g\u00e9n\u00e8re. La r\u00e9pression, elle, consiste \u00e0 en d\u00e9coudre contre des groupes sans faire n\u00e9cessairement la distinction entre les individus violents et les manifestants paisibles, qui peuvent se trouver loin d&rsquo;eux. Or, dans la crise actuelle, les forces de l&rsquo;ordre recourent trop souvent aux &quot;nasses&quot;, qui l&#8217;emp\u00eachent les personnes encercl\u00e9es de quitter les lieux. Il est facile alors de faire des amalgames entre des manifestants tr\u00e8s diff\u00e9rents. Parmi les \u00e9borgn\u00e9s, combien avaient cass\u00e9 des vitrines, retourn\u00e9 des voitures, pill\u00e9 des magasins? De m\u00eame, le souci de diff\u00e9rencier les casseurs &quot;confirm\u00e9s&quot; et les primo-d\u00e9linquants devrait \u00eatre beaucoup plus net.&raquo; Pour Xavier Lemoine, les forces de l&rsquo;ordre ob\u00e9issent \u00e0 un pouvoir qui a choisi la r\u00e9pression et la brutalit\u00e9. Elles ob\u00e9issent. Le responsable, donc le coupable, est celui qui donne l&rsquo;ordre. Et, comme on ne peut imaginer que Castaner ou Philippe prennent la d\u00e9cision seuls, c&rsquo;est au chef de l&rsquo;Etat qu&rsquo;il faut imputer le choix de la r\u00e9pression, donc chaque blessure inflig\u00e9e. Quand ce m\u00eame chef de l&rsquo;Etat affirme \u00e9hont\u00e9ment en Egypte que les forces de l&rsquo;ordre n&rsquo;ont caus\u00e9 aucun mort alors qu&rsquo;on leur doit celle de madame Redoine \u00e0 Marseille, il ment. Et <a href=\"https:\/\/www.francetvinfo.fr\/economie\/transports\/gilets-jaunes\/gilets-jaunes-ce-que-l-on-sait-de-la-mort-d-une-octogenaire-blessee-par-une-grenade-lacrymogene-a-marseille_3084379.html\">il est personnellement responsable de cette mort<\/a>. La brute, c&rsquo;est lui.<\/p>\n<\/p>\n<p><p>Lisons encore Xavier Lemoine : &laquo;Je n&rsquo;incrimine en rien les forces de l&rsquo;ordre, qui ob\u00e9issent, comme il est naturel, aux instructions du ministre de l&rsquo;Int\u00e9rieur. Mais je bl\u00e2me ces instructions, qui me paraissent traduire une volont\u00e9 de monter aux extr\u00eames, d&rsquo;accro&icirc;tre la violence pour justifier une r\u00e9pression. Je n&rsquo;ai aucune complaisance pour les violences pr\u00e9m\u00e9dit\u00e9es des casseurs ou des groupuscules extr\u00e9mistes. Mais la responsabilit\u00e9 du politique est aussi de savoir d\u00e9samorcer un cri de d\u00e9tresse, au lieu de l&rsquo;alimenter en diabolisant les &quot;Gilets jaunes&quot;. Jamais les gouvernants, en 2005, n&rsquo;ont tenu des propos aussi m\u00e9prisants envers les \u00e9meutiers d&rsquo;alors. Actuellement, une partie importante des violences \u00e9mane de manifestants sans casiers judiciaires, d\u00e9sesp\u00e9r\u00e9s et chauff\u00e9s \u00e0 blanc. Ils se sentent provoqu\u00e9s par la rigidit\u00e9 de la riposte de la police. La dynamique de foule aidant, ils se &quot;radicalisent&quot;. Leur r\u00e9flexe vital s&rsquo;exprime de fa\u00e7on brutale. En 2005 aucune manifestation n&rsquo;avait \u00e9t\u00e9 d\u00e9clar\u00e9e en pr\u00e9fecture et toutes d\u00e9g\u00e9n\u00e9raient en \u00e9meutes. Pourtant, \u00e0 l&rsquo;\u00e9poque, en Seine-Saint-Denis, il n&rsquo;y a eu aucune charge de CRS, ni de policiers \u00e0 cheval. Aujourd&rsquo;hui, si. Voil\u00e0 quatorze ans, les forces de l&rsquo;ordre n&rsquo;ont pas recouru au tir tendu, \u00e0 l&rsquo;horizontal, \u00e0 face d&rsquo;homme et \u00e0 courte distance. Aujourd&rsquo;hui, si. Pourquoi ces deux poids, deux mesures de l&rsquo;Etat entre les \u00e9meutes urbaines de 2005 et les sc\u00e8nes d&rsquo;\u00e9meutes des &quot;Gilets jaunes&quot;? Je ne juge pas que les forces de l&rsquo;ordre ont \u00e9t\u00e9 laxistes en 2005 ; j&rsquo;affirme qu&rsquo;elles sont trop &quot;dures&quot; aujourd&rsquo;hui.&raquo;<\/p>\n<\/p>\n<p><p>La violence g\u00e9n\u00e9alogique, celle qui s&rsquo;av\u00e8re fondatrice des premi\u00e8res revendications des Gilets jaunes, c&rsquo;est d&rsquo;abord et avant tout celle qu&rsquo;impose le syst\u00e8me politique lib\u00e9ral<\/p>\n<\/p>\n<p><p>Que le pr\u00e9sident Macron ait choisi la ligne dure de la r\u00e9pression contre la ligne r\u00e9publicaine du maintien de l&rsquo;ordre est donc av\u00e9r\u00e9. Il a donc \u00e0 son service la presse maastrichtienne, autrement dit les m\u00e9dias dominants, dont ceux du service public audiovisuel, il a mis \u00e0 son service la police, l&rsquo;arm\u00e9e, donc les forces de l&rsquo;ordre, il a \u00e9galement essay\u00e9 d&rsquo;y adjoindre la machine judiciaire. Ce dont t\u00e9moigne un article du <em>Canard encha&icirc;n\u00e9<\/em>(30 janvier 2019) intitul\u00e9 &laquo;Les incroyables consignes du parquet sur les Gilets jaunes&raquo;, qui rapporte dans le d\u00e9tail comment le minist\u00e8re dit de la Justice a communiqu\u00e9 par courriel avec les magistrats du parquet de Paris sur la fa\u00e7on de traiter les Gilets jaunes : apr\u00e8s une arrestation, m\u00eame si elle a \u00e9t\u00e9 effectu\u00e9e par erreur, il faut tout de m\u00eame maintenir l&rsquo;inscription au fichier du traitement des ant\u00e9c\u00e9dents judiciaires (TAJ), y compris &laquo;lorsque les faits ne sont pas constitu\u00e9s&raquo;. Le courrier pr\u00e9cise \u00e9galement qu&rsquo;il faut ficher, m\u00eame si &laquo;les faits sont t\u00e9nus&raquo; et m\u00eame dans le cas av\u00e9r\u00e9 &laquo;d&rsquo;une irr\u00e9gularit\u00e9 de proc\u00e9dure&raquo;! Dans ces cas-l\u00e0, arrestation par erreur, infraction non motiv\u00e9e, irr\u00e9gularit\u00e9 de proc\u00e9dure, il est conseill\u00e9 de maintenir les gardes \u00e0 vue et de ne les lever qu&rsquo;apr\u00e8s les manifestations du samedi afin d&rsquo;\u00e9viter que les citoyens fautivement interpell\u00e9s puissent exercer leur droit de gr\u00e8ve, faut-il le rappeler, un droit garanti par la Constitution ? Alin\u00e9a 7 du pr\u00e9ambule&#8230;<\/p>\n<\/p>\n<p><p>Ajoutons \u00e0 cela que le projet de loi dit &laquo;anti casseurs&raquo; propos\u00e9 par Macron se propose purement et simplement d&rsquo;instaurer une pr\u00e9somption de culpabilit\u00e9 \u00e0 l&rsquo;endroit de quiconque serait suspect\u00e9 d&rsquo;\u00eatre sympathisant de la cause des Gilets jaunes. Suspect\u00e9 par qui? Par la m\u00eame justice \u00e0 laquelle le pouvoir demande, premi\u00e8rement, de conserver en garde \u00e0 vue une personne m\u00eame arr\u00eat\u00e9e par erreur, deuxi\u00e8mement, de ne la rel\u00e2cher qu&rsquo;apr\u00e8s la fin des manifestations, troisi\u00e8mement, d&rsquo;agir de m\u00eame y compris dans le cas d&rsquo;une erreur de proc\u00e9dure, quatri\u00e8mement, de ne pas se soucier du fait que les faits soient av\u00e9r\u00e9s, la t\u00e9nuit\u00e9 suffisant pourvu que la justice macronienne soutenue par la police macronienne elle-m\u00eame au ordre de l&rsquo;id\u00e9ologie macronienne, qui est purement et simplement celle de l&rsquo;Etat maastrichtien, aient d\u00e9cid\u00e9 qu&rsquo;il en soit ainsi. M\u00e9lenchon a pu parler \u00e0 ce propos du retour de la lettre de cachet, il n&rsquo;a pas tort sur ce sujet.<\/p>\n<\/p>\n<p><p>La violence g\u00e9n\u00e9alogique, celle qui s&rsquo;av\u00e8re fondatrice des premi\u00e8res revendications des Gilets jaunes, c&rsquo;est d&rsquo;abord et avant tout celle qu&rsquo;impose le syst\u00e8me politique lib\u00e9ral install\u00e9 de fa\u00e7on imp\u00e9rieuse par l&rsquo;Etat maastrichtien depuis 1992. Quand Macron dit que les racines du mal sont anciennes, il ne le sait que trop, car il est l&rsquo;un des hommes dont la courte vie a \u00e9t\u00e9 enti\u00e8rement consacr\u00e9e \u00e0 l&rsquo;instauration de ce programme lib\u00e9ral qui s&rsquo;av\u00e8re fort avec les faibles, on le voit dans les rues depuis douze semaines, et faible avec les forts, on le constate avec la l\u00e9gislation qui leur est favorable -de la suppression de l&rsquo;ISF au refus de s&rsquo;attaquer aux paradis fiscaux en passant par la tol\u00e9rance du fait que les GAFA \u00e9chappent \u00e0 l&rsquo;imp\u00f4t.<\/p>\n<\/p>\n<p><p>La violence de cet Etat maastrichtien sur les plus faibles, les plus d\u00e9sarm\u00e9s, les moins dipl\u00f4m\u00e9s, les plus \u00e9loign\u00e9s de Paris ou des m\u00e9gapoles fran\u00e7aises ; la violence de cet Etat maastrichtien sur les plus pr\u00e9caires en tout, sur les gens modestes qui portent tout seul le poids d&rsquo;une mondialisation heureuse pour d&rsquo;autres qui les conchient \u00e0 longueur d&rsquo;apparitions m\u00e9diatiques ; la violence de cet Etat maastrichtien sur les oubli\u00e9s des nouvelles compassions du politiquement correct ; la violence de cet Etat maastrichtien sur les femmes seules, les m\u00e8res c\u00e9libataires, les veuves aux pensions de retraite amput\u00e9es, les femmes contraintes de louer leur ut\u00e9rus pour qu&rsquo;on y d\u00e9pose un sperme mercenaire, les victimes des violences conjugales surgies de la mis\u00e8re, les jeunes gar\u00e7ons ou les jeunes filles qui se prostituent pour payer leurs \u00e9tudes ; la violence de cet Etat maastrichtien sur les ruraux priv\u00e9s jour apr\u00e8s jour du service public que leurs imp\u00f4ts indirects financent pourtant ; la violence de cet Etat maastrichtien sur les paysans qui se pendent tous les jours parce que la profession de foi \u00e9cologiste des maastrichtiens urbains ne s&rsquo;encombre pas d&rsquo;\u00e9cologie quand il s&rsquo;agit de l&rsquo;assiette des Fran\u00e7ais qu&rsquo;ils remplissent de viandes avari\u00e9es, de produits toxiques, de chimie canc\u00e9rig\u00e8ne, d&rsquo;aliments en provenance du bout de la plan\u00e8te sans souci de la trace carbone et qui peuvent m\u00eame \u00eatre bios ; la violence de cet Etat maastrichtien sur les g\u00e9n\u00e9rations d&rsquo;enfants cr\u00e9tinis\u00e9s par une \u00e9cole qui a cess\u00e9 d&rsquo;\u00eatre r\u00e9publicaine et qui laisse aux seuls filles et fils de la possibilit\u00e9 de s&rsquo;en sortir non pas gr\u00e2ce \u00e0 leur talents, mais avec l&rsquo;aide du piston de leurs familles bien n\u00e9es ; la violence de cet Etat maastrichtien qui a prol\u00e9taris\u00e9 des jeunes n&rsquo;ayant plus pour seul espoir que la s\u00e9curit\u00e9 de l&#8217;emploi du policier, du gendarme, du militaire ou du gardien de prison et dont le m\u00e9tier consiste \u00e0 g\u00e9rer par la violence l\u00e9gale les d\u00e9chets du syst\u00e8me lib\u00e9ral ; la violence de cet Etat maastrichtien sur les petits patrons, les commer\u00e7ants, les artisans qui ignorent les vacances, les loisirs, les week-end, les sorties &ndash; ces violences l\u00e0, oui, sont les violences premi\u00e8res. Ce sont celles qui n&rsquo;ont pas g\u00e9n\u00e9r\u00e9 de violence, mais juste une premi\u00e8re manifestation contre l&rsquo;augmentation du plein d&rsquo;essence. <\/p>\n<\/p>\n<p><p>La r\u00e9ponse du pouvoir, donc de Macron, \u00e0 cet aveu de pauvret\u00e9 des pauvres a \u00e9t\u00e9 tout de suite la criminalisation id\u00e9ologique. Les m\u00e9dias aux ordres ont cri\u00e9 au loup fasciste. Depuis plusieurs mois, c&rsquo;est leur pain quotidien: selon les riches qui les gouvernent, les pauvres seraient donc antis\u00e9mites, racistes, homophobes, violents, complotistes &ndash; &laquo;salauds&raquo;, dit-m\u00eame BHL chez Ruquier. C&rsquo;est la vielle variation sur le th\u00e8me: classes laborieuses, classes dangereuses. C&rsquo;est l&rsquo;antienne de tous les pouvoirs bourgeois quand ils ont peur. Le pouvoir de l&rsquo;Etat maastrichtien man&oelig;uvre assez bien pour que, jusqu&rsquo;\u00e0 ce jour, sa responsabilit\u00e9 ne soit jamais mise en cause! C&rsquo;est pourtant lui le probl\u00e8me! C&rsquo;est tellement lui le probl\u00e8me que Macron veut en faire la solution en expliquant que le probl\u00e8me de l&rsquo;Europe lib\u00e9rale ; c&rsquo;est qu&rsquo;il n&rsquo;y en a pas assez alors que les Gilets jaunes lui disent justement qu&rsquo;il y en a trop &ndash; non pas d&rsquo;Europe, mais de lib\u00e9ralisme.<\/p>\n<\/p>\n<p><p>D\u00e8s lors, le chef de l&rsquo;Etat mobilise les m\u00e9dias qui d\u00e9sinforment, la police qui traque le manifestant, la justice qui les coffre s\u00e9v\u00e8rement, la prison qui les parque quand l&rsquo;h\u00f4pital ne les soigne pas apr\u00e8s tabassages. A partir de quel moment comprendra-t-on que nous disposons l\u00e0 des pi\u00e8ces d&rsquo;un puzzle despotique?<\/p>\n<\/p>\n<p><h4>Michel Onfray<\/h4>\n<\/p>\n<p><p>(Sur RT France le <a href=\"https:\/\/francais.rt.com\/opinions\/58886-la-brute-par-michel-onfray\">8 f\u00e9vrier 2019<\/a>)<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>(*) Macron, le 13 f\u00e9vrier 2018, devant la presse pr\u00e9sidentielle.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Brute &laquo;Je suis le fruit d&rsquo;une forme de brutalit\u00e9 de l&rsquo;Histoire.&raquo; (*) Certes, l&rsquo;Etat d\u00e9finit bien ce Moloch qui dispose du monopole de la violence l\u00e9gale : mais pour quoi faire? Sauf ir\u00e9nisme radical, la nature humaine \u00e9tant ce qu&rsquo;elle est, il n&rsquo;est en effet pas question d&rsquo;imaginer un monde dans lequel on n&rsquo;aurait&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[5607,18606,2617,3582,16011,8014,8046,6619],"class_list":["post-78461","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-despotisme","tag-gilets-jaunes","tag-macron","tag-michel","tag-onfray","tag-policiere","tag-repression","tag-violence"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78461"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78461\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}