{"id":78467,"date":"2019-02-13T07:22:30","date_gmt":"2019-02-13T07:22:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/13\/la-mort-du-traite-inf\/"},"modified":"2019-02-13T07:22:30","modified_gmt":"2019-02-13T07:22:30","slug":"la-mort-du-traite-inf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/13\/la-mort-du-traite-inf\/","title":{"rendered":"La mort du trait\u00e9 INF"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La mort du trait\u00e9 INF<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Victoire de la Russie, Waterloo de l&rsquo;Am\u00e9rique<\/h3>\n<\/p>\n<p><p>Le 1er mars 2018, le monde a appris l&rsquo;existence des nouveaux syst\u00e8mes d&rsquo;armes de la Russie, qui seraient fond\u00e9s sur de nouveaux principes physiques. S&rsquo;adressant \u00e0 l&rsquo;Assembl\u00e9e f\u00e9d\u00e9rale, M. Poutine a expliqu\u00e9 comment ils en \u00e9taient arriv\u00e9s l\u00e0 : en 2002, les &Eacute;tats-Unis se sont retir\u00e9s du Trait\u00e9 sur les missiles antibalistiques. &Agrave; l&rsquo;\u00e9poque, les Russes ont d\u00e9clar\u00e9 qu&rsquo;ils seraient forc\u00e9s de r\u00e9pondre, et on leur a essentiellement dit \u00ab\u00a0Faites ce que vous voulez\u00a0\u00bb<strong>.<\/strong><\/p>\n<\/p>\n<p><p>Et c&rsquo;est ce qu&rsquo;ils ont fait, d\u00e9veloppant de nouvelles armes qu&rsquo;aucun syst\u00e8me de missiles anti-missiles balistiques ne pourra jamais esp\u00e9rer arr\u00eater. Parmi les nouvelles armes russes, il y en a une qui est d\u00e9j\u00e0 en service dans des unit\u00e9s de combat (Kinzhal), une qui est en cours de pr\u00e9paration pour sa production en masse (Avangard) et plusieurs qui sont actuellement test\u00e9es (Pos\u00e9idon, Burevestnik, Peresvet, Sarmat). Leurs caract\u00e9ristiques, bri\u00e8vement, sont les suivantes :<\/p>\n<\/p>\n<p><p><strong>&bull; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kinjal\">Kinzhal<\/a><\/strong> : missile de croisi\u00e8re hypersonique lanc\u00e9 par voie a\u00e9rienne qui vole \u00e0 Mach 10 (12 300 km\/h) et peut d\u00e9truire les installations au sol et les navires ;<\/p>\n<\/p>\n<p><p><strong>&bull; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Avangard_(missile)\">Avangard<\/a><\/strong> : syst\u00e8me de lancement hypersonique man&oelig;uvrable pour missiles balistiques intercontinentaux qui vole \u00e0 une vitesse sup\u00e9rieure \u00e0 Mach 20 (24 600 km\/h). Il a une port\u00e9e de 1190 km et peut transporter une charge nucl\u00e9aire allant jusqu&rsquo;\u00e0 300 kilotonnes. <em>[<\/em>La bombe d&rsquo;Hiroshima, &laquo; Little Boy &raquo;, est estim\u00e9e avoir d\u00e9velopp\u00e9 une puissance de 12 \u00e0 18 kilotonnes de TNT, NdT<em>] ;<\/em><\/p>\n<\/p>\n<p><p><strong>&bull; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Status-6_Poseidon\">Pos\u00e9idon<\/a><\/strong> : torpille autonome \u00e0 propulsion nucl\u00e9aire d&rsquo;une port\u00e9e illimit\u00e9e qui peut se d\u00e9placer \u00e0 une profondeur de 1 km en maintenant une vitesse d&rsquo;un peu plus de 100 n&oelig;uds.<\/p>\n<\/p>\n<p><p>&bull; <strong><a href=\"https:\/\/en.wikipedia.org\/wiki\/9M730_Burevestnik\">Burevestnik<\/a><\/strong> : missile de croisi\u00e8re \u00e0 propulsion nucl\u00e9aire [\u00e0 port\u00e9e th\u00e9oriquement illimit\u00e9e et avec une grande capacit\u00e9 de leurrer les d\u00e9fenses antimissiles par des man&oelig;uvres d&rsquo;\u00e9vitement] ;<\/p>\n<\/p>\n<p><p><strong>&bull; <a href=\"https:\/\/fr.sputniknews.com\/defense\/201812071039210615-laser-russie-peresvet-armee\/\">Peresvet<\/a><\/strong> : un complexe laser mobile qui permet d&rsquo;aveugler des drones et des satellites, en d\u00e9truisant les syst\u00e8mes de reconnaissance spatiale et a\u00e9rienne ;<\/p>\n<\/p>\n<p><p><strong>&bull; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/RS-28_Sarmat\">Sarmat<\/a><\/strong> : un nouveau missile intercontinental lourd qui peut suivre des trajectoires suborbitales arbitraires (comme au-dessus du p\u00f4le Sud) et frapper des points arbitraires partout sur la plan\u00e8te. Parce qu&rsquo;il ne suit pas une trajectoire balistique pr\u00e9visible, il est impossible de l&rsquo;intercepter.<\/p>\n<\/p>\n<p><p>La premi\u00e8re r\u00e9action occidentale \u00e0 cette annonce a \u00e9t\u00e9 un silence sinistre. Quelques personnes ont essay\u00e9 de convaincre quelqu&rsquo;un qui \u00e9couterait que c&rsquo;\u00e9tait du bluff et juste une animation sur ordinateur, et que ces syst\u00e8mes d&rsquo;armes n&rsquo;existaient pas vraiment. (L&rsquo;animation \u00e9tait d&rsquo;assez mauvaise qualit\u00e9, pourrait-on ajouter, probablement parce que les militaires russes ne pouvaient pas imaginer que des graphismes \u00e9l\u00e9gants, tels que ceux pour lesquels les Am\u00e9ricains gaspillent leur argent, rendraient la Russie plus s&ucirc;re). Mais les nouveaux syst\u00e8mes d&rsquo;armes ont fini par fonctionner et les services de renseignement am\u00e9ricains ont <a href=\"https:\/\/reseauinternational.net\/le-pentagone-contemple-avangard\/\">confirm\u00e9<\/a> leur existence.<\/p>\n<\/p>\n<p><p>Forc\u00e9s de r\u00e9agir, les Am\u00e9ricains, avec l&rsquo;UE en remorque, ont tent\u00e9 de provoquer des scandales de relations publiques sur des questions sans rapport. De telles tentatives sont r\u00e9p\u00e9t\u00e9es avec une certaine fr\u00e9quence dans cette sorte de circonstances. Par exemple, apr\u00e8s que le putsch en Ukraine ait pouss\u00e9 la Crim\u00e9e \u00e0 retourner dans le giron de la Russie, il y a eu une offensive m\u00e9diatique hyst\u00e9rique au sujet du vol <a href=\"https:\/\/www.les-crises.fr\/accident-du-vol-malaysia-airlines-mh17\/\">MH17 de Malaysian Airlines<\/a>, que les Am\u00e9ricains avaient abattu au-dessus du territoire ukrainien avec l&rsquo;aide des militaires ukrainiens.<\/p>\n<\/p>\n<p><p>De m\u00eame, apr\u00e8s l&rsquo;annonce par Poutine de nouveaux syst\u00e8mes d&rsquo;armes, il y a eu une r\u00e9action hyst\u00e9rique tout aussi poussive utilisant l&rsquo;affaire du pr\u00e9tendu empoisonnement au \u00ab\u00a0Novichok\u00a0\u00bb de Sergei Skripal et de sa fille. Deux touristes russes, si vous vous souvenez bien, ont \u00e9t\u00e9 accus\u00e9s d&rsquo;avoir empoisonn\u00e9 les Skripal en impr\u00e9gnant de gaz toxique la poign\u00e9e de la porte d&rsquo;entr\u00e9e de sa maison quelque temps apr\u00e8s qu&rsquo;il l&rsquo;eut quitt\u00e9e pour ne jamais y revenir. De telles bouffonneries ont peut-\u00eatre fait du bien \u00e0 certaines personnes, mais s&rsquo;opposer \u00e0 de nouveaux syst\u00e8mes d&rsquo;armes r\u00e9volutionnaires en g\u00e9n\u00e9rant de telles sortes d&rsquo;<a href=\"https:\/\/fr.wiktionary.org\/wiki\/infox\"><em>infox<\/em><\/a> n&rsquo;est pas une r\u00e9action tr\u00e8s s\u00e9rieuse ni professionnelle.<\/p>\n<\/p>\n<p><p>Dites ce que vous voulez au sujet de la r\u00e9ponse russe au retrait des &Eacute;tats-Unis du trait\u00e9 ABM, mais elle \u00e9tait ad\u00e9quate. Elle a \u00e9t\u00e9 rendue n\u00e9cessaire par deux faits bien connus. Tout d&rsquo;abord, les &Eacute;tats-Unis sont le seul pays \u00e0 avoir largu\u00e9 des bombes nucl\u00e9aires sur un autre pays (Hiroshima, Nagasaki). Cela n&rsquo;a pas \u00e9t\u00e9 fait en \u00e9tat de l\u00e9gitime d\u00e9fense, mais simplement pour envoyer un message \u00e0 l&rsquo;URSS selon lequel toute r\u00e9sistance face aux USA serait futile (une man&oelig;uvre stupide s&rsquo;il en est). Deuxi\u00e8mement, on sait que les &Eacute;tats-Unis ont planifi\u00e9 \u00e0 plusieurs reprises la destruction de l&rsquo;URSS en utilisant une premi\u00e8re frappe nucl\u00e9aire. Cela n&rsquo;a pas \u00e9t\u00e9 mise en action, d&rsquo;abord par un manque d&rsquo;armes nucl\u00e9aires US en quantit\u00e9 suffisante, ensuite par la mise au point d&rsquo;armes nucl\u00e9aires sovi\u00e9tiques, puis par le d\u00e9veloppement d&rsquo;ICBM sovi\u00e9tiques.<\/p>\n<\/p>\n<p><p>La<em>\u00ab\u00a0<\/em>Guerre des \u00e9toiles\u00a0\u00bb de Ronald Reagan visait \u00e0 mettre au point un syst\u00e8me qui abattrait suffisamment d&rsquo;ICBM sovi\u00e9tiques pour qu&rsquo;une premi\u00e8re frappe nucl\u00e9aire sur l&rsquo;URSS soit gagnable. Ces travaux ont pris fin lorsque Reagan et Gorbatchev [se sont entendus sur les initiatives de limitation des armements et de d\u00e9sarmement accompagnant la fin de la Guerre froide]. Mais lorsque Bush Jr. s&rsquo;est retir\u00e9 du trait\u00e9 ABM en 2002, les &Eacute;tats-Unis ont relanc\u00e9 la course aux armements. L&rsquo;ann\u00e9e derni\u00e8re, Poutine a d\u00e9clar\u00e9 que la Russie avait gagn\u00e9 : les Am\u00e9ricains peuvent maintenant \u00eatre assur\u00e9s que s&rsquo;ils attaquent la Russie, le r\u00e9sultat sera leur an\u00e9antissement complet et garanti, et les Russes peuvent \u00eatre rassur\u00e9s en sachant que les &Eacute;tats-Unis n&rsquo;oseront jamais les attaquer.<\/p>\n<\/p>\n<p><p>Mais ce n&rsquo;\u00e9tait que le pr\u00e9lude. La v\u00e9ritable victoire a eu lieu le 2 f\u00e9vrier 2019. On se souviendra de ce jour comme du jour o&ugrave; la F\u00e9d\u00e9ration de Russie a vaincu les &Eacute;tats-Unis dans la bataille pour l&rsquo;Eurasie &ndash; de Lisbonne \u00e0 Vladivostok et de Mourmansk \u00e0 Mumbai.<\/p>\n<\/p>\n<p><p>Alors, que voulaient les Am\u00e9ricains, et qu&rsquo;ont-ils obtenu \u00e0 la place ? Ils voulaient ren\u00e9gocier le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Trait%C3%A9_sur_les_forces_nucl%C3%A9aires_%C3%A0_port%C3%A9e_interm%C3%A9diaire\">trait\u00e9 INF<\/a>, en r\u00e9viser certains termes et l&rsquo;\u00e9tendre \u00e0 la Chine. En annon\u00e7ant que les &Eacute;tats-Unis suspendaient le trait\u00e9 INF, M. Trump a d\u00e9clar\u00e9 : <em>&laquo; J&rsquo;esp\u00e8re qu&rsquo;on pourra mettre tout le monde dans une grande et belle salle et faire un nouveau trait\u00e9 qui serait bien mieux&hellip; &raquo;.<\/em> Par <em>&laquo; tout le monde &raquo;<\/em> Trump voulait probablement dire les &Eacute;tats-Unis, la Chine et la Russie.<\/p>\n<\/p>\n<p><p>Pourquoi ce besoin soudain d&rsquo;inclure la Chine ? Parce que la Chine dispose d&rsquo;un arsenal complet d&rsquo;armes de port\u00e9e interm\u00e9diaire avec une port\u00e9e de 500 \u00e0 5500 km (celles qui sont interdites par le trait\u00e9 INF) point\u00e9es sur les bases militaires am\u00e9ricaines dans toute la r\u00e9gion, en Cor\u00e9e du Sud, au Japon et \u00e0 Guam. Le trait\u00e9 INF emp\u00e9chait les &Eacute;tats-Unis de mettre au point quoi que ce soit qui pourrait \u00eatre d\u00e9ploy\u00e9 dans ces bases pour viser sp\u00e9cifiquement la Chine.<\/p>\n<\/p>\n<p><p>Peut-\u00eatre s&rsquo;agissait-il de la tentative de Trump de pratiquer <em>the art of the deal <\/em>avec les superpuissances nucl\u00e9aires comme il en a l&rsquo;exp\u00e9rience en tant que magnat de l&rsquo;immobilier new-yorkais, ou peut-\u00eatre est-ce parce que l&rsquo;orgueil imp\u00e9rial a pourri le cerveau d&rsquo;\u00e0 peu pr\u00e8s tout le monde dans l&rsquo;establishment am\u00e9ricain. Mais le plan pour ren\u00e9gocier le trait\u00e9 INF est aussi stupide que l&rsquo;on peut imaginer :<\/p>\n<\/p>\n<p><p>1). Accuser la Russie de violer le trait\u00e9 INF sans aucun \u00e9l\u00e9ment de preuve tout en ignorant les efforts de la Russie pour d\u00e9montrer que l&rsquo;accusation est fausse ;<\/p>\n<\/p>\n<p><p>2). Annoncer le retrait du trait\u00e9 INF ;<\/p>\n<\/p>\n<p><p>3). Attendre un peu, puis annoncer que le trait\u00e9 INF est important et essentiel ;<\/p>\n<\/p>\n<p><p>4). Condescendre \u00e0 pardonner \u00e0 la Russie et offrir de signer un nouveau trait\u00e9, mais exiger qu&rsquo;il inclue la Chine ;<\/p>\n<\/p>\n<p><p>5). Attendre que la Russie convainque la Chine de le faire ;<\/p>\n<\/p>\n<p><p>6). Signe le nouveau trait\u00e9 dans la <em>&laquo; grande et belle salle &raquo;<\/em>de Trump<em>.<\/em><\/p>\n<\/p>\n<p><p>Alors, comment cela s&rsquo;est pass\u00e9 ? En r\u00e9ponse \u00e0 la d\u00e9cision US, la Russie a instantan\u00e9ment annonc\u00e9 qu&rsquo;elle se retirait \u00e9galement du trait\u00e9 INF. Poutine a ordonn\u00e9 au ministre des Affaires \u00e9trang\u00e8res Lavrov de s&rsquo;abstenir d\u00e9sormais de proposer toute n\u00e9gociation avec les Am\u00e9ricains dans cette affaire. Il a ensuite ordonn\u00e9 au ministre de la D\u00e9fense, M. Shoigu, de construire des plates-formes terrestres pour les nouveaux syst\u00e8mes de missiles a\u00e9riens et navals de la Russie, sans augmenter le budget de la d\u00e9fense. Poutine a ajout\u00e9 que ces nouveaux syst\u00e8mes terrestres ne seront d\u00e9ploy\u00e9s qu&rsquo;en r\u00e9ponse au d\u00e9ploiement d&rsquo;armes \u00e0 port\u00e9e interm\u00e9diaire de fabrication am\u00e9ricaine. Oh, et la Chine a annonc\u00e9 qu&rsquo;elle n&rsquo;\u00e9tait pas int\u00e9ress\u00e9e par de telles n\u00e9gociations. Maintenant, Trump peut avoir sa <em>&laquo; grande et belle salle &raquo;<\/em> pour y parader tout seul.<\/p>\n<\/p>\n<p><p>Pourquoi cela s&rsquo;est-il produit ? Gr\u00e2ce au trait\u00e9 INF, la Russie avait depuis longtemps un \u00e9norme trou b\u00e9ant dans son arsenal, en particulier dans la zone de 500 \u00e0 5500 km. Elle avait des X-101\/102 lanc\u00e9s par voie a\u00e9rienne, puis elle a mis au point le missile de croisi\u00e8re Kalibr, mais elle disposait de peu d&rsquo;avions et de peu de navires &ndash; assez pour assurer sa d\u00e9fense, mais pas assez pour garantir qu&rsquo;elle pourrait d\u00e9truire de fa\u00e7on fiable l&rsquo;OTAN dans son ensemble. En ce qui concerne la s\u00e9curit\u00e9 nationale de la Russie, \u00e9tant donn\u00e9 la position belliqueuse permanente des &Eacute;tats-Unis, il \u00e9tait n\u00e9cessaire que l&rsquo;OTAN sache qu&rsquo;en cas de conflit militaire avec la Russie, elle serait compl\u00e8tement an\u00e9antie et qu&rsquo;aucun syst\u00e8me de d\u00e9fense a\u00e9rienne ne l&rsquo;aiderait jamais \u00e0 \u00e9viter ce sort.<\/p>\n<\/p>\n<p><p>Si vous regardez une carte, vous constaterez que le fait d&rsquo;avoir des armes dans un rayon de 500 \u00e0 5500 km r\u00e9sout assez bien ce probl\u00e8me. Dessinez un cercle d&rsquo;un rayon de 5500 km autour de l&rsquo;enclave russe de Kaliningrad ; notez qu&rsquo;il englobe tous les pays de l&rsquo;OTAN, l&rsquo;Afrique du Nord et le Moyen-Orient. Le trait\u00e9 INF n&rsquo;\u00e9tait pas n\u00e9cessairement une bonne affaire pour la Russie, m\u00eame lorsqu&rsquo;il a \u00e9t\u00e9 sign\u00e9 pour la premi\u00e8re fois (rappelez-vous, Gorbatchev, qui l&rsquo;a sign\u00e9, \u00e9tait un tra&icirc;tre), mais il est devenu un accord extr\u00eamement mauvais lorsque l&rsquo;OTAN a commenc\u00e9e \u00e0 s&rsquo;\u00e9tendre vers l&rsquo;est. Mais la Russie ne pouvait pas s&rsquo;en sortir sans d\u00e9clencher une confrontation, et elle avait besoin de temps pour se remettre et se r\u00e9armer.<\/p>\n<\/p>\n<p><p>D\u00e9j\u00e0 en 2004, Poutine a annonc\u00e9 que <em>&laquo; la Russie a besoin d&rsquo;une perc\u00e9e afin d&rsquo;avoir une nouvelle g\u00e9n\u00e9ration d&rsquo;armes et de technologies &raquo;<\/em>. &Agrave; l&rsquo;\u00e9poque, les Am\u00e9ricains l&rsquo;ignoraient, pensant que la Russie pouvait s&rsquo;effondrer \u00e0 tout moment et qu&rsquo;ils pourraient profiter gratuitement et pour toujours du p\u00e9trole, du gaz, du combustible nucl\u00e9aire et d&rsquo;autres produits strat\u00e9giques russes, m\u00eame si les Russes eux-m\u00eames s&rsquo;\u00e9teignaient. Ils pensaient que m\u00eame si la Russie tentait de r\u00e9sister, il suffirait de soudoyer certains tra&icirc;tres &ndash; comme Gorbatchev ou Eltsine &ndash; et tout irait bien \u00e0 nouveau.<\/p>\n<\/p>\n<p><p>Si on fait une bond de 15 ans dans le tempos, qu&rsquo;est-ce que nous avons ? La Russie s&rsquo;est reconstruite et r\u00e9arm\u00e9e. Ses industries d&rsquo;exportation assurent une balance commerciale positive m\u00eame en l&rsquo;absence d&rsquo;exportations de p\u00e9trole et de gaz. Elle construit trois grands pipelines d&rsquo;exportation en m\u00eame temps vers l&rsquo;Allemagne, la Turquie et la Chine. Elle d\u00e9veloppe la capacit\u00e9 de production d&rsquo;\u00e9nergie nucl\u00e9aire dans le monde entier et poss\u00e8de la part du lion de l&rsquo;industrie nucl\u00e9aire mondiale. Les &Eacute;tats-Unis ne peuvent plus garder leurs lumi\u00e8res allum\u00e9es sans les importations russes de combustible nucl\u00e9aire. Les &Eacute;tats-Unis n&rsquo;ont pas de nouveaux syst\u00e8mes d&rsquo;armes pour contrer le r\u00e9armement de la Russie. Oui, ils parlent d&rsquo;en d\u00e9velopper, mais tout ce qu&rsquo;ils ont pour l&rsquo;instant, ce sont des puits d&rsquo;argent sans fond et beaucoup de pr\u00e9sentations PowerPoint. Il n&rsquo;y a plus les cerveaux pour faire le travail, ou le temps, ou l&rsquo;argent.<\/p>\n<\/p>\n<p><p>Une partie des ordres de Poutine, lorsqu&rsquo;il s&rsquo;est retir\u00e9 du trait\u00e9 INF, \u00e9tait de construire des missiles hypersoniques terrestres \u00e0 moyenne port\u00e9e. C&rsquo;est une nouvelle tournure des \u00e9v\u00e9nements : non seulement il sera impossible de les intercepter, mais ils r\u00e9duiront de quelques minutes \u00e0 quelques secondes le temps qu&rsquo;il reste \u00e0 vivre \u00e0 l&rsquo;OTAN, si jamais elle devait attaquer la Russie. La nouvelle torpille \u00e0 propulsion nucl\u00e9aire Pos\u00e9idon a \u00e9galement \u00e9t\u00e9 mentionn\u00e9e : m\u00eame si une attaque contre la Russie r\u00e9ussissait, ce serait une victoire \u00e0 la Pyrrhus, car les tsunamis de 30 m\u00e8tres de hauts d\u00e9clench\u00e9s par les armes nucl\u00e9aires nettoieront les deux c\u00f4tes des &Eacute;tats-Unis sur des centaines de kilom\u00e8tres dans les terres, r\u00e9duisant ainsi le pays entier \u00e0 un terrain vague l\u00e9g\u00e8rement radioactif.<\/p>\n<\/p>\n<p><p>Non seulement les &Eacute;tats-Unis ont perdu leur capacit\u00e9 d&rsquo;attaquer, mais ils ont \u00e9galement perdu leur capacit\u00e9 de menacer. Leur principal moyen de projeter leur force dans le monde entier est leur marine, et Pos\u00e9idon l&rsquo;a r\u00e9duit \u00e0 un tas de ferraille inutile et lente \u00e0 se d\u00e9placer. Il suffirait d&rsquo;une poign\u00e9e de Pos\u00e9idons qui suivent discr\u00e8tement chaque groupe de porte-avions am\u00e9ricains pour r\u00e9duire \u00e0 z\u00e9ro la valeur strat\u00e9gique de la marine am\u00e9ricaine, o&ugrave; qu&rsquo;elle soit d\u00e9ploy\u00e9e dans le monde.<\/p>\n<\/p>\n<p><p>Sans les entraves du trait\u00e9 INF, la Russie sera en mesure de neutraliser compl\u00e8tement l&rsquo;OTAN d\u00e9j\u00e0 obsol\u00e8te et inutile et d&rsquo;absorber toute l&rsquo;Europe dans sa sph\u00e8re de s\u00e9curit\u00e9. Les politiciens europ\u00e9ens sont assez mall\u00e9ables et apprendront bient\u00f4t \u00e0 appr\u00e9cier le fait que de bonnes relations avec la Russie et la Chine sont un atout alors que toute d\u00e9pendance \u00e0 l&rsquo;\u00e9gard des &Eacute;tats-Unis, si cela continue, constitue un \u00e9norme handicap. Beaucoup d&rsquo;entre eux comprennent d\u00e9j\u00e0 dans quel sens le vent souffle.<\/p>\n<\/p>\n<p><p>Ce ne sera pas une d\u00e9cision difficile \u00e0 prendre pour les dirigeants europ\u00e9ens. D&rsquo;un c\u00f4t\u00e9, il y a la perspective d&rsquo;une Grande Eurasie pacifique et prosp\u00e8re, de Lisbonne \u00e0 Vladivostok et de Mourmansk \u00e0 Mumbai, assur\u00e9e par le parapluie nucl\u00e9aire de la Russie et li\u00e9e avec le projet <em>One Belt One Road<\/em>de la Chine.<\/p>\n<\/p>\n<p><p>De l&rsquo;autre c\u00f4t\u00e9 du spectre, il y a une ancienne colonie obscure perdue dans la nature sauvage de l&rsquo;Am\u00e9rique du Nord, impr\u00e9gn\u00e9e d&rsquo;une foi in\u00e9branlable dans son propre exceptionnalisme alors m\u00eame qu&rsquo;elle s&rsquo;affaiblit, que la guerre civile gronde en son sein ce qui la rend encore plus dangereuse, mais surtout pour elle-m\u00eame, et qui est dirig\u00e9e par un bouffon qui ne peut faire la diff\u00e9rence entre un trait\u00e9 sur les armes nucl\u00e9aires et une affaire immobili\u00e8re. Ce pays a besoin d&rsquo;\u00eatre rel\u00e9gu\u00e9 discr\u00e8tement et pacifiquement \u00e0 la p\u00e9riph\u00e9rie de la civilisation, puis aux marges de l&rsquo;Histoire.<\/p>\n<\/p>\n<p><p>Trump devrait profiter de sa propre compagnie dans sa &laquo;<em> grande et belle salle <\/em>&raquo;, et \u00e9viter de faire quoi que ce soit de plus tragiquement stupide, tandis que les esprits plus raisonnables n\u00e9gocient tranquillement les conditions d&rsquo;une honorable capitulation. La seule strat\u00e9gie de sortie acceptable pour les &Eacute;tats-Unis est de renoncer discr\u00e8tement et pacifiquement \u00e0 leur position dans le monde, de se retirer dans leur propre zone g\u00e9ographique et de s&rsquo;abstenir de s&rsquo;ing\u00e9rer dans les affaires de la Grande Eurasie.<\/p>\n<\/p>\n<p><p>(Le 5 f\u00e9vrier 2019, <a href=\"http:\/\/cluborlov.blogspot.com\/2019\/02\/rip-inf-treaty-russias-victory-americas.html\">Club Orlov<\/a>, &ndash; Traduction du <a href=\"http:\/\/lesakerfrancophone.fr\/mort-du-traite-inf\">Sakerfrancophone<\/a>.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mort du trait\u00e9 INF Victoire de la Russie, Waterloo de l&rsquo;Am\u00e9rique Le 1er mars 2018, le monde a appris l&rsquo;existence des nouveaux syst\u00e8mes d&rsquo;armes de la Russie, qui seraient fond\u00e9s sur de nouveaux principes physiques. S&rsquo;adressant \u00e0 l&rsquo;Assembl\u00e9e f\u00e9d\u00e9rale, M. Poutine a expliqu\u00e9 comment ils en \u00e9taient arriv\u00e9s l\u00e0 : en 2002, les &Eacute;tats-Unis&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3977,8678,3483,18869,14119,2970,584,916,5231,2730,5770,4495],"class_list":["post-78467","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-chine","tag-fni","tag-gorbatchev","tag-grappes","tag-hypersoniques","tag-missiles","tag-otan","tag-poutine","tag-premiere","tag-russie","tag-strategiques","tag-traite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78467"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78467\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}