{"id":78492,"date":"2025-07-30T11:12:44","date_gmt":"2025-07-30T11:12:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/07\/30\/rapsit-usa2025-god-saves-america\/"},"modified":"2025-07-30T11:12:44","modified_gmt":"2025-07-30T11:12:44","slug":"rapsit-usa2025-god-saves-america","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/07\/30\/rapsit-usa2025-god-saves-america\/","title":{"rendered":"RapSit-USA2025\u00a0: \u201c<em>God Saves America\u00a0<\/em>\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2025 : \u00ab\u00a0<em>God Saves America <\/em>\u00ab\u00a0<\/h2>\n<\/p>\n<p><p>Le journaliste et analyste russe Youri Podolyaka a choisi dans un texte publi\u00e9 en traduction anglaise dans &lsquo;<em><a href=\"https:\/\/usa.news-pravda.com\/world\/2025\/07\/29\/396316.html\">usa.news-pravda.com<\/a><\/em>&lsquo; de s&rsquo;int\u00e9resser \u00e0 la prospective courte de la situation interne des USA. On sait que c&rsquo;est pour nous le v\u00e9ritable n&oelig;ud central de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> ; les autres &lsquo;sub-crises&rsquo; en cours (Ukraine, Isra\u00ebl-Iran, Chine-Ta\u00efwan, situation interne des pays d&rsquo;Europe occidentale) ne sont que des \u00e9v\u00e9nements secondaires qui importent d&rsquo;abord par leurs effets sur la situation interne des USA, &ndash; y compris le plus grave d&rsquo;entre eux, une guerre nucl\u00e9aire, parce que cette guerre nucl\u00e9aire, par son caract\u00e8re absolu, met absolument en cause l&rsquo;existence m\u00eame des USA comme de la plupart des autres pays.<\/p>\n<\/p>\n<p><p>L&rsquo;analyse de Podolyaka est centr\u00e9e, d&rsquo;une fa\u00e7on op\u00e9rationnelle, autour de la question soulev\u00e9e par Elon Musk de la cr\u00e9ation d&rsquo;un nouveau, d&rsquo;un troisi\u00e8me parti. Cela implique, &ndash; et \u00e0 notre avis c&rsquo;est bien le cas, &ndash; une rupture politique compl\u00e8te entre Musk et Trump, d&rsquo;ores et d\u00e9j\u00e0 bien amorc\u00e9e et sans aucun doute conduite \u00e0 se mettre en place structurellement tr\u00e8s rapidement. Cette rupture, autant que les intentions potentielles de Musk, s&rsquo;appuient sur une situation que Podolyaka d\u00e9finit de la sorte :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La raison en est la d\u00e9g\u00e9n\u00e9rescence totale des \u00e9lites politiques am\u00e9ricaines actuelles et la demande de la soci\u00e9t\u00e9 am\u00e9ricaine pour de nouvelles id\u00e9es et des politiciens d&rsquo;une nouvelle formation.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Cette tendance est clairement visible dans les \u00e9lectorats \u00ab\u00a0r\u00e9publicain\u00a0\u00bb et \u00ab\u00a0d\u00e9mocrate\u00a0\u00bb. Le premier devient de plus en plus \u00ab\u00a0conservateur\u00a0\u00bb, et le second, socialiste radical de gauche.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>M\u00eame un pr\u00e9sident aussi radical que Donald Trump, en apparence, pour la politique am\u00e9ricaine, para&icirc;t d\u00e9j\u00e0 trop lib\u00e9ral et non radical aux yeux de son \u00e9lectorat \u00ab\u00a0ardent\u00a0\u00bb dit MAGA. Ainsi, le mois dernier, le vice-pr\u00e9sident J. D. Vance s&rsquo;est marginalis\u00e9 et s&rsquo;\u00e9loigne de plus en plus du pr\u00e9sident actuel. Il se pr\u00e9pare d\u00e9j\u00e0 ouvertement aux \u00e9lections de 2028, o&ugrave; il sera clairement le principal candidat des \u00ab\u00a0R\u00e9publicains\u00a0\u00bb. Mais pas ceux d&rsquo;il y a 4 ou 5 ans. Vance est le candidat de l&rsquo;\u00e9lectorat MAGA, ce qui entra&icirc;nera les \u00ab\u00a0R\u00e9publicains\u00a0\u00bb (s&rsquo;ils ne se divisent pas d&rsquo;ici l\u00e0) vers un parti beaucoup plus \u00e0 droite et \u00ab\u00a0isolationniste\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>D&rsquo;autre part, les campagnes municipales de New York et de Minneapolis montrent que les jeunes socialistes de gauche gagnent en popularit\u00e9 dans le camp d\u00e9mocrate, face auquel Bernie Sanders, qui se retire de la politique et \u00e9tait auparavant le chef informel de cette aile des \u00ab\u00a0D\u00e9mocrates\u00a0\u00bb, n&rsquo;est qu&rsquo;un conservateur inv\u00e9t\u00e9r\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Podolyaka estime que l&rsquo;enjeu est capital, c&rsquo;est-\u00e0-dire existentiel pour les &Eacute;tats-Unis. Il prend en compte la situation de terrible d\u00e9cadence des cadres dirigeants des deux partis et autres personnes d&rsquo;importance, une situation qui est mise en \u00e9vidence d&rsquo;une fa\u00e7on obsc\u00e8ne par divers scandales, dont l&rsquo;affaire Epstein est l&rsquo;exemple le plus \u00e9clatant et le plus accablant.<\/p>\n<\/p>\n<p><p>C&rsquo;est dire qu&rsquo;il existe des cons\u00e9quences et des n\u00e9cessit\u00e9s particuli\u00e8rement graves et pressantes.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Ceci repr\u00e9sente deux menaces majeures pour les \u00e9lites politiques des &Eacute;tats-Unis (et du pays tout entier). Premi\u00e8rement, cette polarisation de l&rsquo;\u00e9lectorat est l&rsquo;un des signes les plus importants d&rsquo;une temp\u00eate politique imminente mena\u00e7ant de plonger le pays dans la guerre civile. Deuxi\u00e8mement, avec l&rsquo;exode massif des \u00ab\u00a0R\u00e9publicains\u00a0\u00bb et des \u00ab\u00a0D\u00e9mocrates\u00a0\u00bb radicaux dans les cercles politiques, un vide se cr\u00e9e au centre. Ce vide sera certainement combl\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Qu&rsquo;est-ce qui comblera ce vide ? Une seule alternative : une nouvelle force politique ou la guerre civile. Les r\u00e9centes d\u00e9clarations d&rsquo;Elon Musk sont \u00e9videmment le signe le plus clair de la n\u00e9cessit\u00e9 de cette \u00ab\u00a0nouvelle force politique\u00a0\u00bb. Il est le mieux plac\u00e9 pour tenter de la mettre en place, sans aucune certitude d&rsquo;aucune sorte en raison du caract\u00e8re un peu fantasque de l&rsquo;homme, des forces politiques et financi\u00e8res qui lui sont oppos\u00e9es, etc.<\/p>\n<\/p>\n<p><p>Podolyaka donne \u00e0 Musk des chances acceptables de r\u00e9ussir sa tentative, \u00e9galement pour des raisons objectives, des n\u00e9cessit\u00e9s vitales de la situation, et aussi l&rsquo;attente, non l&rsquo;exigence du public am\u00e9ricain pour des structures et des politiques compl\u00e8tement nouvelles. S&rsquo;il y en a un qui dispose d&rsquo;avantages r\u00e9els dans ce sens, c&rsquo;est Musk, et cela alors que l&rsquo;enjeu, l&rsquo;alternative est terrible :  <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La tentative d&rsquo;Elon Musk de cr\u00e9er une troisi\u00e8me force dans la politique am\u00e9ricaine actuelle repose sur des bases solides. De plus, c&rsquo;est sa cr\u00e9ation qui peut emp\u00eacher les &Eacute;tats-Unis de sombrer davantage dans la guerre civile. C&rsquo;est pr\u00e9cis\u00e9ment un tel projet qui peut devenir un lien stabilisateur emp\u00eachant les \u00ab\u00a0R\u00e9publicains\u00a0\u00bb et les \u00ab\u00a0D\u00e9mocrates\u00a0\u00bb en pleine radicalisation de se d\u00e9chirer<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On va \u00e0 la conclusion de Podolyaka, conclusion \u00e0 la fois \u00e9vidente et extr\u00eamement claire. Il faut absolument, dans la situation de pourrissement \u00e9pouvantable que nous connaissons aujourd&rsquo;hui, faire quelque chose ou bien le destin s&rsquo;en occupera&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Je ne sais pas si Musk cr\u00e9era son propre parti, mais s&rsquo;il ne le fait pas, d&rsquo;autres pourront le faire. Mais il fera certainement mieux<\/em>. [&#8230;] <em>Selon moi, t\u00f4t ou tard, cette n\u00e9cessit\u00e9 se concr\u00e9tisera. Sinon les &Eacute;tats-Unis ne s&rsquo;en sortiront pas bien dans les conditions actuelles<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Si cela n&rsquo;est pas fait du tout dans les conditions actuelles, alors, comme disent les Am\u00e9ricains, \u00ab\u00a0Dieu sauve l&rsquo;Am\u00e9rique\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Le n&oelig;ud de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> du monde (refrain)<\/h3>\n<\/p>\n<p><p>Oui, c&rsquo;est bien notre propos, toujours et encore : la crise am\u00e9ricaniste comme centre, matrice, cause, influenceuse, d\u00e9clencheuse et irr\u00e9sistible entra&icirc;neuse de la crise du monde. Cela, nous le savons, ou croyons le savoir, et le disons depuis longtemps, &ndash; depuis <a href=\"https:\/\/www.dedefensa.org\/article\/de-la-1992-a-la-2017\">le  printemps 1992<\/a> et les \u00e9meutes de Los Angeles pour la s\u00e9quence actuelle. Ce qui a  peut-\u00eatre chang\u00e9, &ndash; une fois de plus, une correction prospective, &ndash; c&rsquo;est, depuis quelques semaines, un mois et des poussi\u00e8res, \u00e0 peine plus, la sensation, &ndash; un sentiment intuitif puisque rien n&rsquo;est assur\u00e9, &ndash; que Trump est irr\u00e9sistiblement emport\u00e9 dans ses humeurs d\u00e9lirantes et tombe \u00e9videmment dans le pi\u00e8ge grossier et gros comme la Statue de la Libert\u00e9 tendu par simple r\u00e9flexe d&rsquo;automatisme robotis\u00e9 par les zombies que sont les <em>neocon<\/em>, men\u00e9s par un Lindsey Graham parfait dans le r\u00f4le de la <em>pom pom girl <\/em>(ou <em>boum boum girl<\/em> ?).<\/p>\n<\/p>\n<p><p>Pour nous, Trump dans ses pires \u00e9lucubrations n&rsquo;a strictement rien \u00e0 voir avec une man&oelig;uvre grossi\u00e8re et absurde d&rsquo;un <em>DeepState <\/em>en compl\u00e8te d\u00e9liquescence. C&rsquo;est simplement une pathologie de narcissique Formule 1, doubl\u00e9 d&rsquo;un pervers grossier sans la moindre parcelle de dext\u00e9rit\u00e9 \u00e0-la-Sade sinon le maniement du dollar. Nous pensions qu&rsquo;il pouvait renverser tout cela et utiliser ses qualit\u00e9s de fouteur de bordel au d\u00e9triment du <em>DeepState<\/em>, emport\u00e9 par un \u00e9lan de populisme habilement manipul\u00e9.<\/p>\n<\/p>\n<p><p>Rien du tout, semble-t-il. Il est &lsquo;<em>unhappy<\/em>&lsquo; du comportement de Poutine qu&rsquo;il voudrait punir en lui faisant \u00e9crire 500 fois \u00ab\u00a0J&rsquo;ob\u00e9irais d\u00e9sormais au ma&icirc;tre de la classe globale\u00a0\u00bb, mais Poutine ne mange pas de ce pain-l\u00e0. Trump devra donc se contenter du couple Zelenski-Netanyahou : du grand cru. Il n&rsquo;a m\u00eame pas su profiter de la formidable trouvaille en train d&rsquo;\u00eatre constitu\u00e9e par une Gabbard au courage magnifique (&laquo; <em>Tulsi Gabbard has cemented herself a place in history<\/em> &raquo;, <a href=\"https:\/\/www.rt.com\/news\/622159-tulsi-gabbard-russiagate-history\/\">\u00e9crit Robert Brtidge<\/a>), qui finira par lui offrir sur un plateau la t\u00eate d&rsquo;Obama-le-tra&icirc;tre, le Claudius oncle et beau-p\u00e8re incestueux de Hamlet, &ndash; il (Trump) n&rsquo;y verra que du feu, uniquement pr\u00e9occup\u00e9 de calculer la dur\u00e9e de son prochain et ni\u00e8me ultimatum, &ndash; sans doute adress\u00e9 \u00e0 Hamlet, car Trump, en raison d&rsquo;une culture fort dispers\u00e9e,  se trompe facilement d&rsquo;ennemi, d&rsquo;\u00e9poque et d&rsquo;interlocuteur.<\/p>\n<\/p>\n<p><p>Pour cette raison principalement, si les choses se poursuivent dans ce sens comme c&rsquo;est sans doute assez probable semble-t-il, Trump s&rsquo;est install\u00e9 dans le r\u00f4le d&rsquo;un super-Joe Biden, encha&icirc;nant la catastrophe sur la catastrophe d\u00e9j\u00e0 en cours. A cette lumi\u00e8re sinistre et lugubre, dispens\u00e9e par les lampes de veille de l&rsquo;h\u00f4pital psychiatrique, effectivement le sch\u00e9ma de Podolyaka a du sens. Et parce que n&rsquo;avons qu&rsquo;une confiance limit\u00e9e dans la capacit\u00e9 de l&rsquo;Am\u00e9rique d&rsquo;absorber un Musk en calmant ses ardeurs d\u00e9sordonn\u00e9es et en en faisant son sauveur, l&rsquo;on  rejoint alors les pires pr\u00e9dictions des plus pessimistes de quelques personnages historiques si souvent cit\u00e9s ici :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p> &laquo; <em>Si la destruction devait un jour nous atteindre, nous devrions en \u00eatre nous-m\u00eames les premiers et les ultimes artisans. En tant que nation d&rsquo;hommes libres, nous devons \u00e9ternellement survivre, ou mourir en nous suicidant<\/em> &raquo;(le pr\u00e9sident Lincoln).<\/p>\n<\/p>\n<p><p> &laquo; <em>Les &Eacute;tats-Unis sont destin\u00e9s \u00e0 remplacer et \u00e0 surpasser l&rsquo;histoire merveilleuse des temps f\u00e9odaux ou ils constitueront le plus retentissant \u00e9chec que le monde ait jamais connu&hellip;<\/em> &raquo; (Walt Whitman, po\u00e8te).<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Enfin, et pour se consoler,, ce n&rsquo;est pas si mal comme destin  catastrophique : se suicider en entra&icirc;nant avec soi la catastrophique civilisation que nous connaissons, qui avait r\u00e9ussi \u00e0 d\u00e9truire &laquo; <em>l&rsquo;histoire merveilleuse des temps f\u00e9odaux<\/em> &raquo; en croyant ainsi en \u00eatre quitte avec le destin m\u00e9tahistorique du monde.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0<em>God Saves America<\/em>\u00a0\u00bb ? Mais Dieu a beaucoup \u00e0 faire, il est pass\u00e9 \u00e0 autre chose, vous savez&#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 30 juillet 2025 \u00e0 11H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2025 : \u00ab\u00a0God Saves America \u00ab\u00a0 Le journaliste et analyste russe Youri Podolyaka a choisi dans un texte publi\u00e9 en traduction anglaise dans &lsquo;usa.news-pravda.com&lsquo; de s&rsquo;int\u00e9resser \u00e0 la prospective courte de la situation interne des USA. On sait que c&rsquo;est pour nous le v\u00e9ritable n&oelig;ud central de la GrandeCrise ; les autres &lsquo;sub-crises&rsquo; en cours&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[3066,2880,2631,2985,2645,10033,13196,2647,5623,18902,8273,2639,14312],"class_list":["post-78492","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-americaniste","tag-civile","tag-de","tag-fin","tag-guerre","tag-lamerique","tag-musk","tag-nouveau","tag-parti","tag-podolyaka","tag-prospective","tag-trump","tag-youri"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78492"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78492\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}