{"id":78501,"date":"2019-03-05T02:55:33","date_gmt":"2019-03-05T02:55:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/05\/une-incivilite-de-gangsters-devoyes\/"},"modified":"2019-03-05T02:55:33","modified_gmt":"2019-03-05T02:55:33","slug":"une-incivilite-de-gangsters-devoyes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/05\/une-incivilite-de-gangsters-devoyes\/","title":{"rendered":"Une \u201cincivilit\u00e9\u201d de gangsters d\u00e9voy\u00e9s"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une \u00ab\u00a0incivilit\u00e9\u00a0\u00bb de gangsters d\u00e9voy\u00e9s<\/h2>\n<\/p>\n<p><p> L&rsquo;une des caract\u00e9ristiques psychologiques refl\u00e9tant la crise du pouvoir aux USA, c&rsquo;est ce qui est d\u00e9sign\u00e9 <strong>comme l'\u00a0\u00bbincivilit\u00e9\u00a0\u00bb<\/strong>, c&rsquo;est-\u00e0-dire <strong>la d\u00e9gradation des relations au niveau de la communication publique<\/strong>, \u00e0 la fois \u00e0 l&rsquo;int\u00e9rieur du monde politique washingtonien entre politiciens, \u00e0 la fois dans les relations internationales. Cette d\u00e9gradation se r\u00e9percute \u00e9videmment au niveau de la politique elle-m\u00eame <strong>autant qu&rsquo;elle en est l&rsquo;effet<\/strong>, et cette politique devenue compl\u00e8tement vide en perdant toute substance <strong>n&rsquo;est plus que l&rsquo;\u00e9cho d&rsquo;une communication devenue catastrophique<\/strong>.<\/p>\n<\/p>\n<p><p>Le parall\u00e8le fait entre le monde politique washingtonien et le monde du \u00ab\u00a0crime organis\u00e9\u00a0\u00bb US, comme <a href=\"http:\/\/www.dedefensa.org\/article\/suite-en-marron-glace\">nous l&rsquo;avons fait<\/a> \u00e0 propos de Trump, est de plus en plus courant et visible. L&rsquo;essentiel ici n&rsquo;est pas tant la situation (que cette similitude ait \u00e9ventuellement d\u00e9j\u00e0 exist\u00e9, comme l&rsquo;affirment certains avec un cynisme d&rsquo;esprit fort) <strong>que la communication publique qui en est faite, sans le moindre souci des d\u00e9g\u00e2ts de statut et de r\u00e9putation<\/strong>. Martin Sieff,   <a href=\"http:\/\/www.dedefensa.org\/article\/locs-se-leve-a-lest\">journaliste exp\u00e9riment\u00e9<\/a> dans la vie politique US, d\u00e9veloppe une tribune furieuse, dans <em>Strategic-Culture.org <\/em>du <a href=\"https:\/\/www.strategic-culture.org\/news\/2019\/03\/04\/deeper-lessons-of-marco-rubio-murder-threat-tweet.html\">4 mars 2019<\/a> \u00e0 propos du comportement du s\u00e9nateur Marco Rubio, qui a menac\u00e9 le pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Maduro d&rsquo;une mort par torture \u00ab\u00a0\u00e0-la-Kadhafi\u00a0\u00bb (voir et entendre l&rsquo;\u00e9l\u00e9gant &laquo; <em><a href=\"http:\/\/www.dedefensa.org\/article\/we-came-we-saw-he-died\">We came, we saw, he died<\/a> <\/em>&raquo; d&rsquo;Hillary Clinton). Sieff insiste sur l&rsquo;extr\u00eame pauvret\u00e9 de caract\u00e8re et de comportement du s\u00e9nateur, reflet du niveau de la vie politique US \u00e0 ce degr\u00e9 d&rsquo;effondrement du Syst\u00e8me se r\u00e9percutant sur le \u00ab\u00a0recrutement\u00a0\u00bb et par cons\u00e9quent sur les attitudes publiques. <\/p>\n<\/p>\n<p><p>Pour le personnage (Rubio) qui pr\u00e9tend \u00e0 un r\u00f4le politique important, dans la crise v\u00e9n\u00e9zu\u00e9lienne comme dans la direction US, Sieff n&rsquo;a que sarcasme et m\u00e9pris. &laquo; <em>Il est facile de se moquer de Rubio, mais les dommages qu&rsquo;il fait \u00e0 la r\u00e9putation de son pays dans le monde et \u00e0 la cause cruciale de la paix dans le monde sont consid\u00e9rables<\/em>. [&#8230;] <em>Rubio n&rsquo;a probablement m\u00eame pas r\u00e9alis\u00e9 ce qu&rsquo;il faisait, il a toujours \u00e9t\u00e9 un opportuniste superficiel et <\/em>[un corrompu] <em>\u00e0 bon march\u00e9<\/em>. &raquo; L\u00e0-dessus Sieff fait cette comparaison avec le \u00ab\u00a0crime organis\u00e9\u00a0\u00bb (\u00ab\u00a0Syndicat du Crime\u00a0\u00bb, ou <em>Cosa Nostra <\/em>[<em>Mafia <\/em>USA]) pour observer que <strong>les politiciens US sont tomb\u00e9s \u00e0 un niveau de comportement public bien plus bas que celui des dirigeants de ces milieux<\/strong>. C&rsquo;est une mesure de la d\u00e9gradation acc\u00e9l\u00e9r\u00e9e, structurelle et psychologique, et par cons\u00e9quent op\u00e9rationnelle du monde politique US : le jugement <strong>est celui de la \u00ab\u00a0morale op\u00e9rationnelle\u00a0\u00bb<\/strong>, car l&rsquo;on ne peut continuer de fonctionner avec un tel comportement <strong>de bassesse et de n\u00e9ant intellectuels, et de barbarie \u00e0 visage sous-humain \u00e9tal\u00e9e publiquement<\/strong>.<\/p>\n<\/p>\n<p><p>&laquo; <em>Que peut-on dire de l&rsquo;\u00e9tonnant <a href=\"https:\/\/www.rt.com\/news\/452329-rubio-gaddafi-venezuela-tweet\/\">message Twitter<\/a> du s\u00e9nateur Marco Rubio mena\u00e7ant le pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Nicolas Maduro du m\u00eame sort que le meurtre par la torture, avec empalement par une bouteille bris\u00e9e, de Muammar Kadhafi, dirigeant de la Libye depuis 43 ans, en 2011 ? <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il y a beaucoup \u00e0 en dire.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Tout d&rsquo;abord, m\u00eame en se r\u00e9f\u00e9rant aux obsc\u00e9nit\u00e9s et \u00e0 la puanteur publiques illimit\u00e9es de la culture politique am\u00e9ricaine des XXe et XXIe si\u00e8cles, la menace publique de Rubio est sans pr\u00e9c\u00e9dent.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Les nazis se sont comport\u00e9s de cette fa\u00e7on. Les gangsters se comportent parfois de la sorte lorsqu&rsquo;ils prennent le pouvoir sur des territoires plus ou moins importants. Souvent, ceux qui se comportent aussi sont jug\u00e9s s\u00e9v\u00e8rement par leurs pairs et ostracis\u00e9s par eux. Les exc\u00e8s publics et les brutalit\u00e9s d&rsquo;Al Capone, de Dutch Schultz et d&rsquo;Albert Anastasia des ann\u00e9es 1920 aux ann\u00e9es 1950 ont \u00e9t\u00e9 si importants et choquants que m\u00eame les autres chefs du Syndicat du Crime (\u00ab\u00a0crime organis\u00e9\u00a0\u00bb) aux USA refusaient de leur serrer la main.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>On peut ainsi juger aujourd&rsquo;hui que des personnages tels que Lucky Luciano, le grand cerveau de la prostitution et de la contrebande d&rsquo;h\u00e9ro\u00efne vers l&rsquo;Am\u00e9rique des ann\u00e9es 1920 aux ann\u00e9es 1950, et Frank Costello, le soi-disant \u00ab\u00a0Premier ministre du Syndicat du Crime\u00a0\u00bb, avaient bien plus de tenue et un comportement public plus convenable que les membres actuels du S\u00e9nat des &Eacute;tats-Unis.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Luciano et Costello d\u00e9sapprouvaient de tels comportements brutaux et grossiers en public et recommandaient \u00e0 leurs hommes et \u00e0 leurs pairs de fa\u00e7on pressante de suivre leur exemple, souvent en exer\u00e7ant des repr\u00e9sailles meurtri\u00e8res contre ceux qui ne se conformaient pas \u00e0 cette \u00ab\u00a0civilit\u00e9\u00a0\u00bb. Au contraire, on constate que pas un seul s\u00e9nateur am\u00e9ricain n&rsquo;a condamn\u00e9 Rubio pour avoir pris une initiative publique aussi \u00e9c&oelig;urante que cet appel largement diffus\u00e9 au meurtre dans des conditions aussi ignobles<\/em>&hellip; &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 5 mars 2019 \u00e0 02H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00ab\u00a0incivilit\u00e9\u00a0\u00bb de gangsters d\u00e9voy\u00e9s L&rsquo;une des caract\u00e9ristiques psychologiques refl\u00e9tant la crise du pouvoir aux USA, c&rsquo;est ce qui est d\u00e9sign\u00e9 comme l&rsquo;\u00a0\u00bbincivilit\u00e9\u00a0\u00bb, c&rsquo;est-\u00e0-dire la d\u00e9gradation des relations au niveau de la communication publique, \u00e0 la fois \u00e0 l&rsquo;int\u00e9rieur du monde politique washingtonien entre politiciens, \u00e0 la fois dans les relations internationales. Cette d\u00e9gradation se&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[18908,18909,14968,18907,8039,18912,18911,10891,16363,2813,11603,2627,18910,4845,3305,5050],"class_list":["post-78501","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-anastasia","tag-came","tag-capone","tag-costello","tag-crime","tag-died","tag-he","tag-kadhafi","tag-luciano","tag-marco","tag-organisee","tag-rubio","tag-saw","tag-sieff","tag-venezuela","tag-we"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78501"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78501\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}