{"id":78513,"date":"2019-03-13T12:02:03","date_gmt":"2019-03-13T12:02:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/13\/les-strange-24-hours-dezerohedgecom\/"},"modified":"2019-03-13T12:02:03","modified_gmt":"2019-03-13T12:02:03","slug":"les-strange-24-hours-dezerohedgecom","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/13\/les-strange-24-hours-dezerohedgecom\/","title":{"rendered":"Les \u201c<em>strange 24 hours<\/em>\u201d de\u00a0<em>ZeroHedge.com<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Les \u00ab\u00a0<em>strange 24 hours<\/em>\u00a0\u00bb de <em>ZeroHedge.com<\/em><\/h2>\n<\/p>\n<p><p>Le texte ci-dessous a \u00e9t\u00e9 mis en ligne par le site <em>ZeroHedge.com <\/em>hier \u00e0 19H59, dans la nuit (\u00e0 02H59) pour nous. Comme nous faisons pour certains textes qui nous semblent assez ais\u00e9ment compr\u00e9hensibles et qu&rsquo;il nous para&icirc;t important de publier rapidement dans leur forme originale, c&rsquo;est-\u00e0-dire autant par manque de temps pour les traduire que parce qu&rsquo;il est d&rsquo;un certain int\u00e9r\u00eat de respecter cette forme originale, nous le reprenons tel que. Il s&rsquo;agit d&rsquo;une \u00e9trange et tr\u00e8s rapide odyss\u00e9e \u00e0 laquelle a \u00e9t\u00e9 contraint le site <em>ZeroHedge.com<\/em>du fait du tout-puissant Facebook dont le comportement s&rsquo;est r\u00e9v\u00e9l\u00e9, <strong>cette fois d&rsquo;une mani\u00e8re \u00e9vidente et r\u00e9v\u00e9latrice<\/strong>, \u00e0 la fois arbitraire, aveugle et primaire, <strong>et compl\u00e8tement erratique<\/strong>.<\/p>\n<\/p>\n<p><p>Le r\u00e9cit, forme vertueuse de ce que nous d\u00e9signons d&rsquo;habitude comme <em>narrative<\/em>, <strong>est pour ce cas simple et sans \u00e9quivoque possible, &ndash; sinon dans les intentions, certes<\/strong>. Lundi matin, sans avoir eu un mot d&rsquo;explication, sans qu&rsquo;aucun contact pr\u00e9alable ou courant n&rsquo;ait \u00e9t\u00e9 pris, <em>ZeroHedge.com <\/em>apprenait que ses r\u00e9f\u00e9rences, citations, URL, etc. avaient \u00e9t\u00e9 bannis depuis deux jours des mises en ligne de Facebook ; il s&rsquo;agissait d&rsquo;un simple avis de Facebook \u00e0 ses utilisateurs, selon lequel <em>ZeroHedge.com <\/em>diffusait du mat\u00e9riel \u00e9ditorial contrevenant aux \u00ab\u00a0standards de la communaut\u00e9 Facebook\u00a0\u00bb (&laquo; <em>lequel standard, au mieux de notre connaissance, dont ni nous ni quiconque d&rsquo;autre n&rsquo;a la moindre id\u00e9e de ce qu&rsquo;ils sont <\/em>&raquo;, commente <em>ZeroHedge.com<\/em>). Apr\u00e8s publication d&rsquo;un premier texte de <em>ZeroHedge.<\/em>com, la journ\u00e9e de lundi vit un flot de tweets de soutien (les autres \u00ab\u00a0grands\u00a0\u00bb de la dictature de l&rsquo;internet n&rsquo;\u00e9tant pas concern\u00e9s) de nombre de personnalit\u00e9s, y compris du fils du pr\u00e9sident Trump. (Quel que soit l&rsquo;avis qu&rsquo;on entretient \u00e0 son propos, <em>ZeroHedge.com <\/em>est l&rsquo;un des plus importants sinon le plus important site d&rsquo;information financi\u00e8re et g\u00e9opolitique alternatif\/de la presse antiSyst\u00e8me.) &laquo; <em>Et soudain, dans la matin\u00e9e de mardi, tout redevint normal, que ce soit la cons\u00e9quence de prudence devant la puissance des r\u00e9actions n\u00e9gatives, ou vraiment une erreur de Facebook&#8230;<\/em> &raquo; Effectivement, Facebook a publi\u00e9 un communiqu\u00e9 alambiqu\u00e9 o&ugrave; il est question d&rsquo;une erreur de la \u00ab\u00a0r\u00e9action automatique\u00a0\u00bb de Facebook lorsqu&rsquo;un <em>spam <\/em>(un \u00ab\u00a0m\u00e9chant\u00a0\u00bb en langage courant) est d\u00e9tect\u00e9, cette \u00ab\u00a0r\u00e9action automatique\u00a0\u00bb \u00e9tant compl\u00e9t\u00e9 par une intervention humaine qui semble cette fois avoir \u00e9t\u00e9 assez languissante et inattentive dans l&rsquo;incident.<\/p>\n<\/p>\n<p><p>Peu importent les causes et les intentions de l&rsquo;incident, ils ne nous apprendraient rien que nous ne sachions d\u00e9j\u00e0 sur la mentalit\u00e9 de Facebook. Par contre, on peut se risquer \u00e0 <strong>quelques remarques et hypoth\u00e8ses g\u00e9n\u00e9rales, portant sur le comportement et l&rsquo;op\u00e9rationnalit\u00e9 du monde des GAFA<\/strong>, qui se sont institu\u00e9s gardien de la moraline-Syst\u00e8me au nom de vertus telles que l&rsquo;arbitraire monopolistique, la puissance de l&rsquo;argent, <strong>la servilit\u00e9 au service du pouvoir exer\u00e7ant les <em>diktat <\/em>du Syst\u00e8me, le go&ucirc;t quasi-pathologique de la censure<\/strong>.<\/p>\n<\/p>\n<p><p>On est conduit \u00e0 observer que se v\u00e9rifie de plus en plus une loi \u00e9tonnamment contradictoire, caract\u00e9ristique de la situation et des tendance du Syst\u00e8me (\u00e0 la fois surpuissance et autodestruction). Le Syst\u00e8me fonctionne, pour son influence, son embrigadement, sa manipulation, essentiellement gr\u00e2ce \u00e0 la surpuissance du syst\u00e8me de la communication <strong>qui pourrait sembler pouvoir r\u00e9duire toutes les oppositions et toutes les r\u00e9sistances <\/strong>parce qu&rsquo;il est sous le contr\u00f4le des puissances politiques et d&rsquo;argent qui travaillent avec et pour le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Cette surpuissance du syst\u00e8me de la communication a besoin, pour se manifester, de la participation active de tous, simplement parce que dans ces \u00ab\u00a0tous\u00a0\u00bb se trouvent tous ceux que le Syst\u00e8me doit influencer, manipuler, embrigader par ce canal de la communication. A cause de cette n\u00e9cessit\u00e9 de dynamisme g\u00e9n\u00e9ralis\u00e9 et non s\u00e9lectif au d\u00e9part, la surpuissance du syst\u00e8me de la communication <strong>fonctionne \u00ab\u00a0en aveugle\u00a0\u00bb pour l&rsquo;amont, oblig\u00e9 d&rsquo;attendre la faute et sa communication pour tenter de la bloquer. <\/strong>Le syst\u00e8me de la communication ne peut rien pr\u00e9voir des effets qu&rsquo;engendre sa surpuissance, qu&rsquo;il r\u00e9percute aussi bien et dont il fait caisse de r\u00e9sonnance ; cela, alors qu&rsquo;il s&rsquo;agit souvent, de plus en plus souvent dans une situation crisique g\u00e9n\u00e9rale en constante aggravation, de r\u00e9actions des utilisateurs empruntant la voie de la contestation et de la protestation jusqu&rsquo;\u00e0 faire craindre des r\u00e9actions organis\u00e9es. Pour tenter de parer \u00e0 cette regrettable \u00e9volution, il est apparu n\u00e9cessaire d&rsquo;instaurer une censure qui est tr\u00e8s d\u00e9licate <strong>parce qu&rsquo;elle se situe apr\u00e8s la diffusion des avis et des informations qu&rsquo;il faut bloquer, apr\u00e8s qu&rsquo;il ait fallu identifier et distinguer ce qu&rsquo;il faut bloquer<\/strong>, etc., dans un monde o&ugrave; existe une multitude de sources et o&ugrave; les positions et les avis sont souvent confus et difficiles \u00e0 cataloguer selon l&rsquo;habituelle subtilit\u00e9 du censeur, &ndash; entre \u00ab\u00a0gentils\u00a0\u00bb et \u00ab\u00a0m\u00e9chants\u00a0\u00bb. Tout cela se fait, d\u00e9licatesse supr\u00eame, dans des conditions de quasi-ill\u00e9galit\u00e9 au regard de la libert\u00e9 d&rsquo;expression, dans ce Syst\u00e8me <strong>qui entend par-dessus tout conserver une apparence respectable, c&rsquo;est-\u00e0-dire un simulacre de respect de la libert\u00e9 d&rsquo;expression<\/strong>. <\/p>\n<\/p>\n<p><p>Le syst\u00e8me de la communication et la toile monstrueuse qu&rsquo;il a cr\u00e9\u00e9 avec l&rsquo;internet constituent, pour le Syst\u00e8me qui entendait apr\u00e8s avoir favoris\u00e9 son d\u00e9veloppement jusqu&rsquo;\u00e0 la surpuissance en faire son outil principal \u00ab\u00a0d&rsquo;influence, d&#8217;embrigadement et de manipulation\u00a0\u00bb, un monstre qui a totalement \u00e9chapp\u00e9 \u00e0 son contr\u00f4le. L'\u00a0\u00bb<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-technologisme-versus-communication-1\">effet-<em>Janus<\/em><\/a>\u00a0\u00bb est lui-m\u00eame \u00e0 son maximum de surpuissance, lui-m\u00eame totalement incontr\u00f4lable.<\/p>\n<\/p>\n<p><p>Puisqu&rsquo;il est impossible pour le Syst\u00e8me de se passer du syst\u00e8me de la communication qui conditionne sa puissance \u00e9conomique et ses entreprises d&rsquo;entropisation, il (le Syst\u00e8me) en est r\u00e9duit \u00e0 <strong>des exp\u00e9dients censureurs o&ugrave; s&rsquo;expriment sans la moindre retenue l&rsquo;amateurisme, l&rsquo;inculture, les hasards catastrophiques de l&rsquo;automatisation, l&rsquo;inintelligence artificielle<\/strong>, &ndash; tous caract\u00e8res qui sont la marque des GAFA, des Zuckerberg &#038; Cie. D&rsquo;o&ugrave; des erreurs catastrophiques de mettre en cause des acteurs quasiment-\u00ab\u00a0intouchables\u00a0\u00bb m\u00eame si de tendance antiSyst\u00e8me, parce que tr\u00e8s connus, consid\u00e9r\u00e9s comme s\u00e9rieux, ayant un lectorat important, une r\u00e9putation, etc., &ndash; comme vient de le d\u00e9montrer l&rsquo;\u00e9pisode <em>ZeroHedge.com <\/em>qui, dans l&rsquo;aventure, gagne un suppl\u00e9ment de publicit\u00e9 et de notori\u00e9t\u00e9, de nouveaux visiteurs et ainsi de suite.<\/p>\n<\/p>\n<p><p><strong>Cela fait d\u00e9sormais vingt ans exactement<\/strong>, &ndash; depuis <a href=\"http:\/\/www.dedefensa.org\/article\/notre-samizdat-globalise\">la guerre du Kosovo<\/a>, dont on f\u00eatera le triste vingti\u00e8me anniversaire dans dix jours, &ndash; que le Syst\u00e8me est <strong>en campagne pour censurer et liquider l&rsquo;opposition alternative, devenue antiSyst\u00e8me, qui se nourrit des immenses possibilit\u00e9s d&rsquo;internet<\/strong>. La m\u00e9saventure de <em>ZeroHedge.com<\/em>, \u00e0 l&rsquo;\u00e9gal par exemple des obsessions tout autant censureuses du gang-Macron et de son <em>FakeNewsisme<\/em>, nous instruit sur l&rsquo;avancement du programme.<\/p>\n<\/p>\n<p><p>Le texte de <em>ZeroHedge.com <\/em>a \u00e9t\u00e9 publi\u00e9 <a href=\"https:\/\/www.zerohedge.com\/news\/2019-03-12\/facebook-reverses-zero-hedge-ban-says-it-made-mistake\">hier soir<\/a> sur son site. Le titre complet est : &laquo; <em>Facebook Reverses Zero Hedge Ban, Says It Made A \u00ab\u00a0Mistake\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Facebook Reverses <em>ZeroHedge <\/em>Ban&#8230;<\/h2>\n<\/p>\n<p><p>It has been a strange 24 hours.<\/p>\n<\/p>\n<p><p>On Monday, we  <a href=\"https:\/\/www.zerohedge.com\/news\/2019-03-11\/facebook-bans-zero-hedge\">first learned<\/a> that for the previous two days, Facebook had banned all Zero Hedge content across its various mediums, as it went against Facebook&rsquo;s \u00ab\u00a0Community Standards\u00a0\u00bb (which to the best of our knowledge, neither we not anyone else has any idea what they are), a decision which &ndash; as we  <a href=\"https:\/\/www.zerohedge.com\/news\/2019-03-11\/facebook-bans-zero-hedge\">noted yesterday <\/a>&ndash; surprised us for two reasons : not only do we not have an official Facebook account, but Facebook did not approach us even once with a warning or even notification.<\/p>\n<\/p>\n<p><p>While we were in the dark about what had triggered Facebook, or what was the company&rsquo;s motive, we were humbled and delighted not only with the media coverage this event received, but far more so with the outpouring of support we received from readers and across social media, where Zero Hedge had not been yet banned, like Twitter, where figures from various industries and across the political spectrum voiced support and came to our defense, with many condemning what we felt was an arbitrary decision.<\/p>\n<\/p>\n<p><p>Among those who spoke up were President Trump&rsquo;s son Donald Trump Jr., Nigel Farage, Peter Thiel&rsquo;s liberal foil at Thiel Capital, Eric Weinstein, Infowars&rsquo; Paul Joseph Watson and many others.<\/p>\n<\/p>\n<p><p>To them, and to everyone else who reached out &ndash; either to us or to Facebook, or \u00ab\u00a0said something\u00a0\u00bb in private or on the Interweb &ndash; our sincerest gratitude.<\/p>\n<\/p>\n<p><p>And then on Tuesday morning, everything had suddenly returned to normal, and whether due to the unexpectedly widespread support we received, or because Facebook had made a sincere error, the ban was reversed.<\/p>\n<\/p>\n<p><p>While Facebook has yet to contact us directly, they did comment with a <a href=\"https:\/\/www.breitbart.com\/tech\/2019\/03\/12\/facebook-temporarily-blocks-users-from-posting-zero-hedge-articles\/\">Facebook spokesman saying<\/a> that  \u00ab\u00a0<strong>This was a mistake with our automation to detect spam and we worked to fix it yesterday.<\/strong>\u00a0\u00bb  He added that &quot;we use a combination of human review and automation to enforce our policies around spam and in this case, our automation incorrectly blocked this link.  \u00ab\u00a0<strong>As soon as we identified the issue, we worked quickly to fix it.<\/strong>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>We still have no insight into which article(s) Facebook decided was sufficiently \u00ab\u00a0spammy\u00a0\u00bb to block everyone&rsquo;s access to our content, or on what basis Facebook&rsquo;s \u00ab\u00a0<em>automation and human review<\/em>\u00a0\u00bb  had made the decision to quarantine our small website from the rest of Facebook&rsquo;s 2.3 billion  <a href=\"https:\/\/s21.q4cdn.com\/399680738\/files\/doc_financials\/2018\/Q4\/Q4-2018-Earnings-Presentation.pdf\">monthly users<\/a>.<\/p>\n<\/p>\n<p><p>But we are heartened by this development, not so much because it means a rebound in our traffic &ndash; as we  <a href=\"https:\/\/www.zerohedge.com\/news\/2019-03-11\/facebook-bans-zero-hedge\">observed yesterday<\/a>, we are lucky in that Facebook represents a tiny source of our inbound referral traffic &ndash;but because it means nothing changes : we can and will continue as before, with zero adjustments to our writing style, and we will certainly continue with our highly critical coverage of all things Facebook. And best of all : it will be read on Facebook, allowing users of the world&rsquo;s biggest media company to escape an informational echo chamber, and be presented with contrasting opinions, which even if wrong, will allow countless readers to make more informed opinions than if served with preapproved, uniform, and ideologically palatable content.<\/p>\n<\/p>\n<p><p>And since some may read this as a quasi-official press release, we leave the \u00ab\u00a0about us\u00a0\u00bb part to the money-losing media venture of billionaire Mike Bloomberg&rsquo;s business empire (funded since day one by the procyclical $25,000\/year Bloomberg terminal business), which  <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2019-03-12\/zero-hedge-says-facebook-banned-users-from-sharing-its-posts\">yesterday<\/a> described our little adventure as follows: \u00ab\u00a0Since being founded in the depths of the financial crisis, Zero Hedge has built a dedicated following by serving up a mix of hardcore financial analysis and populist political commentary. Both the &lsquo;Tyler Durden&rsquo; name and the site&rsquo;s tagline &ndash; &lsquo;On a long enough timeline the survival rate for everyone drops to zero&rsquo; &ndash; are borrowed from the anarchic cult classic &lsquo;Fight Club.'\u00a0\u00bb<\/p>\n<\/p>\n<p><h4>Tyler Durden<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00ab\u00a0strange 24 hours\u00a0\u00bb de ZeroHedge.com Le texte ci-dessous a \u00e9t\u00e9 mis en ligne par le site ZeroHedge.com hier \u00e0 19H59, dans la nuit (\u00e0 02H59) pour nous. Comme nous faisons pour certains textes qui nous semblent assez ais\u00e9ment compr\u00e9hensibles et qu&rsquo;il nous para&icirc;t important de publier rapidement dans leur forme originale, c&rsquo;est-\u00e0-dire autant par&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[18923,8715,3085,18924,13544,10569],"class_list":["post-78513","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-censeur","tag-facebook","tag-kosovo","tag-moraline","tag-zerohedge-com","tag-zuckerberg"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78513"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78513\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}