{"id":78516,"date":"2019-03-11T12:58:58","date_gmt":"2019-03-11T12:58:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/11\/que-faire-de-aoc\/"},"modified":"2019-03-11T12:58:58","modified_gmt":"2019-03-11T12:58:58","slug":"que-faire-de-aoc","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/11\/que-faire-de-aoc\/","title":{"rendered":"Que faire de AOC\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Que faire de AOC ?<\/h2>\n<\/p>\n<p><p>11 mars 2019 &ndash; Je trouve que <a href=\"http:\/\/www.dedefensa.org\/article\/pourquoi-les-capitalistes-detestent-ils-le-socialisme\">cette chronique<\/a> de l&rsquo;inimitable Orlov tombe \u00e0 pic : &laquo; <em>Pourquoi les capitalistes d\u00e9testent-ils les socialistes ? <\/em>&raquo; <strong>On parle ici des <\/strong><strong>vrais socialistes<\/strong>, n&rsquo;est-ce pas. Il n&rsquo;est pas question d&rsquo;\u00e9voquer les \u00ab\u00a0socialistes\u00a0\u00bb, sociaux-d\u00e9mocrates europ\u00e9ens, les plus z\u00e9l\u00e9s porteurs d&rsquo;eau-friqu\u00e9e des capitalistes qu&rsquo;on puisse r\u00eaver. (Par exemple, pr\u00e9senter Attali comme \u00ab\u00a0socialiste-historique-mais-r\u00e9aliste\u00a0\u00bb, et mourir de rire&#8230;)<\/p>\n<\/p>\n<p><p>Orlov parle simple, plein de bon sens commun, avec des questions directes, et des r\u00e9ponses qui le sont tout autant, <strong>tranchantes et sans r\u00e9pliques \u00e0 force de simplicit\u00e9<\/strong>. Les employ\u00e9s-Syst\u00e8me d\u00e9fenseurs du capitalisme qui vous d\u00e9crivent avec horreur ce qui pourrait arriver si l&rsquo;on songeait au socialisme, ont le cul pos\u00e9 sur un amonc\u00e8lement formidable de catastrophes, d&rsquo;incendies, d&rsquo;entropisation \u00e9pouvantables, de \u00ab\u00a0l\u00e0 o&ugrave; il passe l&rsquo;herbe ne repousse pas\u00a0\u00bb <strong>qui repr\u00e9sentent ce qui arrive effectivement, non pas lorsqu&rsquo;on songe au capitalisme mais lorsqu&rsquo;on applique notamment et particuli\u00e8rement depuis bient\u00f4t quatre d\u00e9cennies, <\/strong>le capitalisme <em>neocon <\/em>int\u00e9gral, sans frein ni limites, sans restriction ni mesure.<\/p>\n<\/p>\n<p><p>Le socialisme pourrait \u00eatre une formule \u00e9conomique contestable sinon d\u00e9testable, le capitalisme est la seule formule \u00e9conomique <strong>qui vous garantit sans devis n\u00e9cessaire la destruction du monde par entropisation<\/strong>. C&rsquo;est vrai que le socialisme enfourch\u00e9 par des exalt\u00e9s-froids-et-extr\u00eames comme un L\u00e9nine vous emporte dans des d\u00e9viations catastrophiques dont on a tant de mal \u00e0 se relever ; sans n\u00e9cessit\u00e9 de personnages historiques de cet acabit (ni Thatcher-la-m\u00e9nag\u00e8re ni Reagan-l&rsquo;acteur-de-s\u00e9rie-B n&rsquo;arrivent \u00e0 la cheville de L\u00e9nine du point de vue de la dimension historique), par simple formatage de la pens\u00e9e comme l&rsquo;on voit dans une religion de zombieSyst\u00e8me \u00e0 la spiritualit\u00e9-lobotomis\u00e9e, le capitalisme vous plonge sans que vous ne vous aperceviez de rien <strong>dans le terrible trou noir de l&rsquo;entropisation du monde dont nul jamais ne revint<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>Cela, cette introduction est pour dire que <strong>je me suis surpris \u00e0 d\u00e9couvrir chez moi des r\u00e9flexes qui me font bien r\u00e9fl\u00e9chir<\/strong>. Face \u00e0 l&rsquo;attaque contre le socialisme qui a lieu aujourd&rsquo;hui, notamment chez ceux aux c\u00f4t\u00e9s desquels je me suis souvent retrouv\u00e9 dans la bagarre antiSyst\u00e8me, bagarre essentiellement aux USA \u00e0 cause de la mont\u00e9e du courant socialiste chez les d\u00e9mocrates et \u00e0 cause de la mise en cause f\u00e9roce, \u00e0 la fa\u00e7on des tueurs du crime organis\u00e9, contre le r\u00e9gime v\u00e9n\u00e9zu\u00e9lien du \u00ab\u00a0chavisme\u00a0\u00bb, je me suis retrouv\u00e9 en mode d\u00e9fensif ; appuy\u00e9, bien-heureusement d&rsquo;ailleurs, sur l&rsquo;argument que tout ce qui est antiSyst\u00e8me est bon, sans plus chercher \u00e0 discuter sur le terrain de la valeur du socialisme. Il se trouve qu&rsquo;<strong>Orlov, avec sa simplicit\u00e9 et son ironie, me conduit \u00e0 r\u00e9fl\u00e9chir \u00e0 ce propos<\/strong>.<\/p>\n<\/p>\n<p><p>Et ma r\u00e9flexion donne ceci : \u00e0 c\u00f4t\u00e9 de l&rsquo;argument \u00ab\u00a0tout ce qui est antiSyst\u00e8me est bon\u00a0\u00bb, il y a l&rsquo;argument que d\u00e9veloppe Orlov, selon lequel tout simplement, le capitalisme \u00e9tant le pire de ce que le Diable peut concevoir puisqu&rsquo;il recherche la destruction du monde par entropisation, le socialisme est par d\u00e9finition \u00ab\u00a0moins pire\u00a0\u00bb que lui ne serait-ce que parce qu&rsquo;il s&rsquo;oppose \u00e0 lui. Cela signifie que non seulement \u00ab\u00a0tout ce qui est antiSyst\u00e8me est bon\u00a0\u00bb, mais que ce \u00ab\u00a0tout\u00a0\u00bb peut avoir des vertus par lui-m\u00eame, <strong>et que c&rsquo;est pour cette raison, dans cette circonstance-l\u00e0, qu&rsquo;il est antiSyst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>Le socialisme tel que le d\u00e9finit simplement Orlov est-il tellement diff\u00e9rent du souverainisme et du populisme, d\u00e8s lors qu&rsquo;on oublie sa dimension \u00ab\u00a0supranationaliste\u00a0\u00bb qui a \u00e9t\u00e9 enterr\u00e9e avec l&rsquo;URSS et le communisme ? &laquo; &#8230;[U]<em>ne fiscalit\u00e9 progressive, l&rsquo;insistance mise sur la propri\u00e9t\u00e9 publique des grandes institutions et la part importante de l&rsquo;&Eacute;tat mise dans les entreprises publiques strat\u00e9giquement importantes <\/em>&raquo;, cela n&rsquo;est-il pas un programme <strong>qui sied aux souverainistes et aux populistes<\/strong> ? Et d&rsquo;ailleurs, <strong>ne sied-il pas aux gaullistes de la m\u00eame fa\u00e7on<\/strong> ? Et <strong>aux Gilets-Jaunes, <em>idem<\/em><\/strong> ? Ce que je constate pour mon compte, ce que je confesse pour dire plus juste et plus loyal, c&rsquo;est d&rsquo;avoir \u00e9t\u00e9 mis sur la d\u00e9fensive par la <em>doxa <\/em>capitaliste sur le cas du socialisme, alors que, tout en \u00e9tant toujours et plus que jamais dans le mode \u00ab\u00a0tout ce qui est antiSyst\u00e8me est bon\u00a0\u00bb, <strong>je devrais \u00eatre au contraire dans une posture compl\u00e8tement offensive<\/strong>. La le\u00e7on doit \u00eatre retenue : on est et on reste toujours plus vuln\u00e9rable qu&rsquo;on croit \u00e0 l&rsquo;extraordinaire pilonnage de <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a> constamment aliment\u00e9e par l&rsquo;artillerie nucl\u00e9aire du Syst\u00e8me, et il faut toujours s&rsquo;en d\u00e9fier ; et au-del\u00e0, il faut toujours \u00eatre prompt \u00e0 exploiter tout ce qui peut jouer un r\u00f4le antiSyst\u00e8me, quelles que soient l&rsquo;\u00e9tiquette et les origines&#8230;<\/p>\n<\/p>\n<p><p>Maintenant, venons-en au cas du socialisme qui monte aux USA, comme le dit \u00e9galement Orlov et comme on ne manque pas de le souligner sur ce site, d\u00e8s que l&rsquo;occasion s&rsquo;en pr\u00e9sente. Je prends ici le cas de la jeune et p\u00e9tulante AOC (Alexandria Ocasio-Cortez). Apr\u00e8s tout, lorsqu&rsquo;elle s&rsquo;\u00e9crie hier, au Texas, devant une assembl\u00e9e de sp\u00e9cialistes et d&rsquo;experts des techniques capitalistes de marketing, de la technologie avanc\u00e9e, de l'\u00a0\u00bbinfluence\u00a0\u00bb des m\u00e9dias sociaux, etc. : &laquo; <em>Le capitalisme est une id\u00e9ologie du capital, &ndash; le plus important est la concentration du capital et la recherche de la maximisation des profits &#8230; <strong>pour moi le capitalisme est irr\u00e9formable<\/strong> !<\/em> &raquo;, et cela sous les sarcasmes de <em><a href=\"https:\/\/www.zerohedge.com\/news\/2019-03-10\/aoc-tells-bougie-tech-conference-attendees-capitalism-irredeemable\">ZeroHedge.com<\/a> <\/em>qui me fournit habituellement tant d&rsquo;arguments antiSyst\u00e8me, &ndash; <strong>eh bien, je suis du c\u00f4t\u00e9 de AOC<\/strong>, et je crois que nombre, tr\u00e8s grand nombre de Gilets-Jaunes le seraient \u00e9galement.<\/p>\n<\/p>\n<p><p>Tout comme certaines de ses copines de la Chambre, tout comme le vieux Sanders, AOC s&rsquo;est refus\u00e9e \u00e0 condamner sans condition ni appel Maduro c&rsquo;est-\u00e0-dire \u00e0 approuver l&rsquo;aventure du moustachu Bolton, bouffonne et abracadabrantesque, ill\u00e9gale et monstrueuse, de l&rsquo;attaque du Venezuela \u00e0 l&rsquo;aide de la marionnette de circonstance. <strong>Est-il utile de poser la question de savoir de quel c\u00f4t\u00e9 je me situe par rapport \u00e0 cette position ? <\/strong>AOC, tout comme Omar ou Tlaib, tout comme Gabbard d&rsquo;une autre fa\u00e7on beaucoup plus clairement affirm\u00e9e, &ndash; toutes des filles, vous l&rsquo;avez not\u00e9, &ndash; sont sur la pente de l&rsquo;opposition \u00e0 ces entreprises ext\u00e9rieures. On l&rsquo;a d\u00e9j\u00e0 signal\u00e9 cela, elles tendent \u00e0 \u00eatre le contraire des <em><a href=\"http:\/\/www.dedefensa.org\/article\/hillary-et-ses-harpies-ou-le-feminisme-guerrier\">Harpies <\/a><\/em><a href=\"http:\/\/www.dedefensa.org\/article\/hillary-et-ses-harpies-ou-le-feminisme-guerrier\">de Hillary-Obama<\/a>, m\u00eame si elles sembleraient en d\u00e9couler compl\u00e8tement&#8230;.<\/p>\n<\/p>\n<p><p>(On a d\u00e9j\u00e0 senti le vent de boulet lorsque Omar a mis les pieds dans le plat il y a trois jours en disant qu&rsquo;Obama ne valait pas mieux que Trump, qu&rsquo;il tuait des gens par <em>drones <\/em>interpos\u00e9s, qu&rsquo;il traitait les migrants aussi mal que Trump, etc. Elle a <a href=\"https:\/\/abc13.com\/rep-ilhan-omar-says-her-criticism-of-president-obama-was-distorted\/5178653\/\">r\u00e9trop\u00e9dal\u00e9 le lendemain<\/a>, sous des pressions diverses dont celles du <em>caucus <\/em>afro-am\u00e9ricain qui l&rsquo;avait soutenue \u00e0 la Chambre contre Pelosi et contre les petites mains de l&rsquo;antis\u00e9mitisme, qui a d\u00e9fendu fermement son intouchable idole et a demand\u00e9 un renvoi d&rsquo;ascenseur illico.)<\/p>\n<\/p>\n<p><p>Il y avait ces observations dans le texte du <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-les-vertus-des-filles-du-congres\">16 f\u00e9vrier 2019<\/a>, qui \u00e9tait des <em>Notes d&rsquo;analyse <\/em>sur \u00ab\u00a0<em>les filles du Congr\u00e8s<\/em>\u00a0\u00bb : &laquo; <em>Le titre est un peu leste sinon provocateur mais que les f\u00e9ministes-guillotineuses se rassurent et rengainent leurs lames tranchantes. Il s&rsquo;agit tout de m\u00eame de trois jeunes femmes <\/em>[AOC, Omar, Gabbard] <em>dont aucune n&rsquo;atteint la quarantaine, toutes trois d\u00e9mocrates, toutes trois venues d&rsquo;une \u00ab\u00a0minorit\u00e9\u00a0\u00bb et parlant haut et fort, pas vraiment ou compl\u00e8tement f\u00e9ministes toutes les trois m\u00eame si certaines le sont, mais qui, dans certains de leurs actes, apr\u00e8s tout font beaucoup pour \u00ab\u00a0la cause des femmes\u00a0\u00bb ; trois jeunes femmes repr\u00e9sentant par cons\u00e9quent une nouvelle g\u00e9n\u00e9ration de la politique washingtonienne, <strong>et une politique \u00ab\u00a0nouvelle\u00a0\u00bb dans tous les sens du qualificatif<\/strong>. C&rsquo;est-\u00e0-dire qu&rsquo;\u00e0 les consid\u00e9rer, au c\u00f4t\u00e9 des m\u00e2les de toutes les couleurs et tremblant de trouille, et malgr\u00e9 la consid\u00e9ration d\u00e9favorable qu&rsquo;on peut avoir pour cet production de la postmodernit\u00e9, &ndash; surprise, surprise, &ndash; <strong>on se dit qu&rsquo;il y a du bon dans ce qu&rsquo;il y a de pire<\/strong>&#8230; Ces trois jeunes femmes ne sont pas moins que trois Congress(wo)men, c&rsquo;est-\u00e0-dire membres de la Chambre des Repr\u00e9sentants des &Eacute;tats-Unis<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Je voudrais compl\u00e9ter ce passage \u00e0 la lumi\u00e8re d&rsquo;une r\u00e9flexion prolong\u00e9e et \u00e0 la lumi\u00e8re de diverses d\u00e9clarations et prises de position depuis, des unes et des autres, mettant en \u00e9vidence la mont\u00e9e explosive des contradictions internes du Syst\u00e8me entre l&rsquo;avanc\u00e9e des moyens soci\u00e9taux (f\u00e9minisme, \u00ab\u00a0diversit\u00e9s de couleur\u00a0\u00bb, progressisme, etc.) mis en &oelig;uvre par le Syst\u00e8me pour un but de d\u00e9structuration, et la politiqueSyst\u00e8me qui est poursuivie. <strong>Nous sommes entr\u00e9s dans le domaine o&ugrave; les outils de d\u00e9structuration du Syst\u00e8me agissent contre la structure subversive et invertie du Syst\u00e8me<\/strong>, en attaquant aussi bien la politique belliciste que le capitalisme lui-m\u00eame dans ses caract\u00e8res de rapacit\u00e9 et de financiarisation in\u00e9galitaire, notamment au nom du \u00ab\u00a0socialisme\u00a0\u00bb,<strong>comme Orlov lui-m\u00eame le d\u00e9crit<\/strong>. Bien entendu, la droite classique se r\u00e9crie, avec les conservateurs \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me <strong>pr\u00e9f\u00e9rant \u00ab\u00a0conserver\u00a0\u00bb le Syst\u00e8me <\/strong>dans sa logique d\u00e9structurante que <strong>profiter de cette opportunit\u00e9 d&rsquo;autodestruction<\/strong>, au nom de l&rsquo;hostilit\u00e9 au \u00ab\u00a0gauchisme\u00a0\u00bb ; et la \u00ab\u00a0droite classique\u00a0\u00bb se retrouvant compl\u00e8tement \u00e0 front-renvers\u00e9, objectivement en soutien du Syst\u00e8me et de la modernit\u00e9, objectivement contre la Tradition, encore plus attristant que \u00ab\u00a0la droite la plus b\u00eate du monde\u00a0\u00bb. (Voir ce que <em><a href=\"https:\/\/lesobservateurs.ch\/2019\/03\/10\/antisemitisme-socialisme-islamisme-ces-elues-democrates-americaines-a-la-derive\/\">Valeurs Actuelles<\/a> <\/em>\u00e9crit de ces gauchistes d\u00e9mocrates).<\/p>\n<\/p>\n<p><p>La <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>, je la verrais dans ceci que cette \u00ab\u00a0nouvelle g\u00e9n\u00e9ration\u00a0\u00bb n\u00e9e du f\u00e9minisme et de la diversit\u00e9, sp\u00e9cifiquement aux USA, est <strong>en compl\u00e8te rupture avec la g\u00e9n\u00e9ration pseudo-\u00ab\u00a0f\u00e9ministe\u00a0\u00bb qui l&rsquo;a pr\u00e9c\u00e9d\u00e9e<\/strong>, \u00e0 savoir les <em>Harpies <\/em>de Hillary-Obama qui applaudissaient \u00e0 la liquidation ignoble de Kadhafi dans les conditions qu&rsquo;on sait (&laquo; <em><a href=\"http:\/\/www.dedefensa.org\/article\/we-came-we-saw-he-died\">We came, we saw, he died<\/a> <\/em>&raquo;), aussi bien qu&rsquo;au coup d&rsquo;&Eacute;tat de Kiev de f\u00e9vrier 2014. Les<em>Harpies <\/em>de Hillary-Obama n&rsquo;\u00e9taient que des bonnes femmes qui se prenaient pour des mecs ; la \u00ab\u00a0nouvelle g\u00e9n\u00e9ration\u00a0\u00bb concerne des jeunes femmes qui se retournent contre les mecs, et il se trouve qu&rsquo;en l&rsquo;occurrence \u00ab\u00a0les mecs\u00a0\u00bb c&rsquo;est le Syst\u00e8me. Voil\u00e0 o&ugrave; l&rsquo;occurrence est bonne et inutile d&rsquo;argumenter au-del\u00e0 \u00e0 propos du f\u00e9minisme. <\/p>\n<\/p>\n<p><p>En effet, <strong>je suis hors de la bataille du f\u00e9minisme par refus cat\u00e9gorique d&rsquo;engagement<\/strong>, dans une bataille qui m\u00eale les hyst\u00e9ries paroxystiques, les hallucinations, les souffrances, les manipulations, le besoin de justice et le go&ucirc;t de la terrorisation des autres (*) ; par refus cat\u00e9gorique d&rsquo;engagement, enfin, parce que je ne m&rsquo;engage en rien dans aucun de ces combats de la postmodernit\u00e9, dont je sais <strong>qu&rsquo;ils ne d\u00e9bouchent en eux-m\u00eames sur rien et ne produisent que des cocus \u00e0 la cha&icirc;ne si l&rsquo;on ne va pas \u00e0 la source<\/strong>, &ndash; c&rsquo;est-\u00e0-dire la postmodernit\u00e9 elle-m\u00eame, la modernit\u00e9, le Syst\u00e8me, le \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0. En attendant, laissez-moi identifier et go&ucirc;ter <strong>les fruits d\u00e9licieux de la surpuissance accouchant son autodestruction, de la surpuissance acc\u00e9l\u00e9rant son autodestruction<\/strong>, car l\u00e0 c&rsquo;est bien \u00ab\u00a0aller \u00e0 la source\u00a0\u00bb. Les dieux appuient l\u00e0 o&ugrave; \u00e7a fait mal, car les dieux sont en charge des \u00e9v\u00e9nements du monde. Le bin\u00f4me \u00ab\u00a0f\u00e9minisme-diversit\u00e9\u00a0\u00bb se retourne contre le Syst\u00e8me qui l&rsquo;a enfant\u00e9e, exigeant de pousser la logique \u00e0 son terme, hostile plus ou moins ouvertement \u00e0 l&rsquo;influence de l&rsquo;AIPAC et \u00e0 l&rsquo;attaque contre Maduro, criant sa haine du capitalisme, faisant valser les \u00e9tiquettes&#8230;<\/p>\n<\/p>\n<p><p>Valsez les \u00e9tiquettes ! Droite, gauche-gauchisme, d\u00e9mocrates et r\u00e9publicains, Soros \u00e0 toutes les sauces, tout cela ne vaut plus rien de ce qu&rsquo;on croit y lire&#8230; Qu&rsquo;importe, <strong>l&rsquo;essentiel est que le d\u00e9sordre poursuit sa marche destructrice \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me <\/strong>et les ap\u00f4tres du \u00ab\u00a0nouveau-monde\u00a0\u00bb, qui barbotent dans l&rsquo;ancien, qui ne s&rsquo;aper\u00e7oivent de rien.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>(*) On notera pour l&rsquo;esprit de la chose ces mots de la fantastique joueuse de tennis, la tch\u00e9coslovaque Martina Navratilova (fin des ann\u00e9es 1970), lesbienne affich\u00e9e de l&rsquo;origine mais qui n&rsquo;entend pas suivre les folies des extr\u00e9mistes du domaine, qui l&rsquo;a dit \u00e0 plus d&rsquo;une reprise, qui en a essuy\u00e9 insultes et condamnations malgr\u00e9 son statut, et qui <a href=\"https:\/\/www.rt.com\/news\/453482-liberal-icons-dared-express-opinion\/\">observait hier<\/a> que ses accusateurs lui rappelaient ces &laquo; <em>communistes qui essayaient de me faire taire il y a 45 ans<\/em> &raquo;, en Tch\u00e9coslovaquie. <strong>Ainsi est boucl\u00e9e la boucle de la terreur<\/strong>, et l&rsquo;on se retrouve en terrain de connaissance.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que faire de AOC ? 11 mars 2019 &ndash; Je trouve que cette chronique de l&rsquo;inimitable Orlov tombe \u00e0 pic : &laquo; Pourquoi les capitalistes d\u00e9testent-ils les socialistes ? &raquo; On parle ici des vrais socialistes, n&rsquo;est-ce pas. Il n&rsquo;est pas question d&rsquo;\u00e9voquer les \u00ab\u00a0socialistes\u00a0\u00bb, sociaux-d\u00e9mocrates europ\u00e9ens, les plus z\u00e9l\u00e9s porteurs d&rsquo;eau-friqu\u00e9e des capitalistes qu&rsquo;on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[7599,18381,3359,14273,3837,2750,11992,7465,18382,4945,2668,5304],"class_list":["post-78516","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-aipac","tag-alexandria","tag-chambre","tag-diversite","tag-feminisme","tag-gabbard","tag-maduro","tag-navratilova","tag-ocasio-cortez","tag-omar","tag-orlov","tag-socialisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78516"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78516\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}