{"id":78527,"date":"2019-03-19T05:01:25","date_gmt":"2019-03-19T05:01:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/19\/confession-dun-trois-quarts-de-siecle\/"},"modified":"2019-03-19T05:01:25","modified_gmt":"2019-03-19T05:01:25","slug":"confession-dun-trois-quarts-de-siecle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/03\/19\/confession-dun-trois-quarts-de-siecle\/","title":{"rendered":"Confession d&rsquo;un trois-quarts de si\u00e8cle"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Confession d&rsquo;un trois-quarts de si\u00e8cle<\/h2>\n<\/p>\n<p><p>18 mars 2019 (*) &ndash; Puisque des lecteurs, \u00e0 commencer par notre lecteur-commentateur et ami \u00ab\u00a0jc\u00a0\u00bb, si pr\u00e9cieux au <em>Forum <\/em>et grand-\u00e9rudit, et par monsieur Fabrice Vivier que je salue chaleureusement certes, m&rsquo;ont fait la gr\u00e2ce de remarquer mon petit signe qui \u00e9tait si peu pr\u00e9m\u00e9dit\u00e9, qui m&rsquo;est venu naturellement sous la plume, notamment en raison du symbolisme de l&rsquo;\u00e2ge apr\u00e8s tout (**), j&rsquo;en profite pour encha&icirc;ner sur une chose qu&rsquo;il me pla&icirc;t de confier, attendant l&rsquo;occasion pour le faire&#8230; Il s&rsquo;agit d&rsquo;une citation li\u00e9 \u00e0 mon anniversaire par le hasard d&rsquo;un agenda, et qui me semble me correspondre tout \u00e0 fait au point qu&rsquo;il m&rsquo;arrive de douter du hasard (dans ce cas comme dans tous les autres).<\/p>\n<\/p>\n<p><p>Une courte explication d&rsquo;abord. Je suis un vieil amateur de <em>La Pl\u00e9iade<\/em>, avec l&rsquo;habitude d&rsquo;en acheter deux-trois l&rsquo;an ; et r\u00e9guli\u00e8rement depuis l&rsquo;apparition en 2000 de l&rsquo;agenda-<em>Pl\u00e9iade <\/em>avec ses diverses particularit\u00e9s si litt\u00e9raires et notamment une citation par semaine, regroupant l&rsquo;achat de deux volumes en fin d&rsquo;ann\u00e9e pour disposer de l&rsquo;agenda de l&rsquo;ann\u00e9e suivante. Cette ann\u00e9e 2019, j&rsquo;ai eu la curiosit\u00e9 d\u00e8s que je l&rsquo;eus en ma possession, en novembre 2018, d&rsquo;aller voir la citation de la semaine de mon anniversaire. C&rsquo;\u00e9tait la premi\u00e8re fois que j&rsquo;avais ce geste, sans d\u00e9lib\u00e9rer ni rien, sinon encore une fois \u00e0 cause du symbolislme de cet \u00e2ge des trois-quarts de si\u00e8cle. J&rsquo;inscrivis aussit\u00f4t en haut de page : &laquo; <em>75 ans, &ndash; voil\u00e0 qui me convient parfaitement<\/em> &raquo;, avec une fl\u00e8che jusqu&rsquo;\u00e0 ces quelques lignes de la citation, qui sont de Jean-Paul Sartre, dans <em>Les Mots<\/em>  (***) :<\/p>\n<\/p>\n<p><p>&laquo; <em>Ce que j&rsquo;aime en ma folie, c&rsquo;est qu&rsquo;elle m&rsquo;a prot\u00e9g\u00e9, du premier jour, contre les s\u00e9ductions de l'\u00a0\u00bb\u00e9lite\u00a0\u00bb : jamais je ne me suis cru l&rsquo;heureux propri\u00e9taire d&rsquo;un \u00ab\u00a0talent\u00a0\u00bb : ma seule affaire \u00e9tait de me sauver, &ndash; rien dans les mains, rien dans les poches,  &ndash; par le travail et la foi. Du coup ma pure option ne m&rsquo;\u00e9levait au-dessus de personne : sans \u00e9quipement, sans outillage je me suis mis tout entier \u00e0 l&rsquo;&oelig;uvre pour me sauver tout entier. Si je range l&rsquo;impossible Salut au magasin des accessoires, que reste-t-il ? Tout un homme, fait de tous les hommes et qui les vaut tous et que vaut n&rsquo;importe qui.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Je ne suis certainement pas un admirateur de Sartre ni un adepte de l&rsquo;existentialisme, mais sans exc\u00e8s de rien, ne connaissant l&rsquo;un et l&rsquo;autre que fort peu. (Dans ma jeunesse, tr\u00e8s hostile \u00e0 Sartre, tout d&rsquo;un bloc, sans nuances ni go&ucirc;t de conna&icirc;tre les siennes, \u00e0 cause de ses positions politiques.) Peu importe, je ne juge ici que \u00ab\u00a0les mots\u00a0\u00bb, justement&#8230; Et je trouve, je ressens jusqu&rsquo;\u00e0 \u00eatre touch\u00e9, qu&rsquo;ils disent le vrai d&rsquo;un homme qui devait avoir des vertus personnelles d&rsquo;assez belle facture. (Jean Cau, qui, apr\u00e8s avoir \u00e9t\u00e9 son secr\u00e9taire, s&rsquo;est oppos\u00e9 \u00e0 lui avec une grande f\u00e9rocit\u00e9 mais sans haine ni tra&icirc;trise, en fait un portrait \u00e9mouvant dans ses <em>Croquis de m\u00e9moire <\/em>publi\u00e9s en 1985, cinq ans apr\u00e8s le mort de Sartre.)<\/p>\n<\/p>\n<p><p>M\u00eame lorsqu&rsquo;il parle de se prot\u00e9ger \u00ab\u00a0de l&rsquo;\u00e9lite\u00a0\u00bb dont il nous paraissait en faire si intimement partie qu&rsquo;on aurait dit qu&rsquo;il en \u00e9tait l&rsquo;inspirateur et le Messie, et m\u00eame parfois le dictateur, je ressens qu&rsquo;il dit vrai ; cette fa\u00e7on qu&rsquo;il a de repousser tout supr\u00e9macisme au nom de sa propre int\u00e9grit\u00e9, ce n&rsquo;est ni fausse modestie ni hypocrisie. Lorsqu&rsquo;il \u00e9crit que &laquo; <em>jamais <\/em>[il ne se crut] <em>l&rsquo;heureux propri\u00e9taire d&rsquo;un \u00ab\u00a0talent\u00a0\u00bb<\/em> &raquo;, je m&rsquo;y retrouve moi-m\u00eame absolument, moi que l&rsquo;on dit si justement \u00eatre \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/ma-verite-de-situation\">logocrate<\/a>\u00ab\u00a0, c&rsquo;est-\u00e0-dire messager de mots et d&rsquo;un langage dont je ne me crois aucunement le propri\u00e9taire, ni m\u00eame l&rsquo;inspirateur. J&rsquo;ignore si c&rsquo;est se leurrer soi-m\u00eame mais j&rsquo;aimerais que cette citation soit aussi de moi pour ce que je pense de moi, parce que les sentiments et les traits de caract\u00e8re qu&rsquo;elle met en \u00e9vidence me conviennent absolument. Symbolique proximit\u00e9 pour un symbolique anniversaire.<\/p>\n<\/p>\n<p><p>Et puis il y a toujours le myst\u00e8re de l&rsquo;\u00eatre&#8230; Une chose m&rsquo;arr\u00eate chez cet homme (Sartre), au gr\u00e9 de cette citation et rien que cela, lui qu&rsquo;on sait \u00eatre officiellement l&rsquo;ath\u00e9e absolu ; plus pr\u00e9cis\u00e9ment m&rsquo;arr\u00eatent deux mots et une tournure. Lorsqu&rsquo;il dit \u00ab\u00a0me sauver&#8230; par le travail et par la foi\u00a0\u00bb : je sais bien que le mot \u00ab\u00a0foi\u00a0\u00bb qui vient de <em>fidus <\/em>signifie d&rsquo;abord \u00ab\u00a0confiance\u00a0\u00bb mais on ne peut se d\u00e9barrasser \u00e0 la l\u00e9g\u00e8re de sa connotation, sinon religieuse dans tous les cas spirituelle. Et puis voici cette phrase avec cette tournure : &laquo; <em>Si je range l&rsquo;impossible Salut au magasin des accessoires, que reste-t-il ?<\/em> &raquo; ; non seulement le mot \u00ab\u00a0Salut\u00a0\u00bb, mais surtout l&#8217;emploi du \u00ab\u00a0si\u00a0\u00bb qui expose en g\u00e9n\u00e9ral une signification conditionnelle et <a href=\"http:\/\/activitesfle.over-blog.com\/article-36511927.html\">hypoth\u00e9tique<\/a> au lieu, par exemple, d&rsquo;un \u00ab\u00a0puisque\u00a0\u00bb privatif (\u00ab\u00a0Puisque je range l&rsquo;impossible Salut au magasin des accessoires&#8230;\u00a0\u00bb). Est-ce voulu ou pas ? N&rsquo;y a-t-il pas alors une \u00e9trange contradiction ? Cette contradiction \u00e9ventuelle entre le \u00ab\u00a0si\u00a0\u00bb conditionnel qui indique qu&rsquo;il y a un choix et qu&rsquo;il (Sartre) pourrait aussi bien d\u00e9cider de ne pas ranger \u00ab\u00a0l&rsquo;impossible Salut au magasin des accessoires\u00a0\u00bb, et le qualificatif \u00ab\u00a0impossible\u00a0\u00bb ; puisque le Salut est qualifi\u00e9 d'\u00a0\u00bbimpossible\u00a0\u00bb, il n&rsquo;y a pas de choix possible et le Salut est automatiquement au \u00ab\u00a0magasin des accessoires\u00a0\u00bb, et lui-m\u00eame n&rsquo;a d&rsquo;ailleurs nul besoin de l&rsquo;y mettre, et bien s&ucirc;r encore moins de s&rsquo;interroger pour savoir s&rsquo;il l&rsquo;y met. Y a-t-il ici, dans l&rsquo;\u00e9ventuelle contradiction, une position affirm\u00e9e en conscience et un \u00e9lan secret cach\u00e9 au-del\u00e0 de la conscience ?<\/p>\n<\/p>\n<p><p>Curieux destin de cette citation et \u00e9trange dessein d&rsquo;ainsi en chercher la signification, et <strong>j&rsquo;arr\u00eate l\u00e0 mon enqu\u00eate sans tirer aucune conclusion que ce soit, &ndash; cette affirmation est capitale et r\u00e8gle tout ce propos<\/strong>. Mon \u00e2ge canonique me permettrait de faire acte de connaissance et d&rsquo;exp\u00e9rience, et donc avec une possibilit\u00e9 l\u00e9gitime d&rsquo;affirmation imp\u00e9rative, <strong>et bien entendu je ne le ferai certainement pas dans ce cas<\/strong>. Je voulais simplement confier \u00e0 ma plume quelques observations, \u00e0 partir d&rsquo;une superbe citation, pour montrer l&rsquo;insaisissable l\u00e9g\u00e8ret\u00e9 du jugement sur l&rsquo;\u00eatre. P\u00e9guy disait &laquo; <em>il faut toujours dire ce que l&rsquo;on voit, mais surtout voir ce que l&rsquo;on voit<\/em> &raquo; ; et j&rsquo;ajouterais pour mon compte qu&rsquo;il faut savoir \u00ab\u00a0si nous pensons vraiment ce que nous pensons, et si nous croyons vraiment ce que nous croyons\u00a0\u00bb. Je puis assurer d&rsquo;exp\u00e9rience intime que cet exercice si \u00e9vident ne fait que s&rsquo;av\u00e9rer plus d\u00e9licat avec l&rsquo;\u00e2ge, si l&rsquo;\u00e2ge vous laisse votre lucidit\u00e9 malgr\u00e9 le poids qu&rsquo;il exerce sur vous.<\/p>\n<\/p>\n<p><p>&#8230; Et plus encore, sur un autre sujet qui est pourtant le m\u00eame au fond : cette rude lucidit\u00e9, si elle vous est laiss\u00e9e, vous interdit sous peine d&rsquo;une fatigue mortelle d&rsquo;ennui de vous d\u00e9tourner de votre mission. Cela signifie pour mon compte : le Tome-III (et le reste), jusqu&rsquo;au bout de mes forces.<\/p>\n<\/p>\n<p><p>Bon anniversaire \u00e0 nous tous.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h2>\n<\/p>\n<p><p>(*) Publi\u00e9 le 19 au tr\u00e8s-petit matin mais \u00e9crit le 18.<\/p>\n<\/p>\n<p><p>(**) &laquo; <em>En apart\u00e9 : je l&rsquo;avoue et je le signale en m\u00eame temps comme un signe des temps, je me r\u00e9f\u00e8re beaucoup aux \u00ab\u00a0dieux\u00a0\u00bb ces temps derniers, lest\u00e9 de mes trois-quarts de si\u00e8cle aujourd&rsquo;hui exactement. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>(***) Et naturellement, tout ce d\u00e9veloppement sans la moindre id\u00e9e, qui serait stupide, indigne et inf\u00e2me comme serait celui qui y songerait, de comparaison, de me hausser et me pr\u00e9tendre \u00e0 la notori\u00e9t\u00e9 d&rsquo;un Sartre, et d&rsquo;ailleurs la citation fait justice d&rsquo;une telle interpr\u00e9tation, ridicule en plus de l&rsquo;inf\u00e2me. Cela est si \u00e9vident que cela m\u00e9ritait d&rsquo;\u00eatre dit, pour pouvoir dire que cela va sans dire.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confession d&rsquo;un trois-quarts de si\u00e8cle 18 mars 2019 (*) &ndash; Puisque des lecteurs, \u00e0 commencer par notre lecteur-commentateur et ami \u00ab\u00a0jc\u00a0\u00bb, si pr\u00e9cieux au Forum et grand-\u00e9rudit, et par monsieur Fabrice Vivier que je salue chaleureusement certes, m&rsquo;ont fait la gr\u00e2ce de remarquer mon petit signe qui \u00e9tait si peu pr\u00e9m\u00e9dit\u00e9, qui m&rsquo;est venu naturellement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[5917,4489,5463,18946,11362,2957,18526,14157,18947,3880,11630],"class_list":["post-78527","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-age","tag-agenda","tag-anniversaire","tag-athee","tag-citation","tag-grand","tag-jc","tag-logocrate","tag-pleiade","tag-sartre","tag-symbolique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78527"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78527\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}