{"id":78561,"date":"2019-04-06T12:52:03","date_gmt":"2019-04-06T12:52:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/04\/06\/usa-du-panoptique-a-la-barbarie\/"},"modified":"2019-04-06T12:52:03","modified_gmt":"2019-04-06T12:52:03","slug":"usa-du-panoptique-a-la-barbarie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/04\/06\/usa-du-panoptique-a-la-barbarie\/","title":{"rendered":"USA\u00a0: du Panoptique \u00e0 la barbarie"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">USA : du Panoptique \u00e0 la barbarie<\/h2>\n<\/p>\n<p><p>On voit ci-dessous, dans un texte de <em>WSWS.org <\/em>(<a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/04\/06\/pers-a06.html\">6 avril 2019<\/a>)dont on comprend bien, selon les traditions de ce site, qu&rsquo;il n&rsquo;est en rien dans ses intentions d&rsquo;att\u00e9nuer sous le conformisme bienpensant les horreurs infernales de la situation am\u00e9ricaniste, l&rsquo;\u00e9tat actuel de l'\u00a0\u00bbenfer carc\u00e9ral\u00a0\u00bb que constitue l'\u00a0\u00bbunivers carc\u00e9ral\u00a0\u00bb des USA. Cele est d\u00e9velopp\u00e9 \u00e0 partir d&rsquo;un rapport sur cette situation dans l&rsquo;&Eacute;tat de l&rsquo;Alabama (&Eacute;tat dont Bill Clinton fut le gouverneur). Le texte se passe de tout commentaire, sinon l&#8217;emploi de l&rsquo;expression \u00ab\u00a0sauvagerie barbare\u00a0\u00bb pour d\u00e9signer la situation actuelle de la chose.<\/p>\n<\/p>\n<p><p>Il nous a paru int\u00e9ressant de mettre en regard certaines observations et r\u00e9flexions faites par trois philosophes-commentateurs \u00e0 propos du premier voyage de Tocqueville (avec Beaumont) aux USA en 1831, avec pour mission officielle d&rsquo;\u00e9tudier le syst\u00e8me carc\u00e9ral aux USA, et de faire une comparaison des situations europ\u00e9enne et am\u00e9ricaine. Il s&rsquo;agissait d&rsquo;une \u00e9poque o&ugrave; une r\u00e9flexion utopique \u00e9tait en plein d\u00e9veloppement concernant cette sorte de syst\u00e8me. Nos trois commentateurs, \u00ab\u00a0Kroker, Kroker &#038; Cook\u00a0\u00bb, consultant \u00e9galement le <em>Journal <\/em>de Tocqueville, en tiraient des r\u00e9flexions concernant les \u00e9tats respectifs des deux situations, sinon des deux civilisations.<\/p>\n<\/p>\n<p><p>Ci-dessous, nous donnons un extrait un extrait du sujet de notre <em>Glossaire.dde <\/em>sur \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-lempire-de-la-communication\">l&#8217;empire de la communication<\/a>\u00a0\u00bb (les USA), sur la question du syst\u00e8me carc\u00e9ral des USA \u00e0 l&rsquo;\u00e9poque du voyage Tocqueveille-Beaumont. <\/p>\n<\/p>\n<p><p>&laquo; &hellip; <em>Ce serait un Tocqueville lucide plus qu&rsquo;\u00e9merveill\u00e9 qui d\u00e9barqua en Am\u00e9rique en 1831. Voil\u00e0 qui nous convient. Trois philosophes am\u00e9ricains ont publi\u00e9 en 1989 un court essai qui tente d&rsquo;interpr\u00e9ter et de d\u00e9gager la signification de cette premi\u00e8re exp\u00e9rience am\u00e9ricaine de Tocqueville. &Eacute;crit par Artur et Mari-Louise Kroker, et David Cook, &lsquo;Panic Tocqueville&rsquo; est sous-titr\u00e9 &lsquo;An Essay on de Tocqueville&rsquo;s Pertinence Today&rsquo; ; ou encore, de fa\u00e7on encore plus significative, &lsquo;Tocqueville Sees America First&rsquo;. <strong>Les auteurs proposent l&rsquo;id\u00e9e que la puissance de l&rsquo;Am\u00e9rique est fond\u00e9e, d\u00e8s l&rsquo;origine et ind\u00e9pendamment de l&rsquo;\u00e9tat des technologies de l&rsquo;information, sur la circulation de l&rsquo;information, et qu&rsquo;elle est nourrie et d\u00e9velopp\u00e9e par elle, au contraire des pays europ\u00e9ens o&ugrave; la puissance est organis\u00e9e par la hi\u00e9rarchie.<\/strong> Cette id\u00e9e se r\u00e9f\u00e8re largement \u00e0 une lecture du &lsquo;Journal&rsquo; du voyage en Am\u00e9rique de Tocqueville.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce voyage de 1831-32 avait d&rsquo;abord un but professionnel. Tocqueville et son compagnon de Beaumont \u00e9taient charg\u00e9s par les autorit\u00e9s fran\u00e7aises d&rsquo;une mission d&rsquo;\u00e9tude du syst\u00e8me carc\u00e9ral am\u00e9ricain. Ils visit\u00e8rent longuement les prisons d&rsquo;Auburn et de Sing-Sing. Ils constat\u00e8rent combien le syst\u00e8me carc\u00e9ral am\u00e9ricain pouvait \u00eatre consid\u00e9r\u00e9 comme un reflet pr\u00e9cis de la soci\u00e9t\u00e9 am\u00e9ricaine. Kroker, Kroker &#038; Cook notent ceci : alors que \u00ab\u00a0l&rsquo;Europe aurait pu \u00eatre appr\u00e9ci\u00e9e comme &lsquo;un mus\u00e9e sans les murs&rsquo; (o&ugrave; la force de l&rsquo;ensemble social est distribu\u00e9e par les r\u00e9sidus de culture qui forment un syst\u00e8me guidant le d\u00e9placement des touristes, des artistes, et, de plus en plus, des capitalistes et de leurs gouvernements), <\/em>[&#8230;] <em>pour Tocqueville, l&rsquo;Am\u00e9rique \u00e9tait &lsquo;une prison sans murs&rsquo;, <\/em>[&#8230; o&ugrave;] <em>la puissance reposerait sur la quotidiennet\u00e9 technologique de la reproduction sociale, dans laquelle les deux p\u00f4les de la discipline et de la d\u00e9tente se nourriraient alternativement l&rsquo;un \u00e0 l&rsquo;autre.<\/em>\u00ab\u00a0<\/p>\n<\/p>\n<p><p>&raquo; <em>Les auteurs interpr\u00e8tent les premiers constats de Tocqueville en appr\u00e9ciant que l&rsquo;Europe a son organisation sociale b\u00e2tie sur une organisation des traditions et des valeurs, exprim\u00e9e par la hi\u00e9rarchie en place ; de fa\u00e7on tr\u00e8s diff\u00e9rente, l&rsquo;Am\u00e9rique organise sa puissance sur la vitesse et la densit\u00e9 des \u00e9changes au sein du corps social, ces \u00e9changes allant de la tension de la discipline \u00e0 l&rsquo;apaisement de la d\u00e9tente, pour mieux recommencer le cycle, et tout cela fournissant un effet (une obligation) fondamentale d&rsquo;\u00e9mulation dans un cadre strictement contr\u00f4l\u00e9, et avec comme cons\u00e9quence le renforcement constant de la puissance (g\u00e9n\u00e9ralement \u00e9conomique) g\u00e9n\u00e9r\u00e9e par le corps social<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>La diff\u00e9rence entre l&rsquo;Europe et l&rsquo;Am\u00e9rique, que ne mentionnent pas Kroker, Kroker &#038; Cook, se trouve dans la pr\u00e9sence, dans le cours m\u00eame du processus social europ\u00e9en, du fondement de l&rsquo;effort demand\u00e9 au corps social,<\/em> [dans tous les cas jusqu&rsquo;\u00e0 tr\u00e8s r\u00e9cemment, si l&rsquo;on consid\u00e8re les changements essentiels op\u00e9r\u00e9s en Europe depuis 1985-1992]. <em>C&rsquo;est une proposition de communaut\u00e9 et de d\u00e9veloppement de destin fond\u00e9e sur les traditions avec leur enracinement historique, qu&rsquo;il s&rsquo;agit de poursuivre et sur lesquelles on doit s&rsquo;appuyer, et desquelles on doit s&rsquo;inspirer. On accepte ou pas cette cause fondamentale, \u00e9ventuellement on fait la r\u00e9volution pour la changer (et \u00e9tablir de nouvelles traditions ?) ; mais elle est l\u00e0 <strong>et le corps social a la capacit\u00e9, ou, dans tous les cas, l&rsquo;impression d&rsquo;avoir la capacit\u00e9 d&rsquo;une influence sur elles<\/strong>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>En Am\u00e9rique, au contraire, le processus social ne dispose comme cause fondamentale pour justifier son activit\u00e9 que du seul perfectionnement de son fonctionnement (la cause fondamentale de l&rsquo;existence et du d\u00e9veloppement du syst\u00e8me serait hors du processus historique et donc du corps social, qu&rsquo;elle se nomme Dieu, la Destin\u00e9e manifeste ou la Constitution qu&rsquo;on peut amender mais qu&rsquo;il est hors de question de remplacer) ; on n&rsquo;a pas \u00e0 accepter ou ne pas accepter, parce que le fonctionnement du processus social est une donn\u00e9e axiomatique de l&rsquo;organisation g\u00e9n\u00e9rale : si le fonctionnement cesse, l&rsquo;Am\u00e9rique dispara&icirc;t. <strong>L&rsquo;Europe est une civilisation de choix, l&rsquo;Am\u00e9rique est une civilisation d&rsquo;acquiescement, <\/strong><\/em>[et nous dirions m\u00eame d'\u00a0\u00bb<strong>acquiescement forc\u00e9<\/strong>\u00ab\u00a0].<\/p>\n<\/p>\n<p><p>&raquo; <em>Tocqueville note dans son &lsquo;Journal&rsquo; (cit\u00e9 par Kroker, Kroker &#038; Cook) : \u00ab\u00a0On ne peut observer la prison de Sing Sing et le syst\u00e8me de travail qui y fonctionne sans \u00eatre frapp\u00e9 par l&rsquo;\u00e9tonnement et la crainte. Bien que la discipline y soit parfaite, on sent qu&rsquo;elle repose sur des fondations tr\u00e8s fragiles : elle est l&rsquo;effet d&rsquo;un tour de force qui est une renaissance permanente toujours plus puissante, et qui doit \u00eatre reproduite chaque jour, sous peine de mettre en p\u00e9ril l&rsquo;ensemble du syst\u00e8me de la discipline.\u00a0\u00bb Cette fragilit\u00e9 est, \u00e0 notre sens, explicable \u00e9videmment par le fait que le processus social am\u00e9ricain, qui n&rsquo;a aucune assise historique (les traditions), n&rsquo;est justifi\u00e9 que par son propre fonctionnement<\/em> [qui est information et communication de l&rsquo;information pures]<em>. Il y a un enjeu n\u00e9cessairement radical dans tout accident affectant ce processus : le moindre accroc dans son fonctionnement fait n\u00e9cessairement craindre de compromettre l&rsquo;ensemble. (C&rsquo;est cette crainte, devenue rapidement panique, qui a touch\u00e9 l&rsquo;\u00e9lite am\u00e9ricaine lors de la Grande D\u00e9pression et a suscit\u00e9 ce que nous avons baptis\u00e9 de l&rsquo;expression de &lsquo;crise du caract\u00e8re am\u00e9ricain&rsquo;.) On comprend \u00e9galement que l&rsquo;aliment intellectuel, voire spirituel, de cette machinerie, par o&ugrave; passent l&rsquo;explication, l&rsquo;incitation, l&rsquo;encouragement, la menace, la manipulation, toutes utilis\u00e9es pour accompagner le processus social et pr\u00e9venir ses \u00e0-coups, c&rsquo;est \u00e9videmment l&rsquo;information avec sa technique d&rsquo;animation et de circulation qu&rsquo;est la communication<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;une certaine fa\u00e7on et selon cette absolue pr\u00e9\u00e9minence de l&rsquo;information et de la communication aux origines des USA, <strong>avec l&rsquo;id\u00e9e \u00ab\u00a0id\u00e9ale\u00a0\u00bb de \u00ab\u00a0la prison sans barreaux\u00a0\u00bb<\/strong>, c&rsquo;\u00e9tait le mod\u00e8le utopique du <a href=\"applewebdata:\/\/837906C9-0D64-40A8-9FA8-70A29CE70A60\/panoptique%C2%A0:%20https:\/fr.wikipedia.org\/wiki\/Panoptique\">Panoptique<\/a> qui \u00e9tait destin\u00e9 \u00e0 prosp\u00e9rer, \u00e0 s&rsquo;accomplir et \u00e0 installer ce que Foucault d\u00e9signait comme \u00ab\u00a0le contr\u00f4le social\u00a0\u00bb :<\/p>\n<\/p>\n<p><p>&laquo; <em>L&rsquo;objectif de la structure panoptique est de permettre \u00e0 un gardien, log\u00e9 dans une tour centrale, d&rsquo;observer tous les prisonniers, enferm\u00e9s dans des cellules individuelles autour de la tour, sans que ceux-ci puissent savoir s&rsquo;ils sont observ\u00e9s. Ce <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Dispositif_(philosophie)\" title=\"Dispositif (philosophie)\">dispositif<\/a> devait ainsi donner aux d\u00e9tenus le sentiment d&rsquo;\u00eatre surveill\u00e9s constamment et ce, sans le savoir v\u00e9ritablement, c&rsquo;est-\u00e0-dire \u00e0 tout moment. Le philosophe et historien <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Michel_Foucault\" title=\"Michel Foucault\">Michel Foucault<\/a>, dans <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Surveiller_et_punir\" title=\"Surveiller et punir\">Surveiller et punir<\/a> (1975), en fait le mod\u00e8le abstrait d&rsquo;une <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Soci%C3%A9t%C3%A9_disciplinaire\" title=\"Soci\u00e9t\u00e9 disciplinaire\">soci\u00e9t\u00e9 disciplinaire<\/a>, ax\u00e9e sur le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Contr%C3%B4le_social\" title=\"Contr\u00f4le social\">contr\u00f4le social<\/a><\/em>. &raquo; (Wikip\u00e9dia)<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9tat actuel du syst\u00e8me carc\u00e9ral US, tout comme l&rsquo;\u00e9volution des diverses soci\u00e9t\u00e9s touch\u00e9es <strong>par d&rsquo;innombrables mouvements de r\u00e9voltes diverses <\/strong>qui actent le chaos, la redondance et l&rsquo;impuissance des syst\u00e8mes de surveillance pl\u00e9thoriques de plus en plus sophistiqu\u00e9s, avec toute possibilit\u00e9 de capacit\u00e9 qualitative \u00e9touff\u00e9e par la monstrueuse n\u00e9cessit\u00e9 quantitative des donn\u00e9es, <strong>marquent l&rsquo;\u00e9chec de ce \u00ab\u00a0progr\u00e8s\u00a0\u00bb que d\u00e9non\u00e7ait par avance Foucault<\/strong>. Cet \u00e9chec devrait \u00eatre n\u00e9 \u00e0 partir des premiers signes de d\u00e9l\u00e9gitimation du syst\u00e8me de l&rsquo;am\u00e9ricanisme dans le domaine carc\u00e9ral par rapport \u00e0 ses ambitions de l\u00e9gitimit\u00e9, premiers signes apparus avec la Guerre de S\u00e9cession (o&ugrave; l&rsquo;on vit effectivement les premiers camps de prisonniers transform\u00e9s en camps de r\u00e9pression, de torture et de mouroirs).<\/p>\n<\/p>\n<p><p>Ce que montre l&rsquo;univers carc\u00e9ral US aujourd&rsquo;hui, <strong>ce n&rsquo;est certainement pas le contr\u00f4le par la surveillance, c&rsquo;est-\u00e0-dire dans l&rsquo;ordre, mais son exact contraire<\/strong>, selon l&rsquo;\u00e9tat de d\u00e9sordre chaotique o&ugrave; on le voit (avec les cons\u00e9quences qu&rsquo;on imagine d&rsquo;exporter ce d\u00e9sordre pour ceux qui parviennent \u00e0 s&rsquo;\u00e9chapper, l\u00e9galement ou pas, de cet enfer) : <strong>la barbarie sans surveillance<\/strong>. Une fois de plus, on voit d\u00e9montr\u00e9 le fait que l&rsquo;\u00e9volution de la modernit\u00e9, m\u00eame dans ses ambitions de perfection r\u00e9pressive, n&rsquo;est capable de produire que l&rsquo;inversion de ses projets. M\u00eame dans la contrainte, elle est mauvaise pour sa propre survie, elle ne produit que le d\u00e9sordre chaotique, c&rsquo;est-\u00e0-dire <strong>qu&rsquo;elle se mine elle-m\u00eame en reproduisant les purs et pires aspects des soci\u00e9t\u00e9s totalitaires de contrainte<\/strong>, &ndash; et, l\u00e0 aussi, reproduisant l&rsquo;\u00e9quation <strong>surpuissance-autodestruction<\/strong>.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">L&rsquo;Am\u00e9rique barbare<\/h2>\n<\/p>\n<p><p>Les viols, les meurtres, les passages \u00e0 tabac, les coups de couteau, les mutilations et les incendies criminels sont monnaie courante. Des appels \u00e0 l&rsquo;aide, gribouill\u00e9s de sang, tachent les murs des prisonniers maintenus au secret. Quinze suicides ont \u00e9t\u00e9 enregistr\u00e9s au cours des 15 derniers mois.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pas la description d&rsquo;une chambre de torture dans l&rsquo;Egypte d&rsquo;El-Sisi ou dans l&rsquo;Arabie Saoudite de Bin Salman. Il ne s&rsquo;agit pas non plus des mauvais traitements inflig\u00e9s aux d\u00e9tenus de la c\u00e9l\u00e8bre prison d&rsquo;Abu Ghraib en Irak, du camp de prisonniers de Guantanamo Bay ou d&rsquo;un <em>black site <\/em>de la CIA. Il s&rsquo;agit des conditions <a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/04\/05\/pris-a05.html\">cauchemardesques<\/a> du syst\u00e8me carc\u00e9ral de l&rsquo;&Eacute;tat de l&rsquo;Alabama, d\u00e9crites dans un rapport du minist\u00e8re de la Justice publi\u00e9 cette semaine. Ces conditions constituent une violation flagrante de l&rsquo;interdiction des peines cruelles et hors des normes pr\u00e9vue par le Huiti\u00e8me Amendement de la Constitution am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>Plus de 2 000 photos d&rsquo;abus dans une prison de l&rsquo;Alabama remises aux m\u00e9dias par le Southern Poverty Law Center avant la publication du rapport d\u00e9crivent la r\u00e9alit\u00e9 \u00e9pouvantable des conditions de d\u00e9tention document\u00e9es par des centaines d&rsquo;entrevues avec des d\u00e9tenus et leurs familles men\u00e9es par des enqu\u00eateurs f\u00e9d\u00e9raux pendant plus de deux ans. Bien qu&rsquo;elles soient particuli\u00e8rement horribles, de telles conditions ne sont en aucun cas uniques. Elles se r\u00e9p\u00e8tent sous diff\u00e9rentes formes dans les prisons de chaque &Eacute;tat, comt\u00e9 et ville des &Eacute;tats-Unis. Plus de 2,3 millions de personnes sont entass\u00e9es comme du b\u00e9tail dans le syst\u00e8me surcharg\u00e9 de prisons d&rsquo;&Eacute;tat et f\u00e9d\u00e9rales, de prisons locales et de camps de d\u00e9tention pour immigrants. Si l&rsquo;on inclut les personnes en probation ou en libert\u00e9 conditionnelle, pr\u00e8s de sept millions d&rsquo;Am\u00e9ricains d\u00e9pendent de ce que l&rsquo;on appelle absurdement le \u00ab\u00a0syst\u00e8me de justice p\u00e9nale\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Les &Eacute;tats-Unis repr\u00e9sentent plus du quart de la population carc\u00e9rale mondiale. Pour 100 000 habitants, il y a 698 personnes en d\u00e9tention. Plus de 540 000 des personnes incarc\u00e9r\u00e9es un jour donn\u00e9 n&rsquo;ont jamais \u00e9t\u00e9 reconnues coupables d&rsquo;un crime. Bon nombre d&rsquo;entre elles sont maintenus en d\u00e9tention simplement parce qu&rsquo;ils sont trop mal pay\u00e9s pour payer la caution m\u00e9diane de 10 000 $. Un autre demi-million, soit un d\u00e9tenu sur cinq, purge de longues peines d&#8217;emprisonnement pour des condamnations non violentes en mati\u00e8re de drogue.<\/p>\n<\/p>\n<p><p>Les chercheurs estiment qu&rsquo;un nombre m\u00e9dian de 61 000 prisonniers sont d\u00e9tenus chaque jour en condition d&rsquo;isolement totale, une forme d&rsquo;incarc\u00e9ration que l&rsquo;ONU a d\u00e9clar\u00e9e \u00eatre assimilable \u00e0 de la torture. Au moins 4 000 des personnes d\u00e9tenues dans un isolement total par rapport au monde ext\u00e9rieur souffrent d&rsquo;une maladie mentale grave. L&rsquo;enfermement dans ces cercueils vivants est connu pour pousser les prisonniers au suicide.<\/p>\n<\/p>\n<p><p>Alors que les emprisonnements pour fait de dettes sont officiellement interdits, les travailleurs pauvres sont r\u00e9guli\u00e8rement d\u00e9tenus pour leurs dettes. Une m\u00e8re dans l&rsquo;Indiana a \u00e9t\u00e9 <a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/03\/01\/sing-m01.html\">d\u00e9tenue<\/a> pendant trois jours en f\u00e9vrier dans une prison sordide aux c\u00f4t\u00e9s de condamn\u00e9s en raison d&rsquo;une facture d&rsquo;ambulance impay\u00e9e, qu&rsquo;elle n&rsquo;avait jamais re\u00e7ue par la poste. De telles histoires sont courantes.<\/p>\n<\/p>\n<p><p>Sous l&rsquo;administration Trump, qui prolonge les politiques \u00e9labor\u00e9es par Obama, le gouvernement f\u00e9d\u00e9ral m\u00e8ne une guerre contre les immigrants, d\u00e9tenant des milliers d&rsquo;hommes, de femmes et d&rsquo;enfants dans des conditions d\u00e9gradantes. Quelque 77 000 personnes ont \u00e9t\u00e9 arr\u00eat\u00e9es en f\u00e9vrier pour avoir tent\u00e9 de franchir la fronti\u00e8re Sud. Les travailleurs immigr\u00e9s sont pourchass\u00e9s et arr\u00eat\u00e9s \u00e0 leur domicile et sur leur lieu de travail. La cruaut\u00e9 du gouvernement am\u00e9ricain a \u00e9t\u00e9 pleinement mise en \u00e9vidence cette semaine lorsque 280 travailleurs sans papiers ont \u00e9t\u00e9 d\u00e9tenus par des agents f\u00e9d\u00e9raux \u00e0 Allen, au Texas. Il s&rsquo;agissait du plus grand raid de ce genre en plus d&rsquo;une d\u00e9cennie.<\/p>\n<\/p>\n<p><p>Ensuite, il y a la vague interminable d&rsquo;assassinats de policiers, avec plus de 1 000 personnes tu\u00e9es par balle, par taser ou battues \u00e0 mort chaque ann\u00e9e dans les rues des villes am\u00e9ricaines. Les accusations criminelles pour des meurtres commis par la police sont rares et les condamnations presque inexistantes. Les policiers ont le feu vert pour tuer, mutiler et brutaliser en toute impunit\u00e9.<\/p>\n<\/p>\n<p><p>Avec une hypocrisie sans bornes, les d\u00e9mocrates et les r\u00e9publicains proclament leur indignation face aux violations pr\u00e9sum\u00e9es des droits de l&rsquo;homme dans les pays que la classe dirigeante am\u00e9ricaine cible pour un changement de r\u00e9gime ou une invasion. Ils proclament que l&rsquo;une des soci\u00e9t\u00e9s les plus cruelles et les plus in\u00e9gales du monde, o&ugrave; les trois Am\u00e9ricains les plus riches contr\u00f4lent plus de richesses que la moiti\u00e9 inf\u00e9rieure de la population, est un mod\u00e8le de d\u00e9mocratie pour le monde. Si les conditions qui existent dans les prisons am\u00e9ricaines \u00e9taient \u00e9quivalentes et document\u00e9es en Russie ou en Chine, il y aurait un toll\u00e9 dans la presse et dans les salles du Congr\u00e8s pour des sanctions \u00e9conomiques et une intervention militaire \u00ab\u00a0humanitaire\u00a0\u00bb qui r\u00e9sonnerait dans les m\u00e9dias.<\/p>\n<\/p>\n<p><p>Il y a cinquante ans, un rapport comme celui qui exposait les conditions de d\u00e9tention dans les prisons de l&rsquo;Alabama aurait \u00e9t\u00e9 accueilli, m\u00eame au sein de certains secteurs de l&rsquo;establishment politique et m\u00e9diatique \u00e0 Washington, comme un choc et suivi de demandes d&rsquo;action imm\u00e9diate. Aujourd&rsquo;hui il passe \u00e0 peine avec un murmure.<\/p>\n<\/p>\n<p><p>Le Parti d\u00e9mocrate est silencieux parce qu&rsquo;il est complice de la vaste r\u00e9gression des conditions dans les prisons am\u00e9ricaines. Le pr\u00e9sident Bill Clinton a sign\u00e9 la loi qui a ouvert la voie \u00e0 une augmentation historique de la population carc\u00e9rale. Les d\u00e9mocrates supervisent un syst\u00e8me p\u00e9nitentiaire en Californie qui a \u00e9t\u00e9 jug\u00e9 par la Cour supr\u00eame en 2011 comme \u00e9tant \u00ab\u00a0cruel et hors des normes tol\u00e9rables\u00a0\u00bb, et en violation de la Constitution.<\/p>\n<\/p>\n<p><p>La classe moyenne sup\u00e9rieure et les couches correspondantes au sein et autour du Parti d\u00e9mocrate ne sont pas int\u00e9ress\u00e9es. Les promoteurs de la campagne #MeToo dans les m\u00e9dias et le milieu universitaire n&rsquo;ont rien \u00e0 dire sur la violence sexuelle dans les prisons am\u00e9ricaines, ni sur la violence inflig\u00e9e aux immigrants qui fuient aux &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Les m\u00e9dias ont fait le moins de reportages possibles, sans aucune couverture dans les grands journaux t\u00e9l\u00e9vis\u00e9s du soir. Comme pour les photos d&rsquo;abus \u00e0 Abu Ghraib et le rapport du S\u00e9nat sur la torture de la CIA, il y a eu un effort pour supprimer les informations sur ce qui se passe en Alabama. Le New York Times et d&rsquo;autres m\u00e9dias ont choisi de ne pas publier la plupart des photos documentant les abus et les d\u00e9c\u00e8s.<\/p>\n<\/p>\n<p><p>En fin de compte, cet \u00e9tat leur correspond. Les conditions de d\u00e9tention dans les prisons am\u00e9ricaines et l&rsquo;appareil de violence dans son ensemble sont une expression nocive de la r\u00e9alit\u00e9 de la &quot;d\u00e9mocratie&quot; am\u00e9ricaine. L&rsquo;appareil d&rsquo;&Eacute;tat sera utilis\u00e9 pour supprimer l&rsquo;opposition sociale et politique aux exigences du capital financier. C&rsquo;est le vrai visage du capitalisme am\u00e9ricain.<\/p>\n<\/p>\n<p><h4>Niels Niemuth, <em>WSWS.org<\/em><\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>USA : du Panoptique \u00e0 la barbarie On voit ci-dessous, dans un texte de WSWS.org (6 avril 2019)dont on comprend bien, selon les traditions de ce site, qu&rsquo;il n&rsquo;est en rien dans ses intentions d&rsquo;att\u00e9nuer sous le conformisme bienpensant les horreurs infernales de la situation am\u00e9ricaniste, l&rsquo;\u00e9tat actuel de l&rsquo;\u00a0\u00bbenfer carc\u00e9ral\u00a0\u00bb que constitue l&rsquo;\u00a0\u00bbunivers carc\u00e9ral\u00a0\u00bb&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3845,10372,6182,3811,18981,6183,3098,9715],"class_list":["post-78561","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-article","tag-alabama","tag-carceral","tag-cook","tag-kroker","tag-prisons","tag-tocqueville","tag-univers"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78561"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78561\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}