{"id":78568,"date":"2019-04-11T13:31:53","date_gmt":"2019-04-11T13:31:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/04\/11\/la-nef-des-idiots-us-fait-eau-de-toutes-parts\/"},"modified":"2019-04-11T13:31:53","modified_gmt":"2019-04-11T13:31:53","slug":"la-nef-des-idiots-us-fait-eau-de-toutes-parts","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/04\/11\/la-nef-des-idiots-us-fait-eau-de-toutes-parts\/","title":{"rendered":"La nef des idiots US fait eau de toutes parts"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La nef des idiots US fait eau de toutes parts<\/h2>\n<\/p>\n<p><p>C&rsquo;est certainement ce que ce pays semble faire, et le rythme s&rsquo;acc\u00e9l\u00e8re. Le fait d&rsquo;avoir pass\u00e9 les trois derni\u00e8res semaines dans un endroit discret, loin d&rsquo;Internet, m&rsquo;a permis d&rsquo;observer l&rsquo;augmentation de la mont\u00e9e des eaux dans les cales. Il y avait du Wifi \u00e0 l&rsquo;a\u00e9roport et j&rsquo;ai t\u00e9l\u00e9charg\u00e9 trois semaines d&rsquo;articles que j&rsquo;ai lus pendant le long vol vers la civilisation. Ce que j&rsquo;ai lu a \u00e9t\u00e9 un peu choquant, surtout apr\u00e8s trois semaines de surf, d&rsquo;oiseaux de mer, de crabes en ballade et de gens heureux et amicaux qui ne perdaient pas leur temps \u00e0 se soucier des &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Depuis quelque temps, les gens me disent que je devrais regarder le film <a href=\"http:\/\/www.allocine.fr\/film\/fichefilm_gen_cfilm=109539.html\">Idiocratie<\/a>parce qu&rsquo;il montre ce que les &Eacute;tats-Unis sont en train de devenir. Eh bien, je ne suis pas s&ucirc;r qu&rsquo;un film sur l&rsquo;idiotie puisse \u00e9viter de devenir idiot, alors je vais passer mon tour, mais il y a une augmentation certaine du niveau de stupidit\u00e9 affich\u00e9 par ceux qui font partie de l&rsquo;establishment am\u00e9ricain. Cela ne devrait pas \u00eatre une surprise ; apr\u00e8s tout, pourquoi quelqu&rsquo;un qui poss\u00e8de de la sagesse et de l&rsquo;int\u00e9grit\u00e9 voudrait-il avoir quelque chose \u00e0 voir avec ce truc en ce moment ? Des sommets de stupidit\u00e9 &ndash; si stupides qu&rsquo;on se fait du tort rien qu&rsquo;en les regardant &ndash; sont tout autour de nous en ce moment. Permettez-moi d&rsquo;en souligner quelques-uns parmi les plus importants.<\/p>\n<\/p>\n<p><p>Pendant que j&rsquo;\u00e9tais occup\u00e9 \u00e0 regarder scintiller mes orteils dans les eaux azur\u00e9es, l&rsquo;enqu\u00eateur sp\u00e9cial Robert Mueller a finalement publi\u00e9 son rapport. Il n&rsquo;a pas laiss\u00e9 une pierre sans la retourner, mais n&rsquo;a pas r\u00e9ussi \u00e0 accomplir sa t\u00e2che assign\u00e9e qui \u00e9tait de prouver que Trump avait organis\u00e9 une collusion avec la Russie. Dans son rapport, il affirme que bien qu&rsquo;il n&rsquo;ait trouv\u00e9 aucune preuve de collusion ou d&rsquo;obstruction \u00e0 la justice, son rapport n&rsquo;exon\u00e8re pas Trump. Notez ces deux points d&rsquo;extr\u00eame stupidit\u00e9. Premier point : s&rsquo;il n&rsquo;y a pas de collusion, il n&rsquo;y a pas de crime et donc il n&rsquo;y a pas de cours de la justice \u00e0 entraver. Deuxi\u00e8me point : si, comme Mueller l&rsquo;admet, aucun crime n&rsquo;a \u00e9t\u00e9 commis, il n&rsquo;y a rien dont on doit disculper Trump.<\/p>\n<\/p>\n<p><p>Les d\u00e9mocrates, qui esp\u00e9raient destituer Trump sur la base du rapport Mueller, devraient peut-\u00eatre garder espoir dans le fait que Mueller s&rsquo;est av\u00e9r\u00e9 si incomp\u00e9tent, au point de ne rien comprendre des principes basiques de sa profession, que peut-\u00eatre y a-t-il eu collusion apr\u00e8s tout, mais que Mueller \u00e9tait trop stupide pour en trouver la preuve. Ou peut-\u00eatre les d\u00e9mocrates devraient-ils s&rsquo;effondrer dans un paroxysme de d\u00e9sespoir, parce que Mueller \u00e9tait leur meilleure et derni\u00e8re chance et maintenant ils ressemblent \u00e0 des idiots pour avoir cru en lui.<\/p>\n<\/p>\n<p><p>Ensuite, dans le d\u00e9fil\u00e9 des stupidit\u00e9s, nous avons le procureur g\u00e9n\u00e9ral William Barr, qui, dans son r\u00e9sum\u00e9 du rapport de Mueller, a accept\u00e9 sans la moindre h\u00e9sitation les all\u00e9gations selon lesquelles la Russie s&rsquo;est ing\u00e9r\u00e9e dans l&rsquo;\u00e9lection pr\u00e9sidentielle de 2016. Qu&rsquo;est-ce que c&rsquo;\u00e9tait que cette ing\u00e9rence ?<\/p>\n<\/p>\n<p><p>Il y avait une ferme de trolls \u00e0 Saint-P\u00e9tersbourg g\u00e9r\u00e9e par quelqu&rsquo;un qui aurait cuisin\u00e9 une fois pour Poutine. Les trolls mettaient des annonces comme app\u00e2ts sur les m\u00e9dias sociaux. Leur champ d&rsquo;action \u00e9tait minuscule et la plupart de leurs activit\u00e9s ont eu lieu apr\u00e8s l&rsquo;\u00e9lection, ce qui rend ridicule l&rsquo;affirmation selon laquelle ils ont manipul\u00e9 l&rsquo;\u00e9lection. Les efforts de Mueller pour les poursuivre se sont arr\u00eat\u00e9s nets lorsque leurs avocats se sont pr\u00e9sent\u00e9s devant le tribunal et ont exig\u00e9 de voir les preuves. Mueller ne pouvait pas laisser cela se produire parce que cela aurait fait mourir de rire toute la salle d&rsquo;audience.<\/p>\n<\/p>\n<p><p>Il y avait aussi l&rsquo;all\u00e9gation selon laquelle des pirates russes auraient pirat\u00e9 un serveur de messagerie de la DNC, vol\u00e9 une s\u00e9rie de courriels montrant un effort pour truquer les primaires contre Bernie Sanders, et les auraient divulgu\u00e9s \u00e0 Wikileaks. Mais il y a des preuves que ces courriels n&rsquo;ont pas \u00e9t\u00e9 pirat\u00e9s, mais qu&rsquo;ils ont \u00e9t\u00e9 copi\u00e9s sur une cl\u00e9 USB par une personne ayant un acc\u00e8s physique au serveur.<\/p>\n<\/p>\n<p><p>Barr est-il trop stupide pour se rendre compte de la b\u00eatise de ses affirmations selon lesquelles \u00ab\u00a0les Russes\u00a0\u00bb &ndash; quelle que soit la signification de l&rsquo;expression &ndash; avaient manipul\u00e9 les \u00e9lections am\u00e9ricaines ? Oui, cela semble \u00eatre le cas. Avec des fonctionnaires aussi stupides, \u00e0 quel point \u00e9tait-il stupide pour les d\u00e9mocrates de passer deux ans \u00e0 nourrir leur r\u00eave de se d\u00e9barrasser de Trump avec leur aide ?<\/p>\n<\/p>\n<p><p>Ainsi, Trump est l\u00e0 pour rester. C&rsquo;est ici que cette litanie de stupidit\u00e9 s&rsquo;arr\u00eate ? Non, bien s&ucirc;r que non, car ici nous entrons simplement dans le cercle suivant de la stupidit\u00e9. Trump r\u00eave de &laquo; <em>Rendre sa grandeur \u00e0 l&rsquo;Am\u00e9rique<\/em> &raquo;, mais son r\u00eave est-il stupide ? Voyons les r\u00e9sultats.<\/p>\n<\/p>\n<p><p>Son id\u00e9e \u00e9tait de ren\u00e9gocier les accords commerciaux en faveur des &Eacute;tats-Unis et de rapatrier le secteur manufacturier qui avait \u00e9t\u00e9 d\u00e9localis\u00e9 dans des pays \u00e0 bas salaires, de r\u00e9duire le d\u00e9ficit commercial et de cr\u00e9er beaucoup de bons emplois. Cela semble \u00eatre un bon plan, mais prenons un peu de recul et voyons quel est le vrai probl\u00e8me.<\/p>\n<\/p>\n<p><p>Le vrai probl\u00e8me, c&rsquo;est qu&rsquo;il y a un d\u00e9s\u00e9quilibre massif aux &Eacute;tats-Unis entre ce que les Am\u00e9ricains produisent et ce qu&rsquo;ils consomment : ils consomment beaucoup plus qu&rsquo;ils ne peuvent se le permettre.<\/p>\n<\/p>\n<p><p>Une solution serait de r\u00e9duire la consommation, mais elle repr\u00e9sente 70 % de l&rsquo;\u00e9conomie, et la r\u00e9duire ferait \u00e9clater la bulle d&rsquo;endettement d\u00e9j\u00e0 disproportionn\u00e9e et plongerait l&rsquo;\u00e9conomie am\u00e9ricaine dans une plus profonde d\u00e9pression. &Ccedil;a n&rsquo;a pas l&rsquo;air g\u00e9nial du tout.<\/p>\n<\/p>\n<p><p>Une autre solution serait de d\u00e9valuer le dollar par le biais d&rsquo;\u00e9missions de dollars non contr\u00f4l\u00e9es. Cela rendrait les exportations am\u00e9ricaines comp\u00e9titives par rapport \u00e0 celles des pays \u00e0 bas salaires. Mais cela saperait le dollar am\u00e9ricain en tant que monnaie de r\u00e9serve, pousserait les d\u00e9tenteurs de la dette am\u00e9ricaine dans le monde entier \u00e0 se pr\u00e9cipiter vers la sortie en vendant leurs r\u00e9serves de dollars et provoquerait un choc hyper-inflationniste qui plongerait \u00e0 nouveau l&rsquo;\u00e9conomie am\u00e9ricaine dans une d\u00e9pression plus profonde. Cela ne semble pas g\u00e9nial non plus, mais c&rsquo;\u00e9tait le plan propos\u00e9 par Steve Bannon, l&rsquo;ancien conseiller de Trump. Steve est peut-\u00eatre un peu limit\u00e9 intellectuellement.<\/p>\n<\/p>\n<p><p>Une autre solution, encore, propos\u00e9e par William Dudley de la R\u00e9serve f\u00e9d\u00e9rale, \u00e9tait d&rsquo;utiliser des m\u00e9thodes fiscales pour stimuler une renaissance de la production aux &Eacute;tats-Unis, et c&rsquo;est celle qui a plu \u00e0 Trump et qui a permis aux entreprises de rapatrier leurs b\u00e9n\u00e9fices de l&rsquo;\u00e9tranger sans \u00eatre impos\u00e9es. Est-ce que \u00e7a a march\u00e9 ? Bien s&ucirc;r que non ! Au lieu d&rsquo;investir dans la production, les soci\u00e9t\u00e9s ont utilis\u00e9 cet argent pour racheter leurs propres actions, ce qui a permis \u00e0 leurs principaux actionnaires de vendre leurs actions de fa\u00e7on rentable aux frais de l&rsquo;&Eacute;tat. Voici Alice Walton, propri\u00e9taire \u00e0 10 % de Walmart, qui a liquid\u00e9 pour plus de 700 millions de dollars de ses actions au cours du seul mois de mars. Nous pouvons \u00eatre s&ucirc;rs qu&rsquo;Alice Walton n&rsquo;investira pas ces 700 millions dans la vente au d\u00e9tail. &Eacute;tait-ce stupide de la part de Dudley et Trump de penser que ce plan marcherait ? Apparemment, oui.<\/p>\n<\/p>\n<p><p>C&rsquo;est donc ici que se situe actuellement le plan visant \u00e0 &laquo;<em> Rendre sa grandeur \u00e0 l&rsquo;Am\u00e9rique <\/em>&raquo;. L&rsquo;\u00e9conomie s&rsquo;effondre. La R\u00e9serve f\u00e9d\u00e9rale ne peut pas la sortir du gouffre en abaissant les taux d&rsquo;int\u00e9r\u00eat parce qu&rsquo;ils sont d\u00e9j\u00e0 trop bas. Il y a un carnage massif dans le secteur du commerce de d\u00e9tail et de nombreuses entreprises am\u00e9ricaines sont sur le point de faire faillite. L&rsquo;ancienne grande entreprise General Electrica \u00e9t\u00e9 expuls\u00e9e du Dow Jones et est en train de vendre ses joyaux de la couronne aux Russes. Que reste-t-il \u00e0 faire ?<\/p>\n<\/p>\n<p><p>Voici encore le cas de Janet Yellen, l&rsquo;ancienne pr\u00e9sidente de la R\u00e9serve f\u00e9d\u00e9rale, avec un plan vraiment stup\u00e9fiant de stupidit\u00e9. Elle propose que la R\u00e9serve f\u00e9d\u00e9rale intervienne et commence \u00e0 racheter directement la dette des entreprises en utilisant de la monnaie nouvellement imprim\u00e9e. Notez comment le plan de Yellen combine magnifiquement la stupidit\u00e9 du plan de Bannon (tirer le tapis sous le dollar am\u00e9ricain) avec la stupidit\u00e9 du plan de Dudley (donner aux soci\u00e9t\u00e9s une autre chance de racheter leurs propres actions afin que leurs actionnaires majeurs puissent continuer \u00e0 se renflouer et faire des profits aux frais de l&rsquo;&Eacute;tat). <\/p>\n<\/p>\n<p><p>Ce manque d&rsquo;id\u00e9es non stupides nous laisse avec Trump se balan\u00e7ant dans sa cellule capitonn\u00e9e en \u00e9mettant des tweets stupides tels que les suivants : &laquo;<em> Tr\u00e8s important que l&rsquo;OPEP augmente le flux de p\u00e9trole. Les march\u00e9s mondiaux sont fragiles, le prix du p\u00e9trole devient trop \u00e9lev\u00e9. Merci ! <\/em>&raquo;<em>.<\/em>Pendant ce temps, il a interdit les importations am\u00e9ricaines de p\u00e9trole lourd en provenance du Venezuela (n\u00e9cessaire pour produire du diesel), tandis que les exportations am\u00e9ricaines de p\u00e9trole l\u00e9ger (issues de la fracturation hydraulique) se heurtent \u00e0 des probl\u00e8mes en raison de leur faible qualit\u00e9, que les investissements dans la fracturation ont chut\u00e9 violemment et que les entreprises \u00e9nerg\u00e9tiques qui se consacrent \u00e0 cette activit\u00e9, dont la plupart n&rsquo;ont jamais gagn\u00e9 d&rsquo;argent, signalent une p\u00e9nurie de nouveaux endroits productifs pour forer du p\u00e9trole. Il est stupide de penser que tweeter r\u00e9glera tous ces probl\u00e8mes.<\/p>\n<\/p>\n<p><p>En r\u00e9sum\u00e9, ce navire rempli d&rsquo;idiots prend eau de toutes parts et toutes les propositions formul\u00e9es jusqu&rsquo;\u00e0 pr\u00e9sent sont stupides et \u00e9quivalent \u00e0 une tentative de renflouement \u00e0 l&rsquo;aide d&rsquo;un tamis. C&rsquo;est vraiment \u00e9c&oelig;urant \u00e0 regarder ! Cela me donne envie de retourner sur cette plage et d&rsquo;y vivre avec du lait de coco, des poissons fra&icirc;chement p\u00each\u00e9s et des fruits tropicaux, et de ne plus jamais me connecter \u00e0 l&rsquo;internet.<\/p>\n<\/p>\n<p><p>Mais je vais faire avec et continuer comme avant. Les mardis seront toujours des jours gratuits, tandis que les jeudis, j&rsquo;offrirai \u00e0 mes fid\u00e8les partisans de nouvelles visions grandioses. &Agrave; suivre : l&rsquo;ethnosph\u00e8re humaine, en tant qu&rsquo;aspect \u00e9volutif de la biosph\u00e8re &ndash; un sujet que j&rsquo;ai \u00e9tudi\u00e9 en profondeur, allong\u00e9 sur la plage. Elle d\u00e9tient la cl\u00e9 pour comprendre le cycle de vie des nations, dont certaines sont pleines d&rsquo;\u00e9nergie et de dynamisme, tandis que d&rsquo;autres ont largement d\u00e9pass\u00e9 leur apog\u00e9e et sont dirig\u00e9es par des gens manifestement stupides.<\/p>\n<\/p>\n<p><p>(Le 2 avril 2019, <a href=\"http:\/\/cluborlov.blogspot.com\/2019\/04\/is-uss-ship-of-fools-taking-on-water.html\">Club Orlov<\/a>&ndash; Traduction par <em><a href=\"https:\/\/lesakerfrancophone.fr\/le-navire-americain-rempli-didiots-prend-il-leau\">Le Sakerfrancophone<\/a><\/em>.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nef des idiots US fait eau de toutes parts C&rsquo;est certainement ce que ce pays semble faire, et le rythme s&rsquo;acc\u00e9l\u00e8re. Le fait d&rsquo;avoir pass\u00e9 les trois derni\u00e8res semaines dans un endroit discret, loin d&rsquo;Internet, m&rsquo;a permis d&rsquo;observer l&rsquo;augmentation de la mont\u00e9e des eaux dans les cales. Il y avait du Wifi \u00e0 l&rsquo;a\u00e9roport&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3795,13859,9476,2668,2639],"class_list":["post-78568","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-economie","tag-idiotie","tag-mueller","tag-orlov","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78568"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78568\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}