{"id":78608,"date":"2019-05-02T04:55:15","date_gmt":"2019-05-02T04:55:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/02\/le-martyre-de-saint-julian\/"},"modified":"2019-05-02T04:55:15","modified_gmt":"2019-05-02T04:55:15","slug":"le-martyre-de-saint-julian","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/02\/le-martyre-de-saint-julian\/","title":{"rendered":"Le martyre de Saint-Julian"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le martyre de Saint-Julian<\/h2>\n<\/p>\n<p><p>La nouvelle de l&rsquo;arrestation et de l&#8217;emprisonnement de Julian Assange vous est probablement parvenue, mais, au cas o&ugrave;, voici un r\u00e9sum\u00e9. Julian Assange est un journaliste australien ; en tant que tel, il est un g\u00e9ant imposant parmi un petit groupe de nains. Googlez  \u00ab\u00a0<em>grands journalistes australiens<\/em>\u00ab\u00a0et vous obtenez son nom \u00e0 lui et ceux d&rsquo;un tas de gens dont personne n&rsquo;a jamais entendu parler, beaucoup d&rsquo;entre eux \u00e9tant d\u00e9j\u00e0 morts.<\/p>\n<\/p>\n<p><p>C&rsquo;est aussi un personnage qui compte \u00e0 l&rsquo;ext\u00e9rieur de l&rsquo;Australie. Alors que d&rsquo;autres journalistes occidentaux tentent de faire plaisir \u00e0 leurs propri\u00e9taires, en vendant de l&rsquo;espace publicitaire ou pour \u00e9viter d&rsquo;\u00eatre bannis par l&rsquo;&oelig;il attentif des corporations derri\u00e8re les m\u00e9dias sociaux, Assange est \u00e0 la fois courageux et mu  par des principes. Par l&rsquo;interm\u00e9diaire de son m\u00e9dia Wikileaks, il a d\u00e9voil\u00e9 les sales secrets du D\u00e9partement d&rsquo;&Eacute;tat am\u00e9ricain et les crimes de guerre du Pentagone, les m\u00e9faits des entreprises et la corruption politique, permettant \u00e0 tous de voir le linge sale de nombreuses personnes influentes et puissantes. Cela a fait de lui une cause c\u00e9l\u00e8bre : Le magazine <em>Time<\/em> l&rsquo;a proclam\u00e9 Homme de l&rsquo;ann\u00e9e et il a re\u00e7u des prix sur le th\u00e8me des droits de l&rsquo;homme, nageant dans le m\u00eame panth\u00e9on que Nelson Mandela et le Dala\u00ef Lama. Mais les vicissitudes de la fortune sont telles qu&rsquo;il est maintenant martyris\u00e9, victime de la v\u00e9rit\u00e9, injustement accus\u00e9 et pers\u00e9cut\u00e9 par une race de menteurs inv\u00e9t\u00e9r\u00e9s.<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait in\u00e9vitable. En publiant des preuves de sales secrets et de crimes de guerre, il s&rsquo;est fait beaucoup d&rsquo;ennemis puissants et influents, et ils ont fini par cr\u00e9er de fausses preuves \u00e0 utiliser contre lui. En 2012, face au sort peu enviable d&rsquo;une extradition du Royaume-Uni vers la Su\u00e8de, o&ugrave; il devait \u00eatre humili\u00e9 devant un tribunal populaire su\u00e9dois, Assange choisit d&rsquo;entrer \u00e0 l&rsquo;ambassade d&rsquo;&Eacute;quateur \u00e0 Londres, o&ugrave; il devait passer les sept ann\u00e9es suivantes dans une petite pi\u00e8ce. Il s&rsquo;agissait globalement d&rsquo;une forme d&rsquo;isolement cellulaire, qui est commun\u00e9ment consid\u00e9r\u00e9e comme une forme de torture.<\/p>\n<\/p>\n<p><p>Il est difficile de dire si la d\u00e9cision de se r\u00e9fugier \u00e0 l&rsquo;ambassade de l&rsquo;&Eacute;quateur a \u00e9t\u00e9 une bonne ou une mauvaise d\u00e9cision au d\u00e9part, mais elle s&rsquo;est transform\u00e9e en une d\u00e9cision de plus en plus mauvaise avec le temps. D&rsquo;une part, l&rsquo;affaire su\u00e9doise contre lui a finalement \u00e9t\u00e9 class\u00e9e en raison de l&rsquo;extr\u00eame ridicule des charges retenues contre lui. D&rsquo;autre part, quelque chose s&rsquo;est produit au cours de l&rsquo;\u00e9lection pr\u00e9sidentielle de 2016 aux &Eacute;tats-Unis qui l&rsquo;a plac\u00e9 directement dans le collimateur de certaines personnes exceptionnellement mauvaises.<\/p>\n<\/p>\n<p><p>Sur ses genoux se trouvait le filon principal des preuves que le Comit\u00e9 national d\u00e9mocrate, charg\u00e9 d&rsquo;organiser des \u00e9lections primaires honn\u00eates et transparentes, avait plut\u00f4t conspir\u00e9 pour voler l&rsquo;\u00e9lection \u00e0 Bernie Sanders, enflammant ses partisans et qui parlait devant des stades bond\u00e9s, pour la donner \u00e0 Hillary Clinton, une personne au mauvais caract\u00e8re, criarde, une vieille peau qui pouvait, la plupart du temps, \u00e0 peine remplir une salle de classe sans acheter des gens. Pour moi, choisir entre Sanders, Clinton et Trump, c&rsquo;est comme choisir la couleur des p\u00e9tales de fleurs pour souffler doucement \u00e0 la surface d&rsquo;une fosse d&rsquo;aisance, mais il semble que pour certaines personnes na\u00efves et id\u00e9alistes, la bombe de v\u00e9rit\u00e9 d&rsquo;Assange \u00e9tait une r\u00e9v\u00e9lation : \u00ab\u00a0Quoi ? Hillary serait le diable ? Noooooon !\u00a0\u00bb<em>.<\/em><\/p>\n<\/p>\n<p><p>Assange a publi\u00e9 ces informations et, ce faisant, il est directement entr\u00e9 dans la fosse aux serpents appel\u00e9e la Fondation Clinton, un vaste stratag\u00e8me mondial d&rsquo;escroquerie, de corruption et de blanchiment d&rsquo;argent qui, entre autres choses, fournissait des contrats d&rsquo;armement en \u00e9change de pots-de-vin somptueux offerts par des agents \u00e9trangers. Ses tentacules s&rsquo;\u00e9tendaient \u00e0 toutes les grandes agences f\u00e9d\u00e9rales am\u00e9ricaines, qui avaient \u00e9t\u00e9 approvisionn\u00e9es de partisans de Clinton pendant les deux mandats de Bill Clinton \u00e0 la pr\u00e9sidence. Quand Hillary Clinton a ensuite perdu l&rsquo;\u00e9lection au profit de Donald Trump, entre autres parce que les partisans en col\u00e8re de Sanders ne voulaient pas voter pour elle, comme dans une sorte de guerre civile au ralenti, une guerre civile bureaucratique a \u00e9clat\u00e9 au sein de l&rsquo;establishment de Washington, et Assange a \u00e9t\u00e9 pris dans le feu crois\u00e9.<\/p>\n<\/p>\n<p><p>Les missiles qui ont particip\u00e9 \u00e0 cette guerre transportaient deux types de charges utiles : des missiles bas\u00e9s sur la v\u00e9rit\u00e9 et des missiles bas\u00e9s sur le mensonge. La v\u00e9rit\u00e9 est ce qu&rsquo;avait Assange ; c&rsquo;est une arme puissante, mais elle a deux inconv\u00e9nients majeurs. Premi\u00e8rement, elle est rare et il est difficile de s&rsquo;en procurer. Deuxi\u00e8mement, pour qu&rsquo;elle soit efficace, il faut que les gens la pr\u00e9f\u00e8rent au mensonge. Si la v\u00e9rit\u00e9 est que vous \u00eates impuissants et facilement ignor\u00e9s mais contraints par la force de la propagande de participer p\u00e9riodiquement \u00e0 un carnaval humiliant appel\u00e9 \u00ab\u00a0\u00e9lections nationales\u00a0\u00bb, alors, pour des raisons psychologiques \u00e9videntes, la contre-v\u00e9rit\u00e9 devient votre amie. L&rsquo;inconv\u00e9nient du mensonge est que, lorsqu&rsquo;il est manipul\u00e9 par des menteurs connus, il ne devient pas plus efficace que de jeter des excr\u00e9ments. Cet inconv\u00e9nient peut \u00eatre transform\u00e9 en avantage en rendant suffisamment de gens assez fous pour qu&rsquo;ils aient envie de commencer \u00e0 jeter des excr\u00e9ments eux aussi.<\/p>\n<\/p>\n<p><p>Au cours des ann\u00e9es qui ont suivi, un effort concert\u00e9, organis\u00e9 au plus haut niveau, a \u00e9t\u00e9 fait pour accro&icirc;tre les d\u00e9savantages de la v\u00e9rit\u00e9 et pour diminuer les d\u00e9savantages de la contre-v\u00e9rit\u00e9. Des efforts acharn\u00e9s pour poursuivre les auteurs de fuites, les pirates informatiques et les d\u00e9nonciateurs ont consid\u00e9rablement r\u00e9duit l&rsquo;acc\u00e8s du public \u00e0 la v\u00e9rit\u00e9, donnant aux chercheurs de v\u00e9rit\u00e9 comme Assange beaucoup moins de mat\u00e9riel avec lequel travailler. Les efforts tout aussi acharn\u00e9s des m\u00e9dias de masse am\u00e9ricains pour ignorer la malfaisance de Clinton tout en d\u00e9nigrant sans cesse Trump ont conditionn\u00e9 de nombreux cerveaux politiquement polaris\u00e9s \u00e0 pr\u00e9f\u00e9rer le mensonge \u00e0 la v\u00e9rit\u00e9 si le mensonge aide leur cause perdue alors que la v\u00e9rit\u00e9 lui fait du tort.<\/p>\n<\/p>\n<p><p>La v\u00e9rit\u00e9 qu&rsquo;un initi\u00e9 d\u00e9mocrate furieux et d\u00e9go&ucirc;t\u00e9 ayant un acc\u00e8s physique au serveur a copi\u00e9 des preuves incriminantes sur une cl\u00e9 USB et les a transmises \u00e0 Wikileaks est dommageable. Le mensonge que les \u00ab\u00a0pirates russes\u00a0\u00bb ont r\u00e9ussi \u00e0 pirater sur ce serveur, \u00e0 t\u00e9l\u00e9charger les preuves via une connexion Internet, puis \u00e0 les t\u00e9l\u00e9charger sur Wikileaks afin d&rsquo;obtenir l&rsquo;\u00e9lection de Trump est utile. Quelques poign\u00e9es d&rsquo;hyst\u00e9rie russophobe plus tard, et le r\u00e9cit populaire \u00ab\u00a0Clinton est une escroc ; c&rsquo;est pourquoi elle a perdu\u00a0\u00bb est remplac\u00e9 par le r\u00e9cit populaire \u00ab\u00a0Trump est un pantin russe ; c&rsquo;est pourquoi il a gagn\u00e9\u00a0\u00bb. Pendant ce temps, la machine \u00e0 jeter des excr\u00e9ments n&rsquo;a pas cess\u00e9 de fonctionner, produisant un flot ininterrompu de fausses nouvelles sur l&rsquo;ing\u00e9rence russe, le piratage, l&#8217;empoisonnement et d&rsquo;autres actes qui n&rsquo;ont pas encore \u00e9t\u00e9 invent\u00e9s et qui sont encore plus m\u00e9chants.<\/p>\n<\/p>\n<p><p>En parlant de m\u00e9chancet\u00e9, c&rsquo;est peut-\u00eatre une chose particuli\u00e8rement m\u00e9chante \u00e0 dire pour moi, parce que cela pourrait faire exploser certains cerveaux politiquement polaris\u00e9s, mais je vais quand m\u00eame le dire : La <em>Narrative<\/em>n&rsquo;est pas Tout. Le monde est divis\u00e9 en personnes qui se nourrissent de clics, d&rsquo;opinions, de go&ucirc;ts, d&rsquo;actions, de rediffusions, de notations et d&rsquo;autres b\u00eatises de ce genre ; pour eux, la <em>Narrative<\/em> semble \u00eatre Tout. Apr\u00e8s tout, les gens aiment qu&rsquo;on leur raconte des histoires, et beaucoup de gens simples ne voient pas l&rsquo;int\u00e9r\u00eat de tracer une ligne nette entre la fiction et la non-fiction. Par exemple, que la Bible soit une fiction ou non est une question de croyance et non de fait (les faits existent ind\u00e9pendamment du fait que quelqu&rsquo;un les croit ou non). D&rsquo;autre part, il y a des gens qui sont charg\u00e9s de faire fonctionner le syst\u00e8me, et pour eux la fiction est dangereuse : c&rsquo;est au mieux un chemin d\u00e9tourn\u00e9 qui les \u00e9loigne de bien consid\u00e9rer certains faits importants et les am\u00e8ne \u00e0 donner une importance excessive aux autres, tandis qu&rsquo;un faux r\u00e9cit les \u00e9loigne compl\u00e8tement des faits.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pas parce qu&rsquo;un r\u00e9cit est devenu plus populaire qu&rsquo;un autre qu&rsquo;il a gagn\u00e9 ; cela peut simplement signifier que les gens tristes et fous dont il a infest\u00e9 les esprits ont perdu. Le remplacement du r\u00e9cit populaire\u00a0\u00bbClinton est une escroc ; c&rsquo;est pourquoi elle a perdu\u00a0\u00bb par le r\u00e9cit populaire \u00ab\u00a0Trump est un pantin russe ; c&rsquo;est pourquoi il a gagn\u00e9\u00a0\u00bb n&rsquo;a pas chang\u00e9 la r\u00e9alit\u00e9 sous-jacente. Ce que cela a fait, c&rsquo;est produire une poche de folie f\u00e9cale. Des cliniciens russes en blouse blanche se tiennent pr\u00eats avec des camisoles de force et des seringues de  <a href=\"https:\/\/eurekasante.vidal.fr\/medicaments\/vidal-famille\/medicament-gf700011-LORAZEPAM-MYLAN.html\">loraz\u00e9pam<\/a>  pendant que le reste du monde regarde nerveusement. Tous esp\u00e8rent que cette folie de masse finira par s&rsquo;accomplir sans n\u00e9cessiter d&rsquo;intervention m\u00e9dicale majeure. Pendant ce temps, les habitants de l&rsquo;asile de fous sont obs\u00e9d\u00e9s par la couleur des p\u00e9tales de fleurs \u00e0 r\u00e9pandre sur le cloaque de leur politique nationale en 2020.<\/p>\n<\/p>\n<p><p>Mais revenons \u00e0 Assange : non seulement le monde a chang\u00e9 pendant son isolement cellulaire \u00e0 l&rsquo;ambassade de l&rsquo;&Eacute;quateur, mais lui aussi a chang\u00e9. La superstar qui a prononc\u00e9 des discours passionn\u00e9s depuis le balcon de l&rsquo;ambassade devant une foule excit\u00e9e pouvait \u00e0 peine \u00eatre reconnue dans le vieil homme n\u00e9glig\u00e9 qui a \u00e9t\u00e9 tra&icirc;n\u00e9 sans c\u00e9r\u00e9monie hors de l&rsquo;ambassade et dans un fourgon de police. C&rsquo;\u00e9tait triste \u00e0 voir, et beaucoup de gens sont tr\u00e8s contrari\u00e9s \u00e0 l&rsquo;id\u00e9e que les Britanniques vont maintenant le livrer aux Am\u00e9ricains qui vont le torturer \u00e0 mort. Mais s&rsquo;ils ne le font pas ? Et s&rsquo;ils ne le font pas, est-ce que sept autres ann\u00e9es enferm\u00e9es \u00e0 l&rsquo;ambassade auraient \u00e9t\u00e9 mieux ?<\/p>\n<\/p>\n<p><p>Le pire pour Assange, c&rsquo;est peut-\u00eatre qu&rsquo;il n&rsquo;est plus utile. Wikileaks n&rsquo;a plus besoin de lui depuis que Kristinn Hrafnsson a pris la direction de la r\u00e9daction. Il n&rsquo;est plus utile \u00e0 l&rsquo;&Eacute;quateur, qui en 2012 \u00e9tait dirig\u00e9 par Rafael Correa, un architecte du \u00ab\u00a0nouveau socialisme\u00a0\u00bb et un alli\u00e9 d&rsquo;Hugo Ch&aacute;vez du Venezuela ; mais maintenant Correa a \u00e9t\u00e9 remplac\u00e9 et fait face \u00e0 une pers\u00e9cution alors que Ch&aacute;vez est mort. Alors qu&rsquo;il se trouvait \u00e0 l&rsquo;ambassade, les autorit\u00e9s \u00e9quatoriennes ont syst\u00e9matiquement limit\u00e9 la libert\u00e9 d&rsquo;action d&rsquo;Assange, lui coupant finalement l&rsquo;acc\u00e8s \u00e0 Internet et interdisant les visiteurs, rendant son travail impossible.<\/p>\n<\/p>\n<p><p>Il n&rsquo;est plus utile \u00e0 Trump, dont il a tant fait pour assurer la victoire en faisant conna&icirc;tre au monde la v\u00e9rit\u00e9 sur Hillary et son double visage. Trump, qui a dit &laquo;<em> J&rsquo;aime Wikileaks <\/em>&raquo;, voit maintenant Assange comme un actif toxique : ses opposants vont sans doute essayer d&rsquo;inventer des preuves de collusion entre Assange et lui et, \u00e0 d\u00e9faut, halluciner \u00e0 propos d&rsquo;une&laquo;<em> obstruction \u00e0 la justice <\/em>&raquo;. Du point de vue de Trump, il vaudrait mieux que Assange disparaisse tranquillement. Et bien que les opposants de Trump soient incapables de r\u00e9sister \u00e0 la tentation de pers\u00e9cuter Assange, pour eux, il peut s&rsquo;av\u00e9rer \u00eatre une sorte de calice empoisonn\u00e9, car suffisamment de gens se souviennent d&rsquo;Assange comme le journaliste intr\u00e9pide qui a laiss\u00e9 le monde voir de graves m\u00e9faits au D\u00e9partement d&rsquo;&Eacute;tat am\u00e9ricain et des crimes de guerre au Pentagone, et peuvent prendre la d\u00e9fense de Assange.<\/p>\n<\/p>\n<p><p>Il n&rsquo;est m\u00eame plus utile \u00e0 la Su\u00e8de : les all\u00e9gations de viol port\u00e9es contre lui ont \u00e9t\u00e9 abandonn\u00e9es il y a deux ans. Et on peut se demander si le gouvernement britannique a des motifs l\u00e9gitimes de le d\u00e9tenir ,: il a \u00e9chapp\u00e9 \u00e0 une caution en entrant dans l&rsquo;ambassade \u00e9quatorienne, mais l&rsquo;arrestation et la caution avaient \u00e9t\u00e9 accord\u00e9es en rapport avec la demande d&rsquo;extradition su\u00e9doise, qui n&rsquo;est plus valable, rendant toute l&rsquo;affaire nulle et non avenue. Quant \u00e0 la question de son extradition vers les &Eacute;tats-Unis, le gouvernement \u00e9quatorien a jur\u00e9, de haut en bas, qu&rsquo;il r\u00e9voquait son asile sur la base d&rsquo;une garantie \u00e9crite des Britanniques de ne pas l&rsquo;extrader vers les &Eacute;tats-Unis. C&rsquo;est probablement ce que veut Trump : faire un <em>show<\/em>politique pour faire avancer la cause de la justice sans rien faire.<\/p>\n<\/p>\n<p><p>De ce point de vue, la lib\u00e9ration d&rsquo;Assange de l&rsquo;ambassade \u00e9quatorienne et son incarc\u00e9ration dans une prison britannique pour violation de la libert\u00e9 sous caution pour un motif d&rsquo;arrestation pour lequel il n&rsquo;a pas \u00e9t\u00e9 reconnu coupable depuis, commence \u00e0 ressembler \u00e0 un succ\u00e8s majeur. Il est une fois de plus sous les feux de la rampe, avec de nombreux supporteurs dans le monde entier. Si tout se passe bien, il sera lib\u00e9r\u00e9 et redeviendra une personnalit\u00e9 m\u00e9diatique de grande envergure. Et si tout va mal et que les Am\u00e9ricains mettent la main sur lui et le torturent \u00e0 mort, il mourra en martyr et vivra \u00e0 jamais dans la m\u00e9moire publique.<\/p>\n<\/p>\n<p><p>Je ne sais pas si Assange a \u00e9t\u00e9 baptis\u00e9, mais un bon choix de saint pour lui serait saint Julien d&rsquo;Antioche, qui a \u00e9t\u00e9 martyris\u00e9 pendant la pers\u00e9cution des chr\u00e9tiens par l&#8217;empereur  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Diocl%C3%A9tien\">Diocl\u00e9tien<\/a>  entre 303 et 313 apr\u00e8s J.C. Saint Julien a \u00e9t\u00e9 mis dans un sac rempli de sable, de vip\u00e8res et de scorpions et jet\u00e9 \u00e0 la mer. L&rsquo;initiative de Diocl\u00e9tien fut un \u00e9chec : le fils d&rsquo;un de ses lieutenants, Constantin, non seulement annula la pers\u00e9cution des chr\u00e9tiens, mais fit du christianisme la religion de l&rsquo;Empire romain. Il en transf\u00e9ra ensuite la capitale vers la Nouvelle Rome (Constantinople), abandonnant la Vieille Rome et la laissant languir dans un \u00e2ge des t\u00e9n\u00e8bres alors que sa Nouvelle Rome dura mille ans de gloire.<\/p>\n<\/p>\n<p><p>Si Julian Assange devait finir martyris\u00e9 par les Am\u00e9ricains, on peut s&rsquo;attendre \u00e0 un r\u00e9sultat vaguement similaire : les g\u00e9n\u00e9rations futures d&rsquo;Am\u00e9ricains diront : \u00ab\u00a0Il \u00e9tait une fois un grand journaliste du nom de Julian. Il est mort en martyr pour la v\u00e9rit\u00e9. C&rsquo;\u00e9tait il y a longtemps, et nous ne savons pas ce qui nous est arriv\u00e9 depuis, parce que tout ce que nous avons entendu depuis, ce ne sont que des mensonges&hellip;\u00a0\u00bb <\/p>\n<\/p>\n<p><p>(Le 23 avril 2019, <a href=\"http:\/\/cluborlov.blogspot.com\/2019\/04\/the-martyrdom-of-st-julian.html\">Club Orlov<\/a>, &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/le-martyre-de-saint-julian\">Sakerfrancophone<\/a><\/em>.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le martyre de Saint-Julian La nouvelle de l&rsquo;arrestation et de l&#8217;emprisonnement de Julian Assange vous est probablement parvenue, mais, au cas o&ugrave;, voici un r\u00e9sum\u00e9. Julian Assange est un journaliste australien ; en tant que tel, il est un g\u00e9ant imposant parmi un petit groupe de nains. Googlez \u00ab\u00a0grands journalistes australiens\u00ab\u00a0et vous obtenez son nom&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[934,6193,3278,2668,2639,12538,9887],"class_list":["post-78608","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-clinton","tag-equateur","tag-hillary","tag-orlov","tag-trump","tag-usa-2016","tag-wikileaks"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78608"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78608\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}