{"id":78612,"date":"2019-05-04T08:11:10","date_gmt":"2019-05-04T08:11:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/04\/notes-sur-lebullshit-venezuela\/"},"modified":"2019-05-04T08:11:10","modified_gmt":"2019-05-04T08:11:10","slug":"notes-sur-lebullshit-venezuela","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/04\/notes-sur-lebullshit-venezuela\/","title":{"rendered":"Notes sur le\u00a0<em>bullshit-<\/em>Venezuela"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur le <em>bullshit-<\/em>Venezuela<\/h2>\n<\/p>\n<p><p>4 mai 2019 &ndash; Le Venezuela et sa crise sont une com\u00e9die et un catalogue des erreurs que produisent les USA dans cette sorte d&rsquo;entreprise. L&rsquo;ensemble est r\u00e9v\u00e9lateur de l&rsquo;\u00e9tat tr\u00e8s alarmant de l&#8217;empire et de l&rsquo;extraordinaire constance de Washington D.C. \/\u00a0\u00bbD.C.-la folle\u00a0\u00bb dans la multiplication de ses propres d\u00e9boires caus\u00e9s par elle-M\u00eame. Nous voyons dans quel contexte se d\u00e9veloppent ces erreurs, avant d&rsquo;en venir \u00e0 elles&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>Outre d&rsquo;\u00eatre ce que l&rsquo;on d\u00e9crit quotidiennement, cette caricature d&rsquo;&Eacute;tat-bouffe en cours est en cours d&rsquo;effondrement et parce qu&rsquo;il est cela, les USA <strong>accumulent d&rsquo;extraordinaires erreurs et causent d&rsquo;\u00e9normes d\u00e9g\u00e2ts \u00e0 leur propre parti vis-\u00e0-vis du Venezuela<\/strong>. Cela, d&rsquo;autant plus extraordinaire et important pour le cours des \u00e9v\u00e9nements que <strong>ce pays (le Venezuela) est dans leur \u00ab\u00a0arri\u00e8re-cour\u00a0\u00bb<\/strong>, limitrophe d&rsquo;eux-m\u00eames et leur \u00ab\u00a0chasse gard\u00e9e\u00a0\u00bb depuis Monroe, et qu&rsquo;il <strong>\u00e9chappe pourtant totalement au contr\u00f4le de l&rsquo;ersatz d'\u00a0\u00bbempire\u00a0\u00bb qu&rsquo;ils sont, \u00e0 la d\u00e9rive<\/strong>. L&rsquo;int\u00e9grit\u00e9 de l&rsquo;Empire est totalement mise en cause dans la plus compl\u00e8te irresponsabilit\u00e9, dans l&rsquo;aveuglement et la b\u00eatise au front de taureau (Pompeo) ou de taurillon-moustachu (Bolton).<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Du Venezuela au Syst\u00e8me et retour<\/h3>\n<\/p>\n<p><p>Malgr\u00e9 les graves et savantes analyses des antiSyst\u00e8me qui ne vivent que dans l&rsquo;adoration de la puissance du Syst\u00e8me qui les met plus bas que tout et leur adoration d&rsquo;en-dessous les poussant \u00e0 r\u00e9affirmer sans cesse l&rsquo;invincibilit\u00e9 de la puissance dudit Syst\u00e8me, nous parlons, nous, des USA, c&rsquo;est-\u00e0-dire de la principale courroie de transmission du Syst\u00e8me, <strong>comme \u00e9tant \u00ab\u00a0en cours d&rsquo;effondrement\u00a0\u00bb<\/strong>. Cela rencontre absolument <strong>notre analyse, sans la moindre r\u00e9serve, de l&rsquo;effondrement en cours du Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>(Nous fixons la toute-puissance achev\u00e9e du Syst\u00e8me \u00e0 l&rsquo;\u00e9poque o&ugrave; il n&rsquo;\u00e9tait pas encore question du Syst\u00e8me sans le langage-courant, dans les ann\u00e9es 1950-1990, lorsque finalement personne ne mesurait vraiment l&rsquo;ampleur et l&#8217;empire achev\u00e9s de cette puissance. Depuis, le Syst\u00e8me est en cours d&rsquo;effondrement selon l&rsquo;\u00e9quation surpuissance-autodestruction et son horreur, sa tyrannie, apparaissent au grand jour d\u00e8s lors qu&rsquo;il se montre vuln\u00e9rable \u00e0 la contestation.) <\/p>\n<\/p>\n<p><p>Les cons\u00e9quences de cet effondrement en cours sont excellemment d\u00e9fini par <a href=\"http:\/\/www.dedefensa.org\/article\/la-sequence-dauto-destruction\">Orlov<\/a> et nous tendrions \u00e9videmment \u00e0 les faire n\u00f4tres : &laquo; <em>Comment savoir si la s\u00e9quence d&rsquo;autodestruction a \u00e9t\u00e9 d\u00e9clench\u00e9e ? Il y a deux signes r\u00e9v\u00e9lateurs. La premi\u00e8re est qu&rsquo;il existe une reconnaissance et une acceptation communes du fait qu&rsquo;il faut faire quelque chose pour \u00e9viter l&rsquo;effondrement. La perestro\u00efka de Gorbatchev et le \u00ab\u00a0Make America Great Again\u00a0\u00bb de Trump sont deux signes de d\u00e9sespoir. <strong>La seconde est que chaque tentative de pr\u00e9venir ou de retarder l&rsquo;effondrement nous en rapproche<\/strong>, chaque perturbation augmente le d\u00e9sordre et la port\u00e9e de l&rsquo;action productive se r\u00e9duit \u00e0 presque rien<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0&Ocirc; miroir, dis-moi&hellip;\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>La deuxi\u00e8me cause expos\u00e9e par Orlov d\u00e9finit assez bien l&rsquo;aventure du Venezuela, qui institue une sorte de spasmes du type auxquels l&rsquo;Empire nous a habitu\u00e9s ces derni\u00e8res ann\u00e9es pour pouvoir continuer \u00e0 se dire, se contemplant dans le miroir : \u00ab\u00a0<strong>&Ocirc; miroir, dis-moi<\/strong> que je suis toujours le plus puissant et le plus invincible sur cette plan\u00e8te qui est mon bien et ma chose \u00e0 la fois\u00a0\u00bb. Pour nous, <strong>cette pri\u00e8re passionn\u00e9e est de l&rsquo;ordre de l&rsquo;inconscient chez tous ces faibles psychologies des dirigeants<\/strong>, mang\u00e9es par des inconscients nourris aux vitamines et aux st\u00e9ro\u00efdes des slogans de <em>l&rsquo;hybris <\/em>manufactur\u00e9 <em>Made In USA.<\/em><\/p>\n<\/p>\n<p><p>En effet, l&rsquo;attaque contre le Venezuela, outre les excellentes raisons qui sont r\u00e9guli\u00e8rement avanc\u00e9es (prise en main du p\u00e9trole, attaque contre le socialisme, etc.), s&rsquo;impose <strong>aussi et d&rsquo;abord selon nous<\/strong> <strong>comme une tentative d&rsquo;affirmation<\/strong> de l&rsquo;incontestabilit\u00e9 de la puissance h\u00e9g\u00e9monique des USA, et cette puissance h\u00e9g\u00e9monique <strong>encore plus, bien plus, dans la \u00ab\u00a0sph\u00e8re Monroe\u00a0\u00bb de son arri\u00e8re-cour<\/strong>. La bouffonnerie des erreurs et des maladresses ce cessant de renforcer l&rsquo;adversaire, encore plus que l&rsquo;\u00e9chec qui a marqu\u00e9 les 3-4 premiers mois de cette aventure, depuis janvier 2019,  justifie ais\u00e9ment l&rsquo;argument de cette \u00ab\u00a0deuxi\u00e8me cause\u00a0\u00bb de l&rsquo;effondrement expos\u00e9e par Orlov : &laquo; <em>chaque tentative de pr\u00e9venir ou de retarder l&rsquo;effondrement nous en rapproche, chaque perturbation augmente le d\u00e9sordre et la port\u00e9e de l&rsquo;action productive se r\u00e9duit \u00e0 presque rien<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;action offensive contre le Venezuela, pr\u00e9sent\u00e9e comme irr\u00e9sistible et triomphante, <strong>n&rsquo;a pour effet exclusif qu&rsquo;un affaiblissement suppl\u00e9mentaire du statut, du s\u00e9rieux, de la consid\u00e9ration dont disposent les USA<\/strong>. C&rsquo;est l&rsquo;acte d&rsquo;un imb\u00e9cile, d&rsquo;un somnambule, d&rsquo;un drogu\u00e9, d&rsquo;un maniaco-d\u00e9pressif en phase maniaque, d&rsquo;un ivrogne cuit et recuit faisant la le\u00e7on des vertus civiques au caniveau o&ugrave; il a roul\u00e9&hellip; Ainsi sont-ce aujourd&rsquo;hui les remarques et les expressions qui sont d&rsquo;usage dans le grave domaine des relations internationales pour qualifier le comportement des USA.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La gueule de l&#8217;emploi<\/h3>\n<\/p>\n<p><p>Comme nous avons introduit cette analyse par l&rsquo;affirmation de l&rsquo;accumulation des \u00ab\u00a0extraordinaires erreurs\u00a0\u00bb des USA et de leurs effets, promettant de nous y attacher parce qu&rsquo;ainsi on en jugera mieux de l&rsquo;action des USA, choisissons l&rsquo;analyse d&rsquo;une premi\u00e8re erreur (arbitrairement choisie, mais sans importance puisque sans qualification de gravit\u00e9 ou chronologique), &ndash; <strong>le choix de Guaido comme marionnette de l&rsquo;entreprise<\/strong>.<\/p>\n<\/p>\n<p><p><strong>Ce choix est sans aucun doute tr\u00e8s largement pire que le choix catastrophique fameux <\/strong>que les USA firent, pour un plan assez similaire dans l&rsquo;esprit de <em>regime change<\/em>, d&rsquo;un <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ahmed_Chalabi\">Ahmed Chalabi<\/a> comme conseiller principal de l&rsquo;attaque de l&rsquo;Irak en 2003, premi\u00e8re source de renseignement des divers services US \u00e0 commencer par Cheney et sa clique-cravat\u00e9e, peut-\u00eatre successeur de Saddam dans les intentions de l&rsquo;immanquable triomphe am\u00e9ricain. Guaido est compl\u00e8tement un nouveau-venu sur la sc\u00e8ne m\u00e9diatique et de la communication, un jeune ambitieux sans autre envergure que la circonstance, qui croit avoir trouv\u00e9 avec la CIA la poule aux &oelig;ufs d&rsquo;or. Guaido pourrait \u00eatre <strong>un de ces innombrables morpions ukrainiens que v\u00e9hiculent les services de subversion US et leurs serviettes bourr\u00e9es de dollars<\/strong>. <\/p>\n<\/p>\n<p><p>Il n&rsquo;a pas de r\u00e9seaux politiques, aucun appui populaire, il manque totalement de charisme tant il se force \u00e0 tenter de jouer le leader charismatique. Le choix de Guaido montre bien que <strong>l&rsquo;intelligence politique et psychologique<\/strong> des organismes disons du <em>DeepState <\/em>est compl\u00e8tement r\u00e9duite \u00e0 n\u00e9ant par <strong>le d\u00e9sordre interne et la corruption \u00e9rig\u00e9s en \u00ab\u00a0essence\u00a0\u00bb supra-\u00e9tatique du syst\u00e8me de l&rsquo;am\u00e9ricanisme<\/strong>, accumulant les d\u00e9cisions et les actes qui aggravent la situation am\u00e9ricaniste (aux USA, dans la substance et la structure m\u00eame de l&rsquo;Empire).<\/p>\n<\/p>\n<p><p>&Eacute;tait-il difficile de comprendre tout ce que nous avan\u00e7ons \u00e0 propos de Guaido ? Nous r\u00e9pondrons par le \u00ab\u00a0d\u00e9lit de faci\u00e8s\u00a0\u00bb, si vigoureusement d\u00e9nonc\u00e9 par nos vigiles et gardes du corps de la vertu et de la bienpensance, admis cette fois comme apport intuitif. <strong>Guaido a la gueule, non pas de l&#8217;emploi, mais du Rien qu&rsquo;il est<\/strong> : arrogant \u00e0 propos de rien, parlant comme un perroquet, puant la corruption de petite main et des petits matins, d\u00e9magogue \u00e0 la petite semaine, sans la moindre once de sinc\u00e9rit\u00e9 pour la seule raison qu&rsquo;il ignore, ni le sens ni l&rsquo;existence de ce mot pour lui \u00e9trange et barbare. On comprend que Macron &#038; sa bande <strong>n&rsquo;aient pas h\u00e9sit\u00e9 une seconde \u00e0 le reconna&icirc;tre pr\u00e9sident \u00ab\u00a0par int\u00e9rim\u00a0\u00bb et par <em>e-mail<\/em><\/strong> du Venezuela : on se reconna&icirc;t quand on est issus des m\u00eames caniveaux.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le choix des Russes<\/h3>\n<\/p>\n<p><p>Une deuxi\u00e8me erreur des am\u00e9ricanistes est d\u00e9sormais d&rsquo;une tournure classique : <strong>leur sid\u00e9rante incompr\u00e9hension du comportement des Russes<\/strong>(et des Chinois, souvent en \u00ab\u00a0second rideau\u00a0\u00bb). L&rsquo;analyse US est toujours fausse : autant ils ont encombr\u00e9 la crise de 2014 de nombreuses et exotiques <em>FakeNews<\/em> et affirm\u00e9 jusqu&rsquo;\u00e0 cr\u00e9er pour eux-m\u00eames l&rsquo;\u00e9norme simulacre de  <a href=\"http:\/\/www.dedefensa.org\/article\/le-renseignement-francais-et-lukraine\">l&rsquo;invasion russe<\/a> de l&rsquo;Ukraine (<a href=\"http:\/\/www.dedefensa.org\/article\/heroique-ukraine-36-invasions-russes-en-9-mois\">36 en 9 mois<\/a>) qui n&rsquo;a jamais eu lieu ; autant ils ont cr\u00e9\u00e9 de toutes pi\u00e8ces un <em>Russiagate <\/em>de fameuse m\u00e9moire, simulacre qui fit danser \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb toute la presseSyst\u00e8me et bienpensante pendant trois ans pour d\u00e9boucher sur du n\u00e9ant. Par contre, toujours dans le registre des <em>Fake<\/em>Prospectives, les brillants services US n&rsquo;ont rien vu venir des Russes, ni en Crim\u00e9e, ni en Syrie, ni au Venezuela.<\/p>\n<\/p>\n<p><p>&hellip; Au Venezuela justement. Les premi\u00e8res <strong>\u00ab\u00a0incursions\u00a0\u00bb russes s\u00e9rieuses (c&rsquo;est-\u00e0-dire strat\u00e9giques)<\/strong>, avec un Tu-160 en visite amicale \u00e0 Caracas, accompagn\u00e9 de bruits de la location d&rsquo;un site au Venezuela pour une base a\u00e9rienne et navale russe \u00e0 proximit\u00e9 des USA, &ndash; riposte asym\u00e9trique aux projets US de d\u00e9ploiement en Europe de missiles \u00e0 moyenne port\u00e9e et t\u00eates nucl\u00e9aires apr\u00e8s la sortie des USA du trait\u00e9 FNI. Ces suppos\u00e9s projets russes impliquaient l&rsquo;avantage pour le Venezuela de disposer d&rsquo;une d\u00e9fense indirecte mais solide face \u00e0 une \u00e9ventuelle agression russe dont on parlait d\u00e9j\u00e0 abondamment&hellip; Cela \u00e9tait r\u00e9sum\u00e9 dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article\/tu-160-au-venezuela-la-russie-se-prepare-au-conflit\">11 d\u00e9cembre 2018<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; <em>La visite (techniquement pour des \u00ab\u00a0<a href=\"https:\/\/francais.rt.com\/international\/56593-venezuela-avions-russes-arrivent-caracas-manoeuvres-militaires-conjointes\">manoeuvres conjointes<\/a>\u00ab\u00a0) des Russes suit un voyage du pr\u00e9sident Maduros \u00e0 Moscou il y a quelques semaines. La Russie a effectu\u00e9 des vols similaires au Venezuela en 2008 et en 2013, <strong>mais les conditions internationales sont aujourd&rsquo;hui radicalement diff\u00e9rentes<\/strong>. Alors que les Russes parlent avec leur habituelle prudence d&rsquo;une \u00ab\u00a0visite d&rsquo;amiti\u00e9 conformes aux normes internationales,\u00a0\u00bb les V\u00e9n\u00e9zu\u00e9liens sont autrement explicites, y voyant une affirmation des Russes d&rsquo;aider le Venezuela \u00e0 maintenir sa s\u00e9curit\u00e9 contre toute tentative d&rsquo;agression, et essentiellement bien entendu les agressions directes ou indirectes des USA. Au-del\u00e0 et plus essentiellement, il n&rsquo;est nullement impossible que cette visite amorce des n\u00e9gociations pour <strong>le stationnement \u00e9pisodique sinon permanent d&rsquo;un d\u00e9tachement de forces strat\u00e9giques russes dans le pays<\/strong>, et ce serait une force offensive directement \u00e9quip\u00e9e pour <strong>une attaque contre les USA<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;administration Trump, Bolton en t\u00eate, a \u00e9t\u00e9 compl\u00e8tement prise de cours par cet avant-propos russe \u00e0 la crise v\u00e9n\u00e9zu\u00e9lienne actuelle, et les suppos\u00e9s-projets russes ont certainement pes\u00e9 dans la d\u00e9cision de lancer un coup contre Maduro, pour \u00e9liminer tout risque de base russe dans la r\u00e9gion. C&rsquo;est le contraire qu&rsquo;ils ont obtenu : leur(s) \u00ab\u00a0coup(s)\u00a0\u00bb foireux a (ont) d\u00e9bouch\u00e9 s&rsquo;il(s) n&rsquo;a (ont) m\u00eame \u00e9t\u00e9 accompagn\u00e9(s), voire pr\u00e9c\u00e9d\u00e9(s), <strong>du d\u00e9ploiement de d\u00e9tachements sp\u00e9cialis\u00e9s russes au Venezuela<\/strong>. Ce sont bien les Russes qui ont fait cesser les attaques contre le syst\u00e8me d&rsquo;alimentation en \u00e9lectricit\u00e9 du Venezuela, et qui ont mis \u00e0 niveau la d\u00e9fense anti-a\u00e9rienne dot\u00e9e de S-300, conduisant \u00e0 la d\u00e9cision US d&rsquo;avant-hier d&rsquo;interdire tout survol ou vol \u00e0 proximit\u00e9 du Venezuela d&rsquo;avions pour ne pas risquer de destruction.<\/p>\n<\/p>\n<p><p>Dans toutes ces agitations, les Chinois, qui ont d&rsquo;\u00e9normes int\u00e9r\u00eats \u00e9conomiques dans la r\u00e9gion (les Russes ont des int\u00e9r\u00eats strat\u00e9giques mais aussi \u00e9conomiques), sont derri\u00e8re les Russes. Le r\u00e9sultat de la crise v\u00e9n\u00e9zu\u00e9lienne est donc pour l&rsquo;instant, <strong>du point de vue strat\u00e9gique, une discr\u00e8te mise en place d&rsquo;un important dispositif strat\u00e9gique russe, ou russo-chinois, au Venezuela<\/strong>. C&rsquo;est-\u00e0-dire que les plans \u00e9voqu\u00e9s d&rsquo;une base strat\u00e9gique russe dans le pays, pourraient se transmuter <strong>en une pr\u00e9sence strat\u00e9gique extr\u00eamement significative<\/strong>, si les USA ne parviennent pas \u00e0 \u00e9liminer Maduro et \u00e0 mettre Guaido, &ndash; ou une autre marionnette si Guaido est \u00e9limin\u00e9 par la CIA comme <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-la-longue-vue-de-poutine\">certains<\/a> le <a href=\"http:\/\/www.dedefensa.org\/article\/tourbillon-crisique-et-aveuglement-us\">sugg\u00e8rent<\/a>, &ndash; \u00e0 la t\u00eate d&rsquo;un nouveau r\u00e9gime.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Peuvent-ils esp\u00e9rer encore y parvenir ? <\/h3>\n<\/p>\n<p><p>On conna&icirc;t la situation au Venezuela apr\u00e8s ce qui s&rsquo;av\u00e8re \u00eatre la troisi\u00e8me tentative de coup d&rsquo;&Eacute;tat suscit\u00e9s par les USA. Le site <em>The MoonofAlabama <\/em>(MoA) est \u00e0 cet \u00e9gard le meilleur producteur d&rsquo;informations pour suivre cette \u00e9volution, notamment en fournissant les meilleures donn\u00e9es possibles quant \u00e0 l&rsquo;\u00e9valuation de la qualit\u00e9 et de la pertinence des sources cit\u00e9es, quels que soient leurs partis et leurs orientations : MoA sait d\u00e9nicher ce qui est proche de la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>, m\u00eame chez ses adversaires&hellip;. <\/p>\n<\/p>\n<p><p>Le <em>Sakerfrancophone <\/em>a pris temporairement l&rsquo;heureuse initiative de traduire au jour le jour pour la p\u00e9riode les derniers articles de MoA. On lira notamment le texte du 2-3 mai 2019, <a href=\"https:\/\/www.moonofalabama.org\/2019\/05\/venezuela-coup-failure-necessitates-a-new-policy-bolton-the-stache-is-pushing-for-war-.html#more\">MoA<\/a> traduit par le  <em><a href=\"https:\/\/lesakerfrancophone.fr\/venezuela-bolton-joue-le-va-t-en-guerre\">Sakerfrancophone<\/a><\/em>, avec ce passage qui, pour r\u00e9sumer certains aspects essentiels de la situation, cite une autre source, <em>Associated Press <\/em>avec notamment le journaliste Matt Lee c\u00e9l\u00e8bre pour ses questions tr\u00e8s impertinentes face au porte-parole du d\u00e9partement d&rsquo;&Eacute;tat :<\/p>\n<\/p>\n<p><p>&laquo; <em>Matt Lee et Ben Fox de l&rsquo;Associated Press ont un <a href=\"https:\/\/apnews.com\/efee26c91e0d418fa04da5f981c7d737\">point de vue<\/a> similaire<\/em> :<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0<strong>Pour la troisi\u00e8me fois de l&rsquo;ann\u00e9e, ce qui devait \u00eatre une nouvelle aube pour le Venezuela a tourn\u00e9 au fiasco<\/strong><\/em><strong>.<\/strong><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Les responsables de l&rsquo;administration Trump s&rsquo;attendaient \u00e0 ce que mercredi soit le d\u00e9but de la fin pour le pr\u00e9sident Nicolas Maduro, les hauts responsables du gouvernement lui ayant retir\u00e9 leur soutien et l&rsquo;opposition ayant lanc\u00e9 un soul\u00e8vement de masse appuy\u00e9 par les militaires<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0<strong>Du moins, c&rsquo;est ce que l&rsquo;administration avait \u00e9t\u00e9 amen\u00e9e \u00e0 croire<\/strong><\/em><strong>.<\/strong><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Mais les d\u00e9fections promises n&rsquo;ont pas eu lieu, le soul\u00e8vement militaire ne s&rsquo;est jamais concr\u00e9tis\u00e9 et Maduro semble toujours \u00eatre fermement aux commandes de la nation sud-am\u00e9ricaine. Les responsables de Trump se plaignent \u00e0 nouveau du soutien que le Venezuela re\u00e7oit de Cuba et de la Russie tout en \u00e9mettant de vagues menaces d&rsquo;action militaire.\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Ce passage r\u00e9sume ce qui finit par apparaitre <strong>comme une extraordinaire na\u00efvet\u00e9 et un amateurisme \u00e9difiant  de la part de la direction washingtonienne<\/strong>, n\u00e9s \u00e0 la fois de l&rsquo;arrogance, de l&rsquo;<em>hybris <\/em>et de l&rsquo;aveuglement, poussant ces dirigeants de la s\u00e9curit\u00e9 nationale US \u00e0 prendre pour du comptant toutes les affirmations de Guaido. C&rsquo;est <strong>un \u00e9trange mais tr\u00e8s conforme \u00e0 l&rsquo;\u00e9poque \u00e9change de simulacres qui r\u00e9sume bien la rocambolesque aventure du Venezuela<\/strong> : le simulacre de Guaido promettant des conditions irr\u00e9sistibles pour plaire \u00e0 ses patrons-commanditaires, le sim&ugrave;ulacre des patrons-commanditaires qui ne peuvent concevoir une seconde de s&rsquo;\u00eatre tromp\u00e9 de marionnette et acceptent aveugl\u00e9ment, sinon avec enthousiasme, tous ses bobards. <\/p>\n<\/p>\n<p><p>(Jusqu&rsquo;au jour o&ugrave;, comme vu plus haut, un service de la CIA prendra ombrage de ces \u00e9checs et ordonnera la liquidation du Guaido pour inventaire solde de tous comptes, et parall\u00e8lement recherche d&rsquo;une autre marionnette pour encore plus de catastrophiques initiatives&hellip;)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Option \u00ab\u00a0sur la table\u00a0\u00bb, <em>as usual<\/em><\/h3>\n<\/p>\n<p><p>On ajoutera que les \u00ab\u00a0alli\u00e9s\u00a0\u00bb des USA autour du Venezuela, Br\u00e9siliens compris qui ont fait beaucoup de tintamarre au d\u00e9but, ne se sont nullement empress\u00e9s pour entrer dans la danse d&rsquo;une fa\u00e7on s\u00e9rieuse. Il resterait donc, dit-on et fait dire \u00e0 Trump plut\u00f4t <em>mezzo voce<\/em>, mais <strong><em>fortissimo <\/em>comme il se doit pour le cas Bolton<\/strong>, qu&rsquo;on travaille d\u00e9sormais \u00e0 l&rsquo;option militaire directe des USA, &ndash; cette fameuse \u00ab\u00a0<strong>option\u00a0\u00bb qui ne cesse de rester \u00ab\u00a0sur la table\u00a0\u00bb<\/strong>&#8230; En effet, Bolton est de loin le principal meneur de jeu en faveur d&rsquo;une intervention et \u00e0 la t\u00eate de l&rsquo;op\u00e9ration, avec un Pompeo largement suiviste dans cette surench\u00e8re. <\/p>\n<\/p>\n<p><p>Le Pentagone, lui dont parle fort peu, est une force de freinage qui n&rsquo;est pas sans effets. Le d\u00e9partement de la d\u00e9fense est sans t\u00eate v\u00e9ritable mais avec un Shanahan \u00ab\u00a0faisant fonction\u00a0\u00bb de ministre qui s&rsquo;appuie et d\u00e9pend \u00e0 la fois de ces puissances que sont la bureaucratie et les militaires ; mais cette faiblesse structurelle devient une force dans la mesure o&ugrave;, cette fois, toutes les tendances sont r\u00e9unies dans une opposition \u00e0 l&rsquo;aventure v\u00e9n\u00e9zu\u00e9lienne. Tous sont conscients que l&rsquo;appareil militaire risquerait d&rsquo;y laisser quelques belles et riches plumes suppl\u00e9mentaires et de <strong>se trouver embourb\u00e9 dans une guerre sans fin avec des moyens de plus en plus limit\u00e9es <\/strong>jusqu&rsquo;\u00e0 cr\u00e9er ici ou l\u00e0 dans d&rsquo;autres zones de tr\u00e8s graves vides strat\u00e9giques. <\/p>\n<\/p>\n<p><p>Certains jugent en effet qu&rsquo;il y a l\u00e0 <strong>un risque de d\u00e9structuration g\u00e9n\u00e9rale du syst\u00e8me strat\u00e9gique de bases et d&rsquo;engagements du Pentagone dans le monde<\/strong> \u00e0 un moment d&rsquo;affaiblissement g\u00e9n\u00e9ral des forces. Certes, une intervention au Venezuela y contribuerait gravement, avec les effectifs n\u00e9cessaires, une issue incertaine <strong>face \u00e0 une arm\u00e9e v\u00e9n\u00e9zu\u00e9lienne tr\u00e8s fortement motiv\u00e9e par son \u00ab\u00a0chavisme\u00a0\u00bb militant et antiam\u00e9ricaniste<\/strong>, en plus d&rsquo;un risque catastrophique de d\u00e9stabilisation g\u00e9n\u00e9rale de la r\u00e9gion avec les cons\u00e9quences qu&rsquo;on imagine. <\/p>\n<\/p>\n<blockquote>\n<p><p>Il s&rsquo;agit notamment, selon les calculs enthousiasmants des planificateurs du Pentagone, de <strong>la possibilit\u00e9 d&rsquo;un flux du 8 \u00e0 10 millions<\/strong> de r\u00e9fugi\u00e9s vers le Nord, <strong>d\u00e9stabilisant totalement le Mexique<\/strong> et exer\u00e7ant une pression semblable \u00e0 une <strong>quasi-guerre d&rsquo;invasion sur la fronti\u00e8re US<\/strong>&hellip; Il faudra l&rsquo;arm\u00e9e US au plus haut de sa force, &ndash; et o&ugrave; donc la trouvera-t-on, elle qui est <strong>dispers\u00e9e dans le monde et qui serait verrouill\u00e9e dans le bourbier du Venezuela<\/strong> ?<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Qu&rsquo;on ne s&rsquo;y trompe pas : de telles conditions, la <strong>rupture viendrait tr\u00e8s vite<\/strong> et toucherait <strong>la situation int\u00e9rieure US<\/strong> qui reste en \u00e9tat d&rsquo;effervescence avec les haines en cours, l&rsquo;hostilit\u00e9 contre Trump, les folies des progressistes-soci\u00e9taux partisans de \u00ab\u00a0fronti\u00e8res ouvertes\u00a0\u00bb et ainsi de suite. <strong>L&rsquo;arm\u00e9e US serait m\u00eame n\u00e9cessaire pour maintenir la coh\u00e9sion int\u00e9rieure et emp\u00eacher la guerre civile aux USA <\/strong>; mais ne serait-elle pas au Venezuela ?! Mais si les USA ne font rien, acceptent l&rsquo;\u00e9chec et les Russes dans la place, quel revers strat\u00e9gique&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Situation g\u00e9n\u00e9rale<\/h3>\n<\/p>\n<p><p>Sans surprise excessive pour cette \u00e9volution, nous continuons \u00e0 assister avec le Venezuela \u00e0 un processus qui, r\u00e9duit \u00e0 lui-m\u00eame, est au contraire compl\u00e8tement stup\u00e9fiant. Il s&rsquo;agit du spectacle de la fa\u00e7on dont <strong>les USA se sont encercl\u00e9s eux-m\u00eames dans leur soi-disant forteresse<\/strong>en tentant de porter les remparts de cette forteresse, d&rsquo;une mani\u00e8re paradoxalement offensives (et aussi ill\u00e9gale, ill\u00e9gitime, cruelle, etc.), vers ces pays de l&rsquo;arri\u00e8re-cour.<\/p>\n<\/p>\n<p><p>(On laisse de c\u00f4t\u00e9, par piti\u00e9, les habituelles causes pseudo-strat\u00e9giques et autres dont on nous saoule depuis des ann\u00e9es sinon des d\u00e9cennies, sur le mode complotistes certifi\u00e9 sinon authentifi\u00e9. Oui, le Venezuela a du p\u00e9trole, mais ce genre de choses ne suffit plus, &ndash; le comprendra-t-on finalement ? &ndash; \u00e0 expliquer les extraordinaires catastrophes qui se succ\u00e8dent.)<\/p>\n<\/p>\n<p><p>Donc, en attaquant avec une bombastique assurance, comme doit faire un empire, Washington D.C. alias-\u00ab\u00a0D.C.-la-folle\u00a0\u00bb s&rsquo;est un peu plus cadenass\u00e9 dans un encerclement para&icirc;t-il s\u00e9curitaire, <strong>et pourtant propice \u00e0 l&rsquo;installation de la puissance strat\u00e9gique russe \u00e0 bonne port\u00e9e de frappe courte<\/strong>, &ndash; le paradoxe superbe de la forteresse s\u00e9curitaire affirmant son h\u00e9g\u00e9monie sur le monde, de plus en plus enferm\u00e9e dans ses n\u00e9cessit\u00e9s op\u00e9rationnelles, &ndash; par les Russes, les terribles et horribles Russes. (Aussi avec les Chinois \u00e9nigmatiques, r\u00e9p\u00e9tons-le, en \u00ab\u00a0second rideau\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>Cette fois, les Russes, qui n&rsquo;avaient rien pr\u00e9par\u00e9 ni envisag\u00e9 de s\u00e9rieux et de structur\u00e9, <strong>se trouvent eux aussi pris dans la logique de la situation v\u00e9n\u00e9zu\u00e9lienne<\/strong>. Ils ont pris en main la responsabilit\u00e9 de la protection du r\u00e9gime Maduro, exactement comme <strong>il prot\u00e9gerait leur propre r\u00e9gime contre une op\u00e9ration de <em>regime chang<\/em><\/strong><em>e<\/em>. Ce sont des choses avec lesquelles on ne plaisante plus du tout, puisque la sottise US a \u00e9t\u00e9 jusqu&rsquo;\u00e0 leur donner excellent argument pour cela.<\/p>\n<\/p>\n<p><p>Nous relisons un passage de notre texte du  <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-la-longue-vue-de-poutine\">29 Mars 2019<\/a>  pour comprendre que la logique en marche est inarr\u00eatable&hellip;<\/p>\n<\/p>\n<p><p>&laquo; <em>Ce qui se d\u00e9roule en ce moment au milieu du brouhaha de la communication est bien que <strong>nous passons de ce stade conceptuel expos\u00e9 ci-dessus \u00e0 un stade op\u00e9rationnel<\/strong>, en en revenant aux deux phrases de TTG cit\u00e9es au d\u00e9but de cette analyse, selon lesquelles la Russie estime que la situation v\u00e9n\u00e9zu\u00e9lienne et le maintien du gouvernement Maduro sont des enjeux strat\u00e9giques essentiels pour elle, et que cette fois elle ne \u00ab\u00a0laissera pas faire\u00a0\u00bb comme elle a \u00ab\u00a0laiss\u00e9 faire\u00a0\u00bb en Syrie et en Ukraine. Si cette r\u00e9solution est bien celle de Poutine, <strong>cela implique une situation extr\u00eamement int\u00e9ressante et nouvelle<\/strong>, dans le chef d&rsquo;un engagement russe de cette importance op\u00e9rationnelle dans l'\u00a0\u00bbarri\u00e8re-cour\u00a0\u00bb des USA<\/em>.<\/p>\n<\/p>\n<p><p>&laquo; <em>S&rsquo;il est certes mesur\u00e9, l&rsquo;engagement op\u00e9rationnel russe est n\u00e9anmoins effectif, et bien entendu la communication bombastique du c\u00f4t\u00e9 de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb ne fait que mettre en \u00e9vidence ce fait. On peut m\u00eame dire qu&rsquo;il est assez surprenant que les Russes affichent ainsi leurs intentions, m\u00eame derri\u00e8re des explications de fa\u00e7ade (consultations courantes entre militaires, pr\u00e9vues depuis longtemps, S-300 d\u00e9j\u00e0 command\u00e9s et fournis avant la crise, etc.) ; car la poursuite des relations militaires dans les circonstances pr\u00e9sentes, avec le soutien militaire que cela implique, <strong>sonne bel et bien comme une affirmation de la volont\u00e9 russe, cette fois et justement de ne pas \u00ab\u00a0laisser faire\u00a0\u00bb<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>A c\u00f4t\u00e9 de cela, les <a href=\"https:\/\/www.rt.com\/usa\/458321-trump-says-china-wants-nuclear\/\">coups de t\u00e9l\u00e9phone<\/a> de Trump \u00e0 Poutine pour un accord de r\u00e9gulation des armements nucl\u00e9aires (Russie-USA, avec la Chine en prime) <strong>repr\u00e9sentent une aimable conversation de salon de th\u00e9<\/strong>. Bien entendu, le Russe accueille avec faveur cette id\u00e9e qui date d&rsquo;un autre temps, le temps de la stabilit\u00e9, du respect mutuel des accords de coop\u00e9ration, d&rsquo;une certaine confiance entre \u00ab\u00a0adversaires\u00a0\u00bb de bonne compagnie&hellip; <strong><em>O tempora, o mores<\/em>, &ndash; aujourd&rsquo;hui, nous ne jouons plus ce jeu-l\u00e0<\/strong>. Trump \u00e0 sa fa\u00e7on lunatique et irresponsable, Poutine avec sa ma&icirc;trise et son contr\u00f4le de soi, les Chinois \u00e0 la mani\u00e8re chinoise, <strong>ils sont tous emport\u00e9s par le d\u00e9sordre chaotique du Syst\u00e8me en mode autodestruction<\/strong>, &ndash; lequel passe n\u00e9cessairement (case \u00ab\u00a0d\u00e9part\u00a0\u00bb ? Dans tous les cas, case \u00ab\u00a0principale\u00a0\u00bb) par la destruction du simili-Empire <strong>de carton-p\u00e2te que dirige d&rsquo;une main de coton<\/strong> le pr\u00e9sident Trump.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur le bullshit-Venezuela 4 mai 2019 &ndash; Le Venezuela et sa crise sont une com\u00e9die et un catalogue des erreurs que produisent les USA dans cette sorte d&rsquo;entreprise. L&rsquo;ensemble est r\u00e9v\u00e9lateur de l&rsquo;\u00e9tat tr\u00e8s alarmant de l&#8217;empire et de l&rsquo;extraordinaire constance de Washington D.C. \/\u00a0\u00bbD.C.-la folle\u00a0\u00bb dans la multiplication de ses propres d\u00e9boires caus\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4547,1092,3977,6777,9111,18853,11992,4576,2943,2730,8446,2639],"class_list":["post-78612","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-arriere-cour","tag-bolton","tag-chine","tag-forteresse","tag-frontieres","tag-guaido","tag-maduro","tag-marionnette","tag-mexique","tag-russie","tag-s-300","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78612"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78612\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}