{"id":78643,"date":"2019-05-22T12:23:54","date_gmt":"2019-05-22T12:23:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/22\/comment-les-usa-ont-gagne-la-guerre-contre-liran\/"},"modified":"2019-05-22T12:23:54","modified_gmt":"2019-05-22T12:23:54","slug":"comment-les-usa-ont-gagne-la-guerre-contre-liran","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/22\/comment-les-usa-ont-gagne-la-guerre-contre-liran\/","title":{"rendered":"Comment les USA ont gagn\u00e9 la guerre contre l&rsquo;Iran"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Comment les USA ont gagn\u00e9 la guerre contre l&rsquo;Iran<\/h2>\n<\/p>\n<p><p>Il est possible que Trump ait trouv\u00e9 dans son futur nouveau Secr\u00e9taire \u00e0 la d\u00e9fense \u00ab\u00a0<em>in charge<\/em>\u00ab\u00a0, actuellement encore n&deg;2 faisant fonction de n&deg;1 du Pentagone, l&rsquo;homme id\u00e9al pour le seconder dans sa fa\u00e7on de faire la guerre, &ndash; car il est bien question, non seulement de \u00ab\u00a0faire la guerre\u00a0\u00bb mais de \u00ab\u00a0la gagner\u00a0\u00bb&#8230; Car il est bien question, comme Shanahan l&rsquo;a dit aux journalistes accr\u00e9dit\u00e9s au Pentagone, d&rsquo;une \u00ab\u00a0sorte de guerre\u00a0\u00bb qui a eu lieu entre les &Eacute;tats-Unis et l&rsquo;Iran, puisqu&rsquo;on y a envoy\u00e9 un groupe de porte-avions d&rsquo;attaque et des B-52, et cette \u00ab\u00a0sorte de guerre\u00a0\u00bb annonc\u00e9e comme termin\u00e9e, naturellement par une \u00ab\u00a0sorte de victoire\u00a0\u00bb des &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Ainsi <a href=\"https:\/\/www.rt.com\/news\/459927-pentagon-iran-attacks-on-hold\/\">est pr\u00e9sent\u00e9e<\/a> l&rsquo;intervention de Shanahan, selon l&rsquo;interpr\u00e9tation de RT-com qui nous semble extr\u00eamement conforme \u00e0 \u00ab\u00a0la r\u00e9alit\u00e9 du simulacre\u00a0\u00bb qui nous a \u00e9t\u00e9 pr\u00e9sent\u00e9 en exclusivit\u00e9 mondiale :<\/p>\n<\/p>\n<p><p>&laquo; <em>Les menaces de Washington contre l&rsquo;Iran, ax\u00e9es sur la paix, ont port\u00e9 leurs fruits &ndash; du moins selon le ministre de la d\u00e9fense Patrick Shanahan, qui affirme que la R\u00e9publique islamique a d&ucirc; \u00ab\u00a0suspendre\u00a0\u00bb ses plans de menaces d&rsquo;attaque gr\u00e2ce aux efforts am\u00e9ricains.<\/em><\/p>\n<p>&raquo; <em>Alors que l&rsquo;Iran a d\u00e9menti \u00e0 plusieurs reprises les all\u00e9gations selon lesquelles il serait responsable des tensions r\u00e9centes et a d\u00e9clar\u00e9 pr\u00e9f\u00e9rer la diplomatie aux menaces, Shanahan \u00e9tait certain mardi que le comportement dangereux de T\u00e9h\u00e9ran n&rsquo;avait \u00e9t\u00e9 frein\u00e9 que par les mesures proactives des &Eacute;tats-Unis.<\/em><\/p>\n<p>&raquo; <em>Ces gestes de maintien de la paix comprennent probablement l&rsquo;envoi d&rsquo;un groupe d&rsquo;intervention navale sur les c\u00f4tes iraniennes, l&rsquo;augmentation des sanctions paralysantes et la menace amicale du pr\u00e9sident Donald Trump de mettre un terme d\u00e9finitif \u00e0 l&rsquo;existence de l&rsquo;Iran.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Je pense que nos mesures ont \u00e9t\u00e9 tr\u00e8s prudentes et que nous avons contraint l&rsquo;Iran \u00e0 abandonner ses menaces d&rsquo;attaques contre les Am\u00e9ricains, et c&rsquo;est ce qui est extr\u00eamement important\u00a0\u00bb, a d\u00e9clar\u00e9 Shanahan aux journalistes du Pentagone, sans fournir d&rsquo;informations pr\u00e9cises sur ce qu&rsquo;\u00e9taient ces mesures.<\/em><\/p>\n<p>&raquo; <em>Les \u00ab\u00a0mesures\u00a0\u00bb inexpliqu\u00e9es sont \u00e0 peu pr\u00e8s aussi claires que les accusations des &Eacute;tats-Unis contre l&rsquo;Iran : M. Trump a d\u00e9clar\u00e9 publiquement qu&rsquo;il n&rsquo;y a \u00ab\u00a0rien qui indique que quelque chose se produit ou se produira\u00a0\u00bb en ce qui concerne les provocations iraniennes, mais il a \u00e9galement promis d&rsquo;utiliser \u00ab\u00a0une grande force\u00a0\u00bb dans l&rsquo;\u00e9ventualit\u00e9 o&ugrave; elles se produiraient <\/em>[o&ugrave; le \u00ab\u00a0rien\u00a0\u00bb s&rsquo;av\u00e9rerait n&rsquo;\u00eatre pas rien]. &raquo;<\/p>\n<\/p>\n<p><p>Voici, en suppl\u00e9ment et pour nous r\u00e9compenser d&rsquo;avoir lu sans essayer de comprendre la dialectique du Pentagone, un floril\u00e8ge des d\u00e9clarations du secr\u00e9taire \u00e0 la d\u00e9fense Shanahan hier, &ndash; que ce soit aux journalistes, ou bien dans l&rsquo;un ou l&rsquo;autre tweet, ou bien peut-\u00eatre \u00e0 sa femme lors du d&icirc;ner familial, &ndash; c&rsquo;est-\u00e0-dire <strong>sans suivi logique ni chronologique, mais aussi sans n\u00e9cessit\u00e9 de \u00ab\u00a0suivi logique ni chronologique\u00a0\u00bb<\/strong>&#8230; On retrouvera p\u00eale-m\u00eale les interpr\u00e9tations donn\u00e9es dans l&rsquo;extrait ci-dessus, <strong>sans en comprendre plus n\u00e9cessairement, et surtout sans comprendre n\u00e9cessairement que l&rsquo;important n&rsquo;est pas n\u00e9cessairement de comprendre<\/strong>. <\/p>\n<\/p>\n<p><p>&laquo; <em>Il n&rsquo;y a pas eu d&rsquo;attaques contre les Am\u00e9ricains&#8230; cela ne veut pas dire que les menaces que nous avons identifi\u00e9es pr\u00e9c\u00e9demment ont disparu. Notre r\u00e9ponse prudente a donn\u00e9 aux Iraniens le temps de r\u00e9fl\u00e9chir, je pense que notre r\u00e9ponse \u00e9tait une mesure de notre volont\u00e9 et de notre d\u00e9termination<\/em>. [&#8230;]<\/p>\n<p>&raquo; <em>Nous avons parl\u00e9 de ces menaces et il y a eu des attaques&#8230; Et je tiens vraiment \u00e0 souligner la cr\u00e9dibilit\u00e9 des services de renseignement&#8230; Je pense que nos mesures ont \u00e9t\u00e9 tr\u00e8s prudentes et que nous avons dissuad\u00e9 le potentiel d&rsquo;attaques contre les Am\u00e9ricains et c&rsquo;est ce qui est extr\u00eamement important<\/em>. [&#8230;]<\/p>\n<p>&raquo; <em>Je dirais que nous sommes dans une p\u00e9riode o&ugrave; la menace reste \u00e9lev\u00e9e et que notre travail consiste \u00e0 nous assurer qu&rsquo;il n&rsquo;y a pas d&rsquo;erreur de calcul de la part des Iraniens<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>En gros, les USA exercent des pressions et des provocations contre l&rsquo;Iran, ils d\u00e9placent des forces pour cela en disant que ces forces sont d\u00e9ploy\u00e9es pour contrer des \u00ab\u00a0menaces\u00a0\u00bb dont eux seuls connaissent l&rsquo;existence (&laquo; <em>Et je tiens vraiment \u00e0 souligner la cr\u00e9dibilit\u00e9 des services de renseignement<\/em> &raquo;), au contraire par exemple des Iraniens qui sont pourtant les producteurs de ces \u00ab\u00a0menaces\u00a0\u00bb ; puis ils assurent que ces \u00ab\u00a0menaces\u00a0\u00bb sont \u00e9limin\u00e9es, d&rsquo;autant plus ais\u00e9ment qu&rsquo;eux seuls savaient ce dont il s&rsquo;agissait, et eux-m\u00eames, les USA, ayant non seulement \u00e9cart\u00e9 de ce fait toute possibilit\u00e9 de conflit (au moins pour la journ\u00e9e), mais mieux encore, avec une efficacit\u00e9 telle qu&rsquo;on peut bel et bien affirm\u00e9 qu&rsquo;ils ont gagn\u00e9 la guerre&#8230; Ainsi remporte-t-on \u00e0 la fois la guerre et la paix. <\/p>\n<\/p>\n<p><p>&laquo; <em>Apr\u00e8s avoir d\u00e9nonc\u00e9 \u00ab\u00a0les menaces\u00a0\u00bb de l&rsquo;Iran et envoy\u00e9 des navires, des bombardiers et des missiles au Moyen-Orient, Washington affirme maintenant que ses actions ont \u00ab\u00a0dissuad\u00e9\u00a0\u00bb T\u00e9h\u00e9ran et il salue sa propre victoire. Qui n&rsquo;aurait pu deviner que cela se terminerait ainsi ?<\/em> &raquo;, <a href=\"https:\/\/www.rt.com\/op-ed\/459938-iran-us-tiger-repellent\/\">\u00e9crit Nabojsa Malic<\/a>, qui tente de donner une analyse coh\u00e9rente de l&rsquo;intervention de Shanahan, notamment \u00e0 l&rsquo;aide d&rsquo;une r\u00e9f\u00e9rence \u00e9vidente, qu&rsquo;il pr\u00e9sente comme une plaisante illustration de la man&oelig;uvre : &laquo; <em>Il y a une vieille blague \u00e0 propos d&rsquo;un escroc qui vend des pierres ayant la capacit\u00e9 de repousser les tigres et qui, lorsqu&rsquo;on lui demande comment \u00e7a marche, r\u00e9pond : \u00ab\u00a0Vous ne voyez pas de tigres dans le coin, autour de moi, hein ? Alors, c&rsquo;est la preuve que \u00e7a marche, non ?\u00a0\u00bb<\/em> &raquo;<\/p>\n<\/p>\n<p><p>L\u00e0-dessus, Malic, qui veut tout de m\u00eame faire s\u00e9rieusement son travail de commentateur, conclut par deux affirmations qu&rsquo;il voudrait compl\u00e9mentaires, &ndash; mais le sont-elles ? &laquo; <em>Soyons r\u00e9alistes, Trump est un homme de spectacle. Il a pass\u00e9 des ann\u00e9es dans la t\u00e9l\u00e9-r\u00e9alit\u00e9, et avant cela sous les projecteurs des m\u00e9dias comme un magnat de l&rsquo;immobilier. Il a un certain style de n\u00e9gociation qui implique beaucoup de fanfaronnades, et il l&rsquo;a utilis\u00e9 de la Cor\u00e9e du Nord et de la Chine \u00e0 l&rsquo;Iran. Reste \u00e0 voir si cela fonctionnera r\u00e9ellement<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Effectivement, \u00ab\u00a0soyons r\u00e9aliste\u00a0\u00bb : la premi\u00e8re proposition est une <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> (Trump \u00ab\u00a0homme de spectacle\u00a0\u00bb, etc.) ; la seconde est beaucoup plus hypoth\u00e9tique et m\u00eame compl\u00e8tement al\u00e9atoire : veut-il n\u00e9gocier ? Sait-il ce que c&rsquo;est que de n\u00e9gocier ? N\u00e9gocie-t-il ou bien fait-il du spectacle ? Etc. (Car, jusqu&rsquo;ici, il n&rsquo;a rien obtenu de s\u00e9rieux, de stable, de solide qui ressemble \u00e0 l&rsquo;effet d&rsquo;une n\u00e9gociation r\u00e9ussie, ni de la Cor\u00e9e du Nord, ni de la Chine, ni de l&rsquo;Iran, etc. ; il n&rsquo;a fait qu&rsquo;appliquer des pressions, des sanctions, d\u00e9placer des forces, menacer les autres puis les f\u00e9liciter pour l&rsquo;avoir entendu m\u00eame si personne n&rsquo;a \u00e9cout\u00e9, etc., cela <strong>dans une atmosph\u00e8re de spectacle tonitruant, de <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> \u00e0 grands coups de cymbales<\/strong>, &ndash; \u00ab\u00a0Nous partons en guerre\u00a0\u00bb, \u00ab\u00a0Nous an\u00e9antissons l&rsquo;adversaire\u00a0\u00bb, \u00ab\u00a0Nous avons gagn\u00e9 la guerre\u00a0\u00bb, \u00ab\u00a0Nous sommes tr\u00e8s amis de l&rsquo;ancien adversaire\u00a0\u00bb, etc.)<\/p>\n<\/p>\n<p><p>Le m\u00eame jour o&ugrave; Shanahan d\u00e9clarait tout ce qu&rsquo;on a lu et d\u00e9clarait le 21 mai 2019 \u00ab\u00a0<em>V-Day<\/em>\u00a0\u00bb contre l&rsquo;Iran, le secr\u00e9taire d&rsquo;&Eacute;tat Pompeo d\u00e9clarait, abrit\u00e9 derri\u00e8re une lapalissade, que l&rsquo;Iran &laquo; <em>pourrait bien \u00eatre responsable de l&rsquo;attaque contre les p\u00e9troliers&#8230; Quoiqu&rsquo;il n&rsquo;y ait pas de preuve qu&rsquo;il le soit<\/em>. &raquo; A part les habituelles remarques sur l&rsquo;intense et strat\u00e9gique bordel interne de l&rsquo;administration Trump, avec les batailles de chiffonniers et de d\u00e9clarations contradictoires entre factions, nous voil\u00e0 bien avanc\u00e9s pour fournir un commentaire coh\u00e9rent&#8230; <strong>Par cons\u00e9quent, le seul commentaire coh\u00e9rent \u00e0 faire est qu&rsquo;il n&rsquo;y a pas de commentaire coh\u00e9rent \u00e0 faire<\/strong>, si l&rsquo;on s&rsquo;en tient \u00e0 l&rsquo;apparence des choses qu&rsquo;on nomme \u00ab\u00a0les faits\u00a0\u00bb. Dont acte.<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Pour le reste et plus que jamais<\/strong>, faisons appel \u00e0 un \u00ab\u00a0commentaire coh\u00e9rent\u00a0\u00bb (qu&rsquo;on esp\u00e8re coh\u00e9rent, puisque <a href=\"http:\/\/www.dedefensa.org\/article\/trump-tweet-liran-une-strategie-liquide\">de notre plume<\/a>) qui acte de l&rsquo;incoh\u00e9rence de la chose, comme \u00e9tant une des marques de fabrique de la \u00ab\u00a0strat\u00e9gie\u00a0\u00bb am\u00e9ricaniste, parce que ce qui compte n&rsquo;est en rien dans les buts et les ambitions de la strat\u00e9gie mais dans la forme elle-m\u00eame, <strong>n\u00e9cessairement informe<\/strong>, de cette strat\u00e9gie, &ndash; bref, soyons foucaldiens que diable : &laquo; <em>L&rsquo;effet g\u00e9n\u00e9ral pourrait plut\u00f4t se rapprocher <strong>d&rsquo;une sorte de strat\u00e9gie qu&rsquo;aurait enfant\u00e9e Michel Foucault s&rsquo;il \u00e9tait encore de ce monde <\/strong>devenu trumpiste, c&rsquo;est-\u00e0-dire une <strong>\u00ab\u00a0strat\u00e9gie liquide\u00a0\u00bb ou \u00ab\u00a0strat\u00e9gie de la plasticit\u00e9\u00a0\u00bb, insaisissable et informelle<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Par cons\u00e9quent, nous dirons que Shanahan, qui vient de chez Boeing o&ugrave; l&rsquo;on sait fabriquer des 737Max plus rapidement que des <em>FakeNews <\/em>s&rsquo;av\u00e8re devoir \u00eatre le premier v\u00e9ritable secr\u00e9taire \u00e0 la d\u00e9fense de type-foucaldien, c&rsquo;est-\u00e0-dire capable de fournir \u00e0 son pr\u00e9sident <strong>des \u00ab\u00a0\u00e9l\u00e9ments de langage\u00a0\u00bb pouvant s&rsquo;apparenter \u00e0 des \u00ab\u00a0apparences de faits\u00a0\u00bb<\/strong>, permettant de faire en sorte que \u00ab\u00a0<em>The Show Must Go On<\/em>\u00ab\u00a0. Ce n&rsquo;est pas plaisanter ou se moquer que terminer de la sorte, mais envisager tr\u00e8s s\u00e9rieusement que la strat\u00e9gie US, comme la politique US, comme la puissance US, soient effectivement conduites \u00e0 \u00eatre autant de rassemblements habiles et coh\u00e9rents d'\u00a0\u00bb\u00e9l\u00e9ments de langage\u00a0\u00bb s&rsquo;apparentant \u00e0 des \u00ab\u00a0apparences de faits\u00a0\u00bb. Certes, il faut un porte-avions et 3 ou 4 bombardiers B-52 qu&rsquo;on d\u00e9place de-ci de-l\u00e0 parce qu&rsquo;on sait qu&rsquo;\u00e0 Hollywood, chez les vrais professionnels de la marche du monde, le d\u00e9cor compte dans le rubrique \u00ab\u00a0pour du vrai\u00a0\u00bb. Pour le reste, toujours lui, <strong>il s&rsquo;agit de saltimbanquer haut et fort<\/strong>.<\/p>\n<\/p>\n<p><p>Mis en ligne le 22 mai 2019 \u00e0 12H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment les USA ont gagn\u00e9 la guerre contre l&rsquo;Iran Il est possible que Trump ait trouv\u00e9 dans son futur nouveau Secr\u00e9taire \u00e0 la d\u00e9fense \u00ab\u00a0in charge\u00ab\u00a0, actuellement encore n&deg;2 faisant fonction de n&deg;1 du Pentagone, l&rsquo;homme id\u00e9al pour le seconder dans sa fa\u00e7on de faire la guerre, &ndash; car il est bien question, non seulement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3845,4390,12911,2645,2773,5084,3582,6157,3194,6975,19075,3965,2639,12567,2860],"class_list":["post-78643","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-article","tag-et","tag-foucault","tag-guerre","tag-iran","tag-menaces","tag-michel","tag-paix","tag-pentagone","tag-pressions","tag-shanahan","tag-simulacre","tag-trump","tag-tweet","tag-victoire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78643"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78643\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}