{"id":78649,"date":"2019-05-25T05:15:11","date_gmt":"2019-05-25T05:15:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/25\/comment-les-mutants-font-lhistoire\/"},"modified":"2019-05-25T05:15:11","modified_gmt":"2019-05-25T05:15:11","slug":"comment-les-mutants-font-lhistoire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/05\/25\/comment-les-mutants-font-lhistoire\/","title":{"rendered":"Comment les mutants font l&rsquo;histoire"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Comment les mutants font l&rsquo;histoire<\/h2>\n<\/p>\n<p><p>Nous avons tous tendance \u00e0 nous laisser berner par une perspective : se rapprocher d&rsquo;eux fait para&icirc;tre les objets qui nous sont plus proches relativement plus grands que ceux qui sont plus \u00e9loign\u00e9s. C&rsquo;est \u00e9galement vrai de l&rsquo;histoire : notre vision tend \u00e0 \u00eatre obstru\u00e9e par les \u00e9v\u00e9nements r\u00e9cents, ce qui nous fait accepter comme l&rsquo;ordre immuable des mod\u00e8les de cr\u00e9ation qui peuvent n&rsquo;\u00eatre qu&rsquo;une aberration temporaire et transitoire. <\/p>\n<\/p>\n<p><p>Il n&rsquo;est pas utile que l&rsquo;Histoire ne soit g\u00e9n\u00e9ralement qu&rsquo;un ensemble d&rsquo;histoires, concernant surtout des personnes remarquables et des \u00e9v\u00e9nements importants, et pas du tout le genre de donn\u00e9es tr\u00e8s travaill\u00e9es et abstraites qui nous permettraient de voir des mod\u00e8les immuables. Pourtant, ces mod\u00e8les existent, ils peuvent \u00eatre per\u00e7us en regardant plusieurs milliers d&rsquo;ann\u00e9es d&rsquo;archives arch\u00e9ologiques et d&rsquo;histoire collect\u00e9e, et ils nous en disent long sur ce qui se passe aujourd&rsquo;hui et sur ce que l&rsquo;avenir nous r\u00e9serve probablement. Et la caract\u00e9ristique la plus frappante de tout cela est que l&rsquo;histoire est faite d&rsquo;humains mutants alors que les humains normaux subsistent juste g\u00e9n\u00e9ralement selon ce que la nature et leur environnement local permet, sans laisser beaucoup de traces.<\/p>\n<\/p>\n<p><p>Les historiens et les arch\u00e9ologues se tiennent en haute estime et ont tendance \u00e0 bavarder sur les civilisations et les cultures, mais si nous prenons leur travail dans son ensemble et le r\u00e9duisons \u00e0 des chiffres, nous d\u00e9couvrons que la plupart du temps et dans la plupart des endroits il n&rsquo;y a vraiment pas beaucoup \u00e0 \u00e9crire sur une civilisation et les cultures sont surtout des choses statiques qui tournent en rond, et seulement une fois, de temps \u00e0 autre, quelque chose de notable se produit : l&rsquo;\u00e9mergence d&rsquo;une nouvelle culture ou civilisation. Tout \u00e0 coup, un petit groupe de tribus mongoles conquiert la moiti\u00e9 de l&rsquo;Eurasie en organisant des tribus nomades en une grande arm\u00e9e, ou un petit groupe de tribus ta\u00efwanaises colonise de nombreuses &icirc;les de l&rsquo;oc\u00e9an Pacifique en cano\u00eb \u00e0 voile. D&rsquo;autres tribus construisent des pyramides (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Gizeh\">Gizeh<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Teotihuacan\">Teotihuacan<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Chich%C3%A9n_Itz%C3%A1\">Chichen Itza<\/a>) ou des complexes de temples (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Angkor_Vat\">Angkor Vat<\/a>), ou creusent des syst\u00e8mes de canaux g\u00e9ants qui font fleurir les d\u00e9serts. Mais de tels \u00e9v\u00e9nements sont rares et aucun historien ne peut vous dire ce qui les d\u00e9clenche ou ce qui d\u00e9termine leur timing. Mais il y a une r\u00e9ponse claire et ce sont, en un mot, des mutants.<\/p>\n<\/p>\n<p><p>La r\u00e9ponse a \u00e9t\u00e9 donn\u00e9e par le chercheur  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lev_Goumilev\">Lev Gumil\u00ebv<\/a>  qui, apr\u00e8s avoir  <a href=\"https:\/\/lesakerfrancophone.fr\/introduction-a-lethnosphere-de-la-terre\">examin\u00e9 longuement l&rsquo;Histoire<\/a>, a d\u00e9termin\u00e9 que l&rsquo;apparition de tels \u00e9carts par rapport \u00e0 l&rsquo;\u00e9quilibre hom\u00e9ostatique est constamment observ\u00e9e en des endroits situ\u00e9s le long d&rsquo;une ligne qui ne s&rsquo;\u00e9tend que d&rsquo;un c\u00f4t\u00e9 de la plan\u00e8te. L&rsquo;orientation de cette ligne est arbitraire ; par cons\u00e9quent, elle n&rsquo;est pas li\u00e9e \u00e0 quelque chose qui se produit dans le plan du syst\u00e8me solaire. Les emplacements peuvent \u00eatre s\u00e9par\u00e9s par des mers et des montagnes infranchissables ; par cons\u00e9quent, ce n&rsquo;est pas quelque chose qui s&rsquo;\u00e9tend le long d&rsquo;une ligne mais quelque chose qui se d\u00e9clenche ind\u00e9pendamment le long d&rsquo;une ligne. Les d\u00e9veloppements d\u00e9clench\u00e9s simultan\u00e9ment \u00e0 diff\u00e9rents endroits peuvent conduire \u00e0 des r\u00e9sultats tr\u00e8s diff\u00e9rents et sans rapport les uns avec les autres ; par exemple, la philosophie analytique dans la Gr\u00e8ce antique, la religion (bouddhisme, zoroastrisme) en Inde et en Perse et l&rsquo;\u00e9thique (confucianisme) en Chine.<\/p>\n<\/p>\n<p><p>Ces secousses de d\u00e9veloppement ne se produisent qu&rsquo;une poign\u00e9e de fois au cours d&rsquo;un mill\u00e9naire donn\u00e9, ce qui fait de leur \u00e9tude un sacr\u00e9 probl\u00e8me de recherche. Bien qu&rsquo;il soit impossible d&rsquo;obtenir des donn\u00e9es fiables, nous pouvons formuler une bonne hypoth\u00e8se de travail quant \u00e0 leur cause : il s&rsquo;agit d&rsquo;explosions de rayonnement cosmique. La biosph\u00e8re terrestre est entour\u00e9e d&rsquo;une  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ionosph%C3%A8re\">ionosph\u00e8re<\/a>  qui prot\u00e8ge la vie des effets st\u00e9rilisants et mutag\u00e8nes de la plupart des rayonnements interstellaires. Certains rayonnements ionisants s&rsquo;\u00e9chappent, ce qui donne lieu \u00e0 un taux de mutation faible et relativement constant. Mais il y a des \u00e9v\u00e9nements plut\u00f4t \u00e9nergiques qui se produisent sporadiquement dans la galaxie de la Voie lact\u00e9e et au-del\u00e0 &ndash; des \u00e9toiles qui deviennent des super novas, des trous noirs qui avalent de gros objets, etc. &ndash; qui produisent des jets de particules \u00e0 haute \u00e9nergie qui peuvent percer la  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ionosph%C3%A8re\">ionosph\u00e8re<\/a>. Les astrophysiciens se demandent pourquoi ils la percent le long d&rsquo;une bande \u00e9troite (seulement quelques centaines de kilom\u00e8tres de large), mais apparemment, c&rsquo;est le cas, et quand cela arrive, cela provoque certaines mutations sp\u00e9cifiques dans le g\u00e9nome humain.<\/p>\n<\/p>\n<p><p>Les mutations qui se produisent tout le temps ne provoquent pas ce ph\u00e9nom\u00e8ne (certaines sont r\u00e9par\u00e9es par des m\u00e9canismes d&rsquo;auto-correction d&rsquo;erreurs g\u00e9n\u00e9tiques) ou peuvent causer des malformations cong\u00e9nitales ou des anomalies du d\u00e9veloppement. Certaines mutations peuvent \u00eatre b\u00e9n\u00e9fiques, auquel cas elles peuvent donner un avantage reproductif \u00e0 ceux qui en sont atteints et se propager progressivement dans une population. En g\u00e9n\u00e9ral, les mutations sont s\u00e9lectionn\u00e9es pour leur capacit\u00e9 d&rsquo;adaptation et leur meilleure ad\u00e9quation entre un organisme et son environnement, ce qui lui permet de mieux maintenir l&rsquo;\u00e9quilibre hom\u00e9ostatique dans son coin de biosph\u00e8re. Mais ces mutations particuli\u00e8res, qui r\u00e9sultent de la p\u00e9n\u00e9tration sporadique de rayons cosmiques dans la  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ionosph%C3%A8re\">ionosph\u00e8re<\/a>, ont un autre r\u00e9sultat : elles cr\u00e9ent une impulsion passionn\u00e9e pour un changement radical. Elles \u00e9loignent une population humaine de l&rsquo;\u00e9quilibre hom\u00e9ostatique et ne sont donc pas li\u00e9es \u00e0 la s\u00e9lection naturelle. Ceux qui portent le g\u00e8ne mutant ne sont pas pouss\u00e9es par les pulsions habituelles de s\u00e9curit\u00e9, de s&ucirc;ret\u00e9 et de confort, mais par une impulsion folle, passionn\u00e9e et fr\u00e9n\u00e9tique pour de grandes actions. Ces mutants veulent la conqu\u00eate, la gloire, l&rsquo;accomplissement, l&rsquo;immortalit\u00e9 ; ils ne sont pas motiv\u00e9s par l&rsquo;int\u00e9r\u00eat personnel mais par la passion. Le g\u00e8ne mutant se propage rapidement et s&rsquo;exprime s\u00e9lectivement chez le m\u00e2le de l&rsquo;esp\u00e8ce tandis que les femelles, \u00e0 de tr\u00e8s rares exceptions pr\u00e8s, continuent comme avant. Cela indiquerait que le locus du g\u00e8ne mutant est le chromosome Y. Il n&rsquo;est pr\u00e9sent que chez les m\u00e2les, et il se transmet toujours de p\u00e8re en fils. Puisqu&rsquo;il ne peut y avoir qu&rsquo;un seul chromosome Y dans une cellule donn\u00e9e, il ne contient aucun g\u00e8ne r\u00e9cessif. Le chromosome Y est la partie exp\u00e9rimentale du g\u00e9nome humain et un foyer de l&rsquo;\u00e9volution humaine, qui change beaucoup plus rapidement que le reste du g\u00e9nome.<\/p>\n<\/p>\n<p><p>Lorsqu&rsquo;une population voit son chromosome Y modifi\u00e9 par les rayons spatiaux, il s&rsquo;ensuit une p\u00e9riode d&rsquo;incubation, que Gumil\u00ebv estime entre 100 et 150 ans (rendant encore plus difficile le probl\u00e8me de la d\u00e9tection de l&rsquo;impulsion initiale). Cette p\u00e9riode est marqu\u00e9e par un niveau croissant de meurtres et de mutilations au fur et \u00e0 mesure que le g\u00e8ne de la nouvelle passion se r\u00e9pand dans la population, parce que ses porteurs ont tendance \u00e0 \u00eatre volatiles et \u00e0 se battre \u00e0 mort pour des offenses relativement mineures. Exacerbant cette tendance, ce g\u00e8ne semble aussi activer un syst\u00e8me d&rsquo;identification organique, construit autour de la relation binaire ami ou ennemi : alors que les individus passionn\u00e9s rationalisent leur diff\u00e9rence comme politique, religieuse, philosophique ou esth\u00e9tique, en r\u00e9alit\u00e9 ils combattent, et souvent tuent carr\u00e9ment, tous ceux qu&rsquo;ils sentent inconsciemment comme diff\u00e9rents d&rsquo;eux. Nous ne savons pas sur quoi repose ce sens, mais nous pouvons facilement exclure tout ce qui est li\u00e9 \u00e0 la culture, car la culture peut muter alors que ce sens est fixe et doit donc \u00eatre d\u00e9termin\u00e9 biologiquement. L&rsquo;effet de ce qui semble \u00eatre un massacre sans raison est d&rsquo;\u00e9tablir l&rsquo;homog\u00e9n\u00e9it\u00e9 au sein de la population masculine et, \u00e0 la fin du processus, aucun des individus passionn\u00e9s ne d\u00e9clenche plus les d\u00e9tecteurs d&rsquo;amis ou d&rsquo;ennemis des uns et des autres. Cela permet une coh\u00e9sion interne fantastique et permet \u00e0 des groupes de m\u00e2les d&rsquo;agir comme une unit\u00e9 et de r\u00e9aliser de grandes choses pendant la phase suivante.<\/p>\n<\/p>\n<p><p>Il s&rsquo;ensuit plusieurs autres phases au cours desquelles une nouvelle ethnie se forme, se propage, conquiert, accomplit de grandes choses ou cause d&rsquo;horribles dommages (ou les deux) et finit par s&rsquo;\u00e9teindre. Selon l&rsquo;estimation prudente de Gumil\u00ebv, l&rsquo;ensemble du processus, de son \u00e9mergence \u00e0 son \u00e9puisement total, ne prend jamais beaucoup plus d&rsquo;un seul mill\u00e9naire. Ainsi, les  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ethnie\">ethnies<\/a>  europ\u00e9ennes plus anciennes (pluriel d&rsquo;<em>&laquo; ethnos &raquo;<\/em>) comme les Fran\u00e7ais et les Allemands sont tr\u00e8s proches de leur fin, car la proportion d&rsquo;individus passionn\u00e9s en leur sein devient trop faible. Gumil\u00ebv distingue trois types d&rsquo;hommes : les passionn\u00e9s, les harmonieux (ce sont des hommes de famille solides qui se battent pour se prot\u00e9ger et prot\u00e9ger leur famille mais qui ne sont pas pr\u00eats \u00e0 mourir pour la gloire) et les sous-passionn\u00e9s (qui offrent une r\u00e9sistance minimale). Au fil du temps, le g\u00e8ne passionnel mutant \u00e9tant s\u00e9lectionn\u00e9 parmi la population (il est, apr\u00e8s tout, mal adapt\u00e9 au maintien de l&rsquo;\u00e9quilibre hom\u00e9ostatique), il laisse derri\u00e8re lui une grande proportion d&rsquo;hommes sous-passionn\u00e9s et une proportion relativement moindre d&rsquo;hommes harmonieux (dont le nombre est r\u00e9duit dans tous les \u00e9pisodes passionnels qui se d\u00e9veloppent au fil des diff\u00e9rentes phases, &ndash; auxquelles Gumil\u00ebv donne des noms \u00e9vocateurs tels que soul\u00e8vement, surchauffe et rupture) qui peuvent \u00e0 peine garder un minimum de coh\u00e9sion et sont souvent enti\u00e8rement an\u00e9antis par des envahisseurs relativement plus passionn\u00e9s.<\/p>\n<\/p>\n<p><p>Il y a beaucoup plus \u00e0 dire sur le sujet de la th\u00e9orie de l&rsquo;ethnogen\u00e8se de Gumil\u00ebv, mais je m&rsquo;arr\u00eaterai ici, et je garderai la discussion sur la fa\u00e7on dont cela se rapporte aux activit\u00e9s contemporaines pour de futurs articles. Il y a deux points particuliers qui m\u00e9ritent certainement d&rsquo;\u00eatre explor\u00e9s. L&rsquo;un est ce qui se produit lorsque des groupes ethniques organiquement incompatibles sont forc\u00e9s de vivre ensemble ; l&rsquo;autre est le caract\u00e8re sauvage de la technosph\u00e8re et comment elle a \u00e9volu\u00e9 d&rsquo;un outil \u00e0 une force avec sa propre volont\u00e9 et une intelligence \u00e9mergente, o&ugrave; le contr\u00f4le de diverses parties de celle-ci passe d&rsquo;un groupe ethnique \u00e0 un autre en succession rapide.<\/p>\n<\/p>\n<p><p>Le 16 mai 2019, <a href=\"http:\/\/cluborlov.blogspot.com\/2019\/05\/how-mutants-make-history.html\">Club Orlov<\/a>, &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/comment-les-mutants-font-lhistoire\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment les mutants font l&rsquo;histoire Nous avons tous tendance \u00e0 nous laisser berner par une perspective : se rapprocher d&rsquo;eux fait para&icirc;tre les objets qui nous sont plus proches relativement plus grands que ceux qui sont plus \u00e9loign\u00e9s. C&rsquo;est \u00e9galement vrai de l&rsquo;histoire : notre vision tend \u00e0 \u00eatre obstru\u00e9e par les \u00e9v\u00e9nements r\u00e9cents, ce&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[9810,11590,19093,19094,2668],"class_list":["post-78649","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-biologie","tag-civilisations","tag-gumilev","tag-mutations","tag-orlov"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78649"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78649\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}