{"id":78669,"date":"2019-06-04T11:29:43","date_gmt":"2019-06-04T11:29:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/06\/04\/sagesse-de-pompeo\/"},"modified":"2019-06-04T11:29:43","modified_gmt":"2019-06-04T11:29:43","slug":"sagesse-de-pompeo","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/06\/04\/sagesse-de-pompeo\/","title":{"rendered":"Sagesse de Pompeo"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Sagesse de Pompeo <\/h2>\n<\/p>\n<p><p>Tout est possible dans cette \u00e9trange \u00e9poque et dans la non moins \u00e9trange administration Trump, particuli\u00e8rement au niveau de la s\u00e9curit\u00e9 nationale. Parmi ce \u00ab\u00a0tout est possible\u00a0\u00bb, il y aurait un comportement inattendu de retenue et de \u00ab\u00a0savoir-faire\u00a0\u00bb politique mod\u00e9rateur de la part du secr\u00e9taire d&rsquo;&Eacute;tat Pompeo, r\u00e9put\u00e9 pour \u00eatre l&rsquo;une des deux chenilles du bulldozer Bolton-Pompeo qui accomplit depuis un an un travail de destruction massive pour le compte du pr\u00e9sident Trump. (Dans nos commentaires, nous ne lui m\u00e9nageons pas nos encouragements et nos consid\u00e9rations distingu\u00e9es pour sa fonction de brute ; d&rsquo;o&ugrave; notre attention curieuse pour ce qui para&icirc;t \u00eatre de la sagesse.)<\/p>\n<\/p>\n<p><p>Le Washington <em>Post <\/em>a publi\u00e9 des confidences sur une r\u00e9union secr\u00e8te qu&rsquo;aurait eue, le 28 mai, Pompeo avec des dirigeants juifs am\u00e9ricanistes, \u00e0 propos du fameux \u00ab\u00a0accord du si\u00e8cle\u00a0\u00bb concoct\u00e9 par le gendre de Trump, Jared Kushner, sur le probl\u00e8me isra\u00e9lo-palestinien et le reste. Il n&rsquo;y a pas eu de commentaires ni d&rsquo;espace \u00e9ditorial important accord\u00e9 \u00e0 ces confidences, ce qui tendrait \u00e9ventuellement et paradoxalement \u00e0 prouver leur importance tout autant que la difficult\u00e9 de les expliquer selon le cat\u00e9chisme du Syst\u00e8me, les sensibilit\u00e9s isra\u00e9lo-trumpiennes mais aussi les positions compliqu\u00e9es des uns et des autres dans cette question tr\u00e8s complexe et tr\u00e8s controvers\u00e9e. (Quand il se produit quelque chose d&rsquo;important et d&rsquo;inattendu, qui ne va pas dans le sens de la d\u00e9strucuration voulue part le Syst\u00e8me, le commrentaire le plus courant est le silence.)<\/p>\n<\/p>\n<p><p>La nouvelle est reprise par l&rsquo;un des collaborateurs du colonel Lang, connu sous le patronyme de \u00ab\u00a0Harper\u00a0\u00bb, sur le site <em>Sic Semper Tyrannis <\/em><a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2019\/06\/harper-pompeo-pronounces-kushner-plan-doa.html\">le 3 juin 2019<\/a>. On note donc l&rsquo;appr\u00e9ciation laudative mais \u00e9tonn\u00e9e, &ndash; on le serait \u00e0 moins, &ndash; de \u00ab\u00a0Harper\u00a0\u00bb pour la position de Pompeo, marqu\u00e9e de gras par nous&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Le 28 mai, le secr\u00e9taire d&rsquo;&Eacute;tat Mike Pompeo \u00e9tait \u00e0 New York pour une r\u00e9union \u00e0 huis clos avec la Conf\u00e9rence des pr\u00e9sidents des principales organisations juives am\u00e9ricaines.  Dans des remarques qui ont \u00e9t\u00e9 secr\u00e8tement enregistr\u00e9es et transmises au Washington Post, Pompeo a effectivement d\u00e9clar\u00e9 que le plan de paix au Moyen-Orient \u00e9voqu\u00e9 par le gendre de Trump Jared Kushner n&rsquo;avait aucune chance d&rsquo;\u00eatre adopt\u00e9 et serait rejet\u00e9 par la plupart des parties. Au lieu de l'\u00a0\u00bbaccord du si\u00e8cle\u00a0\u00bb vant\u00e9 par le pr\u00e9sident Donald Trump, Pompeo a admis que le plan de paix \u00e9tait une proposition perdante.  \u00ab\u00a0Je comprends pourquoi les gens pensent que c&rsquo;est un accord que seul Isra\u00ebl pourrait accepter.  Je comprends ce que vous en pensez.  J&rsquo;esp\u00e8re juste que tout le monde aura le temps d&rsquo;\u00e9couter et de r\u00e9fl\u00e9chir un peu.\u00a0\u00bb Pompeo a poursuivi ses remarques sans d\u00e9tour : \u00ab\u00a0Je ne veux pas dire que c&rsquo;est un \u00e9chec.  Appelez \u00e7a comme vous voulez.  Moi aussi, j&rsquo;ai l&rsquo;impression d&rsquo;\u00e9chouer dans nombre de mes tentatives, alors il faut prendre des pr\u00e9cautions avant d&rsquo;utiliser un tel mot.\u00a0\u00bb  M. Pompeo a admis que le d\u00e9partement d&rsquo;&Eacute;tat accorde beaucoup d&rsquo;attention \u00e0 ce qu&rsquo;il faudrait faire si le plan Kushner \u00e9choue.<\/em><\/p>\n<p>&raquo; <em>Jusqu&rsquo;\u00e0 ce que le Premier ministre \u00e9lu Benjamin Netanyahu \u00e9choue cette semaine dans sa tentative de former un gouvernement et doive convoquer des \u00e9lections anticip\u00e9es pour septembre, on s&rsquo;attendait \u00e0 ce que le plan Kushner tant attendu soit mis en &oelig;uvre ce mois-ci. Aujourd&rsquo;hui, la date de lancement est report\u00e9e \u00e0 fin septembre ou d\u00e9but octobre apr\u00e8s la formation et l&rsquo;assermentation d&rsquo;un nouveau gouvernement isra\u00e9lien.<\/em><\/p>\n<p>&raquo; <strong><em>Pompeo a fait preuve dans la circonstance d&rsquo;un savoir-faire politique inattendu en prenant ses distances du \u00ab\u00a0plan de paix\u00a0\u00bb vou\u00e9 \u00e0 l&rsquo;\u00e9chec<\/em><\/strong><em>, qui semble n&rsquo;\u00eatre rien de plus qu&rsquo;un plan pour acheter la capitulation palestinienne par une combinaison de promesses d&rsquo;argent arabe et d&rsquo;engagements politico-militaires des pays du Golfe et d&rsquo;Isra\u00ebl<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Faut-il s&rsquo;\u00e9tonner de ce comportement inattendu de Pompeo, r\u00e9put\u00e9 pour sa lourdeur, sa brutalit\u00e9, etc., et qui montre dans ce cas ce que nous d\u00e9signons comme de la sagesse ? D&rsquo;abord, il ne faut pas oublier que la politique ext\u00e9rieure des &Eacute;tats-Unis est <strong>tellement nulle et inexistante que prendre le contrepied d&rsquo;une d\u00e9cision ou d&rsquo;une orientation suffit en g\u00e9n\u00e9ral \u00e0 faire preuve de \u00ab\u00a0sagesse\u00a0\u00bb<\/strong>. Ensuite, il y a le constat que tous les ex\u00e9cutants de cette politique dont nul ne sait d&rsquo;ailleurs pr\u00e9cis\u00e9ment l&rsquo;inspirateur, et s&rsquo;il y en a un, sont loin d&rsquo;\u00eatre unis et de former une \u00e9quipe solidaire. <strong>Chacun a ses propres int\u00e9r\u00eats, les int\u00e9r\u00eats de sa bureaucratie, etc., et des affrontements ont lieu couramment<\/strong> ; simplement, jusqu&rsquo;ici on en a eu fort peu d&rsquo;\u00e9chos, dans tous les cas sous une forme tr\u00e8s \u00e9labor\u00e9e comme celle d&rsquo;un discours construit comme celui de Pompeo, &ndash; s&rsquo;ils entrent effectivement, Pompeo et sa sagesse, dans cette cat\u00e9gorie des r\u00e8glements de compte et des man&oelig;uvres personnelles.<\/p>\n<\/p>\n<p><p>En effet, il nous semble qu&rsquo;il ne serait pas illogique de placer l&rsquo;\u00e9v\u00e9nement dans cette cat\u00e9gorie, d&rsquo;abord parce que la proposition que Pompeo tourne en ridicule et critique vertement autant qu&rsquo;il l&rsquo;annonce mort-n\u00e9e vient de Jared Kushner, <strong>qui travaille en solo, autant \u00e0 cause de ses liens familiaux (gendre de Trump) que de ses liens <\/strong>avec divers dirigeants isra\u00e9liens et \u00e9ventuellement quelques personnalit\u00e9s du crime organis\u00e9. Pour la bureaucratie du d\u00e9partement d&rsquo;&Eacute;tat, et par cons\u00e9quent pour ce cas pour le ministre lui-m\u00eame, <strong>cette action est une concurrence inacceptable et il faut tout faire pour la contrecarrer<\/strong>. C&rsquo;est d&rsquo;autant plus faisable si la proposition est effectivement mort-n\u00e9e, d\u00e9j\u00e0 perdue dans la perspective de nouvelles \u00e9lections, etc. Pompeo, qui a sans doute organis\u00e9 lui-m\u00eame la fuite vers le Washington <em>Post <\/em>qu&rsquo;il conna&icirc;t bien puisqu&rsquo;il a dirig\u00e9 la CIA,  prend les devants pour annoncer le d\u00e9c\u00e8s de la chose, et pour pr\u00e9ciser <strong>que sa bureaucratie travaille d\u00e9j\u00e0 sur un post-\u00ab\u00a0accord du si\u00e8cle\u00a0\u00bb<\/strong>, de fa\u00e7on \u00e0 se trouver en bonne place pour relancer un autre processus qui serait ma&icirc;tris\u00e9 par la bureaucratie du minist\u00e8re.<\/p>\n<\/p>\n<p><p>Il est \u00e9galement possible que Pompeo se paie Bolton au passage, parce qu&rsquo;il est tr\u00e8s probable qu&rsquo;il doit juger trop grand le champ d&rsquo;activit\u00e9 qui est laiss\u00e9 au conseiller du pr\u00e9sident pour les affaires de s\u00e9curit\u00e9 nationale au d\u00e9triment de ses propres pouvoirs. C&rsquo;est d&rsquo;autant plus possible que Bolton s&rsquo;est plac\u00e9 dans cette affaire tr\u00e8s proche de Netanyahou, &ndash; tout ce qui est extr\u00eame et anti-iranien, le fascine, &ndash; et donc comme soutien plus z\u00e9l\u00e9 du plan-Kushner que Pompeo. <\/p>\n<\/p>\n<p><p>Tout cela nous ram\u00e8ne donc, avec cette surprenante escapade vers une sagesse inattendue de Pompeo, vers les habituelles querelles internes des grands ensembles bureaucratiques. D&rsquo;autre part, la nouvelle elle-m\u00eame de la probable mort du plan-Kushner repr\u00e9sente <strong>un coup tr\u00e8s rude pour Trump, qui proclame volontiers que cet \u00ab\u00a0accord du si\u00e8cle\u00a0\u00bb repr\u00e9sentera sans aucun doute le grand accomplissement, le legs historique de son (premier ?) mandat<\/strong>. Nous n&rsquo;en sommes qu&rsquo;au stade de la communication et des batailles bureaucratiques et il semble bien que Pompeo, le sage inattendu et par procuration, ait lanc\u00e9 sur l&rsquo;accord une torpille fatale. Apr\u00e8s tout, la sagesse elle-m\u00eame, lorsqu&rsquo;elle est convoqu\u00e9e en d&rsquo;aussi \u00e9tranges circonstances, n&rsquo;est rien de moins qu&rsquo;un \u00e9l\u00e9ment suppl\u00e9mentaire et original du d\u00e9sordre ; car effectivement, sans l'\u00a0\u00bbaccord du si\u00e8cle\u00a0\u00bb qui doit consacrer une sorte de recommandation US de la domination de la r\u00e9gion par Isra\u00ebl et l&rsquo;Arabie, ce qu&rsquo;Isra\u00ebl et les amis d&rsquo;Isra\u00ebl \u00e0 Washington consid\u00e8rent comme \u00e9tant du d\u00e9sordre r\u00e9gnera plus que jamais dans la r\u00e9gion.<\/p>\n<\/p>\n<p><p>Mis en ligne le 4 juin 2019 \u00e0 11H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sagesse de Pompeo Tout est possible dans cette \u00e9trange \u00e9poque et dans la non moins \u00e9trange administration Trump, particuli\u00e8rement au niveau de la s\u00e9curit\u00e9 nationale. Parmi ce \u00ab\u00a0tout est possible\u00a0\u00bb, il y aurait un comportement inattendu de retenue et de \u00ab\u00a0savoir-faire\u00a0\u00bb politique mod\u00e9rateur de la part du secr\u00e9taire d&rsquo;&Eacute;tat Pompeo, r\u00e9put\u00e9 pour \u00eatre l&rsquo;une des&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[1092,13542,2849,2774,12958,4014,6136,3050,2639],"class_list":["post-78669","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bolton","tag-century","tag-deal","tag-israel","tag-kushner","tag-of","tag-palestine","tag-the","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78669"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78669\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}