{"id":78687,"date":"2019-06-14T09:38:29","date_gmt":"2019-06-14T09:38:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/06\/14\/une-rasade-de-perlimpinpin\/"},"modified":"2019-06-14T09:38:29","modified_gmt":"2019-06-14T09:38:29","slug":"une-rasade-de-perlimpinpin","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/06\/14\/une-rasade-de-perlimpinpin\/","title":{"rendered":"Une rasade de Perlimpinpin\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Une rasade de Perlimpinpin ?<\/h2>\n<\/p>\n<p><p>Walmart, la grande cha&icirc;ne de distribution \u00e9tasunienne, est poursuivie en justice pour fraude. Le  <a href=\"https:\/\/centerforinquiry.org\/about\/the-history-of-cfi\/#https:\/\/centerforinquiry.org\/about\/the-history-of-cfi\/\"><em>Center for Inquiry<\/em>,<\/a>organisation \u00e0 but non lucratif fond\u00e9e en 1991 sur les bases d&rsquo;un humanisme s\u00e9culier pour lutter contre la superstition et les fausses sciences repr\u00e9sente l&rsquo;institution plaignante.<\/p>\n<\/p>\n<p><p>Le CFI accuse Walmart de <a href=\"https:\/\/www.zerohedge.com\/news\/2019-06-03\/wide-scale-consumer-fraud-walmart-sued-selling-fake-medicine#https:\/\/www.zerohedge.com\/news\/2019-06-03\/wide-scale-consumer-fraud-walmart-sued-selling-fake-medicine\">tromper<\/a>ses clients et de mettre leur sant\u00e9 en danger en pr\u00e9sentant dans la m\u00eame rubrique et sans les diff\u00e9rencier des m\u00e9dicaments et des traitements hom\u00e9opathiques d\u00e9nu\u00e9s d&rsquo;efficacit\u00e9 en dehors de leur effet placebo. <\/p>\n<\/p>\n<p><p>La confusion est manifeste aussi bien dans les rayons des magasins que sur les boutiques en ligne. Cette indistinction est pr\u00e9judiciable \u00e0 la sant\u00e9 quand les patients ont besoin de m\u00e9dicaments r\u00e9ellement actifs. Cette mise en danger est d&rsquo;autant plus grave que Walmart dispose d&rsquo;une puissance de vente colossale.<\/p>\n<\/p>\n<p><p>La  plainte expose la th\u00e9orie \u00e0 l&rsquo;origine de cette m\u00e9decine douce. Au 18<sup>\u00e8me<\/sup> si\u00e8cle s&rsquo;\u00e9tait d\u00e9velopp\u00e9e l&rsquo;id\u00e9e qu&rsquo;il \u00e9tait possible de soigner par la similitude.  L&rsquo;administration d&rsquo;une substance \u00e0 l&rsquo;origine d&rsquo;une maladie gu\u00e9rit la maladie. Pour cela, la substance est cens\u00e9e \u00eatre active apr\u00e8s avoir \u00e9t\u00e9 dilu\u00e9e un grand nombre de fois au point que la mol\u00e9cule devient ind\u00e9tectable dans le produit final. Plus tard fut d\u00e9velopp\u00e9e la th\u00e9orie de la m\u00e9moire de l&rsquo;eau qui s&rsquo;est av\u00e9r\u00e9e une <a href=\"http:\/\/www.linternaute.com\/science\/divers\/dossiers\/06\/impostures\/memoire-de-l-eau.shtml#http:\/\/www.linternaute.com\/science\/divers\/dossiers\/06\/impostures\/memoire-de-l-eau.shtml\">fumisterie d\u00e9lirante<\/a>. La non reproductibilit\u00e9 des exp\u00e9riences de Benveniste pourtant publi\u00e9es dans la c\u00e9l\u00e8bre revue <em>Nature <\/em>invalide totalement les essais conduits dans des conditions o&ugrave; des cellules basophiles, fragiles et sensibles aux variation d&rsquo;osmolarit\u00e9 de leur milieu d\u00e9granulent de fa\u00e7on non sp\u00e9cifique et al\u00e9atoire.  Si l&rsquo;eau avait une m\u00e9moire, pourquoi cette m\u00e9moire serait-elle s\u00e9lective et ne conserverait-elle que la structure de la mol\u00e9cule choisie par l&rsquo;exp\u00e9rimentateur et pas toutes celles qui y ont baign\u00e9. A moins de dissocier H2O en ses composants atomiques, ce sont les m\u00eames mol\u00e9cules d&rsquo;eau qui sont sans cesse recycl\u00e9es. Quelques temps plus tard, le Pr Montagnier a pr\u00e9tendu que les nanostructures d&rsquo;un \u00e9chantillon d&rsquo;eau peuvent garder la trace \u00e9lectromagn\u00e9tique d&rsquo;un fragment d&rsquo;ADN, laquelle permet de reconstruire le fragment d&rsquo;ADN initial \u00e0 partir de cette signature magn\u00e9tique. Interpell\u00e9 par deux biochimistes qui souhaitaient reproduire en sa pr\u00e9sence une telle manipulation, le co-prix Nobel de 2008 <a href=\"https:\/\/www.ouvertures.net\/pr-montagnier-sourd-aux-interpellations-de-biochimistes-sur-ses-experiences-sur-la-memoire-de-l-eau\/#https:\/\/www.ouvertures.net\/pr-montagnier-sourd-aux-interpellations-de-biochimistes-sur-ses-experiences-sur-la-memoire-\">n&rsquo;a pas donn\u00e9 suite<\/a> \u00e0 leur demande.<\/p>\n<\/p>\n<p><p>L&rsquo;exploration de ce domaine &lsquo;magique&rsquo; a s&ucirc;rement plac\u00e9 les biologistes qui l&rsquo;ont entreprise sur une cr\u00eate qui surplombe et conjugue l&rsquo;insignifiance, l&rsquo;imposture et le d\u00e9lire.<\/p>\n<\/p>\n<p><p>En France, une action en justice telle que celle attent\u00e9e par les humanistes la\u00efcs du  C<em>enter For Inquiry<\/em>  ne peut avoir lieu.<\/p>\n<\/p>\n<p><p>D&rsquo;abord parce que les pilules hom\u00e9opathiques, rembours\u00e9es partiellement par la S\u00e9curit\u00e9 Sociale, ne sont distribu\u00e9es qu&rsquo;en officine et non dans des supermarch\u00e9s.<\/p>\n<\/p>\n<p><p>Ensuite parce qu&rsquo;il est inconcevable de malmener la masse des patients potentiels qui &lsquo;croient&rsquo; en cette m\u00e9decine douce.  Les m\u00e9decins qui revendiquent la pratique de cette sp\u00e9cialit\u00e9 re\u00e7oivent un enseignement de moins de 200 heures r\u00e9parties sur deux \u00e0 trois ans. Les praticiens qui lui sont favorables plaident pour son innocuit\u00e9, l&rsquo;absence totale d&rsquo;effets secondaires serait plut\u00f4t p\u00e9jorative car toute substance r\u00e9ellement active entra&icirc;ne au moins des effets ind\u00e9sirables idiosyncrasiques chez certains sujets.<\/p>\n<\/p>\n<p><p>L&rsquo;Acad\u00e9mie de M\u00e9decine avait d\u00e9j\u00e0 \u00e9mis son avis dans des rapports remis en 1984, 1987 et 2004, elle y demandait la suspension des cours universitaires &lsquo;dipl\u00f4mant&rsquo;  et l&rsquo;arr\u00eat du remboursement par la S\u00e9curit\u00e9 Sociale des m\u00e9dicaments en l&rsquo;absence de preuve scientifique rigoureuse de leur efficacit\u00e9. <a href=\"https:\/\/www.industriepharma.fr\/homeopathie-le-ministre-de-la-sante-contre-le-deremboursement-de-l-homeopathie,19870#https:\/\/www.industriepharma.fr\/homeopathie-le-ministre-de-la-sante-contre-le-deremboursement-de-l-homeopathie,19870\">En 2004<\/a>, Philippe Douste-Blazy, alors ministre de la Sant\u00e9, obtemp\u00e9rant sans doute \u00e0 quelque pression, n&rsquo;avait pas suivi l&rsquo;avis de l&rsquo;Acad\u00e9mie.  <a href=\"http:\/\/www.academie-medecine.fr\/lhomeopathie-en-france-position-de-lacademie-nationale-de-medecine-et-de-lacademie-nationale-de-pharmacie\/#http:\/\/www.academie-medecine.fr\/lhomeopathie-en-france-position-de-lacademie-nationale-de-medecine-et-de-la\">Fin mars 2019<\/a>, de nouveau, l&rsquo;Acad\u00e9mie a produit un communiqu\u00e9 de presse dans lequel elle r\u00e9it\u00e8re ses recommandations de d\u00e9remboursement et de la suppression de l&rsquo;enseignement au sein de l&rsquo;Universit\u00e9 d&rsquo;une technique qui n&rsquo;a pas fait ses preuves pour lui retirer toute pr\u00e9tention scientifique. La Haute Autorit\u00e9 de Sant\u00e9 rendra son verdict ce mois-ci en juin 2019 dans le cadre d&rsquo;un d\u00e9cret qui donne un cadre juridique \u00e0 cette \u00e9valuation. Il existe deux cat\u00e9gories de m\u00e9dicaments hom\u00e9opathiques.  Ceux qui ont re\u00e7u une AMM de la part de l&rsquo;Agence fran\u00e7aise du m\u00e9dicament, commercialis\u00e9s sous un nom de marque avec une notice conforme au r\u00e9sum\u00e9 des caract\u00e9ristiques.  &Eacute;ligibles au remboursement, ils ne le sont que rarement. Les autres ont une d\u00e9nomination latine, celle de la souche concern\u00e9e avec en indice la dilution. Ils n&rsquo;ont pas d&rsquo;autorisation de mise sur le march\u00e9 mais sont enregistr\u00e9s aupr\u00e8s de l &lsquo;ANSM sous la triple condition de n&rsquo;\u00eatre d\u00e9livr\u00e9s que sous forme orale ou externe, d&rsquo;avoir une dilution suffisamment importante pour \u00eatre inoffensifs  et de ne pas avoir sur l&rsquo;\u00e9tiquetage d&rsquo;indication th\u00e9rapeutique.  Cette cat\u00e9gorie est remboursable \u00e0 30% depuis 1960. Ce sont ces 1200 m\u00e9dicaments \u00e0 nom commun qui seront examin\u00e9s par la Commission de transparence selon les crit\u00e8res d&rsquo;int\u00e9r\u00eat pour la sant\u00e9 publique, la gravit\u00e9 des maladies auxquels ils sont destin\u00e9s, leur place dans la strat\u00e9gie th\u00e9rapeutique.<\/p>\n<\/p>\n<p><p>En France et aux Usa, la raison scientifique emprunte des voies diff\u00e9rentes pour se faire entendre, mais le r\u00e9sultat  sera dans les deux toujours tributaire d&rsquo;un rapport de forces politique et \u00e9conomique. <\/p>\n<\/p>\n<p><p> Du Rififi chez les g\u00e9n\u00e9riqueurs, Teva en t\u00eate.<\/p>\n<\/p>\n<p><p> Un peu plus t\u00f4t dans le joli mois de mai, une autre proc\u00e9dure judiciaire concernant les m\u00e9dicaments et leurs fabricants a \u00e9t\u00e9 lanc\u00e9e dans ces m\u00eames USA o&ugrave; les questions politiques de fond se d\u00e9battent souvent dans l&rsquo;ar\u00e8ne judiciaire.<\/p>\n<\/p>\n<p><p>43 Etats et Porto Rico accusent des firmes pharmaceutiques <a href=\"https:\/\/eu.usatoday.com\/story\/news\/health\/2019\/05\/13\/teva-and-other-generic-drug-makers-accused-price-fixing\/1190531001\/#https:\/\/eu.usatoday.com\/story\/news\/health\/2019\/05\/13\/teva-and-other-generic-drug-makers-accused-price-fixing\/1190531001\/\">d&rsquo;entente sur les prix,<\/a>contrevenant aux lois anti-trust. Le volumineux dossier de la plainte, lourd de 500 pages, a \u00e9t\u00e9 jug\u00e9 recevable par le Procureur du Connecticut ce 11 mai. Il met en cause deux g\u00e9ants de la pharmacie et quelques entreprises mineures, un total d&rsquo;une vingtaine de firmes. Parmi les &lsquo;Big&rsquo;, Mylan s&rsquo;\u00e9tait distingu\u00e9 <a href=\"https:\/\/www.ouest-france.fr\/monde\/etats-unis\/polemique-aux-etats-unis-le-prix-dun-vaccin-passe-de-100-600-4435914#https:\/\/www.ouest-france.fr\/monde\/etats-unis\/polemique-aux-etats-unis-le-prix-dun-vaccin-passe-de-100-600-4435914\">en multipliant par 6<\/a>le prix d&rsquo;une adr\u00e9naline auto-injectable par stylo largement prescrite pour les allergiques qui risquent de faire des chocs anaphylactiques.  La mol\u00e9cule, hormone m\u00e9dullo-surr\u00e9nalienne identifi\u00e9e depuis plus d&rsquo;un si\u00e8cle n&rsquo;est pas brevet\u00e9e et le dispositif est assez banal puisque des analogues existent depuis longtemps pour les patients diab\u00e9tiques. Les caisses de s\u00e9curit\u00e9 sociale ne pouvaient que s&rsquo;\u00e9mouvoir devant un prix qui passe de 100 \u00e0 600 dollars sans raison. Pfizer s&rsquo;\u00e9tait illustr\u00e9 en participant \u00e0 la hausse d&rsquo;un m\u00e9dicament peu on\u00e9reux initialement (2,83 &pound;). Il a revendu  <a href=\"https:\/\/www.capital.fr\/entreprises-marches\/amende-record-pour-pfizer-apres-d-enormes-hausses-de-prix-1191560#https:\/\/www.capital.fr\/entreprises-marches\/amende-record-pour-pfizer-apres-d-enormes-hausses-de-prix-1191560\">les droits de la ph\u00e9nito\u00efne<\/a>  sodique au laboratoire Flynn  dont le prix a subitement grimp\u00e9 \u00e0 67,50&pound; car la cession avait affranchi la mol\u00e9cule du syst\u00e8me britannique de la fixation des prix. Quant \u00e0 Teva, la compagnie isra\u00e9lienne est c\u00e9l\u00e8bre pour \u00eatre devenue le num\u00e9ro un des fabricants des m\u00e9dicaments g\u00e9n\u00e9riques en employant davantage d&rsquo;avocats que de chercheurs en biologie. Ses \u00e9quipes sont dress\u00e9es pour faire tomber les brevets qui prot\u00e8gent les m\u00e9dicaments princeps. Un  <a href=\"https:\/\/www.nytimes.com\/2016\/12\/15\/business\/generic-drug-price-lawsuit-teva-mylan.html#https:\/\/www.nytimes.com\/2016\/12\/15\/business\/generic-drug-price-lawsuit-teva-mylan.html\">proc\u00e8s similaire<\/a>  avait \u00e9t\u00e9 entrepris en 2016 contre Teva, Mylan et quatre autres petites compagnies par 20 &Eacute;tats avec des griefs similaires, inflation des prix d&rsquo;antibiotiques  et des antidiab\u00e9tiques, partage du march\u00e9 et entente. La hausse vertigineuse de certains prix, particuli\u00e8rement marqu\u00e9e depuis 2012, est si flagrante qu&rsquo;elle a indign\u00e9 et  <a href=\"https:\/\/www.zerohedge.com\/news\/2018-07-10\/drug-companies-roll-back-price-hikes-after-trump-warns-we-will-respond#https:\/\/www.zerohedge.com\/news\/2018-07-10\/drug-companies-roll-back-price-hikes-after-trump-warns-we-will-respond\">fait r\u00e9agir<\/a>  l&rsquo;Homme Orange \u00e0 la M\u00e8che Blonde qui gouverne par tweets interpos\u00e9s depuis la Maison Blanche.<\/p>\n<\/p>\n<p><p>Il semble que cette fois-ci malgr\u00e9 toutes les pr\u00e9cautions prises par les membres de ce formidable cartel pour effacer toute trace de la collusion, des preuves mat\u00e9rielles ont \u00e9t\u00e9 produites et 15 personnes sont nomm\u00e9ment accus\u00e9es d&rsquo;avoir conspir\u00e9 pour \u00e9viter toute baisse de prix voire de l&rsquo;augmenter. Chaque firme respecte le p\u00e9rim\u00e8tre du march\u00e9 de ses complices pour ne pas se faire concurrence. Ce sont 1200 m\u00e9dicaments qui sont en cause, de toute nature et de toute forme gal\u00e9nique. Les &Eacute;tats demandent le remboursement des b\u00e9n\u00e9fices ind&ucirc;ment engrang\u00e9s et une r\u00e9paration pour les patients l\u00e9s\u00e9s.<\/p>\n<\/p>\n<p><p> L&rsquo;exception fran\u00e7aise, vraiment ? <\/p>\n<\/p>\n<p><p> Ici encore, une telle proc\u00e9dure ne peut avoir lieu en France.<\/p>\n<\/p>\n<p><p>Contrairement aux Usa, au Royaume Uni et \u00e0 l&rsquo;Allemagne, les prix des m\u00e9dicaments sont n\u00e9goci\u00e9s entre les firmes et le Comit\u00e9 \u00e9conomique des produits de sant\u00e9 CEPS apr\u00e8s avis donn\u00e9 par la Haute Autorit\u00e9 de Sant\u00e9 sur le service m\u00e9dical rendu ou son am\u00e9lioration. Le m\u00e9canisme d&rsquo;attribution du prix tient compte du prix des m\u00e9dicaments \u00e9quivalents ou relatifs \u00e0 la m\u00eame pathologie d\u00e9j\u00e0 existant sur le march\u00e9, du volume escompt\u00e9 de la vente, du prix fix\u00e9 et pratiqu\u00e9 \u00e0 l&rsquo;\u00e9tranger et du niveau d&rsquo;am\u00e9lioration du syst\u00e8me m\u00e9dical rendu. En r\u00e9alit\u00e9, les n\u00e9gociations sont secr\u00e8tes  et nul n&rsquo;a acc\u00e8s \u00e0 leur motivation, les parties arguent du principe de la protection de la propri\u00e9t\u00e9 intellectuelle et gardent tout \u00e0 fait opaque le processus. Ult\u00e9rieurement, l&rsquo;Union des Caisses d&rsquo;Assurance Maladie appliquera un taux de remboursement en fonction de la gravit\u00e9 de la pathologie et du service m\u00e9dical rendu. <\/p>\n<\/p>\n<p><p>Enfin, l&rsquo;\u00e9tape pr\u00e9alable \u00e0 toutes ces d\u00e9marches consiste pour le fabricant \u00e0 obtenir une autorisation de mise sur le march\u00e9 aupr\u00e8s de la HAS qui juge de l&rsquo;utilit\u00e9 du produit et dont l&rsquo;ind\u00e9pendance est souvent battue en br\u00e8che. <\/p>\n<\/p>\n<p><p>Apr\u00e8s le scandale du Mediator, une loi, dite loi Xavier Bertrand fut promulgu\u00e9e en 2011. Elle oblige tous les acteurs de la Sant\u00e9 \u00e0 d\u00e9clarer publiquement leurs liens de conflits d&rsquo;int\u00e9r\u00eats et concerne donc professions m\u00e9dicales, \u00e9tudiants, soci\u00e9t\u00e9s savantes, associations scientifiques, et experts. Ces auto-d\u00e9clarations sont tr\u00e8s rarement contr\u00f4l\u00e9es. Les membres du CEPM en ont \u00e9t\u00e9 \u00e9pargn\u00e9s apr\u00e8s un arr\u00eat\u00e9 pris en 2012.<\/p>\n<\/p>\n<p><p>La Cour des Comptes elle-m\u00eame se plaint  et elle a d\u00e9plor\u00e9 en 2016  qu&rsquo;il n&rsquo;\u00e9tait pas simple de rendre compte ais\u00e9ment des liens entre les professionnels de sant\u00e9 et le monde industriel.<\/p>\n<\/p>\n<p><p>La loi dispense les industries de d\u00e9clarer les r\u00e9mun\u00e9rations accord\u00e9es dans le cadre de recherche par exemple. Dans le cas d&rsquo;un traitement antiviral pour l&rsquo;h\u00e9patite C, deux experts sur trois avaient b\u00e9n\u00e9fici\u00e9 de r\u00e9tributions du laboratoire. Il est vrai que dans certaines situations qui requi\u00e8rent une sp\u00e9cialisation tr\u00e8s pointue, il est difficile de trouver des experts sans conflits d&rsquo;int\u00e9r\u00eats<\/p>\n<\/p>\n<p><p>Le m\u00e9dicament est un domaine assez \u00e9trange o&ugrave; le co&ucirc;t de la production, recherche et d\u00e9veloppement inclus, n&rsquo;entre pas en ligne de compte pour la fixation d&rsquo;un prix pay\u00e9 cependant par la collectivit\u00e9 et les efforts de chacun au travers des cotisations pr\u00e9lev\u00e9es sur le salaire.<\/p>\n<\/p>\n<p><p>La d\u00e9composition du co&ucirc;t industriel selon des conseils en strat\u00e9gie pharmaceutique sous-estime syst\u00e9matiquement la part allou\u00e9e \u00e0 la &lsquo;promotion&rsquo;, c&rsquo;est-\u00e0-dire la publicit\u00e9 alors que la production proprement dite  <a href=\"https:\/\/www.usinenouvelle.com\/article\/l-industrie-pharmaceutique-joue-la-carte-du-patriotisme-pour-demander-des-aides.N291507#https:\/\/www.usinenouvelle.com\/article\/l-industrie-pharmaceutique-joue-la-carte-du-patriotisme-pour-demander-des-aides.N2\">repr\u00e9sente au plus 10%<\/a>  de ce prix. Le budget marketing est toujours sup\u00e9rieur  <a href=\"https:\/\/naturalsociety.com\/research-development-new-drugs-not-paying-off-6321\/#https:\/\/naturalsociety.com\/research-development-new-drugs-not-paying-off-6321\/\">de deux \u00e0 trois fois  \u00e0 celui de la recherche<\/a>  et du d\u00e9veloppement pour les plus grosses firmes pharmaceutiques. Contrairement \u00e0 ce qu&rsquo;elles avancent pour justifier cette part toujours croissante  du budget publicitaire, mieux informer le patient sur sa pathologie pour une meilleure prise en charge, plus de 60% sont consacr\u00e9s \u00e0 persuader les prescripteurs, \u00e0 savoir les m\u00e9decins. Si les repas, les voyages et autres cadeaux en nature sont en principe de plus en plus s\u00e9v\u00e8rement surveill\u00e9s, les firmes optent pour s\u00e9duire le m\u00e9decin de le faire participer \u00e0 des \u00e9tudes cliniques de pi\u00e8tre qualit\u00e9 en g\u00e9n\u00e9ral, grassement pay\u00e9es. <\/p>\n<\/p>\n<p><p>Les travaux qui rendent compte de la profitabilit\u00e9 du secteur pharmaceutique sont rares tant la profession reste discr\u00e8te sur ses comptes, mais on estime que la recherche et le d\u00e9veloppement rentre pour 10% du prix fournisseur hors taxe et que les b\u00e9n\u00e9fices empoch\u00e9s avoisinent 30 \u00e0 40% du PFHT faisant que cette industrie est tr\u00e8s rentable avec un rendement sup\u00e9rieur \u00e0 l&rsquo;industrie financi\u00e8re. <\/p>\n<\/p>\n<p><p>Ce taux de profit explique l&rsquo;int\u00e9r\u00eat des firmes pour la fabrication des g\u00e9n\u00e9riques et leur intense lobbying aupr\u00e8s des &Eacute;tats. Ainsi en France quand l&rsquo;abattement de 60% est appliqu\u00e9 sur la mol\u00e9cule tomb\u00e9e dans le domaine public, le co&ucirc;t industriel de 10% au maximum laisse une marge tr\u00e8s importante y compris quand un nouvel abattement de 7% est ensuite appliqu\u00e9 au bout d&rsquo;un d\u00e9lai de 18 mois apr\u00e8s la premi\u00e8re d\u00e9cote. <\/p>\n<\/p>\n<p><p>Actuellement le co&ucirc;t de l&rsquo;argent pour les puissantes firmes est tr\u00e8s bas voire n\u00e9gatif compte tenu de l&rsquo;inflation rend plus ais\u00e9 de se lancer dans l&rsquo;aventure de fabrication des g\u00e9n\u00e9riques. En toute rigueur, le prix devrait \u00eatre divis\u00e9 par 10 voire plus si les &Eacute;tats veillaient r\u00e9ellement aux deniers que les cotisants versent aux organismes de s\u00e9curit\u00e9 sociale.<\/p>\n<\/p>\n<p><p> Industrie non innovante.<\/p>\n<\/p>\n<p><p> Un tel engouement pour les g\u00e9n\u00e9riques (car tout le monde s&rsquo;y met) tient donc \u00e0 la forte rentabilit\u00e9 assur\u00e9e de cette production malgr\u00e9 le grand nombre d&rsquo;intervenants sur le march\u00e9. La comp\u00e9tition se fait comme toujours sur la baisse du prix de la production, la plupart des firmes l&rsquo;exportent vers des pays \u00e0 bas co&ucirc;t des salari\u00e9s. L&rsquo;\u00e9t\u00e9 2018, la contamination d&rsquo;anti-tenseurs de la famille des sartans par des nitrosamines a permis de d\u00e9couvrir qu&rsquo;ils \u00e9taient fabriqu\u00e9s en Chine et que le contr\u00f4le de qualit\u00e9 n&rsquo;\u00e9tait pas assur\u00e9 correctement par les g\u00e9n\u00e9riqueurs occidentaux dont Teva. <\/p>\n<\/p>\n<p><p>D&rsquo;autres raisons majeures expliquent cet afflux.<\/p>\n<\/p>\n<p><p>En particulier, l&rsquo;industrie pharmaceutique est de moins en moins innovante.<\/p>\n<\/p>\n<p><p>Pour une ann\u00e9e moyenne, selon la revue Prescrire&reg; dont les analyses objectives sont incontestables car les r\u00e9dacteurs des \u00e9valuations qu&rsquo;elle publie n&rsquo;ont sans doute aucun de lien d&rsquo;int\u00e9r\u00eat de quelques nature que ce soit avec l&rsquo;industrie, sur cent mol\u00e9cules &lsquo;nouvelles&rsquo; mises sur le march\u00e9, trois apportent une avanc\u00e9e th\u00e9rapeutique mineure, soixante seize rien de nouveau et dix neuf pr\u00e9sentent d&rsquo;\u00e9ventuels risque de sant\u00e9 publique. Ainsi la plupart sont des &lsquo;me too&rsquo; c&rsquo;est-\u00e0-dire des copies d&rsquo;existantes avec des similarit\u00e9s tr\u00e8s \u00e9troites, elles n&rsquo;ont \u00e9t\u00e9 d\u00e9velopp\u00e9es que dans le but de prendre des parts de march\u00e9. Les rares m\u00e9dicaments innovants se font conna&icirc;tre bruyamment par leur co&ucirc;t vraiment excessif, Gilead le fabricant du sofosbuvir pour le  <a href=\"https:\/\/www.lequotidiendupharmacien.fr\/actualite\/article\/2017\/03\/31\/hepatite-c-baisse-de-prix-de-la-cure-de-sovaldi_265426#https:\/\/www.lequotidiendupharmacien.fr\/actualite\/article\/2017\/03\/31\/hepatite-c-baisse-de-prix-de-la-cure-de-sovaldi_265426\">traitement de l&rsquo;h\u00e9patite C<\/a>  a fini par faire passer la cure de 12 semaines de 41 000 euros \u00e0 28 700 euros sous pression de l&rsquo;&Eacute;tat fran\u00e7ais  soit encore cent fois le prix de revient.<\/p>\n<\/p>\n<p><p>Cette inertie dans l&rsquo;innovation tient certes \u00e0 la raison d\u00e9j\u00e0 \u00e9voqu\u00e9e que la production d&rsquo;une mol\u00e9cule similaire \u00e0 une existante ou simplement le d\u00e9veloppement d&rsquo;une cha&icirc;ne de g\u00e9n\u00e9riques est une activit\u00e9 suffisamment rentable en soi  sans avoir \u00e0 s&#8217;embarrasser d&rsquo;\u00e9quipes de chercheurs ni d&rsquo;investir du temps dans les essais cliniques.  Il faut signaler tout de m\u00eame \u00e0 propos de ces fameux essais cliniques dont les donn\u00e9es brutes ne sont pas accessibles que le niveau d&rsquo;exigence des preuves de l&rsquo;efficacit\u00e9 et de l&rsquo;innocuit\u00e9 de la part des organismes de contr\u00f4le et de surveillance est de plus en plus faible. De plus en plus, les firmes continuent de r\u00e9aliser leurs  essais de phase 3  apr\u00e8s obtention d&rsquo;une AMM vite accord\u00e9e, faisant peser sur les caisses le co&ucirc;t de la recherche tout en faisant courir des risques aux patients trait\u00e9s devenus de vrais cobayes \u00e0 leur insu.<\/p>\n<\/p>\n<p><p>Mais l&rsquo;autre facteur majeur du manque d&rsquo;innovation tient au manque de perc\u00e9e scientifique dans la recherche fondamentale publique. Car c&rsquo;est la recherche publique pay\u00e9e par les citoyens qui a toujours fourni la mati\u00e8re au d\u00e9veloppement des mol\u00e9cules par le secteur priv\u00e9. L&rsquo;aust\u00e9rit\u00e9 retenue comme hygi\u00e8ne mentale et budg\u00e9taire impos\u00e9e par le capitalisme pour assurer une source de profit pour le secteur financier priv\u00e9 a amoindri les dotations pour le secteur de la recherche publique, particuli\u00e8rement la fondamentale. Cette situation est g\u00e9n\u00e9ralis\u00e9e aux pays dits d\u00e9velopp\u00e9s occidentaux. En France, les mouvements de protestation des \u00e9tudiants et des enseignants-chercheurs de 2007 \u00e0 2009 ont tent\u00e9 de s&rsquo;opposer en vain \u00e0 l&rsquo;autonomisation des Universit\u00e9s avec suppression de postes \u00e0 la cl\u00e9, autre fa\u00e7on de dire  la marche vers la privatisation de l&rsquo;universit\u00e9  <a href=\"https:\/\/fresques.ina.fr\/jalons\/fiche-media\/InaEdu04903\/la-greve-des-enseignants-chercheurs.html#https:\/\/fresques.ina.fr\/jalons\/fiche-media\/InaEdu04903\/la-greve-des-enseignants-chercheurs.html\">sous le gouvernement de Sark\u00f6zy<\/a>. Le d\u00e9cret a fini par passer en avril 2009. <\/p>\n<\/p>\n<p><p>La raret\u00e9 des postes est un facteur aggravant. Il exalte le syst\u00e8me du mandarinat o&ugrave; les postulants sont coopt\u00e9s pour leur docilit\u00e9 et\/ou proximit\u00e9, ce qui pervertit la s\u00e9lection car ce ne sont pas les plus motiv\u00e9s qui seront retenus. Le financement des travaux par le secteur priv\u00e9 qui alloue des bourses \u00e0 des doctorants  dans le cadre du partenariat public-priv\u00e9 oriente les efforts vers le domaine de la recherche appliqu\u00e9e  potentiellement convertissable en produits commercialisable. De la sorte, le priv\u00e9 se fournit en main d&rsquo;&oelig;uvre intellectuelle peu on\u00e9reuse sans engagement vers la cr\u00e9ation d&#8217;emploi, pr\u00e9carisant et d\u00e9courageant ceux qui devraient constituer l&rsquo;\u00e9lite du pays.<\/p>\n<\/p>\n<p><p>La n\u00e9cessaire course aux publications pour exister en tant que chercheur ou unit\u00e9 de recherche et collecter des fonds pour financer les travaux est chronophage et g\u00e9n\u00e8re des travaux de faible qualit\u00e9, pas suffisamment valid\u00e9s. Cette situation a permis que de plus en plus des travaux publi\u00e9s sont entach\u00e9s de fraudes qui lorsqu&rsquo;elles sont d\u00e9couvertes, toujours tardivement, n&rsquo;ont pas de cons\u00e9quence importante. <\/p>\n<\/p>\n<p><p>Enfin, la religion de l&rsquo;argent-Roi ayant fait de plus en plus d&rsquo;adeptes, les jeunes gens les plus dou\u00e9s scolairement de leur g\u00e9n\u00e9ration se d\u00e9tournent de la science pour aller en masse se former dans des \u00e9coles de commerce et de finance, l\u00e0 o&ugrave; le salaire est d\u00e9cupl\u00e9 par rapport \u00e0 celui d&rsquo;un chercheur du CNRS ou de l&rsquo;INSERM qui ne peut m\u00eame plus se pr\u00e9valoir de la satisfaction apport\u00e9e par son travail. Trop souvent les outils qu&rsquo;il est amen\u00e9 \u00e0 manipuler lui \u00e9chappent, instruments de mesure, mat\u00e9riel et y compris concepts sont octroy\u00e9s par le secteur priv\u00e9, le transformant en prol\u00e9taire. C&rsquo;est-\u00e0-dire en un travailleur qui n&rsquo;a pas la ma&icirc;trise de ce qu&rsquo;il produit.<\/p>\n<\/p>\n<p><p>L&rsquo;invention de maladies et leurs traitements.<\/p>\n<\/p>\n<p><p>En manque de nouvelles mol\u00e9cules, les firmes pharmaceutiques vont augmenter la surface de leur vente par deux moyens en ciblant des populations non malades. Elles les persuadent qu&rsquo;elles le sont pour les amener \u00e0 consommer.<\/p>\n<\/p>\n<p><p>La premi\u00e8re technique consiste \u00e0 abaisser le seuil de d\u00e9finition des maladies comme pour le cholest\u00e9rol et l&rsquo;hypertension art\u00e9rielle. Le march\u00e9 des statines a explos\u00e9 \u00e0 chaque fois que les soci\u00e9t\u00e9s savantes de cardiologie ont d\u00e9cid\u00e9 d&rsquo;un taux plus bas de quelques points pour la pr\u00e9vention des maladies cardiovasculaires primaire et secondaire. Le facteur taux de cholest\u00e9rol LDL circulant en exc\u00e8s joue bien un r\u00f4le dans l&rsquo;ath\u00e9rome et les accidents vasculaires mais son poids est bien moindre que le tabagisme et la s\u00e9dentarit\u00e9 qui eux sont tr\u00e8s peu pris en charge. On peut citer dans cet ordre d&rsquo;id\u00e9es le vaccin contre le Papilloma virus dans la pr\u00e9vention du cancer du col de l&rsquo;ut\u00e9rus (3500 nouveaux cas par an). Tous les cancers du col ne sont pas li\u00e9s \u00e0 la d\u00e9g\u00e9n\u00e9rescence de cette infection virale b\u00e9nigne. De plus, le vaccin ne dispense pas d&rsquo;une surveillance gyn\u00e9cologique r\u00e9guli\u00e8re avec frottis. Les &laquo; anti-Vaxx &raquo; qui ont toujours exist\u00e9 depuis l&rsquo;invention de la vaccination ont tort quand ils voient dans le vaccin un risque de maladie auto-immune ou neuro-d\u00e9g\u00e9n\u00e9rative. Ils n\u00e9gligent de s&rsquo;interroger sur l&rsquo;apport b\u00e9n\u00e9fique attendu en terme de sant\u00e9 publique d&rsquo;une vaccination de millions de jeunes filles qui seront amen\u00e9es \u00e0 \u00eatre suivies de toutes les fa\u00e7ons r\u00e9guli\u00e8rement comme en l&rsquo;absence de vaccination et auxquelles seront prodigu\u00e9es du moins c&rsquo;est esp\u00e9r\u00e9 les conseils de pr\u00e9vention des maladies transmises sexuellement dont fait partie le papilloma mais aussi celui de l&rsquo;HIV et des h\u00e9patites. <\/p>\n<\/p>\n<p><p>L&rsquo;autre versant qui vient accro&icirc;tre les profits des firmes pharmaceutiques consiste \u00e0 inventer des domaines d&rsquo;application nouveaux \u00e0 des mol\u00e9cules existantes. <\/p>\n<\/p>\n<p><p>Le probl\u00e8me avait \u00e9t\u00e9 soulev\u00e9 et discut\u00e9 d\u00e8s 1992 par  <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC1122872\/#https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC1122872\/\">Lyn Payer<\/a>  qui a utilis\u00e9 pour la premi\u00e8re fois l&rsquo;expression de &laquo; disease mongering&raquo;. Par exemple, des maladies rares ou des complications exceptionnelles de maladies insignifiantes deviennent par des campagnes bien orchestr\u00e9es un probl\u00e8me de sant\u00e9 publique. En 2009, la pand\u00e9mie de la grippe H1N1 qui n&rsquo;a jamais eu lieu alors qu&rsquo;elle fut prise tr\u00e8s au s\u00e9rieux par l&rsquo;OMS dirig\u00e9e \u00e0 l&rsquo;\u00e9poque par une femme avec des  <a href=\"http:\/\/www.lefigaro.fr\/flash-actu\/2010\/06\/04\/97001-20100604FILWWW00484-h1n1-une-enquete-epingle-l-oms.php#http:\/\/www.lefigaro.fr\/flash-actu\/2010\/06\/04\/97001-20100604FILWWW00484-h1n1-une-enquete-epingle-l-oms.php\">liens de conflits d&rsquo;int\u00e9r\u00eats<\/a>  assez vite d\u00e9montr\u00e9s en est une variante. Cette strat\u00e9gie s&rsquo;est av\u00e9r\u00e9e un moyen puissant de transformer la perception d&rsquo;une population d&rsquo;une affection sans gravit\u00e9 par des op\u00e9rations de marketing qui s&rsquo;adressent d&rsquo;abord aux prescripteurs. Un d\u00e9marchage aupr\u00e8s des leaders d&rsquo;opinion &lsquo;les Ma&icirc;tres en sciences es v\u00e9rit\u00e9&rsquo; charismatiques, ayant titulature et chaire, est la premi\u00e8re \u00e9tape. Chefs de service renomm\u00e9s, experts connus et m\u00e9diatis\u00e9s, puis m\u00e9decins hospitaliers et ensuite de ville avant de descendre dans les m\u00e9dias grand public. C&rsquo;est dans cet ordre que se distribue et se pr\u00eache la bonne parole. <\/p>\n<\/p>\n<p><p>C&rsquo;est tout le probl\u00e8me de l&rsquo;invention de nouvelles pathologies en particulier en psychiatrie o&ugrave; l&rsquo;on ne dispose pas de marqueur biologique ni d&rsquo;imagerie pour d\u00e9finir rigoureusement les cadres nosologiques. Le Manuel de diagnostic et de statistiques des troubles mentaux \u00e9labor\u00e9 par l&rsquo;Association am\u00e9ricaine de psychiatrie APA a r\u00e9pertori\u00e9 plus de 430 maladies psychiatriques lors de sa derni\u00e8re mouture en 2013. En 1952, on en d\u00e9nombrait seulement 106 environ. Un syndrome pr\u00e9menstruel banal devient un trouble dysphorique pr\u00e9menstruel. Une panne sexuelle devient un trouble \u00e9rectile. Un enfant plein de vie turbulent devient un hyperactif. Un chagrin apr\u00e8s la perte d&rsquo;un proche devient une d\u00e9pression.<\/p>\n<\/p>\n<p><p>Glaxo a contribu\u00e9 \u00e0 inventer le maladie de phobie sociale pour \u00e9tendre le champ d&rsquo;application de son antid\u00e9presseur &reg;Paxil en 1999 aux personnes timides et introverties. Pfizer a invent\u00e9 le syndrome post-traumatique pour son &reg;Zoloft. <\/p>\n<\/p>\n<p><p>En quelques ann\u00e9es, depuis 1994, le diagnostic de bipolarit\u00e9 a explos\u00e9 de 4000% chez les enfants avec une multiplication par 5 de prescription de psychotropes.<\/p>\n<\/p>\n<p><p>L&rsquo;OMS se fonde sur les travaux de l&rsquo;APA , elle ne repr\u00e9sente que 7% des psychiatres \u00e9tasuniens, et de son manuel DSM, enseign\u00e9 partout dans le monde o&ugrave; le facteur biologique est mis en avant au d\u00e9triment des conditions sociales et du contexte psychologique du patient. Elle consid\u00e8re qu&rsquo;il existe 400 millions de malades souffrant de troubles mentaux dans le monde. A mettre sous camisole chimique de toute urgence.<\/p>\n<\/p>\n<p><p> De Charybde en Sylla.<\/p>\n<\/p>\n<p><p> L&rsquo;illimitation dans la cupidit\u00e9 des laboratoires pharmaceutiques est garantie par l&rsquo;absence de syst\u00e8me de contr\u00f4le efficace de leur activit\u00e9 qui n&rsquo;est pas de concourir au bien-\u00eatre et \u00e0 la bonne sant\u00e9 de la population. <\/p>\n<\/p>\n<p><p>Ce sont les laboratoires qui d\u00e9terminent les fronti\u00e8res de cette bonne sant\u00e9 et fournissent les moyens chimiques d&rsquo;y parvenir.<\/p>\n<\/p>\n<p><p>Les proc\u00e8s contre les g\u00e9n\u00e9riqueurs aux USA finiront sans doute par le paiement d&rsquo;une amende d\u00e9risoire eu \u00e9gard aux b\u00e9n\u00e9fices engrang\u00e9s.<\/p>\n<\/p>\n<p><p>En France, la HAS aura-t-elle le courage d&rsquo;appliquer les recommandations de l&rsquo;Acad\u00e9mie de M\u00e9decine d\u00e9j\u00e0 formul\u00e9es en 1987 vis-\u00e0-vis de l&rsquo;hom\u00e9opathie ?<\/p>\n<\/p>\n<p><p>L&rsquo;escroquerie patent\u00e9e de Big Pharma conduit certains \u00e0 adopter une attitude de  &lsquo;croyance&rsquo; dans les m\u00e9decines dites douces &lsquo;alternatives&rsquo; sans efficacit\u00e9 prouv\u00e9e. Elle a contribu\u00e9 \u00e0 faire r\u00e9cuser par de plus en plus de sceptiques tout l&rsquo;apport de si\u00e8cles de travail scientifique exp\u00e9rimental et th\u00e9orique. Cette croyance a conduit \u00e0 la cr\u00e9ation d&#8217;empires industriels tr\u00e8s lucratifs bas\u00e9s sur la vente de m\u00e9dicaments sans substrat actif, performance dans l&rsquo;escroquerie d&rsquo;un degr\u00e9 sup\u00e9rieur \u00e0 l&rsquo;allopathie.<\/p>\n<\/p>\n<p><p>Cette industrie de l&rsquo;escroquerie en col blanc et blouse blanche fonctionne \u00e0 merveille, on en consomme \u00e0 volont\u00e9. Elle est sous-tendue comme les autres par une subjugation mentale obtenue par une propagande adroite, elle contraint les corps et les esprits et on en redemande.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une rasade de Perlimpinpin ? Walmart, la grande cha&icirc;ne de distribution \u00e9tasunienne, est poursuivie en justice pour fraude. Le Center for Inquiry,organisation \u00e0 but non lucratif fond\u00e9e en 1991 sur les bases d&rsquo;un humanisme s\u00e9culier pour lutter contre la superstition et les fausses sciences repr\u00e9sente l&rsquo;institution plaignante. Le CFI accuse Walmart de tromperses clients et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[3953,3566,19132,12187,18895],"class_list":["post-78687","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-badia-benjelloun-1","tag-benjelloun","tag-big","tag-generiques","tag-medicaments","tag-pharma"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78687"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78687\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}