{"id":78713,"date":"2019-06-29T11:04:32","date_gmt":"2019-06-29T11:04:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/06\/29\/gabbardin-memoriamet-la-memoire-courte\/"},"modified":"2019-06-29T11:04:32","modified_gmt":"2019-06-29T11:04:32","slug":"gabbardin-memoriamet-la-memoire-courte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/06\/29\/gabbardin-memoriamet-la-memoire-courte\/","title":{"rendered":"Gabbard\u00a0?\u00a0<em>In Memoriam\u00a0<\/em>et la m\u00e9moire courte"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Gabbard ? <em>In Memoriam <\/em>et la m\u00e9moire courte<\/h2>\n<\/p>\n<p><p>29 juin 2019 &ndash; Il m&rsquo;a paru rien moins que tr\u00e8s int\u00e9ressant de suivre les effets et retomb\u00e9es de l&rsquo;excellente performance, en termes d&rsquo;int\u00e9r\u00eat du public, de Tulsi Gabbard dans le premier des deux d\u00e9bats de la cohorte des candidats \u00e0 la d\u00e9signation d\u00e9mocrate. Le reste, y compris dans le deuxi\u00e8me d\u00e9bat, avec les vieux croutons type-Biden, type-Sanders, &ndash; vraiment aucun int\u00e9r\u00eat, chacun calibrant ses interventions. La fille de McCain (Meghan), aussi inepte que son p\u00e8re, avait pourtant raison dans son tweet retir\u00e9 au bout de quelques toutes petites heures, &ndash; car franchise et honn\u00eatet\u00e9 sont des denr\u00e9es rares, qu&rsquo;il ne faut pas trop gaspiller au nez et la barbe dure des imp\u00e9ratifs d&rsquo;image, de communication et de bienpensance partisane : Gabbard fut \u00ab\u00a0la plus authentique\u00a0\u00bb. Qu&rsquo;en reste-t-il dans le syst\u00e8me de la communication ? Voil\u00e0 l&rsquo;objet de cette intervention.<\/p>\n<\/p>\n<p><p>&#8230; Pratiquement rien pour le Syst\u00e8me, la presseSyst\u00e8me &#038; Cie. Gabbard fut l&rsquo;objet d&rsquo;un d\u00e9ni, d&rsquo;une sorte de n\u00e9gationnisme aupr\u00e8s duquel l'\u00a0\u00bbautre\u00a0\u00bb, le seul acceptable, fait figure de pi\u00e8tre montage. Le d\u00e9ni non-Gabbard est autant \u00ab\u00a0authentique\u00a0\u00bb qu&rsquo;elle le fut elle-m\u00eame&#8230; La bienpensance, ou <em>politically correct<\/em>, c&rsquo;est un peu comme la vache qui rumine : on m\u00e2che deux, trois fois apr\u00e8s r\u00e9gurgitation de l&rsquo;estomac les v\u00e9rit\u00e9s-de-situation jusqu&rsquo;\u00e0 ce qu&rsquo;il n&rsquo;en reste rien, sinon quelques pets malodorants sous forme d&rsquo;articles des sacro-saintes putains des New York <em>Times <\/em>et Washington<em>Post<\/em>du cart\u00e9chisme<em>.<\/em><\/p>\n<\/p>\n<p><p>Pour ce faire ma rapide enqu\u00eate, j&#8217;emprunte deux textes qui situeront la chose : aussi bien un d\u00e9tail engag\u00e9 de l&rsquo;intervention de Gabbard par rapport \u00e0 Trump par un partisan honn\u00eate de Trump quand elle n&rsquo;est pas m\u00e2ch\u00e9e-rem\u00e2ch\u00e9e ; que, pour le second texte, un floril\u00e8ge des r\u00e9actions du Syst\u00e8me dans la presseSyst\u00e8me.<\/p>\n<\/p>\n<p><p>&bull; Le premier est du vieux briscard Patrick Buchanan, un des vieux sages de grande influence cach\u00e9e du parti conservateur, tendance pal\u00e9o, un malgr\u00e9-tout-fid\u00e8le de Trump mais qui ne m\u00e2che pas ses mots quand il pense que son pr\u00e9sident est totalement en, mode erratique de trahison de ses engagements. Le titre en dit d\u00e9j\u00e0 long : &laquo; <em>Memo pour Trump : remplacez Bolton par Gabbard<\/em> &raquo; (chronique de Buchanan sur son site, reprise pour <em><a href=\"http:\/\/www.unz.com\/pbuchanan\/memo-to-trump-trade-bolton-for-tulsi\/\">UNZ.com<\/a><\/em>, o&ugrave; l&rsquo;on voit bien que le vieux-sage se fiche compl\u00e8tement des autres croutons pourris jusqu&rsquo;\u00e0 l&rsquo;os, Sanders, Biden, Warren &#038; Cie).<\/p>\n<\/p>\n<p><p>&laquo; <em>\u00ab\u00a0Pendant trop longtemps, nos dirigeants nous ont laiss\u00e9 tomber, nous entra&icirc;nant d&rsquo;une guerre de regime change \u00e0 l&rsquo;autre, nous menant \u00e0 une nouvelle guerre froide et \u00e0 la course aux armements, ce qui nous a co&ucirc;t\u00e9 des milliards de dollars durement gagn\u00e9s en imp\u00f4ts et d&rsquo;innombrables vies. Cette folie doit cesser.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Donald Trump, circa-2016 ?<\/em><\/p>\n<p>&raquo; <em>Pas du tout. Cette d\u00e9nonciation de l&rsquo;interventionnisme de John Bolton est venue de la d\u00e9put\u00e9e Tulsi Gabbard d&rsquo;Hawa\u00ef lors du d\u00e9bat de parti d\u00e9mocrate de mercredi soir. A 38 ans, elle \u00e9tait la plus jeune candidate sur sc\u00e8ne.<\/em><\/p>\n<p>&raquo; <em>Gabbard a pass\u00e9 \u00e0 la moulinette \u00e0 la fois le \u00ab\u00a0pr\u00e9sident et son cabinet de poule mouill\u00e9e (qui) nous ont men\u00e9s au bord de la guerre avec l&rsquo;Iran\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Au cours d&rsquo;un \u00e9change enflamm\u00e9, le parlementaire Tim Ryan de l&rsquo;Ohio a r\u00e9pondu que l&rsquo;Am\u00e9rique ne peut se d\u00e9sengager de l&rsquo;Afghanistan : \u00ab\u00a0Quand nous n&rsquo;\u00e9tions pas l\u00e0, ils ont commenc\u00e9 \u00e0 lancer des avions contre nos b\u00e2timents.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Les talibans ne nous ont pas attaqu\u00e9s le 11 septembre, r\u00e9pondit Gabbard, Al-Qaida nous a attaqu\u00e9s le 11 septembre. C&rsquo;est pour \u00e7a que moi et tant d&rsquo;autres personnes nous sommes enr\u00f4l\u00e9s dans l&rsquo;arm\u00e9e, pour poursuivre Al-Qa\u00efda, pas les talibans.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Quand Ryan a insist\u00e9 pour qu&rsquo;on reste engag\u00e9s en Afghanistan, Gabbard a ripost\u00e9 :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0C&rsquo;est ce que vous allez dire aux parents de ces deux soldats qui viennent d&rsquo;\u00eatre tu\u00e9s en Afghanistan ? &lsquo;Eh bien oui, nous devons continuer \u00e0 rester engag\u00e9s&rsquo;. En tant que soldat, je vous le dis, cette r\u00e9ponse est inacceptable. &#8230; Nous ne sommes pas en meilleure position aujourd&rsquo;hui en Afghanistan que lorsque cette guerre a commenc\u00e9.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>&Agrave; la fin du d\u00e9bat, Gabbard \u00e9tait le vainqueur incontestable des sondages &lsquo;en-ligne&rsquo; Drudge Report et Washington Examiner, loin devant parmi tous les candidats d\u00e9mocrates dont les noms ont \u00e9t\u00e9 recherch\u00e9s sur Google.<\/em><\/p>\n<p>&raquo; <em>Bien qu&rsquo;on lui ait accord\u00e9 moins de sept minutes de temps de parole dans un d\u00e9bat de deux heures, elle n&rsquo;aurait pas pu utiliser ce temps plus efficacement. Et sa performance pourrait \u00e9branler la campagne USA-2020 d\u00e9mocrate.<\/em><\/p>\n<p>&raquo; <em>Si elle peut se hisser quelques points au-dessus de ses 1 \u00e0 2 % dans les sondages, elle pourrait \u00eatre assur\u00e9e d&rsquo;une place dans la deuxi\u00e8me s\u00e9rie de d\u00e9bats.<\/em><\/p>\n<p>&raquo; <em>Si c&rsquo;est le cas, les mod\u00e9rateurs vont maintenant lui poser des questions de politique \u00e9trang\u00e8re qui ne seraient pas soulev\u00e9es sans sa pr\u00e9sence, et ces questions r\u00e9v\u00e9leront les divisions cach\u00e9es du Parti d\u00e9mocrate.<\/em><\/p>\n<p>&raquo; <em>On pourrait demander aux principaux candidats d\u00e9mocrates de d\u00e9clarer ce que devrait \u00eatre la politique am\u00e9ricaine, non seulement envers l&rsquo;Afghanistan, mais aussi envers l&rsquo;Irak, la Syrie, le Y\u00e9men, l&rsquo;Arabie saoudite, Isra\u00ebl, le &quot;Deal of the Century&quot; de Jared Kushner et le rejet apparent de Trump de la solution \u00e0 deux &Eacute;tats.<\/em><\/p>\n<p>&raquo; <em>Si elle atteint le deuxi\u00e8me tour, Gabbard pourrait devenir le catalyseur du genre de d\u00e9bat mondialiste contre nationaliste qui a \u00e9clat\u00e9 entre Trump et les r\u00e9publicains de Bush en 2016, un d\u00e9bat qui a contribu\u00e9 \u00e0 la victoire de Trump \u00e0 la convention de Cleveland et au vote de novembre.<\/em><\/p>\n<p>&raquo; <em>Le probl\u00e8me que Gabbard pr\u00e9sente pour les d\u00e9mocrates est que, comme on l&rsquo;a vu lors de la joute avec Ryan, elle prend des positions qui divisent son parti, alors que ses rivaux et rivales pr\u00e9f\u00e8rent parler de ce qui unit le parti, comme l&rsquo;affreuse conduite de Trump, les frais de scolarit\u00e9 gratuits et le favoritisme  des riches.<\/em><\/p>\n<p>&raquo; <em>Avec plus de temps d&rsquo;antenne, elle pr\u00e9sentera \u00e9galement des probl\u00e8mes pour le GOP. Car la politique \u00e9trang\u00e8re que Tulsi Gabbard r\u00e9clame n&rsquo;est pas loin de la politique \u00e9trang\u00e8re promise par Donald Trump en 2016, qui n&rsquo;a pas tenu ses promesses depuis<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p><em>&bull; <\/em>Le deuxi\u00e8me  texte est de \u00ab\u00a0b.\u00a0\u00bb, de <em>MoonofAlabama <\/em>(disons MoA), excellent chroniqueur au jour le jour des infamies du Syst\u00e8me, qu&rsquo;il d\u00e9nonce essentiellement \u00e0 l&rsquo;aide de la mise en \u00e9vidence des constructions, des manipulations, des simulacre, du  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a> du Syst\u00e8me. Le <em>Sakerfrancophone <\/em>a eu l&rsquo;heureuse id\u00e9e de suivre MoA en traduction fran\u00e7aise, pratiquement \u00ab\u00a0en temps r\u00e9el\u00a0\u00bb avec le texte initial traduit et mis en ligne dans la journ\u00e9e de sa parution ; il nous donnait <a href=\"https:\/\/lesakerfrancophone.fr\/les-medias-et-le-public-ne-sont-pas-daccord-sur-la-performance-de-tulsi-gabbard-pendant-le-debat-democrate\">donc hier<\/a> l&rsquo;analyse critique de MoA des r\u00e9actions et commentaires qui ont suivi le premier d\u00e9bat o&ugrave; Gabbard a brill\u00e9 jusqu&rsquo;\u00e0 figurer tr\u00e8s largement en t\u00eate de tous les sondages \u00ab\u00a0en-ligne\u00a0\u00bb, ceux que notre site pr\u00e9sentait  <a href=\"https:\/\/www.dedefensa.org\/article\/gabbard-explose-le-premier-debat-democrate\">de cette fa\u00e7on<\/a> qui, je dois le reconna&icirc;tre, me va comme un gant bien ajust\u00e9 : ces sondages &laquo; <em>les moins s&ucirc;rs scientifiquement et sans le professionnalisme des experts du sondage, donc  <strong>les plus assur\u00e9s d&rsquo;\u00eatre proches du v\u00e9ritable sentiment d&rsquo;int\u00e9r\u00eat, sinon de soutien des t\u00e9l\u00e9spectateurs et internautes<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Je ne reprends pas cette premi\u00e8re partie  <a href=\"https:\/\/www.moonofalabama.org\/2019\/06\/media-and-public-disagree-on-tulsi-gabbards-debate-performance.html\">du texte MoA<\/a>, qui doublonne notre brave <em>Br\u00e8ve de crise  <\/em><a href=\"https:\/\/www.dedefensa.org\/article\/gabbard-explose-le-premier-debat-democrate\">du 27 juin<\/a>, mais sa deuxi\u00e8me partie o&ugrave; il est question des r\u00e9actions de la presseSyst\u00e8me \u00e0 propos de l&rsquo;excellente performance de Gabbard, devenue soudain inexistante, invisible, inconnue au bataillon, &ndash; \u00ab\u00a0Gabbard qui, dites-vous ? Jamais entendu ce nom-l\u00e0, qui fait pas tr\u00e8s am\u00e9ricaniste, hein !\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&laquo; <em>Le Washington Post <a href=\"https:\/\/www.washingtonpost.com\/politics\/2019\/06\/27\/winners-losers-democratic-presidential-debates-first-night\/?utm_term=.1715a6c57095\">discute<\/a>  des gagnants et des perdants du d\u00e9bat et place Gabbard dans la deuxi\u00e8me cat\u00e9gorie :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Gabbard \u00e9tait perdue pendant une grande partie du d\u00e9bat. Ce n&rsquo;\u00e9tait peut-\u00eatre pas de sa faute, &ndash; on ne lui a pas pos\u00e9 beaucoup de questions&#8230;\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Oups !<\/em><\/p>\n<p>&raquo; <em>L&rsquo;<a href=\"https:\/\/www.nytimes.com\/2019\/06\/26\/us\/politics\/democratic-debate-2020.html\">article principal<\/a>  du New York Times sur le d\u00e9bat ne mentionne Gabbard qu&rsquo;une seule fois, au paragraphe 32, sur 45 paragraphes. Il ne r\u00e9v\u00e8le rien sur ses positions politiques :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Il y a eu peu de discussions sur la politique \u00e9trang\u00e8re jusqu&rsquo;\u00e0 ce que, vers la fin du d\u00e9bat, deux l\u00e9gislateurs peu connus de la Chambre, Tulsi Gabbard d&rsquo;Hawaii et Tim Ryan de l&rsquo;Ohio, s&rsquo;affrontent sur la fa\u00e7on de cibler les talibans avec d\u00e9termination.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Le New York Times a aussi r\u00e9uni des \u00ab\u00a0experts\u00a0\u00bb qui ont  <a href=\"https:\/\/www.nytimes.com\/2019\/06\/27\/us\/politics\/democratic-debate-winners-losers.html\">discut\u00e9<\/a> des gagnants et des perdants. Gabbard n&rsquo;est mentionn\u00e9 qu&rsquo;\u00e0 la toute fin, et par un r\u00e9publicain, comme candidat potentiel au poste de Secr\u00e9taire \u00e0 la D\u00e9fense.<\/em><\/p>\n<p>&raquo; <em>CNN a aussi discut\u00e9 des  <a href=\"https:\/\/edition.cnn.com\/2019\/06\/26\/politics\/who-won-democratic-debate\/index.html\">gagnants et des perdants<\/a>. Gabbard n&rsquo;y est pas mentionn\u00e9 du tout.<\/em><\/p>\n<p>&raquo; <em>NBC News  <a href=\"https:\/\/www.nbcnews.com\/politics\/2020-election\/who-won-first-democratic-presidential-debate-n1023066\">a class\u00e9<\/a> les performances des candidats. Il a mis Gabbard \u00e0 la 8<sup>\u00e8me <\/sup>place et l&rsquo;enfonce carr\u00e9ment :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Tulsi Gabbard, D-Hawaii : Elle a saisi l&rsquo;occasion de mettre en lumi\u00e8re son exp\u00e9rience militaire en Afghanistan et son point de vue caract\u00e9ristique en mati\u00e8re de politique \u00e9trang\u00e8re puisqu&rsquo;elle est anti-interventionniste, sans \u00eatre g\u00ean\u00e9e par ses sympathiques commentaires pass\u00e9s concernant le dictateur syrien Bachar al-Assad.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>La plupart des m\u00e9dias \u00e9voqu\u00e9s ci-dessus ont pendant longtemps cherch\u00e9 \u00e0 \u00e9viter de mentionner Gabbard et de discuter de ses positions politiques. Il est tout \u00e0 fait \u00e9vident que les m\u00e9dias grand public n&rsquo;aiment pas ses opinions contre la politique de &lsquo;regime change&rsquo; dans le monde et ont m\u00eame peur d&rsquo;\u00e9crire \u00e0 ce sujet.<\/em><\/p>\n<p>&raquo; <em>Le bureau de campagne de Tulsi Gabbard a post\u00e9 une  <a href=\"https:\/\/twitter.com\/TulsiGabbard\/status\/1144130437264154624\">vid\u00e9o<\/a> de ses d\u00e9clarations pendant le d\u00e9bat. Elle y est bien applaudie.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Il y a tout de m\u00eame des remarques incroyables, qui illuminent comme la Tour Eiffel c\u00e9l\u00e9brant un discours de Sa Majest\u00e9 Macron l&rsquo;extraordinaire insignifiance d&rsquo;inversion et de simulacre des plumes vari\u00e9es et color\u00e9es de ces zombies-plumitifs qu&rsquo;on n&rsquo;ose qualifier de \u00ab\u00a0salopards\u00a0\u00bb type-sartrien, &ndash; moi, je m&rsquo;en garderais, ce serait leur faire tout de m\u00eame un peu trop d&rsquo;honneur. Deux exemples : <\/p>\n<\/p>\n<p><p>&bull; Le NYT, qui nous parle de ces &laquo; <em>deux l\u00e9gislateurs peu connus de la Chambre, Tulsi Gabbard d&rsquo;Hawaii et&#8230; <\/em>&raquo;. Ces petites plumes des zombies-plumitifs ont donc la m\u00e9moire aussi courte que leurs autres attributs. Ils ont oubli\u00e9, ces chers anges, le  <a href=\"https:\/\/www.dedefensa.org\/article\/gabbard-2020-dc-la-folle-devient-fou\">tintamarre extraordinaire<\/a> que d\u00e9clencha, en janvier de cette ann\u00e9e, il y a cinq mois d&rsquo;ici, l&rsquo;annonce par Tulsi de sa candidature, &ndash; la candidature-inconnue de cette l\u00e9gislatrice peu-connue dont personne n&rsquo;a jamais parl\u00e9 du tout, pas du tout, pas du tout :<\/p>\n<\/p>\n<p><p>Et donc ceci, datant de janvier 2019 : &laquo; <em>RT-USA, qui n&rsquo;a pas manqu\u00e9 l&rsquo;occasion de sauter sur cette nouvelle, d\u00e9veloppe <a href=\"https:\/\/www.rt.com\/usa\/448632-tulsi-gabbard-negative-reactions\/\">un article<\/a> essentiellement \u00e0 partir d&rsquo;une collection de tweet exprimant l&rsquo;horreur et la confusion absolues qui se sont empar\u00e9es de la m\u00e9nagerie des zombieSyst\u00e8me, neocon &#038; harpies <a href=\"http:\/\/www.dedefensa.org\/article\/hillary-et-ses-harpies-ou-le-feminisme-guerrier\">R2P<\/a>, LGTBQ, DeepState, presseSyst\u00e8me, establishment et toute la clique tonitruante. [J&rsquo;ai fait \u00ab\u00a0Gabbard-2020\u00a0\u00bb sur le sympathique moteur de recherche Google \u00e0 10H30 et ai obtenu 8 780 000 r\u00e9sultats en 0,30 seconde.] Titre de <a href=\"https:\/\/www.rt.com\/usa\/448632-tulsi-gabbard-negative-reactions\/\">l&rsquo;article RT-USA<\/a> : \u00ab\u00a0La &lsquo;marionnette de Poutine&rsquo; contre la &lsquo;complice d&rsquo;Assad&rsquo; : D\u00e9mocrates et R\u00e9publicains unis dans une panique commune \u00e0 l&rsquo;id\u00e9e d&rsquo;une Gabbard d\u00e9fiant Trump en 2020\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; NBC, qui remarque \u00e0 propos de cette faussaire Tulsi : &laquo; <em>Elle a saisi l&rsquo;occasion de mettre en lumi\u00e8re son exp\u00e9rience militaire en Afghanistan&#8230;<\/em> &raquo; Ce ton ! On a l&rsquo;impression \u00e9videmment pleinement justifi\u00e9e que c&rsquo;est une l\u00e2chet\u00e9 et un d\u00e9shonneur incroyables, au milieu de toutes ces h\u00e9ro\u00efques <em>chickenhawks<\/em>(les d\u00e9cor\u00e9es-poulesmouill\u00e9es), de rappeler qu&rsquo;on est all\u00e9 au combat et qu&rsquo;on s&rsquo;est battu dans les guerres qu&rsquo;ils vous concoctent depuis \u00ab\u00a0D.C.-la-folle\u00a0\u00bb. Scandaleuse \u00ab\u00a0<em>Politically Incorrect<\/em>\u00ab\u00a0, la Gabbard.<\/p>\n<\/p>\n<p><p>Tout cela d\u00e9crit, on comprend combien Tulsi Gabbard est une candidate dont il est bien difficile de dire quoi que ce soit d&rsquo;assur\u00e9. On dira bien entendu qu&rsquo;avec 1%-2% de popularit\u00e9 dans les sondages, son avenir pr\u00eate \u00e0 sourire tristement ; pourtant, on note <strong>avec quel z\u00e8le, quelle puissance des habituels montages et <em>narrative<\/em><\/strong>, on s&rsquo;\u00e9vertue \u00e0 d\u00e9montrer son inexistence, sa position de non-\u00eatre en plus d&rsquo;\u00eatre une candidate &laquo; <em>si peu connue<\/em> &raquo;, comme si elle existait vraiment, et dangereuse en plus&#8230; Et puis, si je n&rsquo;ai pas de souvenir pr\u00e9cis de la situation de juin 2015, il m&rsquo;\u00e9tonnerait beaucoup qu&rsquo;il y ait eu plus de 1%, et plut\u00f4t moins d&rsquo;ailleurs, aux USA et dans le monde, pour donner une chance \u00e0 Trump d&rsquo;\u00eatre \u00e9lu en novembre 2016. Le pari de Buchanan, c&rsquo;est celui de la candidate boule de neige : arrivant \u00e0 percer ce qu&rsquo;on nomme dans le baratin des salons d&rsquo;experts \u00ab\u00a0le plafond de verre\u00a0\u00bb, avec un \u00e0 trois points de pour-cent en plus, assez pour rester dans la course et, <strong>par ses positions exprim\u00e9es publiquement, forcer au d\u00e9bat sur la politique ext\u00e9rieure<\/strong>, et l\u00e0 s&rsquo;imposer comme l&rsquo;\u00e9vidente repr\u00e9sentante d&rsquo;une ligne qui pourrait peut-\u00eatre emporter l&rsquo;adh\u00e9sion d&rsquo;un large public si l&rsquo;opinion s&#8217;emparait de la question \u00e0 sa fa\u00e7on&#8230;<\/p>\n<\/p>\n<p><p>On dira : \u00ab\u00a0&lsquo;Ils&rsquo; ne la laisseront pas faire\u00a0\u00bb ; on disait d\u00e9j\u00e0 cela de Trump, <strong>et &lsquo;ils&rsquo; n&rsquo;ont rien pu faire, sinon sottise sur sottise<\/strong>. La caract\u00e9ristique centrale de la situation actuelle \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, comme d&rsquo;ailleurs en de nombreux autres lieux du Syst\u00e8me, ce n&rsquo;est pas tant que de si \u00e9tranges candidats puissent appara&icirc;tre et \u00e9ventuellement s&rsquo;affirmer (et \u00eatre \u00e9lu, comme Trump), <strong>c&rsquo;est que le Syst\u00e8me semble totalement impuissant \u00e0 les arr\u00eater<\/strong>une fois qu&rsquo;ils ont franchi une limite de cr\u00e9dibilit\u00e9 et d'\u00a0\u00bbexistence\u00a0\u00bb, <strong>d&rsquo;ailleurs tr\u00e8s difficile \u00e0 identifier et donc \u00e0 pr\u00e9venir et \u00e0 bloquer<\/strong>, dans le syst\u00e8me de la communication.<\/p>\n<\/p>\n<blockquote>\n<p><p>Le grand ph\u00e9nom\u00e8ne de notre temps, ce n&rsquo;est pas la mont\u00e9e du populisme, ou de l&rsquo;antiSyst\u00e8me, ou que sais-je encore ; le grand ph\u00e9nom\u00e8ne <strong>c&rsquo;est l&rsquo;effondrement du Syst\u00e8me et l&rsquo;\u00e9talage de son impuissance comme signe de sa d\u00e9rive autodestructrice<\/strong>, avec la sottise en plus. Comme le diable &laquo; <em>ne peut s&#8217;emp\u00eacher de laisser \u00e9chapper toujours <strong>quelque sottise<\/strong>, qui est comme sa signature<\/em>&#8230; &raquo;, et avec le NYT et le <em>Post <\/em>\u00e0 bonne \u00e9cole, il est bien possible qu&rsquo;\u00e0 force de taper sur Gabbard pour ses propos insens\u00e9s, puis \u00e0 nier son existence jusqu&rsquo;\u00e0 en faire un non-\u00eatre, <strong>&lsquo;ils&rsquo; finissent par lui ouvrir une voie inattendue<\/strong>. <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Par cons\u00e9quent, Gabbard n&rsquo;a strictement <strong>aucune chance sauf<\/strong>si la chance, qui est un peu sans emploi en ce moment vue la m\u00e9diocrit\u00e9 des titulaires, passe par l\u00e0 et qu&rsquo;elle s&rsquo;en saisisse. <strong>Rien n&rsquo;est possible, tout est possible<\/strong>. Elle aussi est impr\u00e9visible comme Trump et donc semeuse de d\u00e9sordre, m\u00eame si elle l&rsquo;est d&rsquo;une fa\u00e7on radicalement diff\u00e9rente ; tr\u00e8s mesur\u00e9e et ma&icirc;tresse d&rsquo;elle-m\u00eame, c&rsquo;est ce qu&rsquo;elle <strong>dit tout haut et tr\u00e8s rationnellement de l&rsquo;absurdit\u00e9 de la politique belliciste du Syst\u00e8me<\/strong>qui pourrait un jour \u00e9clater aux yeux de tous, &ndash; vous savez, le coup du <strong>\u00ab\u00a0Mais le roi est nu\u00a0\u00bb<\/strong>, &ndash; et soudain se transformer en un \u00e9norme dynamitage de la chose.<\/p>\n<\/p>\n<p><p>Bref et pour conclure, la saison USA-2020 appara&icirc;t <strong>grosse de l&rsquo;une ou l&rsquo;autre surprise bien rafra&icirc;chissante<\/strong>. Par ces temps de canicule, ce n&rsquo;est pas \u00e0 d\u00e9daigner.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gabbard ? In Memoriam et la m\u00e9moire courte 29 juin 2019 &ndash; Il m&rsquo;a paru rien moins que tr\u00e8s int\u00e9ressant de suivre les effets et retomb\u00e9es de l&rsquo;excellente performance, en termes d&rsquo;int\u00e9r\u00eat du public, de Tulsi Gabbard dans le premier des deux d\u00e9bats de la cohorte des candidats \u00e0 la d\u00e9signation d\u00e9mocrate. Le reste, y&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[19165,3335,3009,2750,15106,16688,12820,7347,2832,18828],"class_list":["post-78713","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-anti-interventionnisme","tag-buchanan","tag-democrates","tag-gabbard","tag-moa","tag-non-etre","tag-pressesysteme","tag-primaires","tag-tulsi","tag-usa-2020"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78713"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78713\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}