{"id":78746,"date":"2019-07-17T16:57:42","date_gmt":"2019-07-17T16:57:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/07\/17\/crise-de-nerfs-civilisationnelle\/"},"modified":"2019-07-17T16:57:42","modified_gmt":"2019-07-17T16:57:42","slug":"crise-de-nerfs-civilisationnelle","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/07\/17\/crise-de-nerfs-civilisationnelle\/","title":{"rendered":"Crise de nerfs civilisationnelle"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Crise de nerfs civilisationnelle<\/h2>\n<\/p>\n<p><p>17 juillet 2019 &ndash; Nous avons mis en ligne <a href=\"https:\/\/www.dedefensa.org\/article\/reglement-de-compte-atwitterland\">hier un texte<\/a> sur une bataille entre les habituels comp\u00e9titeurs \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb (Trump et <em>Trumphaters<\/em>), o&ugrave; le tweet joue un r\u00f4le essentiel. Bien entendu, nous avions \u00e0 l&rsquo;esprit le d\u00e9veloppement que constitue ce <em>F&#038;C&#8230;<\/em>L&rsquo;id\u00e9e centrale de ce texte est de cerner, d&rsquo;identifier, de comprendre, non seulement l&rsquo;usage du tweet en politique, mais toute la probl\u00e9matique des \u00ab\u00a0r\u00e9seaux sociaux\u00a0\u00bb en g\u00e9n\u00e9ral. Nous commen\u00e7ons en en parlant  principalement pour les \u00e9lites, mais en passant plus largement \u00e0 pour tout ce qui constitue la soci\u00e9t\u00e9 quasi-globalis\u00e9e (le \u00ab\u00a0village global\u00a0\u00bb, disons). Nous consid\u00e9rons le probl\u00e8me  dans son sens d&rsquo;abord politique, mais nullement en isolant ce domaine, <strong>au contraire en l&rsquo;offrant comme base de d\u00e9part du th\u00e9\u00e2tre d&rsquo;un v\u00e9ritable effondrement intellectuel qu&rsquo;on pourrait d\u00e9signer comme une \u00ab\u00a0zombification\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>Essentiellement du fait de l&rsquo;intrusion de Trump sur la sc\u00e8ne politique, comme pr\u00e9sident des &Eacute;tats-Unis, <strong>le tweet joue d\u00e9sormais un r\u00f4le essentiel, d&rsquo;abord dans le domaine du syst\u00e8me de la communication <\/strong>dont nombre de personnes oublient, sinon ignorent qu&rsquo;il est beaucoup plus vaste que le seul champ du \u00ab\u00a0sp\u00e9cialiste de la com'\u00a0\u00bb, ou \u00ab\u00a0communiquant\u00a0\u00bb,  faux-nez pour donner un aspect honorable \u00e0 la fonction de propagandiste. En fait, le syst\u00e8me de la communication tel que nous l&rsquo;entendons, et tel qu&rsquo;il doit \u00eatre entendu \u00e0 notre sens en fonction de l&rsquo;importance consid\u00e9rable de son r\u00f4le, comporte aussi bien la cr\u00e9ation de <em>narrative<\/em>que la recherche des v\u00e9rit\u00e9s-de-situation, que l&rsquo;information elle-m\u00eame, lorsqu&rsquo;elle est per\u00e7ue comme une \u00ab\u00a0mati\u00e8re\u00a0\u00bb neutre sinon inerte (plut\u00f4t qu&rsquo;objective, ce qu&rsquo;elle n&rsquo;est pas) une fois qu&rsquo;elle s&rsquo;est incarn\u00e9e pour \u00eatre per\u00e7ue.<\/p>\n<\/p>\n<p><p>Lorsque Trump est apparu et a commenc\u00e9 \u00e0 manier le tweet, la r\u00e9action de rejet a \u00e9t\u00e9 g\u00e9n\u00e9ral, &ndash; aussi bien du nouveau pr\u00e9sident lui-m\u00eame que de sa manie des tweets, consid\u00e9r\u00e9s avec m\u00e9pris comme objet de communication, sinon objet de caprices d&rsquo;humeur, appel\u00e9 \u00e0 dispara&icirc;tre peu \u00e0 peu et, dans tous les cas, \u00e0 ne rien signifier de fondamental dans l&rsquo;ordre du politique. L&rsquo;id\u00e9e \u00e9tait que \u00ab\u00a0la fonction cr\u00e9erait l&rsquo;organe\u00a0\u00bb, c&rsquo;est-\u00e0-dire ferait de Trump un pr\u00e9sident, certes m\u00e9diocre mais dans tous les cas ma&icirc;tris\u00e9s et devant suivre les us et coutumes de la pr\u00e9sidence. Il n&rsquo;en fut rien : <strong>il apparut peu \u00e0 peu que Trump fonctionnait \u00ab\u00a0aux tweets\u00a0\u00bb<\/strong>, qu&rsquo;il transmettait des d\u00e9cisions, des penchants, des intentions, des soup\u00e7ons, des satisfactions, etc., pour en obtenir des effets politiques d&rsquo;autant plus assur\u00e9s qu&rsquo;ils \u00e9taient bruyants, <strong>bref qu&rsquo;il d\u00e9roulait sa vraie politique trumpiste avec tout ce que qualificatif contient d&rsquo;al\u00e9atoire et de simulacre de t\u00e9l\u00e9r\u00e9alit\u00e9<\/strong>.<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e8re du tweet \u00e9tait donc n\u00e9e.<\/p>\n<\/p>\n<p><p>A ce point, pr\u00e9cisons le plus clairement possibles les choses pour la question \u00e9tudi\u00e9e : nous n&rsquo;applaudissons pas Trump ni ne le maudissons, nous constatons un fait. Tout le monde jurait que ce bouffon abandonnerait le \u00ab\u00a0tweetisme\u00a0\u00bb pour rentrer dans le rang de la politique-p\u00e9p\u00e8re (ou disons la face d&rsquo;apparat de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> que repr\u00e9sente un pr\u00e9sident \u00ab\u00a0normal\u00a0\u00bb), mis au pas par le <em>DeepState <\/em>et la conf\u00e9d\u00e9ration des dirigeants-BAO. Il n&rsquo;en fut rien. Le bouffon \u00e9tait bien un bouffon mais il fit de plus en plus usage du tweet et, bient\u00f4t, fit bien sa politique d&rsquo;abord par le \u00ab\u00a0tweetisme\u00a0\u00bb. Cela ne signifie certainement pas qu&rsquo;il s&rsquo;agisse de la panac\u00e9e, d&rsquo;une nouvelle sorte \u00ab\u00a0g\u00e9niale\u00a0\u00bb, \u00ab\u00a0postmoderne\u00a0\u00bb, de politique mais plus simplement et dirions-nous au contraire qu&rsquo;<strong>il n&rsquo;y a plus rien de structur\u00e9, plus aucune politique \u00e9labor\u00e9e humainement pour r\u00e9sister \u00e0 quoi que ce soit, et notamment au \u00ab\u00a0tweetisme\u00a0\u00bb du bouffon<\/strong>.<\/p>\n<\/p>\n<p><p>On s&rsquo;en est aper\u00e7u clairement, notamment au fait que le <em>DeepState <\/em>s&rsquo;est d\u00e9gonfl\u00e9 comme une vieille baudruche us\u00e9e et n&rsquo;a eu ni la peau, ni la conduite selon les normes-marionnette du pr\u00e9sident-bouffon. Pour le reste, on a compris que les hommes politiques du club-BAO, ceux qui entendaient faire rentrer Trump dans le rang, <strong>ne sont que l&rsquo;ombre de l&rsquo;ombre m\u00e9diocre d&rsquo;une politique \u00e0 l&rsquo;agonie, v\u00e9ritables zombieSyst\u00e8me sans aucune capacit\u00e9<\/strong>. Voil\u00e0 pourquoi l&rsquo;homme aux tweets les a vaincus, sinon convaincus : le triomphe du tweet dans la politique, essentiellement via Trump, est d&rsquo;abord et essentiellement une <strong>mesure de l&rsquo;effondrement absolu de la politique dans le bloc-BAO au profit de la dictature du politiquement correct et de la bienpensance<\/strong>. Cette dictature est d&rsquo;autant plus totalitaire qu&rsquo;elle est totalement vide et stupide, et r\u00e9duite effectivement \u00e0 une &laquo; <em>nature primaire, tribale et bas\u00e9e sur des slogans de surface<\/em> &raquo; (nous empruntons justement et volontairement une d\u00e9finition des r\u00e9seaux sociaux qu&rsquo;on retrouve plus loin).<\/p>\n<\/p>\n<p><p>Effectivement donc, aujourd&rsquo;hui la politique se fait notablement par les tweets. On a pu le voir encore hier o&ugrave; l&rsquo;ouragan de tweet de Trump du week-end a provoqu\u00e9 un \u00e9norme chaos \u00e0 la Chambre des Repr\u00e9sentants US avant que la pitoyable direction d\u00e9mocrate <a href=\"https:\/\/www.zerohedge.com\/news\/2019-07-16\/pelosi-briefly-banned-speaking-house-after-calling-tump-racist-leading-chaos-house\">fasse voter<\/a> une motion accusant personnellement le pr\u00e9sident de \u00ab\u00a0racisme\u00a0\u00bb, &ndash; une d\u00e9marche l\u00e9gislative sans gu\u00e8re de pr\u00e9c\u00e9dent et \u00e0 la limite de la l\u00e9galit\u00e9 ; ce qui conduisit Trump \u00e0 comparer (en tweet) les quatre d\u00e9put\u00e9es d\u00e9mocrates impliqu\u00e9es dans cette trag\u00e9die-bouffe aux \u00ab\u00a0<a href=\"https:\/\/www.zerohedge.com\/news\/2019-07-17\/trump-slams-aocs-squad-four-horsewomen-apocalypse\">Quatre cavali(\u00e8)r(e)s de l&rsquo;Apocalypse<\/a>\u00ab\u00a0. On voit \u00e9galement, avec <a href=\"https:\/\/www.zerohedge.com\/news\/2019-07-15\/racist-disgrace-susan-rice-steamed-chinese-diplomat-who-says-black-families-ruin\">un \u00e9change acerbe<\/a> entre l&rsquo;ancienne conseill\u00e8re pour la s\u00e9curit\u00e9 nationale d&rsquo;Obama Susan Rice et un diplomate chinois, que Trump n&rsquo;est pas du tout seul \u00e0 faire de la politique-tweeteuse, et que cette \u00ab\u00a0politique\u00a0\u00bb est effectivement r\u00e9duite \u00e0 une &laquo; <em>nature primaire, tribale et bas\u00e9e sur des slogans de surface<\/em> &raquo; (accusations r\u00e9ciproques de \u00ab\u00a0racisme\u00a0\u00bb, bien entendu, \u00e0 l&rsquo;initiative de Rice, les am\u00e9ricanistes-occidentalistes \u00e9tant des ma&icirc;tres de la stupidit\u00e9 soci\u00e9tale).<\/p>\n<\/p>\n<p><p>Ce ph\u00e9nom\u00e8ne \u00e9largie \u00e0 la question des r\u00e9seaux sociaux est analys\u00e9 dans un article du professeur de droit Glenn Reynolds, que nous citions dans le texte d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9, dans ces termes :<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans un article sur lequel nous reviendrons, le professeur de droit de l&rsquo;Universit\u00e9 du Tennessee Glenn Reynolds analyse l&rsquo;extraordinaire appauvrissement de la pens\u00e9e qu&rsquo;implique l&rsquo;usage intensif des r\u00e9seaux sociaux, \u00ab\u00a0avec <\/em>[leur]<em> nature primaire, tribale et bas\u00e9e sur des slogans de surface\u00a0\u00bb. Il donne une place particuli\u00e8re, &ndash; la pire, et de loin, &ndash; \u00e0 Twitter, dont il remarque qu&rsquo;il &laquo; semble \u00eatre le plus utilis\u00e9 par les personnes m\u00eames, &ndash; les experts, les journalistes politiques, l&rsquo;intelligentsia, &ndash; les plus importantes pour le type de d\u00e9bat qu&rsquo;Emerson consid\u00e9rait comme essentiel <\/em>[&lsquo;<em>pour examiner la connaissance et d\u00e9couvrir la v\u00e9rit\u00e9<\/em>&lsquo;].<\/p>\n<p>&raquo; <em>En fait, la corruption de la classe politique\/intellectuelle par les m\u00e9dias sociaux est particuli\u00e8rement grave, car leur descente dans une polarisation irr\u00e9fl\u00e9chie peut ensuite s&rsquo;\u00e9tendre au reste de la population, m\u00eame \u00e0 la grande partie qui n&rsquo;utilise pas elle-m\u00eame les m\u00e9dias sociaux, par les canaux traditionnels<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Nous allons reprendre deux passages de cet article, &ndash; la premi\u00e8re partie introductive et la conclusion, &ndash; qui nous conduiront \u00e0 structurer et \u00e0 d\u00e9velopper une r\u00e9flexion sur l&rsquo;\u00e9tat de la politique aujourd&rsquo;hui, notamment de la politique par le biais des r\u00e9seaux sociaux, principalement \u00ab\u00a0le pire d&rsquo;entre eux\u00a0\u00bb (Twitter) pour ce raisonnement, et au-del\u00e0 <strong>l&rsquo;\u00e9tat \u00ab\u00a0de la civilisation\u00a0\u00bb si l&rsquo;on veut, ou encore l&rsquo;\u00e9tat de la Crise G\u00e9n\u00e9rale d&rsquo;Effondrement du Syst\u00e8me<\/strong>. Nous devons aussit\u00f4t pr\u00e9ciser dans une sorte d&rsquo;avertissement que nous ne consid\u00e9rons pas les r\u00e9seaux sociaux comme responsable de cet abaissement extraordinaire de la politique et de la psychologie que l&rsquo;on constate, dans cet article mais \u00e9galement pour notre compte et depuis si longtemps, <strong>mais bien comme des outils dont on use parce que l&rsquo;esprit de la civilisation en cours d&rsquo;effondrement s&rsquo;est abaiss\u00e9e \u00e0 tel degr\u00e9 dans les abysses que cette situation permet d&#8217;employer de tels outils<\/strong>. <\/p>\n<\/p>\n<p><p>(L&rsquo;article du professeur Glenn Reynolds est publi\u00e9 d&rsquo;abord dans <em>TheCollegeFix<\/em>le <a href=\"https:\/\/www.thecollegefix.com\/toxic-technology-how-social-media-is-making-us-dumb-angry-and-addicted\/\">15 juillet 2019<\/a>, repris par <em>ZeroHedge.com <\/em>le m\u00eame <a href=\"https:\/\/www.zerohedge.com\/news\/2019-07-15\/toxic-tech-how-social-media-making-us-dumb-angry-addicted\">15 juillet 2019<\/a>. Le titre en est : &laquo; <em>Technologies toxiques : comment les m\u00e9dias sociaux nous rendent idiots, furieux, &ndash; et d\u00e9pendants <\/em>&raquo;. Il s&rsquo;agit d&rsquo;une adaptation \u00e9videmment r\u00e9sum\u00e9e du livre <em>L&rsquo;Insurrection des M\u00e9dias Sociaux<\/em>du m\u00eame auteur.)<\/p>\n<\/p>\n<p><p>&laquo; <em>Il y a quelques ann\u00e9es, j&rsquo;ai remarqu\u00e9 que j&rsquo;aimais beaucoup lire dans les avions et je me suis demand\u00e9 pourquoi. Apr\u00e8s r\u00e9flexion, j&rsquo;ai r\u00e9alis\u00e9 que c&rsquo;\u00e9tait parce que je n&rsquo;\u00e9tais pas distrait par la tentation de v\u00e9rifier un appareil de temps en temps, permettant \u00e0 la lecture d&rsquo;\u00eatre le genre d&rsquo;exp\u00e9rience immersive que je consid\u00e9rais autrefois comme acquise.<\/em><\/p>\n<p>&raquo; <em>Aujourd&rsquo;hui, je me fais un point d&rsquo;honneur de me d\u00e9connecter tous les soirs, assis avec un roman et un verre de vin, l&rsquo;ordinateur et le t\u00e9l\u00e9phone hors de port\u00e9e. J&rsquo;essaie de faire la m\u00eame chose quand je lis pour le travail plut\u00f4t que pour le plaisir, en mettant mes appareils de c\u00f4t\u00e9 pour que je puisse lire profond\u00e9ment et vraiment penser aux choses, mais c&rsquo;est toujours une lutte. Et je ne pense pas que je suis seul.<\/em><\/p>\n<p>&raquo; <em>Je ne sugg\u00e8re pas quelque chose d&rsquo;aussi simpliste que les livres sont bons et qu&rsquo;Internet est mauvais. Il n&rsquo;y a rien de fondamentalement bon dans les livres en tant que tels,  &ndash; Das Kapital et Mein Kampf sont \u00e0 la fois des livres aux cons\u00e9quences meurtri\u00e8res, et des livres qui n&rsquo;ont \u00e9videmment rien fait pour am\u00e9liorer la pens\u00e9e critique de leurs lecteurs.<\/em><\/p>\n<p>&raquo; <em>Mais la capacit\u00e9 de lire et de r\u00e9fl\u00e9chir en profondeur est pr\u00e9cieuse, et elle est aujourd&rsquo;hui mise de c\u00f4t\u00e9 sans raison particuli\u00e8re. Comme le fait remarquer Fulford, \u00ab\u00a0les universit\u00e9s signalent que les \u00e9tudiants \u00e9vitent maintenant de s&rsquo;inscrire \u00e0 des cours de litt\u00e9rature du XIXe si\u00e8cle. Ils r\u00e9alisent qu&rsquo;ils ne peuvent plus travailler avec Dickens ou George Eliot\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Dans son classique &lsquo;The System of Freedom of Expression&rsquo;, Thomas Emerson, sp\u00e9cialiste du  Premier Amendement \u00e0 Yale, a \u00e9crit :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0La libert\u00e9 d&rsquo;expression est un processus essentiel pour examiner la connaissance et d\u00e9couvrir la v\u00e9rit\u00e9. Un individu qui cherche la connaissance et la v\u00e9rit\u00e9 doit entendre toutes les facettes de la question, consid\u00e9rer toutes les alternatives, tester son jugement en l&rsquo;exposant \u00e0 l&rsquo;opposition, et faire pleinement usage des diff\u00e9rents esprits.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Le genre de d\u00e9bat communautaire multipolaire, vaste et profond qu&rsquo;Emerson consid\u00e9rait comme la clef de notre syst\u00e8me de libert\u00e9 d&rsquo;expression est en contradiction totale avec la nature primaire, tribale et bas\u00e9e sur des slogans de surface des m\u00e9dias sociaux.<\/em><\/p>\n<p>&raquo; <em>Il est malheureux que les m\u00e9dias sociaux non seulement rendent un tel d\u00e9bat plus difficile sur leurs plates-formes, mais aussi, semble-t-il, connectent les cerveaux des gens d&rsquo;une mani\u00e8re qui rend ce d\u00e9bat plus difficile que dans n&rsquo;importe quelle autre condition. Cela est aggrav\u00e9 par le fait que Twitter, en particulier, semble \u00eatre le plus utilis\u00e9 par les personnes m\u00eames, &ndash; les experts, les journalistes politiques, l&rsquo;intelligentsia, &ndash; les plus importantes pour le type de d\u00e9bat qu&rsquo;Emerson consid\u00e9rait comme essentiel.<\/em><\/p>\n<p>&raquo; <em>En fait, la corruption de la classe politique\/intellectuelle par les m\u00e9dias sociaux est particuli\u00e8rement grave, car leur descente dans une polarisation irr\u00e9fl\u00e9chie peut ensuite s&rsquo;\u00e9tendre au reste de la population, m\u00eame \u00e0 la grande partie qui n&rsquo;utilise pas elle-m\u00eame les m\u00e9dias sociaux, par les canaux traditionnels.<\/em><\/p>\n<p>&raquo; <em>Twitter est aussi la plus d\u00e9pouill\u00e9e des plateformes de m\u00e9dias sociaux, et donc la plus illustrative des failles de base des m\u00e9dias sociaux. Tout comme les gens tristes qui tirent \u00e0 r\u00e9p\u00e9tition sur les leviers des machines \u00e0 sous des stations-service illustrent l&rsquo;essence du jeu sans le glamour distrayant des casinos et des hippodromes, Twitter, sans se concentrer sur les \u00ab\u00a0amis\u00a0\u00bb ou les photos, ou autres accessoires, affiche la nature politique humaine telle qu&rsquo;elle se manifeste dans les r\u00e9seaux sociaux dans la pire situation possible<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Dans la suite, Reynolds examine la question de la d\u00e9pendance, l&rsquo;addiction extraordinaire aux r\u00e9seaux sociaux, d&rsquo;une fa\u00e7on totalitaire qui (c&rsquo;est notre r\u00e9flexion) renforce d\u00e9cisivement l&rsquo;individualisme et enferme l&rsquo;individu dans une \u00ab\u00a0bulle\u00a0\u00bb en <strong>d\u00e9bouchant sur le paradoxe qu&rsquo;une connexion maximale sur le syst\u00e8me de la communication implique une rupture totale avec la v\u00e9rit\u00e9-du-monde<\/strong>. Ce point est surtout acquis gr\u00e2ce \u00e0 l&rsquo;arriv\u00e9e massive des \u00ab\u00a0t\u00e9l\u00e9phones intelligents\u00a0\u00bb avec toutes les fonctions d&rsquo;un ordinateur, qui enferme l&rsquo;individu, quasiment d&rsquo;une fa\u00e7on continue, dans une sorte d&rsquo;univers ferm\u00e9, fait de lui et de son portable.<\/p>\n<\/p>\n<p><p>Ayant montr\u00e9 cette addiction extraordinaire que la technologie (\u00ab\u00a0t\u00e9l\u00e9phones intelligents\u00a0\u00bb) suscite par rapport aux r\u00e9seaux sociaux, &ndash; ou \u00ab\u00a0m\u00e9dias sociaux\u00a0\u00bb, &ndash; le professeur Reynolds conclue d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, \u00e9largissant le champ de la r\u00e9flexion au-del\u00e0 de la politique qui est le biais que nous avons choisi pour aborder ce sujet, pour embrasser la question g\u00e9n\u00e9rale de la psychologie des \u00eatres humains confront\u00e9s \u00e0 cette pression et \u00e0 cette addiction. (Nous avons marqu\u00e9 en gras les passages qui retiennent surtout notre attention.)<\/p>\n<\/p>\n<p><p>&laquo; <em>J&rsquo;ai trouv\u00e9 cette observation sur Twitter : \u00ab\u00a0L&rsquo;Internet reconnecte les cerveaux et les relations sociales. <strong>Cela pourrait-il produire une d\u00e9pression nerveuse civilisationnelle ?<\/strong>\u00a0\u00bb Et j&rsquo;ai lu un autre article dans lequel il est dit que la d\u00e9pression chez les adolescents a mont\u00e9 en fl\u00e8che entre 2010 et 2015, <strong>lorsque les t\u00e9l\u00e9phones intelligents ont pris le dessus<\/strong>. Je me suis demand\u00e9 si nous ne serions pas dans la m\u00eame dynamique que les villes n\u00e9olithiques <\/em>[qui \u00e9taient d\u00e9truites par des \u00e9pid\u00e9mies]<em>, mais du fait <strong>de la menace d&rsquo;une autre sorte de virus, que l&rsquo;on pourrait appeler des virus de l&rsquo;esprit<\/strong> : des id\u00e9es toxiques et des \u00e9motions qui se propagent comme des feux de for\u00eat.<\/em><\/p>\n<p>&raquo; <em>Ces derni\u00e8res ann\u00e9es, nous sommes pass\u00e9s d&rsquo;une \u00e9poque o&ugrave; les id\u00e9es se r\u00e9pandaient relativement lentement \u00e0 une \u00e9poque o&ugrave; les m\u00e9dias sociaux, en particulier, leur permettent de se propager comme des feux de for\u00eat. Il y a quelques centaines d&rsquo;ann\u00e9es, les id\u00e9es se r\u00e9pandaient principalement de bouche \u00e0 oreille, ou par les livres, qui devaient voyager physiquement. Ensuite, ils se sont r\u00e9pandus par le biais des journaux. D\u00e9sormais, ils se r\u00e9pandent \u00e0 la vitesse de la lumi\u00e8re, et sont partag\u00e9s presque aussi rapidement, d&rsquo;un simple clic de souris.<\/em><\/p>\n<p>&raquo; <em>Parfois c&rsquo;est bien, quand ce sont de bonnes id\u00e9es. Mais la plupart des id\u00e9es sont probablement mauvaises. <strong>Peut-\u00eatre ne connaissons-nous pas les vecteurs de maladies mentales que nous lib\u00e9rons par inadvertance<\/strong>, tout comme ces premi\u00e8res civilisations ne comprenaient pas les vecteurs de maladies physiques dont elles faisaient la promotion. <strong>Dans la soci\u00e9t\u00e9 d&rsquo;aujourd&rsquo;hui, cela semble certainement plausible<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Pourrissement par manque d&rsquo;hygi\u00e8ne<\/h3>\n<\/p>\n<p><p>&#8230; Nous dirions plus encore, et diff\u00e9remment bien entendu, \u00e0 propos des &laquo; <em>vecteurs de maladies mentales que nous lib\u00e9rons par inadvertance <\/em>&raquo; : \u00ab\u00a0<strong>Dans la crise d&rsquo;aujourd&rsquo;hui, cela semble tout simplement in\u00e9vitable<\/strong>\u00ab\u00a0. Ici, il nous para&icirc;t important d&rsquo;apporter une pr\u00e9cision qui nous d\u00e9marque de ce qui nous para&icirc;t une ambigu\u00eft\u00e9 sinon une voie contestable selon nous dans le texte du professeur Reynolds : &laquo; &#8230;<em>des id\u00e9es toxiques et des \u00e9motions qui se propagent comme des feux de for\u00eat&#8230; <\/em>[&#8230;]  <em>Parfois c&rsquo;est bien, quand ce sont de bonnes id\u00e9es. Mais la plupart des id\u00e9es sont probablement mauvaises.<\/em> &raquo; La m\u00eame remarque vaut quand il semble prendre \u00e0 son compte cette remarque trouv\u00e9e sur Twitter : <em>\u00ab\u00a0L&rsquo;Internet reconnecte les cerveaux et les relations sociales&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Cette derni\u00e8re phrase cit\u00e9e est suivie, toujours du m\u00eame message trouv\u00e9 sur Twitter, de cette remarque fondamentale (soulign\u00e9 en gras par nous) : &laquo; <strong><em>Cela pourrait-il produire une d\u00e9pression nerveuse civilisationnelle ?<\/em><\/strong> &raquo; ; et certes renforc\u00e9e plus loin par cette question quasiment en conclusion : &laquo; <strong><em>Peut-\u00eatre ne connaissons-nous pas les vecteurs de maladies mentales que nous lib\u00e9rons par inadvertance<\/em><\/strong>&#8230; &raquo; Il y a dans ces deux remarques l&rsquo;id\u00e9e d&rsquo;une crise collective de la psychologie, d&rsquo;une pathologie pouvant prendre une dimension civilisationnelle. Et l\u00e0-dessus, nous pensons que <strong>ce ne sont pas les \u00ab\u00a0id\u00e9es\u00a0\u00bb qui sont communiqu\u00e9es, non plus que \u00ab\u00a0l&rsquo;internet\u00a0\u00bb lui-m\u00eame, avec les id\u00e9es qu&rsquo;il v\u00e9hicule, qui sont la cause de la pathologie<\/strong>. Nous pensons que ce qui est \u00e9voqu\u00e9 ici comme cause g\u00e9n\u00e9rale de cette \u00ab\u00a0maladie de la psychologie\u00a0\u00bb (et par cons\u00e9quent, mais indirectement, \u00ab\u00a0maladie de l&rsquo;esprit\u00a0\u00bb) peut-\u00eatre d\u00e9compos\u00e9 sous la forme de deux ph\u00e9nom\u00e8nes, en engendrant un troisi\u00e8me :<\/p>\n<\/p>\n<p><p>&bull; <strong>la puissance du ph\u00e9nom\u00e8ne technologique des \u00ab\u00a0t\u00e9l\u00e9phones intelligents\u00a0\u00bb<\/strong>, avec la d\u00e9pendance terrifiante que ce ph\u00e9nom\u00e8ne impose (qui peut \u00eatre effectivement la cause de d\u00e9pression), la forme paradoxale de solitude et d&rsquo;enfermement qu&rsquo;il cr\u00e9e en cr\u00e9ant une \u00ab\u00a0bulle\u00a0\u00bb, ou simulacre d&rsquo;univers ferm\u00e9, et en r\u00e9duisant \u00e0 rien les rapports humains, en les rempla\u00e7ant par des connexions automatiques et technologiques qui d\u00e9shumanisent l&rsquo;environnement et suscitent angoisse, d\u00e9pression, etc. ;<\/p>\n<p>&bull; <strong>la rapidit\u00e9 extraordinaire de la diffusion des objets et choses de communication<\/strong>, qui produit un effet par sa dynamique et nullement par son contenu, d&rsquo;autant qu&rsquo;effectivement le contenu (les \u00ab\u00a0id\u00e9es\u00a0\u00bb) est r\u00e9duit \u00e0 une sorte de n\u00e9antisation de la pens\u00e9e (&laquo; &#8230;<em>nature primaire, tribale et bas\u00e9e sur des slogans de surface<\/em> &raquo;) qui accentue tous les effets d\u00e9taill\u00e9s par ailleurs.<\/p>\n<p>&bull; <strong>L&rsquo;effet des deux ph\u00e9nom\u00e8nes est \u00e9videmment la n\u00e9antisation de la pens\u00e9e<\/strong>, par l&rsquo;incapacit\u00e9 pour l&rsquo;esprit d&rsquo;appr\u00e9cier les circonstances, et moins encore les \u00ab\u00a0id\u00e9es\u00a0\u00bb transmises s&rsquo;il y en a, c&rsquo;est-\u00e0-dire cette impuissance \u00e0 se m\u00e9nager ces &laquo; <em>exp\u00e9riences immersives<\/em> &raquo;, cette pr\u00e9cieuse &laquo; <em>capacit\u00e9 de lire et de r\u00e9fl\u00e9chir en profondeur<\/em> &raquo; dont parle le professeur Reynolds.<\/p>\n<\/p>\n<p><p>Bien entendu, le fait remarquable est que <strong>les tranches de la soci\u00e9t\u00e9 les plus sensibles \u00e0 ces effets catastrophiques sont justement les \u00e9lites<\/strong>, qui s&rsquo;imaginent avoir leur temps compt\u00e9 par l&rsquo;importance qu&rsquo;elles s&rsquo;attribuent, qui sont toujours \u00e0 la pointe de la progression des technologies de communication, qui tiennent de toutes les fa\u00e7ons pour acquis qu&rsquo;elles savent et comprennent tout <strong>sans n\u00e9cessit\u00e9 d&rsquo;exp\u00e9rimentation, de v\u00e9rification et surtout de m\u00e9ditation<\/strong>. Effectivement comme Reynolds l&rsquo;observe, cette affection des \u00e9lites, <strong>qui est une affection psychologique beaucoup plus qu&rsquo;intellectuelle <\/strong>(les \u00e9lites n&rsquo;ont plus aucune pens\u00e9e qu&rsquo;on puisse vraiment critiquer puisqu&rsquo;elles se contentent de r\u00e9citer le Politiquement Correct), fait de graves d\u00e9g\u00e2ts en descendant vers le bas, mais <strong>peut-\u00eatre pas dans le sens o&ugrave; il le sugg\u00e8re<\/strong>. Ces d\u00e9g\u00e2ts sont, au contraire de la contagion de la n\u00e9antisation de l&rsquo;esprit, une forme de plus en plus extr\u00eame de col\u00e8re et de fureur des populations engendrant une v\u00e9ritable haine \u00e0 l&rsquo;encontre de leurs \u00e9lites, dont le vide et la nullit\u00e9 de l&rsquo;esprit leur sont ainsi expos\u00e9s quasi-automatiquement, comme sous la forme classique, &ndash; \u00ab\u00a0le Roi est nu\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le paradoxe des r\u00e9flexions que nous offre le professeure Reynolds, et que nous retrouvons ais\u00e9ment dans les agitations des politiques qui montrent leur n\u00e9antisation et nullement leur sup\u00e9riorit\u00e9, rendant ainsi insupportable leur arrogance (arrogance parce que n\u00e9antisation), c&rsquo;est bien que la \u00ab\u00a0zombification\u00a0\u00bb produite par le ph\u00e9nom\u00e8ne ainsi d\u00e9crit touche d&rsquo;abord les \u00e9lites, et nous dirions presque \u00ab\u00a0exclusivement\u00a0\u00bb, car cette zombification si visible, si choquante, loin de \u00ab\u00a0zombifier\u00a0\u00bb la population, provoque au contraire un ressentiment, une col\u00e8re extraordinaire contre ces \u00e9lites. <strong>A notre sens, nous avons l\u00e0 une explication acceptable des ph\u00e9nom\u00e8nes qui s&rsquo;accumulent aujourd&rsquo;hui, des Gilets-Jaunes aux divers populismes<\/strong>. Cette \u00e9volution est largement renforc\u00e9e par des politiciens hors-normes (des non-politiciens, en fait), dont Trump est l&rsquo;arch\u00e9type, qui, par leur comportement, par ce qu&rsquo;ils sont eux-m\u00eames, par leur c\u00f4t\u00e9 bouffon, ridiculisent la politique et donc toute la classe politique ; finalement, les Trump divers, qui choquent tant les \u00e9lites n\u00e9antis\u00e9es, <strong>ne cessent de montrer par l&rsquo;absurde que la politique peut \u00eatre r\u00e9duite \u00e0 une <\/strong><strong>&laquo; &#8230;<\/strong><strong><em>nature primaire, tribale et bas\u00e9e sur des slogans de surface<\/em><\/strong><strong> &raquo;<\/strong>, et participent donc avec une exceptionnelle efficacit\u00e9 \u00e0 <strong>la d\u00e9mythification de la classe politique en la montrant dans toute sa zombification<\/strong>. Au fond, Trump nous dit : \u00ab\u00a0Regardez, je ne connais rien \u00e0 la politique, je m&rsquo;en fous, j&rsquo;agis sans le moindre respect des r\u00e8gles, et pourtant je me les fais tous sans qu&rsquo;ils ne puissent rien faire ; c&rsquo;est donc qu&rsquo;ils ne valent plus rien, puisqu&rsquo;ils valent moins que moi&#8230;\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Si tous ces ph\u00e9nom\u00e8nes renvoient aux diverses anticipations pessimistes (<em>Le meilleur des mondes, 1984<\/em>, <em>Fahrenheit 451<\/em>, etc.) dans leur orientation, <strong>les effets sont exactement inverses malgr\u00e9 l&rsquo;univers concentrationnaire qu&rsquo;on nous promet d&rsquo;une fa\u00e7on quasiment ouverte depuis 9\/11<\/strong> : le totalitarisme qui s&rsquo;installe, qui se voudrait \u00ab\u00a0doux\u00a0\u00bb, est identifi\u00e9 comme tels par ceux qui le subissent, le for\u00e7ant \u00e0 tenter de se durcir, &ndash; chose encore plus difficile quand le Politiquement Correct ne cesse de marmonner et de balbutier \u00e0 propos de la d\u00e9mocratie et du reste, &ndash; l&rsquo;ensemble accentuant la sensation de ressentiment et de col\u00e8re contre les \u00e9lites. L&#8217;empire pourrit par la t\u00eate, non seulement parce que c&rsquo;est de bonne tradition, mais surtout parce qu&rsquo;il s&rsquo;est invent\u00e9 les moyens de ce pourrissement et qu&rsquo;il en use \u00e0 la folie, emport\u00e9 par l&rsquo;ivresse de l&rsquo;exp\u00e9rience ; et le fait est que ce qu&rsquo;il suscite finalement chez les populations diverses alert\u00e9es par l&rsquo;odeur <strong>n&rsquo;est pas une extension \u00e0 elles-m\u00eames du pourrissement mais une col\u00e8re contre ce pourrissement<\/strong>.<\/p>\n<\/p>\n<p><p>Tout cela n&rsquo;a rien \u00e0 voir avec les id\u00e9es, les id\u00e9ologies, les conceptions intellectuelles, mais <strong>avec les simples processus psychologiques que ces divers \u00e9v\u00e9nements et ph\u00e9nom\u00e8nes ne cessent de susciter, d&rsquo;exciter, d&rsquo;accroitre, d&rsquo;acc\u00e9l\u00e9rer<\/strong>. C&rsquo;est dans ce sens que les remarques d\u00e9j\u00e0 relev\u00e9es nous conviennent tout \u00e0 fait et rejoignent des hypoth\u00e8ses que nous avons d\u00e9j\u00e0 pr\u00e9sent\u00e9es, sur le caract\u00e8re collectif de ph\u00e9nom\u00e8nes psychologiques, les &laquo; <em>maladies mentales que nous lib\u00e9rons par inadvertance<\/em>&#8230; &raquo;, c&rsquo;est-\u00e0-dire peut-\u00eatre &laquo; <em>une d\u00e9pression nerveuse civilisationnelle<\/em> &raquo; constituant le facteur d\u00e9cisif du paroxysme d\u00e9cisif et lib\u00e9rateur de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me. En effet, le Syst\u00e8me s&rsquo;effondrera simplement par manque d&rsquo;hygi\u00e8ne des fonctions vitales.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crise de nerfs civilisationnelle 17 juillet 2019 &ndash; Nous avons mis en ligne hier un texte sur une bataille entre les habituels comp\u00e9titeurs \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb (Trump et Trumphaters), o&ugrave; le tweet joue un r\u00f4le essentiel. Bien entendu, nous avions \u00e0 l&rsquo;esprit le d\u00e9veloppement que constitue ce F&#038;C&#8230;L&rsquo;id\u00e9e centrale de ce texte est de cerner, d&rsquo;identifier,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[8393,2631,2604,6204,2930,19217,11605,11994,8392,19216,2843,2639,12567,14083],"class_list":["post-78746","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-correct","tag-de","tag-des","tag-elites","tag-glenn","tag-intelligent","tag-lesprit","tag-neantisation","tag-politiquement","tag-reynolds","tag-telephone","tag-trump","tag-tweet","tag-zombification"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78746"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78746\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}