{"id":78759,"date":"2019-07-25T04:08:27","date_gmt":"2019-07-25T04:08:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/07\/25\/appui-et-levier\/"},"modified":"2019-07-25T04:08:27","modified_gmt":"2019-07-25T04:08:27","slug":"appui-et-levier","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/07\/25\/appui-et-levier\/","title":{"rendered":"Appui et levier"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Appui et levier<\/h2>\n<\/p>\n<p><p>Il aurait plut\u00f4t dit &laquo; Depuis un point o&ugrave; je puisse me tenir fermement, je ferais mouvoir la Terre &raquo;.  Peu importe qu&rsquo;il ne l&rsquo;ait pas formul\u00e9 pr\u00e9cis\u00e9ment ainsi mais Archim\u00e8de, fils de Phidias de Syracuse, \u00e9l\u00e8ve de l&rsquo;\u00e9cole d&rsquo;Alexandrie, a \u00e9nonc\u00e9 le principe qu&rsquo;une faible force peut se d\u00e9cupler par un effet de levier exerc\u00e9 depuis un appui.<\/p>\n<\/p>\n<p><p>L&rsquo;ing\u00e9nierie financi\u00e8re de Wall Street tout en ayant l&rsquo;air d&rsquo;avoir invent\u00e9 un moteur perp\u00e9tuel semble bas\u00e9e sur ce principe de physique pr\u00e9-newtonienne.<\/p>\n<\/p>\n<p><p>Le capitalisme \u00e0 ses d\u00e9buts a transform\u00e9 le mode d&rsquo;\u00e9change entre les hommes qui de  Marchandise -&gt;  Argent -&gt; Marchandise, est devenu Argent -&gt; Marchandise -&gt; Argent. Depuis la fin de la Seconde Guerre mondiale, et singuli\u00e8rement depuis le d\u00e9but des ann\u00e9es 70 du si\u00e8cle dernier, les flux financiers mondiaux circulent fermement branch\u00e9s sur l&rsquo;\u00e9talon qui s&rsquo;est substitu\u00e9 \u00e0 l&rsquo;or, le dollar \u00e9tasunien. <\/p>\n<\/p>\n<p><p>Dans un premier temps, le FMI et la Banque mondiale ont agi comme prolongement financier &#8211; et donc politique &#8211; de l&rsquo;arm\u00e9e des Usa.  Elles ont assur\u00e9 d&rsquo;abord le pillage des pays du tiers-monde par des mesures &lsquo;d&rsquo;aide&rsquo;, c&rsquo;est-\u00e0-dire d&rsquo;endettement suivies de restructurations et d&rsquo;aust\u00e9rit\u00e9 avant que ces m\u00eames mesures ne s&rsquo;\u00e9tendent aux vieux pays capitalistes du continent. Un scrupule g\u00eanait encore le soldat US, mercenaire de Wall Street. Le petit caillou dans sa chaussure, c&rsquo;\u00e9tait le syst\u00e8me sovi\u00e9tique qui ne vantait pas le profit comme unique horizon social et la jouissance sans entrave imm\u00e9diate comme morale soci\u00e9tale. Il s&rsquo;est effondr\u00e9 en 1991, en grande partie \u00e0 cause \u00e0 la longue guerre id\u00e9ologique (et des sanctions du COCOM!) men\u00e9e souterrainement en Europe occidentale par des stipendi\u00e9s de la CIA.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Naissance sur ruines \u00e0 cr\u00e9dit<\/h3>\n<\/p>\n<p><p>La position dominante des USA a \u00e9t\u00e9 amorc\u00e9e lors de la premi\u00e8re guerre inter-imp\u00e9rialiste d&rsquo;importance, dite Premi\u00e8re Guerre mondiale. Le rejeton colonial britannique en Am\u00e9rique s&rsquo;est attribu\u00e9 au cours de cette lutte destructrice un r\u00f4le de cr\u00e9ancier. Ils ont fourni argent et armement mais n&rsquo;ont pas effac\u00e9 l&rsquo;ardoise apr\u00e8s la difficile paix qui a d\u00e9membr\u00e9 l&#8217;empire ottoman et autrichien, en m\u00eame temps que s&rsquo; instaurait le r\u00e9gime des Bolcheviks. Les Rouges ont su triompher gr\u00e2ce \u00e0 un projet socialiste mais \u00e9galement patriotique car ils ont emp\u00each\u00e9 le d\u00e9pe\u00e7age de la Russie. Le g\u00e9n\u00e9ral <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alexe%95_Broussilov#https:\/\/fr.wikipedia.org\/wiki\/Alexe%C3%AF_Broussilov\">Broussilov<\/a>  comme tant d&rsquo;autres ont transcend\u00e9 leur appartenance de classe pour d\u00e9fendre leur patrie.  L&rsquo;Angleterre et surtout la France, afin d&rsquo;honorer leurs cr\u00e9ances vis-\u00e0-vis des banques priv\u00e9es \u00e9tasuniennes, vont \u00eatre d&rsquo;abord intransigeants dans leur exigence vis-\u00e0-vis de l&rsquo;Allemagne pour percevoir les r\u00e9parations de guerre.<\/p>\n<\/p>\n<p><p>A la veille de la crise \u00e9conomique mondialis\u00e9e de 1929, les USA repr\u00e9sentaient pr\u00e8s de la moiti\u00e9 de la production industrielle mondiale et plus de 12% des importations mondiales. Comme ce qui allait se produire en 2007-2008 lors de l&rsquo;\u00e9clatement de la bulle des <em>subprimes<\/em>, la crise am\u00e9ricaine d&rsquo;inad\u00e9quation entre la production et la capacit\u00e9 de r\u00e9sorption par le march\u00e9, typique d&rsquo;une surproduction, aura des cons\u00e9quences mondiales. Elle se r\u00e9percutera de mani\u00e8re rapide, durable et profonde en Europe centrale, en Allemagne surtout de mani\u00e8re retard\u00e9e et plut\u00f4t br\u00e8ve en France et en Angleterre. Cette g\u00e9ographie a fait dire qu&rsquo;elle a eu deux \u00e9picentres, les Usa et l&rsquo;Allemagne.<\/p>\n<\/p>\n<p><p>L&rsquo;Angleterre, devant la menace d&rsquo;une r\u00e9volte sociale, a d\u00e9tach\u00e9 la Livre sterling de l&rsquo;or, ce qui entra&icirc;na une d\u00e9pr\u00e9ciation de sa monnaie de 30%. L&rsquo;ampleur de la dette allemande interdisait toute man&oelig;uvre mon\u00e9taire sous peine de r\u00e9\u00e9valuer le service de cette dette. L&rsquo;hyperinflation de 1923 avait d\u00e9truit l&rsquo;\u00e9pargne et le pays vivait sous perfusion de pr\u00eats am\u00e9ricains \u00e0 court-terme. Le  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Plan_Dawes#https:\/\/fr.wikipedia.org\/wiki\/Plan_Dawes\">plan Dawes<\/a>  sign\u00e9 en 1924 am\u00e9nageait les versements des r\u00e9parations de guerre dues par l&rsquo;Allemagne et \u00e9mettait un emprunt sur le march\u00e9 obligataire am\u00e9ricain qui alimentait en capitaux l&rsquo;\u00e9conomie du pays d\u00e9fait. Un comit\u00e9 de financiers \u00e9tasuniens pr\u00e9sid\u00e9 par  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Plan_Young#https:\/\/fr.wikipedia.org\/wiki\/Plan_Young\">Owen Young<\/a>  r\u00e9visa alors cet \u00e9ch\u00e9ancier en 1929 (peu de temps avant la &lsquo;crise&rsquo;) et r\u00e9\u00e9chelonna cette dette r\u00e9duite sensiblement. Lors de la conf\u00e9rence internationale tenue \u00e0 Lausanne en 1932, l&rsquo;Allemagne fut exon\u00e9r\u00e9e de 90% des r\u00e9parations de guerre dues contre 3 millions de marks-or payables en un versement unique diff\u00e9r\u00e9. Hitler n&rsquo;a jamais honor\u00e9 le paiement qui devait avoir lieu en 1935. Les dettes commerciales fran\u00e7aises et britanniques, elles, restaient dues.<\/p>\n<\/p>\n<p><p>Ainsi, le nouvel ordre mondial \u00e9tait pour ainsi dire d\u00e9j\u00e0 mis en place, celui dict\u00e9 par les imp\u00e9ratifs de la pr\u00e9servation des int\u00e9r\u00eats des banques priv\u00e9es \u00e9tasuniennes qui ont financ\u00e9 la reconstruction allemande et facilit\u00e9 son r\u00e9armement. La contamination massive de l&rsquo;\u00e9conomie allemande par le cataclysme \u00e9tasunien de 1929 a cr\u00e9\u00e9 des conditions sociales objectives pour la mont\u00e9e du nazisme et ainsi de la guerre inter-imp\u00e9rialiste  suivante.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sortie de crise, \u00e0 cr\u00e9dit encore<\/h3>\n<\/p>\n<p><p>La guerre de 1939-1945 fut le point culminant de la sortie de crise pour les USA, initi\u00e9e par la politique de Roosevelt du New Deal. La loi-pr\u00eat-bail de 1941 a fourni \u00e0 cr\u00e9dit du mat\u00e9riel aux Alli\u00e9s. L&rsquo;\u00e9conomie am\u00e9ricaine fut litt\u00e9ralement dop\u00e9e, elle a fourni  300 000 avions, 100 000 chars. Elle a construit 2\/3 des bateaux de commerce des alli\u00e9s, compensant largement les destructions op\u00e9r\u00e9es par les sous-marins allemands.<\/p>\n<\/p>\n<p><p>Le budget f\u00e9d\u00e9ral est pass\u00e9 de 9 milliards de dollars en 1941 \u00e0 100 milliards en 1945, les d\u00e9penses militaires suivirent une \u00e9volution courbe strictement parall\u00e8le, l&rsquo;\u00e9cart entre les deux courbes minime t\u00e9moignait du fait que plus de 90% de la d\u00e9pense f\u00e9d\u00e9rale \u00e9tait alors consacr\u00e9e \u00e0 la guerre. Plus de 40% du co&ucirc;t de la guerre fut financ\u00e9 par l&rsquo;imp\u00f4t, le ch\u00f4mage est tomb\u00e9 \u00e0 1,2%, les femmes furent recrut\u00e9es et la s\u00e9gr\u00e9gation raciale a recul\u00e9 \u00e0 l&rsquo;usine.<\/p>\n<\/p>\n<p><p>La loi-pr\u00eat-bail de 1941 a fourni \u00e0 cr\u00e9dit du mat\u00e9riel aux Alli\u00e9s.<\/p>\n<\/p>\n<p><p>Au sortir de l&rsquo;affrontement contre les pays de l&rsquo;Axe dont l&rsquo;essentiel des destructions et du prix du sang a \u00e9t\u00e9 pay\u00e9 par l&rsquo;Union sovi\u00e9tique, les USA concentraient dans leurs mains 2\/3 du stock  mondial de l&rsquo;or et \u00e9taient largement cr\u00e9anciers. Ils purent ais\u00e9ment \u00e9tablir un dispositif mon\u00e9taire et financier dans leur sph\u00e8re d&rsquo;influence o&ugrave; allait circuler leur dollar comme monnaie-\u00e9talon, d&rsquo;\u00e9change, de r\u00e9serve et de mesure.<\/p>\n<\/p>\n<p><p>D\u00e9j\u00e0 la  <a href=\"https:\/\/www.persee.fr\/doc\/ahess_0003-441x_1931_num_3_11_1421#https:\/\/www.persee.fr\/doc\/ahess_0003-441x_1931_num_3_11_1421\">Banque des R\u00e8glements Internationaux<\/a>  entr\u00e9e en activit\u00e9 \u00e0 B\u00e2le en mai 1930 \u00e9tait n\u00e9e de la volont\u00e9 \u00e9tasunienne de faire passer la question des R\u00e8glements de guerre du plan politique au plan commercial a converti la dette en obligations \u00e0 \u00e9mettre dans le public. Une premi\u00e8re tranche de 200 millions de marks \u00e0 5,5% a \u00e9t\u00e9 \u00e9mise d\u00e8s juin 1930 par un consortium de banques. Cette banque allait exister pendant toute la guerre pour assurer, malgr\u00e9 la guerre sur les autres fronts, les flux financiers du 3<sup>e<\/sup> Reich vers les USA, en particulier ceux de Ford Allemagne, avec un directeur citoyen des USA et un vice-directeur citoyen du 3<sup>e<\/sup> Reich.<\/p>\n<\/p>\n<p><p>La BIRD, Banque internationale pour la reconstruction et le d\u00e9veloppement, qui allait va devenir la Banque mondiale, ainsi que le FMI sont le fruit de la conf\u00e9rence internationale tenue en juillet 1944  \u00e0 Bretton Woods, dans les New Hampshire aux USA. Les d\u00e9l\u00e9gu\u00e9s de 44 pays \u00e9taient pr\u00e9sents alors m\u00eame que la guerre n&rsquo;\u00e9tait pas finie. L&rsquo;ONU, appendice politique d&rsquo;un syst\u00e8me qui allait \u00eatre domin\u00e9 par les USA, ne sera cr\u00e9\u00e9e qu&rsquo;un an apr\u00e8s. Juste apr\u00e8s les pr\u00e9occupations de la Reconstruction &#8211; les principaux d\u00e9g\u00e2ts inflig\u00e9s aux villes ouest-europ\u00e9ennes des pays alli\u00e9s furent le fait de l&rsquo;aviation britannique et surtout \u00e9tasunienne, la BM allait octroyer des pr\u00eats d&rsquo;infrastructure \u00e0 long terme. Ils allaient vpermettre de faire travailler les firmes d&rsquo;ing\u00e9nierie am\u00e9ricaine dans les secteurs des ports, des routes qui allaient faciliter la p\u00e9n\u00e9tration commerciale des USA sans \u00e9gard pour les int\u00e9r\u00eats de d\u00e9veloppement r\u00e9el du pays emprunteur. Le FMI pr\u00eate \u00e0 court terme des devises. Dans les deux cas, les transactions se font en dollars et tout est fait pour prot\u00e9ger les cr\u00e9anciers et subventionner les investisseurs \u00e9trangers.<\/p>\n<\/p>\n<p><p>Les dirigeants les plus importants qui se sont succ\u00e9d\u00e9 \u00e0 la t\u00eate de la Banque mondiale ont tous eu un cursus avec un passage oblig\u00e9 par le minist\u00e8re improprement appel\u00e9 de la D\u00e9fense, en r\u00e9alit\u00e9 de la Guerre.  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/John_McCloy#https:\/\/fr.wikipedia.org\/wiki\/John_McCloy\">John Mc Cloy<\/a>, gouverneur de 1947 \u00e0 1949, a \u00e9t\u00e9 assistant du Secr\u00e9taire d&rsquo;Etat \u00e0 la Guerre. <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Robert_McNamara#https:\/\/fr.wikipedia.org\/wiki\/Robert_McNamara\">Robert Mc Namara<\/a>  fut Secr\u00e9taire \u00e0 la D\u00e9fense de 1961 \u00e0 1968, lors de l&rsquo;engagement le plus intense contre le Vietnam avec l&#8217;emploi du fameux agent orange, puis pr\u00e9sida la BM de 1968 \u00e0 1981.  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Paul_Wolfowitz#https:\/\/fr.wikipedia.org\/wiki\/Paul_Wolfowitz\">Paul Wolfowitz<\/a>  secr\u00e9taire adjoint \u00e0 la D\u00e9fense sous G. W. Bush de 2001 \u00e0 2005 et auteur des justifications juridiques de l&rsquo;invasion de l&rsquo;Irak en 2003 est \u00e9loign\u00e9 du gouvernement gr\u00e2ce \u00e0 une promotion comme pr\u00e9sident de la BM avant d&rsquo;en \u00eatre destitu\u00e9 en 2007 pour n\u00e9potisme et de laisser la place \u00e0 Robert Zo\u00ebllick, n\u00e9oconservateur aussi radical que lui. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Marshall, les voil\u00e0<\/h3>\n<\/p>\n<p><p>Les accords sur le commerce General Agreement of Tariffs and Trade, GATT, men\u00e9es sous l&rsquo;impulsion de l&rsquo;ONU ont recueilli la signature de 23 pays en 1947, ils seront 80 d\u00e8s 1971. Les parties contractantes s&rsquo;engageaient \u00e0 ne pas augmenter les droits de douanes dans un premier temps limit\u00e9s aux produits industriels. Services, propri\u00e9t\u00e9 intellectuelle et agriculture seront discut\u00e9s et introduits ult\u00e9rieurement. Les tarifs douaniers passeront de 40% en 1947 \u00e0 quelques 15% dans les ann\u00e9es 1970. En r\u00e9alit\u00e9, les flux commerciaux dans le contexte de la souplesse du GATT se sont organis\u00e9s au b\u00e9n\u00e9fice des nations les plus puissantes et les plus efficaces \u00e9conomiquement, singuli\u00e8rement les Usa, aggravant la divergence qui p\u00e9nalise les anciens pays colonis\u00e9s.<\/p>\n<\/p>\n<p><p>Le Gatt vient en compl\u00e9ment du plan que le G\u00e9n\u00e9ral Marshall a expos\u00e9 devant le public de Harvard le 5 juin 1947, programme de dons et de pr\u00eats en direction de l&rsquo;Europe occidentale dont la dur\u00e9e s&rsquo;\u00e9tendra jusqu&rsquo;en 1952. Il fallait la soutenir car elle s&rsquo;enfon\u00e7ait dans une situation \u00e9conomique &lsquo;angoissante&rsquo; par manque de cr\u00e9dits et de creusement des d\u00e9ficits commerciaux. Et, du coup, la menace d&rsquo;une r\u00e9volution communiste \u00e9tait \u00e0 alors \u00e0 l&rsquo;ordre du jour, au moins en France et en Italie. L&rsquo;exc\u00e9dent de dollars allait y \u00eatre investi avec un bon rendement mais \u00e9galement, voire surtout, il s&rsquo;agissait pour le capitalisme pr\u00e9dateur \u00e9tasunien de pratiquer l&rsquo;endiguement de l&rsquo;influence communiste de l&rsquo;Union sovi\u00e9tique. $13, 6 milliards furent mis \u00e0 disposition de l&rsquo;Europe occidentale, sous forme de dons de mat\u00e9riels surtout. Ils ont ancr\u00e9 l&rsquo;Allemagne \u00e0 l&rsquo;Ouest, principal objectif du plan avec le rel\u00e8vement de l&rsquo;Allemagne occidentale comme point central de la reconstruction europ\u00e9enne. Les gros capitalistes allemands qui avaient fait des b\u00e9n\u00e9fices faramineux sur le dos des populations serviles exploit\u00e9es et extermin\u00e9es pendant la p\u00e9riode nazie s&rsquo;en tiraient \u00e0 bon compte, utiles qu&rsquo;ils \u00e9taient devenus pour le nouvel imp\u00e9rialisme \u00e9mergent.<\/p>\n<\/p>\n<p><p>Toute l&rsquo;architecture de la domination \u00e9tasunienne est alors en place : BRI, Banque mondiale, FMI, additionn\u00e9s du plan Marshall et de l&rsquo;abolition des fronti\u00e8res en tant que barri\u00e8res commerciales et bient\u00f4t financi\u00e8res. Le monde occidental fascin\u00e9 par le mode de consommation \u00e9tasunien est plus en plus perm\u00e9able \u00e0 la culture et la &lsquo;contre-culture&rsquo; nord-am\u00e9ricaines. Devenu le bac \u00e0 sable des entreprises \u00e9tasuniennes, il se lancera \u00e0 l&rsquo;assaut id\u00e9ologique du socialisme r\u00e9el \u00e9difi\u00e9 dans les pays atteints tardivement et peu par l&rsquo;industrialisation.<\/p>\n<\/p>\n<p><p>Cette p\u00e9riode d&rsquo;exc\u00e9dent commercial et budg\u00e9taire allait s&rsquo;achever avec les d\u00e9penses du Pentagone qui se sont perp\u00e9tu\u00e9es puis amplifi\u00e9es. Le Complexe militaro-industriel qui avait \u00e9difi\u00e9 cette supr\u00e9matie en effa\u00e7ant la Grande D\u00e9pression gr\u00e2ce \u00e0 l&rsquo;entr\u00e9e en guerre des Usa \u00e9tait en position de perp\u00e9tuer son activit\u00e9 et sa domination.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">L&rsquo;appui a cinq c\u00f4t\u00e9s et des ruines<\/h3>\n<\/p>\n<p><p>Cette entit\u00e9 pr\u00e9datrice, contre laquelle m\u00eame le pr\u00e9sident Eisenhower allait mettre en garde lors de son discours &#8230;de d\u00e9part, s&rsquo;est aid\u00e9e de la prolif\u00e9ration d&rsquo;agences de renseignements et de services de contre-espionnage dont la fonction revenait non \u00e0 ajuster une politique de d\u00e9fense \u00e0 des r\u00e9alit\u00e9s objectives recueillies ou m\u00eame provoqu\u00e9es mais \u00e0 justifier des agressions d\u00e9cid\u00e9es pr\u00e9alablement.<\/p>\n<\/p>\n<p><p>La Guerre de Cor\u00e9e (1950-1953) allait inaugurer ce qui tr\u00e8s improprement fut appel\u00e9 la Guerre Froide, soit 3 millions de morts, surtout cor\u00e9ens mais aussi dont 900 000 soldats chinois et 33 000 Etasuniens. Le nord de la Cor\u00e9e fut, comme pr\u00e9vu par les strat\u00e8ges du Pentagone, ramen\u00e9 \u00e0 l&rsquo;\u00e2ge de pierre pour servir de le\u00e7on aux autres nations asiatiques, en particulier par les Cor\u00e9ens du Sud mais aussi les Vietnamiens. De part et d&rsquo;autre du 38<sup>\u00e8me<\/sup> parall\u00e8le s&rsquo;affrontent le monde communiste et le monde capitaliste. l&rsquo;URSS est entr\u00e9e en guerre contre le Japon qui avait fait de la Cor\u00e9e une r\u00e9serve d&rsquo;esclaves. Le monde capitaliste incarn\u00e9 par les Usa -s&rsquo;est attribu\u00e9 la qualit\u00e9 de &lsquo;libre&rsquo;. Il a fait tourner \u00e0 plein r\u00e9gime la production d&rsquo;armements et a attis\u00e9 la peur des Rouges \u00e0 l&rsquo;\u00e9chelle nationale, acc\u00e9l\u00e9rant la chasse au communiste ou au simple lib\u00e9ral au travers du maccarthysme, et, au niveau international, avec l&rsquo;\u00e9laboration de la th\u00e9orie fantasm\u00e9e de &lsquo;l&rsquo;effet domino&rsquo;. Si un pays devient communiste, c&rsquo;est toute la r\u00e9gion qui tomberait avec lui dans son camp. Cet \u00e9largissement \u00e0 l&rsquo;Asie de la politique de l&rsquo;endiguement du communisme a \u00e9t\u00e9 l&rsquo;occasion du renforcement de l&rsquo;OTAN avec admission de deux nouveaux membres, la Gr\u00e8ce et la Turquie. En principe r\u00e9serv\u00e9 aux &lsquo;d\u00e9mocraties&rsquo;, l&rsquo;OTAN dans les faits ne s&#8217;embarrassait pas, quand c&rsquo;\u00e9tait utile, de s&rsquo;ouvrir aux r\u00e9gimes militaires ou monarchistes les plus r\u00e9pressifs.<\/p>\n<\/p>\n<p><p>L&rsquo;une des cons\u00e9quences les plus durables et significatives \u00e0 l&rsquo;\u00e9chelle plan\u00e9taire de la guerre de Cor\u00e9e fut  l&rsquo;entr\u00e9e des USA dans le r\u00e9gime des d\u00e9ficits budg\u00e9taires. Son co&ucirc;t de 69 milliards (\u00e0 mettre en rapport avec les 13 du plan Marshall qui a servi de moyen pour coloniser 16 Etats europ\u00e9ens) entra&icirc;na une d\u00e9gradation des finances publiques avec un endettement \u00e0 long terme dont elles ne sortiront jamais. Ce ph\u00e9nom\u00e8ne s&rsquo;est accompagn\u00e9 d&rsquo;une augmentation sans pr\u00e9c\u00e9dent des profits des aci\u00e9ries, d&rsquo;une sant\u00e9 remarquable du march\u00e9 boursier, d&rsquo;un ch\u00f4mage tr\u00e8s bas et d&rsquo;une hausse insolente du PIB. L&rsquo;essor de l&rsquo;industrie de l&rsquo;armement \u00e9tait alors fulgurant, mise au point de la bombe \u00e0 hydrog\u00e8ne et production des bombardiers B52. Les activit\u00e9s de la CIA se sont multipli\u00e9es, en particulier les strat\u00e9gies de guerre psychologique. L&rsquo;adoption du document  <a href=\"https:\/\/en.wikipedia.org\/wiki\/NSC_68#https:\/\/en.wikipedia.org\/wiki\/NSC_68\">NSC-68<\/a>  impliquait que les Usa acceptent de devenir une nation militaris\u00e9e &lsquo;en temps de paix&rsquo; et pouvait consacrer plus de 20% de leur PIB \u00e0 des d\u00e9penses militaires. Celles-ci ont bondi de 13 milliards au d\u00e9but de la guerre \u00e0 50 milliards trois ans plus tard.<\/p>\n<\/p>\n<p><p>La Cor\u00e9e n&rsquo;a \u00e9t\u00e9 qu&rsquo;une entr\u00e9e en mati\u00e8re, sans elle, la guerre du Vietnam n&rsquo;aurait pas vu le jour. Les Usa sont bien entr\u00e9s dans une \u00e9conomie de guerre permanente, cette fois non plus \u00e0 l&rsquo;\u00e9chelle du Far West mais de la plan\u00e8te enti\u00e8re, les d\u00e9penses militaires sont rest\u00e9es \u00e9lev\u00e9es apr\u00e8s la guerre de Cor\u00e9e, stabilis\u00e9es \u00e0 9% du PIB jusque dans les ann\u00e9es 60, apr\u00e8s le pic de 13% en 1952-1953. Les \u00e9conomistes se r\u00e9jouissaient des options politiques de la guerre froide car elles \u00e9taient une incitation keynesienne pour l&rsquo;\u00e9conomie.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Victoire du Vietnam, la machine \u00e0 d\u00e9bit<\/h3>\n<\/p>\n<p><p>Le co&ucirc;t global de la guerre au Vietnam reste difficile \u00e0 \u00e9valuer ($140 milliards ?), ce flou constituera une r\u00e8gle pour tous les engagements ult\u00e9rieurs, de nombreuses d\u00e9penses sont masqu\u00e9es sous d&rsquo;autre titres comme les aides administr\u00e9es par le Secr\u00e9tariat d&rsquo;Etat aux Affaires \u00e9trang\u00e8res, certaines sont secr\u00e8tes tandis que d&rsquo;autres sont malais\u00e9es \u00e0 \u00e9valuer, comme le co&ucirc;t indirect des bless\u00e9s et des traumatis\u00e9s psychologiques graves,  environ 700 000 pour le Vietnam. N\u00e9anmoins, on estime que la &lsquo;D\u00e9fense&rsquo; a absorb\u00e9 dans ces ann\u00e9es 60-70, 45% \u00e0 50% du budget f\u00e9d\u00e9ral soit pr\u00e8s de 77 milliards en 1970.  Cependant la stimulation par l&rsquo;\u00e9conomie de guerre porte en elle-m\u00eame des distorsions car elle se concentre sur certains secteurs avec tension sur la main d&rsquo;&oelig;uvre qualifi\u00e9e et hausse des prix des industries lourdes. La croissance sera moins vigoureuse par rapport aux pays europ\u00e9ens et au Japon ce qui se traduisit par la perte de leur supr\u00e9matie commerciale. Responsables de 46% des exportations mondiales en 1950, les Usa voient leur contribution baisser \u00e0 20% en 1970. Ils pr\u00e9sentaient une balance commerciale exc\u00e9dentaire jusque dans la fin des ann\u00e9es 60, ils accusent depuis 1971 (- $1,7 milliards) un d\u00e9ficit qui va devenir chronique (-$ 5,8 milliards  d\u00e8s 1972).<\/p>\n<\/p>\n<p><p>Le ralentissement \u00e9conomique relatif allait entra&icirc;ner un afflux de capitaux en dollars vers l&rsquo;Europe sans modification de la politique mon\u00e9taire \u00e9tasunienne. Kennedy et Johnson avaient d\u00e9j\u00e0 demand\u00e9 aux Europ\u00e9ens de ne pas exiger la convertibilit\u00e9 or. La masse de dollars en circulation dans le monde atteignait  <a href=\"http:\/\/perspective.usherbrooke.ca\/bilan\/servlet\/BMEve?codeEve=529#http:\/\/perspective.usherbrooke.ca\/bilan\/servlet\/BMEve?codeEve=529\">cinq fois le stock d&rsquo;or de la Fed<\/a>. Nixon a d&ucirc; trancher en ao&ucirc;t 1971 et d\u00e9tacher le dollar de l&rsquo;or, mettant fin \u00e0 l&rsquo;un des principes de Bretton Woods. Nixon a proc\u00e9d\u00e9 \u00e0 deux d\u00e9valuations successives, l&rsquo;once d&rsquo;or \u00e9tait pass\u00e9e de 35 \u00e0 38 puis 42 dollars. C&rsquo;est bien cette faiblesse du dollar qui a induit les chocs p\u00e9troliers et a encourag\u00e9 les pays de l&rsquo;OPEP \u00e0 multiplier le prix du baril libell\u00e9 en dollar.<\/p>\n<\/p>\n<p><p>Cette \u00e9poque de stagnation relative de l&rsquo;\u00e9conomie am\u00e9ricaine a connu un processus inflationniste entam\u00e9 depuis 1962, d&ucirc; au moins \u00e0 deux raisons. L&rsquo;\u00e0-coup de l&rsquo;acc\u00e9l\u00e9ration des d\u00e9penses li\u00e9es \u00e0 la guerre et une politique mon\u00e9taire de la Fed qui contrecarrait les politiques fiscales et budg\u00e9taires en augmentant le cr\u00e9dit et la masse mon\u00e9taire.<\/p>\n<\/p>\n<p><p>D\u00e9ficit budg\u00e9taire et d\u00e9ficit commercial \u00e9tasuniens sont les deux moments d&rsquo;une force qui a fait tourner l&rsquo;\u00e9conomie mondiale. Les Usa impriment du billet vert pour acheter des biens fabriqu\u00e9s pour pas cher ailleurs, d\u00e9truisant leurs infrastructures industrielles, main d&rsquo;&oelig;uvre et son savoir-faire compris. Lequel billet revient \u00e0 la maison, transform\u00e9 en titres et bons du Tr\u00e9sor que l&rsquo;Etat f\u00e9d\u00e9ral propose sans cesse sur le march\u00e9 pour couvrir les frais officiels du Pentagone en expansion constante &#8211; en temps de guerre ou non &#8211; car il s&rsquo;agit de maintenir et d&rsquo;entretenir environ un millier de bases avec son personnel civil et militaire. Le Pentagone est le plus gros  <a href=\"https:\/\/www.mondialisation.ca\/le-pentagone-est-l-un-des-plus-grands-propri-taires-fonciers-du-monde\/4952#https:\/\/www.mondialisation.ca\/le-pentagone-est-l-un-des-plus-grands-propri-taires-fonciers-du-monde\/4952\">propri\u00e9taire foncier : plus de 2 millions<\/a>  d&rsquo;hectares. Chalmers Johnson (1931- 2010) avait acquis <a href=\"http:\/\/americanempireproject.com\/authors\/chalmers-johnson\/#http:\/\/americanempireproject.com\/authors\/chalmers-johnson\/\">une expertise certaine<\/a>  \u00e0 d\u00e9masquer les artifices utilis\u00e9s pour r\u00e9duire la taille de l&#8217;empire militaire \u00e9tasunien. Pour l&rsquo;exercice de 2008, 23 milliards \u00e9taient dissimul\u00e9s dans le d\u00e9partement de l&rsquo;\u00e9nergie alors qu&rsquo;elles allaient \u00e0 des applications militaires, comme minerai et ogives, les cr\u00e9dits d&rsquo;assistance militaire pour l&rsquo;Egypte, Isra\u00ebl, le Bahrein etc pour 25 milliards sont rang\u00e9s dans le budget du D\u00e9partement d&rsquo;Etat, retraites et cr\u00e9dits aux anciens combattants, et surtout les activit\u00e9s paramilitaires du Renseignement sont tenues secr\u00e8tes. Le budget global consenti par le Congr\u00e8s \u00e0 l&rsquo;administration de la Maison Blanche en 2009 \u00e9tait de  <a href=\"https:\/\/blog.mondediplo.net\/2009-05-19-Operation-Vertige#https:\/\/blog.mondediplo.net\/2009-05-19-Operation-Vertige\">533 milliards<\/a>  de dollars, les d\u00e9penses dissimul\u00e9es comptent pour un bon 1\/6 de cette masse. Quant \u00e0 la partie totalement occult\u00e9e car comptabilis\u00e9e nulle part, elle a repr\u00e9sent\u00e9 entre 1998 et 2005 quelques  <a href=\"http:\/\/www.dedefensa.org\/article\/non-a-la-guerre#http:\/\/www.dedefensa.org\/article\/non-a-la-guerre\">21 000 milliards<\/a>  d&rsquo;apr\u00e8s les travaux de Mark Skidmore et Catherine Austin Pitts&hellip; <\/p>\n<\/p>\n<p><p>Le d\u00e9labrement industriel obligea alors l&rsquo;Etat f\u00e9d\u00e9ral \u00e0 adopter des programmes d&rsquo;aide sociale de plus en plus lourds, afin d&rsquo;\u00e9viter les \u00e9meutes (comme celles de 1965). Additionn\u00e9s aux all\u00e8gements fiscaux, r\u00e8gle d&rsquo;or du n\u00e9olib\u00e9ralisme entrepris depuis Reagan, le d\u00e9ficit budg\u00e9taire ne put que s&rsquo;aggraver et requ\u00e9rir l&rsquo;\u00e9mission d&rsquo;obligations sous forme de Bons du Tr\u00e9sor.<\/p>\n<\/p>\n<p><p>La classe ouvri\u00e8re europ\u00e9enne et japonaise puis  chinoise \u00e0 partir de la politique d&rsquo;ouverture de Deng Xiaoping travaillent d\u00e9sormais pour assurer le mode de vie non n\u00e9gociable \u00e0 l&rsquo;Am\u00e9ricain, se fait extraire une plus-value convertie en Dette consentie \u00e0 l&rsquo;Etat f\u00e9d\u00e9ral des Usa qui ne sera jamais rembours\u00e9e. Laquelle Dette assure une certaine paix sociale au c&oelig;ur de l&rsquo;Empire et surtout permet les d\u00e9penses militaires qui maintiennent l&rsquo;h\u00e9g\u00e9monie de la Nation d&rsquo;exception.<\/p>\n<\/p>\n<p><p>Les p\u00e9trodollars ont jou\u00e9 un double r\u00f4le annexe mais loin d&rsquo;\u00eatre n\u00e9gligeable dans la cr\u00e9ation de cette machinerie mon\u00e9taire. Le dollar am\u00e9ricain est la devise institu\u00e9e dans le n\u00e9goce du baril extrait par les p\u00e9tromonarchies et la non r\u00e9injection du produit de la vente dans le circuit financier anglo-saxon sera appr\u00e9ci\u00e9 comme un acte de guerre. C&rsquo;est \u00e0 peu pr\u00e8s dans ces termes que furent accueillies les hausses du prix de l&rsquo;\u00e9nergie fossile d\u00e9tenue par les principaux producteurs, singuli\u00e8rement les S\u00e9oud et les autres roitelets et \u00e9mirs du golfe. Les autres pays en exc\u00e9dent commercial avec les Usa recyclent les dollars qu&rsquo;ils ont per\u00e7us, sous la contrainte de voir monter les taux de change de leur propre monnaie qui risquerait d&rsquo;\u00eatre appr\u00e9ci\u00e9e en cas de cumul trop important de dollars. Or une monnaie trop on\u00e9reuse est d\u00e9favorable aux exportations.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Guerre permanente d\u00e9l\u00e9gu\u00e9e aux mercenaires <\/h3>\n<\/p>\n<p><p>La guerre de Cor\u00e9e puis celle du Vietnam commenc\u00e9e d\u00e8s 1954 par le soutien aux dirigeants politiques du Sud-Vietnam ont bien \u00e9t\u00e9 les circonstances que se sont donn\u00e9es les Usa pour construire le mod\u00e8le \u00e9conomique de guerre permanente sur le plan national et international contre le communisme, dont les dangers expansionnistes ont \u00e9t\u00e9 exag\u00e9r\u00e9s \u00e0 dessein bien avant l&rsquo;invention de guerre pr\u00e9ventive des n\u00e9oconservateurs. Tout un arsenal juridique concernant la s\u00e9curit\u00e9 int\u00e9rieure et les pouvoirs budg\u00e9taires accrus accord\u00e9s \u00e0 l&rsquo;ex\u00e9cutif ont \u00e9t\u00e9 revus \u00e0 la baisse, la guerre du Vietnam et le Watergate y ont chacune contribu\u00e9, de m\u00eame la mont\u00e9e continue du d\u00e9ficit et les gels des cr\u00e9dits (impoundment) vot\u00e9s par le Pr\u00e9sident.  <a href=\"https:\/\/budgetcounsel.files.wordpress.com\/2017\/12\/c2a7-26-introduction-and-sequestration-generally2.pdf#https:\/\/budgetcounsel.files.wordpress.com\/2017\/12\/c2a7-26-introduction-and-sequestration-generally2.pdf\">En 1974, la loi dite<\/a>  Congressional Budget Act permet au Congr\u00e8s d&rsquo;exprimer sa propre position budg\u00e9taire ind\u00e9pendante de celle de l&rsquo;ex\u00e9cutif. Un organisme ind\u00e9pendant d&rsquo;analyses et d&rsquo;\u00e9tudes fut cr\u00e9\u00e9, le nombre de commissions s&rsquo;est multipli\u00e9, il en est des fiscales, des budg\u00e9taires et des d\u00e9pensi\u00e8res. La complexit\u00e9 des proc\u00e9dures et leur d\u00e9centralisation sous pr\u00e9texte de limiter le pouvoir budg\u00e9taire de la Maison Blanche a paradoxalement favoris\u00e9 le financement occulte et incontr\u00f4l\u00e9 du Pentagone et des entit\u00e9s connexes du Renseignement et des Op\u00e9rations sp\u00e9ciales. C&rsquo;est dans ce contexte de rationalisation et de relatif contr\u00f4le budg\u00e9taire que de plus en plus \u00e0 des soci\u00e9t\u00e9s militaires priv\u00e9es ont \u00e9t\u00e9 incorpor\u00e9es dans l&rsquo;organisation de la s\u00e9curit\u00e9 int\u00e9rieure et la d\u00e9fense nationale. D\u00e9s les ann\u00e9es 90, l&rsquo;outsourcing ou l&rsquo;externalisation des services aux arm\u00e9es \u00e9tasuniennes s&rsquo;est \u00e9tendue. Lors de la guerre du Golfe de 1991, le ratio \u00e9tait d&rsquo;un priv\u00e9 pour 100 soldats, il est pass\u00e9 de 1 \u00e0 10 pour l&rsquo;invasion de l&rsquo;Irak en 2003. Les acteurs priv\u00e9s repr\u00e9sentent actuellement au moins 20% des forces \u00e9tasuniennes dans l&rsquo;Orient arabe et sans doute plus en Afrique. Les services priv\u00e9s ont concern\u00e9 la logistique, le maintien du mat\u00e9riel, l&rsquo;entretien et la s\u00e9curit\u00e9 des bases militaires. Puis d&rsquo;autres comp\u00e9tences comme les syst\u00e8mes d&rsquo;armes et le renseignement leur ont \u00e9t\u00e9 attribu\u00e9s au pr\u00e9texte d&rsquo;une meilleure efficacit\u00e9 et flexibilit\u00e9 que les modes conventionnels. Les guerres de l&rsquo;information offensive leur sont d\u00e9volues et ils jouent un plus grand r\u00f4le dans la configuration des guerres asym\u00e9triques. La nouvelle architecture militaire ne s&rsquo;est pas accompagn\u00e9e d&rsquo;une \u00e9volution des instruments de contr\u00f4le politique comme le d\u00e9plorait le Government Accounting Office d\u00e8s 2003. Dans  <a href=\"https:\/\/www.gao.gov\/new.items\/d06865t.pdf#https:\/\/www.gao.gov\/new.items\/d06865t.pdf\">un rapport au S\u00e9nat,<\/a> il d\u00e9non\u00e7ait un manque de visibilit\u00e9, une opacit\u00e9 de la cha&icirc;ne de direction, des d\u00e9rives financi\u00e8res et l&rsquo;absence de supervision \u00e0 propos des soci\u00e9t\u00e9s militaires priv\u00e9es en Irak. <a href=\"https:\/\/webcache.googleusercontent.com\/search?q=cache:livxx8FSqHAJ:https:\/\/tel.archives-ouvertes.fr\/tel-01143455+&#038;cd=1&#038;hl=fr&#038;ct=clnk&#038;gl=ma&#038;client=safari#https:\/\/webcache.googleusercontent.com\/search?q=cache:livxx8FSqHAJ:https:\/\/tel.archives-ouver\">Une th\u00e8se en Droit public<\/a>  soutenue \u00e0 Lille en 2014 par Babou Ciss\u00e9 d\u00e9veloppe cet aspect des activit\u00e9s militaires et s\u00e9curitaires aux Usa au regard du droit est ais\u00e9ment consultable. Les entreprises militaires priv\u00e9es se voient confier des t\u00e2ches comme l&rsquo;int\u00e9gration entre militaires et civils, soit le Pentagone, le Secr\u00e9tariat d&rsquo;Etat et l&rsquo;USAID dans les phases de reconstruction. Les ONG ont aussi recours \u00e0 des soci\u00e9t\u00e9s militaires priv\u00e9es. Des priv\u00e9s interviennent dans des op\u00e9rations de contre-terrorisme <a href=\"https:\/\/apps.dtic.mil\/docs\/citations\/ADA415779#https:\/\/apps.dtic.mil\/docs\/citations\/ADA415779\">aupr\u00e8s de groupes paramilitaires<\/a> de la CIA. Le Lieutenant-colonel Marie-Dominique Charlier, charg\u00e9e d&rsquo;\u00e9tudes \u00e0 l&rsquo;Irsem est intervenue six mois de f\u00e9vrier \u00e0 ao&ucirc;t 2008 comme conseiller politique (political advisor ou polad) aupr\u00e8s de la cha&icirc;ne de commandement de l&rsquo;OTAN en Afghanistan. Les Usa avaient en effet r\u00e9ussi  <a href=\"https:\/\/www.nato.int\/cps\/fr\/natohq\/topics_69366.htm#https:\/\/www.nato.int\/cps\/fr\/natohq\/topics_69366.htm\">le coup de force<\/a>  de transf\u00e9rer la direction de la Force Internationale d&rsquo;assistance \u00e0 la s\u00e9curit\u00e9 (FIAS) mandat\u00e9e par l&rsquo;ONU \u00e0 l&rsquo;OTAN en ao&ucirc;t 2003, sans que nul ne se soit souci\u00e9 de tenter une protestation, l&rsquo;hegemon devenu indiscutable. <a href=\"\/#Etudes+n%C2%B01+Les_crises_en_Afghanistan.pdf\">Le rapport<\/a>  qu&rsquo;elle a pu \u00e9tablir \u00e0 partir de ses observations qui n&rsquo;ont souffert d&rsquo;aucune limitation de d\u00e9placement, fait rare, est fort instructif. Elle y fait le constat implacable du ratio1 soldat\/ 1 contractor, de l&rsquo;absorption de toute &laquo; l&rsquo;aide &raquo; \u00e0 la reconstruction par les SMP et surtout de l&rsquo;absence de volont\u00e9 de ces SMP d&rsquo;accomplir la t\u00e2che de formation de l&rsquo;arm\u00e9e afghane pour ne pas se priver de leur source de revenus. Elle conclut par une formule judicieuse, plut\u00f4t qu&rsquo;\u00e0 l&rsquo;externalisation de certaines fonctions militaires, on assiste \u00e0 l&rsquo;externalisation de la guerre. Ce sont ces m\u00eames SMP qui \u00e9laborent les doctrines politiques \u00e0 l&rsquo;usage de l&rsquo;OTAN et l&rsquo;Etat f\u00e9d\u00e9ral \u00e9tasunien, on ne peut douter qu&rsquo;elles feront en sorte que durent la guerre et leurs profits.<\/p>\n<\/p>\n<p><p>Tous les services de renseignement, CIA, DIA, NSA ainsi que des r\u00e9seaux clandestins sont d\u00e9sormais truff\u00e9s de hordes de &lsquo;contractants priv\u00e9s&rsquo;. En 2006,  <a href=\"https:\/\/www.truthdig.com\/articles\/the-military-industrial-complex-its-much-later-than-you-think\/#https:\/\/www.truthdig.com\/articles\/the-military-industrial-complex-its-much-later-than-you-think\/\">42 milliards soit 70%<\/a>  de ce que le gouvernement f\u00e9d\u00e9ral consacre \u00e0 la surveillance et \u00e0 l&rsquo;espionnage \u00e9taient aux mains de soci\u00e9t\u00e9s mercenaires qui employaient 17 500 agents \u00e0 plein temps. L&rsquo;id\u00e9ologie technologiste alimente un besoin insatiable en enregistrement et conservation de donn\u00e9es. A peine 5% sont traduits en une forme analysable. Science Applications International Corporation, <a href=\"http:\/\/www.saic.com\/#http:\/\/www.saic.com\">SAIC<\/a>, gratifie 42 000 employ\u00e9s \u00e0 San Diego avec de tr\u00e8s hauts salaires et remplace la NSA dans la collecte des signaux pour le renseignement. Les livres de comptabilit\u00e9 qui traitent des d\u00e9penses pour Blackwater devenu Xe puis Academi et maintenant revendu, Dyncop &#038; Triple Canopy sont tenus hors de vue, autorisant la dissimulation du co&ucirc;t des guerres.<\/p>\n<\/p>\n<p><p>Ce transfert vers le priv\u00e9 de l&rsquo;arme et de l&rsquo;espionnage a commenc\u00e9 sous Reagan mais a connu sa plus ample expansion sous Clinton. Bush et Dick Cheney n&rsquo;ont permis son acc\u00e9l\u00e9ration en ajoutant une rationalisation id\u00e9ologique au ph\u00e9nom\u00e8ne de la disparition de l&rsquo;Etat au profit du priv\u00e9 apr\u00e8s le 9\/11. Dans le m\u00eame temps, la CIA, la NSA et le DIA perdaient leurs capacit\u00e9s fonctionnelles et ne pouvaient plus les transmettre aux nouvelles recrues. Le r\u00e8gne des incomp\u00e9tents est advenu en leur sein. Mais surtout, une telle complexit\u00e9 incontr\u00f4l\u00e9e met le renseignement de la puissance h\u00e9g\u00e9monique \u00e0 la port\u00e9e et au service de n&rsquo;importe quel ma&icirc;tre chanteur, manipulateur et surtout Etat \u00e9tranger.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Le monde Post-sovi\u00e9tique, sino-am\u00e9ricain<\/h3>\n<\/p>\n<p><p>Depuis la Grande D\u00e9pression r\u00e9solue gr\u00e2ce \u00e0 la guerre mondiale deuxi\u00e8me du nom, le syst\u00e8me capitaliste s&rsquo;est incarn\u00e9 dans une entit\u00e9 qui lui avait sauv\u00e9 la mise, l&rsquo;\u00e9conomie de guerre. Quand il n&rsquo;a plus eu affaire \u00e0 l&rsquo;ennemi communiste qui nourrissait son destin d&rsquo;affrontement permanent et contre lequel il a form\u00e9 des bataillons de propagandistes cr\u00e9ateurs de fantasmes, il a d&ucirc; bricoler quelque chose de confus et de diffus. Le d\u00e9membrement de la Yougoslavie et la premi\u00e8re guerre du Golfe qui a co&ucirc;t\u00e9 la vie \u00e0 500 000 enfants irakiens en raison de l&#8217;embargo en ont \u00e9t\u00e9 le coup d&rsquo;envoi.<\/p>\n<\/p>\n<p><p>Dix ans plus tard, l&rsquo;Afghanistan et de nouveau l&rsquo;Irak allaient consacrer la mise en application de la &lsquo;Cr\u00e9ation de R\u00e9alit\u00e9&rsquo; et de la guerre pr\u00e9ventive et sans fin contre non un &Eacute;tat ou un groupe d&rsquo;&Eacute;tats, ce qui aurait permis de mesurer son succ\u00e8s et ses effets, mais contre un mode op\u00e9ratoire, le terrorisme de pr\u00e9f\u00e9rence &lsquo;islamiste&rsquo;. Sans opposition aucune par ailleurs aux &Eacute;tats et entit\u00e9s &lsquo;islamistes&rsquo; qui se sont soumises \u00e0 l&#8217;empire et qui sont dans une large mesure d&rsquo;ailleurs les pourvoyeurs du terrorisme takfiri.<\/p>\n<\/p>\n<p><p>L&rsquo;entit\u00e9 \u00e9tasunienne sous-jacente \u00e0 ce fonctionnement a alors connu une maturation et a acquis des caract\u00e8res plus tranch\u00e9s du pr\u00e9dateur qui finit par devenir sa propre proie. La disparition de l&rsquo;arm\u00e9e \u00e9tasunienne et du renseignement sous un enchev\u00eatrement inextricable d&rsquo;int\u00e9r\u00eats priv\u00e9s a transform\u00e9 le Centre du capitalisme mondial en un  <a href=\"http:\/\/www.afrique-asie.fr\/erysichton-le-nom-difficile-a-prononcer-de-celui-qui-se-mange-lui-meme\/#http:\/\/www.afrique-asie.fr\/erysichton-le-nom-difficile-a-prononcer-de-celui-qui-se-mange-lui-meme\/\">nouvel Erysichthon<\/a>. <\/p>\n<\/p>\n<p><p>Le passage de la prosp\u00e9rit\u00e9 avec la p\u00e9riode du fordisme, une industrie nationale au sens classique du 19<sup>\u00e8me<\/sup> si\u00e8cle et des infrastructures robustes, fut bref. L&rsquo;industrie financi\u00e8re de plus en plus exub\u00e9rante et la fuite d&rsquo;un co&ucirc;t exorbitant de la force de travail en rapport avec un logement et des soins de sant\u00e9 on\u00e9reux ont concouru \u00e0 laisser la p\u00e9riph\u00e9rie s&rsquo;occuper de fabriquer des voitures, du v\u00eatement et bient\u00f4t les pourtant indispensables \u00e0 la machine pr\u00e9datrice ordinateurs. L&rsquo;arroseur serait-il d\u00e9sormais arros\u00e9 ?<\/p>\n<\/p>\n<p><p>Au Centre \u00e9choue la tache de produire seulement l&rsquo;environnement culturel qui allait faire passer son r\u00f4le de gendarme du monde en d\u00e9fenseur des ou plut\u00f4t de &lsquo;La Libert\u00e9&rsquo; et d&rsquo;imprimeur-cliqueur de monnaie papier comme \u00e9metteur de &lsquo;richesse&rsquo; &#8230;virtuelle. Tout le monde s&rsquo;apercevait des maladresses de la justification de la destruction de l&rsquo;Afghanistan et de l&rsquo;Irak mais \u00e0 personne n&rsquo;est venue l&rsquo;id\u00e9e qu&rsquo;il ne s&rsquo;agissait pas de ruses supr\u00eames mais d&rsquo;une incomp\u00e9tence la plus ordinaire. Le monde a \u00e9t\u00e9 unifi\u00e9 \u00e9conomiquement sous la houlette de Wall Street mais des diff\u00e9rences de potentiel culturel persistaient malgr\u00e9 le laminage d&rsquo;Hollywood, de l&rsquo;Universit\u00e9 et des mass m\u00e9dias.<\/p>\n<\/p>\n<p><p>Dans l&rsquo;ouverture de la Chine \u00e0 l&rsquo;\u00e9conomie de march\u00e9, l&rsquo;aide militaire aux Usa en Asie \u00e9tait incluse dans le packaging. Le conseiller \u00e0 la S\u00e9curit\u00e9 nationale de l&rsquo;administration Carter, Zbigniew Brzezinski, n&rsquo;a pas \u00e9t\u00e9 seulement l&rsquo;inspirateur de l&rsquo;attraction de l&rsquo;URSS dans le traquenard afghan en 1979. Il avait &oelig;uvr\u00e9 pour cela \u00e0 neutraliser l&rsquo;influence du Secr\u00e9taire d&rsquo;Etat Cyrus Vance favorable \u00e0 un apaisement des tensions avec Moscou et \u00e0 l&rsquo;avanc\u00e9e des n\u00e9gociations de la r\u00e9duction d&rsquo;armement Salt II. Brzezinski \u00e9tait d\u00e9termin\u00e9 \u00e0 jouer la &lsquo;China card&rsquo; d\u00e9j\u00e0 largement amorc\u00e9e par Kissinger. Il d\u00e9clarait lors de sa visite \u00e0 P\u00e9kin en mai 1978 : &laquo; Nous avons \u00e9t\u00e9 alli\u00e9s par le pass\u00e9. Nous devrions collaborer de nouveau face \u00e0 une menace commune. Car l&rsquo;une des caract\u00e9ristiques principales de notre \u00e9poque &ndash; caract\u00e9ristique qui nous am\u00e8ne \u00e0 nous unir &ndash; est l&rsquo;\u00e9mergence de l&rsquo;Union sovi\u00e9tique comme puissance mondiale. &raquo; La rupture des Chinois avec la Grand Fr\u00e8re sovi\u00e9tique allait se traduire par un revers d&rsquo;alliance visible d\u00e9j\u00e0 quand la  <a href=\"https:\/\/reseauinternational.net\/qui-a-soutenu-les-khmers-rouges\/#https:\/\/reseauinternational.net\/qui-a-soutenu-les-khmers-rouges\/\">Chine et les Usa soutiennent les Khmers rouges<\/a> au Cambodge contre l&rsquo;ours russe et le chat vietnamien \u00e0 faire saigner tous les deux. On ignore encore l&rsquo;ampleur de l&rsquo;implication active chinoise aupr\u00e8s des moudjahidines afghans. On sait cependant que la Chine a \u00e9t\u00e9 le premier fournisseur d&rsquo;armement sovi\u00e9tique \u00e0 l&rsquo;interm\u00e9diaire pakistanais. Il a bien fallu les aides conjugu\u00e9es des S\u00e9oud, du Pakistan et de la Chine pour faire durer dix ans l&rsquo;intervention sovi\u00e9tique en faveur du gouvernement de Babrak Karmal puis de Najibullah. D\u00e9cembre 1979 &#8211; f\u00e9vrier 1989 la guerre la plus longue de l&rsquo;URSS a g\u00e9n\u00e9r\u00e9 une d\u00e9moralisation escompt\u00e9e par l&rsquo;architecte du plan afghan. Plus que l&rsquo;engagement mat\u00e9riel et financier pour soutenir Kaboul, il a particip\u00e9 d&rsquo;un bon poids dans la dislocation de l&rsquo;URSS en 1991.<\/p>\n<\/p>\n<p><p>La cr\u00e9ation de zones \u00e9conomiques sociales sur le littoral chinois pour faciliter le transport des mati\u00e8res premi\u00e8res et les exportations allaient donner du r\u00e9pit \u00e0 l&rsquo;\u00e9conomie \u00e9tasunienne mise en difficult\u00e9 par une  <a href=\"https:\/\/www.minneapolisfed.org\/research\/qr\/qr211.pdf#https:\/\/www.minneapolisfed.org\/research\/qr\/qr211.pdf\">inflation et un ch\u00f4mage \u00e9lev\u00e9s<\/a>  au milieu des ann\u00e9es 70 alors qu&rsquo;une seconde  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/R%8Ecession_du_d%8Ebut_des_ann%8Ees_1980_aux_%83tats-Unis#https:\/\/fr.wikipedia.org\/wiki\/R%C3%A9cession_du_d%C3%A9but_des_ann%C3%A9es_1980_aux_%C3%89tats-Unis\">p\u00e9riode r\u00e9cessive<\/a>  allait s&rsquo;ouvrir au d\u00e9but des ann\u00e9es 80. La Chine donnait aux entreprises \u00e9trang\u00e8res une exon\u00e9ration d&rsquo;imp\u00f4ts, un r\u00e9gime d&rsquo;extra-territorialit\u00e9 aux employ\u00e9s des firmes \u00e9trang\u00e8res et offrir l&rsquo;exploitation d&rsquo;une main d&rsquo;&oelig;uvre tr\u00e8s bon march\u00e9 en \u00e9change de l&rsquo;ouverture de la Chine au march\u00e9 mondial. Elle pr\u00e9voyait de sortir de l&rsquo;autarcie jusque l\u00e0 pratiqu\u00e9e par le Parti communiste chinois pour effectuer un rattrapage technologique et industriel rapide. Ce n&rsquo;\u00e9tait l\u00e0 que l&rsquo;un des volets de la r\u00e9forme \u00e9conomique pr\u00e9conis\u00e9e apr\u00e8s la mort de Mao et l&rsquo;\u00e9limination de la bande des quatre.<\/p>\n<\/p>\n<p><p>Deng Xiaoping avait entam\u00e9 en effet une r\u00e9introduction de secteurs capitalistes au niveau de la paysannerie dont une partie de la production qui exc\u00e9dera le quota r\u00e9tribu\u00e9 par l&rsquo;Etat sera vendue sur un march\u00e9 libre. La cr\u00e9ation d&rsquo;entreprises communales et villageoises sous contr\u00f4le des gouvernements locaux mais orient\u00e9s vers le march\u00e9 a permis une production tr\u00e8s dynamique et vari\u00e9e absorbant une main d&rsquo;&oelig;uvre abondante tout en emp\u00eachant un exode rural massif, malheur social des pays en d\u00e9veloppement. Quarante ans apr\u00e8s, la Chine a bien enray\u00e9 le processus de la divergence qui condamne les pays du tiers-monde \u00e0 ne jamais conna&icirc;tre le d\u00e9veloppement des pays &lsquo;riches&rsquo;. Cette mal\u00e9diction est le fruit d&rsquo;un \u00e9change in\u00e9gal structur\u00e9 par la domination financi\u00e8re\/ et militaire des plus anciennement industrialis\u00e9s qui vivent une situation de rente. Cette performance in\u00e9dite, conduire un milliard d&rsquo;humains hors de d&rsquo;une \u00e9conomie majoritairement paysanne, s&rsquo;est r\u00e9alis\u00e9e dans une grande stabilit\u00e9 politique, avec des pertes humaines tr\u00e8s r\u00e9duites en comparaison des co&ucirc;ts repr\u00e9sent\u00e9s par l&rsquo;industrialisation britannique par exemple, au Royaume uni m\u00eame et dans les territoires colonis\u00e9s. Les millions de morts cambodgiens et afghans offerts en sacrifice \u00e0 &lsquo;l&rsquo;amiti\u00e9&rsquo; sino-am\u00e9ricaine sont inclus dans la comptabilit\u00e9 du bond \u00e9conomique chinois.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Levier en forme de bulles <\/h3>\n<\/p>\n<p><p>Est-ce l&rsquo;\u00e9clatement de la bulle des  <a href=\"http:\/\/dot.com\/\">dot.com<\/a>  qui aurait fait planifier par les Usa leur intervention en Afghanistan bien  <a href=\"https:\/\/www.theguardian.com\/world\/2001\/sep\/26\/afghanistan.terrorism4#https:\/\/www.theguardian.com\/world\/2001\/sep\/26\/afghanistan.terrorism4\">avant le 11 septembre 2001<\/a> ? La Guerre perp\u00e9tuelle est d\u00e9clar\u00e9e et la Fed a stimul\u00e9 le secteur immobilier par des taux d&rsquo;int\u00e9r\u00eats tr\u00e8s bas, repoussant \u00e0 2007 l&rsquo;\u00e9clatement de l&rsquo;immobilier \u00e0 risque. L&rsquo;attelage sino-\u00e9tasunien poursuit sa course de guingois, la Chine injectant ses gains en dollars dans les obligations \u00e9mises par le Tr\u00e9sor am\u00e9ricain, perp\u00e9tuant les d\u00e9penses militaires du Gendarme du monde. <\/p>\n<\/p>\n<p><p>En arri\u00e8re-plan, l&rsquo;or sur le march\u00e9 international conna&icirc;  <a href=\"https:\/\/www.loretlargent.info\/aucoffre\/le-cours-de-l%D5or-depuis-13-ans\/13572\/#https:\/\/www.loretlargent.info\/aucoffre\/le-cours-de-l%E2%80%99or-depuis-13-ans\/13572\/\">une hausse de 630%<\/a>  entre 2001 et 2012 et l&rsquo;arr\u00eat de la progression de son cours \u00e0 partir de cette ann\u00e9e ressemble \u00e0 s&rsquo;y m\u00e9prendre \u00e0 une manipulation des cours. L&rsquo;interdit sur la th\u00e9saurisation en or lanc\u00e9 par les Usa \u00e0 ses partenaires commerciaux obligeait le monde \u00e0 n&rsquo;utiliser que le dollar comme r\u00e9serve, il avait commenc\u00e9 \u00e0 \u00eatre lev\u00e9. Le t\u00e9moignage de Jerome Powell, gouverneur de la Fed devant le Congr\u00e8s, lui a permis de r\u00e9it\u00e9rer la semaine pass\u00e9e son opposition au retour \u00e0 une  <a href=\"https:\/\/www.zerohedge.com\/news\/2019-07-21\/why-powell-fears-gold-standard#https:\/\/www.zerohedge.com\/news\/2019-07-21\/why-powell-fears-gold-standard\">monnaie garantie par l&rsquo;or<\/a>. Une telle garantie rendrait impossible le jeu de la cr\u00e9ation mon\u00e9taire sans borne dans le cadre du Quantitative Easing ou assouplissement mon\u00e9taire auquel se livre la Fed et la BCE. Powell a n\u00e9anmoins cit\u00e9 les tensions sur le commerce international comme source d&rsquo;inqui\u00e9tude pour la vigueur de l&rsquo;\u00e9conomie mondiale.<\/p>\n<\/p>\n<p><p>L&rsquo;acquisition de stocks d&rsquo;or par les banques centrales de pays \u00ab\u00a0\u00e9mergeant\u00a0\u00bb est une tendance qui se maintient et  <a href=\"https:\/\/www.lepoint.fr\/economie\/or-la-demande-des-banques-centrales-explose-31-01-2019-2290365_28.php#https:\/\/www.lepoint.fr\/economie\/or-la-demande-des-banques-centrales-explose-31-01-2019-2290365_28.php\">se pr\u00e9cise<\/a>. La  <a href=\"https:\/\/fr.express.live\/russie-reserves-or-dedollarisation\/#https:\/\/fr.express.live\/russie-reserves-or-dedollarisation\/\">Russie<\/a>  se d\u00e9barrasse de ses dollars contre de l&rsquo;or,  <a href=\"https:\/\/fr.express.live\/russie-reserves-or-dedollarisation\/#https:\/\/fr.express.live\/russie-reserves-or-dedollarisation\/\">la Chine<\/a>  apr\u00e8s une petite pause s&rsquo;est remise \u00e0 en acheter. La Dette f\u00e9d\u00e9rale en hausse constante a atteint des niveaux tels que n&rsquo;importe quel investisseur comprend qu&rsquo;elle ne sera jamais pay\u00e9e et que le rendement des Bons du Tr\u00e9sor &#8211; limit\u00e9s par la politique de la Fed qui maintient les taux d&rsquo;int\u00e9r\u00eat au plus bas niveau historique depuis des ann\u00e9es &#8211; est insuffisant pour en rendre le risque attractif. Comme valeur de r\u00e9serve, le dollar ne semble justement plus fonctionner comme valeur de r\u00e9serve. Les pays qui le peuvent pr\u00e9f\u00e8rent effectuer leurs transactions bilat\u00e9rales dans leurs monnaies nationales respectives. Les derni\u00e8res sanctions \u00e9tasuniennes prononc\u00e9es \u00e0 l&rsquo;encontre de l&rsquo;Iran ont provoqu\u00e9 des  <a href=\"https:\/\/www.lopinion.fr\/edition\/wsj\/pays-qui-mettent-defi-dollar-188505#https:\/\/www.lopinion.fr\/edition\/wsj\/pays-qui-mettent-defi-dollar-188505\">tentatives de mesures<\/a>  de pays alli\u00e9s, en particulier de l&rsquo;Union europ\u00e9enne et de l&rsquo;Inde pour tenter de contourner le dollar dans leurs transactions.<\/p>\n<\/p>\n<p><p>L&rsquo;Europe s&rsquo;est lanc\u00e9e dans l&rsquo;\u00e9laboration  <a href=\"https:\/\/business.freefrencharticles.com\/index.php\/2018\/08\/27\/leurope-travaille-sur-une-alternative-au-systme-de-paiement-swift-et-au-fmi-pour-obtenir-une-indpendance-financire-par-rapport-aux-tatsunis.html#https:\/\/business.freefrencharticles.com\/\">d&rsquo;un syst\u00e8me alternatif<\/a>  de paiement \u00e0 SWIFT. Elle a annonc\u00e9 en janvier 2019 la cr\u00e9ation du canal  <a href=\"https:\/\/southfront.org\/europe-launches-swift-alternative-to-send-money-to-iran\/#https:\/\/southfront.org\/europe-launches-swift-alternative-to-send-money-to-iran\/\">INTEX<\/a>  (instrument in support of trace exchange) pour l&rsquo;instant limit\u00e9 aux \u00e9changes humanitaires car au-del\u00e0 du contr\u00f4le des flux de compensation mon\u00e9taire, les USA peuvent prohiber l&rsquo;acc\u00e8s d&rsquo;entreprises \u00e9trang\u00e8res qui bravent leur oukase au march\u00e9 \u00e9tasunien. Des g\u00e9ants comme Total, Siemens, Daimler, Renault ne peuvent pour l&rsquo;instant de se couper de leur d\u00e9bouch\u00e9.<\/p>\n<\/p>\n<p><p>Une s\u00e9rie de banques russes ont de leur c\u00f4t\u00e9 adh\u00e9r\u00e9 au syst\u00e8me international de paiement mis au point par la Chine,  <a href=\"https:\/\/www.zerohedge.com\/news\/2019-03-31\/russian-banks-join-chinas-alternative-swift#https:\/\/www.zerohedge.com\/news\/2019-03-31\/russian-banks-join-chinas-alternative-swift\">CIPS<\/a>, afin de faciliter les \u00e9changes entre les deux pays. En contrepartie, le r\u00e9gulateur de la Banque centrale de Russie souhaite que les partenaires chinois pr\u00eatent plus d&rsquo;attention au syst\u00e8me russe de transfert rapide de messages financiers &#8211; SFPS, r\u00e9seau mis au point d\u00e8s 2014 en r\u00e9ponse \u00e0 la menace \u00e9tasunienne de d\u00e9connecter la Russie de Swift. <\/p>\n<\/p>\n<p><p>Donc les canaux d&rsquo;\u00e9change hors dollar existent, les Banques centrales diversifient leurs r\u00e9serves en devises, affectionnant particuli\u00e8rement l&rsquo;or, tout ceci indique une avanc\u00e9e vers la d\u00e9-dollarisation de l&rsquo;\u00e9conomie-monde. Mieux, les d\u00e9clarations intempestives et inconsid\u00e9r\u00e9es du Pr\u00e9sident Trump concernant la manipulation de sa monnaie par la Chine \u00e0 la baisse pour faciliter ses exportations sont un v\u00e9ritable encouragement \u00e0 d\u00e9laisser l&rsquo;achat des Bons du tr\u00e9sor \u00e9tasunien. L&rsquo;une des mani\u00e8res employ\u00e9es pour ne pas laisser s&rsquo;envoler sa monnaie nationale pour un pays qui commerce avec les USA est d&rsquo;acheter de la Dette \u00e9tasunienne. A plusieurs reprises, le  <a href=\"https:\/\/www.lesaffaires.com\/bourse\/nouvelles-economiques\/aucune-preuve-que-la-chine-manipule-sa-monnaie-selon-le-fmi\/603955#https:\/\/www.lesaffaires.com\/bourse\/nouvelles-economiques\/aucune-preuve-que-la-chine-manipule-sa-monnaie-selon-le-fmi\/60395\">FMI et le Tr\u00e9sor \u00e9tasunien<\/a>  soucieux de la d\u00e9saffection pour les Bons du tr\u00e9sor ont r\u00e9pliqu\u00e9 publiquement qu&rsquo;il n&rsquo;existait aucune preuve d&rsquo;une manipulation des cours. Bien au contraire, la Chine table sur une stabilit\u00e9 de sa monnaie dont elle esp\u00e8re qu&rsquo;elle  <a href=\"https:\/\/www.agefi.com\/home\/news\/detail-ageficom\/edition\/online\/article\/marche-actions-pekin-a-menace-les-speculateurs-de-lourdes-pertes-sils-misaient-sur-la-chute-de-la-devise-488536.html#https:\/\/www.agefi.com\/home\/news\/detail-ageficom\/edition\/on\">acquerra un statut<\/a>  de monnaie de r\u00e9serve et lutte contre toute sp\u00e9culation \u00e0 sa baisse car elle induirait une fuite des capitaux des  <a href=\"https:\/\/www.lesechos.fr\/2009\/05\/la-chine-bouscule-le-classement-des-grandes-places-boursieres-455869#https:\/\/www.lesechos.fr\/2009\/05\/la-chine-bouscule-le-classement-des-grandes-places-boursieres-455869\">places boursi\u00e8res chinoises<\/a>. Celles-ci ont \u00e9t\u00e9 bien chahut\u00e9es en 2018 quand les indices composites de Shanghai et de Shenzhen ont perdu respectivement 24% et 33% dans un environnement de guerre commerciale avec un ralentissement de la croissance du PIB et un resserrement du cr\u00e9dit destin\u00e9 au placement.<\/p>\n<\/p>\n<p><p>Il appara&icirc;t clairement gr\u00e2ce \u00e0 la crise iranienne, plus que celle du Venezuela, que deux vecteurs sur trois de l&rsquo;\u00e9difice financier et mon\u00e9taire \u00e9tasunien sont en train de rompre. Techniquement, le statut de monnaie de r\u00e9serve et d&rsquo;\u00e9change du dollar est en train d&rsquo;\u00eatre perdu, d&rsquo;autant que les crypto-monnaies et l&rsquo;or peuvent le concurrencer sans l&rsquo;aspect martial d&rsquo;une guerre entre monnaies nationales. <\/p>\n<\/p>\n<p><p>La troisi\u00e8me force de nature giratoire, elle fait tourner la finance et \u00e7a donne le vertige, est celle de la dette et du d\u00e9ficit budg\u00e9taire \u00e9tasuniens. Cette machine permet \u00e0 un Etat de faire la guerre en la faisant payer par ses victimes (c&rsquo;est classique), ses alli\u00e9s (des pr\u00e9c\u00e9dents historiques existent aussi) mais aussi ses adversaires pr\u00e9sents et futurs (un peu moins). Elle fonctionne ainsi depuis la guerre de Cor\u00e9e, soit soixante-dix ans, ce qui repr\u00e9sente la dur\u00e9e approximative de la domination d&rsquo;Ath\u00e8nes au travers de la ligue de D\u00e9los (478-404). L&rsquo;originalit\u00e9 de la situation \u00e9tasunienne tient au fait que le &lsquo;Reste du Monde&rsquo; r\u00e9investit son surplus dans le march\u00e9 am\u00e9ricain afin d&rsquo;assurer aux Am\u00e9ricains la possibilit\u00e9 d&rsquo;acheter ses marchandises tout en contribuant au financement du Pentagone.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Plus d&rsquo;appui ni de levier<\/h3>\n<\/p>\n<p><p>En raison d&rsquo;une politique fiscale favorable aux entreprises cens\u00e9e relancer la production et d&rsquo;un gonflement du budget du Pentagone (40 milliards de plus en 2018 et 20 autres additionnels en 2019), le d\u00e9ficit a atteint 5% du PIB, soit le niveau exceptionnel de la Seconde Guerre mondiale et des ann\u00e9es 2008-2009. En 2019-2020, il atteindra 6%, territoire encore inexplor\u00e9 et il sera difficile de pr\u00e9tendre comme l&rsquo;a fait avec arrogance d\u00e9sinvolte Dick Cheney en 2004 &lsquo;Deficits don&rsquo;t matter&rsquo;. Les dettes souveraines, recherch\u00e9es comme placement s\u00e9curis\u00e9 malgr\u00e9 leur faible rendement, sont un instrument important du syst\u00e8me bancaire mondial car elles sont les meilleures garanties pour un emprunt et une protection formidable quand il s&rsquo;agit de d\u00e9fendre sa monnaie nationale quand elle est attaqu\u00e9e. (Le\u00e7on de la crise financi\u00e8re asiatique des ann\u00e9es 90). Cependant elles ont \u00e9t\u00e9 ternies par la crise de 2008 d&rsquo;autant que les Banques centrales se sont transform\u00e9es en banques de d\u00e9faisance pour les banques priv\u00e9es dites &laquo; too big to fail &raquo;. Les pr\u00eateurs vont exiger des taux plus importants, ce qui conduira soit \u00e0 une politique d&rsquo;aust\u00e9rit\u00e9 soit \u00e0 une inflation, augmenter encore davantage la masse mon\u00e9taire pour d\u00e9valuer la dette. Emprunter a donc ses limites. Une anomalie majeure avait \u00e9t\u00e9 per\u00e7ue dans les comptes de la Fed dans la publication trimestrielle du  <a href=\"https:\/\/fiscal.treasury.gov\/files\/reports-statements\/treasury-bulletin\/b2018-4.pdf#v\">Bulletin du Tr\u00e9sor<\/a>  de d\u00e9cembre 2018. Des  <a href=\"https:\/\/econimica.blogspot.com\/2019\/02\/treasury-bulletinnobody-buys-us.html#https:\/\/econimica.blogspot.com\/2019\/02\/treasury-bulletinnobody-buys-us.html\">investisseurs ind\u00e9termin\u00e9s<\/a>  qui ne sont ni la Fed, ni les banques, ni les assureurs, ni les \u00e9trangers emprunteraient \u00e0 court terme (3 000 milliards depuis 2015, c&rsquo;est-\u00e0-dire \u00e0 la fin officielle du programme d&rsquo;assouplissement mon\u00e9taire) pour acqu\u00e9rir des actifs \u00e0 maturit\u00e9 longue ou moyenne avec un \u00e9cart de taux ridiculement bas. Seules des Banques centrales ou leurs interm\u00e9diaires peuvent &lsquo;trouver&rsquo; des sommes aussi importantes pour un papier \u00e0 rendement n\u00e9gatif \u00e0 10 ou 30 ans. Ce stratag\u00e8me a tout l&rsquo;air d&rsquo;un sch\u00e9ma o&ugrave; le Tr\u00e9sor s&rsquo;ach\u00e8te \u00e0 lui-m\u00eame, aid\u00e9 d&rsquo;un dispositif \u00e9cran des obligations qui d\u00e9terminent le taux du cr\u00e9dit hypoth\u00e9caire \u00e0 30 ans. D\u00e9sormais, en plus des B52, de la bombe H, des &lsquo;regime change&rsquo;, des assassinats politiques, les Usa emploient du maquillage et des tours de magie pour sauver leur Ponzi. Pour combien de temps ?<\/p>\n<\/p>\n<p><p>R\u00e9duire le budget du Pentagone ? Impensable, le Secr\u00e9taire \u00e0 la D\u00e9fense qui est en train d&rsquo;\u00eatre confirm\u00e9 par le S\u00e9nat   <a href=\"https:\/\/www.nouvelobs.com\/monde\/20190622.OBS14770\/qui-est-mark-esper-le-nouveau-ministre-de-la-defense-de-trump.html#https:\/\/www.nouvelobs.com\/monde\/20190622.OBS14770\/qui-est-mark-esper-le-nouveau-ministre-de-la-defense-de-trump.html\">n&rsquo;est qu&rsquo;un lobbyiste<\/a>, il a servi Raytheon avant l&rsquo;&Eacute;tat f\u00e9d\u00e9ral et continuera dans cette voie pour retourner au Conseil d&rsquo;administration d&rsquo;une des unit\u00e9s priv\u00e9es du CMI (Complexe militaro-industriel). Le  <a href=\"http:\/\/www.leparisien.fr\/international\/etats-unis-le-nouveau-ministre-de-la-defense-vient-de-chez-boeing-31-12-2018-7978695.php#http:\/\/www.leparisien.fr\/international\/etats-unis-le-nouveau-ministre-de-la-defense-vient-de-chez-boeing-31-12-2018-79\">pr\u00e9c\u00e9dent candidat<\/a>  au remplacement de Mattis avait servi 31 ans Boeing.<\/p>\n<\/p>\n<p><p>En effet, ce genre de toilettage et d&rsquo;arrangements myst\u00e9rieux dans les livres de comptes ne peut rester occult\u00e9s que par la force des ba\u00efonnettes. La Syrie et l&rsquo;Iran d\u00e9montrent que la sup\u00e9riorit\u00e9 de l&rsquo;armement de nouvelle g\u00e9n\u00e9ration russe rendent  inconsistant l&rsquo;hypoth\u00e8se d&rsquo;une guerre \u00e9clair et encore moins d&rsquo;un d\u00e9barquement d&rsquo;intimidation ou punitifs.<\/p>\n<\/p>\n<p><p>Faire des coupes dans la partie non discr\u00e9tionnaire de l&rsquo;Etat, c&rsquo;est-\u00e0-dire les d\u00e9penses dans le social, retraites, \u00e9ducation et soins m\u00e9dicaux pour les plus d\u00e9munis? Ce serait relancer une guerre sociale qui couve d\u00e9j\u00e0. Les r\u00e9voltes des quartiers populaires (et donc noirs) dans les ann\u00e9es 60 avaient d\u00e9termin\u00e9 une relative expansion du budget social f\u00e9d\u00e9ral difficile \u00e0 comprimer.<\/p>\n<\/p>\n<p><p>Le Bureau du Budget au Congr\u00e8s  <a href=\"http:\/\/www.crfb.org\/papers\/cbos-2019-long-term-budget-outlook#http:\/\/www.crfb.org\/papers\/cbos-2019-long-term-budget-outlook\">a publi\u00e9 ses perspectives<\/a>  \u00e0 long terme. Dans une projection \u00e0 30 ans, si les d\u00e9penses et les r\u00e9ductions d&rsquo;imp\u00f4ts continuaient \u00e0 \u00e9voluer selon le rythme actuel, la dette triplera. Elle est d\u00e9j\u00e0 insoutenable, les int\u00e9r\u00eats pay\u00e9s en 2018 repr\u00e9sentent plus que les budgets de l&rsquo;aide m\u00e9dicale, du d\u00e9partement du logement ainsi que de l&rsquo;aide alimentaire sur un d\u00e9ficit record de 779 milliards. Sur les quatre premiers mois de 2019, ils ont connu une hausse de 10% pour la m\u00eame p\u00e9riode en 2018 et vont s&rsquo;\u00e9tablir \u00e0 591 milliards pour 2019, ce qui rapproche consid\u00e9rablement la charge de la dette du d\u00e9ficit !<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">La pluralit\u00e9 contre le global<\/h3>\n<\/p>\n<p><p> Quand cr\u00e8vera-t-elle cette bulle de la dette publique des Usa et avec elle le ballon de baudruche de sa puissance en d\u00e9clin ?<\/p>\n<\/p>\n<p><p> Le sympt\u00f4me Trump qui souhaite redresser l&rsquo;\u00e9conomie \u00e9tasunienne en augmentant les tarifs douaniers et en faisant des cadeaux fiscaux a aggrav\u00e9 les d\u00e9ficit de la balance commerciale car les Am\u00e9ricains ont achet\u00e9 tout bonnement aux Chinois ce qu&rsquo;ils ne produisent pas ou plus. Avant m\u00eame son intervention intempestive sur les tarifs douaniers, le volume et la valeur mondiale des biens surtout et des services \u00e9chang\u00e9s ont connu  <a href=\"https:\/\/unctad.org\/en\/PublicationsLibrary\/ditctab2017d6_en.pdf#https:\/\/unctad.org\/en\/PublicationsLibrary\/ditctab2017d6_en.pdf\">une contraction<\/a>  en 2015 et 2016, il faut souligner que ce sont les \u00e9changes Sud-Sud qui ont fait progresser le commerce mondial ces dix derni\u00e8res ann\u00e9es. La valeur des biens \u00e9chang\u00e9s exprim\u00e9e en pourcentage du PIB mondial n&rsquo;avait cess\u00e9 de progresser depuis les ann\u00e9es 70 atteignant  <a href=\"https:\/\/donnees.banquemondiale.org\/indicateur\/TG.VAL.TOTL.GD.ZS?end=2018&#038;start=1960&#038;view=chart#https:\/\/donnees.banquemondiale.org\/indicateur\/TG.VAL.TOTL.GD.ZS?end=2018&#038;start=1960&#038;view=chart\">le pic mirobolant de 51%<\/a>  en 2008, elle est en 2018 de 46% selon la Banque mondiale. En traduction tr\u00e8s imparfaite, une marchandise produite sur deux est destin\u00e9e \u00e0 l&rsquo;exportation, un tel niveau est in\u00e9dit dans l&rsquo;histoire, expression \u00e0 la fois de l&rsquo;interd\u00e9pendance entre les nations et de l&rsquo;\u00e9normit\u00e9  gargantuesque du transport international. L&rsquo;activit\u00e9 parasite de la distribution prend une importance en proportion de ce trafic, que le droguiste-fleuriste-libraire-etc. g\u00e9ant Jeff Bezos soit devenu l&rsquo;homme le plus riche du monde rend compte de cette aberration.<\/p>\n<\/p>\n<p><p>Tant que le d\u00e9sordre et le pillage \u00e9hont\u00e9 ne concernaient que des contr\u00e9es lointaines, tellement exotiques qu&rsquo;elles en devenaient improbables, la vie en Occident pouvait sembler harmonieuse. La Gr\u00e8ce, pays europ\u00e9en et appartenant \u00e0 l&rsquo;Union europ\u00e9enne, est devenue exsangue pour s&rsquo;\u00eatre faite vampiriser par les banques fran\u00e7aises et allemandes et sa bourgeoisie qui voit ses comptes bancaires gonfler en Suisse. La Deutsche Bank sur l&rsquo;autel de laquelle a \u00e9t\u00e9 sacrifi\u00e9 le peuple grec, ses millions de jeunes ch\u00f4meurs et ses retrait\u00e9s avec une pension amput\u00e9e, n&rsquo;y a gagn\u00e9 qu&rsquo;une r\u00e9mission de courte dur\u00e9e dans une situation de soins palliatifs alors que pauvret\u00e9 et l&rsquo;\u00e9migration des Grecs est durable. Blanchiment d&rsquo;argent, fraudes, abus, falsification de comptabilit\u00e9, voici le  <a href=\"https:\/\/fr.sputniknews.com\/economie\/201905131041104369-deutsche-bank-crise-financiere-mondiale\/#https:\/\/fr.sputniknews.com\/economie\/201905131041104369-deutsche-bank-crise-financiere-mondiale\/\">menu des principales banques<\/a>  que les Banques Centrales ont voulu sauver en instituant l&rsquo;aust\u00e9rit\u00e9. <\/p>\n<\/p>\n<p><p>Le mouvement des Gilets Jaunes en France, ac\u00e9phale mais persistant et profond dit que la polarisation entre les 1% et les 99% est criante au c&oelig;ur du capitalisme et n&rsquo;est plus vivable. Leurs fins de mois de plus en plus difficiles les emp\u00eachent de cesser leur protestation de plus en plus politique. En plus de revenus d\u00e9cents, ils s&rsquo;indignent de la privatisation des biens publics et de la disparition des services publics et r\u00e9clament plus de d\u00e9mocratie r\u00e9elle. La r\u00e9pression qu&rsquo;ils subissent est \u00e0 la mesure de leur mise en danger d&rsquo;un syst\u00e8me jusque l\u00e0 confiant dans sa p\u00e9rennit\u00e9. Quand on interroge les Fran\u00e7ais, ils d\u00e9clarent ne plus se contenter d&rsquo;une vie par procuration, celle prodigu\u00e9e par les sympt\u00f4mes &lsquo;people&rsquo; comme Monarc 1<sup>er<\/sup>. Pour 39% d&rsquo;entre eux, une  <a href=\"https:\/\/fr.sputniknews.com\/france\/201903201040427606-france-sondage-ifop-revolution\/#https:\/\/fr.sputniknews.com\/france\/201903201040427606-france-sondage-ifop-revolution\/\">r\u00e9volution est n\u00e9cessaire<\/a>  pour changer une situation devenue intol\u00e9rable.<\/p>\n<\/p>\n<p><p>Sous quelle forme le monde va-t-il sortir de cette lente agonie quand des sympt\u00f4mes comme Trump, vulgaire homme de cirque qui a fait fortune en escroquant des banques, parviennent au pouvoir politique et occupent la sc\u00e8ne m\u00e9diatique ? Le  <a href=\"https:\/\/fr.sputniknews.com\/international\/201907211041732104-un-cimetiere-de-boeing-737-max-decouvert-en-californie\/#https:\/\/fr.sputniknews.com\/international\/201907211041732104-un-cimetiere-de-boeing-737-max-decouvert-en-californie\/\">parking-cimeti\u00e8re<\/a>  de Boeing 737 Max et les d\u00e9g\u00e2ts irr\u00e9versibles port\u00e9s \u00e0 la diversit\u00e9 des esp\u00e8ces t\u00e9moignent que le technologisme ne peut plus nourrir la croyance qu&rsquo;il sauvera l&rsquo;humanit\u00e9. Vu de l&rsquo;Occident, croulant entre une population vieillissante et son incapacit\u00e9 \u00e0 g\u00e9rer paisiblement ses \u00e9migr\u00e9s, le monde nouveau tarde \u00e0 s&rsquo;en d\u00e9gager. En dehors et en d\u00e9pit des points de conflits, nombreux et entretenus d\u00e9sesp\u00e9r\u00e9ment par les avatars de la CIA, l&rsquo;Afrique et l&rsquo;Asie se transforment \u00e0 vue d&rsquo;&oelig;il. Les anciens \u00e9mergeants et les puissances moyennes s&rsquo;y d\u00e9ploient. La Chine s&rsquo;adapte \u00e0 sa position de premi\u00e8re puissance \u00e9conomique acquise apr\u00e8s avoir \u00e9t\u00e9 l&rsquo;alli\u00e9e objective des Usa contre l&rsquo;URSS,  elle \u00e9quipe avec profusion ceux qui en sont rest\u00e9s d\u00e9pourvus de voies de communication (pour que s&rsquo;y d\u00e9versent ses marchandises ?). C&rsquo;est la Russie qui, une nouvelle fois, sous sa forme poutinienne, a fait barrage \u00e0 la barbarie occidentale responsable du d\u00e9litement de l&rsquo;Irak et la Libye (etc.) singuli\u00e8rement en Syrie et au Venezuela.<\/p>\n<\/p>\n<p><p>Certains nationalismes, ceux qui prot\u00e8gent les territoires et leurs habitants de l&rsquo;intrusion d\u00e9stabilisante d&rsquo;une \u00e9conomie-monde qui asservit et prol\u00e9tarise tout ce qu&rsquo;elle contamine sans chercher \u00e0 se projeter comme force conqu\u00e9rante au-del\u00e0, participent \u00e0 cette recomposition.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appui et levier Il aurait plut\u00f4t dit &laquo; Depuis un point o&ugrave; je puisse me tenir fermement, je ferais mouvoir la Terre &raquo;. Peu importe qu&rsquo;il ne l&rsquo;ait pas formul\u00e9 pr\u00e9cis\u00e9ment ainsi mais Archim\u00e8de, fils de Phidias de Syracuse, \u00e9l\u00e8ve de l&rsquo;\u00e9cole d&rsquo;Alexandrie, a \u00e9nonc\u00e9 le principe qu&rsquo;une faible force peut se d\u00e9cupler par un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[3066,12614,3974,4363,3228,2803,11929,2869,2891,15376,3372,3132],"class_list":["post-78759","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-badia-benjelloun-1","tag-americaniste","tag-archimede","tag-argent","tag-capitalisme","tag-crise","tag-effondrement","tag-entropisation","tag-fou","tag-grande","tag-hegemonisme","tag-street","tag-wall"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78759"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78759\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}