{"id":78822,"date":"2019-08-28T15:32:54","date_gmt":"2019-08-28T15:32:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/08\/28\/epstein-option-a-et-option-b\/"},"modified":"2019-08-28T15:32:54","modified_gmt":"2019-08-28T15:32:54","slug":"epstein-option-a-et-option-b","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/08\/28\/epstein-option-a-et-option-b\/","title":{"rendered":"Epstein, option-A et option-B"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Epstein, option-A et option-B<\/h2>\n<\/p>\n<p><p>Une audience g\u00e9n\u00e9rale sur l&rsquo;affaire Epstein a eu lieu hier \u00e0 New York, avec toutes les parties en pr\u00e9sence, &ndash; l&rsquo;accusation (les autorit\u00e9s de New York), les d\u00e9fenseurs d&rsquo;Epstein, les diverses parties civiles qui se sont \u00e9tablies \u00e0 partir de diverses personnes qui ont \u00e9t\u00e9 victimes des activit\u00e9s d&rsquo;Epstein, c&rsquo;est-\u00e0-dire \u00e9videmment des femmes de diff\u00e9rents \u00e2ges. Les positions, r\u00e9percut\u00e9es par divers m\u00e9dias (voir notamment <em><a href=\"https:\/\/www.zerohedge.com\/news\/2019-08-27\/epstein-coward-who-robbed-victims-their-day-court-tuesday-hearing\">ZeroHedge.com<\/a><\/em>) sont les suivantes, telles qu&rsquo;on peut les r\u00e9sumer :<\/p>\n<\/p>\n<p><p>&bull; Le procureur repr\u00e9sentant les autorit\u00e9s l\u00e9gales (New York City et l&rsquo;&Eacute;tat de New York) demande de classer sans suite les poursuites contre Epstein mais pr\u00e9cise qu&rsquo;une telle d\u00e9cision n&rsquo;entrave en rien la poursuite de l&rsquo;enqu\u00eate, notamment sur la possible identification de co-conspirateurs, et l&rsquo;inculpations de personnes dans ce cadre. Il signale qu&rsquo;actuellement, sur le plan f\u00e9d\u00e9ral, le FBI et d&rsquo;autres juridictions continuent d&rsquo;enqu\u00eater sur la mort d&rsquo;Epstein et sur ses activit\u00e9s.<\/p>\n<\/p>\n<p><p>&bull; Les avocats d&rsquo;Epstein contestent la version du suicide et demandent au juge Berman, charg\u00e9 de l&rsquo;affaire, d&rsquo;entreprendre, sous sa propre autorit\u00e9, sa propre enqu\u00eate sur la mort de l&rsquo;accus\u00e9. Les pouvoirs du juge sont tels qu&rsquo;il pourrait intervenir sur place, au MCC (<em>Metropolitan Correctional Center<\/em>), o&ugrave; \u00e9tait emprisonn\u00e9s Epstein, dans sa cellule m\u00eame, et qu&rsquo;il pourrait ainsi ordonner sa propre enqu\u00eate de police.<\/p>\n<\/p>\n<p><p>&bull; Les parties civiles repr\u00e9sentant de nombreuses plaignantes (chiffre inconnu, autour sinon plus de trente femmes) sont en g\u00e9n\u00e9ral pour le maximum d&rsquo;enqu\u00eates, de poursuites, etc., pour faire toute la lumi\u00e8re sur les activit\u00e9s d&rsquo;Epstein. L&rsquo;un des avocat, David Boies repr\u00e9sentant Virginia Giuffre,  accusatrice et victime d&rsquo;Epstein, r\u00e9sume le sentiment g\u00e9n\u00e9ral en estimant qu&rsquo;&laquo; <em>Epstein n&rsquo;a pas agi seul. Il n&rsquo;aurait pas pu faire ce qu&rsquo;il a fait, \u00e0 une telle \u00e9chelle, pendant tant d&rsquo;ann\u00e9es, sans plusieurs autres personnes-clef. Ces personnes doivent assumer leur part de responsabilit\u00e9 et dire ce qu&rsquo;elles savent<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; Le juge n&rsquo;a pas statu\u00e9 sur ces diverses demandes, et pr\u00e9cis\u00e9ment sur la demande de cl\u00f4ture du classement sans suite de l&rsquo;inculpation d&rsquo;Epstein, car il veut examiner toutes ces demandes \u00e0 la lumi\u00e8re des t\u00e9moignages de plusieurs personnes victimes de Epstein, entendues hier, et dont certains ont \u00e9t\u00e9 extr\u00eamement charg\u00e9s d&rsquo;\u00e9motion.<\/p>\n<\/p>\n<p><p>L&rsquo;appr\u00e9ciation qu&rsquo;on peut en tirer \u00e0 ce point est que l&rsquo;extr\u00eame complexit\u00e9 et l&rsquo;ampleur du cas, avec le nombre consid\u00e9rable de parties prenantes, <strong>emp\u00eachent un \u00e9touffement de l&rsquo;affaire<\/strong>, le syst\u00e8me juridique US fonctionnant <strong>comme un bulldozer que rien n&rsquo;arr\u00eate lorsqu&rsquo;on se trouve dans cette sorte ce circonstances<\/strong>. Cela est encore plus compliqu\u00e9 par le fait que cette affaire \u00e9volue en fait dans deux dimensions, chacune d&rsquo;une extr\u00eame importance dans le syst\u00e8me de la communication, et qu&rsquo;il semble extr\u00eamement difficile, voire tout simplement impossible de les annuler toutes deux, alors qu&rsquo;elles semblent promises de plus en plus \u00e0 interagir l&rsquo;une dans l&rsquo;autre, et \u00e0 d\u00e9pendre l&rsquo;une de l&rsquo;autre, notamment (essentiellement) du point de vue capital de la communication:<\/p>\n<p>D&rsquo;une part, la dimension abord\u00e9e jusqu&rsquo;ici prioritairement, avec l&rsquo;implication de personnalit\u00e9s politiques, voire les activit\u00e9s occultes d&rsquo;Epstein (agent de tel ou tel service) ;<\/p>\n<p>D&rsquo;autre part, la dimension \u00ab\u00a0f\u00e9ministe\u00a0\u00bb (c&rsquo;est-\u00e0-dire le sort fait \u00e0 tant de jeunes filles, adolescentes, etc., en nombre impressionnant, sur une dur\u00e9e extraordinairement longue) ; c&rsquo;est un point capital, lorsqu&rsquo;on conna&icirc;t l&rsquo;importance et le poids des questions soci\u00e9tales aujourd&rsquo;hui.  <\/p>\n<\/p>\n<p><p>Jusqu&rsquo;ici, il a \u00e9t\u00e9 surtout question de la premi\u00e8re dimension, \u00e0 peine de la seconde. D\u00e9sormais, on sent que la seconde commence \u00e0 appara&icirc;tre sur le devant de la sc\u00e8ne sans que la premi\u00e8re ne disparaisse, notamment gr\u00e2ce <a href=\"https:\/\/www.dedefensa.org\/article\/epstein-ou-languille-sous-roche\">aux bons soins<\/a> du Washington <em>Post <\/em>(<em>WaPo<\/em>). A ce sujet, on a vu, notamment dans le m\u00eame texte r\u00e9f\u00e9renc\u00e9, combien l&rsquo;attitude du New York <em>Times <\/em>(NYT) diff\u00e9rait du <em>WaPo <\/em>jusqu&rsquo;\u00e0 l&rsquo;exact inverse du \u00ab\u00a0Circulez y a rien \u00e0 voir\u00a0\u00bb. Soudain, changement d&rsquo;attitude du NYT : un tr\u00e8s-abondant article <a href=\"https:\/\/www.nytimes.com\/2019\/08\/26\/us\/epstein-farmer-sisters-maxwell.html\">du 26 ao&ucirc;t<\/a> du susdit quotidien de r\u00e9f\u00e9rence, avec nombre de t\u00e9moignages des victimes d&rsquo;Epstein, porte sur les frasques extraordinaires jusqu&rsquo;\u00e0 l&rsquo;\u00e9trange et au bizarro\u00efde, sorte de labyrinthe kafka\u00efen avec une touche diabolique, non seulement d&rsquo;Epstein mais du non moins \u00e9trange-bizarro\u00efde couple Epstein-Ghislaine Maxwell.<\/p>\n<\/p>\n<p><p>On comprend le sens de la man&oelig;uvre : le NYT, inquiet pour son influence et sa notori\u00e9t\u00e9 des \u00e9panchements du <em>WaPo <\/em>qui mettent en \u00e9vidence sa propre et suspecte retenue dans la dimension politique, se met lui aussi \u00e0 foncer. Simplement <strong>le <em>WaPo <\/em>exploite la dimension politique, disons l&rsquo;option-A<\/strong>, on l&rsquo;a vu pour des raisons peut \u00eatre peu ordinaires et tr\u00e8s-int\u00e9ressantes, mais l<strong>e NYT choisit l&rsquo;option-B, la \u00ab\u00a0dimension f\u00e9ministe\u00a0\u00bb, c&rsquo;est-\u00e0-dire soci\u00e9tale<\/strong> : puisqu&rsquo;il se trouve vuln\u00e9rable, sur son aile <em>DeepState<\/em>, il se renforce sur son aile soci\u00e9tale. Tout cela se comprend et fait aussi bien, bel et bien notre affaire, car les deux domaines, les deux options A et B, <strong>ne s&rsquo;annulent pas mais, au contraire, cheminent c\u00f4te-\u00e0-c\u00f4te<\/strong>.<\/p>\n<\/p>\n<p><p>Un point de d\u00e9tail, qui ne l&rsquo;est certainement pas dans ses prolongements possibles, dans les circonstances et en fonction des forces existantes, en fonction de l&rsquo;importance du syst\u00e8me de la communication. Dans la partie civile se trouvent plusieurs avocats repr\u00e9sentant diverses plaignantes (le flou est complet \u00e0 cet \u00e9gard, sur le nombre, l&rsquo;identit\u00e9 ou l&rsquo;anonymat, etc., de ces plaignantes), <strong>dont <a href=\"https:\/\/en.wikipedia.org\/wiki\/Gloria_Allred\">Gloria Bloom Allred<\/a>, qui se trouvait \u00e0 l&rsquo;audience d&rsquo;hier, qui est une avocate c\u00e9l\u00e8bre des causes f\u00e9ministes militantes<\/strong>. Cela signifie que le lobby hyperpuissant aux USA du f\u00e9minisme et des associations soci\u00e9tales se rapproche d&rsquo;une implication dans l&rsquo;affaire Epstein, <strong>\u00e9videmment contre Epstein et pour une r\u00e9solution la plus compl\u00e8te possible de cette affaire, pour la cause de la d\u00e9fense des femmes<\/strong>.<\/p>\n<\/p>\n<p><p>Si effectivement, l&rsquo;on parvient \u00e0 cette \u00e9volution qui montre une compl\u00e8te autonomie (plut\u00f4t qu&rsquo;ind\u00e9pendance) du mouvement soci\u00e9tal \u00e0 cause de sa propre puissance au sein du Syst\u00e8me, <strong>on en d\u00e9duira sa remarquable \u00e9volution par rapport \u00e0, disons 2013 puisqu&rsquo;un exemple pr\u00e9cis est disponible<\/strong>. Cette ann\u00e9e-l\u00e0, la <em>Gay Pride<\/em>de San Francisco, &ndash; exemple embl\u00e9matique de manifestation soci\u00e9tale, &ndash;fut l&rsquo;objet d&rsquo;une pol\u00e9mique vigoureuse o&ugrave; l&rsquo;on vit le soci\u00e9tal le c\u00e9der compl\u00e8tement au complexe militaro-industriel (avec adjonction du <em>corporate power<\/em>). La chose fut vigoureusement d\u00e9nonc\u00e9e par deux dissidents homosexuels, Glenn Greenwald et Justin Raimondo, &ndash; et elle m\u00e9rite <a href=\"https:\/\/www.dedefensa.org\/article\/gay-daccord-pride-cest-a-voir\">d&rsquo;\u00eatre rappel\u00e9e<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; &#8230;<em>L&rsquo;un ou l&rsquo;autre membre de l&rsquo;organisation, ou l&rsquo;un ou l&rsquo;autre militant, avait pris sur lui, ou sur eux s&rsquo;ils sont plusieurs, d&rsquo;instituer le soldat  <a href=\"http:\/\/en.wikipedia.org\/wiki\/Bradley_Manning\">Bradley Manning<\/a>  comme h\u00e9ros (Grand Marshall) de la Parade. Manning est notoirement homosexuel <\/em>[il\/elle a depuis effectu\u00e9 l&rsquo;op\u00e9ration transgenre pour devenir Chelsea Manning]<em>, en plus d&rsquo;\u00eatre le h\u00e9ros \u00e0 l&rsquo;incroyable courage qui a pass\u00e9 \u00e0 WikiLeaks les centaines de milliers de cables confidentiels des organisations de s\u00e9curit\u00e9 (Pentagone, d\u00e9partement d&rsquo;&Eacute;tat, etc.) du syst\u00e8me de l&rsquo;am\u00e9ricanisme, principal organisme du Syst\u00e8me. Identifi\u00e9 et arr\u00eat\u00e9, Manning subit depuis plus d&rsquo;un an, d&rsquo;une fa\u00e7on absolument arbitraire et m\u00eame totalitaire, \u00e0 l&rsquo;image des pires dictatures, un traitement inhumain et cruel d&rsquo;une barbarie sans pr\u00e9c\u00e9dent. (Nous disons bien \u00ab\u00a0sans pr\u00e9c\u00e9dent\u00a0\u00bb parce que, dans sa sophistication inf\u00e2me, dans sa vindicte aveugle, dans sa haine absolue de tout ce qui n&rsquo;est pas elle, dans sa volont\u00e9 \u00e9galement absolue de d\u00e9shumanisation par la torture, la pression psychologique, l&rsquo;humiliation permanente, dans la dur\u00e9e qu&rsquo;elle imprime \u00e0 toutes ces pratiques, etc., la barbarie moderniste enfant\u00e9e par le Syst\u00e8me et pratiqu\u00e9e dans nombre d&rsquo;organisations de s\u00e9curit\u00e9 des USA est litt\u00e9ralement sans pr\u00e9c\u00e9dent.) Faire de Manning le h\u00e9ros de la Gay Pride, c&rsquo;\u00e9tait l&rsquo;\u00e9vidence m\u00eame selon ce qu&rsquo;on suppose que devrait \u00eatre \u00ab\u00a0l&rsquo;esprit gay\u00a0\u00bb, si la chose existe. Le  <a href=\"http:\/\/lgbtweekly.com\/2013\/04\/26\/sf-pridebradley-manning-will-not-be-a-grand-marshal\">26 avril 2013<\/a>, la \u00ab\u00a0president of the Board of SF Pride\u00a0\u00bb, Lisa L Williams, a pris la d\u00e9cision d&rsquo;annuler presto subito cette d\u00e9cision.<\/em><\/p>\n<p>&raquo; <em>&bull; On trouvera tous les d\u00e9tails de cette op\u00e9ration inf\u00e2me dans une chronique absolument furieuse de Glenn Greenwald, dans le Guardian du  <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2013\/apr\/27\/bradley-manning-sf-gay-pride\">27 avril 2013<\/a>. Greenwald dit non seulement son m\u00e9pris pour cette d\u00e9cision, mais il rajoute les pr\u00e9cisions selon lesquelles la Gay Pride est activement soutenue par l&rsquo;\u00e9l\u00e9ment-clef du Syst\u00e8me dans cette analyse, le corporate power&#8230; Il s&rsquo;agit d&rsquo;une d\u00e9monstration \u00e0 couper le souffle de l&rsquo;asservissement total au Syst\u00e8me de cet \u00e9v\u00e9nement \u00ab\u00a0soci\u00e9tal\u00a0\u00bb qu&rsquo;est l&rsquo;\u00e9volution statutaire de la \u00ab\u00a0communaut\u00e9 gay\u00a0\u00bb. (Cela n&rsquo;a \u00e9videmment rien \u00e0 voir avec le sentiment des gay-militants, selon ce qu&rsquo;il en est. C&rsquo;est \u00e0 eux de comprendre ce qui se passe pr\u00e9cis\u00e9ment, ce qui est fait en leur nom et quel but servent <strong>d&rsquo;abord<\/strong> la sollicitude officielle qui les entoure et les r\u00e9formes fondamentales qui leur sont offertes. C&rsquo;est un d\u00e9fi redoutable qu&rsquo;ils ont \u00e0 relever.)<\/em><\/p>\n<p>[&#8230;]<\/p>\n<p>&raquo; <em>&bull; L\u00e0-dessus, nous nous tournons vers Justin Raimondo, avec sa chronique d&rsquo;Antiwar.com du  <a href=\"http:\/\/original.antiwar.com\/justin\/2013\/04\/28\/imperial-america-and-the-end-of-progressivism\/%E2%80%AC\">29 avril 2013<\/a>. Justin n&rsquo;allait pas rater l&rsquo;\u00e9v\u00e9nement : libertarien de la droite extr\u00eame, antiguerre et isolationniste, et&#8230; homosexuel qui se garde bien d&rsquo;\u00eatre militant au nom de cette seule caract\u00e9ristique. N\u00e9anmoins, il faisait partie de la premi\u00e8re Gay Pride, non autoris\u00e9e, non sponsoris\u00e9e, \u00e0 San Francisco en 1972. A cette \u00e9poque, la Gay Pride pouvait, selon Raimondo, \u00e9prouver une certaine fiert\u00e9 (pride) d&rsquo;\u00eatre, puisqu&rsquo;elle s&rsquo;affichait d&rsquo;abord dissidente et adversaire de l&rsquo;establishment, du National Security State, &ndash; bref, de ce que nous avons coutume de nommer le Syst\u00e8me.<\/em><\/p>\n<p>&raquo; <em>&#8230; Aujourd&rsquo;hui, constate Raimondo, c&rsquo;est le contraire. Le mouvement gay, c&rsquo;est le Syst\u00e8me m\u00eame ; compl\u00e8tement r\u00e9cup\u00e9r\u00e9, noyaut\u00e9 par les partisans d&rsquo;Obama, devenus quasiment militariste, ce sont les suppl\u00e9tifs des flics du Syst\u00e8me, sinon les flics du Syst\u00e8me eux-m\u00eames. C&rsquo;est Raimondo qui parle, certes, mais nous aurions vraiment beaucoup de peine \u00e0 lui donner tort&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Nous ne dirions certainement pas qu&rsquo;avec ses multiples associations \u00e0 but tr\u00e8s lucratif, ses r\u00e9giments d&rsquo;asserment\u00e9s nous chapitrant sur la libert\u00e9 du monde, avec son emprise incontestable sur la haute morale de l&rsquo;\u00e9poque nous ne dirions pas une seconde que le \u00ab\u00a0syst\u00e8me soci\u00e9tal\u00a0\u00bb s&rsquo;est lib\u00e9r\u00e9 de l&#8217;emprise du Syst\u00e8me (du CMI et du<em>corporate power<\/em>) ; tout au contraire, nous dirons droitement <strong>qu&rsquo;il s&rsquo;est institutionnalis\u00e9, qu&rsquo;il a acquis sa propre puissance et ses propres int\u00e9r\u00eats et sources de revenu au sein du Syst\u00e8me<\/strong>, et qu&rsquo;il n&rsquo;est plus pr\u00eat \u00e0 c\u00e9der aux injonctions d&rsquo;autres composants du Syst\u00e8me.<\/p>\n<\/p>\n<blockquote>\n<p><p>C&rsquo;est effectivement pour cette raison <strong>que l&rsquo;option-B (\u00ab\u00a0Epstein ennemi des femmes comme esclavagiste sexuel\u00a0\u00bb) pourrait bien s&rsquo;av\u00e9rer aussi valable que l&rsquo;option-A (\u00ab\u00a0Epstein et sa troupe de personnalit\u00e9s politiques compromises\u00a0\u00bb)<\/strong> . Elle ne la supprime pas ni ne la supplante, et la logique de ce brillant arrangement serait de les observer cheminant c\u00f4te-\u00e0-c\u00f4te pour notre plus grand plaisir et notre satisfaction esth\u00e9tique d&rsquo;appr\u00e9cier comment le Syst\u00e8me produit ainsi des enfants terribles qui le valent bien, <strong>chacun r\u00e9clamant sa part au risque d&rsquo;\u00e9branler l&rsquo;ensemble<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il ne faut pas s&rsquo;y tromper et garder bon espoir : l&rsquo;affaire Epstein reste plus incandescente que jamais, <strong>avec des braises qui rougeoient, pr\u00eates \u00e0 enflammer ce qui passe \u00e0 port\u00e9e<\/strong>. Le piteux communiqu\u00e9 <a href=\"https:\/\/eu.usatoday.com\/story\/entertainment\/celebrities\/2019\/08\/24\/jeffrey-epstein-prince-andrew-clarifies-relationship-financier-sex-offender\/2107646001\/\">du 24 ao&ucirc;t<\/a>, du Prince Edward, fils d&rsquo;Elisabeth II et petit baiseur de d\u00e9cadence, en dit long \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>Mis en ligne le 28 ao&ucirc;t 2019 \u00e0 15H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Epstein, option-A et option-B Une audience g\u00e9n\u00e9rale sur l&rsquo;affaire Epstein a eu lieu hier \u00e0 New York, avec toutes les parties en pr\u00e9sence, &ndash; l&rsquo;accusation (les autorit\u00e9s de New York), les d\u00e9fenseurs d&rsquo;Epstein, les diverses parties civiles qui se sont \u00e9tablies \u00e0 partir de diverses personnes qui ont \u00e9t\u00e9 victimes des activit\u00e9s d&rsquo;Epstein, c&rsquo;est-\u00e0-dire \u00e9videmment&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[19317,16153,8615,3837,12107,19316,17174,6944,19312,3256,7622,12124,4337,11925,2852,12520,3257],"class_list":["post-78822","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-allred","tag-bloom","tag-domaine","tag-feminisme","tag-gay","tag-ghislaine","tag-gloria","tag-greenwald","tag-maxwell","tag-new","tag-nyt","tag-pride","tag-raimondo","tag-societal","tag-times","tag-wapo","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78822"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78822\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}