{"id":78827,"date":"2019-08-30T19:54:23","date_gmt":"2019-08-30T19:54:23","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/08\/30\/notes-sur-le-doigt-sur-la-detente\/"},"modified":"2019-08-30T19:54:23","modified_gmt":"2019-08-30T19:54:23","slug":"notes-sur-le-doigt-sur-la-detente","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/08\/30\/notes-sur-le-doigt-sur-la-detente\/","title":{"rendered":"Notes sur le doigt sur la d\u00e9tente"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur le doigt sur la d\u00e9tente<\/h2>\n<\/p>\n<p><p>30 ao&ucirc;t 2019 &ndash; D&rsquo;une fa\u00e7on subreptice plus que spectaculaire, l&rsquo;\u00e9norme puissance militaire en d\u00e9clin sinon en d\u00e9liquescence des USA, donc essentiellement le Pentagone, progresse vers une sorte de point de \u00ab\u00a0tout ou rien\u00a0\u00bb o&ugrave; cette puissance <strong>se trouverait accul\u00e9e \u00e0 \u00eatre surpass\u00e9e<\/strong>, refuserait de l&rsquo;\u00eatre, et serait pr\u00eate \u00e0 tous les risques, toutes les aventures pour \u00e9carter cette issue, <strong>jusqu&rsquo;\u00e0 des issues suicidaires emportant les autres dans son effondrement<\/strong>. A cet \u00e9gard, il semble que l&rsquo;abandon du trait\u00e9 FNI, avec le d\u00e9veloppement d&rsquo;un surarmement nucl\u00e9aire \u00e0 capacit\u00e9s op\u00e9rationnelles adapt\u00e9es et tr\u00e8s souples que cela induit, avec les armes jusqu&rsquo;alors interdites par lui, <strong>constitue un tournant dans cette voie<\/strong>.<\/p>\n<\/p>\n<p><p>Nous ne disons pas que ce tournant est con\u00e7u, voulu et n\u00e9goci\u00e9 comme tel, &ndash; comme un instrument pouvant et devant aller jusqu&rsquo;au suicide collectif, &ndash; <strong>mais il s&rsquo;ins\u00e8re parfaitement dans l&rsquo;\u00e9volution des strat\u00e9gies, des conceptions et surtout des psychologies<\/strong>. Dans cet immense asile qu&rsquo;est \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, le Pentagone est en passe de retrouver un r\u00f4le central de fou particuli\u00e8rement actif, sous la direction d&rsquo;un \u00ab\u00a0homme nouveau\u00a0\u00bb qui a le profil de l&#8217;emploi, le nouveau secr\u00e9taire \u00e0 la d\u00e9fense Mark Esper. Guerrier victorieux du temps du sommet de la puissance am\u00e9ricaniste (colonel de l&rsquo;US Army en action durant la premi\u00e8re guerre du Golfe de 1991 puis <em>scholar <\/em>\u00e0 tendance <em>neocon <\/em>\u00e0 <em>Heritage Foundation<\/em> \u00e0 la fin des ann\u00e9es 1990, lobbyiste pour Raytheon durant une d\u00e9cade), Esper repr\u00e9sente avec son caract\u00e8re sombre et ses faibles engagements politiques la personnalit\u00e9 id\u00e9ale pour suivre le Pentagone avec sa bureaucratie \u00e9crasante, et lui permettre de s&rsquo;installer dans <strong>une posture beaucoup plus agressive et activiste que celle qu&rsquo;il eut durant une d\u00e9cennie apr\u00e8s  l&rsquo;attaque du 11-septembre<\/strong>. <\/p>\n<\/p>\n<p><p>Nous suivons pour cette appr\u00e9ciation g\u00e9n\u00e9rale de l&rsquo;\u00e9volution du Pentagone un texte de l&rsquo;analyste Darius Shahtahmasebi, un sp\u00e9cialiste du droit international bas\u00e9 en Nouvelle-Z\u00e9lande, qui est devenu analyste g\u00e9opoliticien et publie notamment dans <em>RT.com<\/em>. Son dernier article, du <a href=\"https:\/\/www.rt.com\/op-ed\/467563-indo-pacific-military-base-us\/\">29 ao&ucirc;t 2019<\/a>, est bienvenu pour donner une base op\u00e9rationnelle \u00e0 notre raisonnement, sous le titre : &laquo; <em>De nouvelles bases pour s&rsquo;opposer \u00e0 la Chine ? La zone Indo-Pacifique est la nouvelle r\u00e9gion prioritaire pour les USA <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Nous allons pr\u00e9senter et d\u00e9velopper notre commentaire \u00e0 partir des trois parties entre laquelle nous avons divis\u00e9 cet article. La premi\u00e8re concerne les projets d&rsquo;expansion du Pentagone dans la zone Indo-Pacifique, puisqu&rsquo;il s&rsquo;av\u00e8re d\u00e9cid\u00e9ment qu&rsquo;avec son plus d&rsquo;un millier de bases outremer, le Pentagone se juge clairement \u00e0 la portion congrue \u00e0 cet \u00e9gard. Il est \u00e9vident qu&rsquo;il n&rsquo;est plus possible, ni de raisonner, ni de contr\u00f4ler <strong>un monstre de cette sorte devenu absolument fou d&rsquo;<em>hybris <\/em>et d&rsquo;aveuglement sur ses propres capacit\u00e9s<\/strong>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Les projets de Mark Esper<\/h3>\n<\/p>\n<p><p>&laquo; <em>Apr\u00e8s avoir d\u00e9vast\u00e9 le Moyen-Orient par des sanctions, des guerres et le soutien d&rsquo;extr\u00e9mistes pour mener des guerres par procuration, les USA se tournent vers la r\u00e9gion Indo-Pacifique. Pour le Pentagone, cette zone, et non le Moyen-Orient, est d\u00e9sormais \u00ab\u00a0prioritaire\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Cette semaine, lors d&rsquo;une intervention au Naval War College, le secr\u00e9taire am\u00e9ricain \u00e0 la D\u00e9fense Mark Esper <a href=\"https:\/\/www.defensenews.com\/pentagon\/2019\/08\/27\/esper-calls-for-new-basing-investments-in-the-pacific\/\">a appel\u00e9 \u00e0 l&rsquo;expansion<\/a> des bases dans la r\u00e9gion du Pacifique, surnommant le th\u00e9\u00e2tre Indo-Pacifique \u00ab\u00a0notre th\u00e9\u00e2tre prioritaire\u00a0\u00bb. Ces remarques s&rsquo;inscrivaient clairement dans le cadre plus large de l&rsquo;objectif du Pentagone de freiner et de contenir l&rsquo;influence croissante de la Chine dans l&rsquo;ensemble de la r\u00e9gion.<\/em><\/p>\n<p>&raquo; <em>M. Esper a clairement indiqu\u00e9 que les &Eacute;tats-Unis avaient identifi\u00e9 un certain nombre d&rsquo;endroits cl\u00e9s de la r\u00e9gion Indo-Pacifique ; ils chercheraient \u00e0 investir \u00ab\u00a0plus de temps et de ressources dans ces zones que nous avons d\u00e9laiss\u00e9es dans le pass\u00e9\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Bien qu&rsquo;il ne soit pas si \u00e9vident de savoir ce que sont ces r\u00e9gions ou lieux, il y a quelques possibilit\u00e9s flagrantes qui viennent \u00e0 l&rsquo;esprit, y compris Singapour, les Philippines, le Vietnam, la Malaisie, l&rsquo;Indon\u00e9sie et m\u00eame certaines des petites nations insulaires du Pacifique moins connues du public am\u00e9ricain comme les Palaos. Les Palaos sont un candidat probable, \u00e9tant donn\u00e9 que les m\u00e9dias occidentaux ont d\u00e9j\u00e0 <a href=\"https:\/\/www.theguardian.com\/global-development\/2018\/sep\/08\/palau-against-china-the-tiny-island-defying-the-worlds-biggest-country\">applaudi<\/a> le fait qu&rsquo;ils ont &laquo; tenu t\u00eate \u00e0 un g\u00e9ant &raquo; <\/em>[P\u00e9kin]<em> sur la question de Taiwan. <\/em><\/p>\n<p>&raquo; <em>Comme l&rsquo;a soulign\u00e9 Eric Sayers du Center for a New American Security, le probl\u00e8me avec des pays comme les Philippines est qu&rsquo;ils peuvent restreindre l&rsquo;acc\u00e8s \u00e0 leurs ports en fonction de la nature du litige. Avec des nations plus petites comme les Palaos, il est probable que les &Eacute;tats-Unis n&rsquo;auraient m\u00eame pas besoin de claquer des doigts pour utiliser cet endroit pour combattre la Chine<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&#8217;empire envers et contre tout<\/h3>\n<\/p>\n<p><p>Comme on le voit, l&rsquo;\u00e9tat d&rsquo;esprit est absolument radical. Le Pentagone \u00e9tant devenu cette puissance qu&rsquo;on sait, \u00e9volua \u00e0 partir de 9\/11 avec une certaine retenue, disons <strong>selon les termes qu&#8217;emploierait la raison bureaucratique de la puissance ma&icirc;tris\u00e9e et irr\u00e9sistible<\/strong> : puisqu&rsquo;il est acquis que rien ne peut nous r\u00e9sister et que tout le monde le reconna&icirc;t, il est inutile de prendre des risques collat\u00e9raux qui pourraient r\u00e9duire notre influence par des difficult\u00e9s inattendues. Pour cette raison, le Pentagone et les chefs militaires frein\u00e8rent pendant ces ann\u00e9es les lubies de leurs directions politiques enfi\u00e9vr\u00e9es par les d\u00e9lires des <em>neocons. <\/em>(C&rsquo;est l&rsquo;U.S. Navy qui, en 2006-2009, bloqua les man&oelig;uvres politiques destin\u00e9es \u00e0 d\u00e9clencher un conflit avec l&rsquo;Iran.)<\/p>\n<\/p>\n<p><p><strong>Aujourd&rsquo;hui, la situation a fondamentalement chang\u00e9<\/strong>. Partout, le Pentagone sent l&rsquo;influence de sa puissance diminuer, et son statut imp\u00e9rial mis ainsi en question. Puisque la puissance n&rsquo;est plus ni ma&icirc;tris\u00e9e, ni irr\u00e9sistible, la \u00ab\u00a0raison bureaucratique\u00a0\u00bb qui l&rsquo;accompagnait dispara&icirc;t et <strong>laisse place \u00e0 des sentiments irrationnels d&rsquo;angoisse, de panique, de fureur destructrice, etc.  <\/strong>D\u00e8s lors, le Pentagone est pouss\u00e9 \u00e0 la radicalit\u00e9 absolue, au \u00ab\u00a0tout ou rien\u00a0\u00bb, suivant une logique folle d&rsquo;engagement extr\u00eame, allant \u00e0 son terme jusqu&rsquo;au nucl\u00e9aire, domaine o&ugrave; les USA poss\u00e8dent \u00e0 la diff\u00e9rence du reste une puissance consid\u00e9rable.<\/p>\n<\/p>\n<p><p>Pour cela, <strong>l&rsquo;abandon du trait\u00e9 FNI est primordial<\/strong>. Il permet la r\u00e9introduction de vecteurs de moyenne port\u00e9e et de th\u00e9\u00e2tre, bas\u00e9s \u00e0 terre (alors que de tels missiles peuvent \u00eatre et ont toujours pu \u00eatre port\u00e9s par des avions, des navires de surface et des sous-marins) ; c&rsquo;est-\u00e0-dire des armes nucl\u00e9aires d\u00e9ploy\u00e9es quasi-exclusivement \u00e0 partir de territoires non-am\u00e9ricains, c&rsquo;est-\u00e0-dire r\u00e9affirmant l&#8217;empire puisqu&rsquo;il s&rsquo;agit de bases constellant les pays associ\u00e9s ou soumis \u00e0 l&#8217;empire, <strong>c&rsquo;est-\u00e0-dire soumettant tout l&#8217;empire \u00e0 la radicalisation du \u00ab\u00a0tout ou rien\u00a0\u00bb du Pentagone<\/strong>.<\/p>\n<\/p>\n<p><p>Mais il y a des obstacles \u00e0 ce programme que sous-tendent avec force l&rsquo;intervention et les projets d&rsquo;Esper et de la bureaucratie qui sont au service de cette entit\u00e9, de cet \u00e9gr\u00e9gore qu&rsquo;est le Pentagone. Certains pays alli\u00e9s, peut-\u00eatre nombre d&rsquo;entre eux, parmi les plus fid\u00e8les, peuvent \u00eatre entrav\u00e9s dans leur soutien jusqu&rsquo;\u00e0 la perspective qu&rsquo;ils puissent le refuser dans certaines circonstances, &ndash; \u00e0 cause des Chinois par exemple&#8230; <strong>N&rsquo;y a-t-il pas de cas plus probant que l&rsquo;Australie, pourtant per\u00e7ue comme alli\u00e8 tr\u00e8s des USA ?<\/strong><\/p>\n<\/p>\n<p><p>Retour au texte de Shahtahmasebi&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;Australie tenue par la Chine<\/h3>\n<\/p>\n<p><p>&laquo; <em>Ce qui sera int\u00e9ressant \u00e0 voir dans les ann\u00e9es \u00e0 venir, c&rsquo;est la place d&rsquo;&Eacute;tats comme l&rsquo;Australie et la Nouvelle-Z\u00e9lande dans ce \u00ab\u00a0th\u00e9\u00e2tre prioritaire\u00a0\u00bb. <\/em><\/p>\n<p>&raquo; <em>Un  <a href=\"https:\/\/www.defensenews.com\/pentagon\/2019\/08\/27\/to-combat-chinas-hold-on-rare-earth-minerals-pentagon-looks-to-australia\/\">rapport r\u00e9cent<\/a><\/em>  <em>sugg\u00e8re que les &Eacute;tats-Unis sont en pourparlers avec le gouvernement australien dans le but de formuler un accord qui permettrait \u00e0 Canberra de traiter une grande quantit\u00e9 de &lsquo;terres rares&rsquo; requises par le Pentagone. L&rsquo;adversaire dans cet \u00e9pisode est \u00e0 nouveau P\u00e9kin, qui maintient un certain monopole sur la production de &lsquo;terres rares&rsquo;, ces mati\u00e8res premi\u00e8res peu r\u00e9pandues qui sont utilis\u00e9es dans les lasers, les radars et m\u00eame les moteurs \u00e0 r\u00e9action.<\/em><\/p>\n<p>&raquo; <em>Toujours \u00e0 propos de la situation strat\u00e9gique de l&rsquo;Australie, un  <a href=\"https:\/\/www.ussc.edu.au\/analysis\/averting-crisis-american-strategy-military-spending-and-collective-defence-in-the-indo-pacific\">groupe de r\u00e9flexion<\/a><\/em>  <em>australien vient d&rsquo;avertir que l&rsquo;arm\u00e9e am\u00e9ricaine est  <a href=\"https:\/\/www.janes.com\/article\/90669\/australian-think-tank-warns-of-overstretched-us-military-in-indo-pacific-region\">surcharg\u00e9e<\/a><\/em>  <em>dans la r\u00e9gion Indo-Pacifique et risque de subir une d\u00e9faite cuisante face \u00e0 P\u00e9kin avant m\u00eame d&rsquo;avoir la possibilit\u00e9 d&rsquo;intervenir. Le rapport indique que \u00ab\u00a0l&rsquo;arsenal croissant de missiles \u00e0 longue port\u00e9e et tr\u00e8s pr\u00e9cis de la Chine constitue une menace majeure pour presque toutes les bases, pistes d&rsquo;atterrissage, ports et installations militaires des &Eacute;tats-Unis, et de ses alli\u00e9s et partenaires dans le Pacifique occidental\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Si quelqu&rsquo;un se demande encore pourquoi la r\u00e9gion Indo-Pacifique est soudainement devenue un \u00ab\u00a0th\u00e9\u00e2tre prioritaire\u00a0\u00bb, cela devrait \u00eatre tout sauf clair \u00e0 ce stade. C&rsquo;est une priorit\u00e9 pour les Etats-Unis car l&rsquo;Am\u00e9rique est sur le point d&rsquo;\u00eatre compl\u00e8tement \u00e9vinc\u00e9e. Effectivement, certains analystes mettent en garde contre cette \u00e9volution depuis <a href=\"https:\/\/www.rt.com\/op-ed\/421726-china-australia-pacific-collision\/\">un certain temps<\/a>.<\/em><\/p>\n<p>&raquo; <em>Encore une fois, je ne suis pas la seule personne \u00e0 mettre ces questions en lumi\u00e8re. Dans un article  <a href=\"https:\/\/www.bbc.com\/news\/world-us-canada-49423590\">de la BBC<\/a>  intitul\u00e9 &laquo; Les &Eacute;tats-Unis sont-ils toujours la seule superpuissance militaire de l&rsquo;Asie ? &raquo;, Jonathan Marcus, correspondant diplomatique et de d\u00e9fense, conclut que &laquo; la pr\u00e9\u00e9minence des &Eacute;tats-Unis dans le Pacifique n&rsquo;existe plus &raquo;. Le probl\u00e8me, comme c&rsquo;est souvent le cas avec les commentateurs occidentaux sur les questions impliquant la domination am\u00e9ricaine dans les grandes affaires g\u00e9opolitiques, est que la question est g\u00e9n\u00e9ralement formul\u00e9e dans la perspective de \u00ab\u00a0Que peuvent bien faire les &Eacute;tats-Unis pour emp\u00eacher la puissance chinoise de se d\u00e9velopper ?\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Or, il se trouve que les &Eacute;tats-Unis devront probablement faire face \u00e0 des v\u00e9rit\u00e9s d\u00e9stabilisantes, en particulier en ce qui concerne cette zone Indo-Pacifique. Le mois dernier, un professeur australien d&rsquo;\u00e9tudes strat\u00e9giques au Strategic and Defence Studies Centre a \u00e9crit dans le Guardian un article d&rsquo;opinion  <a href=\"https:\/\/www.theguardian.com\/world\/commentisfree\/2019\/jul\/15\/australia-must-prepare-for-a-chinese-military-base-in-the-pacific\">estimant essentiellement<\/a><\/em>  <em>que l&rsquo;Australie devra accepter une base militaire chinoise dans la r\u00e9gion \u00e0 un moment donn\u00e9. Contrairement \u00e0 la strat\u00e9gie actuelle de Washington qui consiste \u00e0 essayer (ou \u00e0 esp\u00e9rer) de surpasser la Chine, le professeur Hugh White croit que les \u00ab\u00a0co&ucirc;ts que nous devrions assumer pour emp\u00eacher la Chine d&rsquo;entrer dans la r\u00e9gion pourraient simplement s&rsquo;av\u00e9rer impossibles \u00e0 supporter\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Aussi antagonistes que soient les relations sp\u00e9cifiques de Washington avec P\u00e9kin, les relations entre la Chine et le reste du monde sont trop imbriqu\u00e9es pour s&rsquo;attendre \u00e0 autre chose qu&rsquo;un d\u00e9sastre si l&rsquo;on continue \u00e0 suivre la strat\u00e9gie actuelle. Un rapport r\u00e9cemment publi\u00e9 par le groupe de r\u00e9flexion &lsquo;China Matters&rsquo; vient de  <a href=\"http:\/\/chinamatters.org.au\/wp-content\/uploads\/2019\/08\/China-Matters-Explores-August-2019-embargo-copy.pdf\">conclure<\/a><\/em>  <em>que si la croissance \u00e9conomique de la Chine ne diminuait que de quelques pour cent, l&rsquo;Australie pourrait perdre $140 milliards de revenus et plus d&rsquo;un demi-million d&#8217;emplois<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Apocalypse requise<\/h3>\n<\/p>\n<p><p>Dans de telles conditions et compte tenu du fait que cette situation de tension dans la zone indo-Pacifique se retrouve dans d&rsquo;autres zones, <strong>l&rsquo;esprit du \u00ab\u00a0tout ou rien\u00a0\u00bb et l&rsquo;angoisse de l&rsquo;Empire (du Pentagone) conduisent \u00e0 l&rsquo;hypoth\u00e8se suicidaire<\/strong>. C&rsquo;est la conclusion de Shahtahmasebi :<\/p>\n<\/p>\n<p><p>&laquo; <em>Et il se pourrait que les avanc\u00e9es chinoises ouvre d&rsquo;autres fronts de cette sorte de conflit du fait de la strat\u00e9gie inadapt\u00e9e des USA ; la r\u00e9gion Indo-Pacifique ne serait alors que la pointe \u00e9merg\u00e9e de l&rsquo;iceberg. Dans le cadre de son projet de la Nouvelle Route de la Soie, P\u00e9kin a commenc\u00e9 \u00e0 impliquer dans cette immense initiative des &Eacute;tats des Balkans, ce qui ne fera qu&rsquo;irriter davantage les USA et pourrait les conduire \u00e0 faire quelque chose de terriblement catastrophique en r\u00e9action.<\/em><\/p>\n<p>&raquo; <em>Tous les empires ont une fin. C&rsquo;est un aspect indiscutable de notre histoire. Reste bien s&ucirc;r \u00e0 voir si tous les empires continueront \u00e0 tomber \u00e0 l&rsquo;avenir, mais en g\u00e9n\u00e9ral, nous basons toutes les pr\u00e9dictions futures sur les exp\u00e9riences pass\u00e9es. Jusqu&rsquo;o&ugrave; un empire est pr\u00eat \u00e0 pr\u00e9cipiter sa propre chute avec ses infrastructures imp\u00e9riales pour emp\u00eacher une puissance montante de le d\u00e9passer en profitant de ces infrastructures, c&rsquo;est aussi une hypoth\u00e8se qu&rsquo;il est imp\u00e9ratif de prendre en compte.<\/em><\/p>\n<p>&raquo; <em>Les &Eacute;tats-Unis ont des armes nucl\u00e9aires, beaucoup d&rsquo;armes nucl\u00e9aires, et l&rsquo;id\u00e9e fait de plus en plus son chemin qu&rsquo;ils pourraient les utiliser dans des conditions hors des doctrines courantes, les situations classique o&ugrave; une frappe nucl\u00e9aire est n\u00e9cessaire pour se d\u00e9fendre contre une autre frappe nucl\u00e9aire. Cela voudrait dire de leur part : \u00ab\u00a0H\u00e9, si nous tombons, nous allons entra&icirc;ner  <a href=\"https:\/\/www.rt.com\/op-ed\/464467-nuclear-weapons-doctrine-american\/\">le reste de la plan\u00e8te<\/a><\/em>  <em>avec nous\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Bien entendu, le tableau est notablement incomplet. Il y a des points convergents qui l&rsquo;assombrissent, et d&rsquo;autres, tr\u00e8s divergents, qui le relativisent consid\u00e9rablement.<\/p>\n<\/p>\n<p><p>&bull; Les points convergents concernent l&rsquo;\u00e9vidence que l&rsquo;\u00e9tat d&rsquo;esprit et les mesures qu&rsquo;on distingue concernent aussi bien les autres th\u00e9\u00e2tres d&rsquo;op\u00e9ration, notamment autour de la Russie. Un exemple tr\u00e8s r\u00e9cent, qui a paru d&rsquo;abord \u00eatre une plaisanterie de Trump, est la proposition de rachat du Groenland. Depuis le tweet de Trump, les penseurs-<em>neocon<\/em> se sont empar\u00e9s du sujet, s&rsquo;ils ne l&rsquo;ont inspir\u00e9 eux-m\u00eames bien entendu. D&rsquo;o&ugrave; des  <a href=\"https:\/\/www.zerohedge.com\/news\/2019-08-28\/talk-purchasing-greenland-deterrent-china-and-russia-defense-expert-says\">appr\u00e9ciations argument\u00e9es<\/a>  sur la valeur strat\u00e9gique qu&rsquo;aurait le Groenland pour les USA vis-\u00e0-vis de l&rsquo;Europe et de la Russie.<\/p>\n<\/p>\n<p><p>Dans tous les cas, on a pu entendre Macron, dans son discours aux ambassadeurs, <strong>affirmer que la fin du trait\u00e9 FNI posait un grave probl\u00e8me \u00e0 l&rsquo;Europe<\/strong>, devant ce qu&rsquo;on devine \u00eatre les intentions am\u00e9ricaines de red\u00e9ployer des missiles \u00e0 port\u00e9e interm\u00e9diaire en Europe, comme durant la p\u00e9riode 1983-1987 ; c&rsquo;est dans tous les cas <strong>ce qu&rsquo;on croit distinguer <\/strong>dans ce passage du discours :<\/p>\n<\/p>\n<p><p>&laquo; <em>Nous sommes dans une Europe o&ugrave; nous avons laiss\u00e9 le sujet des armements \u00e0 la main de trait\u00e9s qui \u00e9taient pr\u00e9alables \u00e0 la fin de la guerre froide entre les &Eacute;tats-Unis et la Russie. Est-ce que c&rsquo;est \u00e7a une Europe qui pense son destin, qui construit ? Pour ma part je ne crois pas donc il faut avoir ce dialogue avec la Russie. La fin du trait\u00e9 FNI nous oblige \u00e0 avoir ce dialogue parce que<\/em> [sinon les missiles US] <em>reviendraient sur notre territoire&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Les points divergents, sinon tr\u00e8s divergents, concernent bien entendu les situations int\u00e9rieures, notamment aux USA et dans les pays alli\u00e9s des USA qui seraient sollicit\u00e9s de recevoir les missiles post-FNI. Il s&rsquo;agit d&rsquo;un vaste sujet que nous ne cessons d&rsquo;explorer, &ndash; <strong>surtout la situation de quasi-<a href=\"https:\/\/www.rt.com\/op-ed\/467625-american-patriotism-decline-reasons\/\">guerre civile<\/a> aux USA, dont l&rsquo;importance dans la probl\u00e9matique que nous \u00e9voquons est \u00e9vidente et consid\u00e9rable<\/strong>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une psychologie autonome<\/h3>\n<\/p>\n<p><p>De quoi s&rsquo;agit-il finalement, si l&rsquo;on va au c&oelig;ur de la psychologie qui conduit cette op\u00e9ration qu&rsquo;on pourrait tout simplement baptiser \u00ab\u00a0post-FNI\u00a0\u00bb, <strong>tant la d\u00e9nonciation du trait\u00e9 FNI prend une importance consid\u00e9rable<\/strong> ? Techniquement, derri\u00e8re la rh\u00e9torique de type \u00ab\u00a0d\u00e9fensif\u00a0\u00bb et d&rsquo;\u00e9quilibrage des forces (notamment avec la Chine), il s&rsquo;agit aussi bien et encore plus s&ucirc;rement <strong>d&rsquo;installer la possibilit\u00e9 d&rsquo;une <em>first strike <\/em>nucl\u00e9aire tactique <\/strong>contre la Chine, contre la Russie, et contre d&rsquo;autres peut-\u00eatre ; cette <em>first strike <\/em>nucl\u00e9aire tactique devant en th\u00e9orie annihiler les capacit\u00e9s de riposte nucl\u00e9aire strat\u00e9gique par la destruction de centres de commandement, de communication, etc.<\/p>\n<\/p>\n<p><p>Mais tout cela rel\u00e8ve bien entendu de la rh\u00e9torique technique, d&rsquo;ailleurs soumise \u00e0 de nombreux al\u00e9as comme on l&rsquo;a vu. <strong>Le plus important est l&rsquo;\u00e9tat d&rsquo;esprit, la psychologie que nous nous donnent \u00e0 voir ces divers constats et analyses<\/strong>. Il y a la d\u00e9marche absolument inarr\u00eatable de vivre dans un \u00e9tat de pr\u00e9-affrontement permanent avec des hausses constantes de la tension, dans la perspective d&rsquo;un affrontement probable qui exclut de moins en moins le nucl\u00e9aire dans des conditions op\u00e9rationnelles \u00ab\u00a0normales\u00a0\u00bb. Cet \u00e9tat d&rsquo;esprit est directement d\u00e9pendant du sentiment de d\u00e9clin qui est ressenti au moins inconsciemment, <strong>et jug\u00e9 insupportable et inadmissible par le Pentagone<\/strong>, &ndash; et par cette expression \u00ab\u00a0le Pentagone\u00a0\u00bb, on sugg\u00e9rerait qu&rsquo;il y a l\u00e0 <strong>une perception et une psychologie uniques d\u00e9pendant de cette entit\u00e9 charg\u00e9e \u00e0 la fois de puissances et de symboles<\/strong>. La chose a souvent \u00e9t\u00e9 sugg\u00e9r\u00e9e, aussi bien par un  <a href=\"https:\/\/www.dedefensa.org\/article\/nous-et-le-pentagone\">Alexander Cockburn<\/a>  (&laquo; <em>Le complexe militaro-industriel  <\/em>[CMI]  <em>am\u00e9ricain est devenu un organisme autonome dot\u00e9 d&rsquo;un syst\u00e8me immunitaire qui attaque et \u00e9touffe toute menace \u00e0 son approvisionnement alimentaire, &ndash; l&rsquo;argent des contribuables<\/em>. &raquo;), que par un Rumsfeld  <a href=\"https:\/\/www.dedefensa.org\/article\/rumsfeld-le-jour-davant\">le 10 septembre 2001<\/a>, discourant <strong>en d\u00e9tails saisissant qui repr\u00e9sentent d&rsquo;une fa\u00e7on r\u00e9aliste une entit\u00e9 et une psychologie autonomes<\/strong> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Notre sujet aujourd&rsquo;hui est un adversaire qui constitue une menace, une s\u00e9rieuse menace, contre la s\u00e9curit\u00e9 des &Eacute;tats-Unis d&rsquo;Am\u00e9rique. Cet adversaire est un des derniers bastions de la planification centralis\u00e9e. Il gouverne en \u00e9dictant des plans quinquennaux. D&rsquo;une seule capitale o&ugrave; il se trouve, il tente d&rsquo;imposer ses exigences au travers des fuseaux horaires, des continents, des oc\u00e9ans et au-del\u00e0. Avec une brutale constance, il b\u00e2illonne la pens\u00e9e libre et d\u00e9truit les id\u00e9es nouvelles. Il d\u00e9sorganise la d\u00e9fense des &Eacute;tats-Unis et met en danger les vies des hommes et des femmes en uniforme<\/em>.<\/p>\n<p>&raquo; <em>Peut-\u00eatre cet adversaire para&icirc;t ressembler \u00e0 ce que fut l&rsquo;Union Sovi\u00e9tique, mais cet ennemi s&rsquo;en est all\u00e9 : nos ennemis sont aujourd&rsquo;hui plus subtils et plus implacables. Vous devez penser que je suis en train de d\u00e9crire un de ces dictateurs d\u00e9cr\u00e9pits qui survivent encore. Mais leur temps est pass\u00e9, \u00e0 eux aussi, et ils ne font pas le poids \u00e0 c\u00f4t\u00e9 de cet adversaire que je d\u00e9cris.<\/em><\/p>\n<p>&raquo; <em>Cet adversaire est beaucoup plus proche de nous. C&rsquo;est la bureaucratie du Pentagone. Non pas les gens mais les processus. Non pas les hommes et les femmes en uniforme mais l&rsquo;uniformit\u00e9 de la pens\u00e9e et de l&rsquo;action que nous leur imposons bien trop souvent&#8230; <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Notre Grande Crise d&rsquo;Effondrement du Syst\u00e8me \u00e9tant ce qu&rsquo;elle est, sa r\u00e9solution ne peut passer par une r\u00e9forme quelconque. Il faut des fractures et des ruptures, et la plus indispensable d&rsquo;entre toutes, aujourd&rsquo;hui, concerne le Pentagone <strong>parce qu&rsquo;il s&rsquo;agit d&rsquo;une entit\u00e9 op\u00e9rationnelle disposant des capacit\u00e9s de destruction totale du monde<\/strong> et d&rsquo;une psychologie autonome qui pourrait tendre vers un paroxysme suicidaire. C&rsquo;est pour cette raison que nous jugeons d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale le sort des USA allant vers une d\u00e9sint\u00e9gration comme le facteur n\u00e9cessaire et suffisant dans la possibilit\u00e9 de ces chocs de fracture-rupture qui sont les composants du paroxysme de cette Grande Crise ; <strong>parce que le sort des USA, \u00e0 ce stade de pression de la Grande Crise, d\u00e9terminera celui du Pentagone<\/strong>.<\/p>\n<\/p>\n<p><p>La question est de savoir s&rsquo;il faudra une guerre pour cela, &ndash; ce dont, secr\u00e8tement, le Pentagone-en-crise doit r\u00eaver comme ultime affirmation de sa puissance, &ndash; ou si la possibilit\u00e9 extr\u00eame de la guerre provoquera des chocs internes suffisants aux USA pour <strong>provoquer des temp\u00eates terribles, capables d&#8217;emporter notamment le Pentagone<\/strong>. Dans tous les cas, ce que nous dit Esper, c&rsquo;est que <strong>le Pentagone commence \u00e0 perdre patience <\/strong>devant ces \u00e9v\u00e9nements impr\u00e9vus de son d\u00e9clin qui surviennent, et ces \u00e9v\u00e9nements esp\u00e9r\u00e9s qui ne surviennent pas. Il est possible que l&rsquo;on sache assez vite de quoi il retourne.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur le doigt sur la d\u00e9tente 30 ao&ucirc;t 2019 &ndash; D&rsquo;une fa\u00e7on subreptice plus que spectaculaire, l&rsquo;\u00e9norme puissance militaire en d\u00e9clin sinon en d\u00e9liquescence des USA, donc essentiellement le Pentagone, progresse vers une sorte de point de \u00ab\u00a0tout ou rien\u00a0\u00bb o&ugrave; cette puissance se trouverait accul\u00e9e \u00e0 \u00eatre surpass\u00e9e, refuserait de l&rsquo;\u00eatre, et serait&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[5994,13725,8678,19322,4086,3194,19323,5491,4495],"class_list":["post-78827","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-asie","tag-esper","tag-fni","tag-indo-pacifique","tag-mark","tag-pentagone","tag-shahtahmasebi","tag-suicide","tag-traite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78827"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78827\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}