{"id":78847,"date":"2019-09-14T13:21:59","date_gmt":"2019-09-14T13:21:59","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/09\/14\/la-splendeur-de-landerson\/"},"modified":"2019-09-14T13:21:59","modified_gmt":"2019-09-14T13:21:59","slug":"la-splendeur-de-landerson","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/09\/14\/la-splendeur-de-landerson\/","title":{"rendered":"La splendeur de l&rsquo;Anderson"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La splendeur de l&rsquo;Anderson<\/h2>\n<\/p>\n<p><p>14 septembre 2019 &ndash; Jusqu&rsquo;il y a peu, je restais encore et tout \u00e0 fait accessoirement pour le peu d&rsquo;int\u00e9r\u00eat que je portais au cas, sur un jugement au mieux d\u00e9risoire et un peu m\u00e9prisant pour l&rsquo;actrice Pamela Anderson. Je connaissais vaguement sa notori\u00e9t\u00e9 de mannequin <em>sexy<\/em>, de <em>playmate <\/em>pour <em>Playboy <\/em>(recordwoman des photos de couverture, treize fois entre 1989 et 2011), de vedette de la s\u00e9rie <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alerte_%C3%A0_Malibu\">Alerte \u00e0 Malibu<\/a><\/em>, de ses innombrables mariages et liaisons tonitruantes, vid\u00e9os dites \u00ab\u00a0porno-\u00e9rotiques\u00a0\u00bb avec l&rsquo;un ou l&rsquo;autre de ses maris, etc., bref l&rsquo;arch\u00e9type de celles qu&rsquo;on cat\u00e9gorise \u00e9galement comme des <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Bimbo\">bimbos<\/a><\/em>.<\/p>\n<\/p>\n<p><p>Entretemps, j&rsquo;appris, l\u00e0 encore tout \u00e0 fait accessoirement, qu&rsquo;elle d\u00e9fendait des causes, notamment celle de la d\u00e9fense des animaux, ce qui n&rsquo;\u00e9tait pas antipathique. Mais cela restait bien accessoire, et mon jugement restait celui d&rsquo;une pauvre cr\u00e9ature \u00e0 la fois victime et complice du syst\u00e8me de l&rsquo;<em>entertainment-sexy<\/em>, qui constitue une des branches actives de d\u00e9structuration du Syst\u00e8me. Tout cela, jusqu&rsquo;au jour o&ugrave; j&rsquo;appris qu&rsquo;elle \u00e9tait devenue une visiteuse assidue de Assange, coinc\u00e9 dans son ambassade \u00e9quatorienne de Londres. Cela \u00e9veilla mon int\u00e9r\u00eat pour elle, quoique certains pouvait y voir des missions du type \u00ab\u00a0repos du prisonnier\u00a0\u00bb. On se d\u00e9fait difficilement des jugements accessoires sugg\u00e9r\u00e9s pour le Syst\u00e8me, tant qu&rsquo;on ne les a pas explor\u00e9s au plus pr\u00e8s pour les pulv\u00e9riser.<\/p>\n<\/p>\n<p><p>Ces derni\u00e8res semaines, j&rsquo;ai enfin compl\u00e8tement r\u00e9vis\u00e9 ce jugement, et ne consid\u00e8re plus qu&rsquo;il soit accessoire. Anderson, qui est aussi une v\u00e9ritable actrice, s&rsquo;est r\u00e9v\u00e9l\u00e9e comme une femme courageuse, sinon h\u00e9ro\u00efque. Elle continue \u00e0 suivre Assange et elle a \u00e9t\u00e9 l&rsquo;un de ses premiers visiteurs (deux heures en mai dernier) dans l&rsquo;ignoble prison de Belmarsh o&ugrave; la d\u00e9mocratie britannique le retient <strong>dans des conditions f\u00e9roces, que ni la Gestapo ni le NKVD ne d\u00e9sapprouveraient<\/strong>. (&laquo; <em>Quand je l&rsquo;ai vu, il \u00e9tait mince. Mais ses yeux \u00e9taient clairs et concentr\u00e9s. Ses cheveux \u00e9taient peign\u00e9s. Il \u00e9tait ras\u00e9 de pr\u00e8s. Il \u00e9tait pr\u00eat. Comme un soldat&#8230; Il a tant sacrifi\u00e9 et il est vuln\u00e9rable maintenant. Il compte sur nous tous pour le sauver et il sait que nous l&#8217;emporterons si nous restons concentr\u00e9s et implacables<\/em>. &raquo;)<\/p>\n<\/p>\n<p><p><strong>D\u00e9sormais, tout le monde prend Anderson au s\u00e9rieux, politiquement parlant<\/strong>. Elle a figur\u00e9 avec un brio \u00e9tonnant et une belle ma&icirc;trise de soi dans le fameux <em>talk-show <\/em>politique de ABC, &lsquo;<em>The View<\/em>&lsquo;. A la suite de cette performance, <strong>l&rsquo;aust\u00e8re et spartiate site trotskiste <\/strong>que nous connaissons bien, <em>WSWS.org<\/em>, a consacr\u00e9 <strong>deux articles de suite<\/strong>\u00e0 celle dont les jugements rapides, dont le mien, faisaient une <em>bimbo <\/em>sans la moindre profondeur. Dans le premier, du 9 septembre (version fran\u00e7aise du <a href=\"file:\/\/\/\/Users\/philippe\/Documents\/ACTU-DOC-AAA-transfertportable.20171027\/%22Quand%20je%20l'ai%20vu,%20il%20%C3%A9tait%20mince.%20Mais%20ses%20yeux%20%C3%A9taient%20clairs%20et%20concentr%C3%A9s.%20Ses%20cheveux%20%C3%A9taient%20peign%C3%A9s.%20Il%20%C3%A9tait%20ras%C3%A9%20de%20pr%C3%A8s.%20Il%20%C3%A9tait%20pr%C3%AAt.%20Comme%20un%20soldat....%20Il%20a%20tant%20sacrifi%C3%A9%20et%20est%20vuln%C3%A9rable%20maintenant.%20Il%20compte%20sur%20nous%20tous%20pour%20le%20sauver%20et%20il%20sait%20que%20nous%20l'emporterons%20si%20nous%20restons%20concentr%C3%A9s%20et%20implacables.%22\">12 septembre<\/a>) <em>WSWS.org <\/em>rendait compte de l&rsquo;\u00e9mission du 6 septembre<\/p>\n<\/p>\n<p><p>&laquo; &#8230;<em>Anderson a r\u00e9pondu de fa\u00e7on tranchante en posant la question: \u00ab\u00a0Combien de personnes innocentes le gouvernement am\u00e9ricain a-t-il tu\u00e9es, et combien WikiLeaks en a-t-il tu\u00e9es ?<\/em>[&#8230;] <em>L&rsquo;arm\u00e9e a mis de nombreuses vies innocentes en danger\u00a0\u00bb, a-t-elle d\u00e9clar\u00e9.<\/em><\/p>\n<p>&raquo; <em>Un certain nombre de membres de l&rsquo;auditoire ont applaudi aux d\u00e9clarations factuelles et franches d&rsquo;Anderson, qui sont si rares \u00e0 la t\u00e9l\u00e9vision commerciale. Meghan McCain<\/em>[la fille du s\u00e9nateur McCain, r\u00e9cemment d\u00e9c\u00e9d\u00e9]<em>, visiblement en col\u00e8re, a ordonn\u00e9 aux interrupteurs de \u00ab\u00a0se calmer\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Anderson, malgr\u00e9 l&rsquo;intervention provocatrice de McCain, a continu\u00e9: \u00ab\u00a0Des crimes de guerre ont \u00e9t\u00e9 commis et ils doivent \u00eatre punis et ils ne l&rsquo;ont pas \u00e9t\u00e9. Personne ne s&rsquo;est occup\u00e9 des crimes de guerre qu&rsquo;Assange a expos\u00e9s, mais ils l&rsquo;ont mis en prison pour le faire taire.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le <a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/09\/13\/ande-s13.html\">13 septembre<\/a>, donc, un deuxi\u00e8me article de <em>WSWS.org <\/em>\u00e9tait consacr\u00e9 \u00e0 Anderson, cette fois avec une interview de l&rsquo;actrice par le site trotskiste.<\/p>\n<\/p>\n<p><p>&laquo; <em>WSWS.org a interrog\u00e9 Anderson sur l&rsquo;exp\u00e9rience de sa participation \u00e0 &lsquo;The View&rsquo;. Elle a r\u00e9pondu : \u00ab\u00a0Je suis toujours pr\u00eate \u00e0 avoir une conversation solide et j&rsquo;en ai tant entendu. Mais l\u00e0, j&rsquo;ai vu avec stup\u00e9faction cinq femmes intelligentes, pour lesquelles j&rsquo;ai beaucoup de respect, avec tant de points de vue d\u00e9form\u00e9s, n\u00e9gatifs, d\u00e9sinform\u00e9s et compl\u00e8tement propagandistes.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Elle a not\u00e9 que cela \u00e9tait li\u00e9 \u00e0 une longue campagne de diffamation contre Assange : \u00ab\u00a0J&rsquo;entends les m\u00eames choses de beaucoup de gens : &lsquo;Cet homme est mauvais&rsquo;, &lsquo;Il blesse des gens&rsquo;, etc. Mais quand vous demandez pourquoi ou qui, ils ne savent pas ! Et il faut habituellement du temps, des heures ou des liens vers des faits av\u00e9r\u00e9s pour faire comprendre aux gens qu&rsquo;ils ont \u00e9t\u00e9 intoxiqu\u00e9s par la campagne de diffamation. &Ccedil;a a malheureusement march\u00e9, et Julian n&rsquo;a pas eu le soutien dont il avait besoin<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Voil\u00e0&#8230; d\u00e9sormais, Anderson est compl\u00e8tement sur la liste noire du Syst\u00e8me, car il appara&icirc;t bien qu&rsquo;une d\u00e9fense et un activisme s\u00e9rieux et politique en faveur d&rsquo;Assange <strong>rel\u00e8vent du \u00ab\u00a0crime contre le Syst\u00e8me\u00a0\u00bb parmi les plus impardonnables<\/strong>. J&rsquo;en veux pour un signe de plus une petite f\u00e9lonie de <em>Wikip\u00e9dia<\/em>, qu&rsquo;on peut mettre dans la m\u00eame poubelle que les GAFA \u00e0 cet \u00e9gard, pour ce qui est du respect des consignes du Syst\u00e8me. Dans le sujet que <em>Wiki <\/em>consacre <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pamela_Anderson\">\u00e0 Pamela Anderson<\/a>, &ndash; qui n&rsquo;est pas rien : 25 003 signes ou 4 260 mots, &ndash; le nom d&rsquo;Assange <strong>appara&icirc;t en tout et pour tout UNE SEULE FOIS, et accessoirement, sans aucune explication ni information sur l&rsquo;activisme d&rsquo;Anderson pour Assange<\/strong>. <em>Wiki<\/em>veut bien vous dire qu&rsquo;elle a pris position pour les Gilets-Jaunes et soutenu M\u00e9lenchon aux pr\u00e9sidentielles (elle a v\u00e9cu ces 3-4 derni\u00e8res ann\u00e9es en France), mais Assange, avec la description des conditions de sa d\u00e9tention, l&rsquo;argument de son cas, etc., <strong>c&rsquo;est du <em>off limits <\/em>pour le Syst\u00e8me<\/strong>. (La phrase o&ugrave; le nom est mentionn\u00e9 cette SEULE FOIS : &laquo; <em>En 2017, elle soutient la cause des migrants des camps de Calais et de Grande-Synthe en leur apportant des livres. La m\u00eame ann\u00e9e, elle apporte son soutien \u00e0 Jean-Luc M\u00e9lenchon en vue de l&rsquo;\u00e9lection pr\u00e9sidentielle fran\u00e7aise, appr\u00e9ciant son positionnement concernant Julian Assange et les droits des animaux<\/em>&#8230; &raquo;)<\/p>\n<\/p>\n<p><p>Il y a tout de m\u00eame des enseignements bien singuliers \u00e0 tirer de ce cas Pamela Anderson. Voil\u00e0 une femme qui, par faiblesse, \u00e0 cause des circonstances, par jugements fautifs et passions factices, par entra&icirc;nements des apparences-clinquantes et du plaqu\u00e9-or de pacotille des c\u00e9l\u00e9brit\u00e9s faussaires et des obsessions de cette \u00e9trange \u00e9poque invertie, en \u00e9tait arriv\u00e9e \u00e0 pr\u00e9senter l&rsquo;image que j&rsquo;ai d\u00e9crite, et \u00e0 laquelle moi-m\u00eame j&rsquo;ai compl\u00e8tement succomb\u00e9. Mais les circonstances s&rsquo;y mettent, et les \u00e9v\u00e9nements incontr\u00f4lables que l&rsquo;on sait, <strong>et la voil\u00e0 qui r\u00e9v\u00e8le un caract\u00e8re de r\u00e9demption o&ugrave; se glisse de l&rsquo;h\u00e9ro\u00efsme<\/strong>, &ndash; car il en faut pour affronter ces \u00e9preuves \u00e9pouvantables mises en place par la communication-Syst\u00e8me, ces <a href=\"https:\/\/www.youtube.com\/watch?v=IDszr45rNaM\">charmantes conversations<\/a> o&ugrave; se glissent des monstres type-Meghan McCain, qui se transforment alors en autant d&rsquo;op\u00e9rations de <em>lynch <\/em>public et t\u00e9l\u00e9vis\u00e9. Et Anderson <a href=\"https:\/\/www.youtube.com\/watch?v=IDszr45rNaM\">l&#8217;emporte haut la main<\/a> malgr\u00e9 l&rsquo;acharnement des Fouquier-Tinville de la philogynie guerri\u00e8re, et alors \u00ab\u00a0chapeau bas\u00a0\u00bb&#8230; <\/p>\n<\/p>\n<p><p>Manifestement, s&rsquo;il fallait donner un classement politique, Anderson serait mise \u00e0 gauche, ce qui serait compl\u00e8tement trompeur. Meryl Streep,  Robert De Niro et toute la bande progressiste-soci\u00e9tale de Hollywood se disent \u00e9galement \u00ab\u00a0de gauche\u00a0\u00bb et ne souhaitent qu&rsquo;une chose, mise \u00e0 part une bonne petite guerre de plus : <strong>l&rsquo;enfermement d&rsquo;Assange dans une prison de torture o&ugrave; le Syst\u00e8me vous rend fou<\/strong>, ce qui est son sort probable si l&rsquo;Angleterre, entre deux <em>Brexit <\/em>manqu\u00e9s, le livre au Moloch qui attend son d&ucirc; sur les terres du <em>Mordor <\/em>d&rsquo;outre-Atlantique. Toute cette partie de ce monde qui sombre s&rsquo;accroche \u00e0 la d\u00e9fense de ses pauvres illusions, comme des privil\u00e8ges de l&rsquo;arrogance et de la facticit\u00e9 de la renomm\u00e9e et de la fortune en argent de papier-m\u00e2ch\u00e9. Il faudrait les avertir que, vous savez, les temps changent si vite, si vite, &ndash; par <strong>les temps qui courent<\/strong>&#8230; Et il n&rsquo;y a qu&rsquo;un seul classement acceptable, qui est par rapport au Syst\u00e8me : <strong><em>Delenda Est Systemum<\/em>, ou bien tant pis pour vous<\/strong>.<\/p>\n<\/p>\n<p><p>On peut et on doit ne pas s&#8217;emp\u00eacher une seule seconde, sans avoir froid aux yeux, d&rsquo;observer \u00e0 quel point cette lutte titanesque autour du Syst\u00e8me, emport\u00e9 dans son effondrement catastrophique, brouille toutes les images, tous les jugements faciles auxquels il nous obligeait jusqu&rsquo;alors. Aucun lieu, aucune personne, f&ucirc;t-ce la plus futile et la plus factice comme semblait \u00eatre si injustement Anderson, <strong>n&rsquo;\u00e9chappe aux obligations et aux pressions de l&rsquo;immense Grande-Crise qui d\u00e9chire notre civilisation<\/strong>, celle-l\u00e0 qui se croyait universelle et qui s&rsquo;ach\u00e8ve en une contre-civilisation catastrophique. Il faut le r\u00e9aliser, chacun \u00e0 sa mani\u00e8re, et assumer la responsabilit\u00e9 qui va avec ; Anderson le fait, &laquo; <em>comme un soldat <\/em>&raquo;&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>Je voudrais tant insister sur cet aspect de <strong>la p\u00e9n\u00e9tration des psychologies d&rsquo;une telle <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a><\/strong>, cela qui influence nos pens\u00e9es puis nos jugements, sans que nous en ayons pleine conscience ni, parfois, la moindre conscience. Il y a <strong>quelque chose d&rsquo;un ph\u00e9nom\u00e8ne collectif en marche<\/strong>, sans que les composants de cette collectivit\u00e9, &ndash; nous-m\u00eames, <em>sapiens-sapiens<\/em>de si grande pr\u00e9tention, &ndash; ne s&rsquo;en avisent, sans qu&rsquo;il y ait la moindre manigance humaine \u00e0 son origine. <strong>La m\u00e9tahistoire, d\u00e9sormais, nous parle directement, par le biais de ces grands \u00e9lans collectifs qui nous emportent<\/strong> ; \u00e9coutez-l\u00e0, ce n&rsquo;est pas inint\u00e9ressant&#8230; C&rsquo;est <strong>cette p\u00e9n\u00e9tration de toutes les psychologies, ce bouleversement jusqu&rsquo;\u00e0 la d\u00e9sint\u00e9gration<\/strong>des simulacres patiemment \u00e9labor\u00e9es pour nous tromper qui me fascinent, qui renforcent mon ardeur sans fin, mon \u00e9lan sans compter, <strong>comme quelque chose d&rsquo;ext\u00e9rieur \u00e0 moi<\/strong>. Nul n&rsquo;\u00e9chappe \u00e0 cette bataille immense, cet Armageddon de la postmodernit\u00e9. <\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>La splendeur de l&rsquo;Anderson 14 septembre 2019 &ndash; Jusqu&rsquo;il y a peu, je restais encore et tout \u00e0 fait accessoirement pour le peu d&rsquo;int\u00e9r\u00eat que je portais au cas, sur un jugement au mieux d\u00e9risoire et un peu m\u00e9prisant pour l&rsquo;actrice Pamela Anderson. Je connaissais vaguement sa notori\u00e9t\u00e9 de mannequin sexy, de playmate pour Playboy&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[9164,9886,19349,19173,19351,4063,14884,3050,19350,5169],"class_list":["post-78847","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-anderson","tag-assange","tag-bimbo","tag-julian","tag-maghain","tag-mccain","tag-pamela","tag-the","tag-view","tag-wsws-org"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78847"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78847\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}