{"id":78867,"date":"2019-09-26T07:31:51","date_gmt":"2019-09-26T07:31:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/09\/26\/qui-a-fait-sauter-le-marche-petrolier\/"},"modified":"2019-09-26T07:31:51","modified_gmt":"2019-09-26T07:31:51","slug":"qui-a-fait-sauter-le-marche-petrolier","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/09\/26\/qui-a-fait-sauter-le-marche-petrolier\/","title":{"rendered":"Qui a fait sauter le march\u00e9 p\u00e9trolier ?"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Qui a fait sauter le march\u00e9 p\u00e9trolier ?<\/h2>\n<\/p>\n<p><p>&Ccedil;a n&rsquo;aurait pas pu arriver \u00e0 une plus belle usine de traitement du p\u00e9trole. Elle \u00e9tait l\u00e0, assise dans le d\u00e9sert saoudien, \u00e0 traiter sept millions de barils par jour de p\u00e9trole brut, d\u00e9fendu par des centaines de milliards de dollars de syst\u00e8mes d&rsquo;armes \u00ab\u00a0<em>made in USA<\/em>\u00ab\u00a0, et les Y\u00e9m\u00e9nites l&rsquo;ont mise en bien mauvais \u00e9t\u00e9t avec quelques drones qu&rsquo;ils ont assembl\u00e9s \u00e0 coups de marteau dans un garage \u00e9ventr\u00e9 par les bombes [saoudiennes], programm\u00e9 par un  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nerd\">nerd<\/a>, neveu d&rsquo;Al-whiz. Et maintenant, tout d&rsquo;un coup, 8 % de la production mondiale de p\u00e9trole ne peut plus \u00eatre exp\u00e9di\u00e9e parce que tant qu&rsquo;elle n&rsquo;est pas trait\u00e9e ce n&rsquo;est pas exactement du p\u00e9trole. Que s&rsquo;est-il pass\u00e9, qui est responsable et qu&rsquo;est-ce que cela signifie pour vous ? Permettez-moi de vous expliquer tout cela&hellip;<\/p>\n<\/p>\n<p><p>Les gisements de p\u00e9trole saoudiens sont encore abondants, mais plut\u00f4t \u00e2g\u00e9s et le p\u00e9trole n&rsquo;en jaillit plus comme autrefois. Ils doivent faire l&rsquo;objet d&rsquo;une s\u00e9rie constante de  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Injection_d%27eau_(production_de_p%C3%A9trole)\">lavements<\/a>  d&rsquo;eau de mer \u00e0 haute pression. Et ce qui en r\u00e9sulte n&rsquo;est pas exactement du p\u00e9trole, mais plut\u00f4t un \u00e9chantillon de selles. L&rsquo;usine de traitement d&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Abqa%C3%AFq\">Abqaiq<\/a>, la plus grande au monde, nettoie ce liquide et le transforme en quelque chose qui pouvait \u00eatre charg\u00e9 dans des camions-citernes et exp\u00e9di\u00e9 aux raffineries.<\/p>\n<\/p>\n<p><p>C&rsquo;est du pass\u00e9, du moins pour les prochaines semaines, parce que l&rsquo;autre jour, le puissant Empire y\u00e9m\u00e9nite a ripost\u00e9 et l&rsquo;a mis hors service. C&rsquo;est du moins ce que disent les Y\u00e9m\u00e9nites ; le secr\u00e9taire d&rsquo;&Eacute;tat am\u00e9ricain Mike Pompeo dit que c&rsquo;\u00e9tait l&rsquo;Iran ; d&rsquo;autres pensent que c&rsquo;\u00e9tait peut-\u00eatre Isra\u00ebl ; et enfin vous pouvez toujours bl\u00e2mer la Russie. (Avez-vous \u00e9gar\u00e9 ce Post-it&reg; qui dit \u00ab\u00a0Toujours la faute de la Russie\u00a0\u00bb ? Eh bien, s&rsquo;il vous pla&icirc;t trouver-le et coller-le \u00e0 nouveau sur votre \u00e9cran o&ugrave; c&rsquo;est sa place !)<\/p>\n<\/p>\n<p><p>L&rsquo;incident d&rsquo;Abqaiq ressemble \u00e0 l&rsquo;intrigue d&rsquo;un roman policier. L&rsquo;odieux patriarche de la famille est retrouv\u00e9 poignard\u00e9 dans le dos, \u00e9touff\u00e9, \u00e9lectrocut\u00e9, jet\u00e9 par une fen\u00eatre et noy\u00e9 dans une piscine. Qui a fait \u00e7a ? &Eacute;tait-ce les deux ou trois ma&icirc;tresses abandonn\u00e9es, l&rsquo;\u00e9pouse d\u00e9laiss\u00e9e, les enfants ali\u00e9n\u00e9s, les partenaires d&rsquo;affaires escroqu\u00e9s ou l&rsquo;\u00e9tranger \u00e0 capuchon qui se cachait dans les buissons ?<\/p>\n<\/p>\n<p><p>Et si, malgr\u00e9 ce que dit l&rsquo;<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Jacques_Clouseau\">inspecteur Clouseau<\/a>, n&rsquo;\u00e9tait-ce pas, de toute \u00e9vidence, un suicide motiv\u00e9 par un traumatisme de l&rsquo;enfance et un c&oelig;ur bris\u00e9 ? Il est temps d&rsquo;allumer nos \u00ab\u00a0petites cellules grises\u00a0\u00bb et de poser les questions difficiles : qui avait les moyens, le mobile et l&rsquo;opportunit\u00e9. Plus important encore, <em>cui bono<\/em>&hellip; qui b\u00e9n\u00e9ficiera le plus d&rsquo;une r\u00e9duction de 8 % de l&rsquo;offre mondiale de p\u00e9trole pour une p\u00e9riode ind\u00e9termin\u00e9e ?<\/p>\n<\/p>\n<p><p>Il est clair que les Y\u00e9m\u00e9nites sont les derniers \u00e0 se soucier de l&rsquo;approvisionnement mondial en p\u00e9trole ; ils le prennent aux Saoudiens depuis longtemps maintenant [Les Saoudiens en pompent aussi avec une paille courb\u00e9e sous la fronti\u00e8re, NdT] et sont tr\u00e8s d\u00e9termin\u00e9s \u00e0 se venger. Ils l&rsquo;ont dit eux-m\u00eames et ont d\u00e9clar\u00e9 qu&rsquo;ils n&rsquo;avaient pas encore fini de faire sauter des installations en Arabie saoudite. Mais l&rsquo;Arabie saoudite est cens\u00e9e \u00eatre tr\u00e8s bien d\u00e9fendue avec ces centaines de milliards de dollars de syst\u00e8mes d&rsquo;armes am\u00e9ricains alors que le Y\u00e9men est un pays tr\u00e8s pauvre qui, jusqu&rsquo;\u00e0 pr\u00e9sent, a lanc\u00e9 des missiles <em>Scud <\/em>obsol\u00e8tes et d&rsquo;autres vieux d\u00e9chets vaguement en direction de l&rsquo;Arabie saoudite, causant des d\u00e9g\u00e2ts minimes. Comment se fait-il qu&rsquo;ils aient  soudainement chang\u00e9 de cat\u00e9gorie ?<\/p>\n<\/p>\n<p><p>D&rsquo;un autre c\u00f4t\u00e9, nous savons que tous ces syst\u00e8mes d&rsquo;armement am\u00e9ricains tr\u00e8s co&ucirc;teux font fondamentalement partie d&rsquo;un racket d&rsquo;extorsion : les paiements sont r\u00e9els, mais les armes elles-m\u00eames peuvent ou non fonctionner, et les Saoudiens aurait pu simplement les enfouir dans le sable. Ajoutez \u00e0 cela le fait que les Saoudiens ont \u00e9t\u00e9 ind\u00e9finiment corrompus par l&rsquo;argent du p\u00e9trole gratuit (la plupart d&rsquo;entre eux vivent sans travailler), ont \u00e9pous\u00e9 leurs cousines germaines depuis assez longtemps pour \u00eatre affaiblis par des ph\u00e9nom\u00e8nes dysg\u00e9niques et ne parviennent \u00e0 tenir le coup que gr\u00e2ce aux travailleurs import\u00e9s de pays comme l&rsquo;Inde et le Bangladesh. Les Y\u00e9m\u00e9nites, par contre, sont durs au mal. Le fait que les Saoudiens, apr\u00e8s avoir attaqu\u00e9 le Y\u00e9men, perdent maintenant la guerre contre ce pays, est assez r\u00e9v\u00e9lateur.<\/p>\n<\/p>\n<p><p>Pourtant, il semble douteux que les Y\u00e9m\u00e9nites aient pu lancer tout un escadron de drones suicide super-modernes ind\u00e9tectables sans aide ext\u00e9rieure, et ce n&rsquo;est pas un secret qu&rsquo;ils ont re\u00e7u l&rsquo;aide des Iraniens. En effet, le diplomate en chef des &Eacute;tats-Unis, Mike Pompeo, n&rsquo;a pas tard\u00e9 \u00e0 bl\u00e2mer l&rsquo;Iran pour cet incident en se fondant sur &hellip; aucune preuve. (On dit que Pompeo a obtenu un dipl\u00f4me \u00e0 la \u00ab\u00a0<em>John Bolton School of Diplomacy<\/em>\u00ab\u00a0, en remplissant un formulaire trouv\u00e9 \u00e0 l&rsquo;int\u00e9rieur d&rsquo;une pochette surprise).<\/p>\n<\/p>\n<p><p>Les Iraniens ont rapidement ni\u00e9 toute responsabilit\u00e9. Mais ils ont aussi d\u00e9clar\u00e9 que s&rsquo;ils ne peuvent pas exporter de p\u00e9trole (en raison de sanctions unilat\u00e9rales am\u00e9ricaines), personne d&rsquo;autre ne pourra le faire non plus, et selon la norme \u00ab\u00a0tr\u00e8s probable\u00a0\u00bb qui pr\u00e9vaut actuellement parmi les gouvernements occidentaux, ils sont automatiquement coupables des accusations, sans preuve n\u00e9cessaire. Bien s&ucirc;r, les Iraniens exportent en fait du p\u00e9trole, mais s&rsquo;il vous pla&icirc;t ne dites pas cela \u00e0 Pompeo parce que cela ne correspond pas \u00e0 son r\u00e9cit et cela ne fera que le rendre fou.<\/p>\n<\/p>\n<p><p>Cependant, si nous osons regarder au-del\u00e0 du sourire satisfait de Pompeo, l&rsquo;histoire ne tient pas tr\u00e8s bien debout. Les Iraniens ne sont pas int\u00e9ress\u00e9s par le d\u00e9clenchement d&rsquo;une conflagration massive ; ils sont int\u00e9ress\u00e9s par la vente de p\u00e9trole en d\u00e9pit des sanctions am\u00e9ricaines. Ils s&rsquo;en sont plut\u00f4t bien sortis : leurs efforts pour contourner les sanctions ont \u00e9t\u00e9 tr\u00e8s efficaces et la Chine ach\u00e8te une grande partie de leur p\u00e9trole. Faire sauter le march\u00e9 p\u00e9trolier et toute l&rsquo;\u00e9conomie mondiale ne plairait ni \u00e0 leur principal client, ni \u00e0 aucun des autres. Ce n&rsquo;est pas non plus une question de strat\u00e9gie pour l&rsquo;Iran elle-m\u00eame : une grande partie de ses revenus \u00e9trangers provient des ventes de p\u00e9trole, et le maintien de ce flux n\u00e9cessite un march\u00e9 p\u00e9trolier stable, ce qui exige \u00e0 son tour une stabilit\u00e9 \u00e9conomique dans les pays importateurs de p\u00e9trole.<\/p>\n<\/p>\n<p><p>Certaines personnes (qui, soit dit en passant, d\u00e9testent qu&rsquo;on les appelle \u00ab\u00a0th\u00e9oriciens du complot\u00a0\u00bb) se sont empress\u00e9es de dire qu&rsquo;Isra\u00ebl \u00e9tait derri\u00e8re les attaques. Isra\u00ebl importe 99% de son p\u00e9trole et choisir de le payer beaucoup plus cher en faisant sauter des installations p\u00e9troli\u00e8res saoudiennes semble anormal. Quand avez-vous rencontr\u00e9 pour la derni\u00e8re fois un Juif qui s&rsquo;est port\u00e9 volontaire pour payer plus cher ? En outre, Isra\u00ebl et l&rsquo;Arabie saoudite sont globalement des alli\u00e9s. Les deux pays sont les toutous r\u00e9gionaux de l&rsquo;Am\u00e9rique et sont incit\u00e9s \u00e0 s&rsquo;entendre et \u00e0 ne pas s&rsquo;attaquer l&rsquo;un \u00e0 l&rsquo;autre parce que de telles attaques sont peu susceptibles de plaire \u00e0 leur seigneur et ma&icirc;tre.<\/p>\n<\/p>\n<p><p>Netanyahou, l&rsquo;isra\u00e9lien, \u00e9tait r\u00e9cemment en Russie, suppliant Poutine de le laisser bombarder un peu les positions iraniennes en Syrie et en Irak, juste pour qu&rsquo;il ait l&rsquo;air assez \u00e9nergique pour gagner une \u00e9lection, ce qu&rsquo;il doit faire pour \u00e9viter la prison. Poutine lui a globalement dit \u00ab\u00a0Non, et vous ne pouvez plus bombarder le Liban non plus ! Vos privil\u00e8ges de bombardement ont \u00e9t\u00e9 r\u00e9voqu\u00e9s jusqu&rsquo;\u00e0 nouvel ordre !\u00a0\u00bb Dans ce contexte, l&rsquo;id\u00e9e qu&rsquo;Isra\u00ebl puisse se retourner et frapper l&rsquo;Arabie saoudite semble vraiment farfelue.<\/p>\n<\/p>\n<p><p>C&rsquo;est le moment d&rsquo;\u00e9plucher ce \u00ab\u00a0Toujours bl\u00e2mer la Russie !\u00a0\u00bb, le Post-it&reg; sur votre \u00e9cran. Examinez-le attentivement. La Russie poss\u00e8de des drones d&rsquo;attaque furtifs ultramodernes tr\u00e8s sophistiqu\u00e9s et pourrait les lancer depuis la Syrie voisine. La Russie est \u00e9galement le deuxi\u00e8me producteur mondial de p\u00e9trole (un peu plus petit que les &Eacute;tats-Unis, mais c&rsquo;est un effet temporaire d&ucirc; \u00e0 la fracturation hydraulique jamais rentable). C&rsquo;est un grand exportateur de p\u00e9trole et elle devrait b\u00e9n\u00e9ficier de la hausse des prix du p\u00e9trole. Mais quand m\u00eame, elle est vraiment, vraiment loin d&rsquo;\u00eatre assez d\u00e9sesp\u00e9r\u00e9e pour essayer quelque chose d&rsquo;aussi risqu\u00e9 que faire sauter Abqaiq.<\/p>\n<\/p>\n<p><p>En fait, la Russie n&rsquo;est pas d\u00e9sesp\u00e9r\u00e9e du tout ; sa situation est m\u00eame assez savoureuse ; sa croissance est lente mais r\u00e9guli\u00e8re, ses r\u00e9serves financi\u00e8res abondantes, son exc\u00e9dent commercial est sain et sa dette nette est nulle. En outre, la Russie d\u00e9pense continuellement des ressources et la vie de ses soldats pour assurer la stabilit\u00e9 r\u00e9gionale au Moyen-Orient parce que l&rsquo;instabilit\u00e9 engendre le terrorisme et que les terroristes menacent la Russie. Ajoutez \u00e0 cela le fait que la Russie est en bons termes avec les responsables saoudiens au sein d&rsquo;une organisation informelle appel\u00e9e OPEP+ qui tente de r\u00e9guler le march\u00e9 p\u00e9trolier \u00e0 leur satisfaction mutuelle. Pourquoi la Russie mettrait-elle tout cela en p\u00e9ril ?<\/p>\n<\/p>\n<p><p>Peut-\u00eatre devriez-vous alors froisser ce Post-it&reg; et le jeter dans la corbeille \u00e0 papier&hellip; et essayer de bl\u00e2mer l&rsquo;Am\u00e9rique \u00e0 la place. C&rsquo;est actuellement le plus grand producteur de p\u00e9trole au monde, mais, comme je l&rsquo;ai mentionn\u00e9, cela n&rsquo;est d&ucirc; qu&rsquo;\u00e0 la fracturation hydraulique, et l&rsquo;industrie de la fracturation est en faillite. Les soci\u00e9t\u00e9s de production font faillite parce qu&rsquo;elles ont besoin de prix du p\u00e9trole beaucoup plus \u00e9lev\u00e9s pour atteindre le seuil de rentabilit\u00e9. Auparavant, elles \u00e9taient en mesure de fonctionner en appliquant une sorte de syst\u00e8me de Ponzi, o&ugrave; des investisseurs un peu stupides se ruaient sur la base de promesses de rentabilit\u00e9 future qui ne se sont jamais concr\u00e9tis\u00e9es. Mais l&rsquo;industrie enti\u00e8re a r\u00e9cemment manqu\u00e9 de ce genre d&rsquo;investisseurs et elle est maintenant en ruine. Des prix du p\u00e9trole beaucoup plus \u00e9lev\u00e9s lui donneraient certainement un nouveau souffle.<\/p>\n<\/p>\n<p><p>Ajoutez \u00e0 cela le fait que les &Eacute;tats-Unis tentent de d\u00e9clencher une guerre avec l&rsquo;Iran depuis un certain temps d\u00e9j\u00e0. Le d\u00e9clenchement d&rsquo;une guerre avec l&rsquo;Iran est une obsession chez les bellicistes am\u00e9ricains depuis que la r\u00e9volution islamique de 1979 a renvers\u00e9 leur marionnette, le Chah. Il ne fait aucun doute que Trump a remarqu\u00e9 que le seul moment o&ugrave; il est encens\u00e9 par les d\u00e9mocrates, c&rsquo;est quand il bombarde un pays. C&rsquo;est lorsqu&rsquo;il a ordonn\u00e9 la futile attaque a\u00e9rienne d&rsquo;un a\u00e9rodrome syrien inutilis\u00e9 que les interlocuteurs de CNN ont d\u00e9clar\u00e9 que c&rsquo;\u00e9tait <em>&laquo; le jour o&ugrave; il est vraiment devenu pr\u00e9sident &raquo;<\/em>. Trump est donc peut-\u00eatre assez superficiel et malavis\u00e9 pour penser que le lancement d&rsquo;une campagne de bombardement tout aussi futile contre l&rsquo;Iran lui assurerait une victoire facile lors des prochaines \u00e9lections. Faire sauter Alqaiq et bl\u00e2mer l&rsquo;Iran fournirait un <em>casus belli<\/em> puissant.<\/p>\n<\/p>\n<p><p>Enfin, il y a le puissant facteur de d\u00e9sespoir. Malgr\u00e9 Trump qui tweete de mani\u00e8re insipide que l&rsquo;\u00e9conomie am\u00e9ricaine n&rsquo;a jamais \u00e9t\u00e9 aussi en forme, tout le monde sait que \u00ab\u00a0<em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Game_of_Thrones\">l&rsquo;hiver arrive<\/a><\/em>\u00a0\u00bb  &ndash; c&rsquo;est-\u00e0-dire la r\u00e9cession ; ou, si vous voulez, l&rsquo;effondrement financier. Il est probable qu&rsquo;il sera bien pire que celui d&rsquo;il y a dix ans parce que le fardeau de la dette des gouvernements et des entreprises est beaucoup plus lourd alors que les banques centrales n&rsquo;ont plus de marge de man&oelig;uvre parce que les taux d&rsquo;int\u00e9r\u00eat sont d\u00e9j\u00e0 soit proches de z\u00e9ro, soit en fait n\u00e9gatifs.<\/p>\n<\/p>\n<p><p>Il convient de noter que ce prochain effondrement ne sera pas du tout comme la fin habituelle d&rsquo;un cycle \u00e9conomique. Ce que les taux d&rsquo;int\u00e9r\u00eat n\u00e9gatifs indiquent, c&rsquo;est que le capitalisme occidental, dans son ensemble, a \u00e9chou\u00e9. La fa\u00e7on dont cela est cens\u00e9 fonctionner est la suivante : les gens \u00e9conomisent de l&rsquo;argent ; les banques versent des int\u00e9r\u00eats aux \u00e9pargnants, pr\u00eatent de l&rsquo;argent aux entreprises \u00e0 un taux plus \u00e9lev\u00e9 en r\u00e9alisant un profit sur la diff\u00e9rence et les entreprises investissent dans des activit\u00e9s productives et lucratives afin de pouvoir rembourser leurs dettes avec int\u00e9r\u00eat. Mais lorsque les taux deviennent n\u00e9gatifs, les banques font de l&rsquo;argent en confisquant l&rsquo;\u00e9pargne des gens, pr\u00eatent une partie de l&rsquo;argent confisqu\u00e9 aux entreprises \u00e0 des taux n\u00e9gatifs, et les entreprises font de l&rsquo;argent en ne faisant rien ou en jouant \u00e0 la bourse.<\/p>\n<\/p>\n<p><p>Normalement, les gouvernements empruntent de l&rsquo;argent \u00e0 un taux d&rsquo;int\u00e9r\u00eat positif parce que la croissance \u00e9conomique augmentera leur assiette fiscale, ce qui permettra de rembourser la dette avec int\u00e9r\u00eats. Mais maintenant, les gouvernements sont en mesure d&#8217;emprunter \u00e0 des taux d&rsquo;int\u00e9r\u00eat inf\u00e9rieurs \u00e0 z\u00e9ro parce que les investisseurs parient que les taux seront encore plus n\u00e9gatifs \u00e0 l&rsquo;avenir, rendant leur investissement \u00e0 rendement n\u00e9gatif relativement plus rentable. Si vous pensez que c&rsquo;est de la folie, vous avez probablement raison.<\/p>\n<\/p>\n<p><p>En bref, le capitalisme occidental est bris\u00e9. Il est cens\u00e9 faire des profits \u00e0 partir d&rsquo;activit\u00e9s productives, mais au lieu de cela, il ne fait que gaspiller des ressources tout en faisant des dettes \u00e0 partir d&rsquo;autres dettes, \u00e0 l&rsquo;infini. Cet \u00e9tat des choses ne peut qu&rsquo;engendrer un d\u00e9sespoir extr\u00eame. Une solution serait d&rsquo;en parler franchement, d&rsquo;en tirer des conclusions d\u00e9sagr\u00e9ables et d&rsquo;apporter des changements rapides et radicaux qui pourraient peut-\u00eatre \u00e9viter l&rsquo;effondrement, mais personne ne sait comment faire cela. L&rsquo;autre ligne de conduite consiste \u00e0 organiser un autre 9\/11 et bl\u00e2mer les terroristes pour l&rsquo;effondrement qui s&rsquo;en suivrait. C&rsquo;est quelque chose que les Washingtoniens savent certainement faire.<\/p>\n<\/p>\n<p><p>Mais ces sp\u00e9culations, qui sont que ce qu&rsquo;elles sont, semblent beaucoup trop fantaisistes. Il semble beaucoup plus s&ucirc;r de supposer que c&rsquo;\u00e9tait les Y\u00e9m\u00e9nites apr\u00e8s tout. Peut-\u00eatre qu&rsquo;un nerd, le neveu de quelqu&rsquo;un a habilement programm\u00e9 des drones qui ont \u00e9t\u00e9 assembl\u00e9s \u00e0 coups de marteau par des rebelles Houthis dans un garage \u00e9ventr\u00e9 par les bombes. Les \u00e9quipes de d\u00e9fense a\u00e9rienne saoudiennes \u00e9taient sorties d\u00e9jeuner comme d&rsquo;habitude, et Abqaiq s&rsquo;est transform\u00e9 en boule de feu. Vous \u00eates, bien s&ucirc;r, libre de penser ce que vous voulez. Peut-\u00eatre que quelqu&rsquo;un l&rsquo;a fait. Ou peut-\u00eatre que l&rsquo;inspecteur Clouseau avait raison de penser qu&rsquo;il s&rsquo;agissait d&rsquo;un suicide motiv\u00e9 par une combinaison de traumatismes de l&rsquo;enfance et d&rsquo;un c&oelig;ur bris\u00e9. Ou peut-\u00eatre que c&rsquo;\u00e9tait juste un accident. La civilisation occidentale est devenue extr\u00eamement sujette aux accidents ces derniers temps, et il arrive que des accidents se produisent.<\/p>\n<\/p>\n<p><p>17 septembre 2019, <a href=\"http:\/\/cluborlov.blogspot.com\/2019\/09\/who-blew-up-oil-market.html\">Club Orlov<\/a>, &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/qui-a-fait-sauter-le-marche-petrolier\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui a fait sauter le march\u00e9 p\u00e9trolier ? &Ccedil;a n&rsquo;aurait pas pu arriver \u00e0 une plus belle usine de traitement du p\u00e9trole. Elle \u00e9tait l\u00e0, assise dans le d\u00e9sert saoudien, \u00e0 traiter sept millions de barils par jour de p\u00e9trole brut, d\u00e9fendu par des centaines de milliards de dollars de syst\u00e8mes d&rsquo;armes \u00ab\u00a0made in USA\u00ab\u00a0,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3259,13618,2870,12132,2668,2730],"class_list":["post-78867","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-arabie","tag-aramco","tag-attaque","tag-falseflag","tag-orlov","tag-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78867"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78867\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}