{"id":78894,"date":"2019-10-11T13:21:58","date_gmt":"2019-10-11T13:21:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/11\/notes-sur-une-destitution-metahistorique\/"},"modified":"2019-10-11T13:21:58","modified_gmt":"2019-10-11T13:21:58","slug":"notes-sur-une-destitution-metahistorique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/11\/notes-sur-une-destitution-metahistorique\/","title":{"rendered":"Notes sur une destitution m\u00e9tahistorique"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur une destitution m\u00e9tahistorique<\/h2>\n<\/p>\n<p><p>10 octobre 2019 &ndash; Bien s&ucirc;r, le titre de ces <em>Notes d&rsquo;analyse <\/em>pouvait se se r\u00e9f\u00e8rer au texte du 9 octobre de PhG dans son <em>Journal-dde.crisis<\/em>, justement avec le titre de \u00ab\u00a0<em>Notes sur &lsquo;une destitution Rock&rsquo;n Roll&rsquo;<\/em>\u00a0\u00bb que nous envisag\u00e9 un instant de choisir. Ce texte constituait une analyse g\u00e9n\u00e9rale, du point de vue structurel comme on s&rsquo;en doute, de la situation extraordinaire \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb : d\u00e9structuration, structuration emprisonnant les agents du Syst\u00e8me, poussant \u00e0 des structures explosives au sein du Syst\u00e8me, et donc structures-d\u00e9structurantes&hellip;<\/p>\n<\/p>\n<p><p>Nous avons rassembl\u00e9 dans ces <em>Notes d&rsquo;analyse <\/em>les principaux \u00e9v\u00e9nements, les attitudes, les man&oelig;uvres, la dynamique fantastique de d\u00e9sordre, etc., qui justifient cette analyse structurelle. Pour \u00ab\u00a0rendre \u00e0 C\u00e9sar&hellip;\u00a0\u00bb, ou disons \u00ab\u00a0lui emprunter\u00a0\u00bb en tout bien tout honneur, nous rappelons quelques passages du texte du capitaine au long cours, permettant de resituer cette tentative de structuration d&rsquo;un processus crisique dynamique absolument explosif.<\/p>\n<\/p>\n<p><p>&laquo; <em>Certes, il n&rsquo;en est plus rien, il n&rsquo;y a plus rien du tout  <\/em>[\u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb \u00e0 la l&rsquo;heure de cette destitution]  <em>d&rsquo;un \u00ab\u00a0\u00e9pisode compr\u00e9hensible rationnellement\u00a0\u00bb. La mise en accusation d\u00e9cid\u00e9e par les d\u00e9mocrates de la Chambre a donn\u00e9 une structure institutionnelle \u00e0 cette formidable entreprise de d\u00e9structuration marqu\u00e9e par l&rsquo;irrationalit\u00e9 d&rsquo;une haine hyst\u00e9rique sans aucune mesure et appuy\u00e9e sur un d\u00e9lire id\u00e9ologique de m\u00eame facture. Ainsi peut-on dire, d&rsquo;une mani\u00e8re diff\u00e9rente mais significative et dans tous les cas paradoxale parce que <strong>totalement dans l&rsquo;inversion<\/strong>, que, parvenue \u00e0 ce stade de l&rsquo;institutionnalisation qui est effectivement un d\u00e9veloppement de structuration incontestable, cette <strong>crise de la d\u00e9structuration absolue du pouvoir am\u00e9ricaniste est entr\u00e9e dans une phase de structuration explosive<\/strong>, en atteignant <strong>sa s\u00e9quence paroxystique<\/strong><\/em>.<\/p>\n<p>&raquo; <em>Il s&rsquo;agit d&rsquo;un cas qui restera d&rsquo;\u00e9cole et arch\u00e9typique du caract\u00e8re fondamental de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me (GCES) : <strong>l&rsquo;inversion imposant une structure institutionnelle \u00e0 une crise qui est celle de la d\u00e9structuration absolue, pour faciliter d\u00e9cisivement l&rsquo;explosion de toutes ses structures<\/strong><\/em>.<\/p>\n<p>&raquo; <em>Nous sommes entr\u00e9s dans une s\u00e9quence <strong>de dynamique de d\u00e9structuration maximale<\/strong>, dans le cadre <strong>d&rsquo;une structuration <\/strong>qui est <strong>comme une prison <\/strong>emp\u00eachant les promoteurs et acteurs de la chose de sortir de cette dynamique, encore moins de la stopper. On ajoute \u00e0 cette situation d\u00e9j\u00e0 admirable d&rsquo;inversion le fait que l&rsquo;objet de tout cette agitation compulsive et sans le moindre frein possible du fait de l&rsquo;excitation exacerb\u00e9e des psychologies n&rsquo;est rien de moins que le pouvoir de l&rsquo;am\u00e9ricanisme, <strong>la forme m\u00eame, &ndash; comme une essence (simulacre d&rsquo;essence) de l&rsquo;inversion, &ndash; du bras arm\u00e9 du Syst\u00e8me<\/strong>, car ce pouvoir de l&rsquo;am\u00e9ricanisme est effectivement ce qui fait que le Syst\u00e8me peut op\u00e9rationnaliser sa puissance<\/em>. [&hellip;]<\/p>\n<p>&raquo; <em>Ainsi peut-on parler d&rsquo;une \u00ab\u00a0destitution rock&rsquo;n&rsquo;roll\u00a0\u00bb. J&#8217;emploie cette expression tr\u00e8s \u00ab\u00a0tendance\u00a0\u00bb (\u00ab\u00a0dans le vent\u00a0\u00bb, disait-on in illo tempore) \u00e0 dessein, dans un but d&rsquo;inversion vertueuse ; cette expression postmoderne relevant de la technique de communication \u00e9galement postmoderne d&rsquo;endoctrinement par l&rsquo;entertainment, les automatismes de mode, la \u00ab\u00a0philosophie\u00a0\u00bb pavlovienne de l&rsquo;optimisme et l&#8217;emprisonnement du langage prisonnier du rythme obs\u00e9dant et r\u00e9p\u00e9titif, comme moyen dialectique d&rsquo;inversion vertueuse <strong>dans le but de r\u00e9duction \u00e0 la d\u00e9rision et de reductio ad absurdum <\/strong>de l&rsquo;objet consid\u00e9r\u00e9, &ndash; d\u00e9sign\u00e9 comme le serait <strong>une trag\u00e9die du XVII\u00e8me si\u00e8cle devenue trag\u00e9diebouffe du XXI\u00e8me si\u00e8cle<\/strong>, &ndash; j&rsquo;ai nomm\u00e9 \u00ab\u00a0La destitution du pr\u00e9sident Donald Trump\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Apr\u00e8s un passage en revue des conditions de la situation \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb qui justifient le titre de \u00ab\u00a0Une destitution <em>Rock&rsquo;n Roll<\/em>\u00ab\u00a0, nous entendons encha&icirc;ner sur les conceptions et hypoth\u00e8ses qui justifient d&rsquo;autre part, mais dans le m\u00eame sens et la m\u00eame logique, une trentaine d&rsquo;\u00e9tages plus haut, ce qui pourrait \u00eatre le titre de \u00ab\u00a0une destitution m\u00e9tahistorique\u00a0\u00bb. Sur cette perspective, la m\u00eame remarque que fait PhG est encore valable, pour la gloire de notre intelligence, et cela servira de conclusion \u00e0 notre introduction apr\u00e8s tout : &laquo; &hellip;<em>nous <strong>r\u00e9affirmons et confirmons la sottise sans fin ni bornes, ni limites, ni rien du tout<\/strong>, de l&rsquo;intelligentsia si-intelligente des \u00e9lites parisiennes, constamment nourries au petit lait sucr\u00e9 de l&rsquo;am\u00e9ricanisme ; pour redire et redire qu&rsquo;elles <strong>ne voient rien, \u00ab\u00a0absolumentissimement\u00a0\u00bb rien de tout cela<\/strong>. (Pour l&rsquo;occasion, pour saluer l&rsquo;abyssal colosse de Rien qu&rsquo;est cette sottise parisienne, nous nous permettons effectivement d&#8217;emprunter \u00e0 PhG sa derni\u00e8re cr\u00e9ation, dite \u00ab\u00a0de bric et de broc\u00a0\u00bb,  ce n\u00e9ologisme \u00e0 la mani\u00e8re de l'\u00a0\u00bbabracadabrantesque\u00a0\u00bb de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Abracadabrantesque\">Rimbaud-Chirac<\/a>.)<\/em> &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le pi\u00e8ge de Dame Pelosi<\/h3>\n<\/p>\n<p><p>Il faut savoir que les d\u00e9mocrates de la Chambre, sous la direction de la tr\u00e8s-catholique et v\u00e9n\u00e9rable Nancy Pelosi, avec l&rsquo;appoint du <em>Squad<\/em> et surtout d&rsquo;Adam Schiff, pr\u00e9sident de la commission du renseignement de la Chambre, <strong>ont \u00e9labor\u00e9 un pi\u00e8ge de premi\u00e8re dimension<\/strong>., &ndash; croient-ils&#8230; Pelosi a impos\u00e9 de nouvelles dispositions concernant la proc\u00e9dure de mise en accusation, &ndash; la Chambre jouant le r\u00f4le du procureur [accusateur] et le S\u00e9nat celui du juge qui monte proc\u00e8s, examine le dossier, et tranche, &ndash; pardon \u00ab\u00a0&#8230;et vote\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le but \u00e9tait d&rsquo;\u00e9carter la minorit\u00e9 r\u00e9publicaine du processus (de l&rsquo;acte d&rsquo;accusation) et d&rsquo;\u00e9viter le vote de l&rsquo;assembl\u00e9e, en s&rsquo;en tenant au <em>diktat <\/em>de la commission accusatrice (la commission Schiff). L&rsquo;int\u00e9r\u00eat et la nouveaut\u00e9 ont \u00e9t\u00e9 \u00e0 la fois de red\u00e9finir les motifs de mise en accusation, et donc de destitution, et dans ce cas de r\u00e9duire exactement l&rsquo;accusation \u00e0 un cas bien pr\u00e9cis (la conversation Trump-Zelenski, et toute la soupe de faux-t\u00e9moins et sources-bidon autour). Comme l&rsquo;\u00e9crit plusieurs fois dans un m\u00eame <a href=\"https:\/\/www.strategic-culture.org\/news\/2019\/10\/06\/dont-bet-on-republicans-saving-trump\/\">article<\/a> Tom Luongo, <strong>\u00ab\u00a0la destitution est un processus politique, pas un processus juridique\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>&laquo; <em>La destitution est un processus politique, pas un processus juridique. Il n&rsquo;existe pas de norme juridique pour les \u00ab\u00a0crimes et d\u00e9lits graves\u00a0\u00bb, comme le stipule la Constitution. Cette d\u00e9finition s&rsquo;appuiera <\/em>[pour ce cas de Trump]<em> sur ce que le S\u00e9nat nominalement contr\u00f4l\u00e9 par les r\u00e9publicains pense<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>La cause de la man&oelig;uvre de Pelosi-Schiff, c&rsquo;est d&rsquo;\u00e9viter que la minorit\u00e9 r\u00e9publicaine de la Chambre, sachant qu&rsquo;elle ne peut \u00e9viter le vote de la mise en accusation que la majorit\u00e9 d\u00e9mocrate voterait \u00e0 coup s&ucirc;r, tenterait d&rsquo;\u00e9largir le cadre de cette mise en accusation, par exemple au <em>Russiagate <\/em>dont le \u00ab\u00a0s\u00e9nile Mueller\u00a0\u00bb, apr\u00e8s deux ans d&rsquo;enqu\u00eate anti-Trump, a d&ucirc; conclure qu&rsquo;il n&rsquo;avait rien trouv\u00e9 de solide contre Trump. Par contre, on peut imaginer qu&rsquo;on pourrait <strong>trouver quelque chose de solide contre les d\u00e9mocrates dans ce cadre \u00e9largi <\/strong>: c&rsquo;est ce que Trump demandait sp\u00e9cifiquement \u00e0 Zelenski dans la fameuse \u00ab\u00a0<a href=\"https:\/\/www.whitehouse.gov\/wp-content\/uploads\/2019\/09\/Unclassified09.2019.pdf\">conversation<\/a>\u00a0\u00bb du 25 juillet avant d&rsquo;effleurer le cas Biden, &ndash; \u00e0 savoir un montage anti-Trump effectu\u00e9 par les hommes d&rsquo;Obama encore en poste jusqu&rsquo;en janvier 2017 \u00e0 partir de l&rsquo;Ukraine, \u00e0 partir d&rsquo;un serveur (<em><a href=\"https:\/\/www.zerohedge.com\/political\/time-reassess-crowdstrikes-credibility\">Crowdstrike<\/a><\/em>) ayant op\u00e9r\u00e9 pour les d\u00e9mocrates pendant la campagne USA-2016, tout cela m\u00eal\u00e9 \u00e0 l&rsquo;implication d&rsquo;un oligarque ukrainien \u00e0 la demande de certains milieux anti-Trump.<\/p>\n<\/p>\n<p><p>&laquo; <em>J&rsquo;aimerais que vous nous fassiez une faveur parce que notre pays a travers\u00e9 beaucoup de choses et que l&rsquo;Ukraine en sait beaucoup \u00e0 ce sujet. J&rsquo;aimerais que vous d\u00e9couvriez ce qui s&rsquo;est pass\u00e9 avec toute cette situation avec l&rsquo;Ukraine,<\/em> [on parle du serveur] <em>Crowdstrike<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Mais la messe n&rsquo;est pas dite, d&rsquo;autant que les pressions \u00e0 l&rsquo;int\u00e9rieur du parti d\u00e9mocrate sont terribles, illustr\u00e9es par cette remarque du chef de la majorit\u00e9 r\u00e9publicaine au S\u00e9nat Mitch McConnell : &laquo; <strong><em>Nancy Pelosi est dans les griffes d&rsquo;une clique gauchiste <\/em><\/strong>[de son parti]<em>. Ils l&rsquo;ont finalement convaincue de destituer le Pr\u00e9sident<\/em>&#8230; &raquo; Ces pressions peuvent aboutir, du fait m\u00eame de l&rsquo;extr\u00e9misme chez les d\u00e9mocrates, \u00e0 l&rsquo;\u00e9largissement de la mise en accusation au <em>Russiagate<\/em>.<\/p>\n<\/p>\n<p><p>Il faut avoir \u00e0 l&rsquo;esprit que diverses <em>narrative <\/em>et autant de simulacres r\u00e8glent le jugement des uns et des autres, et qu&rsquo;ainsi <strong>de graves erreurs pour leur camp peuvent \u00eatre commises par certains selon le simulacre d&rsquo;o&ugrave; ils per\u00e7oivent une version sp\u00e9cifique de la \u00ab\u00a0r\u00e9alit\u00e9\u00a0\u00bb, et donc s&rsquo;appuient sur \u00ab\u00a0leurs\u00a0\u00bb r\u00e9alit\u00e9s<\/strong>. Nombre de gauchistes-d\u00e9mocrates n&rsquo;ont pas accept\u00e9 les conclusions du \u00ab\u00a0s\u00e9nile Mueller\u00a0\u00bb et restent persuad\u00e9s qu&rsquo;on peut d\u00e9molir Trump sur le <em>Russiagate<\/em>.<\/p>\n<\/p>\n<p><p>Au fond et en fait, chacun se voit un peu comme \u00ab\u00a0le Grand Sachem\u00a0\u00bb de l&rsquo;affaire et trouve dans son propre simulacre et la perception faussaire qui en d\u00e9coule une formidable exacerbation de l&rsquo;excitation psychologique en cours depuis USA-2016 ; et ainsi est-on en train d&rsquo;atteindre une sorte de paroxysme et de <em>nirvana <\/em>\u00e0 la fois, avec le processus de mise en accusation o&ugrave; l&rsquo;on croit approcher <strong>du but tant r\u00eav\u00e9 : avoir le scalp, la peau et la t\u00eate de Trump tout ensemble !<\/strong><\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">On fonce \u00e0 tombeau ouvert<\/h3>\n<\/p>\n<p><p>Les conditions et le parcours \u00e0 la Chambre sont une partie du probl\u00e8me, la partie o&ugrave; les d\u00e9mocrates foncent \u00e0 tombeau ouvert&#8230; Mais au S\u00e9nat, justement, \u00e0 la prochaine \u00e9tape et l&rsquo;\u00e9tape ultime, <strong>le tombeau sera plus ouvert que jamais, et pour tout le monde encore<\/strong> ! Objectivement consid\u00e9r\u00e9, il r\u00e8gne un formidable d\u00e9sordre sur les possibilit\u00e9s de d\u00e9roulement <strong>d&rsquo;un proc\u00e8s dont les r\u00e9publicains, sous la pression de Trump, seront les ma&icirc;tres d&rsquo;&oelig;uvre<\/strong>. Cela vaut pour la citation des t\u00e9moins, avec d&rsquo;infinies possibilit\u00e9s de confrontation dans des affaires o&ugrave; plusieurs versions sont confront\u00e9es et aucune assur\u00e9e, et surtout pas celle(s) des d\u00e9mocrates, sur laquelle (lesquelles) la mise en accusation est fond\u00e9e.<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.washingtontimes.com\/news\/2019\/oct\/7\/joe-biden-hunter-biden-could-be-forced-testify-don\/\">Un article<\/a>du Washington <em>Times  <\/em>du 8 octobre ouvrait l&rsquo;\u00e9ventail de possibilit\u00e9s incroyables d&rsquo;affrontements publics, y compris avec Trump affrontant les t\u00e9moins qui l&rsquo;incriminent&#8230; L&rsquo;avis d&rsquo;experts travaillant au S\u00e9nat, sur lesquels l&rsquo;article est bas\u00e9, est que <strong>les d\u00e9mocrates ne se rendent pas compte de la machine incontr\u00f4lable qu&rsquo;ils ont lanc\u00e9e<\/strong>&#8230; <em><a href=\"https:\/\/www.zerohedge.com\/political\/joe-and-hunter-biden-could-be-forced-testify-during-trump-impeachment-trial\">ZeroHedge.com<\/a><\/em> a repris quelques extraits de l&rsquo;article et les commente, et ces quelques lignes rendent compte de l&rsquo;esprit de la chose :<\/p>\n<\/p>\n<p><p> &laquo; <em>L&rsquo;ancien vice-pr\u00e9sident Joe Biden et son fils Hunter pourraient \u00eatre contraints de t\u00e9moigner si le S\u00e9nat d\u00e9cidait de tenir un proc\u00e8s pour destitution du pr\u00e9sident Trump, selon le <a href=\"https:\/\/www.washingtontimes.com\/news\/2019\/oct\/7\/joe-biden-hunter-biden-could-be-forced-testify-don\/\">Washington Times<\/a>, citant des assistants du Congr\u00e8s \u00ab\u00a0qui se demandent si les d\u00e9mocrates ont r\u00e9fl\u00e9chi \u00e0 toutes les implications de leur action\u00a0\u00bb<\/em>. <\/p>\n<p>&raquo; <em>\u00ab\u00a0&lsquo;Non seulement M. Biden pourrait \u00eatre contraint d&rsquo;\u00eatre \u00e0 Washington \u00e0 un moment critique de la campagne pr\u00e9sidentielle, mais nombre de ses principaux rivaux, &ndash; la demi-douzaine de s\u00e9nateurs qui se disputent \u00e9galement l&rsquo;investiture des d\u00e9mocrates, &ndash; pourraient l&rsquo;\u00e2tre aussi&rsquo; ont d\u00e9clar\u00e9 les experts en destitution.\u00a0\u00bb<\/em> [&#8230;] <em>\u00ab\u00a0M. Trump pourrait m\u00eame \u00eatre pr\u00e9sent pendant tout le spectacle. Les experts ont d\u00e9clar\u00e9 que le S\u00e9nat aurait du mal \u00e0 le refuser <\/em>[si Trump] <em>exigeait de confronter les t\u00e9moins l&rsquo;impliquant<\/em>. <\/p>\n<p>&raquo; <em>Il y aurait \u00e9galement la forte possibilit\u00e9 de forcer les &lsquo;lanceurs d&rsquo;alerte&rsquo; accusant Trump de \u00ab\u00a0comportements r\u00e9pr\u00e9hensibles\u00a0\u00bb \u00e0 t\u00e9moigner publiquement, selon le s\u00e9nateur Lindsey Graham (R-SC), pr\u00e9sident de la commission judiciaire du S\u00e9nat.  Graham a \u00e9galement estim\u00e9 que le pr\u00e9sident de la commission du renseignement de la Chambre, Adam Schiff (D-CA), pourrait \u00eatre appel\u00e9 \u00e0 t\u00e9moigner pour avoir cach\u00e9 les interactions de son bureau avec l&rsquo;un des \u00ab\u00a0lanceurs d&rsquo;alerte\u00a0\u00bb<\/em>.<\/p>\n<p>&raquo; <em>\u00ab\u00a0Je pense que les d\u00e9mocrates n&rsquo;ont pas r\u00e9fl\u00e9chi \u00e0 toutes les implications de leur action\u00a0\u00bb a d\u00e9clar\u00e9 au &lsquo;Times&rsquo; un membre du personnel, qui note que le S\u00e9nat contr\u00f4l\u00e9 par les r\u00e9publicains \u00ab\u00a0aurait le contr\u00f4le complet sur le d\u00e9roulement du proc\u00e8s\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>On comprend par cons\u00e9quent selon quelles indications et quelles observations PhG peut se trouver fond\u00e9 d&rsquo;\u00e9crire ceci \u00e0 propos des \u00e9v\u00e9nements courants et en-cours et des perspectives <strong>\u00e0 terme, disons de quelques jours pour ne pas s&rsquo;arr\u00eater \u00e0 \u00ab\u00a0quelques heures\u00a0\u00bb<\/strong>, &ndash; et ainsi d\u00e9crire le champ de la bataille qui ne cesse de se d\u00e9velopper sous nos yeux, jusqu&rsquo;\u00e0 l&rsquo;hypoth\u00e8se presque extraterrestre d&rsquo;un proc\u00e8s de Trump devant le S\u00e9nat, <strong>avec Trump pr\u00e9sent et interpellant ses accusateurs corrompus jusqu&rsquo;\u00e0 l&rsquo;os, ses t\u00e9moins \u00e0 charge compl\u00e8tement fabriqu\u00e9s<\/strong>, un Joe Biden venant justifier les \u00e9moluments de son fils entre deux primaires d\u00e9mocrates :<\/p>\n<\/p>\n<p><p>&laquo; <em>C&rsquo;est dire enfin que les avis, les perspectives et les prospectives ; les jugements \u00e0 terme de 24 heures ou 48 heures, sinon les jugements imm\u00e9diats, pour l&rsquo;heure courante ; les \u00e9valuations, les certitudes de l&rsquo;instant d\u00e9sint\u00e9gr\u00e9es l&rsquo;instant d&rsquo;apr\u00e8s, ne cessent de se succ\u00e9der dans une sarabande infernale, c&rsquo;est-\u00e0-dire infernale-bouffe. Le Diable qui ne cesse d'\u00a0\u00bben rire encore\u00a0\u00bb selon l&rsquo;expression consacr\u00e9e, <strong>a-t-il trouv\u00e9 son ma&icirc;tre <\/strong>en pr\u00e9sidant d&rsquo;une fa\u00e7on aussi ostentatoire, <strong>lui-m\u00eame naturellement, \u00e0 ce d\u00e9sordre qui devient un objet de d\u00e9rision de lui-m\u00eame<\/strong> ? Bonne question<\/em>&hellip; &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Horloges et d\u00e9sordre<\/h3>\n<\/p>\n<p><p>Certains jugeront assez peu justifi\u00e9e l&rsquo;importance que nous accordons au facteur de d\u00e9sordre dans la crise du pouvoir de l&rsquo;am\u00e9ricanisme. Cela n&rsquo;importe car notre religion est faite <strong>pour la s\u00e9quence en cours qui pr\u00e9sente une unit\u00e9 de facture et une durabilit\u00e9 (depuis 2016) extraordinaires<\/strong> : \u00e0 Washington (<a href=\"https:\/\/www.dedefensa.org\/article\/washington-paris-laxe-du-desordre-final\">comme \u00e0 Paris<\/a>et ailleurs), le d\u00e9sordre r\u00e8gle tout ; il est, comme on se pla&icirc;t \u00e0 dire, <strong>le ma&icirc;tre des horlogers qui se pr\u00e9tendent \u00ab\u00a0ma&icirc;tres des horloges\u00a0\u00bb<\/strong>. Pour autant, nous pouvons s&rsquo;il le faut \u00ab\u00a0\u00eatre s\u00e9rieux\u00a0\u00bb et envisager des portions d&rsquo;analyse classique qui pr\u00e9tendraient se r\u00e9f\u00e9rer \u00e0 une situation rationnellement compr\u00e9hensible, dans la mesure o&ugrave; elles peuvent jouer un r\u00f4le non n\u00e9gligeable.<\/p>\n<\/p>\n<p><p>Ainsi et dans ce sens, nous abordons plusieurs th\u00e8mes, personnes ou circonstances, qui jouent ou joueront un r\u00f4le dans cette crise de d\u00e9mence de l'\u00a0\u00bbhyperpuissance\u00a0\u00bb en cours d&rsquo;effondrement. Nous en gardons ou en extrayons l&rsquo;aspect qui s&rsquo;adapte le mieux au d\u00e9sordre, pour l&rsquo;alimenter ; il s&rsquo;agit de th\u00e8mes qui peuvent \u00eatre class\u00e9s, disons, \u00ab\u00a0auxiliaires du d\u00e9sordre\u00a0\u00bb.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">&bull; Trump :<em>&laquo; That&rsquo;s War ! &raquo;<\/em><\/h3>\n<\/p>\n<p><p>Il y a quelques jours, Trump proclamait emphatiquement, apprenant le lancement de la proc\u00e9dure de destitution : <strong>\u00ab\u00a0<em>That&rsquo;s war !<\/em>\u00ab\u00a0<\/strong>. Il confirme la chose en annon\u00e7ant que la Maison-Blanche refuse toute coop\u00e9ration avec les commissions de la Chambre charg\u00e9es du dossier : refus de livrer des documents, refus d&rsquo;autoriser des fonctionnaires \u00e0 t\u00e9moigner, etc. <strong>Il s&rsquo;agit d&rsquo;une confirmation op\u00e9rationnelle de la \u00ab\u00a0d\u00e9claration de guerre\u00a0\u00bb<\/strong>, dont <em>WSWS.org <\/em><a href=\"https:\/\/www.wsws.org\/fr\/articles\/2019\/10\/10\/pers-o10.html\">rend compte<\/a> dans son style habituel qui tente continuellement de renvoyer dos \u00e0 dos les deux adversaires, tous deux membres de l&rsquo;Internationale Capitaliste.<\/p>\n<\/p>\n<p><p>&laquo; <em>La Maison Blanche a d\u00e9clar\u00e9 mardi soir qu&rsquo;elle ne coop\u00e9rerait pas avec la Chambre des repr\u00e9sentants am\u00e9ricaine et avec l&rsquo;enqu\u00eate de destitution lanc\u00e9e par la direction du Parti d\u00e9mocrate. Cette d\u00e9cision marque une escalade majeure de la guerre politique \u00e0 Washington.<\/em><\/p>\n<p>&raquo; <em>Une lettre sign\u00e9e par Pat Cipollone, l&rsquo;avocat de la Maison-Blanche, affirme que l&rsquo;enqu\u00eate est une violation de la \u00ab\u00a0proc\u00e9dure r\u00e9guli\u00e8re\u00a0\u00bb et de la Constitution des &Eacute;tats-Unis. \u00ab\u00a0Afin de remplir ses obligations envers le peuple am\u00e9ricain, la Constitution, le pouvoir ex\u00e9cutif et tous les futurs occupants de la pr\u00e9sidence, le pr\u00e9sident Trump et son administration ne peuvent pas participer \u00e0 votre enqu\u00eate partisane et inconstitutionnelle dans ces circonstances\u00a0\u00bb, d\u00e9clare-t-il<\/em><\/p>\n<p>&raquo; <em>La lettre avertit que la Maison Blanche ne fournira pas de t\u00e9moignage ni de documents r\u00e9clam\u00e9s par l&rsquo;enqu\u00eate du Congr\u00e8s, ouverte pour enqu\u00eater sur la conversation t\u00e9l\u00e9phonique de Trump avec le pr\u00e9sident ukrainien Zelenski le 25 juillet. Plus t\u00f4t dans la journ\u00e9e, le gouvernement Trump a ordonn\u00e9 \u00e0 l&rsquo;ambassadeur des &Eacute;tats-Unis aupr\u00e8s de l&rsquo;Union europ\u00e9enne, Gordon Sondland, de ne pas se pr\u00e9senter \u00e0 un entretien pr\u00e9vu avec l&rsquo;enqu\u00eate de la Chambre. &Agrave; la suite de cette annonce, Trump a qualifi\u00e9 l&rsquo;enqu\u00eate \u00ab\u00a0de tribunal bidon totalement compromis\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Le m\u00e9pris de Trump \u00e0 l&rsquo;\u00e9gard du Congr\u00e8s a un caract\u00e8re nettement dictatorial. Il d\u00e9clare en substance que sa Maison-Blanche ne reconna&icirc;t aucune contrainte juridique au pouvoir de la pr\u00e9sidence. Son extraordinaire affirmation d&rsquo;un pouvoir incontr\u00f4l\u00e9 s&rsquo;accompagne d&rsquo;efforts pour mobiliser sa base droiti\u00e8re. Jeudi, Trump <\/em>[a tenu] <em>un meeting devant des policiers \u00e0 Minneapolis, Minnesota, dans le cadre d&rsquo;une campagne contre celui qu&rsquo;il appelle le maire \u00ab\u00a0d&rsquo;extr\u00eame gauche\u00a0\u00bb de la ville.<\/em><\/p>\n<p>&raquo; <em>Le d\u00e9fi lanc\u00e9 par Trump au Congr\u00e8s &ndash; qu&rsquo;il cherche \u00e0 l\u00e9gitimer en se pr\u00e9sentant comme la victime d&rsquo;un complot &ndash; est facilit\u00e9 par les m\u00e9thodes employ\u00e9es par les d\u00e9mocrates. Leur combat contre Trump n&rsquo;a aucun contenu d\u00e9mocratique ni progressiste. L&rsquo;argument des d\u00e9mocrates et de leurs soutiens des m\u00e9dias est que la politique de Trump a sap\u00e9 les int\u00e9r\u00eats strat\u00e9giques de l&rsquo;imp\u00e9rialisme am\u00e9ricain. En pointant les m\u00e9faits de Trump, ils s&rsquo;adressent, non pas \u00e0 la classe ouvri\u00e8re et \u00e0 la jeunesse, mais aux sections de la classe dirigeante &ndash; services de renseignement et arm\u00e9e et m\u00eame une partie des r\u00e9publicains &ndash; qui s&rsquo;opposent \u00e0 ce que Trump s&rsquo;\u00e9carte des priorit\u00e9s g\u00e9opolitiques et politiques de la CIA<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Il appara&icirc;t clairement que Trump se battra de toutes ses forces, sans reculer devant aucun moyen ; <strong>il y est pr\u00eat politiquement et psychologiquement, presque avec une satisfaction agressive<\/strong>&hellip; <a href=\"https:\/\/tomluongo.me\/2019\/10\/04\/trump-the-dude-break-woke\/\">Le 4 octobre<\/a>, Tom Luango d\u00e9crivait Trump comme un bagarreur de rue, un incroyable caract\u00e8re narcissique qui ne reculera devant rien pour conserver l&rsquo;avantage qui le met en avant ; pour un pr\u00e9sident-amateur qui a <strong>appris \u00e0 introduire dans l&rsquo;op\u00e9rationnalit\u00e9 de sa fonction la \u00ab\u00a0bagarre de rue\u00a0\u00bb <\/strong>pour agir sans s&#8217;emprisonner dans les rets des arm\u00e9es bureaucratiques de conseillers o&ugrave; les double jeu et les \u00ab\u00a0lanceurs d&rsquo;alerte\u00a0\u00bb pullulent, <strong>cette psychologie est un \u00e9l\u00e9ment au moins aussi important que la situation institutionnelle<\/strong> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Pat Buchanan, au d\u00e9but de la pr\u00e9sidence de Trump, nous a averti que Trump n&rsquo;\u00e9tait pas Nixon. Nixon a d\u00e9missionn\u00e9 par honte de sa conduite et pour prot\u00e9ger la fonction et l&rsquo;unit\u00e9 du pays. Trump ne s&rsquo;en irait pas aussi discr\u00e8tement dans l&rsquo;ombre de la nuit<\/em>.<\/p>\n<p>&raquo; <em>Il est fait d&rsquo;une mati\u00e8re diff\u00e9rente. Qu&rsquo;il ait tort ou raison, on ne le sortira du Bureau Ovale que les pieds devant..<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">&bull; \u00ab\u00a0<em>PostModern-<\/em>Lady MacBeth\u00a0\u00bb <em>is back<\/em><\/h3>\n<\/p>\n<p><p>Le d\u00e9sarroi ou\/et la folie des d\u00e9mocrates se mesure(nt) aussi bien par l&rsquo;extraordinaire nouvelle du retour possible d&rsquo;Hillary Clinton. Le couple qui pourrait concourir pour <strong>le titre du \u00ab\u00a0couple politique le plus corrompu et le plus pervers <\/strong>de l&rsquo;histoire des USA\u00a0\u00bb, &ndash; ce qui n&rsquo;est pas rien ! &ndash;, et l\u00e0-dedans la femme politique la plus pr\u00e9datrice et la plus intrigante, &ndash; <strong>sorte de \u00ab\u00a0Lady MacBeth postmoderne\u00a0\u00bb<\/strong>, &ndash; les Clinton seraient <strong>de retour<\/strong>(dans la mesure o&ugrave; ils nous auraient quitt\u00e9s, ce qui reste \u00e0 voir). Hillary d\u00e9ment mais tout le monde bourdonne autour d&rsquo;elle et les sondages la prennent soudain en compte, <a href=\"https:\/\/www.zerohedge.com\/political\/hillary-rockets-3rd-place-predictit-rumors-swirl-over-2020-run\">comme troisi\u00e8me<\/a>dans la lutte pour la candidature d\u00e9mocrate, &ndash; et <strong>comme seule personnalit\u00e9 d\u00e9mocrate capable de battre Trump<\/strong>.<\/p>\n<\/p>\n<p><p>On imagine le potentiel de d\u00e9sordre suppl\u00e9mentaire qu&rsquo;impliquerait un retour d&rsquo;Hillary pour une seconde fois face \u00e0 Trump, <strong>le d\u00e9cha&icirc;nement de haine et d&rsquo;hyst\u00e9rie que cela impliquerait<\/strong>, &ndash; des deux c\u00f4t\u00e9s, d&rsquo;ailleurs. Les r\u00e9actions tweeteuses sont si nombreuses et si compl\u00e8tement significatives (&laquo; <em>Oh yes absolutely she should run because the annihilation and carnage will be fun to watch<\/em> &raquo;, &laquo; <em>Yes, she deserves a second chance at being defeated<\/em> &raquo;) ;Trump se pourl\u00e8che d\u00e9j\u00e0 les babines \u00e0 l&rsquo;id\u00e9e de la possibilit\u00e9 d&rsquo;affronter <em>The-Crooked<\/em>Hillary. On a difficilement l&rsquo;impression qu&rsquo;un tel d\u00e9veloppement pourrait stabiliser la situation, notamment du c\u00f4t\u00e9 des d\u00e9mocrates, en quelque fa\u00e7on que ce soit, &ndash; <strong>et que ce serait plut\u00f4t le contraire<\/strong>&hellip;<\/p>\n<\/p>\n<p><p>Sur ce dernier point, on ajoutera l&rsquo;appendice qu&rsquo;un retour d&rsquo;Hillary <strong>aggraverait brutalement la situation au sein du parti d\u00e9mocrate o&ugrave; l&rsquo;on ne l&rsquo;attend pas avec des fleurs <\/strong>: les jeunes activistes de gauche ont de moins en moins besoin des le\u00e7ons et du chaperonnage d&rsquo;une vieille crapule de sa trempe ; surtout, une r\u00e9action contre la corruption du parti, d\u00e9j\u00e0 visible et gagnant en importance, <strong>serait fouett\u00e9e par le retour d'\u00a0\u00bbHillary l&rsquo;escroque\u00a0\u00bb<\/strong>. <a href=\"https:\/\/sputniknews.com\/us\/201910101077014041-tulsi-gabbard-may-boycott-ohio-debate-over-dnc-medias-hijacking-of-election-process\/\">Chez des candidates<\/a> comme Marianne Williamson et surtout Tulsi Gabbard (qui juge la destitution comme un risque de guerre civile), la puanteur de la corruption du DNC est d\u00e9j\u00e0 insoutenable et elles le font savoir&hellip; On imagine le tableau si Hillary revenait : l'\u00a0\u00bbunit\u00e9\u00a0\u00bb des d\u00e9mocrates volerait en \u00e9clats, <strong>jusqu&rsquo;\u00e0 <a href=\"https:\/\/www.zerohedge.com\/political\/will-clintons-destroy-democratic-party\">une scission possible<\/a> d&rsquo;affrontement ajoutant au chaos<\/strong>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">&bull; Soutien r\u00e9publicain \u00e0 g\u00e9om\u00e9trie variable<\/h3>\n<\/p>\n<p><p>&hellip;Le bouffe n&rsquo;ayant aucune limite, il est possible que nous voyons \u00e9galement r\u00e9appara&icirc;tre, cette fois du c\u00f4t\u00e9 r\u00e9publicain, <a href=\"https:\/\/www.rt.com\/op-ed\/470394-clinton-romney-politics-hollywood-remakes\/\">Mitt Romney<\/a>comme adversaire de Trump, <strong>tentant de rallier le camp de tendance <em>neocon <\/em>et du complexe militaro-industriel contre Trump<\/strong>. Romney est une vieille crapule corrompue et fortun\u00e9e, candidat r\u00e9publicain \u00ab\u00a0malheureux\u00a0\u00bb en 2012 et d&rsquo;une m\u00e9diocrit\u00e9 sans nom. <strong>Cela lui donne beaucoup d&rsquo;atouts, certes<\/strong>, dans un parti r\u00e9publicain corrompu dont le soutien \u00e0 Trump a \u00e9t\u00e9 impos\u00e9 plus que d\u00e9sir\u00e9.<\/p>\n<\/p>\n<p><p>Le cas Romney, \u00ab\u00a0tra&icirc;tre\u00a0\u00bb notoire \u00e0 Trump et sans le moindre scrupule, illustre une certaine incertitude du soutien r\u00e9publicain \u00e0 Trump, &ndash; lequel soutien conditionne \u00e9videmment son acquittement en cas de proc\u00e8s. <a href=\"https:\/\/www.strategic-culture.org\/news\/2019\/10\/06\/dont-bet-on-republicans-saving-trump\/\">Un autre texte<\/a> du m\u00eame Longo d\u00e9taille cette situation qui n&rsquo;est pas sans risque pour Trump.<\/p>\n<\/p>\n<p><p>(D&rsquo;une fa\u00e7on finalement <strong>tr\u00e8s significative de la complexit\u00e9 et de l&rsquo;incertitude de lutte autour, avec et contre Trump<\/strong>, ce texte de Longo <a href=\"https:\/\/www.strategic-culture.org\/news\/2019\/10\/06\/dont-bet-on-republicans-saving-trump\/\">du 6 octobre<\/a> contredit, d&rsquo;ailleurs d&rsquo;une fa\u00e7on assum\u00e9e, celui du <a href=\"https:\/\/tomluongo.me\/2019\/10\/04\/trump-the-dude-break-woke\/\">4 octobre<\/a> d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9 sur les qualit\u00e9s de r\u00e9silience de Trump. <strong>Cette contradiction est \u00e0 l&rsquo;image de la situation de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb<\/strong>.)<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, Trump dispose d&rsquo;un fort moyen de pression sur les r\u00e9publicains : <strong>sa popularit\u00e9 dans la base populaire des votants, dont d\u00e9pendent les \u00e9lus r\u00e9publicains<\/strong>. Ce n&rsquo;est pas pour rien que McConnell, pr\u00e9sident du groupe r\u00e9publicain au S\u00e9nat, assure que tant qu&rsquo;il d\u00e9tiendra ce poste, Trump ne sera pas destitu\u00e9, &ndash; et il met cela sur le compte <em>Facebook <\/em>de sa campagne \u00e9lectorale pour sa r\u00e9\u00e9lection comme s\u00e9nateur, comme un bon gros clin d&rsquo;&oelig;il aux \u00e9lecteurs : &laquo; <em>Nancy Pelosi est dans les griffes d&rsquo;une clique gauchiste. Ils l&rsquo;ont finalement convaincue de destituer le Pr\u00e9sident. Vous connaissez tous votre Constitution. La fa\u00e7on dont le processus de destitution sera tenu en \u00e9chec, c&rsquo;est avec une majorit\u00e9 au S\u00e9nat et avec moi comme chef de cette majorit\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">&bull; Les \u00ab\u00a0guerres-sans-fin\u00a0\u00bb : ajouter le d\u00e9sordre au d\u00e9sordre<\/h3>\n<\/p>\n<p><p>Il est certain qu&rsquo;il y a une tangente belliciste contre Trump, jug\u00e9 par les milieux <em>neocons <\/em>&#038; associ\u00e9s, jusqu&rsquo;au <em>DeepState <\/em>bien entendu, c&rsquo;est-\u00e0-dire selon un courant qui transcende les partis, <strong>comme un pr\u00e9sident \u00ab\u00a0dangereux\u00a0\u00bb pour ses impulsions \u00ab\u00a0pacifistes\u00a0\u00bb<\/strong>, comme lorsqu&rsquo;il a annonc\u00e9 une fois de plus, il y a quatre jours, que les troupes US devaient se retirer imm\u00e9diatement de leurs positions en  Syrie au nom de l&rsquo;absurdit\u00e9 de ces \u00ab\u00a0guerres ext\u00e9rieures\u00a0\u00bb, &ndash; mais, dans ce cas, laissant les Kurdes seuls face aux Turcs. La \u00ab\u00a0d\u00e9cision\u00a0\u00bb (?) a provoqu\u00e9 un toll\u00e9, notamment chez les r\u00e9publicains. La chronologie de l&rsquo;\u00e9v\u00e9nement appara&icirc;t d&rsquo;ailleurs assez \u00e9trange et <a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2019\/10\/bohica-ttg.html\">m\u00eame un Pat Lang<\/a>, adversaires d\u00e9clar\u00e9 des guerres ext\u00e9rieures \u00e0-la-<em>neocon<\/em>, <a href=\"https:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2019\/10\/httpsthehillcompolicydefense464604-us-troops-leaving-positions-in-northern-syria-ahead-of-turkish-inva.html\">juge d\u00e9plorable<\/a>cet \u00e9pisode.<\/p>\n<\/p>\n<p><p>Il est vrai que Trump est un peu revenu sur ses pas en mena\u00e7ant la Turquie, tandis que des sources au Pentagone \u00ab\u00a0temp\u00e9raient\u00a0\u00bb les d\u00e9clarations de dimanche. Depuis, Trump, \u00e0 nouveau et dans l&rsquo;autre sens, est revenu \u00e0 une charge furieuse d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale et sensationnelle, <a href=\"https:\/\/www.dedefensa.org\/article\/les-usa-attendent-leur-nuremberg\">qui met en accusation les USA<\/a>pour toutes leurs interventions ext\u00e9rieures depuis 9\/11 et <strong>radicalise d&rsquo;une fa\u00e7on ontologique sa dimension antiSyst\u00e8me<\/strong>, et l&rsquo;opposition des extr\u00e9mistes du bellicisme. <\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, on n&rsquo;\u00e9tonnera personne en observant que nous sommes ici encore dans <strong>une dynamique de confusion si caract\u00e9ristique du \u00ab\u00a0syst\u00e8me (?) Trump\u00a0\u00bb<\/strong>, que l&rsquo;on en vient \u00e0 conclure que la probl\u00e9matique des \u00ab\u00a0guerres ext\u00e9rieures\u00a0\u00bb <strong>devrait surtout conduire \u00e0 \u00ab\u00a0ajouter du d\u00e9sordre au d\u00e9sordre\u00a0\u00bb<\/strong>, et il n&rsquo;est pas ais\u00e9 de distinguer malgr\u00e9 la corruption pro-Syst\u00e8me du parti r\u00e9publicain comment <strong>un regroupement anti-Trump dans ce domaine pourrait acqu\u00e9rir une puissance d\u00e9cisive <\/strong>jusqu&rsquo;\u00e0 peser indirectement en faveur de la destitution.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le mod\u00e8le \u00ab\u00a0dosto\u00efevskien\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Dans les situations que l&rsquo;on a d\u00e9crites o&ugrave; est menac\u00e9e l&rsquo;existence des deux ailes (d\u00e9mocrates et r\u00e9publicains) du \u00ab\u00a0parti unique\u00a0\u00bb, \u00e9cras\u00e9es par leur corruption et leurs liens inf\u00e2mes avec divers centres d&rsquo;int\u00e9r\u00eats particuliers, priv\u00e9s et subversifs, US ou non-US, on distingue au-del\u00e0 du cas de la destitution une situation exemplaire de <strong>menace de la d\u00e9sint\u00e9gration totale de tout l&rsquo;arrangement bipartisan <\/strong>du syst\u00e8me du pouvoir de l&rsquo;am\u00e9ricanisme. De m\u00eame et parce que ces situations sont surtout faites <strong>d&rsquo;arrangements de corruption de circonstances, sans autre buts que le lucre et la sauvegarde<\/strong>, et cela sous une pression ext\u00e9rieure \u00e9norme et <strong>hors de tout contr\u00f4le humain et de toute force partisane organis\u00e9e, comme une force suprahumaine<\/strong>, on en arrive tr\u00e8s rapidement et \u00e9videmment \u00e0 \u00e9mettre des doutes fondamentaux sinon d\u00e9cisifs concernant le caract\u00e8re purement id\u00e9ologique que certains veulent donner \u00e0 l&rsquo;affrontement en cours, de la guerre civile potentielle \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>En actant toutes ces donn\u00e9es objectives de d\u00e9sordre et de chaos, on est conduit \u00e0 chercher une explication plus haute, plus fondamentale, de la situation. <strong>C&rsquo;est ainsi que nous pr\u00e9sentons l&rsquo;hypoth\u00e8se du \u00ab\u00a0mod\u00e8le dosto\u00efevskien\u00a0\u00bb<\/strong>, qui vaut bien entendu pour \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, et aussi pour tous les autres foyers et incendies, hors des USA, qui peuvent \u00eatre <strong>li\u00e9s directement ou indirectement \u00e0 ce que nous nommons la Grande Crise d&rsquo;Effondrement du Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;hypoth\u00e8se du \u00ab\u00a0mod\u00e8le dosto\u00efevskien\u00a0\u00bb : description<\/h3>\n<\/p>\n<p><p>Le cas sp\u00e9cifiquement m\u00e9tahistorique choisi ici est inspir\u00e9 par la th\u00e8se de Mircea Marghescu, dont nous avons <a href=\"https:\/\/www.dedefensa.org\/article\/tc-78vertigo\">d\u00e9j\u00e0 parl\u00e9e<\/a>, dans son livre <em>Homunculus <\/em>sur une &lsquo;<em>Critique dosto\u00efevskienne de l&rsquo;anthropologie<\/em>&lsquo;. Accordant une importance quasiment sans \u00e9gale sur la signification et l&rsquo;analyse tr\u00e8s originale et d\u00e9cisive <strong>de la modernit\u00e9 dans son affrontement avec la Tradition<\/strong>, dans l&rsquo;&oelig;uvre de Dosto\u00efevski, Marghescu \u00e9carte l&rsquo;explication id\u00e9ologique au profit de <strong>l&rsquo;explication d\u00e9cisivement fondamentale de l&rsquo;ontologie<\/strong>.<\/p>\n<\/p>\n<p><p>&laquo; <em>Deux hypostases de l&rsquo;humain s&rsquo;affrontent, ontologiquement diff\u00e9rentes puisque chacune \u00e0 son ouverture au monde sp\u00e9cifique&hellip; <\/em>[&hellip;] <em>La transgression dont Raskolnikov se rend coupable et qui plus tard ne fera que se r\u00e9p\u00e9ter avec le meurtre, n&rsquo;est pas id\u00e9ologique mais ontologique ; \u00ab\u00a0avant\u00a0\u00bb et \u00ab\u00a0apr\u00e8s\u00a0\u00bb, ce n&rsquo;est pas d&rsquo;un m\u00eame homme puisque le second a une conscience nouvelle dont les comp\u00e9tences ont \u00e9t\u00e9 \u00ab\u00a0\u00e9largies\u00a0\u00bb.<\/em>[&hellip;] <em>On comprend mieux ainsi la teneur du conflit dosto\u00efevskien, &ndash; qui n&rsquo;a rien de commun avec le d\u00e9bat id\u00e9ologique&hellip; <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Marghescu oppose ainsi, dans l&rsquo;univers dosto\u00efevskien, l'\u00a0\u00bbhomme normal\u00a0\u00bb, \u00e9galement d\u00e9sign\u00e9 plus pr\u00e9cis\u00e9ment comme \u00ab\u00a0homme traditionnel\u00a0\u00bb, et \u00ab\u00a0l&rsquo;homme nouveau\u00a0\u00bb, qui est le moderne et qui pourrait \u00eatre \u00ab\u00a0l&rsquo;homme moderne\u00a0\u00bb, &ndash; Raskolnikov nous \u00e9tant pr\u00e9sent\u00e9 comme l&rsquo;arch\u00e9type de l&rsquo;\u00eatre qui, changeant d'\u00a0\u00bb\u00eatre\u00a0\u00bb, passe de l&rsquo;un \u00e0 l&rsquo;autre. On comprend ainsi que, <strong>loin d&rsquo;\u00eatre un progr\u00e8s dans le sens de la valeur qualitative<\/strong>, cette \u00e9volution, qui passe sous les fourches caudines de cette inversion diabolique du progr\u00e8s qu&rsquo;est \u00ab\u00a0le Progr\u00e8s  selon le moderne\u00a0\u00bb, <strong>repr\u00e9sente une compl\u00e8te catastrophe ontologique <\/strong>pr\u00e9sentant aujourd&rsquo;hui les comptes d\u00e9cisifs qu&rsquo;il importe de r\u00e9gler, dans le cadre absolument contraignant comme un Temps de la Grande Crise de l&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>L'\u00a0\u00bbhomme nouveau\u00a0\u00bb &laquo; <em>voit s&rsquo;achever l&rsquo;aventure commenc\u00e9e \u00e0 la Renaissance puisqu&rsquo;il a \u00e9puis\u00e9 ses projets dans l&rsquo;action et qu&rsquo;il n&rsquo;en a pas d&rsquo;autres. <\/em>[&hellip;] <em>Au moment m\u00eame o&ugrave; Zarathoustra, &ndash; et les na\u00effs, &ndash; se croient encore aux aurores et appellent un \u00ab\u00a0homme nouveau\u00a0\u00bb, Stavroguine et Raskolnikov savent que la nuit tombe et que \u00ab\u00a0l&rsquo;homme nouveau\u00a0\u00bb a v\u00e9cu&hellip; <\/em>&raquo;.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">USA, l'\u00a0\u00bbhomme traditionnel\u00a0\u00bb contre l'\u00a0\u00bbhomme nouveau\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>En prenant cette approche Marghescu\/Dosto\u00efevski, nous ne pr\u00e9tendons pas une seconde, cela va de soi, que la crise am\u00e9ricaniste se ram\u00e8ne au conflit entre l'\u00a0\u00bbhomme traditionnel\u00a0\u00bb et l'\u00a0\u00bbhomme nouveau\u00a0\u00bb ; nous pr\u00e9tendons que dans un sens op\u00e9rationnel pr\u00e9cieux pour l&rsquo;analyse, \u00ab\u00a0tout se passe comme si la crise am\u00e9ricaniste se ramenait au conflit entre l\u00a0\u00bbhomme traditionnel&rsquo; et l\u00a0\u00bbhomme nouveau'\u00a0\u00bb. Dans ce sens pr\u00e9cis\u00e9ment et seulement dans ce sens, malgr\u00e9 et en d\u00e9pit des singularit\u00e9s extraordinaires des USA et du citoyen des USA qui n&rsquo;ont finalement <strong>leur utilit\u00e9 que parce qu&rsquo;ils constituent le d\u00e9tonateur exceptionnel <\/strong>de la crise les d\u00e9truisant eux-m\u00eames et le reste de notre contre-civilisation, la crise am\u00e9ricaniste <strong>est absolument similaire <\/strong>\u00e0 toutes les autres crises, elle est <strong>la plus parfaite repr\u00e9sentation de la crise du monde et de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me <\/strong>; et encore plus, et par cons\u00e9quent comme justification de notre d\u00e9marche analogique, elle est la plus parfaite repr\u00e9sentation par interpr\u00e9tation <strong>de la crise fondamentale, &ndash; modernit\u00e9 contre Tradition, &ndash; qu&rsquo;illustre le \u00ab\u00a0mod\u00e8le dosto\u00efevskien\u00a0\u00bb<\/strong>. <\/p>\n<\/p>\n<p><p>Pour Dosto\u00efevski, l'\u00a0\u00bbhomme normal\u00a0\u00bb (encore au XIX\u00e8me si\u00e8cle), plus s&ucirc;rement \u00ab\u00a0homme de la Tradition\u00a0\u00bb, est l&rsquo;homme qui na&icirc;t dans un monde o&ugrave; existent un cadre transcendant qu&rsquo;il importe de respecter comme la nature m\u00eame du monde dont il doit faire partie ; une multitude de \u00ab\u00a0liens\u00a0\u00bb transcendants, c&rsquo;est-\u00e0-dire <strong>des structures qui forment le cadre de la nature du monde<\/strong>, qui vont dire \u00e0 cet homme, de fa\u00e7on imp\u00e9rative, dans quel sens et de quelle fa\u00e7on doivent aller ses actes et sa vie. L'\u00a0\u00bbhomme nouveau\u00a0\u00bb, ou \u00ab\u00a0homme moderne\u00a0\u00bb, c&rsquo;est l&rsquo;homme dont la conscience a pris le pas sur le reste et d\u00e9cidera \u00ab\u00a0de fa\u00e7on imp\u00e9rative dans quel sens et de quelle fa\u00e7on vont aller ses actes et sa vie\u00a0\u00bb, et <strong>donc qui soumet la \u00ab\u00a0nature du monde\u00a0\u00bb dont il tend de plus en plus \u00e0 douter de sa pertinence sinon de son existence <\/strong><strong>au jugement triomphal de sa conscience<\/strong>. &laquo; <em>Chaque lien, nagu\u00e8re transcendant, perd son statut pour devenir relation permanente et, de ce fait, pr\u00e9caire<\/em>&hellip; &raquo; (\u00ab\u00a0pr\u00e9caire\u00a0\u00bb, et bient\u00f4t crisique, puis catastrophique comme on le voit aujourd&rsquo;hui).<\/p>\n<\/p>\n<p><p>Notre id\u00e9e est donc que les USA crisiques, au travers de leur crise fondamentale (ontologique, certes !), se sont transform\u00e9s, passant d&rsquo;un affrontement pseudo-id\u00e9ologique, en un affrontement ontologique <strong>sans que les acteurs de la chose <\/strong>en soient n\u00e9cessairement conscients, &ndash; <strong>ce qui n&rsquo;a strictement et absolument aucune importance<\/strong>. <\/p>\n<\/p>\n<p><p>(Ce dernier membre de phrase situe o&ugrave; nous nous trouvons dans cet affrontement, o&ugrave; nous nous pla\u00e7ons, combien nous prenons en compte  cette interpr\u00e9tation et qui peut l&#8217;emporter, et qui ne peut en aucun cas, en aucune fa\u00e7on, jamais l&#8217;emporter.)<\/p>\n<\/p>\n<p><p>Bien entendu, dans notre sch\u00e9matisation :<\/p>\n<\/p>\n<p><p>&bull; les adversaires des progressistes-soci\u00e9taux (plut\u00f4t que \u00ab\u00a0partisans de Trump\u00a0\u00bb, circonstance tactique importance mais devenant anodine) repr\u00e9sentent les \u00ab\u00a0hommes traditionnels\u00a0\u00bb bien qu&rsquo;<strong>ils ne le soient absolument pas <em>stricto sensu <\/em><\/strong>puisqu&rsquo;ils sont au d\u00e9part fils des USA, donc des \u00ab\u00a0hommes nouveaux\u00a0\u00bb fid\u00e8les aux principes des P\u00e8res fondateurs qui ont engendr\u00e9 la modernit\u00e9 ; <\/p>\n<\/p>\n<p><p>&bull; Les progressistes-soci\u00e9taux (les ennemis de Trump) sont effectivement des \u00ab\u00a0hommes nouveaux\u00a0\u00bb, ils ne s&rsquo;en cachent pas et m\u00eame s&rsquo;en revendiquent ; mais \u00ab\u00a0hommes nouveaux\u00a0\u00bb qui <strong>font la d\u00e9monstration de la catastrophique absurdit\u00e9 que constitue cette \u00ab\u00a0nouveaut\u00e9\u00a0\u00bb qu&rsquo;est la modernit\u00e9 <\/strong>puisque, poussant \u00e0 l&rsquo;extr\u00eame ses \u00ab\u00a0valeurs\u00a0\u00bb (\u00e9galit\u00e9, individualisme, <em>hybris <\/em>par rapport \u00e0 la nature du monde, etc.) qui sont, elles, id\u00e9ologiques, <strong>ils arrivent compl\u00e8tement, cliniquement \u00e0 la d\u00e9mence<\/strong>, en m\u00eame temps qu&rsquo;\u00e0 la <strong>destruction de leur civilisation et du monde<\/strong>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La crise US comme Incarnation<\/h3>\n<\/p>\n<p><p>Autrement dit, la crise US est une incarnation (mais nullement un simulacre) du paroxysme de la catastrophe originelle qui a frapp\u00e9 notre civilisation, l&rsquo;a transform\u00e9e en contre-civilisation et la conduit vers la n\u00e9antisation, \u00e0 l&rsquo;entropisation, &ndash; <strong>qu&rsquo;elle atteindra d&rsquo;une fa\u00e7on ou l&rsquo;autre, pour laisser place \u00e0 \u00ab\u00a0autre chose\u00a0\u00bb qui reprendra la cha&icirc;ne interrompue (<a href=\"https:\/\/www.dedefensa.org\/article\/la-civilisation-imposture\">voir<\/a> <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-une-fin-des-temps\">Toynbee<\/a>)<\/strong>. Comme l&rsquo;on voit, cette crise US n&rsquo;a aucun lien direct, disons d\u00e9cisif, avec les divers gadgets id\u00e9ologiques dont on nous rebat les oreilles, y compris avec le capitalisme qui n&rsquo;est qu&rsquo;un outil de la Chute&hellip;<\/p>\n<\/p>\n<p><p>Comme l&rsquo;on voit c&rsquo;est et ce ne peut \u00eatre qu&rsquo;une crise destructrice, comme partout ailleurs, et une crise destructrice du Syst\u00e8me. Tous les moyens sont bons pour l&rsquo;activer dans toute sa puissance. <strong>Les acteurs jouet \u00e0 faux-emploi <\/strong><strong>et s&rsquo;av\u00e8rent fort efficaces <\/strong>: les \u00ab\u00a0Tradis\u00a0\u00bb sont en fait des \u00ab\u00a0hommes nouveaux\u00a0\u00bb trahis et manipul\u00e9s et reprenant les revendications des \u00ab\u00a0Tradis\u00a0\u00bb ; les \u00ab\u00a0hommes nouveaux\u00a0\u00bb, poussant jusqu&rsquo;\u00e0 l&rsquo;extr\u00eame de la d\u00e9mence et de la d\u00e9route totale les exigences de la modernit\u00e9, deviennent des caricatures inf\u00e2mes de ce qu&rsquo;ils pr\u00e9tendent \u00eatre, et ainsi <strong>premiers d\u00e9nonciateurs paradoxaux de ce dont ils pr\u00e9tendent faire la promotion<\/strong>. Et dans cette bataille \u00e0 faux-nez, des arguments des uns peuvent \u00eatre utilis\u00e9s pour servir la cause assez mal identifi\u00e9e de leurs adversaires.<\/p>\n<\/p>\n<p><p>Crise absolument destructrice, <strong>crise de d\u00e9structuration d&rsquo;une structure (le Syst\u00e8me) con\u00e7ue pour d\u00e9structurer la nature du monde<\/strong>. Il s&rsquo;agit donc pour l&rsquo;instant de d\u00e9truire, <em>Delenda Est Systemum<\/em>. Apr\u00e8s, l&rsquo;on se comptera et l&rsquo;on verra &hellip; Apr\u00e8s, la loi du monde reprendra ses droits.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur une destitution m\u00e9tahistorique 10 octobre 2019 &ndash; Bien s&ucirc;r, le titre de ces Notes d&rsquo;analyse pouvait se se r\u00e9f\u00e8rer au texte du 9 octobre de PhG dans son Journal-dde.crisis, justement avec le titre de \u00ab\u00a0Notes sur &lsquo;une destitution Rock&rsquo;n Roll&rsquo;\u00a0\u00bb que nous envisag\u00e9 un instant de choisir. Ce texte constituait une analyse g\u00e9n\u00e9rale,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4911,12334,19413,3278,5875,5649,19327,19414,5197,11306,6140,19416,19417,6776,19415,2639],"class_list":["post-78894","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-destitution","tag-dostoievski","tag-dostoievskien","tag-hillary","tag-ideologie","tag-luongo","tag-marghescu","tag-mircea","tag-modele","tag-ontologie","tag-pelosi","tag-rockn","tag-roll","tag-romney","tag-traditionaliste","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78894"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78894\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}