{"id":78896,"date":"2019-10-12T16:21:32","date_gmt":"2019-10-12T16:21:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/12\/trump-fait-le-menage\/"},"modified":"2019-10-12T16:21:32","modified_gmt":"2019-10-12T16:21:32","slug":"trump-fait-le-menage","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/12\/trump-fait-le-menage\/","title":{"rendered":"Trump fait le m\u00e9nage"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Trump fait le m\u00e9nage<\/h2>\n<\/p>\n<p><p>Des indications pr\u00e9cises apparaissent de plus en plus sur l&rsquo;action entreprise par le pr\u00e9sident Trump dans les rangs du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Conseil_de_s%C3%A9curit%C3%A9_nationale_(%C3%89tats-Unis)\">NSC<\/a> (National Security Council), qui est ce \u00ab\u00a0gouvernement\u00a0\u00bb restreint du pr\u00e9sident,  coordonnant et int\u00e9grant les diverses informations et analyses de s\u00e9curit\u00e9 nationale (notamment venues des minist\u00e8res concern\u00e9s) pour le pr\u00e9sident, pour lui permettre de prendre ses d\u00e9cisions dans cette mati\u00e8re. A l&rsquo;occasion du troisi\u00e8me (un record) changement du directeur et conseiller de s\u00e9curit\u00e9 national, il semble que Trump ait donn\u00e9 l&rsquo;ordre \u00e0 Robert O&rsquo;Brien, le rempla\u00e7ant de Bolton, d&rsquo;op\u00e9rer une vaste purge des effectifs.<\/p>\n<\/p>\n<p><p>Bloomberg rapportait la chose le <a href=\"https:\/\/www.bnnbloomberg.ca\/trump-orders-cut-to-national-security-staff-after-whistle-blower-1.1326901\">7 octobre 2019<\/a> : &laquo; <em>Le pr\u00e9sident Donald Trump a ordonn\u00e9 une r\u00e9duction substantielle du personnel du Conseil de S\u00e9curit\u00e9 Nationale, selon cinq personnes au courant des plans, alors que la Maison-Blanche fait face \u00e0 une enqu\u00eate de destitution d\u00e9clench\u00e9e par une plainte de d\u00e9nonciateur concernant le travail de l&rsquo;agence<\/em>.<\/p>\n<p>&raquo; <em>Certaines personnes ont d\u00e9crit les compressions de personnel comme faisant partie d&rsquo;un effort de la Maison-Blanche visant \u00e0 all\u00e9ger son \u00e9quipe de politique \u00e9trang\u00e8re sous la direction du nouveau conseiller \u00e0 la s\u00e9curit\u00e9 nationale, Robert O&rsquo;Brien<\/em>.<\/p>\n<p>&raquo; <em>Cette semaine, le chef d&rsquo;\u00e9tat-major par int\u00e9rim de la Maison-Blanche, Mick Mulvaney et O&rsquo;Brien, a transmis la demande de limiter la taille du personnel du NSC aux cadres sup\u00e9rieurs de l&rsquo;organisme<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Sur le site <em>Sic Semper Tyrannis <\/em>(SST) du colonel Lang, le chroniqueurs Larry C. Johnson donne une explication plus sp\u00e9cifique et plus \u00ab\u00a0politique\u00a0\u00bb puisqu&rsquo;il s&rsquo;agit en fait d&rsquo;une \u00ab\u00a0purge\u00a0\u00bb effectivement politique, et non pas simplement administrative. (L&rsquo;un des arguments pour l&rsquo;explication administrative a \u00e9t\u00e9 qu&rsquo;avec le gonflement consid\u00e9rable des effectifs du NSC, &ndash; d&rsquo;une cinquantaine de personnes \u00e0 plus de 700, &ndash; le Congr\u00e8s pouvait intervenir et exiger que le choix du directeur du NSC, et conseiller du pr\u00e9sident, soit soumis \u00e0 l&rsquo;approbation du S\u00e9nat, &ndash; ce que tous les pr\u00e9sidents veulent \u00e9viter pour ne pas voir r\u00e9duite leur autonomie en mati\u00e8re de politique de s\u00e9curit\u00e9 nationale.)<\/p>\n<\/p>\n<p><p>Johnson d\u00e9crit ainsi comment a fonctionn\u00e9 un NSC qui a continu\u00e9 \u00e0 exercer l&rsquo;influence voulue par l&rsquo;administration Obama durant les trois premi\u00e8res ann\u00e9es Trump : &laquo; <em>Il semblerait que le Pr\u00e9sident Trump r\u00e9alise enfin qu&rsquo;il travaille dans une fosse remplie de serpents. Lorsqu&rsquo;il a pris ses fonctions le 20 janvier 2017, il a laiss\u00e9 en place un \u00e9norme contingent de cadres acquis \u00e0 la clique Obama-Hillary. Il aurait pu (et aurait d&ucirc;) les d\u00e9placer et les r\u00e9affecter \u00e0 un \u00e9quivalent bureaucratique de la Sib\u00e9rie. Mais il ne l&rsquo;a pas fait. Prenons le cas de Tina Kaidanow, qui dirigeait le Bureau de l&rsquo;antiterrorisme lorsque Trump a pris le pouvoir. Plut\u00f4t que de demander sa d\u00e9mission, on l&rsquo;a plac\u00e9e en deuxi\u00e8me position au Bureau des affaires politico-militaires. <\/em><\/p>\n<p>&raquo; <em>En septembre 2018, Kaidanow a obtenu <a href=\"https:\/\/www.defensenews.com\/pentagon\/2018\/09\/06\/longtime-diplomat-kaidanow-heads-to-pentagon\/\">une autre promotion<\/a>:<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0L&rsquo;ambassadrice Tina Kaidanow, fonctionnaire de longue date du d\u00e9partement d&rsquo;&Eacute;tat et acteur clef des r\u00e9centes r\u00e9formes du processus am\u00e9ricain de vente d&rsquo;armes, est affect\u00e9e au Pentagone.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Kaidanow traversera le Potomac et entrera au Pentagone en tant  que prochain directeur de la coop\u00e9ration internationale, un bureau qui rel\u00e8vera du bureau des acquisitions et de l&rsquo;entretien reconstitu\u00e9 du Minist\u00e8re.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Tina est embl\u00e9matique de l&rsquo;\u00e9tat profond. Je ne serais pas surpris que son nom fasse surface en Ukraine. Elle fera tout ce qui est en son pouvoir, \u00e0 mon avis, pour savonner la planche sous les pas de Donald Trump.<\/em><\/p>\n<p>&raquo; <em>Sous le pr\u00e9sident Obama, le nombre d&rsquo;officiers de la CIA \u00ab\u00a0d\u00e9tach\u00e9s\u00a0\u00bb pour des fonctions temporaires au Conseil de S\u00e9curit\u00e9 Nationale <\/em>[NSC]<em>est pass\u00e9 \u00e0 environ 200. Il y a donc un nombre \u00e9norme de fant\u00f4mes dans les couloirs du Old Executive Office Building <\/em>[<a href=\"https:\/\/en.wikipedia.org\/wiki\/Eisenhower_Executive_Office_Building\">OEOB, rebaptis\u00e9 EEOB<\/a>, immeuble \u00e0 c\u00f4t\u00e9 de la Maison-Blanche, avec les anciens bureaux de certains minist\u00e8res et services de l&rsquo;ex\u00e9cutif, devenu le si\u00e8ge du NSC]<em>. Lorsque Donald Trump a \u00e9t\u00e9 inaugur\u00e9, la CIA a port\u00e9 ce nombre \u00e0 pr\u00e8s de 300. Il \u00e9tait fini, le temps o&ugrave; les agents de la CIA \u00e9vitaient la politique partisane et se concentraient sur le service du pr\u00e9sident \u00e9lu. L&rsquo;\u00e9quipe actuelle est fortement politis\u00e9e et la plupart ont un parti pris antiTrump.<\/em><\/p>\n<p>&raquo; <em>&#8230; Mais depuis la semaine derni\u00e8re, le pr\u00e9sident Trump a commenc\u00e9 \u00e0 faire le m\u00e9nage. Un nombre important d&rsquo;officiers de la CIA qui comptaient se pr\u00e9senter \u00e0 leur travail dans leurs bureaux de l&rsquo;OEOB, se sont entendu dire que leurs services n&rsquo;\u00e9taient plus requis et qu&rsquo;ils devaient retourner sur leurs pas, jusqu&rsquo;\u00e0 leurs anciens bureaux de l&rsquo;Agence, \u00e0 McClean, en Virginie.<\/em> <\/p>\n<p>&raquo; <em>Si vous avez la chance de visiter l&rsquo;OEOB, vous y trouverez beaucoup de bureaux vides et inoccup\u00e9s cette semaine. Il ne s&rsquo;agit pas d&rsquo;un changement temporaire. C&rsquo;est une mesure attendue depuis longtemps. Le pr\u00e9sident Trump se rend enfin compte qu&rsquo;il est entour\u00e9 de s\u00e9ditionnistes partisans et il \u00e9limine leur acc\u00e8s et leur influence. Ce n&rsquo;est pas trop t\u00f4t<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Ce cas n&rsquo;est pas unique, de voir un nouveau pr\u00e9sident second\u00e9 par une administration essentielle et tr\u00e8s proche de lui d&rsquo;une orientation politique diff\u00e9rente de la sienne. En g\u00e9n\u00e9ral, le probl\u00e8me est r\u00e9gl\u00e9 comme il est possible de :l&rsquo;\u00eatre dans un milieu bureaucratique dans la premi\u00e8re ann\u00e9e de la nouvelle pr\u00e9sidence. Le cas de Trump est exceptionnel et rel\u00e8ve beaucoup plus de l&rsquo;inexp\u00e9rience du pr\u00e9sident dans ces affaires de s\u00e9curit\u00e9 nationale, de son incapacit\u00e9 \u00e0 trouver les bonnes personnes pour faire sa politique, ses choix critiquables voire catastrophiques des directeurs du NSC, l&rsquo;influence \u00e9galement catastrophique de son  gendre Kushner dans les affaires de s\u00e9curit\u00e9 nationale, &ndash; \u00ab\u00a0catastrophique\u00a0\u00bb dans tous les cas, pour la politique que Trump pr\u00e9tendait mener lors de la campagne \u00e9lectorale, et qui serait effectivement accord\u00e9e \u00e0 ses conceptions unilat\u00e9ralistes et n\u00e9o-isolationnistes. Enfin la pr\u00e9sence de plusieurs centaines d&rsquo;officiers de la CIA choisis par Brennan, l&rsquo;ancien directeur et homme d&rsquo;Obama, constituait une formidable puissance d&rsquo;influence bureaucratique.<\/p>\n<\/p>\n<p><p>La responsabilit\u00e9 de Trump est certainement tr\u00e8s grande dans certaines d\u00e9cisions et choix, mais elle n&rsquo;est donc pas unique ni exclusive car la question est plus bureaucratique, avec la n\u00e9cessit\u00e9 d&rsquo;une bonne connaissance de ces arcanes, que purement politique. (C&rsquo;est l\u00e0 o&ugrave; l&rsquo;on doit h\u00e9siter sur une formulation de l&rsquo;identification de l&rsquo;&Eacute;tat profond&#8230;) Par exemple, le cas de Kaidanow, cit\u00e9 dans le texte de Johnson, en rappelle un autre, qui est celui de Victoria Nuland, <em>neocon <\/em>d\u00e9j\u00e0 install\u00e9e du temps de l&rsquo;administration GW Bush, rest\u00e9e au d\u00e9partement d&rsquo;&Eacute;tat sous Hillary Clinton et h\u00e9rit\u00e9e par John Kerry en 2013, &ndash; et ce cas exemplaire, tel que nous en rapportions quelques \u00e9l\u00e9ments <a href=\"https:\/\/www.dedefensa.org\/article\/les-confidences-de-kerry\">en juin 2015<\/a>, \u00e0 propos de cette haut-fonctionnaire (Nuland) qui, avec l&rsquo;ambassadeur US \u00e0 Kiev qu&rsquo;elle avait mobilis\u00e9 pour la cause, a sans aucun doute \u00e9t\u00e9 la principale instigatrice du c\u00f4t\u00e9 de l&rsquo;administration US du coup d&rsquo;&Eacute;tat du Maidan du 20 f\u00e9vrier 20214&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans une autre occasion, d\u00e9j\u00e0, nous avions eu l&rsquo;occasion de commenter un a-parte de Lavrov et de Kerry, lors d&rsquo;une rencontre du printemps 2013 du Russe avec le nouveau secr\u00e9taire d&rsquo;&Eacute;tat. Notre commentaire, venue d&rsquo;une \u00ab\u00a0confidence\u00a0\u00bb de Lavrov \u00e0 des parlementaires de la Douma, sonnait au d\u00e9savantage de Kerry, alors qu&rsquo;on peut aujourd&rsquo;hui avancer une autre interpr\u00e9tation. Lavrov lui-m\u00eame peut avoir modifi\u00e9 son avis, par rapport aux circonstances o&ugrave; il rapporta cet \u00e9pisode une premi\u00e8re fois, \u00e0 propos d&rsquo;une de ses premi\u00e8res rencontres (peut-\u00eatre la premi\u00e8re) avec Kerry, alors que les deux hommes ne se connaissaient pas et avaient n\u00e9cessairement une attitude de retenue l&rsquo;un par rapport \u00e0 l&rsquo;autre. On pouvait lire ceci, le <a href=\"http:\/\/www.dedefensa.org\/article-hyst_ries_en_m_nage_neocons_et_r2p_21_04_2014.html\">21 avril 2015<\/a>, qui rapportait cette \u00ab\u00a0confidence\u00a0\u00bb de Lavrov faite pr\u00e8s de deux ans plus t\u00f4t aux parlementaires russes<\/em> :<\/p>\n<p>&raquo; <em>\u00ab\u00a0Le Russe Lavrov a racont\u00e9 comment, lors d&rsquo;une de ses premi\u00e8res rencontres avec le nouveau secr\u00e9taire d&rsquo;&Eacute;tat au printemps 2013, il avait f\u00e9licit\u00e9 Kerry pour avoir &lsquo;liquid\u00e9&rsquo; Victoria Nuland de sa position de porte-parole du d\u00e9partement o&ugrave; l&rsquo;avait install\u00e9e Clinton ; Kerry lui avait r\u00e9pondu qu&rsquo;il l&rsquo;avait au contraire promue (comme assistante au secr\u00e9taire d&rsquo;&Eacute;tat pour l&rsquo;Europe et l&rsquo;Eurasie), ajoutant qu&rsquo;il aurait ainsi, \u00e0 ses c\u00f4t\u00e9s, une diplomate exp\u00e9riment\u00e9e pour conduire une politique d&rsquo;entente, notamment et pr\u00e9cis\u00e9ment avec la Russie. Lavrov avait consid\u00e9r\u00e9 Kerry pour tenter de distinguer dans ses paroles quelque ironie ou sarcasme, pour n&rsquo;y trouver qu&rsquo;un s\u00e9rieux ing\u00e9nu et d\u00e9sesp\u00e9r\u00e9ment na\u00eff, &ndash; et peut-\u00eatre, m\u00eame, volontairement na\u00eff. La question se pose en effet, dans ce cas de Kerry comme dans tant d&rsquo;autres, et dans le cas d&rsquo;Obama comme dans celui de Kerry, s&rsquo;il existe une conscience r\u00e9elle de la signification des actes ainsi pos\u00e9s, par rapport \u00e0 ce que tout homme normalement inform\u00e9 doit en savoir, \u00e0 la lumi\u00e8re de la personnalit\u00e9 et de l&rsquo;activisme bien connues d&rsquo;une Nuland. Lavrov rapporte que Kerry ne semblait pas vraiment comprendre ce que signifiait, en termes de perspectives politiques, la nomination de Nuland \u00e0 un tel poste, &ndash; non plus que, dans un autre contexte, celle de Power \u00e0 la t\u00eate de la d\u00e9l\u00e9gation diplomatique US aux Nations-Unies.<\/em>\u00ab\u00a0<\/p>\n<p>&raquo; <em>Le d\u00e9veloppement de notre hypoth\u00e8se \u00e0 partir de ces divers \u00e9l\u00e9ments nous conduit \u00e0 penser que la remarque de Poutine lors de son interview au  &lsquo;Corriere della Sera&rsquo;  renverrait essentiellement \u00e0 sa longue rencontre avec Kerry et Lavrov, au cours de laquelle le secr\u00e9taire d&rsquo;&Eacute;tat aurait expos\u00e9 \u00e0 ses interlocuteurs qu'\u00a0\u00bbil ne contr\u00f4lait pas (directement ou indirectement) la situation en Ukraine\u00a0\u00bb. La m\u00e9connaissance de Kerry de la d\u00e9claration de Porochenko, dont probablement Lavrov et Poutine l&rsquo;ont inform\u00e9, serait alors un signe de cette absence de contr\u00f4le, qui serait \u00e9galement, et plus gravement encore, une m\u00e9sinformation de la situation en Ukraine. La &lsquo;l\u00e9g\u00e8ret\u00e9&rsquo; de Kerry dont nous parlons plus haut, la l\u00e9g\u00e8ret\u00e9 avec laquelle Kerry recommande (\u00e0 Lavrov) de ne pas prendre au s\u00e9rieux les d\u00e9clarations d&rsquo;Obama (voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_diplomatie_ouverte_comme_arme_de_destruction_massive_20_11_2014.htmlq\">20 novembre 2014<\/a>), signifie plus que de la l\u00e9g\u00e8ret\u00e9, mais \u00e9galement une confidence cach\u00e9e selon laquelle nombre de d\u00e9clarations officielles doivent \u00eatre prises en tenant compte de pressions bellicistes auxquelles c\u00e8dent Obama, et son administration derri\u00e8re lui ; de m\u00eame pour la nomination de Nuland, qui lui aurait \u00e9t\u00e9 impos\u00e9e ou qu&rsquo;il se serait jug\u00e9 contraint d&rsquo;accepter &#8230; D\u00e8s lors, la d\u00e9claration de Poutine (\u00ab\u00a0les d\u00e9marches non professionnelles\u00a0\u00bb des USA qui sont \u00ab\u00a0\u00e0 l&rsquo;origine de\u00a0\u00bb la crise ukrainienne) renvoie \u00e9videmment et notamment au r\u00f4le de Nuland (avec l&rsquo;ambassadeur US \u00e0 Kiev), non supervis\u00e9, non contr\u00f4l\u00e9 par Kerry, &ndash; ce qui a toujours \u00e9t\u00e9 l&rsquo;hypoth\u00e8se que nous privil\u00e9gions ; et \u00ab\u00a0l&rsquo;absence de contr\u00f4le\u00a0\u00bb d\u00e9crit par Poutine concerne aussi bien la position de la direction US par rapport \u00e0 son administration, son autorit\u00e9 sur elle, chose mise en \u00e9vidence (d\u00e9claration de Porochenko) lors de la rencontre de Sotchi, et que Kerry lui-m\u00eame aurait reconnue<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette longue s\u00e9quence mettant en sc\u00e8ne des personnages d&rsquo;une m\u00eame administration (des d\u00e9mocrates, aujourd&rsquo;hui consid\u00e9r\u00e9e comme plut\u00f4t \u00ab\u00a0complices\u00a0\u00bb du Syst\u00e8me contre Trump si l&rsquo;on veut simplifier) montre que les attaques du Syst\u00e8me sont syst\u00e9matiques et ne tiennent aucun compte des politiques voulues par les concepteurs et d\u00e9cideurs humains, quelles que soient leurs tendances. Kerry \u00e9tait venu en 2013 dans l&rsquo;administration Obama pour permettre un r\u00e9chauffement d\u00e9cisif des relations des USA avec la Russie, apr\u00e8s le <em><a href=\"https:\/\/www.dedefensa.org\/article\/on-reduit-la-toile\">reset rat\u00e9<\/a> <\/em>d&rsquo;Hillary Clinton en 2009. Les Russes l&rsquo;attendaient, <a href=\"https:\/\/www.dedefensa.org\/article\/dites-a-vlad-quil-patiente\">\u00e0 la demande<\/a> d&rsquo;Obama lui-m\u00eame qui avait promis la chose. C&rsquo;est le contraire qui est venu, et notamment sinon essentiellement avec cette nomination de Nuland qui lui permit de lancer la crise ukrainienne, et cela sans que Kerry ne s&rsquo;en avise.<\/p>\n<\/p>\n<p><p>(La \u00ab\u00a0rencontre-surprise\u00a0\u00bb de Kerry \u00e0 Sotchi <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-sotchi-a-lombre-du-bataillon-immortel\">en mai 2015<\/a>, avec Poutine-Lavrov, montra bien <em>a contrario<\/em>, avec la reprise en main temporaire et trop tardive de Nuland par Kerry, combien le secr\u00e9taire d&rsquo;&Eacute;tat n&rsquo;avait rien vu de son r\u00f4le jusqu&rsquo;alors. Mais d&rsquo;ores et d\u00e9j\u00e0, tout \u00e9tait jou\u00e9 dans le sens d&rsquo;une aggravation des relations avec la Russie qui \u00e9taient devenues structurelles et ne se sont plus d\u00e9menties depuis, au contraire qui n&rsquo;ont fait que s&rsquo;aggraver. Pass\u00e9s d\u00e9sormais dans l&rsquo;opposition, les d\u00e9mocrates jouent cette carte antirusse \u00e0 fond et le Syst\u00e8me est tr\u00e8s content d&rsquo;eux&#8230; Et nous disons bien \u00ab\u00a0Syst\u00e8me\u00a0\u00bb plut\u00f4t que <em>DeepState <\/em>dont la composition et l&rsquo;\u00e9volution varient constamment, &ndash; justement en fonction de l&rsquo;alignement sur le Syst\u00e8me par rapport aux \u00ab\u00a0apparences de tendance\u00a0\u00bb des administrations .) <\/p>\n<\/p>\n<p><p>Tout cela, &ndash; ce long rappel, &ndash; est pour dire que m\u00eame si Trump \u00ab\u00a0fait le m\u00e9nage\u00a0\u00bb dans son NSC, on voit mal comment il pourrait prendre en main sa propre ligne politique apr\u00e8s l&rsquo;avoir impos\u00e9e \u00e0 sa bureaucratie, s&rsquo;il y parvient. D&rsquo;ailleurs, et pour faire court, Trump a-t-il une \u00ab\u00a0ligne politique\u00a0\u00bb \u00e0 imposer ? Cet homme est trop producteur de d\u00e9sordre, notamment dans des domaines (diplomatie, s\u00e9curit\u00e9 nationale) qui demandent une souplesse et une finesse que sa culture de brutal <em>businessman <\/em>ignore compl\u00e8tement, pour d\u00e9velopper une \u00ab\u00a0ligne coh\u00e9rente\u00a0\u00bb. De ce point de vue, nous serions tent\u00e9s de penser que \u00ab\u00a0le m\u00e9nage\u00a0\u00bb au NSC, m\u00eame s&rsquo;il r\u00e9ussit, ne changera rien fondamentalement \u00e0 la politique (non-politique, non ?) de s\u00e9curit\u00e9 nationale de Trump : le d\u00e9sordre reste le d\u00e9sordre, point final. Par contre, l&rsquo;op\u00e9ration va exacerber l&rsquo;opposition contre Trump, notamment de la CIA dont les officiers sont expuls\u00e9s du NSC, des d\u00e9mocrates par cons\u00e9quent, et la suite, toute cette clique qui juge qu&rsquo;une sorte de \u00ab\u00a0coup d&rsquo;&Eacute;tat\u00a0\u00bb contre la fonction pr\u00e9sidentielle de la part d&rsquo;un organisme de renseignement ne met danger aucun principe de la Grande R\u00e9publique, d\u00e9mocratique en plus d&rsquo;\u00eatre \u00ab\u00a0grande\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>L\u00e0 encore, comme ailleurs \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, comme hier et comme demain, encore du d\u00e9sordre, toujours du d\u00e9sordre.<\/p>\n<\/p>\n<p><p>Mis en ligne le 12 octobre 2019 \u00e0 16H24<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trump fait le m\u00e9nage Des indications pr\u00e9cises apparaissent de plus en plus sur l&rsquo;action entreprise par le pr\u00e9sident Trump dans les rangs du NSC (National Security Council), qui est ce \u00ab\u00a0gouvernement\u00a0\u00bb restreint du pr\u00e9sident, coordonnant et int\u00e9grant les diverses informations et analyses de s\u00e9curit\u00e9 nationale (notamment venues des minist\u00e8res concern\u00e9s) pour le pr\u00e9sident, pour lui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2623,11782,3104,2866,19418,855,2906,3698,5520,19362,6208,12535,3134,2639],"class_list":["post-78896","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bureaucratie","tag-c","tag-cia","tag-johnson","tag-kaidanow","tag-kerry","tag-larry","tag-nsc","tag-nuland","tag-obrien","tag-obama","tag-purge","tag-robert","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78896"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78896\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}