{"id":78899,"date":"2019-10-14T10:18:38","date_gmt":"2019-10-14T10:18:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/14\/fake-voila-maintenant-lesdeepfuck\/"},"modified":"2019-10-14T10:18:38","modified_gmt":"2019-10-14T10:18:38","slug":"fake-voila-maintenant-lesdeepfuck","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/14\/fake-voila-maintenant-lesdeepfuck\/","title":{"rendered":"<em>Fake\u00a0<\/em>! Voil\u00e0 maintenant les\u00a0<em>DeepFuck<\/em>\u00a0!"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>Fake <\/em>! Voil\u00e0 maintenant les <em>DeepFuck<\/em> !<\/h2>\n<\/p>\n<p><p>14 octobre 2019 &ndash; Hier donc, cela devait \u00eatre dans la \u00ab\u00a0tranche 13H00-14H00\u00a0\u00bb, je m&rsquo;invite sans crier gare sur la cha&icirc;ne LCI o&ugrave; l&rsquo;on bavarde sans discontinuer autour du cadavre puant de la r\u00e9alit\u00e9 du monde totalement d\u00e9sint\u00e9gr\u00e9e. On nous parlait d&rsquo;une nouvelle cat\u00e9gorie, type Formule 1, dans le circuit du <em>FakeNewsisme<\/em>, la<em>DeepFake <\/em>qui d\u00e9chire les \u00e2mes sensibles. On nous entretint donc d&rsquo;un exemple tr\u00e8s r\u00e9cent et tonitruant de la m\u00e9thode, le montage publicitaire de <em>Solidarit\u00e9-SIDA<\/em>qui fait <a href=\"https:\/\/www.lci.fr\/sante\/lutte-contre-le-sida-le-deepfake-de-donald-trump-deja-vu-3-millions-de-fois-2134311.html\">dire \u00e0 Trump<\/a>que le SIDA est vaincu, avec la voix, les mimiques, les gestes de Trump (apr\u00e8s tout, \u00ab\u00a0AIDS\u00a0\u00bb n&rsquo;est pas si loin d'\u00a0\u00bbISIS\u00a0\u00bb, alors le travail en est facilit\u00e9 avec lui qui ne cesse de r\u00e9p\u00e9ter qu&rsquo;ISIS est liquid\u00e9). On s&rsquo;exclame sur ce nouvel aspect du <em>Fake<\/em>, une sorte de <em>Fake <\/em>absolue qui fabrique du simulacre absolu de l&rsquo;image, du geste, de la parole et du contenu de la parole ; mais tout cela, hein, sur la pointe des pieds du point d&rsquo;exclamation car <em>Solidarit\u00e9-SIDA<\/em>, tout de m\u00eame, c&rsquo;est du lourd en mati\u00e8re de vertuSyst\u00e8me et il ne faudrait pas qu&rsquo;on lui fasse porter la moindre responsabilit\u00e9 de la manufacture de ce simulacre-parfait, de cette faussaire-tromperie sans retour en mati\u00e8re de communication.<\/p>\n<\/p>\n<p><p>C&rsquo;est un zombie de LCI (appelons-le Zombie-<em>DeepFuck <\/em>pour ne pas d\u00e9voiler son nom comme on d\u00e9nonce, d&rsquo;autant que je l&rsquo;ai oubli\u00e9, le nom) , un charg\u00e9 de mission aupr\u00e8s des <em>FuckNews <\/em>pour s&rsquo;en sp\u00e9cialiser, qui avait \u00e9t\u00e9 introduit dans le cercle de nos bienpensants de cette tranche horaire 13H00-14H00 de LCI pour nous entretenir de ce grave probl\u00e8me du <em>DeepFake<\/em>o&ugrave; n&rsquo;importe quoi pourra faire \u00e9crire ou dire n&rsquo;importe qui \u00e0 n&rsquo;importe comment, surtout d\u00e9shonorant ainsi un biendisant-PC, \u00ab\u00a0journaliste\u00a0\u00bb parce qu&rsquo;inscrit dans l'\u00a0\u00bbours\u00a0\u00bb de <em>Lib\u00e9 <\/em>ou du <em>Monde<\/em>. On se montra presque s\u00e9v\u00e8re pour <em>Solidarit\u00e9-SIDA<\/em>, qui ouvre la voie, &ndash; sauf que, je le r\u00e9p\u00e8te lourdement, le SIDA, les LGTBQ, les PC, toutes ces v\u00e9rit\u00e9s-l\u00e0 n&rsquo;est-ce pas, entre <em>Fake <\/em>et <em>Fuck<\/em>, &ndash; bref, ces messieurs-dames marchaient sur des &oelig;ufs&#8230; <\/p>\n<\/p>\n<p><p>L\u00e0-dessus, &ndash; je cite cela comme exemplaire des r\u00e9actions de ces susdits messieurs-dames, &ndash; un journaliste faisant partie de l&rsquo;\u00e9tat-major de commentaire des zombies du jour s&rsquo;exclame plaintivement (il avait l&rsquo;air vraiment malheureux), quelque chose du genre : \u00ab\u00a0Mais c&rsquo;est affreux, nous [les journalistes de la presseSyst\u00e8me, les types \u00e9patants] nous qui luttons pour faire conna&icirc;tre la petite parcelle de r\u00e9alit\u00e9 que nous connaissons, [nous qui sommes les derniers d\u00e9fenseurs de la r\u00e9alit\u00e9-v\u00e9rit\u00e9, qui contribuons \u00e0 sauver ce qui reste de nos belle \u00ab\u00a0valeurs\u00a0\u00bb d\u00e9mocratiques assaillies de toutes parts], avec ces proc\u00e9d\u00e9s de tromperie absolue, eh bien voil\u00e0, bient\u00f4t on ne nous croira plus comme Paroles d&rsquo;&Eacute;vangile\u00a0\u00bb. Il est aussit\u00f4t repris par Zombie-<em>DeepFuck <\/em>qui a bien travaill\u00e9 son dossier et qui nous sort la derni\u00e8re concernant le pauvre Joseph Robinette Joe Biden, &ndash;et qui annonce : \u00ab\u00a0Mais c&rsquo;est d\u00e9j\u00e0 fait, les montages politiques c&rsquo;est en marche !\u00a0\u00bb Et de nous sortir l&rsquo;affaire de Joseph Robinette <a href=\"https:\/\/www.dedefensa.org\/article\/cest-le-plus-vite-corrompu-qui-sy-met\">mena\u00e7ant Porochenko<\/a> de bloquer l&rsquo;aide US de 1 $milliard s&rsquo;il ne vire pas un certain procureur qui comme par pur hasard am\u00e9ricaniste, comprend dans son enqu\u00eate en-cours les activit\u00e9s du fiston, Hunter Biden&#8230; \u00ab\u00a0Bien s&ucirc;r, c&rsquo;est un faux, cette vid\u00e9o un montage complet comme celui-vertueux de <em>Solidarit\u00e9-SIDA<\/em>, tout le monde le sait aujourd&rsquo;hui, poursuit Zombie-<em>DeepFuck, <\/em>, mais songez \u00e0 tout ce qu&rsquo;ils peuvent faire pour nous tromper !!\u00a0\u00bb&#8230; Et tout le monde de songer.<\/p>\n<\/p>\n<p><p>La sc\u00e8ne en question (vid\u00e9o de Biden devant le <em>Council of Foreign Relations<\/em>), qui serait donc une torpille h\u00e2tivement mais parfaitement produite et r\u00e9alis\u00e9e ces derniers jours pour \u00eatre lanc\u00e9e contre Joe Robinette, a \u00e9t\u00e9 tout de m\u00eame diffus\u00e9e par <em>ZeroHedge.com <\/em><a href=\"https:\/\/www.zerohedge.com\/news\/2018-01-24\/son-bitch-got-fired-joe-biden-brags-he-forced-ukraine-fire-key-official-exchange\">le 24 janvier 2018<\/a>, ce qui rend compte d&rsquo;une sacr\u00e9e <em>vista <\/em>pour les n\u00e9cessit\u00e9s des montages et tromperies du futur. On avait <a href=\"https:\/\/www.dedefensa.org\/article\/cest-le-plus-vite-corrompu-qui-sy-met\">d\u00e9j\u00e0 publi\u00e9<\/a> l\u00e0-dessus dans ce soi-disant &lsquo;Journal&rsquo; (mon <em>FackFuck-dde.crisis<\/em>), tombant dans le traquenard-<em>DeepFuck<\/em>, ou bien alors, &ndash; n&rsquo;est-ce pas, <em>Mister <\/em>PhG ? &ndash;s&rsquo;en faisant consciemment et complotistement l&rsquo;inf\u00e2me complice, publiant un texte sur cette sombre histoire o&ugrave; le virginal Joseph Robinette serait pi\u00e9g\u00e9 par d&rsquo;immondes <em>Trump-Men<\/em>. Sur ce point, Biden a r\u00e9gl\u00e9 le probl\u00e8me : il a simplement dit que tout cela \u00e9tait faux et qu&rsquo;il interdisait aux m\u00e9dias de diffuser cette vid\u00e9o ; interdiction, comme \u00e7a, sans autre forme de proc\u00e8s au propre et au figur\u00e9, sur la seule simple parole de l&rsquo;int\u00e9ress\u00e9. LCI, soulag\u00e9, a opin\u00e9.<\/p>\n<\/p>\n<p><p> (En plus de quoi apprenons-nous que les salopards viennent de faire <a href=\"https:\/\/www.zerohedge.com\/political\/hunter-biden-emerges-quits-board-chinese-private-equity-firm\">un autre montage<\/a> contre le pauvre sacr\u00e9 vieux Joseph Robinette Joe, et fiston Hunter. Un vrai casse-t\u00eate chinois avec $millions-$milliards, montage de A \u00e0 Z, c&rsquo;est vrai \u00e0 la fin ! L&rsquo;excellent Hunter Biden s&rsquo;est \u00e9lev\u00e9 contre ce barrage de <em>FakeFuckNews <\/em>et, par pure co\u00efncidence de date, d&rsquo;innocence et de prudence, <a href=\"https:\/\/www.rt.com\/usa\/470852-hunter-biden-resigns-trump\/\">a d\u00e9missionn\u00e9<\/a> du poste qu&rsquo;il occupait, &laquo; <em>from the board of a Chinese equity company<\/em> &raquo;) <\/p>\n<\/p>\n<p><p>Une fois encore, et toujours et encore, je dois constater ma sid\u00e9ration devant celle de mes confr\u00e8res de la presseSyst\u00e8me, des \u00ab\u00a0communicants\u00a0\u00bb, des sp\u00e9cialistes de RP, leur sid\u00e9ration devant l&rsquo;\u00e9pouvantable conduite de tant de gens dans le monde, et des qui se font prendre pour des journalistes et qui n&rsquo;en sont pas, des qui ne sont pas au courant des consignes, mal align\u00e9s, etc. La presseSyst\u00e8me ne supporte pas cette sorte de d\u00e9loyale concurrence, elle honnit v\u00e9ritablement tous ceux qui n&rsquo;ont pas pignon sur rue et consignes dans la musette. A \u00e9couter ces int\u00e9ressants bavardage au Salon du Commerce, on entend leurs voix vibrer de col\u00e8re et de la plus compl\u00e8te, la plus achev\u00e9e, la plus \u00e9crasante incompr\u00e9hension fond\u00e9e sur une bonne foi et une bonne conscience \u00e0 ne pas croire&#8230; (Car je suis absolument s&ucirc;r que ces virginales vestales de la presseSyst\u00e8me &#038; Cie nagent dans leur bonne foi comme dans un marigot d&rsquo;une sinc\u00e9rit\u00e9 absolue et aussi pr\u00e9gnante qu&rsquo;un sable mouvant et humide.)<\/p>\n<\/p>\n<p><p>Car, disent-ils, \u00ab\u00a0mais nous disons la v\u00e9rit\u00e9-r\u00e9alit\u00e9, et l&rsquo;on a l&rsquo;impression d\u00e9sormais, avec ces horreurs-<em>FakeFuck <\/em>de n&rsquo;\u00eatre plus crus \u00e0 notre juste valeur\u00a0\u00bb. J&rsquo;ai senti cette panique indicible, ce path\u00e9tique d\u00e9sarroi, alors qu&rsquo;ils \u00e9coutaient Zombie-<em>DeepFuck <\/em>leur conter l&rsquo;effroyable diffamation insaisissable contre cet honn\u00eate homme de Joseph Robinette Joe Biden. Ils atteignaient le terme de leur calvaire, l\u00e0 o&ugrave; gronde l&rsquo;enfer des journalistes-Syst\u00e8me que les complotistes, les antiSyst\u00e8me, les alternatifs ont pav\u00e9 de simulacres de bonnes intentions&#8230;<\/p>\n<\/p>\n<p><p>Enfin, tr\u00eave de sarcasmes et de bons mots faciles : le fait est que tous ces braves zombies de la communicationSyst\u00e8me paraissaient litt\u00e9ralement terroris\u00e9s. Revoyant le montage Trump\/SIDA, ils s&rsquo;exclamaient que, d\u00e9sormais, on ne pourrait m\u00eame plus croire pour du comptant ce que disent les hommes politiques. (Certes, et alors ? Vous y croyez encore, vous ? Questions incongrues, passons outre.)<\/p>\n<\/p>\n<p><p>Je fais alors le constat fort s\u00e9rieux constituant la morale de cette s\u00e9quence, qu&rsquo;il est vrai que l&rsquo;affaire <em>DeepFake <\/em>introduit un \u00e9l\u00e9ment de plus dans le tourbillon crisique devenu \u00ab\u00a0Trou Noir crisique\u00a0\u00bb o&ugrave; s&rsquo;est engloutie la r\u00e9alit\u00e9 du monde. Quasiment plus rien aujourd&rsquo;hui n&rsquo;est garantie d&rsquo;authenticit\u00e9 directe et tout doit \u00eatre soumis \u00e0 enqu\u00eate, o&ugrave; l&rsquo;exp\u00e9rience (hors-Syst\u00e8me et pr\u00e9-Syst\u00e8me [ou pr\u00e9-9\/11]) et l&rsquo;intuition jouent un r\u00f4le fondamental, avec la raison comme outil \u00e9galement fondamental si elle est sous contr\u00f4le et hors de <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-crise-de-la-raison-humaine-1\">la subversion du Syst\u00e8me<\/a>. Le processus, cette \u00ab\u00a0enqu\u00eate\u00a0\u00bb pour d\u00e9jouer la facticit\u00e9 compl\u00e8te d&rsquo;un \u00ab\u00a0r\u00e9alit\u00e9\u00a0\u00bb d\u00e9sint\u00e9gr\u00e9e en autant de simulacres que n\u00e9cessaire, emplies d&rsquo;autant de <em>narrative <\/em>qu&rsquo;in\u00e9vitable, nous le connaissons depuis un certain temps : il est d\u00e9crit dans le <em>Glossaire.dde <\/em>sous l&rsquo;expression de \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>Bref, rien de nouveau pour nous, qui savons <a href=\"https:\/\/www.dedefensa.org\/article\/je-doute-donc-je-suis\">depuis si longtemps<\/a>ce qu&rsquo;il en est de la transformation de la communication par le Syst\u00e8me (communicationSyst\u00e8me), avec licence pour nous de jouer l\u00e0-dessus avec <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-technologisme-versus-communication-1\">l&rsquo;effet-<em>Janus<\/em><\/a> de la communication. Mais pour eux ! Je parle des potiches-zombies de la presseSyst\u00e8me, oblig\u00e9es de s&rsquo;encenser elles-m\u00eames, de se trouver si formidablement vertueuses et de se d\u00e9couvrir si compl\u00e8tement cocues, de se d\u00e9composer de frayeur, de geindre contre les m\u00e9chants, de pleurnicher, chialer, couiner, de pleuroter, &ndash; \u00ab\u00a0bobo maman, les m\u00e9chants antiSyst\u00e8me\u00a0\u00bb, &ndash;  puisque voil\u00e0 encore de la tromperie qui corrompt la V\u00e9rit\u00e9 dont ils sont les gardiens, et encore plus, chose symboliquement affreuse &ndash; cette terrible nouvelle apport\u00e9e par les amis si vertueux de <em>Solidarit\u00e9-SIDA<\/em> !<\/p>\n<\/p>\n<p><p>Excellente <em>FuckNews<\/em>, les amis. Ils r\u00e9alisent de plus en plus, peut-\u00eatre d\u00e9cisivement cette fois, qu&rsquo;ils sont devant un monde insaisissables, eux qui croyaient \u00e0 chaque instant saisir la v\u00e9rit\u00e9 postmoderne du monde entre leurs mains et leurs comptes en banque. Les voil\u00e0 \u00e0 la d\u00e9rive dans le torrent tumultueux du monde d\u00e9structur\u00e9 et de sa r\u00e9alit\u00e9 d\u00e9sint\u00e9gr\u00e9e. Ils n&rsquo;ont jamais appris \u00e0 naviguer dans ces eaux temp\u00e9tueuses, tandis que nous, nous ne faisons que cela, depuis des ann\u00e9es longues comme des si\u00e8cles. Nous savons depuis longtemps que, dans ce monde pulv\u00e9ris\u00e9, la v\u00e9rit\u00e9 est quelque chose qui se conquiert \u00e0 la force de l&rsquo;\u00e2me, et de l&rsquo;\u00e2me po\u00e9tique pour les plus intuitifs ; eux, ils croyaient que cela leur \u00e9tait donn\u00e9 par la force de la promotion-Syst\u00e8me obtenus par cirages de bottes labellis\u00e9s. Bon vent, mes gaillards !<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fake ! Voil\u00e0 maintenant les DeepFuck ! 14 octobre 2019 &ndash; Hier donc, cela devait \u00eatre dans la \u00ab\u00a0tranche 13H00-14H00\u00a0\u00bb, je m&rsquo;invite sans crier gare sur la cha&icirc;ne LCI o&ugrave; l&rsquo;on bavarde sans discontinuer autour du cadavre puant de la r\u00e9alit\u00e9 du monde totalement d\u00e9sint\u00e9gr\u00e9e. On nous parlait d&rsquo;une nouvelle cat\u00e9gorie, type Formule 1, dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[1235,19419,17639,18217,826,8503,4595,14515,12820,19363,19420],"class_list":["post-78899","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-biden","tag-deepfake","tag-effet-janus","tag-fakenewsisme","tag-hunter","tag-joe","tag-joseph","tag-lci","tag-pressesysteme","tag-robinette","tag-solidarite-sida"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78899"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78899\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}