{"id":78903,"date":"2019-10-16T17:08:45","date_gmt":"2019-10-16T17:08:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/16\/orfevrerie-russe\/"},"modified":"2019-10-16T17:08:45","modified_gmt":"2019-10-16T17:08:45","slug":"orfevrerie-russe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/16\/orfevrerie-russe\/","title":{"rendered":"Orf\u00e8vrerie russe"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Orf\u00e8vrerie russe<\/h2>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Les morts qu&rsquo;on ne pleure pas<\/h3>\n<\/p>\n<p><p>Une certaine presse, celle-l\u00e0 qui fabrique le plasma dans lequel nous sommes immerg\u00e9s pollu\u00e9 de travestissements de la v\u00e9rit\u00e9 tant elle nous la sert estropi\u00e9e, invalide, sans substance car elle se trouve tronqu\u00e9e de l&rsquo;essentiel qui est tu, se lamente r\u00e9cemment sur les Kurdes promis \u00e0 une mort certaine. <\/p>\n<\/p>\n<p><p>Depuis 2014, une coalition dirig\u00e9e par les Usa &lsquo;contre Daesh&rsquo; op\u00e8re en Syrie et en Irak et m\u00e8ne des attaques a\u00e9riennes sur ces deux pays. <a href=\"https:\/\/airwars.org\/conflict\/coalition-in-iraq-and-syria\/#https:\/\/airwars.org\/conflict\/coalition-in-iraq-and-syria\/\">Airwars<\/a> estime qu&rsquo;elle a tu\u00e9 entre 8 214 et 13 125 civils au cours de 2 890 incidents distincts dont environ 2000 enfants et 1300 femmes. Le porte-parole du Haut Commissariat aux R\u00e9fugi\u00e9s des Nations Unies d\u00e9clarait pour sa part en d\u00e9but d&rsquo;ann\u00e9e que les 30 000 attaques a\u00e9riennes conduites par la coalition depuis  auraient fait <a href=\"https:\/\/www.commondreams.org\/views\/2019\/02\/21\/ihchr-11800-civilians-killed-us-led-air-strikes-syria-iraq#https:\/\/www.commondreams.org\/views\/2019\/02\/21\/ihchr-11800-civilians-killed-us-led-air-strikes-syria-iraq\">11 800 morts<\/a> parmi les civils syriens et irakiens. Pour lui, ce nombre \u00e9lev\u00e9 est une violation claire des lois internationales et de la Convention de Gen\u00e8ve selon lesquelles les bellig\u00e9rants ont le devoir de prot\u00e9ger les populations civiles.<\/p>\n<\/p>\n<p><p>En avril 2017, une attaque a\u00e9rienne sur un site dens\u00e9ment peupl\u00e9 \u00e0 l&rsquo;Est de Mossoul avait tu\u00e9 pr\u00e8s de 300 personnes en une seule fois, performance la plus meurtri\u00e8re depuis la guerre du Vietnam. <\/p>\n<\/p>\n<p><p>Les \u00e9crans risquaient de d\u00e9gouliner bient\u00f4t du sang des pauvres Kurdes abattus par l&rsquo;arm\u00e9e turque auxquelles les forces \u00e9tasuniennes ont fort obligeamment c\u00e9d\u00e9 les lieux en se retirant. Un tel sc\u00e9nario a failli \u00eatre jou\u00e9 d\u00e9j\u00e0 l&rsquo;\u00e9t\u00e9 2016 et 2018, les Usa allaient c\u00e9der et les Kurdes se ranger derri\u00e8re la banni\u00e8re de l&rsquo;Etat l\u00e9gal de Syrie, Ankara n&rsquo;\u00e9tait pas pr\u00eate. Devant l&rsquo;offensive turque, les forces d\u00e9mocratiques syriennes (YPG) accul\u00e9es par une certaine passivit\u00e9 de la coalition ont quasiment \u00e9t\u00e9 incorpor\u00e9es \u00e0 celles de l&rsquo;arm\u00e9e arabe syrienne. Elles   avancent dans le Nord Est de la Syrie sans grande difficult\u00e9. Elles se d\u00e9ploient autour de Manbij, de Tabqah vers A\u00efn Issa et de Hassaka vers Qamishli sans avoir \u00e9t\u00e9 confront\u00e9es \u00e0 l&rsquo;arm\u00e9e turque. Ce p\u00e9rim\u00e8tre dessine \u00e0 peu pr\u00e8s le contour du sandjak de Deir Zour pendant l&rsquo;Empire ottoman et s&rsquo;\u00e9tend tr\u00e8s largement au del\u00e0 des minces bandes de peuplement traditionnel kurde limitrophes de la Turquie actuelle. Cette aisance implique l&rsquo;existence d&rsquo;accords pr\u00e9alables sans doute n\u00e9goci\u00e9s sous l&rsquo;\u00e9gide \u00e0 la fois de la Russie et de l&rsquo;Iran.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">La diplomatie russe et l&rsquo;ambivalence turque<\/h3>\n<\/p>\n<p><p>La Turquie et la Russie ont mis en place \u00e0 la veille de cette recomposition au Nord de la Syrie un <a href=\"https:\/\/www.rt.com\/business\/470452-russia-turkey-national-currencies\/#https:\/\/www.rt.com\/business\/470452-russia-turkey-national-currencies\/\">protocole<\/a> qui va permettre le remplacement progressif des \u00e9changes commerciaux entre les deux pays par leurs monnaies nationales respectives.  Cette volont\u00e9 commune de s&rsquo;affranchir du dollar, exprim\u00e9e depuis quelque temps par les deux partenaires, est en train de se concr\u00e9tiser. Les ordres interbancaires vont emprunter un circuit qui shunte le Swift \u00e9tasunien et il sera fait usage de cartes de paiement de conception russe (MIR) \u00e9vitant Visa et Mastercard. La sanction proclam\u00e9e par Trump d&rsquo;augmenter les taxes douani\u00e8res sur les importations d&rsquo;acier turc vont le rench\u00e9rir et impacter d\u00e9favorablement le consommateur \u00e9tasunien avant d&rsquo;avoir un effet improbable sur la relance de la production locale \u00e9tasunienne. Les haut-fourneaux ne red\u00e9marrent pas aussi vite qu&rsquo;une \u00e9criture de quelques signes composant un tweet. Or l&rsquo;\u00e9conomie \u00e9tasunienne repose sur la consommation elle-m\u00eame \u00e9tay\u00e9e par le syst\u00e8me de la dette priv\u00e9e.  Compromettre un \u00e9quilibre d\u00e9j\u00e0 p\u00e9rilleux, ces derniers trimestres sont marqu\u00e9s par une baisse de cr\u00e9ation d&#8217;emplois tr\u00e8s nette, comporte des risques pour l&rsquo;actuel POTUS en p\u00e9riode pr\u00e9-\u00e9lectorale.   <\/p>\n<\/p>\n<p><p>L&rsquo;offensive contr\u00f4l\u00e9e en territoire syrien de l&rsquo;arm\u00e9e turque cherche \u00e0 \u00e9radiquer les liens du PKK avec le PYD (parti de l&rsquo;union d\u00e9mocratique, \u00e9manation politique du mouvement autonomiste kurde syrien) et emp\u00eacher la formation d&rsquo;une entit\u00e9 politique kurde souveraine sur son flanc Sud. Elle a aussi l&rsquo;ambition de ranimer un patriotisme panturc autour de l&rsquo;AKP boud\u00e9 lors des derniers \u00e9lections l\u00e9gislatives et communales en raison du marasme \u00e9conomique et de pratiques douteuses et corrompues de l&rsquo;entourage du pouvoir. La blessure jamais cicatris\u00e9e de la perte de l&#8217;empire ottoman trouve dans cette communion de quoi \u00eatre pans\u00e9e.<\/p>\n<\/p>\n<p><p>Toujours membre de l&rsquo;OTAN et continuant d&rsquo;abriter la base \u00e9tasunienne d&rsquo;Incirlik et ses bombes nucl\u00e9aires, la Turquie b\u00e9n\u00e9ficie encore \u00e0 ce titre de son assistance militaire. Lors de la visite \u00e0 Ankara de son secr\u00e9taire g\u00e9n\u00e9ral Jens Stoltenberg deux jours avant le d\u00e9but de l&rsquo;invasion en Syrie, les d\u00e9penses de plus de 5 milliards de dollars en bases et infrastructures n&rsquo;ont pas \u00e9t\u00e9 remises en cause. Le syst\u00e8me de d\u00e9fense a\u00e9rienne Samp-T co-production fran\u00e7aise et italienne est <a href=\"http:\/\/www.wikistrike.com\/2019\/10\/deux-jour-avant-le-debut-de-l-invasion-le-secretaire-general-de-l-otan-est-venu-en-personne-a-ankara-pour-donner-le-feu-vert-a-erdog#http:\/\/www.wikistrike.com\/2019\/10\/deux-jour-avant-le-debut-de-l-invasion-le-sec\">toujours d\u00e9ploy\u00e9<\/a> pour d\u00e9fendre (contr\u00f4ler ?) la fronti\u00e8re m\u00e9ridionale turque.<\/p>\n<\/p>\n<p><p>A l&rsquo;\u00e9poque du d\u00e9mant\u00e8lement du Grand Homme malade de l&rsquo;Europe, la Turquie k\u00e9maliste ramassait ses d\u00e9bris et tout en acceptant les millions de roubles de l&rsquo;URSS nouvellement cr\u00e9\u00e9e menait d\u00e9j\u00e0 activement des tractations avec le Foreign Office. Erdogan joue encore des m\u00eames ambigu\u00eft\u00e9s.  <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Le Sandjak de Deir Zour<\/h3>\n<\/p>\n<p><p>Le Moyen Orient continue de payer pour l&rsquo;ordre \u00e9tabli au sortir de la premi\u00e8re guerre mondiale, issu de la concertation entre les deux puissances europ\u00e9ennes alli\u00e9es, la France et le Royaume Uni. La cr\u00e9ation d&rsquo;Etats centralis\u00e9s sur le mod\u00e8le des &lsquo;nations europ\u00e9ennes&rsquo; construites au travers de guerres incessantes intra-europ\u00e9ennes au fil des si\u00e8cles de l&rsquo;\u00e9mergence du capitalisme marchand puis industriel a rompu l&rsquo;harmonie relative pr\u00e9alable. Les provinces ottomanes moyennant quelque tribut \u00e0 la Porte jouissaient d&rsquo;une relative autonomie administrative. L&rsquo;ethnicisation de la lutte politique est une question r\u00e9cente, actualis\u00e9e par les puissances occidentales.<\/p>\n<\/p>\n<p><p>Il suffit de se r\u00e9f\u00e9rer \u00e0 la mani\u00e8re qu&rsquo;a eue la puissance mandataire en Syrie de traiter la haute Djazira, cette r\u00e9gion syrienne entre Hassakah et Ain Al Arab qui s&rsquo;enfonce en bec de canard dans la r\u00e9gion frontali\u00e8re entre l&rsquo;Irak et la Turquie. Pour &lsquo;stabiliser&rsquo; la zone des ambitions turques, la France qui avait d\u00e9j\u00e0 c\u00e9d\u00e9 la Cilicie et Mardin entreprend de modifier la d\u00e9mographie et l&rsquo;\u00e9conomie de la r\u00e9gion.<\/p>\n<\/p>\n<p><p>Elle accueille des Kurdes de Turquie surtout apr\u00e8s l&rsquo;effondrement de la r\u00e9volte kurde de 1925, encourage l&rsquo;installation de chr\u00e9tiens, Assyriens d&rsquo;Irak, Syriaques et Arm\u00e9niens de Turquie. Le Haut-Commissariat favorise la s\u00e9dentarisation d&rsquo;une r\u00e9gion essentiellement zone de nomadisme pour des tribus arabes et kurdes \u00e9leveurs de moutons. Il a initi\u00e9 les \u00e9lites urbaines qu&rsquo;il a forg\u00e9es en distribuant terres, mandats l\u00e9gislatifs et autres pr\u00e9bendes \u00e0 des revendications d&rsquo;autonomie selon des bases religieuses ou ethniques. Il a pratiqu\u00e9 comme ailleurs au Maghreb le dialogue direct avec les chefs de tribus en les \u00e9levant au rang de collaborateurs redevables de quelques privil\u00e8ges. Le principe de la pulv\u00e9risation de grands ensembles en confettis de principaut\u00e9s autonomes et sans souverainet\u00e9 de fait car toujours d\u00e9pendantes d&rsquo;une puissance externe qui entretient leur division a \u00e9t\u00e9 appliqu\u00e9 plus que de raison dans l&rsquo;Orient arabe. Il \u00e9tait de plus hautement morcelable car fait d&rsquo;une mosa\u00efque d&rsquo;ethnies et de confessions. Ici n&rsquo;a pas \u00e9t\u00e9 appliqu\u00e9 le &lsquo;cujus regio ejus religio&rsquo; qui a an\u00e9anti les chr\u00e9tiens ariens n\u00e9gateurs de la consubstantialit\u00e9 du P\u00e8re et du Fils, les cathares, les albigeois puis les protestants sous le glaive du Prince unificateur des langues et des croyances. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Mosa\u00efque plut\u00f4t que l&rsquo;uniformit\u00e9 monochrome<\/h3>\n<\/p>\n<p><p> Si cette op\u00e9ration de l&rsquo;arm\u00e9e arabe syrienne r\u00e9ussissait d\u00e9finitivement, un foyer de tension entre Syriens et Turcs se r\u00e9sorberait. L&rsquo;avenir des Kurdes habitant la r\u00e9gion devra reposer sur une solution politique de type f\u00e9d\u00e9raliste comme pourrait l&rsquo;\u00eatre la solution \u00e9bauch\u00e9e en Irak. Les Kurdes de Syrie sont loin d&rsquo;\u00eatre homog\u00e8nes et pr\u00e9sentent une grande diversit\u00e9. Certains y r\u00e9sident de longue date, ce sont les groupes s\u00e9dentaires Hassenan et Miran qui ont toujours \u00e9t\u00e9 le moins sensibles au sentiment s\u00e9cessionniste, comme les tribus nomades des Milli, Dakkouri\u00e9 et des Heverkan. D&rsquo;autres sont de nouveaux venus install\u00e9s par vagues successives et provenant de la Turquie ou de l&rsquo;Irak, leur arriv\u00e9e fut facilit\u00e9e par la France puis plus tard par un Hafez Assad soucieux de se pr\u00e9munir d&rsquo;une alliance contre ses deux voisins. Si tous parlent le kurmanji, dialecte le plus r\u00e9pandu (70% des Kurdes), certains l&rsquo;\u00e9crivent avec l&rsquo;alphabet latin, d&rsquo;autres avec l&rsquo;arabo-persan. Si la majorit\u00e9 des deux millions de Kurdes syriens sont musulmans sunnites, il en est des minoritaires chr\u00e9tiens, shiites et y\u00e9z\u00e9dis. <\/p>\n<\/p>\n<p><p>Le gouvernement de Damas saura-t-il faire preuve d&rsquo;originalit\u00e9 constitutionnelle et admettre comme l&rsquo;a fait la Bolivie \u00eatre un Etat de plusieurs peuples ?<\/p>\n<\/p>\n<p><p>De toute \u00e9vidence, cette s\u00e9quence historique souligne de nouveau que les affaires du monde \u00e9chappent de plus en plus \u00e0 l&rsquo;h\u00e9g\u00e9monie occidentale. Elle a s&ucirc;rement \u00e9t\u00e9 pr\u00e9par\u00e9e de longue date.<\/p>\n<\/p>\n<p><p>Le r\u00f4le que se pr\u00e9pare \u00e0 jouer la diplomatie fran\u00e7aise consiste \u00e0 <a href=\"https:\/\/www.lexpress.fr\/actualite\/monde\/jean-yves-le-drian-va-se-rendre-en-irak-pour-discuter-des-djihadistes-etrangers-en-syrie_2103544.html#https:\/\/www.lexpress.fr\/actualite\/monde\/jean-yves-le-drian-va-se-rendre-en-irak-pour-discuter-des-djihad\">assurer le m\u00e9nage<\/a> dans les rangs des djihadistes mercenaires av\u00e9r\u00e9s de la coalition \u00e9tasunienne, une basse besogne de nettoyage en somme.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orf\u00e8vrerie russe Les morts qu&rsquo;on ne pleure pas Une certaine presse, celle-l\u00e0 qui fabrique le plasma dans lequel nous sommes immerg\u00e9s pollu\u00e9 de travestissements de la v\u00e9rit\u00e9 tant elle nous la sert estropi\u00e9e, invalide, sans substance car elle se trouve tronqu\u00e9e de l&rsquo;essentiel qui est tu, se lamente r\u00e9cemment sur les Kurdes promis \u00e0 une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[3953,4447,2730,3867],"class_list":["post-78903","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-badia-benjelloun-1","tag-benjelloun","tag-kurdes","tag-russie","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78903"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78903\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}