{"id":78930,"date":"2019-10-31T15:01:26","date_gmt":"2019-10-31T15:01:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/31\/nordstream-2-pour-quelques-kilometres\/"},"modified":"2019-10-31T15:01:26","modified_gmt":"2019-10-31T15:01:26","slug":"nordstream-2-pour-quelques-kilometres","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/10\/31\/nordstream-2-pour-quelques-kilometres\/","title":{"rendered":"<em>NordStream-2<\/em>, pour quelques kilom\u00e8tres&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\"><em>NordStream-2<\/em>, pour quelques kilom\u00e8tres&#8230;<\/h2>\n<\/p>\n<p><p>Les Danois ont finalement donn\u00e9 leur accord pour que le gazoduc  <em>NordStream-2 <\/em>passe dans leurs eaux et ach\u00e8ve sa mise en place, de la Russie \u00e0 l&rsquo;Allemagne. Les Danois ont finalement r\u00e9sist\u00e9 aux tr\u00e8s fortes pressions des USA, qui leur demandaient de sortir n&rsquo;importe quel argument environnemental pour interdire le passage de la chose dans leurs eaux dont la puret\u00e9 est bien connue ; certains jugeront, avec quelque raison, qu&rsquo;il s&rsquo;agit d&rsquo;un acte de courage de la part du Danemark&#8230;<\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.lemonde.fr\/economie\/article\/2019\/10\/30\/nord-stream-2-le-danemark-autorise-la-construction-du-gazoduc-qui-doit-relier-l-allemagne-et-la-russie_6017464_3234.html\">Dit autrement<\/a> et avec quelques d\u00e9tails des meilleures sources, loin des suppositions aventureuses : &laquo; <em>Le Danemark a autoris\u00e9 mercredi 30 octobre la construction du gazoduc Nord Stream 2, \u00f4tant le dernier obstacle \u00e0 la finalisation de cet ouvrage controvers\u00e9 qui doit approvisionner l&rsquo;Europe en gaz russe via la Baltique. D\u00e9j\u00e0 construit \u00e0 plus de 80 %, le gazoduc Nord Stream 2, un investissement d&rsquo;une dizaine de milliards d&rsquo;euros financ\u00e9 pour moiti\u00e9 par le g\u00e9ant russe Gazprom, doit permettre le doublement des livraisons de gaz russe \u00e0 l&rsquo;Allemagne<\/em>.<\/p>\n<p>&raquo; <em>Sa construction  <a href=\"https:\/\/www.lemonde.fr\/international\/article\/2019\/01\/03\/le-danemark-fait-de-la-resistance-face-a-nord-stream-2_5404690_3210.html\">\u00e9tait jusqu&rsquo;\u00e0 pr\u00e9sent bloqu\u00e9e<\/a><\/em>  <em>par l&rsquo;absence de permis d\u00e9livr\u00e9 par le Danemark pour traverser ses eaux territoriales. Le projet initial de construction pr\u00e9voyait en effet de passer au large de l&rsquo;&icirc;le de Bornholm, tout comme le gazoduc Nord Stream 1, op\u00e9rationnel depuis 2012. Plusieurs trac\u00e9s avaient \u00e9t\u00e9 propos\u00e9s, et refus\u00e9s, mais la route du sud-est qui a finalement \u00e9t\u00e9 retenue \u00ab\u00a0pr\u00e9sente le moins de risques et d&rsquo;impacts du point de vue de l&rsquo;environnement et de la s\u00e9curit\u00e9\u00a0\u00bb, a indiqu\u00e9 l&rsquo;agence danoise de l&rsquo;\u00e9nergie dans un communiqu\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Tom Luongo, un chroniqueur dissident US de tendance libertarienne et d&rsquo;esprit ind\u00e9pendant consacre  <a href=\"https:\/\/tomluongo.me\/2019\/10\/30\/trump-loses-more-than-just-the-battle-over-nordstream-2\/\">une analyse<\/a> \u00e0 cet \u00e9v\u00e9nement qui compl\u00e8te une saga d&rsquo;affrontement entre la Russie d&rsquo;une part avec les encouragements chuchot\u00e9s de certains europ\u00e9ens, les USA de l&rsquo;autre, avec plus ou moins de partenaires du  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a> selon les occasions. Pour Loango, c&rsquo;est une grande victoire pour l&rsquo;Allemagne, c&rsquo;est m\u00eame une sorte de \u00ab\u00a0lib\u00e9ration\u00a0\u00bb, &ndash; comme symboliquement la fin d&rsquo;une \u00ab\u00a0occupation\u00a0\u00bb par moyens diff\u00e9rents interpos\u00e9s, ou plus justement dit selon nous tout en adoptant ce point de vue, le \u00ab\u00a0d\u00e9but de la fin \u00e9ventuelle\u00a0\u00bb d&rsquo;une \u00ab\u00a0occupation\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&laquo; <em>En un sens, ce gazoduc est la d\u00e9claration d&rsquo;ind\u00e9pendance de l&rsquo;Allemagne par rapport \u00e0 plus de soixante-dix ans de politique am\u00e9ricaine. N&rsquo;oubliez jamais que l&rsquo;Allemagne est un territoire occup\u00e9 avec plus de 50 000 soldats am\u00e9ricains stationn\u00e9s l\u00e0-bas<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;id\u00e9e d\u00e9velopp\u00e9e ici est que cette \u00ab\u00a0occupation\u00a0\u00bb militaire aurait continu\u00e9 de peser de tout son poids si la d\u00e9pendance \u00e9nerg\u00e9tique s&rsquo;y \u00e9tait ajout\u00e9e dans l&rsquo;hypoth\u00e8se d&rsquo;un \u00e9chec de  <em>NordStream-2<\/em>, \u00e0 un moment o&ugrave; les Allemands croient  <a href=\"https:\/\/www.dedefensa.org\/article\/drole-de-guerre-a-lallemande\">de moins en moins<\/a> \u00e0 la r\u00e9alit\u00e9 de la protection militaire des USA. <\/p>\n<\/p>\n<p><p>&laquo; <em>Le stratag\u00e8me consistait \u00e0 arr\u00eater Nordstream 2, puis \u00e0 poursuivre en justice Gazprom pour ne pas avoir respect\u00e9 les volumes qu&rsquo;elle avait promis de livrer. Pendant des ann\u00e9es, l&rsquo;entreprise aurait d&ucirc; faire face \u00e0 des proc\u00e8s divers et vari\u00e9s au sein de l&rsquo;UE tandis que les &Eacute;tats-Unis seraient intervenus<\/em>[avec leur gaz] <em>comme le chevalier blanc, pour emp\u00eacher les Europ\u00e9ens de geler jusqu&rsquo;\u00e0 la mort.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Heureusement pour le monde, ce plan a \u00e9chou\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&#8230; Et, selon, Luongo, les forces militaires d\u00e9ploy\u00e9es en Allemagne n&rsquo;ont plus gu\u00e8re de poids sur la direction politique allemande, sans le levier de l&rsquo;alimentation \u00e9nerg\u00e9tique, ou plus cr&ucirc;ment dit le \u00ab\u00a0chantage \u00e9nerg\u00e9tique\u00a0\u00bb. Il est par cons\u00e9quent tr\u00e8s possible qu&rsquo;on voit se renforcer le courant d\u00e9j\u00e0 tr\u00e8s fort acc\u00e9l\u00e9r\u00e9 sous la pr\u00e9sidence Trump de privil\u00e9gier pour la Pologne l&rsquo;engagement US en Europe, \u00e9ventuellement au d\u00e9triment de l&rsquo;Allemagne avec  <a href=\"https:\/\/www.dedefensa.org\/article\/trump-remplacera-t-il-lallemagne-par-la-pologne\">des transferts de force<\/a> comme la menace en a d\u00e9j\u00e0 \u00e9t\u00e9 \u00e9voqu\u00e9e, puisqu&rsquo;effectivement la Pologne est le principal acolyte des USA dans ce jeu&#8230; Voici le d\u00e9but de l&rsquo;analyse de Luongo, centr\u00e9 sur l&rsquo;Allemagne.<\/p>\n<\/p>\n<p><p> &laquo; <em>Au cours des trois derni\u00e8res ann\u00e9es et jusqu&rsquo;aux derniers kilom\u00e8tres, les &Eacute;tats-Unis se sont oppos\u00e9s \u00e0 la construction du gazoduc Nordstream 2 de la Russie \u00e0 l&rsquo;Allemagne<\/em>.<\/p>\n<p>&raquo; <em>Effectivement, la bataille s&rsquo;est d\u00e9roul\u00e9e jusqu&rsquo;aux derniers kilom\u00e8tres, puisque le Danemark a refus\u00e9 pendant des mois le permis environnemental final sur Nordstream 2<\/em>.<\/p>\n<p>&raquo; <em>Les &Eacute;tats-Unis, en particulier sous l&rsquo;\u00e9gide de Trump, s&rsquo;\u00e9taient engag\u00e9s \u00e0 adopter une \u00ab\u00a0approche <a href=\"https:\/\/tomluongo.me\/2018\/06\/04\/nordstream-2-reveals-us-weakness\/\">pangouvernementale<\/a>\u00a0\u00bb pour emp\u00eacher que le gazoduc ne touche terre en Allemagne<\/em>.<\/p>\n<p>&raquo; <em>J&rsquo;ai document\u00e9 tous les rebondissements de Nordstream 2 au cours des derni\u00e8res ann\u00e9es (<a href=\"https:\/\/tomluongo.me\/?s=nordstream+2\">voyez mes archives<\/a>), aussi bien sur ce site que sur Seeking Alpha et dans la collection de mon ancienne Newsletter sur Newsmax<\/em>. <\/p>\n<p>&raquo; <em>Jamais je n&rsquo;ai pens\u00e9 qu&rsquo;arriverait un jour o&ugrave; les &Eacute;tats-Unis finiraient par bloquer ce projet. La raison en est simple. L&rsquo;Europe, et en particulier l&rsquo;Allemagne, a besoin du gaz et il n&rsquo;y a aucune raison imp\u00e9rieuse pour que l&rsquo;Allemagne en soit arriv\u00e9 \u00e0 c\u00e9der si elle veut survivre au XXIe si\u00e8cle comme une des grandes \u00e9conomies du monde<\/em>.<\/p>\n<p>&raquo; <em>Le gazoduc russe est tout simplement trop bon march\u00e9 pour qu&rsquo;un autre GNL puisse rivaliser avec le projet russe<\/em>. <\/p>\n<p>&raquo; <em>En un sens, ce gazoduc est la d\u00e9claration d&rsquo;ind\u00e9pendance de l&rsquo;Allemagne par rapport \u00e0 plus de soixante-dix ans de politique am\u00e9ricaine. N&rsquo;oubliez jamais que l&rsquo;Allemagne est un territoire occup\u00e9 avec plus de 50 000 soldats am\u00e9ricains stationn\u00e9s l\u00e0-bas<\/em>.<\/p>\n<p>&raquo; <em>Il \u00e9tait extr\u00eamement audacieux de la part du pr\u00e9sident Trump de d\u00e9crire Nordstream 2 comme l&rsquo;acceptation par l&rsquo;Allemagne de devenir une \u00ab\u00a0otage de la Russie\u00a0\u00bb quand l&rsquo;Allemagne a \u00e9t\u00e9 otage des &Eacute;tats-Unis depuis 1945<\/em>.<\/p>\n<p>&raquo; <em>L&rsquo;histoire n&rsquo;est pas le fort de Trump<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Luongo, qui a suivi avec attentions cette affaire comme il le rappelle lui-m\u00eame, juge qu&rsquo;il y eut essentiellement un seul alli\u00e9 v\u00e9ritablement actif et efficace pour les USA dans cette bataille, et qu&rsquo;il s&rsquo;agit effectivement de la Pologne qui a, elle, choisi d&rsquo;acheter du gaz US et non russe. L&rsquo;hostilit\u00e9 visc\u00e9rale, historique et strat\u00e9gique de la Russie dans le chef des Polonais, s&rsquo;accompagne dans ce cas d&rsquo;une hostilit\u00e9 polonaise \u00e0 l&rsquo;Allemagne plut\u00f4t du fait des conceptions compl\u00e8tement divergentes entre ces deux pays au sein de l&rsquo;UE, &ndash; l&rsquo;euroscepticisme polonais qui voit l&rsquo;UE comme une machine \u00e0 d\u00e9vorer sa souverainet\u00e9, contre la puissante position de l&rsquo;Allemagne au sein, sinon au faite de l&rsquo;UE&#8230;<\/p>\n<\/p>\n<p><p>Comme on le voit dans ce cas, on se trouve dans les contradictions qu&rsquo;impliquent les  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a> strat\u00e9giques aussi bien que le combat de l&rsquo;antiSyst\u00e8me contre le Syst\u00e8me&#8230; Comme on le voit, d&rsquo;ailleurs, essentiellement dans le cas germano-polonais, o&ugrave; tout le monde perd et tout le monde gagne \u00e0 la fois ; c&rsquo;est-\u00e0-dire, o&ugrave; cette affaire (r\u00e9ussite de  <em>NordStream-2<\/em>) ne peut \u00eatre consid\u00e9r\u00e9e que comme une \u00e9tape dans un affrontement bien plus vaste (alors que la r\u00e9ussite des USA de contrecarrer le projet aurait par contre constitu\u00e9 une victoire du Syst\u00e8me). Effectivement, les mouvements autour de la Pologne compl\u00e8tent fort bien les enseignements des mouvements autour de l&rsquo;Allemagne :<\/p>\n<p>&bull; on doit consid\u00e9rer que l&rsquo;ach\u00e8vement de  <em>NordStream-2 <\/em>constitue une d\u00e9faite pour l&rsquo;implantation et l&rsquo;influence des USA en Europe, &ndash; une d\u00e9faite \u00ab\u00a0objective\u00a0\u00bb politique et culturelle, et donc d\u00e9structurante comme l&rsquo;est le syst\u00e8me de l&rsquo;am\u00e9ricanisme de notre point de vue ontologique quelles qu&rsquo;aient \u00e9t\u00e9 les pr\u00e9occupation de Trump, qui \u00e9taient \u00e9videmment, essentiellement \u00e9conomiques, la question de l&rsquo;ontologie, comme celle de l&rsquo;histoire, \u00e9tant de peu d&rsquo;int\u00e9r\u00eat pour lui ;<\/p>\n<p>&bull; m\u00eame si elle constitue un soutien absurde du point de vue souverainiste et de l'\u00a0\u00bbantimodernit\u00e9\u00a0\u00bb du fait de la tradition, c&rsquo;est-\u00e0-dire du point de vue antimoderniste culturel (ce sont des positions qu&rsquo;on peut distinguer chez les populistes polonais au pouvoir) lorsqu&rsquo;on voit comment les USA traitent la souverainet\u00e9 et les cultures des autres, m\u00eame de la part du pseudo-\u00ab\u00a0populiste\u00a0\u00bb (?) Trump, la position de la Pologne est compr\u00e9hensible dans le chef de son hostilit\u00e9 \u00e0 l&rsquo;UE comme machine \u00e0 broyer la souverainet\u00e9 et les traditions soutenant l&rsquo;antimodernisme culturel ;<\/p>\n<p>&bull; de ce point de vue (souverainisme et antimodernisme), la proximit\u00e9 entre la Russie et l&rsquo;Allemagne dans cette affaire, de m\u00eame que l&rsquo;hostilit\u00e9 de la Pologne \u00e0 l&rsquo;encontre de la Russie, si elles se comprennent strat\u00e9giquement et autres dans les concepts politiques relatifs, sont compl\u00e8tement invertis d&rsquo;un point de vue ontologique, puisque la Russie est manifestement une force de tendance souverainiste et culturellement antimoderne ;  <\/p>\n<p>&bull; par cons\u00e9quent, on peut effectivement parler dans la probable conclusion de la saga  <em>NordStream-2  <\/em>d&rsquo;une \u00e9tape dans la Grande Crise G\u00e9n\u00e9rale, avec les entrechocs et entrelacs habituels des contradictions, des positions \u00e0 contrepieds, des inversions, d&rsquo;une d\u00e9structuration suppl\u00e9mentaire de l&rsquo;Europe-UE (excellente chose), etc. Pour nous, bien entendu et comme nous le r\u00e9p\u00e9tons souvent, plus aucune des mati\u00e8res habituelles des grandes donn\u00e9es pseudo-scientifiques habituelles ne r\u00e8gle rien de la situation crisique g\u00e9n\u00e9rale : ni la g\u00e9ostrat\u00e9gie de la puissance d&rsquo;influence et d&rsquo;h\u00e9g\u00e9monie, ni la g\u00e9opolitique de la puissance \u00e9nerg\u00e9tique, etc. Tous ces facteurs, consid\u00e9r\u00e9s en g\u00e9n\u00e9ral comme essentiels et strat\u00e9giques, ne sont consid\u00e9r\u00e9s, selon notre point de vue, que comme tactique et rien d&rsquo;autre. <\/p>\n<\/p>\n<blockquote>\n<p><p>Le seul int\u00e9r\u00eat, le seul avantage de l&rsquo;issue qu&rsquo;on observe est l&rsquo;absence de \u00ab\u00a0victoire\u00a0\u00bb des forces \u00e9conomiques et d&rsquo;influence du syst\u00e8me de l&rsquo;am\u00e9ricanisme, avec comme cons\u00e9quence l&rsquo;approfondissement du foss\u00e9 s\u00e9parant les USA de l&rsquo;Europe\/UE (c&rsquo;est-\u00e0-dire un foss\u00e9 \u00e0 l&rsquo;int\u00e9rieur du bloc-BAO). Il s&rsquo;agit l\u00e0 d&rsquo;un facteur int\u00e9ressant de l&rsquo;accroissement du d\u00e9sordre et de la confusion \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 31 octobre 2019 \u00e0 15H05<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NordStream-2, pour quelques kilom\u00e8tres&#8230; Les Danois ont finalement donn\u00e9 leur accord pour que le gazoduc NordStream-2 passe dans leurs eaux et ach\u00e8ve sa mise en place, de la Russie \u00e0 l&rsquo;Allemagne. Les Danois ont finalement r\u00e9sist\u00e9 aux tr\u00e8s fortes pressions des USA, qui leur demandaient de sortir n&rsquo;importe quel argument environnemental pour interdire le passage&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2748,19456,3843,2631,4522,16682,5009,5649,2827,2730,5439],"class_list":["post-78930","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-allemagne","tag-bornholm","tag-danemark","tag-de","tag-energie","tag-gazoduc","tag-ile","tag-luongo","tag-pologne","tag-russie","tag-tom"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78930"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78930\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}