{"id":78968,"date":"2019-11-23T11:48:52","date_gmt":"2019-11-23T11:48:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/11\/23\/trump-a-la-baston\/"},"modified":"2019-11-23T11:48:52","modified_gmt":"2019-11-23T11:48:52","slug":"trump-a-la-baston","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/11\/23\/trump-a-la-baston\/","title":{"rendered":"Trump \u00e0 la baston"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Trump \u00e0 la baston<\/h2>\n<\/p>\n<p><p>Alors que le processus de l&rsquo;instruction de la mise en accusation par la commission judiciaire de la Chambre est en pleine vitesse (deux semaines d&rsquo;audition) et approche de son terme, alors que nous subissons de plein fouet ce ph\u00e9nom\u00e8ne dans la situation d\u00e9sormais connue et <a href=\"https:\/\/www.dedefensa.org\/article\/solitude-cognitive-du-citoyen\">bien identifi\u00e9e<\/a>de la &laquo; <em>Solitude cognitive du citoyen<\/em> &raquo;, &ndash; c&rsquo;est-\u00e0-dire \u00e0 peu pr\u00e8s tous et nous-m\u00eames, notamment \u00e0 <em>dedefensa.org<\/em>, n&rsquo;y comprenant rien pr\u00e9cis\u00e9ment et d&rsquo;une fa\u00e7on objective sur la raisin d&rsquo;\u00eatre et l&rsquo;orientation de ce processus&#8230; Raison de plus, bien entendu, pour expliquer \u00e0 nos lecteurs, et sur un ton assur\u00e9 qui implique que personne ne pourra nous imposer la moindre r\u00e9alit\u00e9 imp\u00e9rative que de toutes les fa\u00e7ons plus personne ne parvient \u00e0 saisir, ce qu&rsquo;il pourrait bien et probablement se passer derri\u00e8re notre compl\u00e8te incompr\u00e9hension. Tout cela constitue apr\u00e8s tout le <em>modus operandi <\/em>standard de l&rsquo;aventure in\u00e9dite du commentaire politique de cette \u00e9trange \u00e9poque.<\/p>\n<\/p>\n<p><p>Trump, au contraire, s&rsquo;il se fiche bien de comprendre quelque chose, disons des faits et de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>, comprend parfaitement ce qu&rsquo;il a d\u00e9cid\u00e9 de faire. Il montre d\u00e9sormais une volont\u00e9 affich\u00e9e et proclam\u00e9e d&rsquo;en d\u00e9coudre au cours du proc\u00e8s devant le S\u00e9nat qui pourrait avoir lieu si la mise en accusation \u00e9tait vot\u00e9e comme cela semble probable. En effet, il proclame bien haut qu&rsquo;il est n\u00e9cessaire qu&rsquo;il y ait un proc\u00e8s sur sa destitution, et avec le S\u00e9nat pour juge, \u00e0 partir de la probable mise en accusation de la Chambre. Si donc, comme dit plus haut, il n&rsquo;est pas assur\u00e9 qu&rsquo;il en comprenne plus que nous sur l&rsquo;instruction et l&rsquo;orientation de l&rsquo;enqu\u00eate, son id\u00e9e est tr\u00e8s fortement affirm\u00e9e : la baston.<\/p>\n<\/p>\n<p><p>Dans une interview t\u00e9l\u00e9phonique \u00e0 Fox News, Trump a affirm\u00e9 qu&rsquo;il pr\u00e9f\u00e9rait un proc\u00e8s \u00e0 un rejet pur et simple de la mise en accusation qui peut \u00eatre vot\u00e9 \u00e0 la volont\u00e9 de la majorit\u00e9 r\u00e9publicaine du S\u00e9nat, coupant court \u00e0 toute autre proc\u00e9dure. Trump <a href=\"https:\/\/www.rt.com\/usa\/474106-trump-senate-impeachment-trial\/\">dit au contraire<\/a>qu&rsquo;il veut un proc\u00e8s au cours duquel il entend bien que d&rsquo;importants t\u00e9moignages pol\u00e9miques de diff\u00e9rents acteurs de la mise en accusation soient r\u00e9alis\u00e9es pour mettre den lumi\u00e8re les v\u00e9ritables raisons et objectifs de ce processus. <\/p>\n<\/p>\n<p><p>(Il n&rsquo;est m\u00eame pas exclu qu&rsquo;il ne r\u00e9clame pas de g\u00e9moigner lui-m\u00eame lors du proc\u00e8s qu&rsquo;il appelle de ses voeux. A notre sens, cela lui correspondrait tellement bien : la baston devant les cent s\u00e9nateurs et les USA fascin\u00e9s, lui-m\u00eame au centre d&rsquo;un \u00e9v\u00e9nement sans pr\u00e9c\u00e9dent, lui-m\u00eame devenant \u00e9v\u00e9nement sans pr\u00e9c\u00e9dent. Narcisse ne pourrait r\u00eaver mieux.)<\/p>\n<\/p>\n<p><p>&laquo; <em>\u00ab\u00a0Je veux un proc\u00e8s\u00a0\u00bb, a dit le pr\u00e9sident. \u00ab\u00a0Je veux entendre Adam Schiff t\u00e9moigner au sujet du lanceur d&rsquo;alerte, &ndash; qui est un faux lanceur d&rsquo;alerte\u00a0\u00bb, a-t-il poursuivi, faisant r\u00e9f\u00e9rence au lanceur d&rsquo;alerte de la communaut\u00e9 du renseignement dont le rapport sur un appel t\u00e9l\u00e9phonique entre Trump et le pr\u00e9sident ukrainien Volodymyr Zelensky a lanc\u00e9 la campagne de destitution contre lui.<\/em><\/p>\n<p>&raquo; <em>Qualifiant Adam Schiff, le pr\u00e9sident du House Intelligence Committee, de \u00ab\u00a0dingue\u00a0\u00bb, Trump a ajout\u00e9 : \u00ab\u00a0Celui que je veux le plus entendre t\u00e9moigner, c&rsquo;est Shifty Schiff&#8230; et ce que je veux le plus savoir, c&rsquo;est pourquoi il a falsifi\u00e9 ma d\u00e9claration.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Trump a \u00e9galement reproch\u00e9 \u00e0 M. Schiff d&rsquo;avoir tenu des audiences de destitution avec des t\u00e9moins de deuxi\u00e8me et de troisi\u00e8me main qui n&rsquo;ont jusqu&rsquo;\u00e0 pr\u00e9sent pas fourni de preuves concr\u00e8tes que le pr\u00e9sident avait conclu un accord \u00e0 l&rsquo;amiable qui pro quo avec le pr\u00e9sident ukrainien Zelensky. Les d\u00e9mocrates all\u00e8guent que Trump a retenu l&rsquo;aide militaire \u00e0 l&rsquo;Ukraine en \u00e9change de la r\u00e9ouverture par Kiev d&rsquo;une enqu\u00eate pour corruption contre la famille du candidat Joe Biden, en 2020<\/em>.<\/p>\n<p>&raquo; <em>Trump a \u00e9galement dit qu&rsquo;il aimerait entendre Hunter Biden, le fils du vice-pr\u00e9sident Joe Biden, t\u00e9moigner devant le S\u00e9nat. Hunter Biden a si\u00e9g\u00e9 au conseil d&rsquo;administration de la soci\u00e9t\u00e9 \u00e9nerg\u00e9tique ukrainienne Burisma de 2015 \u00e0 2019, un poste pour lequel il n&rsquo;\u00e9tait pas qualifi\u00e9, et une r\u00e9mun\u00e9ration lui a \u00e9t\u00e9 offert dans le cadre d&rsquo;un march\u00e9 de corruption entre son p\u00e8re et Kiev<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Il semble maintenant que c&rsquo;est en janvier 2020 que la mise en accusation viendrait devant le S\u00e9nat, et non d\u00e9but d\u00e9cembre comme certains l&rsquo;avaient envisag\u00e9. Ce retard est du bien entendu \u00e0 l&rsquo;atmosph\u00e8re \u00e9lectrique de pol\u00e9mique, \u00e0 l&rsquo;abondance des t\u00e9moignages qui ont surtout comme r\u00e9sultats de rendre la mise en accusation plus confuse d&rsquo;une part, d&rsquo;autre part d&rsquo;exacerber l&rsquo;hostilit\u00e9 et la tension entre d\u00e9mocrates et r\u00e9publicains, avec notamment le radicalisme du pr\u00e9sident de la commission de renseignement de la Chambre Adam Schiff conduisant \u00e0 un radicalisme antith\u00e9tique des r\u00e9publicains.<\/p>\n<\/p>\n<p><p>L&rsquo;attitude de Trump semble loin d&rsquo;\u00eatre une initiative personnelle lanc\u00e9e sur une impulsion du type-tweet\u00e9, toujours soumise aux possibilit\u00e9s de sautes de l&rsquo;humeur et des foucades du pr\u00e9sident, mais une strat\u00e9gie d&rsquo;ores et d\u00e9j\u00e0 \u00e9labor\u00e9e. Une d\u00e9l\u00e9gation de s\u00e9nateurs r\u00e9publicains a rencontr\u00e9 l&rsquo;\u00e9quipe juridique et politique de la Maison-Blanche qui g\u00e8re le dossier et il y a bien une volont\u00e9 d&rsquo;un proc\u00e8s destin\u00e9 \u00e0 mettre en pi\u00e8ces la mise en accusation des d\u00e9mocrates. Trump veut donc renverser le sens du proc\u00e8s : non plus le proc\u00e8s de Trump mais le proc\u00e8s des d\u00e9mocrates. <em><a href=\"https:\/\/www.zerohedge.com\/political\/bring-it-trump-wants-senate-trial-some-length-if-house-impeaches\">ZeroHedge.com<\/a><\/em> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Jeudi matin, un groupe de s\u00e9nateurs r\u00e9publicains a rencontr\u00e9 Pat Cipollone, Kellyanne Conway, Jared Kushner et Mick Mulvaney, conseillers juridiques de la Maison-Blanche, pour discuter de la strat\u00e9gie d&rsquo;un \u00e9ventuel proc\u00e8s devant le S\u00e9nat qui aurait probablement lieu en janvier, selon <a href=\"https:\/\/www.politico.com\/news\/2019\/11\/21\/white-house-backs-full-senate-trial-if-house-impeaches-trump-072578\">Politico<\/a><\/em>.<\/p>\n<p>&raquo; <em>\u00ab\u00a0Deux participants ont d\u00e9clar\u00e9 que la Maison-Blanche souhaitait que le S\u00e9nat tienne un proc\u00e8s d&rsquo;une certaine dur\u00e9e et ne rejette pas imm\u00e9diatement tout article de destitution avec la majorit\u00e9 du GOP, comme certains r\u00e9publicains l&rsquo;ont sugg\u00e9r\u00e9.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Les alli\u00e9s de la Maison-Blanche et du GOP de Trump ont plut\u00f4t d\u00e9cid\u00e9 qu&rsquo;ils voulaient une d\u00e9fense affirmative factuelle sur le fond, a d\u00e9clar\u00e9 un participant.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Un participant a fait remarquer que la Maison-Blanche veut montrer son engagement envers l&rsquo;application r\u00e9guli\u00e8re de la loi, d&rsquo;autant plus que les r\u00e9publicains ont critiqu\u00e9 les d\u00e9mocrates de la Chambre pour la fa\u00e7on dont ils ont men\u00e9 leurs proc\u00e9dures de destitution<\/em>. [&#8230;]<\/p>\n<p>&raquo; <em>\u00ab\u00a0Un fonctionnaire de la Maison-Blanche a d\u00e9clar\u00e9 que la r\u00e9union &lsquo;ne portait pas tant sur les d\u00e9tails que sur la faiblesse de la position des d\u00e9mocrates, et nous voulons montrer \u00e0 quel point cette position est faible'\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>On peut dire, apr\u00e8s deux semaines d&rsquo;audience de la commission charg\u00e9e d&rsquo;instruire le dossier \u00e0 charge, que plus personne ne comprend exactement o&ugrave; on en est du point de vue du fond de cette mise en accusation ; les uns interpr\u00e8tent le r\u00e9sultat de ces auditions comme la confirmation de la culpabilit\u00e9 de Trump, les autres comme la confirmation de la faiblesse du dossier des d\u00e9mocrates et de leur intention de d\u00e9truire Trump par tous les montages possibles. Bien entendu, de ce point de vue on identifie ais\u00e9ment qui est qui, quelles sont les forces qui s&rsquo;affrontent, et le fait que le dossier de la destitution n&rsquo;est qu&rsquo;un outil pour cet affrontement. N&rsquo;apparaissent \u00e9videntes dans cet imbroglio que la volont\u00e9 forcen\u00e9e des d\u00e9mocrates, men\u00e9s par Adam Schiff, de d\u00e9truire Trump, et la radicalisation de Trump dans sa volont\u00e9 non seulement de se d\u00e9fendre mais de contre-attaquer vigoureusement les d\u00e9mocrates, &ndash; \u00e9ventuellement pour les d\u00e9truire, selon le principe du <em>qui pro quo<\/em>.<\/p>\n<\/p>\n<p><p>Certains qui, eux, pr\u00e9tendent comprendre, &ndash; \u00e0 cet \u00e9gard, nul ne peut \u00eatre critiqu\u00e9 pour un si louable effort, &ndash; jugent que cette grande mascarade de la destitution, ce simulacre \u00e0 l&rsquo;\u00e9chelle d&rsquo;une hyperpuissance compl\u00e8tement ivre de sa d\u00e9mence, a pour v\u00e9ritable cause l&rsquo;engagement am\u00e9ricaniste en Ukraine, et de l\u00e0 la pr\u00e9paration d&rsquo;un conflit contre la Russie.<\/p>\n<\/p>\n<p><p>Le site  <em><a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/11\/23\/pers-n23.html\">WSWS.org<\/a> <\/em>a plusieurs excellents articles \u00e0 cet \u00e9gard, qui m\u00e9riteraient une analyse \u00e0 part. Pour autant, et m\u00eame si certains des acteurs de la farce-bouffe ont cela \u00e0 l&rsquo;esprit, il nous para&icirc;t un peu trop rationnel de r\u00e9duire la dite-farce \u00e0 cette seule probl\u00e9matique. Au-dessus r\u00e8gne une extraordinaire sensation d&rsquo;irrationnel et de complet d\u00e9sint\u00e9r\u00eat pour le moindre des faits parmi ceux qui sont \u00e9voqu\u00e9s. Chacun \u00e9volue \u00e0 sa place dans le simulacre, et force est de reconna&icirc;tre que les d\u00e9mocrates occupent la place principale, sorte de <em>vernaculi ex machina<\/em>si l&rsquo;on ose dire, sans le moindre souci de v\u00e9racit\u00e9, de logique, de l\u00e9galisme ni rien d&rsquo;autre de cette sorte. Il est vrai qu&rsquo;\u00e0 cette aune, on a vu resurgir le serpent de mer de la vilenie sans retour des Russes, et la n\u00e9cessit\u00e9 d&rsquo;aider l&rsquo;Ukraine dans ce qui pourrait ressembler \u00e0 un futur conflit avec la Russie.<\/p>\n<\/p>\n<blockquote>\n<p><p>Il n&rsquo;est pas s&ucirc;r que Trump, qui a jusqu&rsquo;ici pest\u00e9 d&rsquo;\u00eatre ainsi totalement accapar\u00e9, donc emp\u00each\u00e9 de traiter s\u00e9rieusement les affaires courantes, n&rsquo;ait pas fini par trouver l&rsquo;occasion excellente d&rsquo;entrer en plein au milieu de ce cirque, o&ugrave; il devrait bien figurer, pour lancer sa campagne \u00e9lectorale dans les bruits de grosse caisse et de sifflements propres \u00e0 cette sorte d&rsquo;activit\u00e9 (le cirque). Il n&rsquo;est donc pas s&ucirc;r qu&rsquo;il ne cherche pas \u00e0 prolonger cette mascarade au-del\u00e0 du d\u00e9but des primaires pour que la dite-mascarade p\u00e8se de tout son poids, &ndash; en sa faveur estimerait-il et esp\u00e9rerait-il, &ndash; dans les pr\u00e9sidentielles.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les r\u00e9publicains semblent de moins en moins inclin\u00e9s \u00e0 le ralentir ou \u00e0 lui mesurer leur soutien, devant l&rsquo;\u00e9vidence de l&rsquo;aspect d&rsquo;une compl\u00e8te usine \u00e0 gaz qu&rsquo;a pris cette affaire, au long des auditions, dans le chef des d\u00e9mocrates. Il semble en effet que le soutien \u00e0 leur pr\u00e9sident des r\u00e9publicains, eux aussi pouss\u00e9s au radicalisme antagoniste par le radicalisme des d\u00e9mocrates, soit aujourd&rsquo;hui bien plus ferme qu&rsquo;il y a un mois, &ndash; et eux-m\u00eames, dont certains ont une campagne \u00e9lectorale personnelle pour 2020, estimant \u00e0 leur tour qu&rsquo;ils pourraient den tirer profit.<\/p>\n<\/p>\n<p><p>Pour autant, et d&rsquo;ailleurs en compl\u00e8te logique avec le caract\u00e8re incontr\u00f4lable de la situation, il est effectivement plus que jamais impossible de dire o&ugrave; tout cela nous am\u00e8ne. La seule chose assur\u00e9e que l&rsquo;on puisse proposer est que l&rsquo;affaire de la destitution est d\u00e9sormais bien ancr\u00e9e, non pas dans un conflit constitutionnel classique, mais dans ce que Isra\u00ebl Shamir nomme &laquo; <em>la guerre civile froide<\/em> &raquo; qui d\u00e9chire les USA, et particuli\u00e8rement tous les grands centres du pouvoir du syst\u00e8me de l&rsquo;am\u00e9ricanisme, depuis 2015-2016.<\/p>\n<\/p>\n<p><p>Mis en ligne le 23 novembre 2019 \u00e0 11H55<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trump \u00e0 la baston Alors que le processus de l&rsquo;instruction de la mise en accusation par la commission judiciaire de la Chambre est en pleine vitesse (deux semaines d&rsquo;audition) et approche de son terme, alors que nous subissons de plein fouet ce ph\u00e9nom\u00e8ne dans la situation d\u00e9sormais connue et bien identifi\u00e9ede la &laquo; Solitude cognitive&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5763,2880,4911,3106,2645,3340,6286,2730,15073,3531,11486,1296,18828],"class_list":["post-78968","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-adam","tag-civile","tag-destitution","tag-froide","tag-guerre","tag-presidentielles","tag-proces","tag-russie","tag-schiff","tag-senat","tag-temoignage","tag-ukraine","tag-usa-2020"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78968"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78968\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}