{"id":78989,"date":"2019-12-04T20:42:45","date_gmt":"2019-12-04T20:42:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/04\/angoisse-indicible-parution-du-tome-iii1\/"},"modified":"2019-12-04T20:42:45","modified_gmt":"2019-12-04T20:42:45","slug":"angoisse-indicible-parution-du-tome-iii1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/04\/angoisse-indicible-parution-du-tome-iii1\/","title":{"rendered":"Angoisse &amp; indicible\u00a0: parution du Tome-III\/1"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Angoisse &#038; indicible : parution du Tome-III\/1<\/h2>\n<\/p>\n<p><p>4 d\u00e9cembre 2019 &ndash; Chassez de vos esprits tout ce qui a pu vous appara&icirc;tre de pr\u00e9cis et de pr\u00e9visions structur\u00e9es dans les quelques textes d\u00e9j\u00e0 parus sur le Tome-III de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, comme par exemple les deux derniers du  <a href=\"http:\/\/www.dedefensa.org\/article\/le-tome-iii-a-lhorizon\">11 novembre 2018<\/a>  et du  <a href=\"http:\/\/www.dedefensa.org\/article\/le-tome-iii-a-lhorizon\">10 f\u00e9vrier 2019<\/a>. Aujourd&rsquo;hui est le jour de ce qu&rsquo;on nommerait \u00ab\u00a0r\u00e9alit\u00e9\u00a0\u00bb, de ce que je pr\u00e9f\u00e8re d\u00e9signer comme \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>\u00a0\u00bb du \u00ab\u00a0Tome-III-en-partie\u00a0\u00bb, puisqu&rsquo;il y a parution. Il s&rsquo;agit bien de la \u00ab\u00a0premi\u00e8re partie du Tome-III\u00a0\u00bb, correspondant au choix fait de publier ce &laquo; <em>monstre qu&rsquo;est ce Tome-III.<\/em>.. &raquo; partie par partie \u00e0 mesure qu&rsquo;il avance, et cela tant qu&rsquo;il avance, et cela sans savoir o&ugrave; je vais, et cela avec une seule et unique fid\u00e9lit\u00e9 au monde, &ndash; ma plume qui court et me guide, m&rsquo;angoisse et m&rsquo;\u00e9pouvante, m&rsquo;\u00e9meut et me transporte.<\/p>\n<\/p>\n<p><p>Je l&rsquo;\u00e9cris (dans l&rsquo;introduction) et je le crois intens\u00e9ment, avec au c&oelig;ur et dans l&rsquo;\u00e2me le poids de l&rsquo;humaine nature et de toute ma mis\u00e8re humaine qui me tient saisi par mes angoisses terrestres, et les horizons de l&rsquo;indicible radieux qui me d\u00e9livreraient pour l&rsquo;envol vers les cieux :<\/p>\n<\/p>\n<blockquote>\n<p><p>&laquo; <em>Je marche dans la nuit, avec une bougie tremblotante \u00e0 la main, dans un temps de fureurs et de bourrasques qui ridiculisent cette flamme insaisissable ; et je ne peux douter un seul instant que ma mission est d&rsquo;\u00e9clairer la nuit d&rsquo;une \u00e9blouissante lumi\u00e8re<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi ce livre, cette &oelig;uvre me terrorise litt\u00e9ralement, jamais je n&rsquo;ai \u00e9t\u00e9 aussi tenu par l&rsquo;angoisse, jusqu&rsquo;\u00e0 repousser et repousser encore le temps de ce qui n&rsquo;est qu&rsquo;un d\u00e9but incertain de l&rsquo;\u00e9dition du monstre :<\/p>\n<\/p>\n<blockquote>\n<p><p>&laquo; <em>Ce Tome-III, \u00e0 la fois me fascine et m&rsquo;effraie horriblement. Combien de fois ai-je cru le saisir pour enfin d\u00e9couvrir son myst\u00e8re, combien de fois l&rsquo;ai-je repouss\u00e9 pour n&rsquo;y plus penser, d\u00e9courag\u00e9 par ce qui me paraissait soudainement un herm\u00e9tisme arrogant et sardonique<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette &oelig;uvre, cette ambition, cette tentative, ce r\u00e9cit d&rsquo;un essai qui tente de se surpasser et d&rsquo;exister, et qui n&rsquo;est peut-\u00eatre, peut-\u00eatre bien, qu&rsquo;un ramassis d&rsquo;incertitudes que bien plus d&rsquo;un trouveraient d\u00e9testables, tout cela repr\u00e9sente \u00e9galement sinon principalement, disons une tentative d&rsquo;un dialogue avec la Mort. Cela fait, d\u00e9couvris-je en \u00e9crivant cette phrase, que, pour moi, la Mort est chose bien vivante avec quoi l&rsquo;on peut dialoguer, et donc contradiction joyeuse en soi, ou alors V\u00e9rit\u00e9 absolue bien au-del\u00e0 de la connaissance, dans la connaissance devenue inconnaissance&#8230; Entre autres mais certes dans ce cas, cette phrase qui n&rsquo;en finit pas du Pseudo-Denys l&rsquo;Ar\u00e9opagite me hante, &ndash; dont on souffrira que le sujet devienne compl\u00e8tement anonyme pour cette unique fois o&ugrave; j&rsquo;en use de cette fa\u00e7on : <\/p>\n<\/p>\n<p><p>&laquo; <em>C&rsquo;est alors seulement que, d\u00e9passant le monde o&ugrave; l&rsquo;on est vu et o&ugrave; l&rsquo;on voit, <\/em>[l&rsquo;\u00eatre] <em>p\u00e9n\u00e8tre dans la T\u00e9n\u00e8bre v\u00e9ritablement mystique de l&rsquo;inconnaissance : c&rsquo;est l\u00e0 qu&rsquo;il fait taire tout savoir positif, qu&rsquo;il \u00e9chappe enti\u00e8rement \u00e0 toute saisie et \u00e0 toute vision, car il appartient tout entier \u00e0 Celui qui est au-del\u00e0 de tout, car il ne s&rsquo;appartient plus lui-m\u00eame ni n&rsquo;appartient \u00e0 rien d&rsquo;\u00e9tranger, uni par le meilleur de lui-m\u00eame \u00e0 Celui qui \u00e9chappe \u00e0 toute inconnaissance, ayant renonc\u00e9 \u00e0 tout savoir positif, et gr\u00e2ce \u00e0 cette inconnaissance m\u00eame connaissant par-del\u00e0 toute intelligence. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Je ne pense pas qu&rsquo;il y ait meilleure introduction \u00e0 cette \u00e9trange \u00e9dition, hoquetante, qu&rsquo;on croirait sans queue ni t\u00eate, que de reprendre l&rsquo;introduction justement, du volume en question. (Cette \u00ab\u00a0Introduction\u00a0\u00bb intitul\u00e9e <em>De la nostalgie \u00e0 l&rsquo;&Eacute;ternit\u00e9 <\/em>est suivie d&rsquo;un \u00ab\u00a0Avertissement\u00a0\u00bb, \u00e9galement repris ici, qui donne un aper\u00e7u de l&rsquo;\u00e9trange m\u00e9canique animant l&rsquo;\u00e9dition \u00ab\u00a0saucissonn\u00e9e\u00a0\u00bb de ce Tome-III.) La chose, le Tome-III\/1 de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, est d\u00e9sormais  <a href=\"https:\/\/www.amazon.fr\/dp\/2960206223\/ref=sr_1_7?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&#038;keywords=La+Gr%C3%A2ce+de+l%27Histoire&#038;qid=1575316288&#038;sr=8-7\">en vente ici<\/a>, au prix le plus modique qui soit de &euro;5,80, passant par la fabrication d&rsquo;\u00e9dition du monstrueux <em>Orque <\/em>(<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Orque_(Terre_du_Milieu)\">celui de Tolkien<\/a>) nomm\u00e9 <em>Amazon<\/em>, dont vous savez ce que je pense de lui mais dont il me pla&icirc;t de savoir qu'\u00a0\u00bbil\u00a0\u00bb a fait imprimer ce qu'\u00a0\u00bbil\u00a0\u00bb d\u00e9testerait sans aucun doute par-dessus tout s'\u00a0\u00bbil\u00a0\u00bb en avait connaissance.<\/p>\n<\/p>\n<p><p>Je crois et je pense que nous reviendrons sur le sujet du Tome-III\/1, suite &#038; cons\u00e9quences&#8230;<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">De la nostalgie \u00e0 l&rsquo;&Eacute;ternit\u00e9<\/h2>\n<\/p>\n<p><p>Depuis le plus loin de mon adolescence, et \u00e0 partir d&rsquo;une simple imagerie qui montrait ce visage extraordinaire dans un concours du journal quotidien qu&rsquo;on jugeait \u00e0 cette \u00e9poque respectable, c&rsquo;\u00e9tait<em>Le Figaro<\/em>,pour le classement des \u00ab\u00a0100 personnalit\u00e9s les plus importantes de l&rsquo;Europe\u00a0\u00bb, \u00e0 l&rsquo;occasion de la signature du Trait\u00e9 de Rome de 1956 ou 1957, &ndash; depuis le plus loin dans ma vie symbolique et intellectuelle donc, il y a cette fascination pour Nietzsche. Je le redis car c&rsquo;est important, expliquant en cela l&rsquo;aspect symbolique, cette fascination na&icirc;t de cet \u00ab\u00a0extraordinaire visage\u00a0\u00bb comme il m&rsquo;appara&icirc;t, et aussi de l&rsquo;\u00e9trange composition du nom (ce z avec un s).<\/p>\n<\/p>\n<p><p>Cela est dit sans autre forme de proc\u00e8s et, surtout, sans y rien comprendre ni avoir \u00e0 m&rsquo;en expliquer, &ndash; aujourd&rsquo;hui comme hier, je le pr\u00e9cise, car je n&rsquo;ai toujours pas l&rsquo;esprit de vouloir soumettre mes intuitions radicales \u00e0 l&rsquo;enqu\u00eate pointilleuse de la Raison. A partir de cette origine et dans l&rsquo;encha&icirc;nement fascination-intuition, cela fait que j&rsquo;ai cru lire Fr\u00e9d\u00e9ric Nietzsche (FN) et comprendre sa pens\u00e9e pendant des d\u00e9cennies sans rien n&rsquo;y voir ni rien en entendre. Soudain pourrais-je presque dire, ces derni\u00e8res ann\u00e9es, ayant fait la somme des ex\u00e9g\u00e8ses et explicateurs divers de Nietzsche qu&rsquo;il m&rsquo;arriva de rencontrer, je me suis convaincu de ceci que la foule de ceux qui avaient vu et entendu FN comme il faut \u00e9tait si abondante et si diverse, si contradictoire, si assur\u00e9e de tant de directions diff\u00e9rentes sinon antagonistes, qu&rsquo;il importait de ne pas trop chercher \u00e0 en faire partie.<\/p>\n<\/p>\n<p><p>Tout cela, jusqu&rsquo;\u00e0 ce livre, et peut-\u00eatre d\u00e9cisivement \u00e0 cause de ce livre de Gustave Thibon, de 1948, r\u00e9\u00e9dit\u00e9 r\u00e9cemment, qui s&rsquo;intitule <em>Nietzsche ou le d\u00e9clin de l&rsquo;esprit<\/em>, &ndash; Thibon que j&rsquo;avais tant appr\u00e9ci\u00e9 dans une \u00e9mission t\u00e9l\u00e9vis\u00e9e d&rsquo;entretiens entre Pierre Buisson et lui, de 2012 je crois, intitul\u00e9e <em>Il \u00e9tait une foi<\/em>. Thibon ne m&rsquo;a pas converti, mais il m&rsquo;a tant s\u00e9duit comme son personnage de lui-m\u00eame&hellip; Pour en venir \u00e0 ceci enfin, son livre sur Nietzsche commen\u00e7ant exactement par cette phrase : &laquo; <em>Quand une tr\u00e8s grande gloire s&rsquo;abat sur un tr\u00e8s grand homme, il faut voir l\u00e0 un ch\u00e2timent plut\u00f4t qu&rsquo;une r\u00e9compense.<\/em> &raquo; Trois lignes plus loin, \u00e0 propos des tr\u00e8s nombreuses et diverses \u00ab\u00a0interpr\u00e9tations\u00a0\u00bb de FN (\u00ab\u00a0J&rsquo;ai lu, j&rsquo;ai vu, j&rsquo;ai compris\u00a0\u00bb), cette autre phrase, avec la dent dure, sans concessions, ni bien heureusement de charit\u00e9 chr\u00e9tienne, de la part de Gustave Thibon : &laquo; <em>Ainsi la pens\u00e9e la plus haute <\/em>[celle de FN] <em>passe presque sans transition de l&rsquo;\u00e9tat de vierge \u00e0 celui de prostitu\u00e9e.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>(L&rsquo;admirable chez Thibon c&rsquo;est son affirmation sans restriction, sans le moindre calcul ni la moindre hypocrisie, &ndash; je suis s&ucirc;r de cela, de ce qu&rsquo;on nommerait de fa\u00e7on plus g\u00e9n\u00e9rale une \u00ab\u00a0absence de malice\u00a0\u00bb, &ndash; de l&rsquo;immensit\u00e9, de la hauteur pratiquement jusqu&rsquo;aux cieux de ce qu&rsquo;il consid\u00e8re comme le g\u00e9nie de l&rsquo;intuition nietzsch\u00e9enne en m\u00eame temps que l&rsquo;attaque frontale qu&rsquo;il lance contre lui, &ndash; et nullement contre elle [l&rsquo;intuition]. Sorti des r\u00e9actions sur le jugement, le sujet lui-m\u00eame, l&rsquo;attitude de Thibon, on en vient \u00e0 s&rsquo;interroger, si l&rsquo;on accepte son ing\u00e9nuit\u00e9 et la justesse de son jugement sur l&rsquo;homme lui-m\u00eame [FN] : \u00ab\u00a0L&rsquo;intuition nietzsch\u00e9enne n&rsquo;\u00e9tait-elle pas trop grande, trop forte, trop haute pour lui-m\u00eame, Fr\u00e9d\u00e9ric Nietzsche, c&rsquo;est-\u00e0-dire pour sa raison ?\u00a0\u00bb \u00ab\u00a0Trop grande, trop forte&hellip;\u00a0\u00bb, litt\u00e9ralement, pour \u00ab\u00a0\u00eatre port\u00e9e\u00a0\u00bb, ou plus pr\u00e9cis\u00e9ment \u00ab\u00a0pour \u00eatre accueillie et offerte \u00e0 nos esprits comme un diamant dans son \u00e9crin\u00a0\u00bb ? D&rsquo;o&ugrave; sa folie, n&rsquo;est-ce pas, et ajoute Thibon avec un sourire goguenard : d&rsquo;o&ugrave; son erreur d&rsquo;aiguillage entre le cul-de-sac du \u00ab\u00a0Surhomme\u00a0\u00bb et l&rsquo;envol\u00e9e de la transcendance&hellip;)<\/p>\n<\/p>\n<p><p>Dans le m\u00eame genre des rapports tr\u00e8s difficiles entre les esprits hauts et l&rsquo;attention, sinon la compr\u00e9hension des contemporains, il y a ces quelques mots du compositeur Sch\u00f6nberg, homme toujours tr\u00e8s religieux dans ses d\u00e9marches du jugement artistique. (Pour situer la chose, nous pr\u00e9ciserons qu&rsquo;il s&rsquo;agit d&rsquo;une citation d&rsquo;une conversation \u00e0 la radio de 1931, dans <em>Exil &#038; Musique<\/em>, Etienne Barilier&hellip;) &laquo; <em>A celui \u00e0 qui le Seigneur a assign\u00e9 la vocation de dire des choses impopulaires, le Seigneur a donn\u00e9 \u00e9galement la facult\u00e9 de se r\u00e9signer \u00e0 ce que ce soit toujours les autres qui soient compris.<\/em> &raquo; J&rsquo;aurais \u00e9crit plut\u00f4t, pour mon compte et parce que je suis de ceux qui ne comprennent pas n\u00e9cessairement ce que je suis conduit \u00e0 \u00e9crire, et enfin parce que j&rsquo;aime les myst\u00e8res de l&rsquo;\u00e9vidence, &ndash; mais peut-\u00eatre y a-t-il une approximation de traduction, \u00e0 partir de la source initiale qui est le <em>Arnold Sch\u00f6nberg<\/em>de H. H. Stuckenschmidt, p .355, et peut-\u00eatre l&rsquo;\u00e9crit de Sch\u00f6nberg va-t-il plut\u00f4t dans ce sens :<\/p>\n<\/p>\n<p><p>&laquo; <em>A celui \u00e0 qui le Seigneur a assign\u00e9 la vocation de dire des choses <strong><u>incompr\u00e9hensibles<\/u><\/strong><\/em>[impopulaires parce qu&rsquo;incompr\u00e9hensibles]<em>, le Seigneur a donn\u00e9 \u00e9galement la facult\u00e9 de se r\u00e9signer \u00e0 ce que ce soit toujours les autres qui soient compris.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Enfin, je clos ce floril\u00e8ge en empruntant une citation (de Nietzsche, encore, vous l&rsquo;auriez devin\u00e9) que Michel Onfray avait plac\u00e9 en \u00e9pitaphe de son <em>Archipel des com\u00e8tes<\/em> : &laquo; <em>Je me suis rendu compte, peu \u00e0 peu, de ce qu&rsquo;a \u00e9t\u00e9, jusqu&rsquo;\u00e0 pr\u00e9sent, toute grande philosophie : une confession de son auteur, et une sorte de m\u00e9moires involontaires et inaper\u00e7us<\/em>. &raquo; (Nietzsche, <em>Par-del\u00e0 le bien et le mal<\/em>). Ainsi se trouvent r\u00e9unis, par le canal de citations et du choix de citations d&rsquo;auteurs et d&rsquo;artistes de haute culture, trois sentiments qui m&rsquo;habitent et, sans doute, m&rsquo;obs\u00e8dent bien plus que je n&rsquo;ai d&rsquo;int\u00e9r\u00eat de l&rsquo;exprimer : <\/p>\n<\/p>\n<p><p>La compr\u00e9hensibilit\u00e9 faussaire et trompeuse, souvent empress\u00e9e pour son propre parti, qui accueille la pens\u00e9e d&rsquo;esprits ayant choisi de s&rsquo;exprimer, pour la d\u00e9former sans m\u00eame r\u00e9aliser la chose ; mais aussi, par extension et pour g\u00e9n\u00e9raliser mon jugement \u00e0 cet \u00e9gard, telle \u00ab\u00a0compr\u00e9hensibilit\u00e9 faussaire et trompeuse\u00a0\u00bb qui caract\u00e9rise \u00e9galement l&rsquo;historiographie, le simulacre du savoir de la modernit\u00e9, les diktats de la raison-subvertie, tout ce qui ne cesse de peser sur l&rsquo;esprit pour le d\u00e9voyer, pour l&rsquo;an\u00e9antir litt\u00e9ralement ; aujourd&rsquo;hui sans aucun doute, dans ces temps si incertains, dans ces temps de la Grande Crise diluvienne, cette \u00ab\u00a0compr\u00e9hensibilit\u00e9 faussaire et trompeuse\u00a0\u00bb avec une puissance et une efficacit\u00e9 qu&rsquo;on ne peut imaginer avant d&rsquo;en avoir embrass\u00e9 les effets et mesur\u00e9 les cons\u00e9quences ;<\/p>\n<\/p>\n<p><p>L&rsquo;incompr\u00e9hensibilit\u00e9 des autres au premier abord, au premier regard, par n\u00e9cessit\u00e9 en quelque sorte, des choses \u00e0 la fois profondes et inatteignables sous une forme descriptible ais\u00e9e, et dont l&rsquo;auteur ne sait ni ne comprend rien lui-m\u00eame de l&rsquo;existence dans son chef de ce caract\u00e8re d&rsquo;incompr\u00e9hensibilit\u00e9 ; alors que cet auteur assure par ailleurs, sans souci de distinguer entre ces deux termes une contradiction, que la r\u00e9action de cette \u00ab\u00a0incompr\u00e9hensibilit\u00e9 des autres\u00a0\u00bb est compr\u00e9hensible et qu&rsquo;il faut s&rsquo;y r\u00e9signer, voire l&rsquo;accepter sans amertume ni quelque vindicte que ce soit, voire m\u00eame en \u00e9prouver un certain soulagement, sinon pour ceux qui ext\u00e9riorise leur foi, une joie profonde comme lorsqu&rsquo;on dit \u00ab\u00a0Ainsi soit-il\u00a0\u00bb ;<\/p>\n<\/p>\n<p><p>La n\u00e9cessit\u00e9 de prendre le \u00ab\u00a0mat\u00e9riel de sa vie\u00a0\u00bb pour d\u00e9velopper, exprimer, substantiver sa pens\u00e9e, particuli\u00e8rement pour mon compte quand la source est compl\u00e8tement intuitive, venue du dehors de moi : les &laquo; <em>m\u00e9moires involontaires et inaper\u00e7ues<\/em> &raquo; de Nietzsche constituent l&rsquo;outil dont on ne peut se passer parce qu&rsquo;il est le seul \u00e0 pouvoir substantiver, \u00e0 exprimer pour notre compr\u00e9hension l&rsquo;intuition dans toute sa richesse et sa puissance.<\/p>\n<\/p>\n<p><p>Je voulais d\u00e9velopper ces trois points tr\u00e8s contraignants, qui sont pourtant communs dans des travaux qu&rsquo;on jugerait pourtant rares et insaisissables, pour pouvoir d\u00e9finir ma d\u00e9marche et mieux exposer aux lecteurs cette v\u00e9rit\u00e9 terrible et sublime qu&rsquo;il y a dans cette d\u00e9marche, et dans mon chef dans tous les cas, justement \u00e0 cause de cette conscience de telles contraintes qui paraissent parfois comme les murs infranchissables d&rsquo;une forteresse prot\u00e9geant l&rsquo;esprit mais risquant aussi de l&rsquo;enfermer, une solitude extr\u00eame et une angoisse d&rsquo;une profondeur peu commune ; et l\u00e0-dessus, abruptement, il me faut ajouter que rien de tout cela, une fois exp\u00e9riment\u00e9es ces perceptions de solitude et d&rsquo;angoisse, ne vous quitte jamais tout \u00e0 fait ; et plus encore, une fois exp\u00e9riment\u00e9es ces perceptions de solitude et d&rsquo;angoisse vous ne voudrez plus jamais qu&rsquo;elles ne vous quittent parce qu&rsquo;en v\u00e9rit\u00e9 <strong>vous les aimez<\/strong>. C&rsquo;est ainsi que ce Tome-III, \u00e0 la diff\u00e9rence des deux tomes pr\u00e9c\u00e9dents je crois, est entam\u00e9, \u00e9crit, &ndash; fini ou \u00e0 finir, je ne sais&hellip;, &ndash; dans une tension extr\u00eame et un constant risque de d\u00e9s\u00e9quilibre, et je parlerais m\u00eame \u00e0 certains moments d&rsquo;une souffrance indescriptible.<\/p>\n<\/p>\n<p><p>Je marche dans la nuit, avec une bougie tremblotante \u00e0 la main, dans un temps de fureurs et de bourrasques qui ridiculisent cette flamme insaisissable ; et je ne peux douter un seul instant que ma mission est d&rsquo;\u00e9clairer la nuit d&rsquo;une \u00e9blouissante lumi\u00e8re. Comment faire et comment cela peut-il \u00eatre fait, &ndash; je l&rsquo;ignore. J&rsquo;ai l&rsquo;impression d&rsquo;\u00eatre un aveugle dont la mission est de d\u00e9crire avec une terrible pr\u00e9cision ce qu&rsquo;il ne voit pas, comme s&rsquo;il voyait \u00ab\u00a0les choses derri\u00e8re les choses\u00a0\u00bb, c&rsquo;est-\u00e0-dire les choses que personne ne voit derri\u00e8re les choses que je ne vois pas ; ou bien, suis-je un fou qui croit \u00eatre cette personne qui croit \u00ab\u00a0\u00eatre un aveugle dont la mission&hellip;\u00a0\u00bb, etc. ?<\/p>\n<\/p>\n<p><p>D&rsquo;autre part et m\u00eame plus encore, comme les lecteurs tr\u00e8s rares qui m&rsquo;ont fait la gr\u00e2ce de les lire, on d\u00e9couvrira combien ce Tome-III est d&rsquo;esprit, de facture, de forme, de structures extr\u00eamement diff\u00e9rentes des deux pr\u00e9c\u00e9dents, &ndash; quasiment d&rsquo;un autre \u00e9tat de l&rsquo;esprit et d&rsquo;un esprit d&rsquo;une nature autre, &ndash; jusqu&rsquo;\u00e0 faire douter de la filiation, de l&rsquo;h\u00e9ritage, de la communaut\u00e9 de dessein. C&rsquo;est \u00e0 ne pas croire, &ndash; et c&rsquo;est \u00e0 croire me dirais-je en les parcourant ici et l\u00e0, que c&rsquo;est un autre qui a pris la plume, ou bien que c&rsquo;est une autre plume qui s&rsquo;est empar\u00e9e de moi&#8230; Ici, dans ce Tome-III, domine l&rsquo;\u00e2me po\u00e9tique, comme si le pseudo-historien, ou plus justement de pr\u00e9tention m\u00e9tahistorique, avait d\u00e9couvert finalement ce Graal qui lui dit que seul l&rsquo;esprit de la po\u00e9sie ouvre la porte de la m\u00e9taphysique&hellip; Dans tous les cas, je pense qu&rsquo;il le croit et je n&rsquo;ai pas voulu le d\u00e9courager ni l&rsquo;en d\u00e9tourner ; je lui ai laiss\u00e9 bride sur le cou, car je le sens d\u00e9j\u00e0 enflamm\u00e9 par l&rsquo;ivresse du galop.<\/p>\n<\/p>\n<p><p>***<\/p>\n<\/p>\n<p><p>Ce Tome-III, \u00e0 la fois me fascine et m&rsquo;effraie horriblement. Combien de fois ai-je cru le saisir pour enfin d\u00e9couvrir son myst\u00e8re, combien de fois l&rsquo;ai-je repouss\u00e9 pour n&rsquo;y plus penser, d\u00e9courag\u00e9 par ce qui me paraissait soudainement un herm\u00e9tisme arrogant et sardonique. Jamais je n&rsquo;ai eu autant de difficult\u00e9 \u00e0 \u00e9crire jusqu&rsquo;\u00e0 me sentir proche d&rsquo;une d\u00e9cision d&rsquo;abandon \u00e0 cet \u00e9gard, pour ce projet, pour ce qui est un livre qui a toujours \u00e9t\u00e9 l&rsquo;unique ambition de ma vie terrestre ; jamais pourtant je n&rsquo;ai senti ma plume aussi impatiente de tracer les phrases, les mots, les signes dont elle \u00e9tait absolument habit\u00e9e, comme si elle d\u00e9tenait la clef du Myst\u00e8re du monde. Avec lui, avec ce Tome-III, j&rsquo;ai un instant la conviction que le Grand Tout est \u00e0 port\u00e9e de plume, et l&rsquo;instant d&rsquo;apr\u00e8s la certitude pour mon compte de n&rsquo;\u00eatre rien, oserais-je dire le Grand Rien.<\/p>\n<\/p>\n<p><p>Ainsi en est-il de poursuivre dans cette ombre gigantesque, dans cet ouragan foudroyant qui secoue le monde. Jamais sans doute, dirais-je en exprimant une hypoth\u00e8se qui m&rsquo;obs\u00e8de depuis le d\u00e9but du si\u00e8cle, jamais les \u00e9v\u00e9nements de ce que je nommerais l'\u00a0\u00bbhistoire-courante\u00a0\u00bb, celle dont nous nourrissons nos esprits depuis le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb, ne se r\u00e9v\u00e8lent aussi proches des espaces et des forces suprahumaines, de celles qu&rsquo;on fr\u00f4le et devine lorsqu&rsquo;on pr\u00e9tend arriver \u00e0 la m\u00e9tahistoire, au point de penser que peut-\u00eatre nous y sommes.<\/p>\n<\/p>\n<p><p>Pour cette raison, bien entendu, le cycle qui m&rsquo;appara&icirc;t comme le don de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>se trouve transform\u00e9 en une sorte de coup de d\u00e9s, non pas d&rsquo;un jeu qui d\u00e9pend des rumeurs du hasard mais d&rsquo;un dessein cosmique et transcendant qui par d\u00e9finition nous d\u00e9passe et dont je solliciterais certaines indications. C&rsquo;est la seule raison, on le comprend, qui me pousse encore \u00e0 progresser dans la nuit, avec ma flamme vacillante et insaisissable, malgr\u00e9 ma solitude, malgr\u00e9 mon angoisse, ou peut-\u00eatre au contraire port\u00e9 par ma solitude et par mon angoisse comme par deux forces irr\u00e9sistibles et de cette sorte qui, seule, peut permettre \u00e0 celui les supporte et qui les porte de se permettre de s&rsquo;adresser au Ciel.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Avertissement<\/h2>\n<\/p>\n<p><p>Je dois compl\u00e9ter cette Introduction d&rsquo;une sorte d'\u00a0\u00bbAvertissement\u00a0\u00bb qui est d&rsquo;une mati\u00e8re plus terre-\u00e0-terre, &ndash; pour que le lecteur s&rsquo;y retrouve. Il s&rsquo;agit d&rsquo;expliquer ce que contient ce volume, sa raison d&rsquo;\u00eatre, \u00e9ventuellement et en filigrane, ou dans tous les cas indirectement, ou m\u00eame sugg\u00e9r\u00e9e dirais-je, &ndash; la raison de ma d\u00e9marche. <\/p>\n<\/p>\n<p><p>Ce volume n&rsquo;est bien entendu qu&rsquo;une partie du Tome-III de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, et le d\u00e9but \u00e9videmment&hellip; Cette s\u00e9rie, \u00e9dit\u00e9e dans des circonstances diverses, dans une \u00e9poque extr\u00eamement et affreusement d\u00e9sordonn\u00e9e, a pris des allures inattendues, tant sur la dur\u00e9e que sur la longueur. Les moyens consid\u00e9rables mais tout aussi d\u00e9sordonn\u00e9s d&rsquo;\u00e9dition que nous offre cette m\u00eame \u00e9poque, \u00e0 la fois consid\u00e9rables et ex\u00e9crables moyens, permettent \u00e0 un auteur de voir ses livres \u00e9dit\u00e9s hors des circuits traditionnels, \u00e0 sa guise et compl\u00e8tement sous son contr\u00f4le, assez ais\u00e9ment. Ainsi ai-je pu disposer de toute ma libert\u00e9 pour choisir la voie qui m&rsquo;arrange, et qui par ailleurs m&rsquo;apaise grandement du point de vue de ma psychologie et de mon humeur, &ndash; dans tous les cas, pour un instant.<\/p>\n<\/p>\n<p><p>(Pour le reste, la diffusion, les ventes, la promotion, les lecteurs, etc. et tout cela, voil\u00e0 une toute autre histoire qui n&rsquo;est plus de mon registre, &ndash; dis-je avec une certaine ironie nostalgique.)<\/p>\n<\/p>\n<p><p>La v\u00e9rit\u00e9 est que je ne crains rien de plus que de ne pouvoir terminer ce Tome-III. Les raisons abondent, \u00e0 commencer par la plus \u00e9vidente qui est \u00ab\u00a0l&rsquo;\u00e2ge du capitaine\u00a0\u00bb. Laissons cela qui est de peu d&rsquo;importance pour notre propos, et venons-en au constat que cette publication partielle du Tome-III a quelque chose d&rsquo;une th\u00e9rapie pour mon compte, qui est de ne pas laisser s&rsquo;\u00e9chapper ce qui semble d\u00e9j\u00e0 \u00eatre compl\u00e9t\u00e9, et qui, \u00e0 mon sens, forme d\u00e9j\u00e0 une sorte de \u00ab\u00a0tout dans le tout\u00a0\u00bb (ou \u00ab\u00a0de tout dans le Tout\u00a0\u00bb) que doit \u00eatre le Tome-III. Toutes ces choses, rangement, structuration, le Tome-III comme \u00ab\u00a0Tout\u00a0\u00bb, etc., \u00e9taient impr\u00e9vues et se sont greff\u00e9es, sinon r\u00e9v\u00e9l\u00e9es \u00e0 moi \u00e0 mesure que le travail se faisait ; et, oserais-je dire, \u00ab\u00a0se sont r\u00e9v\u00e9l\u00e9es \u00e0 moi\u00a0\u00bb d&rsquo;elles-m\u00eames, comme si le travail \u00ab\u00a0se faisait\u00a0\u00bb de lui-m\u00eame ; on ne chasse pas ais\u00e9ment le logocrate qui est en vous, quand il est r\u00e9ellement en vous&hellip;<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, ce qui est publi\u00e9 ici est une premi\u00e8re \u00ab\u00a0partie\u00a0\u00bb du Tome-III, comprenant une introduction (&laquo; <em>De la nostalgie \u00e0 l&rsquo;&Eacute;ternit\u00e9 <\/em>&raquo;) et les deux premi\u00e8res Parties de l&rsquo;ensemble (&laquo; <em>Le d\u00e9senchantement de Dieu <\/em>&raquo; et &laquo; <em>La parabole de Rodin <\/em>&raquo;). Je pense que cette tranche telle qu&rsquo;elle est livr\u00e9e peut se comprendre, sinon c&rsquo;est le signe que le lecteur n&rsquo;y entendra rien ou bien n&rsquo;en tirera aucune \u00e9motion ni enrichissement et le livre n&rsquo;est pas pour lui ; litt\u00e9ralement ce livre ne le m\u00e9rite pas, ce lecteur-l\u00e0, et ce lecteur-l\u00e0 n&rsquo;a que faire de ce livre dont il peut lui prendre de le consid\u00e9rer avec d\u00e9rision ; mais il y a des lecteurs dont on se passe parce qu&rsquo;on doit s&rsquo;en passer, et de m\u00eame nombre d&rsquo;\u00eatres assurent pouvoir se passer de tels ou tels livres, dont celui-ci, car litt\u00e9ralement ils ne savent quoi en faire et en sourient avec d\u00e9rision&hellip; Ainsi tout le monde est-il quitte sans nulle autre querelle.<\/p>\n<\/p>\n<p><p>Un autre point \u00e0 signaler, si cette premi\u00e8re publication est suivie d&rsquo;une ou d&rsquo;autres, toutes en tranches ou pas, et finalement d&rsquo;une publication du Tome-III dans son entier si c&rsquo;est le cas, c&rsquo;est que les textes qui suivent seront relus et revus, peut-\u00eatre modifi\u00e9s, etc. J&rsquo;entends par l\u00e0 terminer cette rubrique \u00ab\u00a0<em>Avertissement<\/em>\u00a0\u00bb par un dernier avertissement. C&rsquo;est une v\u00e9rit\u00e9 qu&rsquo;on ne peut s&rsquo;abstenir d&rsquo;observer que les textes qui suivent, d\u00e9j\u00e0 souvent lus et relus, sont encore \u00e0 relire pour de futures \u00e9ditions, dans les temps incertains \u00e0 venir et ils le seront, selon le temps qui m&rsquo;est sans doute d\u00e9j\u00e0 imparti, &ndash; ou bien est-ce \u00e0 dire que l&rsquo;&Eacute;ternit\u00e9 est parfois pouss\u00e9e \u00e0 assumer d&rsquo;\u00e9tranges besognes, \u00e0 prendre des initiatives dont elle-seule conna&icirc;t le secret et la justification, selon les accidents du temps-courant, &ndash; s&rsquo;il y a apr\u00e8s tout quelque chose \u00e0 en sortir, pourquoi pas ?<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angoisse &#038; indicible : parution du Tome-III\/1 4 d\u00e9cembre 2019 &ndash; Chassez de vos esprits tout ce qui a pu vous appara&icirc;tre de pr\u00e9cis et de pr\u00e9visions structur\u00e9es dans les quelques textes d\u00e9j\u00e0 parus sur le Tome-III de La Gr\u00e2ce de l&rsquo;Histoire, comme par exemple les deux derniers du 11 novembre 2018 et du 10&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[7046,10435,8675,2631,3969,8911,10792,8386,16755,10928,19538],"class_list":["post-78989","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-7046","tag-amazon","tag-avertissement","tag-de","tag-grace","tag-introduction","tag-l","tag-lhistoire","tag-orque","tag-parution","tag-tomme-iii"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78989"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78989\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}