{"id":79006,"date":"2019-12-14T13:57:08","date_gmt":"2019-12-14T13:57:08","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/14\/comment-boeing-se-suicide\/"},"modified":"2019-12-14T13:57:08","modified_gmt":"2019-12-14T13:57:08","slug":"comment-boeing-se-suicide","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/14\/comment-boeing-se-suicide\/","title":{"rendered":"Comment Boeing se suicide"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Comment Boeing se suicide<\/h2>\n<\/p>\n<p><p>On sait que l&rsquo;affaire Boeing-737Max est devenue une crise en soi, qui m\u00e9rite d&rsquo;\u00eatre suivie avec attention dans la mesure o&ugrave; elle refl\u00e8te bien les comportements et l&rsquo;\u00e9volution du <em>Corporate Power  <\/em>dans cette \u00e9poque de crise g\u00e9n\u00e9rale, ou Grande Crise d&rsquo;Effondrement du Syst\u00e8me. La crise Boeing-737Max est d&rsquo;autant plus int\u00e9ressante qu&rsquo;elle r\u00e9unit des \u00e9l\u00e9ments fondamentaux de la postmodernit\u00e9 et de notre contre-civilisation :<\/p>\n<\/p>\n<p><p>&bull; un ensemble crisique type du syst\u00e8me de l&rsquo;am\u00e9ricanisme ;<\/p>\n<p>&bull; une entreprise gigantesque du point de vue du capitalisme am\u00e9ricaniste et globalis\u00e9, c&rsquo;est-\u00e0-dire des points de vue financier et commercial, comme deuxi\u00e8me entreprise des USA en volume financier et premier exportateur des USA ;<\/p>\n<p>&bull; une entreprise qui con\u00e7oit et fabrique des produits \u00e0 l&rsquo;avant-garde de la technologie op\u00e9rationnelle ;<\/p>\n<p>&bull; une entreprise qui, dans sa production a\u00e9ronautique, est aussi active dans le secteur civil que dans le secteur militaire.<\/p>\n<\/p>\n<blockquote>\n<p><p>Le caract\u00e8re unique et \u00ab\u00a0exceptionnaliste\u00a0\u00bb (comme sont les USA) de Boeing est en train de nous appara&icirc;tre comme tr\u00e8s largement \u00e9quilibr\u00e9, comme par un effet-miroir invers\u00e9, par le \u00ab\u00a0caract\u00e8re unique et &lsquo;exceptionnaliste'\u00a0\u00bb de la catastrophe qui est en train de se d\u00e9velopper en son sein. Une audition de t\u00e9moins venus de Boeing et de la FAA, mercredi devant la Commission des Transports de la Chambre des Repr\u00e9sentants, a permis de prendre une nouvelle mesure de cet \u00e9v\u00e9nement qui progresse, souvent d&rsquo;une fa\u00e7on feutr\u00e9e et dissimul\u00e9e, mais qui se signalent tout de m\u00eame par  <a href=\"https:\/\/www.dedefensa.org\/article\/impasse-du-cul-de-sac-les737max-papers\">de brutales incursions<\/a> dans la progression de la  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>  s&rsquo;accordant parfaitement au processus \u00e9ventuellement <em><a href=\"https:\/\/www.dedefensa.org\/article\/lere-dupost-simulacre\">post-simulacre<\/a><\/em>  que nous d\u00e9crivions hier.<\/p>\n<\/p>\n<p><p>Le <em>cover-up <\/em>(dissimulation, \u00e9touffement) de la catastrophe semble devenir impossible, justement \u00e0 cause de l&rsquo;ampleur de la catastrophe et des \u00ab\u00a0fuites\u00a0\u00bb sans nombre, officialis\u00e9es, institutionnalis\u00e9es, de la part d&rsquo;acteurs du drame, notamment ceux qui le virent venir et tent\u00e8rent de pr\u00e9venir les dirigeants.  Cette impossibilit\u00e9 possible du <em>cover-up  <\/em>ferait ainsi partie de l&rsquo;arsenal de notre hypoth\u00e8se sur une \u00e9poque <em>post-<\/em>simulacre.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ci-dessous, nous reprenons un texte de <em>WSWS.org <\/em>qui poursuit bien entendu Boeing de ses foudres trotskistes et anticapitalistes et qui, dans ce cas, comme ce l&rsquo;est dans diverses occasions o&ugrave; nous utilisions cette source, fournit une excellente documentation qui est \u00e0 notre sens beaucoup plus de caract\u00e8re antiSyst\u00e8me que de caract\u00e8re trotskiste. C&rsquo;est le caract\u00e8re antiSyst\u00e8me, d&rsquo;o&ugrave; qu&rsquo;il vienne, qui nous int\u00e9resse et nous laissons le caract\u00e8re trotskiste \u00e0 ceux qui en r\u00eavent encore et toujours. <\/p>\n<\/p>\n<p><p>Ce que nous montrent les diff\u00e9rents \u00e9l\u00e9ments de t\u00e9moignage entendus \u00e0 la Chambre, &ndash; sans que la Chambre, pourrie jusqu&rsquo;\u00e0 l&rsquo;os, notamment par le pr\u00e9bendes de Boeing, ne s&rsquo;en \u00e9meuve vraiment, &ndash; c&rsquo;est l&rsquo;extr\u00eame profondeur du cancer qui ronge Boeing. Cela concerne certes le 737Max, mais aussi la mani\u00e8re de produire, les pressions sur le personnel tr\u00e8s qualifi\u00e9 mais qui perd cette qualification sous la force de ces pressions, l&rsquo;affichage sans aucune retenue du changement ontologique qui a affect\u00e9 cette compagnie qui est historiquement l&rsquo;une des premi\u00e8res, chronologiquement et qualitativement, de l&rsquo;histoire de l&rsquo;aviation.<\/p>\n<\/p>\n<p><p>Le principal t\u00e9moin Ed Pierson, cadre sup\u00e9rieur de chez Boeing, a ainsi rapport\u00e9 la r\u00e9ponse de son sup\u00e9rieur, vice-pr\u00e9sident de Boeing et responsable du programme 737Max, \u00e0 qui il demandait de ralentir la cadence forc\u00e9e de production et de r\u00e9organiser les \u00e9quipes affect\u00e9es \u00e0 cette production, &ndash; ce qui impliquait une interruption puis une reprise moins rapide de la production, &ndash; avec r\u00e9ponse dans ces termes : &laquo; <em>Nous ne pouvons pas faire \u00e7a. Je ne peux pas faire \u00e7a <\/em>[parce que Boeing est] <em>une organisation \u00e0 but lucratif. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le fric, pas les avions, &ndash; et quant aux passagers&#8230;<\/p>\n<\/p>\n<p><p>Tout est \u00e0 l&rsquo;aune de cet \u00e9pisode qui nous dit que Boeing en tant que tel qu&rsquo;il fut dans l&rsquo;histoire n&rsquo;existe plus. Boeing n&rsquo;est plus guid\u00e9 que par les b\u00e9n\u00e9fices, les revenus, l&rsquo;argent et rien d&rsquo;autre, et tous les imp\u00e9ratifs de qualit\u00e9 et de s\u00e9curit\u00e9 sont d\u00e9sormais, et \u00e0 notre sens irr\u00e9m\u00e9diablement, pass\u00e9s au second plan&#8230; \u00ab\u00a0Irr\u00e9m\u00e9diablement\u00a0\u00bb en effet, \u00e0 cause du changement de nature de Boeing, de son ontologie compl\u00e8tement diff\u00e9rente de ce qu&rsquo;elle fut jusqu&rsquo;\u00e0 quelque part autour de 1975-1985. Le temps \u00e9coul\u00e9 entre ces dates et aujourd&rsquo;hui, et la trag\u00e9die du 737Max, correspond au temps n\u00e9cessaire pour cette op\u00e9ration fondamentale du \u00ab\u00a0changement d&rsquo;\u00eatre\u00a0\u00bb. On ne revient pas sur de telles perversions qui tuent le pass\u00e9 et ce qui a exist\u00e9, c&rsquo;est-\u00e0-dire la tradition.<\/p>\n<\/p>\n<p><p>(Eh certes oui, l&rsquo;on peut parler de \u00ab\u00a0tradition\u00a0\u00bb qui est un facteur relatif, et dans le cas de Boeing la \u00ab\u00a0tradition\u00a0\u00bb est celle de ses d\u00e9buts puis de ses succ\u00e8s appuy\u00e9s sur le savoir-faire de ces d\u00e9buts, et c&rsquo;est cela qui est rompu tant la modernit\u00e9 ne cesse de se d\u00e9vorer elle-m\u00eame \u00e0 mesure qu&rsquo;elle avance, pour ne jamais d\u00e9pendre de structures stables et harmonieuses, et pouvoir terminer dans ce qu&rsquo;il y a de plus volatile, de plus simulacre, de plus \u00ab\u00a0absence d&rsquo;\u00eatre\u00a0\u00bb, &ndash; la financiarisation postmoderne, clef de voute de l&rsquo;effondrement.)<\/p>\n<\/p>\n<p><p>Bien entendu, nous croyons plus que jamais \u00e0 &laquo; <em><a href=\"https:\/\/www.dedefensa.org\/article\/la-cataracte-boeing\">la cataracte Boeing<\/a><\/em> &raquo;, c&rsquo;est-\u00e0-dire \u00e0 la catastrophe de l&rsquo;effondrement de l&rsquo;avionneur. Lorsque, dans son z\u00e8le \u00e0 montrer la cupidit\u00e9 et l&rsquo;injustice du capitalisme, le texte de <em>WSWS.org  <\/em>indique &laquo; <em>Alors que l&rsquo;immobilisation du Max 8 et les poursuites par les pilotes et les proches des victimes devraient co&ucirc;ter 8 milliards de dollars \u00e0 Boeing, la valeur de la soci\u00e9t\u00e9 a augment\u00e9 de pr\u00e8s de 200 milliards de dollars entre le moment o&ugrave; les avions ont \u00e9t\u00e9 annonc\u00e9s en 2011 et le moment o&ugrave; l&rsquo;ensemble de la flotte a \u00e9t\u00e9 clou\u00e9 au sol<\/em> &raquo;, &ndash; bien, s&ucirc;r, il p\u00eache par militantisme tactique et nous donne une fausse image de la v\u00e9rit\u00e9 de situation.<\/p>\n<\/p>\n<p><p>C&rsquo;est \u00ab\u00a0jusqu&rsquo;ici\u00a0\u00bb qu&rsquo;il faut dire \u00e0 propos des $8 milliards que devraient co&ucirc;ter \u00e0 Boeing &laquo; <em>l&rsquo;immobilisation du Max 8 et les poursuites par les pilotes et les proches des victimes<\/em> &raquo;. En effet, cette affaire ne fait que commencer et Boeing a d\u00e9j\u00e0 subi, en plus des $8 milliards, des pertes de manque-\u00e0-gagner avec plus de 250 avions command\u00e9s chez Airbus par trois compagnies, qui s&rsquo;\u00e9taient auparavant d\u00e9cid\u00e9 pour le 737Max. Les pertes \u00e0 pr\u00e9voir, non seulement pour des raisons techniques et de s\u00e9curit\u00e9 des appareils, mais aussi et surtout de confiance dans toutes les productions Boeing sont colossales et finalement \u00e0 la mesure d&rsquo;un \u00e9branlement d\u00e9cisif vers l&rsquo;effondrement de ce g\u00e9ant <em>too big to fail\/to fall<\/em>. Ce n&rsquo;est pas la logique historique de la \u00ab\u00a0r\u00e9volution permanente\u00a0\u00bb trotskiste qui menace Boeing, mais la logique pr\u00e9datrice et autodestructrice du n\u00e9o-capitalisme ultralib\u00e9ral.<\/p>\n<\/p>\n<p><p>Le texte ci-dessous, de <em>WSWS.org <\/em>est du <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2019\/12\/14\/pers-d14.html\">14 d\u00e9cembre 2019<\/a> (traduction de la version originale en anglais du <a href=\"https:\/\/www.wsws.org\/en\/articles\/2019\/12\/13\/pers-d13.html\">13 d\u00e9cembre 2019<\/a>).<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les dirigeants de Boeing doivent rendre des comptes<\/h2>\n<\/p>\n<p><p>L&rsquo;ancien cadre sup\u00e9rieur de Boeing Ed Pierson a t\u00e9moign\u00e9 mercredi devant la commission des transports et des infrastructures de la Chambre des Repr\u00e9sentants qu&rsquo;il avait averti la haute direction de l&rsquo;entreprise \u00e0 deux reprises au cours de l&rsquo;\u00e9t\u00e9 2018 que &laquo;la d\u00e9t\u00e9rioration des conditions \u00e0 l&rsquo;usine&raquo; de production du Boeing 737 de Renton, dans l&rsquo;&Eacute;tat de Washington, entra&icirc;nerait in\u00e9vitablement une production d&rsquo;avions d\u00e9faillants et potentiellement mortels.<\/p>\n<\/p>\n<p><p>Le rapport de cet ex-employ\u00e9 r\u00e9v\u00e8le un autre niveau de la criminalit\u00e9 et de la n\u00e9gligence des dirigeants de Boeing dans leur volont\u00e9 de g\u00e9n\u00e9rer des b\u00e9n\u00e9fices de plusieurs milliards de dollars avec l&rsquo;avion 737 Max 8. Ce fut un autre avertissement, cette fois par un travailleur qui produisait ces avions, que les conditions dans l&rsquo;usine compromettaient la s\u00e9curit\u00e9 de dizaines d&rsquo;avions qui pourraient \u00e9ventuellement transporter des centaines de milliers d&rsquo;hommes, de femmes et d&rsquo;enfants.<\/p>\n<\/p>\n<p><p>Les craintes de Pierson se sont r\u00e9alis\u00e9es quatre mois apr\u00e8s son deuxi\u00e8me avertissement lorsque le vol 610 de Lion Air a plong\u00e9 dans la mer de Java apr\u00e8s avoir d\u00e9coll\u00e9 de Jakarta, en Indon\u00e9sie, tuant les 189 passagers et membres d&rsquo;\u00e9quipage \u00e0 bord. Cela a \u00e9t\u00e9 suivi d&rsquo;un deuxi\u00e8me crash d&rsquo;un avion Max 8 juste aux abords d&rsquo;Addis-Abeba, le vol 302 d&rsquo;Ethiopian Airlines, qui a an\u00e9anti la vie de 157 autres \u00eatres humains.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est qu&rsquo;apr\u00e8s le deuxi\u00e8me crash que Boeing a d\u00e9cid\u00e9 de clouer au sol l&rsquo;avion meurtrier dans le monde entier, et cela ne s&rsquo;est produit qu&rsquo;apr\u00e8s que l&rsquo;indignation internationale a mont\u00e9 lorsque Boeing a d\u00e9clar\u00e9 deux jours apr\u00e8s le deuxi\u00e8me crash qu&rsquo;ils avaient &laquo;pleinement confiance en la s\u00e9curit\u00e9 du 737 Max&raquo;. Ces commentaires ont \u00e9t\u00e9 soutenus et repris par la Federal Aviation Administration (FAA) et le pr\u00e9sident am\u00e9ricain Donald Trump.<\/p>\n<\/p>\n<p><p>La m\u00eame audience du Congr\u00e8s a \u00e9galement r\u00e9v\u00e9l\u00e9 que le mois suivant le premier accident, une analyse interne de la FAA a d\u00e9termin\u00e9 que, \u00e0 moins que l&rsquo;avion ne soit immobilis\u00e9, le Max 8 ferait l&rsquo;objet en moyenne d&rsquo;un accident mortel tous les deux ou trois ans, une quantit\u00e9 sup\u00e9rieure \u00e0 celle indiqu\u00e9e par Boeing ou l&rsquo;agence \u00e0 l&rsquo;\u00e9poque. Ce rapport a \u00e9t\u00e9 \u00e9cart\u00e9 par l&rsquo;agence pendant plus d&rsquo;un an, m\u00eame apr\u00e8s le deuxi\u00e8me crash en moins de six mois.<\/p>\n<\/p>\n<p><p>La raison imm\u00e9diate de ces deux accidents \u00e9tait un logiciel auparavant inconnu appel\u00e9 syst\u00e8me d&rsquo;augmentation des caract\u00e9ristiques de man&oelig;uvre (MCAS), qui s&rsquo;est activ\u00e9 par erreur en raison d&rsquo;un capteur d&rsquo;angle d&rsquo;attaque d\u00e9fectueux et a forc\u00e9 les deux avions \u00e0 plonger de fa\u00e7on incontr\u00f4lable. Les capteurs, a not\u00e9 Pierson, rempla\u00e7aient les originaux \u00e9galement d\u00e9fectueux, ce qui n&rsquo;aurait pas d&ucirc; se produire sur des avions vieux de quelques mois seulement. Ces faits mettaient en \u00e9vidence  de graves probl\u00e8mes dans le processus de production elle-m\u00eame du Max 8.<\/p>\n<\/p>\n<p><p>Dans un courriel de juin 2018 adress\u00e9 au vice-pr\u00e9sident de Boeing, Scott Campbell responsable du programme Max 8, Pierson a averti que &laquo;franchement, toutes les sonneries d&rsquo;alarme sont activ\u00e9es dans mon jugement&raquo;. Il a explicitement not\u00e9 le manque de m\u00e9caniciens, d&rsquo;\u00e9lectriciens et de techniciens qualifi\u00e9s, un taux d&rsquo;heures suppl\u00e9mentaires qui a plus que doubl\u00e9 et qui affecte l&rsquo;attention des travailleurs. Il a ajout\u00e9 que &laquo;pour la premi\u00e8re fois de ma vie, je suis d\u00e9sol\u00e9 de dire que j&rsquo;h\u00e9site \u00e0 faire monter ma famille dans un avion Boeing.&raquo;<\/p>\n<\/p>\n<p><p>Dans ses commentaires devant le Congr\u00e8s, Pierson a soulign\u00e9 &laquo;la pression dogmatique exerc\u00e9e sur le calendrier&raquo; apr\u00e8s que l&rsquo;entreprise ait exig\u00e9 que l&rsquo;usine augmente la production du nombre d&rsquo;avions qu&rsquo;elle fabrique de 47 \u00e0 52 par mois, avec l&rsquo;augmentation des &laquo;risques pour la s\u00e9curit\u00e9 des produits et des travailleurs.&raquo;<\/p>\n<\/p>\n<p><p>En cons\u00e9quence, les mesures de suivi de la qualit\u00e9 interne de Boeing ont r\u00e9v\u00e9l\u00e9 une augmentation de 30 pour cent de d\u00e9fauts d&rsquo;ing\u00e9nierie et de c\u00e2blage, qui peuvent tous provoquer des pannes ou des incidents potentiellement mortels dans un avion. Tout cela aurait pu avoir un effet sur les d\u00e9faillances des capteurs MCAS. Afin de r\u00e9soudre ces probl\u00e8mes, Pierson a affirm\u00e9 qu&rsquo;il \u00e9tait n\u00e9cessaire de fermer l&rsquo;usine &laquo;pour permettre \u00e0 notre \u00e9quipe de se regrouper afin que nous puissions terminer les avions en toute s\u00e9curit\u00e9&raquo;.<\/p>\n<\/p>\n<p><p>Alors m\u00eame que les conditions de production se d\u00e9gradaient, les dirigeants de Boeing ont continu\u00e9 \u00e0 ignorer les averissements de Pierson. Lors d&rsquo;une r\u00e9union entre Pierson et Campbell, au cours de laquelle le premier a r\u00e9it\u00e9r\u00e9 son appel \u00e0 arr\u00eater la production pour r\u00e9pondre \u00e0 des probl\u00e8mes de s\u00e9curit\u00e9 av\u00e9r\u00e9s, le responsable du programme 737 Max lui a dit: &laquo;Nous ne pouvons pas faire \u00e7a. Je ne peux pas faire \u00e7a&raquo; parce que Boeing est &laquo;une organisation \u00e0 but lucratif&raquo;.<\/p>\n<\/p>\n<p><p>La cupidit\u00e9 sans g\u00eane incarn\u00e9e dans cette d\u00e9claration ne donne qu&rsquo;un aper\u00e7u des \u00e9normes sommes d&rsquo;argent que Boeing a gagn\u00e9es gr\u00e2ce au programme Max 8. Alors que l&rsquo;immobilisation du Max 8 et les poursuites par les pilotes et les proches des victimes devraient co&ucirc;ter 8 milliards de dollars \u00e0 Boeing, la valeur de la soci\u00e9t\u00e9 a augment\u00e9 de pr\u00e8s de 200 milliards de dollars entre le moment o&ugrave; les avions ont \u00e9t\u00e9 annonc\u00e9s en 2011 et le moment o&ugrave; l&rsquo;ensemble de la flotte a \u00e9t\u00e9 clou\u00e9 au sol.<\/p>\n<\/p>\n<p><p>Les dirigeants de Boeing eux-m\u00eames ont \u00e9galement fait d&rsquo;immenses fortunes personnelles. Lors de la mont\u00e9e fulgurante des actions de la soci\u00e9t\u00e9 en janvier et f\u00e9vrier de cette ann\u00e9e, le directeur financier Gregory Smith, le vice-pr\u00e9sident ex\u00e9cutif John Keating, l&rsquo;avocat g\u00e9n\u00e9ral Michael Luttig et le directeur g\u00e9n\u00e9ral Dennis Muilenberg ont tous vendu des actions pour une valeur de 9,5 millions de dollars, 10,1 millions de dollars, 9,5 millions de dollars et 6,5 millions de dollars respectivement.<\/p>\n<\/p>\n<p><p>Ces chiffres d\u00e9mentent les larmes de crocodile que la direction de Boeing a vers\u00e9es, surtout quand on se rend compte que le deuxi\u00e8me crash du Max 8 s&rsquo;est produit juste un mois apr\u00e8s ces fructueuses op\u00e9rations boursi\u00e8res. &Eacute;taient-ils conscients des dangers de l&rsquo;avion et, plut\u00f4t que d&rsquo;avertir leurs pilotes et passagers, ont-ils profit\u00e9 de l&rsquo;occasion pour en tirer profit ?<\/p>\n<\/p>\n<p><p>On ne peut pas non plus passer sous silence les remarques faites par les Repr\u00e9sentants de la commission des transports de la Chambre. En r\u00e9ponse \u00e0 la publication du document interne de la FAA, le repr\u00e9sentant d\u00e9mocrate Peter DeFazio de l&rsquo;Oregon a d\u00e9clar\u00e9: &laquo; Malgr\u00e9 ses propres calculs, la FAA a voulu parier avec la s\u00e9curit\u00e9 du public en laissant le 737 Max continuer \u00e0 voler.&raquo; Le pr\u00e9sident de la sous-commission de Transport de la Chambre n&rsquo;a fait aucune mention du fait que lui et ses coll\u00e8gues avaient r\u00e9cemment adopt\u00e9 la loi sur la r\u00e9-autorisation de la FAA, qui donne \u00e0 Boeing et \u00e0 d&rsquo;autres constructeurs d&rsquo;avions encore plus de libert\u00e9 \u00e0 l&rsquo;\u00e9gard de la r\u00e9glementation et de la surveillance.<\/p>\n<\/p>\n<p><p>De plus, le gouvernement am\u00e9ricain ainsi que des municipalit\u00e9s et des &Eacute;tats f\u00e9d\u00e9r\u00e9s ont subventionn\u00e9 les op\u00e9rations de Boeing. Depuis 1994, Boeing a re\u00e7u 74 milliards de dollars de subventions et de pr\u00eats gouvernementaux, dont 14 milliards proviennent uniquement de l&rsquo;&Eacute;tat de Washington [o&ugrave; sont install\u00e9es les usines Boeing]. Cet argent a \u00e9t\u00e9 pr\u00e9lev\u00e9 directement de la classe ouvri\u00e8re et d\u00e9pos\u00e9 dans les poches des dirigeants et des gros actionnaires de la soci\u00e9t\u00e9.<\/p>\n<\/p>\n<p><p>Cela montre clairement la relation entre le gouvernement am\u00e9ricain et Boeing, le deuxi\u00e8me plus grand entrepreneur de d\u00e9fense du pays et le plus gros exportateur US. Ils n&rsquo;ont pas de relation contradictoire, mais repr\u00e9sentent plut\u00f4t le lien entre le <em>Corporate Power<\/em>, l&rsquo;&Eacute;tat et <em>l&rsquo;establishment <\/em>militaire.<\/p>\n<\/p>\n<p><p>Malgr\u00e9 des preuves \u00e9videntes et croissantes de la n\u00e9gligence criminelle de la part des dirigeants de Boeing qui a caus\u00e9 la mort de plus de 300 personnes, aucune accusation p\u00e9nale n&rsquo;a \u00e9t\u00e9 port\u00e9e contre les responsables concern\u00e9s. Cela est tout \u00e0 fait dans la ligne judiciaire \u00e9tablie ces temps-ci, o&ugrave; m\u00eame les d\u00e9lits de grandes entreprises les plus horribles n&rsquo;ont donn\u00e9 lieu \u00e0 aucune poursuite. Mais la justice pour les victimes, sans parler de la s\u00e9curit\u00e9 du public, exige que les cadres sup\u00e9rieurs et les responsables gouvernementaux impliqu\u00e9s dans ces crimes soient tenus de rendre des comptes.<\/p>\n<\/p>\n<p><p>Ces liens et les catastrophes des Max 8 ne sont pas simplement des sympt\u00f4mes de la cupidit\u00e9 des grandes entreprises, mais le r\u00e9sultat final du syst\u00e8me capitaliste lui-m\u00eame, qui subordonne tous les besoins sociaux au profit priv\u00e9. Il existe une contradiction fondamentale entre les int\u00e9r\u00eats de la soci\u00e9t\u00e9, y compris le transport a\u00e9rien s&ucirc;r, efficace et peu co&ucirc;teux, et la propri\u00e9t\u00e9 priv\u00e9e des industries essentielles, ainsi que la division de l&rsquo;\u00e9conomie mondiale entre les &Eacute;tats-nations rivaux. Les m\u00eames contradictions fondamentales du capitalisme alimentent les conflits g\u00e9opolitiques et \u00e9conomiques qui menacent le monde de guerre nucl\u00e9aire et de catastrophes \u00e9cologiques.<\/p>\n<\/p>\n<p><p>La seule fa\u00e7on de pr\u00e9venir de nouvelles catastrophes est de supprimer le but lucratif dans l&rsquo;industrie des avions de lignes, de mettre fin \u00e0 la domination de Wall Street et de remplacer le cauchemar du march\u00e9 capitaliste par un syst\u00e8me de transport a\u00e9rien planifi\u00e9 de mani\u00e8re rationnelle et organis\u00e9 au niveau international. Cela n\u00e9cessite la nationalisation des compagnies a\u00e9riennes et a\u00e9rospatiales et leur transformation en services publics appartenant \u00e0 la collectivit\u00e9 et contr\u00f4l\u00e9s d\u00e9mocratiquement.<\/p>\n<\/p>\n<p><h4>Bryan Dyne, <em>WSWS.org<\/em><\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment Boeing se suicide On sait que l&rsquo;affaire Boeing-737Max est devenue une crise en soi, qui m\u00e9rite d&rsquo;\u00eatre suivie avec attention dans la mesure o&ugrave; elle refl\u00e8te bien les comportements et l&rsquo;\u00e9volution du Corporate Power dans cette \u00e9poque de crise g\u00e9n\u00e9rale, ou Grande Crise d&rsquo;Effondrement du Syst\u00e8me. La crise Boeing-737Max est d&rsquo;autant plus int\u00e9ressante qu&rsquo;elle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3192,6045,2651,17035,19564,7865,13898,19563,3286,3534,18222],"class_list":["post-79006","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-boeing","tag-catastrophe","tag-du","tag-ed","tag-existe","tag-faire","tag-financiarisation","tag-pierson","tag-pour","tag-production","tag-profit"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79006"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79006\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}