{"id":79028,"date":"2019-12-28T15:30:21","date_gmt":"2019-12-28T15:30:21","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/28\/lalgerie-pivot-strategique-a-la-russe\/"},"modified":"2019-12-28T15:30:21","modified_gmt":"2019-12-28T15:30:21","slug":"lalgerie-pivot-strategique-a-la-russe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/28\/lalgerie-pivot-strategique-a-la-russe\/","title":{"rendered":"L&rsquo;Alg\u00e9rie, pivot strat\u00e9gique \u00e0-la-russe"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">L&rsquo;Alg\u00e9rie, pivot strat\u00e9gique \u00e0-la-russe<\/h2>\n<\/p>\n<p><p>Ces derniers mois et m\u00eame ces derni\u00e8res ann\u00e9es, l&rsquo;Alg\u00e9rie s&rsquo;est essentiellement signal\u00e9e du fait de ses probl\u00e8mes int\u00e9rieurs. La France a d&rsquo;ailleurs pris l&rsquo;habitude de consid\u00e9rer ce pays de ce seul point de vue en y int\u00e9grant des relations France-Alg\u00e9rie marqu\u00e9es par l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a>et une incroyable comp\u00e9tition de culpabilisation et de repentance plongeant au c&oelig;ur des pathologies psychologiques qui sont la marque tr\u00e8s caract\u00e9ristique de cette \u00e9trange \u00e9poque. De ce fait, la France, qui s&rsquo;affiche \u00ab\u00a0grande puissance m\u00e9diterran\u00e9enne\u00a0\u00bb, n&rsquo;a aucune politique strat\u00e9gique fondamentale avec l&rsquo;Alg\u00e9rie, qui est l&rsquo;un des pays m\u00e9diterran\u00e9ens les plus importants, et certainement le pays musulman qui joue un r\u00f4le strat\u00e9gique pivot dans la M\u00e9diterran\u00e9e occidentale et entre l&rsquo;Afrique et l&rsquo;Europe. Par contre, la Russie, elle, a certainement une politique strat\u00e9gique vis-\u00e0-vis de l&rsquo;Alg\u00e9rie.<\/p>\n<\/p>\n<p><p>Les Russes font de plus en plus leur la fameuse politique ext\u00e9rieure de l&rsquo;armement (gr\u00e2ce \u00e0 l&rsquo;armement) selon la notion d\u00e9velopp\u00e9e par la France gaulliste dans les ann\u00e9es 1960, c&rsquo;est-\u00e0-dire sans faire peser sur les acheteurs les contraintes qu&rsquo;imposent les USA \u00e0 leurs clients. Les Russes montrent ce qui semble bien \u00eatre une politique strat\u00e9gique avec le march\u00e9 qu&rsquo;ils ont pass\u00e9 avec l&rsquo;Alg\u00e9rie, qui est constitu\u00e9 d&rsquo;une triple commande de trois types d&rsquo;avions les plus avanc\u00e9s de l&rsquo;arsenal russe, et les plus aptes \u00e0 transformer le facteur tactique de l&rsquo;aviation de combat en d\u00e9ploiement strat\u00e9gique.<\/p>\n<\/p>\n<p><p>De ce point de vue de l&rsquo;importance qualitative des mat\u00e9riels, la commande alg\u00e9rienne, qui est annonc\u00e9e quelques jours apr\u00e8s l&rsquo;\u00e9lection pr\u00e9sidentielle, offre un autre \u00e9clairage sur la crise alg\u00e9rienne en cours, une \u00e9clairage plus marqu\u00e9 par la situation de la politique ext\u00e9rieure que par les \u00e9v\u00e9nements int\u00e9rieurs comme elle l&rsquo;est en g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>L&rsquo;Alg\u00e9rie annonce donc trois commandes :<\/p>\n<\/p>\n<p><p>&bull; 14 Su-34, avion d&rsquo;attaque au sol de p\u00e9n\u00e9tration profonde, dont les performances en autonomie et en capacit\u00e9s \u00e9lectroniques font un avion de combat tactique \u00e0 la limite du strat\u00e9gique.<\/p>\n<p>&bull; 14 Su-35, les chasseurs de sup\u00e9riorit\u00e9 a\u00e9rienne les plus avanc\u00e9s de la Russie, qui sont \u00e0 classer dans la premi\u00e8re cat\u00e9gorie au monde de ce type d&rsquo;avion de combat ;<\/p>\n<p>&bull; 14 Su-57, le nouvel avion de combat russe, employant des technologies furtives comme les F-22 et F-35 US, et class\u00e9 comme avion de combat de la 5<sup>\u00e8me<\/sup>g\u00e9n\u00e9ration.<\/p>\n<\/p>\n<p><p>Ci-dessous, <em>Spoutnik<\/em>pr\u00e9sente la commande alg\u00e9rienne et divers commentaires d&rsquo;experts alg\u00e9riens. On voit que toutes les dimensions strat\u00e9giques sont prises en compte pour expliquer ces commandes qualitativement tr\u00e8s importantes : que ce soit la situation \u00e0 l&rsquo;Est (le ministre libyen de l&rsquo;int\u00e9rieur apr\u00e8s sa rencontre avec le ministre de l&rsquo;int\u00e9rieur alg\u00e9rien <a href=\"https:\/\/www.dzairdaily.com\/libye-tripoli-alger-algerie-ministre-libyen\/\">le 26 d\u00e9cembre<\/a> : &laquo; <em>Si Tripoli tombe <\/em>[dans les mains du mar\u00e9chal Khalifa Haftar]<em>, Tunis et Alger tomberont \u00e0 leur tour <\/em>&raquo;) ; que ce soit la situation au Sud  (dans le Sahel avec les troubles en cours) ; mais \u00e9galement et de mani\u00e8re beaucoup plus int\u00e9ressante du point de vue politique dans cette politique strat\u00e9gique, que ce soit la situation en M\u00e9diterran\u00e9e et au Nord, en Europe dans la zone OTAN.<\/p>\n<\/p>\n<p><p>Ainsi, les Alg\u00e9riens semblent justifier l&rsquo;achat du Su-57 par l&rsquo;\u00e9quipement de F-35 <em>Lightning<\/em>II, avion de 5<sup>\u00e8me<\/sup>g\u00e9n\u00e9ration \u00e0 technologies furtives, de pays riverains du Nord, comme l&rsquo;Italie principalement, en tant que membre de l&rsquo;OTAN. (Avec l&rsquo;argument compl\u00e9mentaire dans ce cas de la possession par Isra\u00ebl des m\u00eames F-35 justifiant l&rsquo;achat de Su-57.) On observera avec int\u00e9r\u00eat cette mont\u00e9e de l&rsquo;escalade dans l&rsquo;\u00e9quilibre des forces, \u00e0 partir d&rsquo;avions, et essentiellement du F-35 dont on est toujours en train de se demander quel sont son int\u00e9r\u00eat et, encore plus, ou encore moins, son efficacit\u00e9. Mais peu importe : aujourd&rsquo;hui, la strat\u00e9gie se r\u00e8gle elle aussi par la communication, le plus souvent sans rapport avec la r\u00e9alit\u00e9 dont il ne reste que quelques d\u00e9bris \u00e9pars, et ainsi la situation strat\u00e9gique \u00e9volue-t-elle de fa\u00e7on radicale \u00e0 partir de <em>narrative <\/em>diverses. Par cons\u00e9quent et selon la formule consacr\u00e9e, &ndash; quoi qu&rsquo;il en soit, il s&rsquo;agit sans aucun doute d&rsquo;une perspective particuli\u00e8rement importante que l&rsquo;Alg\u00e9rie puisse se mettre en position d&rsquo;\u00e9quilibrer une soi-disant puissance a\u00e9rienne de l&rsquo;OTAN, dans le chef de l&rsquo;Italie pourtant bien pacifique, avec ses JSF.<\/p>\n<\/p>\n<blockquote>\n<p><p>Dans ce cas, il y a strat\u00e9gie-bouffe comme il y a <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a>, c&rsquo;est-\u00e0-dire un v\u00e9ritable d\u00e9placement strat\u00e9gique pour des arguments relevant en g\u00e9n\u00e9ral du facteur bouffe si important dans notre \u00e9poque. (Le F-35, facteur\/acteur-bouffe.) Quoi qu&rsquo;il en soit (suite), le r\u00e9sultat sera sans aucun doute passionnant de retrouver l&rsquo;Alg\u00e9rie en position de d\u00e9fiance vis-\u00e0-vis du poids op\u00e9rationnel suppos\u00e9e de l&rsquo;OTAN, alors qu&rsquo;elle se trouve fermement avec la Tunisie au c\u00f4t\u00e9 de la Turquie contre le mar\u00e9chal Haftar, &ndash; la Turquie, pays de l&rsquo;OTAN \u00e9galement, mais sans doute priv\u00e9 de F-35, peut-\u00eatre bien acqu\u00e9reur un jour de Su-57.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>D\u00e9cid\u00e9ment, strat\u00e9gie-bouffe pour qui observe cette sc\u00e8ne dans tous ses composants mais n\u00e9anmoins strat\u00e9gie, quoi qu&rsquo;on en veuille. Si l&rsquo;Alg\u00e9rie s&rsquo;affirme comme un p\u00f4le neutre de stabilisation strat\u00e9gique, un des experts (l&rsquo;ex-g\u00e9n\u00e9ral Larbi Ch\u00e9rif) interrog\u00e9s dans le texte de Kamal Louadj, de <em>Spoutnik<\/em>, ce <a href=\"https:\/\/fr.sputniknews.com\/maghreb\/201912271042670860-lacquisition-de-su-57-par-lalgerie-est-une-revolution-sur-le-flanc-ouest-de-la-mediterranee\/\">28 d\u00e9cembre 2019<\/a>, explique l&rsquo;omportance strat\u00e9gique de ces acquisitions de mat\u00e9riels (russes) notamment par ce constat : &laquo; <em>Car bien que le projet am\u00e9ricain du Grand Moyen-Orient ait \u00e9chou\u00e9 pour l&rsquo;instant, rien ne dit qu&rsquo;il ne reviendrait pas sous une autre appellation<\/em> &raquo;&hellip; On voit d&rsquo;o&ugrave; vient le d\u00e9sordre&hellip;<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">R\u00e9volution : des Su-57 alg\u00e9riens <\/h2>\n<\/p>\n<blockquote>\n<p><p>L&rsquo;Alg\u00e9rie a conclu trois contrats pour l&rsquo;achat de Su-57, Su-34 et Su-35 avec 14 appareils pour chaque mod\u00e8le, a indiqu\u00e9 le site alg\u00e9rien Menadefense. Deux experts alg\u00e9riens des questions s\u00e9curitaires et de d\u00e9fense ont comment\u00e9 \u00e0 Spoutnik l&rsquo;importance strat\u00e9gique de ces nouvelles acquisitions.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;Alg\u00e9rie va acqu\u00e9rir de la part de la Russie des chasseurs furtifs Su-57, devenant ainsi le premier client \u00e0 qui le constructeur Sukhoi exportera ce fleuron de l&rsquo;aviation de combat de 5e g\u00e9n\u00e9ration, indique le site alg\u00e9rien d&rsquo;information militaire Menadefense. Par ailleurs, le m\u00e9dia pr\u00e9cise que l&rsquo;Arm\u00e9e de l&rsquo;air alg\u00e9rienne a \u00e9galement sign\u00e9 deux autres contrats portant sur l&rsquo;achat de bombardiers de type Su-34, dont elle est le premier client \u00e9galement, et des appareils de domination a\u00e9rienne Su-35.<\/p>\n<\/p>\n<p><p>Ainsi, Menadefense indique que la d\u00e9cision d&rsquo;acqu\u00e9rir 14 Su-57 a \u00e9t\u00e9 prise l&rsquo;\u00e9t\u00e9 dernier apr\u00e8s la visite d&rsquo;une d\u00e9l\u00e9gation alg\u00e9rienne au salon a\u00e9ronautique MAKS de Moscou. Selon lui, lors de cette visite, la d\u00e9l\u00e9gation alg\u00e9rienne conduite par le g\u00e9n\u00e9ral major Hamid Bouma\u00efza, commandant de l&rsquo;Arm\u00e9e de l&rsquo;air, a examin\u00e9 dans les plus infimes d\u00e9tails le chasseur en question. <a href=\"https:\/\/fr.sputniknews.com\/maghreb\/201912171042616296-quel-role-pour-les-elites-dans-le-changement-politique-en-algerie\/\">Le g\u00e9n\u00e9ral Bouma\u00efza<\/a>, ancien pilote de MiG-29, a m\u00eame \u00e9t\u00e9 un des rares \u00e9trangers \u00e0 essayer l&rsquo;avion furtif russe sur simulateur, ajoute la m\u00eame source, pr\u00e9cisant que ces accords devraient \u00eatre achev\u00e9s en 2025.<\/p>\n<\/p>\n<p><p>Par ailleurs, le m\u00e9dia indique que les Forces a\u00e9riennes alg\u00e9riennes ont conclu deux autres contrats relatifs \u00e0 l&rsquo;acquisition de 14 bombardiers \u00e0 long rayon d&rsquo;action Su-34 et de 14 appareils de sup\u00e9riorit\u00e9 a\u00e9rienne Su-35. Deux autres contrats en option pour l&rsquo;achat de Su-34 et Su-35 avec 14 appareils chacun \u00e9galement ont \u00e9t\u00e9 sign\u00e9s dans le but de remplacer les avions qui seront retir\u00e9s de la flotte de l&rsquo;Arm\u00e9e de l&rsquo;air dans les prochaines ann\u00e9es, pr\u00e9cise la m\u00eame source.<\/p>\n<\/p>\n<p><p>En 2025, l&rsquo;Arm\u00e9e de l&rsquo;air alg\u00e9rienne sera en mesure de d\u00e9ployer deux escadrons de Su-30MKA, un autre de Su-57, un de Su-35 et un de MiG-29M2. Elle aura \u00e9galement en sa possession deux escadrons de Su-24 modernis\u00e9s et un de Su-34 pour la flotte de bombardiers, rappelle le m\u00e9dia, soulignant que la formation des pilotes se fera avec des Yak-130.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Quel impact strat\u00e9gique ?<\/h3>\n<\/p>\n<p><p>Dans un entretien accord\u00e9 \u00e0 Spoutnik, Akram Kharief, expert des questions s\u00e9curitaires et de d\u00e9fense et r\u00e9dacteur en chef et \u00e9diteur du site Menadefense, a affirm\u00e9 que c&rsquo;est &laquo;l&rsquo;apparition de F-35 dans la flotte italienne qui a motiv\u00e9 la prise de d\u00e9cision rapide de l&rsquo;Alg\u00e9rie&raquo;.<\/p>\n<\/p>\n<p><p>L&rsquo;acquisition du Su-57 par l&rsquo;Alg\u00e9rie &laquo;est une r\u00e9volution sur le flanc ouest de la M\u00e9diterran\u00e9e&raquo;, a-t-il d\u00e9clar\u00e9, pr\u00e9cisant que &laquo;c&rsquo;est la premi\u00e8re fois qu&rsquo;un avion furtif de 5e g\u00e9n\u00e9ration sera introduit en Afrique&raquo;. &laquo;C&rsquo;est in\u00e9dit \u00e9galement en M\u00e9diterran\u00e9e, car dans ce bassin il n&rsquo;y a qu&rsquo;Isra\u00ebl et l&rsquo;Italie qui disposent d&rsquo;avions furtifs en l&rsquo;occurrence le F-35&raquo;, a-t-il ajout\u00e9, pr\u00e9cisant que &laquo;m\u00eame la France n&rsquo;en dispose pas&raquo;.<\/p>\n<\/p>\n<p><p>Et d&rsquo;ajouter, M.Kharief a expliqu\u00e9 que &laquo;l&rsquo;importance strat\u00e9gique du Su-34 r\u00e9side dans le fait que cet avion est un bombardier \u00e0 long rayon d&rsquo;action capable de mener des op\u00e9rations \u00e0 des milliers de kilom\u00e8tres, ce qui \u00e9tend les possibilit\u00e9s offensives de l&rsquo;Arm\u00e9e de l&rsquo;air alg\u00e9rienne&raquo;. &laquo;Le Su-34 est \u00e9galement un avion qui est capable de se d\u00e9fendre lui-m\u00eame et qui n&rsquo;a pas besoin d&rsquo;\u00eatre accompagn\u00e9&raquo;, a-t-il indiqu\u00e9, rappelant &laquo;qu&rsquo;il a fait ses preuves dans la guerre en Syrie&raquo;.<\/p>\n<\/p>\n<p><p>De son c\u00f4t\u00e9, l&rsquo;ex-colonel des services de renseignement alg\u00e9riens, Abdelhamid Larbi Ch\u00e9rif, a expliqu\u00e9 au micro de Sputnik que &laquo;la M\u00e9diterran\u00e9e, en particulier son flanc ouest, a toujours \u00e9t\u00e9 un espace strat\u00e9gique de concurrence entre toutes les grandes puissances mondiales&raquo;. &laquo;L&rsquo;ins\u00e9curit\u00e9 qui s&rsquo;est install\u00e9e au Maghreb et au Sahel apr\u00e8s la chute en 2011 du r\u00e9gime du guide libyen Mouammar Kadhafi est une source d&rsquo;inqui\u00e9tude qui est prise tr\u00e8s au s\u00e9rieux par les autorit\u00e9s civiles et militaires alg\u00e9riennes&raquo;, a-t-il affirm\u00e9, indiquant que &laquo;ceci s&rsquo;ajoutait au red\u00e9ploiement des organisations terroristes au Maghreb et au Sahel apr\u00e8s leur d\u00e9faite en Syrie et en Irak&raquo;.<\/p>\n<\/p>\n<p><p>Dans le m\u00eame sens, l&rsquo;ex-haut grad\u00e9 a point\u00e9 &laquo;l&rsquo;\u00e9mergence de l&rsquo;importance \u00e9conomique de l&rsquo;Afrique qui suscite les convoitises de beaucoup de puissances, notamment les ex-colonisatrices&raquo;. &laquo;Pour s&rsquo;en convaincre il n&rsquo;y a qu&rsquo;\u00e0 voir les d\u00e9ploiements militaires \u00e9trangers au Mali, au Niger et ailleurs en Afrique&raquo;, a-t-il soulign\u00e9.<\/p>\n<\/p>\n<p><p>Partant de ce constat, M. Larbi Ch\u00e9rif a expliqu\u00e9 que &laquo;l&rsquo;Alg\u00e9rie qui ne participe \u00e0 aucune alliance militaire entend par l&rsquo;acquisition de ce genre d&rsquo;armements, comme les Su-57, les Su-34 et les syst\u00e8mes de d\u00e9fense antia\u00e9rienne tels que les S-300, maintenir l&rsquo;\u00e9quilibre militaire \u00e0 m\u00eame de lui permettre de d\u00e9fendre son int\u00e9grit\u00e9 territoriale et ses int\u00e9r\u00eats vitaux&raquo;. &laquo;Car bien que le projet am\u00e9ricain du Grand Moyen-Orient ait \u00e9chou\u00e9 pour l&rsquo;instant, rien ne dit qu&rsquo;il ne reviendrait pas sous une autre appellation&raquo;, a-t-il conclu.<\/p>\n<\/p>\n<p><h4>Kamal Louadj<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Alg\u00e9rie, pivot strat\u00e9gique \u00e0-la-russe Ces derniers mois et m\u00eame ces derni\u00e8res ann\u00e9es, l&rsquo;Alg\u00e9rie s&rsquo;est essentiellement signal\u00e9e du fait de ses probl\u00e8mes int\u00e9rieurs. La France a d&rsquo;ailleurs pris l&rsquo;habitude de consid\u00e9rer ce pays de ce seul point de vue en y int\u00e9grant des relations France-Alg\u00e9rie marqu\u00e9es par l&rsquo;affectivismeet une incroyable comp\u00e9tition de culpabilisation et de repentance&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2631,2969,2687,18607,19598,3442,2622,6902,584,3411,19597,18139,3519],"class_list":["post-79028","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-de","tag-f-35","tag-france","tag-furtitivite","tag-haftar","tag-italie","tag-la","tag-libye","tag-otan","tag-stealth","tag-strategie-bouffe","tag-su-57","tag-technologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79028"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79028\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}