{"id":79032,"date":"2019-12-30T11:45:41","date_gmt":"2019-12-30T11:45:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/30\/si-homere-avait-eu-un-milliard\/"},"modified":"2019-12-30T11:45:41","modified_gmt":"2019-12-30T11:45:41","slug":"si-homere-avait-eu-un-milliard","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/12\/30\/si-homere-avait-eu-un-milliard\/","title":{"rendered":"Si Hom\u00e8re avait eu un $milliard&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Si Hom\u00e8re avait eu un $milliard&#8230;<\/h2>\n<\/p>\n<p><p>C&rsquo;est un exercice courant de cette \u00e9poque de s&rsquo;informer r\u00e9guli\u00e8rement de la situation financi\u00e8re de nos \u00e9lites oligarchiques, ceux que l&rsquo;on surnomme \u00ab\u00a0les tr\u00e8s-riches\u00a0\u00bb et qui m\u00e9riteraient bien d&rsquo;\u00eatre faits \u00ab\u00a0les tr\u00e8s-tr\u00e8s-riches\u00a0\u00bb, &ndash; un peu comme l&rsquo;on fait Grand-Croix un Grand Officier de l&rsquo;Ordre de la L\u00e9gion d&rsquo;Honneur. Il est int\u00e9ressant de conna&icirc;tre leur situation en cette fin d&rsquo;ann\u00e9e 2019, pour se rassurer sur la bonne marche des choses puisqu&rsquo;on apprend que les 500 personnes les plus riches du monde cumulent une \u00ab\u00a0valeur nette combin\u00e9e\u00a0\u00bb sup\u00e9rieure au PIB des Etats-Unis \u00e0 la fin du troisi\u00e8me trimestre 2019 : $5 900 milliards contre $5 100 milliards pour les USA, et que cela est d&ucirc; \u00e0 un tr\u00e8s encourageant accroissement de leur fortune g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><p>Toutes ces informations, et bien d&rsquo;autres certes, viennent d&rsquo;un texte du site <em>WSWS.org <\/em>dont on sait la vigueur \u00e0 vanter les m\u00e9rites du trotskisme. Dans ce cas, &ndash; comme d&rsquo;ailleurs le plus souvent lorsqu&rsquo;il s&rsquo;agit d&rsquo;informations, &ndash; il n&rsquo;y a aucun \u00ab\u00a0gauchissement\u00a0\u00bb (!) id\u00e9ologique \u00e0 craindre dans ce compte-rendu, tant les chiffres parlent d&rsquo;eux-m\u00eames et qu&rsquo;ils sont extr\u00eamement bavards. Ce site nous les restitue excellemment, avec quelques bouff\u00e9es de rage scandalis\u00e9e qui ont parfaitement leur place.<\/p>\n<\/p>\n<p><p>Souvent, les images parcellaires et les comparaisons op\u00e9rationnelles illustrent avec bonheur le bavardage assourdissant des chiffres de cette monstrueuse in\u00e9galit\u00e9 de l&rsquo;argent du monde. Ainsi <em>WSWS.org <\/em>cite-t-il l&rsquo;\u00e9conomiste Branko Milanovic, dont l&rsquo;on doit lire l&rsquo;extrait de son livre <em>Global Inequality <\/em>en ayant \u00e0 l&rsquo;esprit qu&rsquo;il est question de $milliards par milliers d&rsquo;une part, tandis qu&rsquo;il nous cite un exemple qui nous rappelle qu&rsquo;Hom\u00e8re \u00e9crivit il y a 2 700 ans cette &oelig;uvre sans prix et donc inestimable en $milliards qu&rsquo;est <em>L&rsquo;Illiade <\/em>:<\/p>\n<\/p>\n<p><p>&laquo; <em>Un milliard de dollars est tellement loin de l&rsquo;exp\u00e9rience habituelle de pratiquement tout le monde sur terre que la quantit\u00e9 m\u00eame que cela implique n&rsquo;est pas facile \u00e0 comprendre.<\/em>[&#8230;] <em>Supposons maintenant que vous ayez h\u00e9rit\u00e9 de 1 million de dollars ou de 1 milliard de dollars, et que vous avez d\u00e9pens\u00e9 1000 dollars par jour. Il vous faudrait moins de trois ans pour \u00e9puiser votre h\u00e9ritage dans le premier cas, et plus de 2700 ans (c&rsquo;est-\u00e0-dire le temps qui nous s\u00e9pare de l&rsquo; Iliade d&rsquo; Hom\u00e8re) pour dilapider votre h\u00e9ritage dans le second cas<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Comme \u00e0 l&rsquo;habitude, mais de plus en plus selon une habitude qui confine \u00e0 la d\u00e9mence, l&rsquo;aspect totalement absurde de cette situation d&rsquo;in\u00e9galit\u00e9 ne cesse de s&rsquo;affirmer, de hurler, de se d\u00e9battre comme dans un gigantesque filet o&ugrave; l&rsquo;esp\u00e8ce humaine se trouve prise au pi\u00e8ge comme un banc de sardines attendant la baleine bienfaisante qui les gobera d&rsquo;un \u00e9l\u00e9gant mouvement de m\u00e2choire. L&rsquo;invective, la protestation, l&rsquo;accusation contre l&rsquo;injustice ne suffisent certainement plus du tout \u00e0 caract\u00e9riser les r\u00e9actions qu&rsquo;il est logique d&rsquo;avoir devant ces constats. Il y a d\u00e9sormais, fortement install\u00e9e, la sensation d&rsquo;un d\u00e9s\u00e9quilibre catastrophique dont on voit mal comment il pourrait ne pas d\u00e9boucher sur des situation de d\u00e9sordre et de chaos entrain\u00e9s par et dans un \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">tourbillon crisique<\/a>\u00a0\u00bb aux dimensions des plus profonds trous noirs de l&rsquo;univers.<\/p>\n<\/p>\n<p><p>On a les premiers signes s\u00e9rieux et marquants de ce \u00ab\u00a0d\u00e9s\u00e9quilibre catastrophique\u00a0\u00bb dans cette ann\u00e9e 2019 avec le nombre qui s&rsquo;est tr\u00e8s fortement accru jusqu&rsquo;\u00e0 faire penser \u00e0 une insurrection globale, une sorte de jacquerie mondialis\u00e9e, de mouvement de d\u00e9sordres sociaux, de r\u00e9voltes populaires, etc. Comme l&rsquo;on sait, les motifs sont divers et permettent des interpr\u00e9tations politiques \u00e9galement les plus diverses alors que tout le monde comprend bien ou devrait tr\u00e8s bien comprendre que la seule cause de ces agitations est l&rsquo;in\u00e9galit\u00e9 monstrueuse qui fait peser sur nos conscience une insupportable inversion ontologique entre le mat\u00e9riel et le spirituel ; que la seule cause enfin est ce monstrueux Syst\u00e8me qui a pris possession du monde et fait de tous ceux qu&rsquo;il emprisonne, y compris les oligarques aussi stupides que leurs $milliards, des esclaves d\u00e9vou\u00e9s \u00e0 son &oelig;uvre d&rsquo;entropisation du susdit monde.<\/p>\n<\/p>\n<p><p>Il faut insister sur cette situation d&rsquo;inversion qui, par le mouvement qu&rsquo;elle implique, entra&icirc;ne l&rsquo;ivresse, la confusion, la contradiction jusqu&rsquo;aux plus terribles affections psychologiques. M\u00eame leurs r\u00e9f\u00e9rences les plus sacr\u00e9es deviennent totalement inverties et ce qui, <em>in illo tempore<\/em>, annon\u00e7ait des lendemains capitalistes qui chantent, signalent aujourd&rsquo;hui l&rsquo;extension catastrophiques de l&rsquo;incendie de folie qui ravage la plan\u00e8te. La bourse  est d\u00e9sormais un indice effectivement marqu\u00e9e de cette inversion totale : au plus elle monte, au plus la situation s&rsquo;aggrave dans le chef des r\u00e9voltes sociales, de l&rsquo;extension de la criminalit\u00e9, des folies soci\u00e9tales, de l&rsquo;extension de la pauvret\u00e9 et des pathologies psychologiques, des d\u00e9s\u00e9quilibres de toutes les sortes possibles que suscite le \u00ab\u00a0tourbillon crisique\u00a0\u00bb. &laquo; &#8230;<em>Le march\u00e9 boursier atteint des records et les fortunes des milliardaires du monde continuent \u00e0 monter en fl\u00e8che<\/em> &raquo;, &ndash; c&rsquo;est-\u00e0-dire une augmentation de 25% entre 2018 et 2019 de la \u00ab\u00a0valeur nette combin\u00e9e\u00a0\u00bb des 500 dont on a signal\u00e9 plus haut qu&rsquo;ils p\u00e8sent plus lourd que le PIB des USA.<\/p>\n<\/p>\n<p><p>Il nous est impossible, d\u00e9crivant comme faire se peut \u00e0 l&rsquo;aide d&rsquo;images et de symboles cette situation indescriptible et indicible, de ne pas songer \u00e0 l&rsquo;\u00e9quation cardinale et fondamentale du Syst\u00e8me : surpuissance-autodestruction, certes. Car c&rsquo;est bien ce que montre cette \u00e9volution qui construit un formidable, un catastrophique d\u00e9s\u00e9quilibre dont la destination finale est la destruction totale de lui-m\u00eame. <\/p>\n<\/p>\n<p><p>Certes, l&rsquo;in\u00e9galit\u00e9 expos\u00e9e ici, qui est l&rsquo;in\u00e9galit\u00e9 de ce moteur devenu monstrueux qu&rsquo;est l&rsquo;argent, n&rsquo;est pas le seul aliment de l&rsquo;\u00e9quation surpuissance-autodestruction. L&rsquo;\u00e9galit\u00e9 totalement utopique et \u00e9galement d\u00e9mente que recherche le clan progressiste-soci\u00e9tale est exactement de la m\u00eame boutique, et r\u00e9pondant \u00e0 la m\u00eame \u00e9quation. <\/p>\n<\/p>\n<p><p>Bref, tout marche \u00e0 la m\u00eame musique, celle du fameux <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Joueur_de_fl%C3%BBte_de_Hamelin\">joueur de flute<\/a>entra&icirc;nant derri\u00e8re lui les rats qui infestaient la ville de Hamelin pour les noyer dans la rivi\u00e8re avoisinante aux flots tumultueux ; les rats, ou zombieSyst\u00e8me, y compris les 500 qui p\u00e8sent plus lourd que le PIB-USA, suivent avec encore plus de z\u00e8le que leurs pr\u00e9d\u00e9cesseurs, car bien plus qu&rsquo;eux, ce sont des rats-pensants et ils sont persuad\u00e9s qu&rsquo;on les emm\u00e8ne dans un jacuzzi amical et qu&rsquo;ils savent nager mieux que tous les requins du monde.<\/p>\n<\/p>\n<p><p>Ci-dessous, le texte de Barry Grey, de <em>WSWS.org<\/em>,du <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2019\/12\/30\/pers-d30.html\">30 d\u00e9cembre 2019<\/a><em>.<\/em><\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La richesse des milliardaires a bondi en 2019<\/h2>\n<\/p>\n<p><p>Alors que la deuxi\u00e8me d\u00e9cennie du 21e si\u00e8cle touche \u00e0 sa fin, sa caract\u00e9ristique la plus saillante &#8211; le pillage de l&rsquo;humanit\u00e9 par une oligarchie financi\u00e8re mondiale &#8211; se poursuit sans rel\u00e2che.<\/p>\n<\/p>\n<p><p>Sur fond de guerre commerciale et de mont\u00e9e du militarisme et de l&rsquo;autoritarisme d&rsquo;un c\u00f4t\u00e9, et de l&rsquo;\u00e9ruption de gr\u00e8ves internationales et de protestations de la classe ouvri\u00e8re contre les in\u00e9galit\u00e9s sociales de l&rsquo;autre, le march\u00e9 boursier atteint des records et les fortunes des milliardaires du monde continuent \u00e0 monter en fl\u00e8che.<\/p>\n<\/p>\n<p><p>Vendredi, un jour apr\u00e8s que les trois principaux indices boursiers am\u00e9ricains aient \u00e9tabli de nouveaux records, Bloomberg a publi\u00e9 son enqu\u00eate de fin d&rsquo;ann\u00e9e sur les 500 personnes les plus riches du monde. Le Bloomberg Billionaires Index a indiqu\u00e9 que les fortunes des oligarques ont augment\u00e9 d&rsquo;un total combin\u00e9 de 1200 milliards de dollars, soit une augmentation de 25 pour cent par rapport \u00e0 2018. Leur valeur nette combin\u00e9e s&rsquo;\u00e9l\u00e8ve d\u00e9sormais \u00e0 5900 milliards de dollars.<\/p>\n<\/p>\n<p><p>Pour mettre ce chiffre dans une certaine perspective, ces 500 personnes contr\u00f4lent plus de richesse que le produit int\u00e9rieur des &Eacute;tats-Unis \u00e0 la fin du troisi\u00e8me trimestre de 2019, qui \u00e9tait de 5400 milliards de dollars.<\/p>\n<\/p>\n<p><p>Le plus gros gain de l&rsquo;ann\u00e9e a \u00e9t\u00e9 r\u00e9alis\u00e9 par le fran\u00e7ais Bernard Arnault, qui a ajout\u00e9 36,5 milliards de dollars \u00e0 sa fortune, le portant au-dessus du niveau exceptionnel de100 milliards de dollars, \u00e0 105 milliards de dollars. Il a battu le sp\u00e9culateur Warren Buffett, \u00e0 89,3 milliards de dollars, pour le rel\u00e9guer \u00e0 la quatri\u00e8me place. Le patron d&rsquo;Amazon, Jeff Bezos, a perdu pr\u00e8s de 9 milliards de dollars en raison d&rsquo;un r\u00e8glement de divorce, mais a conserv\u00e9 la premi\u00e8re position, avec une valeur nette de 116 milliards de dollars. Le fondateur de Microsoft, Bill Gates, a gagn\u00e9 22,7 milliards de dollars pour l&rsquo;ann\u00e9e et s&rsquo;est maintenu \u00e0 la deuxi\u00e8me place avec 113 milliards de dollars.<\/p>\n<\/p>\n<p><p>Les 172 milliardaires am\u00e9ricains sur la liste Bloomberg ont ajout\u00e9 500 milliards de dollars \u00e0 leurs portefeuilles, avec Mark Zuckerberg de Facebook r\u00e9alisant le plus gros gain am\u00e9ricain de l&rsquo;ann\u00e9e avec 27,3 milliards de dollars, le pla\u00e7ant \u00e0 la cinqui\u00e8me place dans le monde avec une valeur nette de 79,3 milliards de dollars.<\/p>\n<\/p>\n<p><p>Il est difficile de comprendre ce que repr\u00e9sentent vraiment de ces sommes stratosph\u00e9riques. Dans son livre de 2016 Global Inequality, l&rsquo;\u00e9conomiste Branko Milanovic \u00e9crit:<\/p>\n<\/p>\n<p><p>&laquo; Un milliard de dollars est tellement loin de l&rsquo;exp\u00e9rience habituelle de pratiquement tout le monde sur terre que la quantit\u00e9 m\u00eame que cela implique n&rsquo;est pas facile \u00e0 comprendre [&#8230;] Supposons maintenant que vous ayez h\u00e9rit\u00e9 de 1 million de dollars ou de 1 milliard de dollars, et que vous avez d\u00e9pens\u00e9 1000 dollars par jour. Il vous faudrait moins de trois ans pour \u00e9puiser votre h\u00e9ritage dans le premier cas, et plus de 2700 ans (c&rsquo;est-\u00e0-dire le temps qui nous s\u00e9pare de l&rsquo; Iliade d&rsquo; Hom\u00e8re) pour dilapider votre h\u00e9ritage dans le second cas. &raquo;<\/p>\n<\/p>\n<p><p>La vaste redistribution des richesses du bas vers le haut de la soci\u00e9t\u00e9 est le r\u00e9sultat d&rsquo;un processus de plusieurs d\u00e9cennies, qui s&rsquo;est acc\u00e9l\u00e9r\u00e9 apr\u00e8s le krach de Wall Street en 2008. Ce n&rsquo;est pas le r\u00e9sultat de processus impersonnel et simplement automatique. Au contraire, les politiques des gouvernements et des partis capitalistes du monde entier, que ce soit nominalement &laquo;de gauche&raquo; ou de droite, ont \u00e9t\u00e9 consacr\u00e9es \u00e0 l&rsquo;appauvrissement toujours plus grand de la classe ouvri\u00e8re et \u00e0 l&rsquo;enrichissement de l&rsquo;\u00e9lite dirigeante.<\/p>\n<\/p>\n<p><p>Aux &Eacute;tats-Unis, le un pour cent des plus riches a accapar\u00e9 toute l&rsquo;augmentation du revenu national au cours des deux derni\u00e8res d\u00e9cennies et toute l&rsquo;augmentation de la richesse nationale depuis le krach de 2008.<\/p>\n<\/p>\n<p><p>Le principal m\u00e9canisme de ce transfert de richesse a \u00e9t\u00e9 le march\u00e9 boursier, et les politiques de la R\u00e9serve f\u00e9d\u00e9rale am\u00e9ricaine et des banques centrales \u00e0 l&rsquo;\u00e9chelle internationale ont \u00e9t\u00e9 con\u00e7ues pour fournir de l&rsquo;argent bon march\u00e9 afin de faire grimper les cours des actions. Le co&ucirc;t de cette subvention massive aux march\u00e9s financiers et aux oligarques a \u00e9t\u00e9 pay\u00e9 par la classe ouvri\u00e8re, sous la forme de coupes sociales, de licenciements collectifs, de la destruction des retraites et des prestations de sant\u00e9, et du remplacement d&#8217;emplois relativement s&ucirc;rs et r\u00e9mun\u00e9r\u00e9s correctement par des emplois \u00e0 temps partiel, d&rsquo;int\u00e9rimaires et de petits boulots.<\/p>\n<\/p>\n<p><p>Depuis que Trump est entr\u00e9 en fonctions en janvier 2017, s&rsquo;engageant \u00e0 r\u00e9duire les imp\u00f4ts des soci\u00e9t\u00e9s, \u00e0 diminuer les r\u00e9glementations sur les activit\u00e9s des grandes entreprises et \u00e0 augmenter consid\u00e9rablement le budget militaire, le Dow Jones a bondi de pr\u00e8s de 19.000 points. Cette ann\u00e9e, Trump et les march\u00e9s financiers ont exerc\u00e9 une pression massive sur la Fed pour inverser ses efforts de &laquo;normalisation&raquo; des taux d&rsquo;int\u00e9r\u00eat. La Fed s&rsquo;est pli\u00e9e \u00e0 cette demande. Elle a proc\u00e9d\u00e9 \u00e0 trois baisses de taux et a rassur\u00e9 les march\u00e9s \u00e0 plusieurs reprises qu&rsquo;elle n&rsquo;avait pas l&rsquo;intention d&rsquo;augmenter les taux en 2020.<\/p>\n<\/p>\n<p><p>Cette manne pour les banques et les fonds sp\u00e9culatifs a \u00e9t\u00e9 accept\u00e9e autant par les d\u00e9mocrates que les r\u00e9publicains. En fait, la politique \u00e9conomique de Trump a re\u00e7u de facto le soutien du Parti d\u00e9mocrate de A \u00e0 Z &#8211; de ses r\u00e9ductions d&rsquo;imp\u00f4ts pour les soci\u00e9t\u00e9s et les riches \u00e0 son attaque pour \u00e9liminer pratiquement toutes les r\u00e9glementations sur les affaires. M\u00eame au milieu de la destitution &#8211; effectu\u00e9e enti\u00e8rement sur la base de la &laquo;s\u00e9curit\u00e9 nationale&raquo; et de la &laquo;bienveillance&raquo; suppos\u00e9e de Trump envers la Russie &#8211; les d\u00e9mocrates ont vot\u00e9 par de larges marges pour le budget de Trump, son pacte commercial anti-chinois entre les &Eacute;tats-Unis, le Mexique et le Canada et son budget record de 738 milliards de dollars de guerre du Pentagone.<\/p>\n<\/p>\n<p><p>Cela a notamment consist\u00e9 \u00e0 donner \u00e0 Trump tout l&rsquo;argent qu&rsquo;il voulait pour construire son mur frontalier et mener \u00e0 bien l&rsquo;incarc\u00e9ration et la pers\u00e9cution de masse des immigrants.<\/p>\n<\/p>\n<p><p>Les politiques pro-grandes entreprises de Trump sont une continuation et une expansion de celles poursuivies par le gouvernement Obama. Il a allou\u00e9 des milliers de milliards de dollars provenant des contribuables pour renflouer les banques et inonder les march\u00e9s financiers de cr\u00e9dit bon march\u00e9, faisant grimper les cours des actions, tout en imposant une baisse de 50 pour cent des salaires des travailleurs de l&rsquo;automobile nouvellement embauch\u00e9s dans le cadre de son renflouement de General Motors et Chrysler. Obama a supervis\u00e9 la fermeture de milliers d&rsquo;\u00e9coles et le licenciement de centaines de milliers d&rsquo;enseignants, et a promulgu\u00e9 des budgets d&rsquo;aust\u00e9rit\u00e9 qui ont r\u00e9duit les aides sociales.<\/p>\n<\/p>\n<p><p>Deux de ceux qui se pr\u00e9sentent pour la nomination pr\u00e9sidentielle d\u00e9mocrate de 2020 sont des milliardaires &#8211; Tom Steyer et Michael Bloomberg. Ce dernier, avec une valeur nette de 56 milliards de dollars, est la neuvi\u00e8me personne la plus riche des &Eacute;tats-Unis. Il est entr\u00e9 dans la course en tant que porte-parole des oligarques indign\u00e9s par des allusions faites par Bernie Sanders et Elizabeth Warren de vouloir instaurer une augmentation fiscale symbolique sur les super-riches.<\/p>\n<\/p>\n<p><p>Les oligarques n&rsquo;ont pas peur de Sanders et Warren &#8211; deux d\u00e9fenseurs de longue date de la classe dirigeante am\u00e9ricaine, qui cherchent \u00e0 masquer leur soumission au capital en parlant de faire payer aux oligarques &laquo;leur juste part&raquo; &#8211; un euph\u00e9misme pour d\u00e9fendre leur droit de piller la population. Ils sont effray\u00e9s par la mont\u00e9e de l&rsquo;opposition de masse au capitalisme qui trouve une expression d\u00e9form\u00e9e \u00e0 travers le soutien apport\u00e9 aux faux progressistes dans le giron du Parti d\u00e9mocrate.<\/p>\n<\/p>\n<p><p>&Agrave; eux deux, Bloomberg et Steyer ont d\u00e9j\u00e0 d\u00e9pens\u00e9 200 millions de dollars de leur propre argent dans le but d&rsquo;acheter les \u00e9lections.<\/p>\n<\/p>\n<p><p>L&rsquo;effet de cette politique de pillage social se traduit par l&rsquo;aggravation d&rsquo;une crise sociale maligne pays apr\u00e8s pays. Aux &Eacute;tats-Unis, la soci\u00e9t\u00e9 recule, car le besoin criant d&rsquo;\u00e9coles, d&rsquo;h\u00f4pitaux, de logements abordables, de pensions de retraite, de la reconstruction de routes d\u00e9labr\u00e9es, de ponts, de transports, de protection contre les inondations, d&rsquo;eau potable, d&rsquo;\u00e9gouts, de lutte contre les incendies et d&rsquo;entretien des r\u00e9seaux \u00e9lectriques rencontre la r\u00e9ponse administrative: &laquo;Il n&rsquo;y a pas d&rsquo;argent&raquo;.<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat? Trois ann\u00e9es cons\u00e9cutives de baisse de l&rsquo;esp\u00e9rance de vie, de taux de toxicomanie et de suicide records, d&rsquo;incendies de for\u00eat et d&rsquo;inondations d\u00e9vastateurs, et de coupures d&rsquo;\u00e9lectricit\u00e9 par des fournisseurs profiteurs. Et une crise climatique qui ne peut \u00eatre abord\u00e9e dans le cadre d&rsquo;un syst\u00e8me domin\u00e9 par une ploutocratie folle d&rsquo;argent.<\/p>\n<\/p>\n<p><p>Aucun probl\u00e8me social grave ne peut \u00eatre r\u00e9solu dans des conditions o&ugrave; l&rsquo;\u00e9lite dirigeante &#8211; par le biais de ses partis et politiciens corrompus, aid\u00e9e par ses syndicats pro-capitalistes et appuy\u00e9e par ses tribunaux, sa police et ses troupes &#8211; d\u00e9tourne des ressources de la soci\u00e9t\u00e9 vers l&rsquo;accumulation de yachts, h\u00f4tels particuliers, &icirc;les priv\u00e9es et jets personnels toujours plus luxueux.<\/p>\n<\/p>\n<p><p>L\u00e0 o&ugrave; la r\u00e9forme sociale est impossible, la r\u00e9volution sociale est in\u00e9vitable. La solution \u00e0 l&rsquo;impasse se trouve dans la mont\u00e9e de la lutte des classes. Le mouvement des travailleurs et des jeunes dans le monde entier &#8211; des gr\u00e8ves de masse en France aux gr\u00e8ves des travailleurs de l&rsquo;automobile et des enseignants aux &Eacute;tats-Unis, des manifestations au Chili, en Bolivie, en &Eacute;quateur et au Br\u00e9sil, aux gr\u00e8ves et manifestations de masse au Liban, en Iran, en Irak et en Inde &#8211; r\u00e9v\u00e8le la force sociale qui peut mettre fin au capitalisme et qui le fera.<\/p>\n<\/p>\n<p><p>Le mot d&rsquo;ordre doit \u00eatre &#8211; par opposition aux Corbyn, aux Sanders, aux Tsipras et \u00e0 leurs promoteurs de pseudo-gauche &ndash; &laquo;Exproprier les super-riches!&raquo; C&rsquo;est le point de d\u00e9part du remplacement de la propri\u00e9t\u00e9 priv\u00e9e capitaliste de la production par la propri\u00e9t\u00e9 sociale et la planification internationale, c&rsquo;est-\u00e0-dire la r\u00e9volution socialiste mondiale.<\/p>\n<\/p>\n<p><h4>Barry Grey, <em>WSWS.org<\/em><\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si Hom\u00e8re avait eu un $milliard&#8230; C&rsquo;est un exercice courant de cette \u00e9poque de s&rsquo;informer r\u00e9guli\u00e8rement de la situation financi\u00e8re de nos \u00e9lites oligarchiques, ceux que l&rsquo;on surnomme \u00ab\u00a0les tr\u00e8s-riches\u00a0\u00bb et qui m\u00e9riteraient bien d&rsquo;\u00eatre faits \u00ab\u00a0les tr\u00e8s-tr\u00e8s-riches\u00a0\u00bb, &ndash; un peu comme l&rsquo;on fait Grand-Croix un Grand Officier de l&rsquo;Ordre de la L\u00e9gion d&rsquo;Honneur. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[19602,17343,4363,8294,2631,15453,5481,19604,6553,9054,19603,12041,8846,12735,2804],"class_list":["post-79032","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-19602","tag-boursiere","tag-capitalisme","tag-crisique","tag-de","tag-dement","tag-dollars","tag-hausse","tag-inegalite","tag-inversion","tag-millards","tag-oligarques","tag-pib","tag-tourbillon","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79032"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79032\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}