{"id":79079,"date":"2020-01-25T15:57:57","date_gmt":"2020-01-25T15:57:57","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/01\/25\/tc-85-dissonance-globale\/"},"modified":"2020-01-25T15:57:57","modified_gmt":"2020-01-25T15:57:57","slug":"tc-85-dissonance-globale","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/01\/25\/tc-85-dissonance-globale\/","title":{"rendered":"T.C.-85\u00a0: dissonance globale"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">T.C.-85 : dissonance globale<\/h2>\n<\/p>\n<p><p>25 janvier 2020 &ndash; &#8230; Non seulement le monde est un maelstrom de d\u00e9sordre mais plus encore, comme si l&rsquo;on pouvait croire cela possible, ce d\u00e9sordre-l\u00e0 est chaotique. Il fait grincer des dents, il est plein de fausses notes, de simulacres de sons de crincrins, de cahots pleins de bruits et de fureurs jaillissant dans toutes les directions ; d&rsquo;o&ugrave; cette id\u00e9e de \u00ab\u00a0dissonance\u00a0\u00bb dont la d\u00e9finition embrasse bien le chaos du son que nous entendons au d\u00e9sordre de la chose (je ne parle m\u00eame pas d'\u00a0\u00bbinstrument\u00a0\u00bb) qui les \u00e9met : &laquo; <em>un ensemble de sons (dans un accord ou un intervalle) produisant une impression d&rsquo;instabilit\u00e9, de contrari\u00e9t\u00e9 entre les notes et de tension, et n\u00e9cessitant une r\u00e9solution<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Ainsi une \u00ab\u00a0r\u00e9solution\u00a0\u00bb serait n\u00e9cessaire&#8230; On verra, en attendant mesurons l&rsquo;\u00e9tendue du champ de la m\u00eal\u00e9e.<\/p>\n<\/p>\n<p><p>On parlera d&rsquo;abord de cette nouveaut\u00e9 dans le domaine du d\u00e9sordre de la pand\u00e9mie\/de l&rsquo;\u00e9pid\u00e9mie du coronavirus qui a pris son essor en Chine et qui, gr\u00e2ce \u00e0 la globalisation, introduit une anxi\u00e9t\u00e9 de plus sur cette \u00e9trange plan\u00e8te. L&rsquo;on vous avise aussit\u00f4t que d&rsquo;avis\u00e9s pr\u00e9visionnistes savent <a href=\"https:\/\/www.zerohedge.com\/health\/coronavirus-pandemic-simulation-run-3-months-ago-predicts-65-million-people-could-die\">o&ugrave; nous m\u00e8ne cette affaire<\/a> : &laquo; <em>Eric Toner, un scientifique du Centre Johns Hopkins pour la s\u00e9curit\u00e9 sanitaire, a effectu\u00e9  <\/em>[il y a trois mois] <em>une simulation d&rsquo;une pand\u00e9mie mondiale impliquant exactement le m\u00eame type de virus, selon Business Insider. Sa simulation pr\u00e9voyait que 65 millions de personnes pourraient mourir \u00ab\u00a0dans les 18 mois\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>La simulation venant peut \u00eatre bien du financements de la Bill &#038; Melinda Gates Foundation, <a href=\"https:\/\/www.infowars.com\/bill-and-melinda-gates-foundation-others-predicted-up-to-65-million-deaths-via-coronavirus-in-simulation-ran-3-months-ago\/\">les soup\u00e7ons<\/a> sont nombreux chez les observateurs des r\u00e9seaux pour distinguer dans cette affaire une tentative des globalistes de lancer leurs projets bien connus de d\u00e9population du globe par millions. Pourquoi tout cela ? Il s&rsquo;agit du d\u00e9sordre-chaotique, mes bien chers fr\u00e8res&#8230;<\/p>\n<\/p>\n<p><p>Des millions, dites-vous ? Il y en avait au moins un si pas plus, dans les rues de Bagdad hier, pour r\u00e9clamer le d\u00e9part des forces de l&rsquo;Arm\u00e9e du Chaos du syst\u00e8me de l&rsquo;am\u00e9ricanisme. \u00ab\u00a0b\u00a0\u00bb, de <em>The Moon of Alabama<\/em>, <a href=\"https:\/\/www.moonofalabama.org\/2020\/01\/associated-press-sees-hundreds-where-pictures-show-millions.html#more\">s&rsquo;en paye une tranche<\/a> \u00e0 comparer l&rsquo;entame du texte de AP (&laquo; <em>Des centaines de supporteurs d&rsquo;un dirigeant chiite radical et influent d\u00e9filent dans les rues de Bagdad pour demander que les troupes am\u00e9ricaines quittent le pays<\/em> &raquo;) avec les photos et les vid\u00e9os comme vous et moi : &laquo; <em>Associated Press en d\u00e9compte \u00ab\u00a0des centaines\u00a0\u00bb l\u00e0 o&ugrave; les photos en montrent des millions.<\/em> &raquo; Je croyais que l&rsquo;Irak \u00e9tait territoire am\u00e9ricaniste depuis 2003 et qu&rsquo;on n&rsquo;en parlait plus.<\/p>\n<\/p>\n<p><p>Il n&rsquo;y a pas que cela, comme vous vous en doutez&#8230; Apr\u00e8s tout, il y a un destitution en cours \u00e0 Washington D.C., \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb o&ugrave; l&rsquo;on dit que certains s\u00e9nateurs somnolent \u00e0 l&rsquo;audition rab\u00e2ch\u00e9e des sempiternelles accusations qui s&rsquo;\u00e9changent et \u00e0 la lecture des tweets incendiaires du pr\u00e9sident.<\/p>\n<\/p>\n<p><p>&#8230;Tant il est vrai que jamais  <a href=\"https:\/\/www.zerohedge.com\/political\/us-presidential-partisan-divide-hits-record-high\">la polarisation<\/a> n&rsquo;a \u00e9t\u00e9 aussi forte aux USA, gr\u00e2ce \u00e0 Trump qui n&rsquo;en finit pas de nous \u00e9tonner : elle a atteint 82% en 2019 (89% des r\u00e9publicains sont derri\u00e8re Trump, et 7% des d\u00e9mocrates) tandis qu&rsquo;elle n&rsquo;atteignait, &ndash; c&rsquo;\u00e9tait d\u00e9j\u00e0 un record, &ndash; 79% en 2018 (87% des r\u00e9publicains, 8% des d\u00e9mocrates). <a href=\"https:\/\/www.dedefensa.org\/article\/ontologie-decettehaine\">La haine<\/a> se porte bien, comme d&rsquo;ailleurs en France o&ugrave; rien, absolument rien ne parvient \u00e0 faire cesser les troubles des rues au long de ce quinquennat original qui semble \u00e0 cet \u00e9gard, celui de la rue, n&rsquo;avoir jamais \u00e9t\u00e9 aussi proche du citoyen&#8230; On ne s&rsquo;arr\u00eate pas l\u00e0 : Tom Luongo nous susurre, cerise sur le g\u00e2teau dans le  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>, que les \u00e9lections r\u00e9gionales de ce week-end dans l&rsquo;&Eacute;milie-Romagne vont confirmer le succ\u00e8s de la <em>Liga <\/em>et l&rsquo;effondrement du M5S commenc\u00e9 avec la d\u00e9mission de la t\u00eate du parti de Di Maio (qui reste ministre d&rsquo;une coalition en lambeaux), tout cela nous r\u00e9servant, <a href=\"https:\/\/tomluongo.me\/2020\/01\/24\/italy-slouches-towards-new-elections\/\">insiste Luongo<\/a>, un raccourci vers des \u00e9lections et un retour triomphal, type \u00ab\u00a0marche sur Rome\u00a0\u00bb disent les n\u00e9vros\u00e9s, du <em>commandatore-duce<\/em>Salvini. <\/p>\n<\/p>\n<p><p>M\u00eame nos idoles sont \u00e9branl\u00e9es dans un m\u00e9lange \u00e9trange de d\u00e9sordre-tragique et de chaos-bouffe, avec  <a href=\"https:\/\/www.rt.com\/news\/479113-icymi-saudis-hack-bezos\/\">cette affaire<\/a> exemplaire de <em>hacking <\/em>entre deux h\u00e9ro\u00efques progressistes postmoderne, <a href=\"https:\/\/www.youtube.com\/watch?time_continue=1&#038;v=Xm5be2_zcEM&#038;feature=emb_logo\">MbS et Jeff Bezos<\/a>, icones de la globalisation et de la g\u00e9opolitique du simulacre qui va avec. La morale de cette histoire est qu&rsquo;une enqu\u00eate est en cours pour d\u00e9terminer si l&#8217;emploi du t\u00e9l\u00e9phone portable n&rsquo;est pas l&rsquo;Achille Talon de ces puissants complotistes ; et son aspect anecdotique se trouve dans mon aveu que je n&rsquo;ai pu retenir un sourire \u00e0 contempler combien ces h\u00e9ros hom\u00e9riques de la globalisation se conduisent comme des aigrefins de corridor comme vous et moi n&rsquo;oserions m\u00eame pas \u00eatre.<\/p>\n<\/p>\n<p><p>Il \u00e9tait question de millions voire de $milliards dans tout cela, il est aussi question d&rsquo;une poign\u00e9e de secondes, cent pr\u00e9cis\u00e9ment, pour donner une mesure de la fameuse <em>Doomsday Horloge <\/em>(\u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Horloge_de_la_fin_du_monde\">l&rsquo;Horloge de l&rsquo;Apocalypse<\/a>\u00ab\u00a0) tenue \u00e0 jour et \u00e0 l&rsquo;heure depuis 1947 par le <em>Bulletin of the Atomic Scientists <\/em>(universit\u00e9 de Chicago), o&ugrave; minuit repr\u00e9sente la fin du monde. Depuis le 23 janvier 2020, nous sommes \u00e0 100 secondes de la fin du monde (il est 23H58&rsquo;20\u00a0\u00bb), alors que le \u00ab\u00a0record\u00a0\u00bb datant de 1953 et de 2018 \u00e9tait de 23H58, soit \u00e0 120 secondes du <em>Big Bang <\/em>inverti.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0L&rsquo;Horloge de l&rsquo;Apocalypse\u00a0\u00bb a \u00e9volu\u00e9 depuis ces temps anciens o&ugrave; l&rsquo;Apocalypse semblait devoir \u00e9chapper au d\u00e9sordre-chaotique. Longtemps, elle n&rsquo;a pris en compte que le risque nucl\u00e9aire, ce qui donnait l&rsquo;impression d&rsquo;un rangement impeccable. D\u00e9sormais elle y ajoute (retenez votre souffle), &laquo; <em>le risque d&rsquo;un d\u00e9clenchement de la guerre par un accident technique, un acte de terrorisme ou une attaque informatique, les probl\u00e8mes li\u00e9s au changement climatique, aux hydrocarbures (pic p\u00e9trolier, g\u00e9opolitique du p\u00e9trole) ou encore les \u00ab\u00a0nouveaux d\u00e9veloppements dans les sciences du vivant qui pourraient infliger des dommages irr\u00e9vocables\u00a0\u00bb, c&rsquo;est-\u00e0-dire les risques li\u00e9s aux nouvelles technologies (nanotechnologie, biotechnologie, etc.)<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Mais j&rsquo;allais oublier, cet  <a href=\"https:\/\/edition.cnn.com\/2020\/01\/23\/us\/doomsday-clock-trnd\/index.html\">autre risque<\/a> que signalent les horlogers de l&rsquo;Apocalypse : les <em>FakeNews<\/em>, d\u00e9fini comme l&rsquo;absence d&rsquo;une capacit\u00e9 de jugement du public de faire la diff\u00e9rence entre la v\u00e9rit\u00e9 et le mensonge dans les nouvelles du monde&#8230; &laquo; <em>Pr\u00e9occupant<\/em> &raquo;, dit l&rsquo;astrophysicien Robert Rosner, un des horlogers, dont on ne sait si lui-m\u00eame parvient \u00e0 faire le tri.<\/p>\n<\/p>\n<p><p>Prenez Soros, par exemple&#8230; En annon\u00e7ant qu&rsquo;il <a href=\"https:\/\/southfront.org\/is-inevitable-vengeance-moving-towards-george-soros\/\">d\u00e9gageait un $milliard<\/a> pour une nouvelle tentative conceptuelle globale de son  <em>Open Society  <\/em>en fondant une<em> Global University<\/em>, George Soros, qui a 89 ans mais qui continuera \u00e0 financer les forces du d\u00e9sordre-chaotique bien apr\u00e8s sa mort, a d\u00e9sign\u00e9 les \u00ab\u00a0dictateurs\u00a0\u00bb contre lesquels il importe de lutter : le Chinois Xi, l&rsquo;Indien Modi, le Br\u00e9silien Bolsanaro, le US  <em>citizen  <\/em>Trump, et aussi  <em>Facebook Inc. <\/em>A ma connaissance pour ce cas, pas un mot contre Poutine et par contre Zuckerberg dans le collimateur&#8230; Par cons\u00e9quent, m\u00eame Soros se met de la partie pour brouiller les cartes du chaos dans le jeu du d\u00e9sordre. &laquo; <em>En tenant compte de l&rsquo;urgence climatique et des soul\u00e8vements partout dans le monde, <\/em>dit l&rsquo;ami-Soros, <em>il n&rsquo;est pas exag\u00e9r\u00e9 de dire que 2020 et les quelques ann\u00e9es suivantes d\u00e9termineront non seulement le sort de Xi et de Trump, mais aussi le sort du monde. &raquo;<\/em><\/p>\n<\/p>\n<p><p>&#8230; Il n&rsquo;a pas tort, n&rsquo;est-ce pas, quant \u00e0 l&rsquo;annonce de l&rsquo;Acte final ? Cela fait curieux de poser cette question \u00e0 son propos, lui que je d\u00e9non\u00e7ais volontiers  <a href=\"https:\/\/www.dedefensa.org\/article\/la-haine-du-diable-et-le-mepris-de-la-hauteur\">comme le Diable<\/a> soi-m\u00eame.<\/p>\n<\/p>\n<p><p>Finalement, n&rsquo;est-il pas plus concluant, plus logique, plus \u00ab\u00a0stable dans l&rsquo;instabilit\u00e9\u00a0\u00bb du jugement d&rsquo;admettre que oui, finalement, faire de Trump l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/lantechrist-et-larmee-du-chaos\">Ant\u00e9christ<\/a> \u00e0 la t\u00eate de ses Arm\u00e9es du Chaos, c&rsquo;est une fa\u00e7on de rendre les choses plus claires et plus nettes, chacun dans son r\u00f4le \u00e0 la satisfaction de tous, se jetant dans l&rsquo;ab&icirc;me et l&rsquo;abysse de la gueule du loup&#8230; Car il n&rsquo;est vraiment pas simple, justement, il n&rsquo;est pas simple aujourd&rsquo;hui de fixer son jugement \u00e0 propos de ce qui est antiSyst\u00e8me et qui ne l&rsquo;est pas, de ce qui est l&rsquo;Apocalypse et de ce qui ne l&rsquo;est pas.<\/p>\n<\/p>\n<blockquote>\n<p><p>Moi et les <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-limpeachmentdu-systeme\"><em>Roaring Twenties<\/em><\/a>, nous pourrions vous dire ce que c&rsquo;est que l&rsquo;Apocalypse, et quand, et comment, si nous n&rsquo;\u00e9tions tenus par le Secret-D\u00e9fense. N\u00e9anmoins, tendez l&rsquo;oreille : quand la musique sonnera dans le Ciel, dissipant la dissonance gr\u00e2ce \u00e0 la force et \u00e0 la forme de son harmonie ordonn\u00e9e et \u00e9quilibr\u00e9e.<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>T.C.-85 : dissonance globale 25 janvier 2020 &ndash; &#8230; Non seulement le monde est un maelstrom de d\u00e9sordre mais plus encore, comme si l&rsquo;on pouvait croire cela possible, ce d\u00e9sordre-l\u00e0 est chaotique. Il fait grincer des dents, il est plein de fausses notes, de simulacres de sons de crincrins, de cahots pleins de bruits et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[4012,13564,3934,2631,19661,4911,12666,4237,13500,857,3442,18690,5649,13596,6320,9586,18370,4163,5439,2639,13999],"class_list":["post-79079","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-apocalypse","tag-bezos","tag-chaos","tag-de","tag-desordre-chaotique","tag-destitution","tag-fakenews","tag-global","tag-horloge","tag-irak","tag-italie","tag-lapocalypse","tag-luongo","tag-mbs","tag-pandemie","tag-polarisation","tag-salvini","tag-soros","tag-tom","tag-trump","tag-university"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79079"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79079\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}