{"id":79082,"date":"2020-01-29T07:48:34","date_gmt":"2020-01-29T07:48:34","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/01\/29\/boeing-est-devenue-un-walking-zombie\/"},"modified":"2020-01-29T07:48:34","modified_gmt":"2020-01-29T07:48:34","slug":"boeing-est-devenue-un-walking-zombie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/01\/29\/boeing-est-devenue-un-walking-zombie\/","title":{"rendered":"Boeing est devenue un \u201c<em>walking zombie<\/em>\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Boeing est devenue un \u00ab\u00a0<em>walking zombie<\/em>\u00ab\u00a0<\/h2>\n<\/p>\n<p><p><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Max_Keiser\">Max Keiser<\/a> nous parle de Boeing dans sa derni\u00e8re \u00e9dition du <em>Keiser Report <\/em>sur RT.com le  <a href=\"https:\/\/www.rt.com\/business\/479396-boeing-garbage-company-walking-zombie\/\">28 janvier 2020<\/a>. Comme d&rsquo;habitude, Keiser ne m\u00e2che pas ses mots malgr\u00e9 qu&rsquo;il s&rsquo;agisse du 737Max : Boeing transform\u00e9e en \u00ab\u00a0poubelle\u00a0\u00bb insolvable, dont le dynamisme conceptuel est r\u00e9sum\u00e9 par l&rsquo;expression intraduisible dans sa bri\u00e8vet\u00e9 tr\u00e8s parlante de \u00ab\u00a0<em>walking zombie<\/em>\u00a0\u00bb (\u00ab\u00a0zombie ambulant\u00a0\u00bb ? Ou encore, en plus <em>sexy<\/em>, \u00ab\u00a0zombie &lsquo;En-Marche'\u00a0\u00bb peut-\u00eatre ? &laquo; <em>A garbage company that is just a walking zombie<\/em> &raquo;).<\/p>\n<\/p>\n<p><p>Keiser parle de  <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-boeingversususa\">l&rsquo;\u00e9tat de la compagnie<\/a> depuis qu&rsquo;a <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-lemad-maxde-boeing\">commenc\u00e9<\/a> la crise du 737Max. L&rsquo;argent perdu depuis, l&rsquo;incomp\u00e9tence et la rapacit\u00e9 des dirigeants, l&rsquo;attitude arrogante de Boeing, la chute compl\u00e8te de la confiance et les r\u00e9sultats effrayants pour 2019 (380 avions livr\u00e9s alors qu&rsquo;il en \u00e9tait pr\u00e9vu 895-905, 246 commandes mais &ndash; 87 avec toutes les annulations de commandes du 737Max), tout cela a conduit la compagnie \u00e0 demander de l&rsquo;aide aux banques. Cette aide, estime Keiser, ne sert strictement \u00e0 rien sinon \u00e0 consolider la fortune des cadres dirigeants, ce qui fait que la situation structurelle comptable de la soci\u00e9t\u00e9 s&rsquo;est encore plus d\u00e9t\u00e9rior\u00e9e jusqu&rsquo;\u00e0 approcher une situation de banqueroute.<\/p>\n<\/p>\n<p><p>Le financement obtenu par Boeing ne servant qu&rsquo;\u00e0 aggraver sa situation, Keiser juge effectivement  que cette compagnie-poubelle est d\u00e9sormais \u00ab\u00a0insolvable\u00a0\u00bb. Un exemple parfait du caract\u00e8re autodestructeur de l&rsquo;hypercapitalisme de la modernit\u00e9 tardive.<\/p>\n<\/p>\n<p><p>&laquo; <em>Le g\u00e9ant am\u00e9ricain de l&rsquo;a\u00e9rospatiale Boeing a obtenu des engagements sur plus de $12 milliards de financement de la part de plus d&rsquo;une douzaine de banques, ont rapport\u00e9 les m\u00e9dias en citant des personnes connaissant le sujet.<\/em><\/p>\n<p>&raquo; <em>La soci\u00e9t\u00e9 rach\u00e8te ses propres actions avec de l&rsquo;argent bon march\u00e9 de la R\u00e9serve f\u00e9d\u00e9rale, a d\u00e9clar\u00e9 Max Keiser dans son \u00e9mission &lsquo;The Keyser Report&rsquo; sur RT.com. L&rsquo;argent qui \u00e9tait cens\u00e9 aider l&rsquo;entreprise en difficult\u00e9 la prive en fait de ses capacit\u00e9s. \u00ab\u00a0De l&rsquo;autre c\u00f4t\u00e9, du c\u00f4t\u00e9 de Boeing il y a les cadres de la direction de l&rsquo;entreprise, qui re\u00e7oivent cet argent de la Fed directement dans leur poche&#8230;\u00a0\u00bb, note Keiser.<\/em><\/p>\n<p>&raquo; <em>Selon lui, \u00ab\u00a0Boeing n&rsquo;est plus une entreprise viable&#8230; Elle est dans une situation si catastrophique que m\u00eame l&rsquo;argent de financement \u00e0 z\u00e9ro pour cent ne va pas les aider \u00e0 recapitaliser cette entreprise qui est devenue une poubelle. Boeing ne vaut rien, elle est essentiellement insolvable.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Il y a beaucoup d&rsquo;entreprises-zombies dans le S&#038;P 500 qui sont comme Boeing, ajoute-t-il. \u00ab\u00a0Les dirigeants ont vol\u00e9 \u00e0 la Fed tous les capitaux propres qui passaient par les liquidit\u00e9s \u00e0 taux d&rsquo;int\u00e9r\u00eat de z\u00e9ro pour cent&#8230; et maintenant ils ne sont plus que des zombies ambulants<\/em>&#8230;<em>\u00ab\u00a0<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 29 janvier 2020 \u00e0 07H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boeing est devenue un \u00ab\u00a0walking zombie\u00ab\u00a0 Max Keiser nous parle de Boeing dans sa derni\u00e8re \u00e9dition du Keiser Report sur RT.com le 28 janvier 2020. Comme d&rsquo;habitude, Keiser ne m\u00e2che pas ses mots malgr\u00e9 qu&rsquo;il s&rsquo;agisse du 737Max : Boeing transform\u00e9e en \u00ab\u00a0poubelle\u00a0\u00bb insolvable, dont le dynamisme conceptuel est r\u00e9sum\u00e9 par l&rsquo;expression intraduisible dans sa&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[19195,3192,2868,19662,15401,13745],"class_list":["post-79082","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-737max","tag-boeing","tag-est","tag-insolvable","tag-keiser","tag-max"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79082"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79082\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}