{"id":79084,"date":"2020-01-30T16:17:32","date_gmt":"2020-01-30T16:17:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/01\/30\/lafghanistan-vu-den-haut\/"},"modified":"2020-01-30T16:17:32","modified_gmt":"2020-01-30T16:17:32","slug":"lafghanistan-vu-den-haut","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/01\/30\/lafghanistan-vu-den-haut\/","title":{"rendered":"L&rsquo;Afghanistan vu d&rsquo;en haut"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;Afghanistan vu d&rsquo;en haut<\/h2>\n<\/p>\n<p><p>Plusieurs articles signalent l&rsquo;intensification consid\u00e9rable en Afghanistan de la guerre a\u00e9rienne US, &ndash; ou plut\u00f4t, de la guerre US en Afghanistan de plus en plus concentr\u00e9e dans l&rsquo;intervention a\u00e9rienne contre les forces terrestres \u00ab\u00a0ennemies\u00a0\u00bb, accompagn\u00e9es bien entendu des innombrables dommages \u00ab\u00a0collat\u00e9raux\u00a0\u00bb frappant les civils. Les textes suivent la publication par le US Central Command du bilan des interventions ariennes arm\u00e9es de l&rsquo;USAF en Afghanistan pour 2019, l&rsquo;ann\u00e9e la plus active \u00e0 cet \u00e9gard, suivant 2018 qui \u00e9tait \u00e0 son tour l&rsquo;ann\u00e9e la plus active.<\/p>\n<\/p>\n<p><p>On consultera notamment deux textes sur ce sujet, \u00e0 partir <a href=\"https:\/\/www.janes.com\/article\/93916\/us-records-highest-airstrike-rate-in-afghanistan-for-a-decade\">du texte<\/a>  de <em>Jane&rsquo;s Defense Weekly <\/em>reprenant les donn\u00e9es de Central Command :<\/p>\n<p>&bull; un texte de <em>WSWS.org <\/em>du  <a href=\"https:\/\/www.wsws.org\/en\/articles\/2020\/01\/29\/afgh-j29.html\">29 janvier 2020<\/a>.<\/p>\n<p>&bull; un texte de <em><a href=\"https:\/\/www.moonofalabama.org\/2020\/01\/the-air-war-in-afghanistan-expands-on-both-sides.html#more\">The Moon of Alabama<\/a><\/em>, repris <a href=\"https:\/\/lesakerfrancophone.fr\/la-guerre-aerienne-en-afghanistan-prend-de-lampleur\">en fran\u00e7ais<\/a>par le <em>Sakerfrancophone<\/em>, et dont nous donnons un extrait ci-dessous, permettant d&rsquo;avoir un aper\u00e7u \u00e0 la fois sur la situation op\u00e9rationnelle et sur les cons\u00e9quences \u00ab\u00a0collat\u00e9rales\u00a0\u00bb ;<\/p>\n<\/p>\n<p><p>&laquo; <em>Sous l&rsquo;administration Trump, les attaques a\u00e9riennes am\u00e9ricaines en Afghanistan ont fortement augment\u00e9. Mais il semble maintenant que les Talibans aient acquis des moyens pour les contrer.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;ann\u00e9e derni\u00e8re, les &Eacute;tats-Unis ont largu\u00e9 un <a href=\"https:\/\/www.janes.com\/article\/93916\/us-records-highest-airstrike-rate-in-afghanistan-for-a-decade\">nombre record<\/a> de bombes sur l&rsquo;Afghanistan, ce qui a entra&icirc;n\u00e9 une augmentation constante du nombre de victimes parmi les civils :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Selon les statistiques sur la puissance a\u00e9rienne 2013-2019 publi\u00e9es fin janvier par le commandant de la composante a\u00e9rienne des forces combin\u00e9es (CFACC), Des armes ont \u00e9t\u00e9 utilis\u00e9es au cours de 7 423 missions effectu\u00e9es en Afghanistan en 2019. Il y a eu le plus grand nombre d&rsquo;utilisations d&rsquo;armes au cours de la plupart des mois de cette ann\u00e9e, compar\u00e9s \u00e0 ceux des ann\u00e9es pr\u00e9c\u00e9dentes, depuis que les registres ont \u00e9t\u00e9 publi\u00e9s pour la premi\u00e8re fois en 2009 ; le mois de septembre enregistrant le plus grand nombre d&rsquo;utilisations d&rsquo;armes pour l&rsquo;ann\u00e9e, soit 948.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Le record annuel pr\u00e9c\u00e9dent \u00e9tait de 7 362 en 2018, et les deux derni\u00e8res ann\u00e9es ont vu plus d&rsquo;utilisations d&rsquo;armes en Afghanistan que pendant toute la p\u00e9riode 2012 \u00e0 2017.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>Vingt bombardements par jour, c&rsquo;est un chiffre assez impressionnant. De nombreux civils sont tu\u00e9s dans ces bombardement men\u00e9s par les \u00e9tasuniens. ils semblent souvent ne pas savoir qui ils frappent. <a href=\"https:\/\/www.military.com\/daily-news\/2020\/01\/23\/afghan-officials-us-airstrike-killed-least-10-civilians-herat.html\">Ce rapport<\/a>  datant de la semaine derni\u00e8re est typique :<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Une attaque de drone men\u00e9e par les forces am\u00e9ricaines au d\u00e9but du mois dans l&rsquo;ouest de l&rsquo;Afghanistan qui visait apparemment un groupe taliban dissident a \u00e9galement tu\u00e9 au moins 10 civils, dont trois femmes et trois enfants, a d\u00e9clar\u00e9 mercredi un responsable des droits de l&rsquo;homme afghan et un membre du conseil. &#8230;<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Il n&rsquo;y a eu aucun commentaire imm\u00e9diat de la part de l&rsquo;arm\u00e9e afghane ou des forces am\u00e9ricaines. Mais Wakil Ahmad Karokhi, un membre du conseil provincial de Herat, a d\u00e9clar\u00e9 que l&rsquo;attaque du 8 janvier avait \u00e9galement tu\u00e9 le commandant d&rsquo;un groupe dissident taliban, connu sous le nom de Mullah Nangyalia, ainsi que 15 autres militants. &#8230;<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Les fun\u00e9railles du commandant ont eu lieu le lendemain dans le quartier de Guzargah, dans la capitale provinciale de Herat, et des dizaines de militants y ont assist\u00e9.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Karokhi a estim\u00e9 que cette frappe \u00e9tait une &lsquo;\u00e9norme erreur&rsquo;, affirmant que le commandant \u00e9tait une protection utile contre les talibans dans le district de Shindand, prenant les armes avec ses combattants contre les insurg\u00e9s &lsquo;quand personne d&rsquo;autre ne le faisait&rsquo;et laissant les civils de la r\u00e9gion en paix<\/em>.<em>\u00ab\u00a0<\/em> <\/p>\n<\/p>\n<p><p>En fait, ce qui nous appara&icirc;t le plus frappant dans les chiffres donn\u00e9es c&rsquo;est le fait que les interventions a\u00e9riennes arm\u00e9es en 2018-2019, &ndash; respectivement 7 362 interventions a\u00e9riennes arm\u00e9es en 2018, 7 423 en 2019, &ndash; semblent illustrer par leur importance relative une nouvelle forme de la guerre en Afghanistan. Ces 14 785 sorties sont largement sup\u00e9rieures aux sorties a\u00e9riennes arm\u00e9es cumul\u00e9es entre 2009 et 2017, avec notamment des chiffres de 2 365 sorties en 2014, 947 en 20215 (le chiffre le plus bas pour une ann\u00e9e de toute cette guerre en Afghanistan), 1 337 en 2016 et 4 361 en 2017.<\/p>\n<\/p>\n<p><p>Manifestement, les ann\u00e9es 2018-2019, avec une pr\u00e9paration en 2017, marquent une pouss\u00e9e tr\u00e8s forte de l&rsquo;intervention a\u00e9rienne tactique air-sol d&rsquo;appui a\u00e9rien, et surtout d&rsquo;attaque et de frappe, en m\u00eame temps que les forces terrestres US sont \u00e0 un niveau tr\u00e8s bas. Il y a actuellement 12 000 hommes (et femmes certes) de troupe, US Army et Marines, en Afghanistan, dont 4 000 destin\u00e9s \u00e0 \u00eatre retir\u00e9s dans l&rsquo;ann\u00e9e ; en 2009, ils \u00e9taient 100 000. Il y a \u00e9videmment un rapport entre ceci et cela, et ce rapport se nomme le \u00ab\u00a0mod\u00e8le vietnamien\u00a0\u00bb, &ndash; dans ses grandes lignes, avec des diff\u00e9rences circonstancielles et  op\u00e9rationnelles notables. <\/p>\n<\/p>\n<p><p>On retrouve en Afghanistan le m\u00eame sch\u00e9ma conduisant vers la d\u00e9fensive et \u00e9ventuellement le retrait progressif maquill\u00e9e en victoire, avec une dur\u00e9e plus longue que dans le mod\u00e8le vietnamien du fait de la dynamique impos\u00e9e par l&rsquo;opinion publique pour un d\u00e9sengagement du Vietnam (\u00e0 cause de la conscription qui touchait directement la population US). Ce sch\u00e9ma implique d&rsquo;abord un engagement terrestre marqu\u00e9 suivi par un coup d&rsquo;arr\u00eat avec tentative de transf\u00e9rer le poids du conflit sur les forces locales \u00ab\u00a0loyalistes\u00a0\u00bb, puis une r\u00e9duction graduelle des effectifs terrestres avec une augmentation cons\u00e9quente de l&rsquo;activit\u00e9 a\u00e9rienne, assez nette en Afghanistan, tr\u00e8s brutale au Vietnam (r\u00e9engagement a\u00e9rien du printemps 1972). La diff\u00e9rence est que la campagne a\u00e9rienne de 1972 au Vietnam fut nettement victorieuse dans la mesure o&ugrave; le Vietnam du Nord s&rsquo;\u00e9tait engag\u00e9 dans une guerre conventionnelle, ce qui permit le retrait US complet avec des accords de paix d\u00e9but 1973, &ndash; et l&rsquo;invasion du Sud par le Nord deux ans plus tard, sans coup f\u00e9rir et non-intervention US malgr\u00e9 les promesses faites dans ce sens. La campagne a\u00e9rienne est beaucoup moins efficace en Afghanistan, o&ugrave; les combats restent ceux d&rsquo;une gu\u00e9rilla ou d&rsquo;une guerre asym\u00e9trique \u00e0 grande \u00e9chelle.<\/p>\n<\/p>\n<p><p>Dans tous les cas, la r\u00e9duction des engagements terrestres accompagn\u00e9e d&rsquo;une recrudescence de l&rsquo;activit\u00e9 a\u00e9rienne constitue en g\u00e9n\u00e9ral, avec les arm\u00e9es US, un pr\u00e9lude \u00e0 un d\u00e9sengagement rapide qui peut susciter \u00e0 terme des effets indirects catastrophiques, notamment pour les alli\u00e9s des USA (Saigon en 1975). Il s&rsquo;agit alors toujours d&rsquo;une \u00ab\u00a0offensive a\u00e9rienne de d\u00e9fense\u00a0\u00bb, pour contenir l&rsquo;ennemi dans le but de gagner du temps (soit pour n\u00e9gocier, soit pour se d\u00e9sengager).<\/p>\n<\/p>\n<p><p>&bull; Une autre diff\u00e9rence importante avec le Vietnam est en train d&rsquo;appara&icirc;tre, rappelant par contre le conflit avec l&rsquo;URSS en Afghanistan : ce qui semble \u00eatre la constitution d&rsquo;une composante tactique de d\u00e9fense a\u00e9rienne du c\u00f4t\u00e9 des Talibans. Certaines informations font \u00e9tat de quatre h\u00e9licopt\u00e8res abattus en janvie par des missiles que se seraient procur\u00e9s les talibans ou \u00e9quivalents. (Le Vietcong n&rsquo;a jamais eu de missiles sol-air tactique dans le Sud. Le Nord-Vietnam, qui fut tr\u00e8s fortement bombard\u00e9, avait une d\u00e9fense a\u00e9rienne efficace, qui couta cher aux USA. Il s&rsquo;agissait d&rsquo;une facette du conflit compl\u00e8tement diff\u00e9rente et inexistante en Afghanistan, o&ugrave; il n&rsquo;existe pas de pays ext\u00e9rieur qui soit partie prenante dans le conflit.<\/p>\n<\/p>\n<p><p>&bull; Dans cette m\u00eame dimension a\u00e9rienne, il y a l&rsquo;affaire de l&rsquo;avion de l&rsquo;USAF  Bombardier\/Northrop-Grumman E-11A qui s&rsquo;est \u00e9cras\u00e9 en Afghanistan le 27 janvier, dans une r\u00e9gion tenue par les talibans. Le Pentagone  <a href=\"https:\/\/www.veteranstoday.com\/2020\/01\/30\/afghanistan-pentagon-confirmed-dead-airmens-identity-pilot-likely-worked-for-intelligence-cia\/\">communique \u00ab\u00a0par bribes\u00a0\u00bb<\/a> sur cette affaire, renfor\u00e7ant peu \u00e0 peu les contours d&rsquo;une version \u00e9labor\u00e9e, venue de <em>Veterans Today<\/em>(VT), selon lequel cet appareil sp\u00e9cial de communications et de guerre \u00e9lectronique, utilis\u00e9 pour la coordination et la gestion des forces terrestres de combat, aurait \u00e9t\u00e9 abattu par les talibans. Gordon Duff, de VT, a  <a href=\"https:\/\/www.veteranstoday.com\/2020\/01\/28\/breaking-unconfirmed-direct-us-prisoners-taken-after-afghanistan-crash-updating\/\">largement sp\u00e9cul\u00e9<\/a> sur la pr\u00e9sence \u00e0 son bord  <a href=\"https:\/\/www.veteranstoday.com\/2020\/01\/29\/vt-had-it-first-pentagons-top-spy-plane-downed-by-taliban-crypto-gear-docs-captured-warning-unpleasant-photos\/\">d&rsquo;officiers de haut rang de la CIA<\/a>, tandis que se poserait la question de l&#8217;emploi et de la provenance de missiles sol-air si c&rsquo;est le cas (aussi bien pour le E-11A que pour les h\u00e9licopt\u00e8res), ce qui serait une nouveaut\u00e9 consid\u00e9rable pour les talibans. L\u00e0 aussi des sp\u00e9culations citent la possibilit\u00e9 de livraisons de missiles iraniens dans le cadre des mesure de r\u00e9torsions apr\u00e8s l&rsquo;assassinat du g\u00e9n\u00e9ral Soleimani, mais la Russie et la Chine seraient aussi des candidats possibles pour cette sp\u00e9culation. Duff signalait dans son article que l&rsquo;officier de haut rang de la CIA Michael D&rsquo;Andrea, qui avait orchestr\u00e9 l&rsquo;assassinat de Soleimani, se trouvait \u00e0 bord du E-11A (et aurait trouv\u00e9 la mort, par cons\u00e9quent). Quoique qualifi\u00e9e de \u00ab\u00a0<em>highly dubious<\/em>\u00ab\u00a0, l&rsquo;information a \u00e9t\u00e9 n\u00e9anmoins reprise <a href=\"https:\/\/www.veteranstoday.com\/2020\/01\/28\/vt-cited-by-uk-daily-mail-for-breaking-spy-plane-story-with-russian-help\/\">par le <em>Daily Mail<\/em><\/a>.<\/p>\n<\/p>\n<p><p>Cela fait beaucoup d&rsquo;agitations autour de cette nouvelle dimension a\u00e9rienne, offensive et d\u00e9fensive, en Afghanistan, dans un conflit jusqu&rsquo;ici essentiellement de type terrestre avec adjonction de forces et d&rsquo;appui a\u00e9rotransport\u00e9s. Il est pour l&rsquo;instant extr\u00eamement difficile d&rsquo;avoir une image g\u00e9n\u00e9rale pr\u00e9cise de cette \u00e9volution, &ndash; et d&rsquo;abord si elle a bien lieu, si elle est importante, si elle est sp\u00e9cifique et significative, etc. Des sp\u00e9culations aussi nombreuses autour d&rsquo;un \u00e9v\u00e9nement dont certains faits sont av\u00e9r\u00e9s (augmentation drastiques des sorties de combat de l&rsquo;USAF, crash du E-11A) font penser qu&rsquo;il existe effectivement une dynamique nouvelle dans un conflit qui est proche de sa vingti\u00e8me ann\u00e9e dans la dur\u00e9e, qui est encalmin\u00e9 dans une montagne de <em>narrative<\/em>qui laissent parfois filtrer quelques  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a>, jusqu&rsquo;\u00e0 nous faire parler de  \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/lere-dupost-simulacre\">contre-simulacres<\/a>\u00ab\u00a0&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>Selon une logique intuitive que nous affectionnons dans la mesure o&ugrave; elle permet d&rsquo;\u00e9ventuellement ouvrir des horizons nouveaux, on dira qu&rsquo;une possibilit\u00e9 s\u00e9rieuse existe qu&rsquo;il s&rsquo;agisse d&rsquo;un tournant dans le conflit afghan, si les forces US se trouvent dans une position de moins en moins ais\u00e9e \u00e0 tenir, avec de possibles pressions internes aux USA pour un retrait. D&rsquo;autre part, on pourrait voir dans une telle possibilit\u00e9 une connexion directe avec une mont\u00e9e de l&rsquo;activit\u00e9 iranienne asym\u00e9trique anti-US \u00e0 la suite de l&rsquo;assassinat de Soleimani. Il y a donc beaucoup d&rsquo;interf\u00e9rences, suffisamment pour ne pas voir dans ces sp\u00e9culations, justement, que des sp\u00e9culations gratuites et sans fondement.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 30 janvier 2020 \u00e0 16H25<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Afghanistan vu d&rsquo;en haut Plusieurs articles signalent l&rsquo;intensification consid\u00e9rable en Afghanistan de la guerre a\u00e9rienne US, &ndash; ou plut\u00f4t, de la guerre US en Afghanistan de plus en plus concentr\u00e9e dans l&rsquo;intervention a\u00e9rienne contre les forces terrestres \u00ab\u00a0ennemies\u00a0\u00bb, accompagn\u00e9es bien entendu des innombrables dommages \u00ab\u00a0collat\u00e9raux\u00a0\u00bb frappant les civils. Les textes suivent la publication par le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3020,10372,3578,19664,5147,2773,2970,5197,4896,4014,2892,3959,13985,4146,6925,19665,19666],"class_list":["post-79084","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-aerienne","tag-alabama","tag-duff","tag-e-11a","tag-gordon","tag-iran","tag-missiles","tag-modele","tag-moon","tag-of","tag-offensive","tag-sol-air","tag-soleimani","tag-talibans","tag-today","tag-veteran","tag-vietnamien"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79084"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79084\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}