{"id":79088,"date":"2020-02-02T11:19:18","date_gmt":"2020-02-02T11:19:18","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/02\/introspection-de-la-riposte-iranienne\/"},"modified":"2020-02-02T11:19:18","modified_gmt":"2020-02-02T11:19:18","slug":"introspection-de-la-riposte-iranienne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/02\/introspection-de-la-riposte-iranienne\/","title":{"rendered":"Introspection de la riposte iranienne"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Introspection de la riposte iranienne<\/h2>\n<\/p>\n<p><p>Dans ce texte et selon sa d\u00e9marche habituelle dont on conna&icirc;t la valeur et l&rsquo;orientation, E.J. Magnier expose le d\u00e9tail de la d\u00e9cision, des plans et des intentions de la riposte iranienne \u00e0 l&rsquo;assassinat de Soleimani. Comme \u00e0 l&rsquo;habitude, on sait quelles sont ses sources, \u00e0 la fois s&ucirc;res et nettement orient\u00e9es. Mais dans un monde o&ugrave; la r\u00e9alit\u00e9 est pulv\u00e9ris\u00e9e, la  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> se trouve dans la confrontation des <em>narrative <\/em>des acteurs, des observateurs et des commentateurs. Pour ce cas, nous dirons en esp\u00e9rant ne surprendre personne que nous accordons beaucoup plus d&rsquo;int\u00e9r\u00eat et de v\u00e9racit\u00e9 \u00e0 la <em>narrative <\/em>iranienne ou de la tendance iranienne (de la tendance de l'\u00a0\u00bbAxe de la R\u00e9sistance\u00a0\u00bb) qu&rsquo;\u00e0 la <em>narrative <\/em>am\u00e9ricaniste, si seulement il y en a une plut\u00f4t que les myriades habituelles dans l&rsquo;usine \u00e0 gaz de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>L&rsquo;int\u00e9r\u00eat du texte de Magnier est surtout de nous faire p\u00e9n\u00e9trer dans la psychologie des dirigeants iraniens au travers des ripostes envisag\u00e9es, de la r\u00e9solution affirm\u00e9e, de la prise de responsabilit\u00e9 des cons\u00e9quences. Il en d\u00e9coule aussit\u00f4t une meilleure compr\u00e9hension de l&rsquo;attitude am\u00e9ricaniste apr\u00e8s l&rsquo;attaque et de ce que doivent \u00eatre les effets psychologiques de la riposte iranienne.<\/p>\n<\/p>\n<p><p>Ce que nous montre le texte, et certainement ce que les Iraniens veulent montrer indirectement par leurs confidences et leurs explications, c&rsquo;est l&rsquo;affichage d&rsquo;une r\u00e9solution sans faille, d&rsquo;une volont\u00e9 absolue de ne rien accepter de la part des USA, de riposter \u00e0 mesure m\u00eame si cette mesure est celle de la guerre totale, et tout cela avec les moyens de le faire. Il appara&icirc;t, \u00e0 lire ce texte, que les Iraniens \u00e9taient pr\u00eats \u00e0 aller jusqu&rsquo;au bout, c&rsquo;est-\u00e0-dire au d\u00e9clenchement de cette \u00ab\u00a0guerre asym\u00e9trique totale\u00a0\u00bb, qui semble une mani\u00e8re nouvelle et d\u00e9vastatrice de d\u00e9fier et de mettre en tr\u00e8s grande danger la puissance conventionnelle et nucl\u00e9aire totale que pr\u00e9tendent \u00eatre les USA.<\/p>\n<\/p>\n<p><p>Nous parlons ici encore bien plus de psychologie que de moyens militaires et de technologie, et l&rsquo;on sait l&rsquo;exceptionnelle, &ndash; exceptionnalisme am\u00e9ricaniste oblige, &ndash; l&rsquo;exceptionnelle faiblesse des USA dans la compr\u00e9hension de la psychologie des autres ; d&rsquo;o&ugrave; la surprise un peu effray\u00e9e qu&rsquo;ils ont d&ucirc; \u00e9prouver durant cette s\u00e9quence&#8230; En effet, la r\u00e9solution iranienne appara&icirc;t effectivement in\u00e9branlable et Magnier insiste sur le fait que les Iraniens sont le seul pays engag\u00e9 dans la r\u00e9gion, et peut-\u00eatre l&rsquo;un des seuls voire le seul pays au monde, qui n&rsquo;acceptera pas de se soumettre, m\u00eame par simple choix tactique et temporaire, au <em>diktat <\/em>irresponsable des USA. Dans cette remarque, la Russie, bien que plut\u00f4t amie de l&rsquo;Iran, est cit\u00e9e :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Lorsque les USA ont bombard\u00e9 des centaines de sous-traitants russes qui traversaient l&rsquo;Euphrate \u00e0 la hauteur de Deir Ezzor, en Syrie, pour pourchasser le reliquat de militants de Daech, la Russie a choisi de ne rien faire. Aucun pays ou arm\u00e9e du Moyen-Orient n&rsquo;a os\u00e9 d\u00e9fier les USA, notamment lorsque ceux-ci y ont d\u00e9ploy\u00e9 des dizaines de milliers de militaires et d&rsquo;effectifs. Seul l&rsquo;Iran s&rsquo;oppose directement \u00e0 l&rsquo;h\u00e9g\u00e9monie et \u00e0 la puissance militaire des USA<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Maintenant, voyons un point qui nous int\u00e9resse grandement et qui, d&rsquo;une certaine fa\u00e7on, constitue un bon indicateur des positions des uns et des autres dans cette s\u00e9quence.  <a href=\"https:\/\/www.dedefensa.org\/article\/les-mecomptes-du-pentagone\">Comme l&rsquo;on sait<\/a>, nous avons beaucoup d&rsquo;int\u00e9r\u00eat pour la cause du comportement si inhabituel du Pentagone, qui nous distille au goutte-\u00e0-goutte les nouvelles des dizaines de bless\u00e9s US \u00e0 la suite de l&rsquo;attaque iranienne pour, \u00e0 la fois et paradoxalement, faire mieux passer en douceur le suppositoire et nous rappeler constamment qu&rsquo;il s&rsquo;agit d&rsquo;un suppositoire. Cela signifie, en consultant le texte de Magnier comme lui-m\u00eame l&rsquo;\u00e9crit, que dans les hypoth\u00e8ses que nous  <a href=\"https:\/\/www.dedefensa.org\/article\/les-mecomptes-du-pentagone\">envisagions hier<\/a> pour expliquer ce comportement du Pentagone, nous choisirions celle o&ugrave; il est dit <\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Ou bien encore, le comportement si inhabituel du Pentagone est-il fait pour souligner la puissance des Iraniens et les risques que courent les forces US dans la r\u00e9gion, cette attitude contre ceux des dirigeants civils trop neocon (les exemples ne manquent pas), ou trop inconscients, comme Trump par instants, qui s&rsquo;engageraient sans h\u00e9siter sur la voie de l&rsquo;affrontement ? C&rsquo;est une hypoth\u00e8se audacieuse, mais rien ne doit \u00eatre exclu dans le domaine de l&rsquo;audace, aujourd&rsquo;hui \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voici le passage (en conclusion) du texte de Magnier o&ugrave; nous voyons \u00e9clair\u00e9s le comportement du Pentagone et quelques autres aspects de cette s\u00e9quence d&rsquo;affrontement tr\u00e8s intense o&ugrave; les uns et les autres, selon leur attention et leur capacit\u00e9 de compr\u00e9hension des choses hors de soi-m\u00eame, ont plus ou moins beaucoup appris les uns sur les autres&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>La magie s&rsquo;est retourn\u00e9e contre le magicien et Trump a offert \u00e0 l&rsquo;Iran un immense cadeau en lui permettant de bombarder son arm\u00e9e et de le d\u00e9fier ouvertement. Trump n&rsquo;a pas os\u00e9 annoncer le nombre de victimes la premi\u00e8re semaine. Le Pentagone a commenc\u00e9 \u00e0 d\u00e9voiler une partie de la r\u00e9alit\u00e9 chaque semaine. Les USA, et non pas l&rsquo;Iran, montrent ainsi qu&rsquo;ils ont peur<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Comme on le lit, les deux derni\u00e8res phrases, &ndash; &laquo; <em>Le Pentagone a commenc\u00e9 \u00e0 d\u00e9voiler une partie de la r\u00e9alit\u00e9 chaque semaine. Les USA, et non pas l&rsquo;Iran, montrent ainsi qu&rsquo;ils ont peur<\/em> &raquo;, &ndash;vont dans le sens de l&rsquo;explication de la crainte du Pentagone pour ce qui concerne l&rsquo;id\u00e9e d&rsquo;affronter l&rsquo;Iran, qui est communiqu\u00e9e indirectement par ce d\u00e9voilement tr\u00e8s <em>soft <\/em>mais significatif des pertes subies par les forces US ;<\/p>\n<p>&bull; L\u00e0 o&ugrave; nous avons une perception diff\u00e9rente, c&rsquo;est sur le constat que &laquo; <em>Trump n&rsquo;a pas os\u00e9 annoncer le nombre de victimes la premi\u00e8re semaine<\/em> &raquo;, puisqu&rsquo;il a r\u00e9agi aussit\u00f4t en annon\u00e7ant qu&rsquo;il n&rsquo;y avait aucune perte, alors qu&rsquo;effectivement il est tout \u00e0 fait probable qu&rsquo;on ne savait pas encore pr\u00e9cis\u00e9ment les r\u00e9sultats de l&rsquo;attaque et qu&rsquo;on ne pouvait encore confirmer rien de pr\u00e9cis ; tout cela avant, dans les jours suivants, de noyer le poisson en \u00e9cartant les questions sur les bless\u00e9s d&rsquo;une fa\u00e7on cavali\u00e8re et totalement indiff\u00e9rente, caract\u00e9ristique de Trump ; <\/p>\n<p>&bull; Mais ce passage veut \u00e9galement signifier au lecteur que la perception de la s\u00e9quence est bien que les USA ont accept\u00e9 d&rsquo;\u00eatre frapp\u00e9s par l&rsquo;Iran sans riposter, certainement par crainte d&rsquo;un encha&icirc;nement de ripostes o&ugrave; ils avaient beaucoup, beaucoup \u00e0 perdre. La \u00ab\u00a0pression maximale\u00a0\u00bb n&rsquo;est pas une exclusivit\u00e9 US (sanctions US contre l&rsquo;Iran), et il s&rsquo;av\u00e8re que les Iraniens sembleraient savoir en user \u00e9galement dans le domaine de la psychologie, &ndash; d&rsquo;ailleurs, pour la seule raison qu&rsquo;ils ne bluffent pas dans l&rsquo;affichage de leur r\u00e9solution.<\/p>\n<\/p>\n<p><p>Encore une fois, il s&rsquo;agit d&rsquo;une analyse qui vient d&rsquo;un c\u00f4t\u00e9 et qui nous offre la version iranienne. Encore une fois, nous ne pouvons assurer la validit\u00e9 de la version iranienne mais nous serions tent\u00e9s de pencher vers elle, ne serait-ce que pour la seule cause antagoniste de la puanteur et de la pourriture de toute version-Syst\u00e8me de provenance am\u00e9ricaniste, o&ugrave; s&#8217;empilent simulacre, mensonge, corruption de la psychologie et n\u00e9antisation de l&rsquo;esprit, et entra&icirc;nement joyeux \u00e0 l&rsquo;autodestruction. Il est effectivement question, dans ce cas, d&rsquo;une histoire de suppositoires&#8230;<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il soit, nous ne pouvons que confirmer notre appr\u00e9ciation que la mort de g\u00e9n\u00e9ral Soleimani est bien un \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/un-assassinat-metahistorique\">assassinat m\u00e9tahistorique<\/a>\u00a0\u00bb qui change le sens et l&rsquo;orientation du r\u00e9cit des \u00e9v\u00e9nements dans la r\u00e9gion, et au sein du tourbillon crisique de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me&#8230; Le texte ci-dessous est donc de Elijah J. Magnier (traduction de Daniel G.), du <a href=\"https:\/\/ejmagnier.com\/2020\/02\/01\/comment-liran-en-est-venu-a-bombarder-des-bases-us-et-comment-trump-a-evite-une-guerre-totale\/\">1<sup>er<\/sup>f\u00e9vrier 2020<\/a>.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>______________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Comment l&rsquo;Iran en est venu \u00e0 riposter <\/h2>\n<\/p>\n<p><p>Peu apr\u00e8s minuit le 3 janvier, la nouvelle de l&rsquo;assassinat du major g\u00e9n\u00e9ral iranien Qassem Soleimani, du brigadier g\u00e9n\u00e9ral Hussein Pourjafari, du colonel Shahroud Muzaffari Nia, du major Hadi Tameri et du capitaine Wahid Zamaniam est parvenue \u00e0 l&rsquo;ambassade de l&rsquo;Iran \u00e0 Bagdad. Des officiers \u00e0 l&rsquo;ambassade \u00e9taient en contact avec le convoi lorsque la communication s&rsquo;est soudainement interrompue. Sardar Soleimani jouissait d&rsquo;une immunit\u00e9 diplomatique et avait \u00e9t\u00e9 invit\u00e9 officiellement par le gouvernement irakien \u00e0 contribuer \u00e0 la d\u00e9faite de Daech. De plus, l&rsquo;attaque contre le convoi s&rsquo;est produite \u00e0 proximit\u00e9 d&rsquo;un point de contr\u00f4le irakien, o&ugrave; l&rsquo;on savait que le commandant irakien Abou Mahdi al-Muhandes et l&rsquo;\u00e9quipe assurant sa protection faisaient partie du convoi. La nouvelle a \u00e9t\u00e9 communiqu\u00e9e \u00e0 T\u00e9h\u00e9ran, puis \u00e0 la demeure du guide de la R\u00e9volution iranienne Sayyed Ali Khamenei.<\/p>\n<\/p>\n<p><p>&laquo; &Agrave; Dieu nous appartenons et \u00e0 lui nous retournerons. &raquo; C&rsquo;est ce verset du Coran qu&rsquo;un croyant prononce lorsqu&rsquo;il apprend la mort d&rsquo;une personne qu&rsquo;il conna&icirc;t de loin ou de proche. C&rsquo;est un rappel que tous les \u00eatres humains sont mortels. Ce fut la premi\u00e8re r\u00e9action de Sayyed Khamenei lorsque la nouvelle de la mort &laquo; d&rsquo;un fils &raquo; lui est parvenue. Ce qui montre jusqu&rsquo;\u00e0 quel point Sardar Soleimani \u00e9tait proche de Sayyed Khamenei. Soleimani d\u00e9tenait le titre de &laquo; martyr vivant &raquo; en raison des nombreuses fois o&ugrave; sa vie a \u00e9t\u00e9 mise en danger en combattant Daech et al-Qaeda en Irak et en Syrie. <\/p>\n<\/p>\n<p><p>Le premier janvier, Soleimani a quitt\u00e9 Beyrouth et a dormi en Syrie, pas loin de l&rsquo;a\u00e9roport de Damas. &Agrave; chacun de ses voyages en Syrie, il r\u00e9unissait tous ses commandants apr\u00e8s la pri\u00e8re du matin, juste avant le lever du soleil, pendant tout au plus deux heures. Ce jour-l\u00e0, tous les commandants sont rest\u00e9s pendant le d\u00e9jeuner et n&rsquo;ont \u00e9t\u00e9 autoris\u00e9s \u00e0 partir qu&rsquo;au coucher du soleil. Soleimani n&rsquo;arr\u00eatait pas de parler, en donnant ses instructions \u00e0 son \u00e9quipe de commandants au Levant. Le capitaine Wahid Zamaniam \u00e9tait son compagnon ins\u00e9parable. &Agrave; son arriv\u00e9e \u00e0 l&rsquo;a\u00e9roport de Bagdad, le major g\u00e9n\u00e9ral \u00e9tait accueilli par des responsables iraniens et irakiens lorsqu&rsquo;un drone am\u00e9ricain les a tous assassin\u00e9s.  <\/p>\n<\/p>\n<p><p>Selon une source bien inform\u00e9e au sein de l&rsquo;Axe de la R\u00e9sistance, lorsqu&rsquo;il a \u00e9t\u00e9 mis au courant de l&rsquo;assassinat, Sayyed Khamenei a convoqu\u00e9 une r\u00e9union de ses commandants dans les heures qui ont suivi le meurtre, en donnant les instructions suivantes : &laquo; Pr\u00e9parez-vous \u00e0 une riposte dure. Nous devons d\u00e9clarer notre responsabilit\u00e9 directe, pour que nos ennemis sachent que nous les affrontons ouvertement et non d&rsquo;une mani\u00e8re l\u00e2che comme les USA l&rsquo;ont fait en tuant Soleimani et ses compagnons. Frappez durement l&rsquo;arm\u00e9e am\u00e9ricaine pour briser leur arrogance l\u00e0 o&ugrave; ils ont perp\u00e9tr\u00e9 ce vil assassinat. &raquo; <\/p>\n<\/p>\n<p><p>Bon nombre de sc\u00e9narios ont \u00e9t\u00e9 pr\u00e9sent\u00e9s \u00e0 Sayyed Khamenei. Le premier choix \u00e9tait Ayn al-Assad, la base a\u00e9rienne la plus importante et imposante en Irak, l\u00e0 o&ugrave; le pr\u00e9sident Trump avait atterri et qu&rsquo;il consid\u00e9rait comme l&rsquo;endroit le plus s&ucirc;r en Irak. L&rsquo;Iran conna&icirc;t cette base dans ses moindres d\u00e9tails. Ses drones et ses services du renseignement avaient suffi pour savoir ce que contenait chaque hangar et installation de la base.<\/p>\n<\/p>\n<p><p>Une deuxi\u00e8me frappe \u00e9tait \u00e9galement pr\u00e9vue contre une base US \u00e0 l&rsquo;ext\u00e9rieur de l&rsquo;Irak de l&rsquo;autre c\u00f4t\u00e9 du golfe Persique, qui aurait \u00e9t\u00e9 plus puissante et douloureuse que le premier objectif, au cas o&ugrave; les USA auraient ripost\u00e9 \u00e0 la frappe d&rsquo;Ayn al-Assad. <\/p>\n<\/p>\n<p><p>Une troisi\u00e8me frappe \u00e9tait \u00e9galement dans les plans, qui aurait \u00e9t\u00e9 encore plus puissante et d\u00e9vastatrice que les deux premi\u00e8res, contre la base US la plus importante du Moyen-Orient. Cette frappe visait \u00e0 faire de nombreuses victimes, un nombre de loin sup\u00e9rieur \u00e0 toutes repr\u00e9sailles possibles des USA.<\/p>\n<\/p>\n<p><p>Trois plans et trois sc\u00e9narios donc, tous pr\u00e9vus pour \u00eatre ex\u00e9cut\u00e9s l&rsquo;un apr\u00e8s l&rsquo;autre pour en faire trois frappes cons\u00e9cutives. Sayyed Ali Khamenei a approuv\u00e9 ces trois ripostes, \u00e9vitant ainsi \u00e0 ses commandants d&rsquo;avoir \u00e0 le convaincre pour obtenir sa b\u00e9n\u00e9diction. Sayyed Khamenei a ensuite demand\u00e9 \u00e0 ses commandants de revenir pour obtenir de nouvelles instructions et appeler \u00e0 une mobilisation g\u00e9n\u00e9rale au pays, qui aurait d\u00e9clar\u00e9 une guerre ouverte contre les USA en cas de ripostes militaires des USA contre toutes les frappes iraniennes. Pour ce dernier sc\u00e9nario, Sayyed Khamenei a ordonn\u00e9 un plan pr\u00e9voyant le lancement simultan\u00e9 de centaines de missiles contre toutes les bases militaires am\u00e9ricaines dans les pays entourant l&rsquo;Iran, au Levant et ailleurs. Tous les alli\u00e9s de l&rsquo;Iran au Moyen-Orient auraient \u00e9t\u00e9 impliqu\u00e9s et les alli\u00e9s des USA auraient \u00e9t\u00e9 frapp\u00e9s directement. Mais cette d\u00e9cision ultime devait \u00eatre r\u00e9\u00e9valu\u00e9e une derni\u00e8re fois par Sayyed Khamenei.<\/p>\n<\/p>\n<p><p>C&rsquo;est ce sc\u00e9nario pr\u00e9visible que s&rsquo;est \u00e9vit\u00e9 le pr\u00e9sident des USA en d\u00e9cidant de ne pas intervenir, malgr\u00e9 les souffrances humaines et la destruction inflig\u00e9es dans l&rsquo;attaque de la base militaire d&rsquo;Ayn al-Assad. <\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;Iran n&rsquo;a utilis\u00e9 aucun missile provenant de ses silos pour frapper les cibles am\u00e9ricaines \u00e0 Ayn al-Assad. Bien au contraire, les missiles \u00e9taient d\u00e9ploy\u00e9s ouvertement et pr\u00eats \u00e0 \u00eatre lanc\u00e9s deux jours avant, au vu et au su des satellites US. L&rsquo;Iran n&rsquo;arr\u00eatait pas de recevoir des messages de diplomates lui demandant de s&rsquo;abstenir de repr\u00e9sailles ou d&rsquo;en limiter la port\u00e9e. Toutes ces demandes ont \u00e9t\u00e9 rejet\u00e9es. L&rsquo;Iran a \u00e9vit\u00e9 de surprendre les USA; s&rsquo;il avait voulu le faire, les missiles auraient \u00e9t\u00e9 lanc\u00e9s \u00e0 partir de ses silos sans avertissement. C&rsquo;\u00e9tait un affront direct \u00e0 l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaine. De plus, l&rsquo;Iran a inform\u00e9 les USA que la frappe allait avoir lieu, d\u00e9fiant encore plus le pr\u00e9sident Trump et son arsenal militaire au Moyen-Orient pour montrer qu&rsquo;il ne craignait pas les cons\u00e9quences &raquo;, a expliqu\u00e9 la source. <\/p>\n<\/p>\n<p><p>L&rsquo;Iran a envoy\u00e9 ses drones survoler les bases US au Kowe\u00eft, au Qatar, en Arabie saoudite, dans les &Eacute;mirats et dans d&rsquo;autres pays avoisinants. C&rsquo;\u00e9tait un signal montrant que T\u00e9h\u00e9ran s&rsquo;\u00e9tait pr\u00e9par\u00e9 pour la guerre et une indication de ce qui fait partie de sa panoplie d&rsquo;objectifs. Les dirigeants de l&rsquo;Iran \u00e9taient pr\u00eats \u00e0 d\u00e9passer le point de non-retour si n\u00e9cessaire. <\/p>\n<\/p>\n<p><p>Personne en Iran n&rsquo;est pr\u00eat \u00e0 abandonner son programme de missile qui est devenu la fiert\u00e9 du peuple iranien et de ses forces arm\u00e9es. Lorsque les USA ont bombard\u00e9 des centaines de sous-traitants russes qui traversaient l&rsquo;Euphrate \u00e0 la hauteur de Deir Ezzor, en Syrie, pour pourchasser le reliquat de militants de Daech, la Russie a choisi de ne rien faire. Aucun pays ou arm\u00e9e du Moyen-Orient n&rsquo;a os\u00e9 d\u00e9fier les USA, notamment lorsque ceux-ci y ont d\u00e9ploy\u00e9 des dizaines de milliers de militaires et d&rsquo;effectifs. Seul l&rsquo;Iran s&rsquo;oppose directement \u00e0 l&rsquo;h\u00e9g\u00e9monie et \u00e0 la puissance militaire des USA. <\/p>\n<\/p>\n<p><p>L&rsquo;Axe de la R\u00e9sistance a confirm\u00e9 l&rsquo;\u00e9quilibre de la peur et l&rsquo;imposition d&rsquo;une politique de dissuasion sur les USA au Moyen-Orient. L&rsquo;Iran a d\u00e9fi\u00e9 ouvertement les USA en revendiquant sa responsabilit\u00e9 sans craindre les cons\u00e9quences. Les USA ont confirm\u00e9 jusqu&rsquo;ici que 64 personnes ont subi des contrecoups de l&rsquo;attaque iranienne. Un peu plus t\u00f4t, l&rsquo;Iran avait annonc\u00e9 &laquo; pas moins de 80 victimes am\u00e9ricaines &raquo;. <\/p>\n<\/p>\n<p><p>Le pr\u00e9sident Trump croyait vivre un moment historique de sa vie, o&ugrave; il pouvait faire tout ce qu&rsquo;il voulait sans craindre les cons\u00e9quences. Il croyait qu&rsquo;aucun pays du monde n&rsquo;oserait le d\u00e9fier. On lui disait aussi que l&rsquo;Irak \u00e9tait divis\u00e9, qu&rsquo;aucun gouvernement ne contesterait la violation de sa souverainet\u00e9 et que l&rsquo;Iran n&rsquo;\u00e9tait plus tol\u00e9r\u00e9 en M\u00e9sopotamie. On lui a probablement dit que le feu mis \u00e0 deux consulats iraniens suffirait \u00e0 faire partir l&rsquo;Iran de l&rsquo;Irak. Peut-\u00eatre s&rsquo;imaginait-il que l&rsquo;assassinat de Sardar Qassem Soleimani resterait impuni, quand il s&rsquo;est vant\u00e9 d&rsquo;en avoir tu\u00e9 &laquo; deux pour le prix d&rsquo;un &raquo;. Lui et son \u00e9quipe de bellicistes croyaient (et croient encore selon moi) que sa &laquo; pression maximale &raquo; et ses dures sanctions feraient plier l&rsquo;\u00e9chine \u00e0 l&rsquo;Iran et l&rsquo;obligeraient \u00e0 demander gr\u00e2ce. Il disait attendre l&rsquo;appel t\u00e9l\u00e9phonique de l&rsquo;Iran, ce qui en dit long sur sa m\u00e9connaissance de l&rsquo;Iran, de sa mentalit\u00e9, de sa culture, de sa patience, de sa rigueur et de sa fiert\u00e9. <\/p>\n<\/p>\n<p><p>La magie s&rsquo;est retourn\u00e9e contre le magicien et Trump a offert \u00e0 l&rsquo;Iran un immense cadeau en lui permettant de bombarder son arm\u00e9e et de le d\u00e9fier ouvertement. Trump n&rsquo;a pas os\u00e9 annoncer le nombre de victimes la premi\u00e8re semaine. Le Pentagone a commenc\u00e9 \u00e0 d\u00e9voiler une partie de la r\u00e9alit\u00e9 chaque semaine. Les USA, et non pas l&rsquo;Iran, montrent ainsi qu&rsquo;ils ont peur.<\/p>\n<\/p>\n<p><p>&laquo; Toutes les bases militaires US sont devenues une menace pour les pays o&ugrave; elles se trouvent au Moyen-Orient. Ces bases ne servent plus \u00e0 prot\u00e9ger ces pays et constituent pour l&rsquo;Iran une liste imposante de cibles parfaites. Aucun endroit ne sera s&ucirc;r pour les forces US au Moyen-Orient si elles d\u00e9passent la ligne \u00e0 ne pas franchir, comme ce fut le cas apr\u00e8s l&rsquo;assassinat de Sardar Soleimani &raquo;, a pr\u00e9cis\u00e9 la source.<\/p>\n<\/p>\n<p><h4>Elijah J. Magnier<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introspection de la riposte iranienne Dans ce texte et selon sa d\u00e9marche habituelle dont on conna&icirc;t la valeur et l&rsquo;orientation, E.J. Magnier expose le d\u00e9tail de la d\u00e9cision, des plans et des intentions de la riposte iranienne \u00e0 l&rsquo;assassinat de Soleimani. Comme \u00e0 l&rsquo;habitude, on sait quelles sont ses sources, \u00e0 la fois s&ucirc;res et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[19615,7029,3745,3680,15075,5518,2631,8794,2645,857,2773,7177,14999,2622,17191,3194,2755,5812,2883,13985,2861,2639],"class_list":["post-79088","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-al-assad","tag-assassinat","tag-asymetrique","tag-axe","tag-ayn","tag-base","tag-de","tag-e-j","tag-guerre","tag-irak","tag-iran","tag-iranienne","tag-khameini","tag-la","tag-magnier","tag-pentagone","tag-resistance","tag-resolution","tag-riposte","tag-soleimani","tag-totale","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79088"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79088\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}