{"id":79100,"date":"2020-02-10T14:27:10","date_gmt":"2020-02-10T14:27:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/10\/deconstructuration-du-deconstructeur\/"},"modified":"2020-02-10T14:27:10","modified_gmt":"2020-02-10T14:27:10","slug":"deconstructuration-du-deconstructeur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/10\/deconstructuration-du-deconstructeur\/","title":{"rendered":"\u201cD\u00e9constructuration\u201d du d\u00e9constructeur"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">\u00ab\u00a0D\u00e9constructuration\u00a0\u00bb du d\u00e9constructeur<\/h2>\n<\/p>\n<p><p>10 f\u00e9vrier 2020 &ndash;  Nous avions consacr\u00e9  <em>in illo tempore  <\/em>(le  <a href=\"http:\/\/www.dedefensa.org\/article\/lentropisation-de-lentropie-postmoderne\">30 d\u00e9cembre 2017<\/a>) un  <em>F&#038;C  <\/em>s&rsquo;appuyant sur un texte du  <a href=\"http:\/\/www.theamericanconservative.com\/articles\/beyond-cynicism-america-fumbles-towards-kafkas-castle\/\">21 d\u00e9cembre 2017<\/a>  que James Edward Kunstler consacrait \u00e0 la situation crisique extraordinaire o&ugrave; se trouve emport\u00e9e l&rsquo;Am\u00e9rique, &ndash; et les 26 mois depuis ce texte n&rsquo;ont fait qu&rsquo;accentuer la tendance et justifi\u00e9 les remarques ainsi rappel\u00e9es. Kunstler parlait d&rsquo;une situation d'\u00a0\u00bbirr\u00e9alit\u00e9\u00a0\u00bb (terme qui se marie avec tant de nos concepts) et citait deux \u00ab\u00a0op\u00e9rationnalisation de [cette] irr\u00e9alit\u00e9\u00a0\u00bb qui, \u00e0 notre avis, se compl\u00e8tent pour donner toute sa puissance \u00e0 l&rsquo;\u00e9pisode crisique fondamental et d\u00e9cisif commenc\u00e9 en 2015-2016 aux USA et qui ne cesse de s&rsquo;affirmer et de se d\u00e9velopper en pleine surpuissance.<\/p>\n<\/p>\n<p><p>(C&rsquo;en est au point o&ugrave;  <a href=\"https:\/\/www.infowars.com\/bannon-trump-shouldnt-deliver-sotu-until-after-senate-impeachment-acquittal\/\">un Steve Bannon<\/a>  qualifie la fin de la proc\u00e9dure de destitution de Trump par son acquittement de \u00ab\u00a0Fin de l&rsquo;Acte I\u00a0\u00bb : &laquo; <em>Nancy Pelosi et tous ces gens ne vont certainement pas s&rsquo;arr\u00eater. L&rsquo;acquittement formel de mercredi <\/em>[5 f\u00e9vrier 2020] <em>est juste le rideau qui tombe sur l&rsquo;Acte I. La pi\u00e8ce va continuer. <\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Nous nous attachons ici \u00e0 l&rsquo;explication de Kunstler de la deuxi\u00e8me \u00ab\u00a0op\u00e9rationnalisation de l&rsquo;irr\u00e9alit\u00e9\u00a0\u00bb, celle qui est d\u00e9velopp\u00e9e par le progressisme-soci\u00e9tal. Nous citons le passage d\u00e9crivant cet \u00e9v\u00e8nement<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; &#8230; <em>La seconde est ainsi synth\u00e9tis\u00e9e par Kunstler, \u00e0 propos <strong>des diff\u00e9rentes facettes du progressisme-soci\u00e9tal tel qu&rsquo;il s&rsquo;est d\u00e9velopp\u00e9 \u00e0 une vitesse extraordinaire depuis 2015-2016<\/strong>, essentiellement \u00e0 l&rsquo;occasion de la campagne puis de l&rsquo;\u00e9lection de Donald Trump :<\/em><\/p>\n<\/p>\n<p><p>&raquo; \u00a0\u00bb <em>L&rsquo;id\u00e9e nouvelle et fausse que quelque chose \u00e9tiquet\u00e9 &lsquo;discours de haine&rsquo; &ndash; \u00e9tiquet\u00e9 par qui ? &ndash;\u00e9quivaut \u00e0 la violence qu&rsquo;il d\u00e9crit flottait autour des \u00e9tablissements d&rsquo;enseignement des cycles sup\u00e9rieurs en un nuage toxique d&rsquo;hyst\u00e9rie intellectuelle concoct\u00e9 dans le laboratoire de la philosophie dite \u00ab\u00a0post-structuraliste\u00a0\u00bb, o&ugrave; gisaient des parties des corps de Michel Foucault, <strong>Jacques Derrida<\/strong>, Judith Butler et Gilles Deleuze, qui seraient surmont\u00e9 d&rsquo;un cerveau fait d&rsquo;un tiers de Thomas Hobbes, d&rsquo;un tiers de Saul Alinsky et d&rsquo;un tiers de Tupac Shakur, le tout donnant un parfait Frankenstein accouchant d&rsquo;une monstrueuse pens\u00e9e&#8230; \u00ab\u00a0<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce passage est d&rsquo;une extr\u00eame importance pour nous, dans la mesure essentiellement o&ugrave; Kunstler mentionne quelques noms de \u00ab\u00a0d\u00e9constructivistes\u00a0\u00bb dont la pens\u00e9e p\u00e8se sur notre \u00e9poque, &ndash; non pour l&rsquo;aider \u00e0 reconstruire quelque chose sur ce qui aurait \u00e9t\u00e9 d\u00e9truit <strong>mais pour la pousser, pour l&rsquo;entra&icirc;ner, pour l&#8217;emprisonner dans une irr\u00e9sistible pulsion de destruction<\/strong>, quel que soit l&rsquo;objet \u00e0 d\u00e9truire. (\u00ab\u00a0Destruction\u00a0\u00bb plut\u00f4t que \u00ab\u00a0mort\u00a0\u00bb parce que ces d\u00e9constructivistes pensent finalement que la destruction n&rsquo;est pas la mort, &ndash; et c&rsquo;est en cela que cette pens\u00e9e est singuli\u00e8rement diabolique.)<\/em>&#8230; &raquo; <\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;on voit l&rsquo;importance d\u00e9terminante que Kunstler attribue \u00e0 un courant philosophique bien connu, celui que l&rsquo;on identifie principalement comme la th\u00e9orie et l&rsquo;\u00e9cole de la \u00ab\u00a0d\u00e9construction\u00a0\u00bb. Le nom de Jacques Derrida y figure en bonne place et il nous sembla \u00e0 l&rsquo;\u00e9poque, et encore plus aujourd&rsquo;hui, particuli\u00e8rement opportun de revenir sur un texte  <em>F&#038;C<\/em>  (<a href=\"http:\/\/www.dedefensa.org\/article\/la-revelation-de-jacques-derrida\">du 27 avril 2015<\/a>), sur une intervention de Derrida particuli\u00e8rement r\u00e9v\u00e9latrice \u00e0 notre sens.<\/p>\n<\/p>\n<p><p>&Eacute;cout\u00e9e et r\u00e9\u00e9cout\u00e9e, y compris et m\u00eame plus que jamais aujourd&rsquo;hui que nous l&rsquo;avons fait \u00e0 nouveau, cette intervention \u00e0 la fois path\u00e9tique, \u00e9trange et \u00e9clairante, donne \u00e0 l&rsquo;audition non seulement toute sa puissance tragique, mais un renforcement constant de cette puissance tragique \u00e0 chaque nouvelle audition. Cette observation constitue pour nous, en fait d&rsquo;intuition, un argument d&rsquo;une tr\u00e8s grande force pour la r\u00e9flexion que nous en tirons. Cet homme, Derrida, nous sugg\u00e8re involontairement mais du tr\u00e9fonds de lui-m\u00eame des <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a> absolument fondamentales<\/p>\n<\/p>\n<p><p>Dans ce texte de commentaire, nous nous orientions vers une hypoth\u00e8se g\u00e9n\u00e9rale offrant une explication de l&rsquo;\u00e9volution de la politique mondiale dans tous les domaines et ainsi justifiant une appr\u00e9ciation m\u00e9tahistorique. Cette hypoth\u00e8se s&rsquo;appuyait sur l&rsquo;op\u00e9rationnalisation, sous la forme d&rsquo;une intervention catastrophique, de ce que nous nommons la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>, absolument d\u00e9structurante, sans autre but que la d\u00e9structuration (la d\u00e9construction), con\u00e7ue d&rsquo;une fa\u00e7on compl\u00e8tement incontestable comme un ph\u00e9nom\u00e8ne impos\u00e9 par le Syst\u00e8me, lui-m\u00eame \u00e9tant l&rsquo;op\u00e9rationnalisation du  \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>Depuis lors, cet ensemble d&rsquo;observation est compl\u00e9t\u00e9 et renforc\u00e9 d&rsquo;une fa\u00e7on encore plus significative, d&rsquo;une fa\u00e7on d\u00e9vastatrice, \u00e0 un rythme stup\u00e9fiant, dans le cadre furieux et incontr\u00f4lable de la grande crise de l&rsquo;am\u00e9ricanisme et du pouvoir de Washington D.C. ouverte \u00e0 l&rsquo;\u00e9t\u00e9 2015 et qui ne cesse de s&rsquo;aggraver, par l&rsquo;acc\u00e9l\u00e9ration extraordinaire du ph\u00e9nom\u00e8ne de d\u00e9structuration-dissolution que produit le courant doctrinal que nous baptisons \u00ab\u00a0progressisme-soci\u00e9tal\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>(Certains aux USA l&rsquo;identifient comme un ph\u00e9nom\u00e8ne de \u00ab\u00a0marxisme culturel\u00a0\u00bb, qui est une expression selon nous trop marqu\u00e9e et contrainte id\u00e9ologiquement, allant m\u00eame jusqu&rsquo;\u00e0 la contradiction, pour rendre compte de l&rsquo;ampleur formidable, de la vitesse de d\u00e9veloppement stup\u00e9fiante et de la terrifiante originalit\u00e9 du ph\u00e9nom\u00e8ne.)<\/p>\n<\/p>\n<p><p>Datant de 2002, la \u00ab\u00a0confession\u00a0\u00bb involontaire, ou semi-involontaire du philosophe Derrida, \u00e0 partir de sa propre exp\u00e9rience d&rsquo;\u00e9crivain et de penseur de la d\u00e9construction, ne cesse, comme d\u00e9j\u00e0 remarqu\u00e9, d&rsquo;acqu\u00e9rir une force suppl\u00e9mentaire \u00e0 l&rsquo;audition renouvel\u00e9e, \u00e0 la lumi\u00e8re du temps qui passe, tant ce temps qui passe, absolument crisique, produit la crise dont ce philosophe sugg\u00e8re les pr\u00e9misses et la matrice dans les profondeurs d&rsquo;entit\u00e9s inconcevables. Cette confession nous sugg\u00e8re donc plus que jamais, jusqu&rsquo;\u00e0 la confirmer de mani\u00e8re irr\u00e9futable, cette hypoth\u00e8se op\u00e9rationnelle et contradictoire selon laquelle la d\u00e9construction produite par le d\u00e9constructeur alimente \u00e0 une tr\u00e8s grande vitesse, \u00e0 une vitesse multipli\u00e9e par rapport \u00e0 l&rsquo;impulsion contradictoire originelle, un ph\u00e9nom\u00e8ne de d\u00e9construction (d&rsquo;auto-d\u00e9construction) chez ce m\u00eame d\u00e9constructeur.<\/p>\n<\/p>\n<p><p>D&rsquo;une certaine fa\u00e7on, cette observation, qui n&rsquo;est complexe qu&rsquo;en apparence, n&rsquo;est nullement contradictoire avec nos conceptions g\u00e9n\u00e9rales ; l&rsquo;on retrouve dans ce cas de \u00ab\u00a0la d\u00e9construction produite par le d\u00e9constructeur et [alimentant] la d\u00e9construction (l&rsquo;auto-d\u00e9construction) du d\u00e9constructeur\u00a0\u00bb rien de moins qu&rsquo;une variante \u00e9vidente de la formule surpuissance-autodestruction. On comprend, au travers des liens de Derrida avec l&rsquo;\u00e9volution de la pens\u00e9e progressiste-soci\u00e9tale et de la psychologie de l&rsquo;am\u00e9ricanisme, le lien extr\u00eamement fort et r\u00e9v\u00e9lateur que nous offre cet incident (la \u00ab\u00a0confession\u00a0\u00bb de Derrida) avec la situation pr\u00e9sente.<\/p>\n<\/p>\n<p><p>Le texte du 27 avril 2015 repris ci-dessous a \u00e9t\u00e9 \u00e9videmment relu et tr\u00e8s fortement modifi\u00e9 en fonction des plus r\u00e9cents \u00e9v\u00e9nements de ces deux derni\u00e8res ann\u00e9es. Il nous para&icirc;t plus pertinent que jamais, encore plus aujourd&rsquo;hui (2020) qu&rsquo;hier (2015) et digne d&rsquo;\u00eatre r\u00e9guli\u00e8rement reprogramm\u00e9 pour rappeler, renforcer et mettre en \u00e9vidence l&rsquo;hypoth\u00e8se fondamentale notamment dans ses monstrueuses cons\u00e9quences psychologiques, sous-tendant selon nous tous les \u00e9v\u00e9nements catastrophiques de cette \u00e9poque \u00e9trange et extraordinaire qui ne peut \u00eatre que celle de \u00ab\u00a0la Fin des Temps\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Terreur de Jacques Derrida<\/h2>\n<\/p>\n<p><p>27 avril 2015 &#8211; 10 f\u00e9vrier 2020 &ndash; La gen\u00e8se de ce texte est chronologiquement complexe \u00e0 \u00e9tablir. Qu&rsquo;il nous suffise de dire qu&rsquo;un proche, qui suivait nos travaux concernant notamment le processus-Syst\u00e8me de \u00ab\u00a0n\u00e9antisation\u00a0\u00bb sous la formule  <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-dde-definition-et-usage-1\"><em>dd&#038;e<\/em><\/a>  (d\u00e9structuration-dissolution-entropisation), nous signala la pr\u00e9sence sur  <em>YouTube  <\/em>d&rsquo;une intervention du philosophe \u00ab\u00a0d\u00e9constructeur\u00a0\u00bb Jacques Derrida, sous doute datant de 2002, sous le titre (anglais) de <em>Derrida&rsquo;s Terror<\/em>. C&rsquo;est sur ce document que nous appuyons notre texte qui d\u00e9veloppe une hypoth\u00e8se ambitieuse.<\/p>\n<\/p>\n<p><p>(Nous sollicitons ici le terme \u00ab\u00a0n\u00e9antisation\u00a0\u00bb pour d\u00e9signer en une forme plus d\u00e9finitive le processus  <em>dd&#038;e<\/em>, et bien qu&rsquo;on puisse arguer que \u00ab\u00a0n\u00e9antisation\u00a0\u00bb pourrait \u00e9quivaloir \u00e0 \u00ab\u00a0entropisation\u00a0\u00bb ; mais le premier n\u00e9ologisme [de Heidegger], d&rsquo;origine philosophique et m\u00e9taphysique, semble apte \u00e0 embrasser la processus g\u00e9n\u00e9ral  <em>dd&#038;e<\/em>, plus que le terme \u00ab\u00a0entropisation\u00a0\u00bb, de facture fortement scientifique, et qui de plus fait partie de la formule [<em>dd&#038;e<\/em>], donc dans une position qu&rsquo;on pourrait juger inopportun\u00e9ment \u00ab\u00a0juge et partie\u00a0\u00bb. Une hypoth\u00e8se serait que, dans notre esprit, \u00ab\u00a0entropisation\u00a0\u00bb constitu\u00e2t l&rsquo;op\u00e9rationnalisation de la \u00ab\u00a0n\u00e9antisation\u00a0\u00bb tandis que la \u00ab\u00a0n\u00e9antisation\u00a0\u00bb engloberait l&rsquo;ensemble du processus  <em>dd&#038;e<\/em>. C&rsquo;est \u00e0 voir et qui a une bonne vue verra sans aucun doute. En attendant, on notera ce que Gorge Steiner dit, dans  <em>Grammaires de la cr\u00e9ation  <\/em>[NRF essais\/Gallimard, 2001], du terme \u00ab\u00a0n\u00e9antisation\u00a0\u00bb :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Mais c&rsquo;est Heidegger qui va le plus loin dans le repliement des contours du langage ordinaire et de la syntaxe rationnelle. Dans le contexte historique qui est d\u00e9terminant pour cette \u00e9tude, \u00e0 l&rsquo;\u00e9poque de la longue \u00e9clipse des espoirs humains et de la dislocation du temps futur, Heidegger fait du \u00ab\u00a0n\u00e9ant\u00a0\u00bb un verbe : \u00ab\u00a0Nichten\u00a0\u00bb, \u00ab\u00a0n\u00e9antir\u00a0\u00bb. Le n\u00e9ologisme va beaucoup plus loin que \u00ab\u00a0vernichten\u00a0\u00bb, qui signifie \u00ab\u00a0d\u00e9truire\u00a0\u00bb, \u00ab\u00a0an\u00e9antir\u00a0\u00bb. Il laisse pressentir comme \u00e0 travers un voile, &ndash; la notion d'\u00a0\u00bbombre\u00a0\u00bb est ici cruciale, &ndash; l&rsquo;an\u00e9antissement de ce qui existe<\/em>. &raquo;)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le document  <em>Derrida&rsquo;s Terror<\/em>, mis sur  <em>YouTube <\/em>le  <a href=\"http:\/\/www.youtube.com\/watch?v=NNwTLb4YVd4&#038;feature=share\">24 novembre 2008<\/a>  par un incertain <em>Xenosophia<\/em>, est manifestement une interview faite par une (des) personnes intervieweuse(s) de langue anglaise, de tendance anglo-am\u00e9ricaine sans nul doute (<a href=\"http:\/\/fr.wikipedia.org\/wiki\/Jacques_Derrida\">Derrida<\/a>, d\u00e9c\u00e9d\u00e9 en 2004, enseignait r\u00e9guli\u00e8rement aux USA, comme on va le voir \u00e9videmment). La pr\u00e9sentation \u00e9crite est en anglais, il y a des sous-titres anglais et, \u00e0 un moment, Derrida dit une phrase en anglais alors que le reste de son intervention est en fran\u00e7ais. D&rsquo;apr\u00e8s les indications que nous avons recueillies, il s&rsquo;agirait d&rsquo;un document r\u00e9alis\u00e9 par deux des anciennes \u00e9l\u00e8ves de Derrida, de Kirby Dick &#038; Amy Ziering Kofman (voir ce <a href=\"http:\/\/www.imdb.com\/title\/tt0303326\/combined\">lien<\/a>).<\/p>\n<\/p>\n<p><p>&bull; Le texte de pr\u00e9sentation dit ceci (le soulign\u00e9 en caract\u00e8re gras est de nous : il marque combien l&rsquo;acte de la d\u00e9construction est irr\u00e9m\u00e9diablement un acte d&rsquo;une extraordinaire agressivit\u00e9 destructrice parce qu&rsquo;il est une attaque impitoyable contre tout ce qui est, activement ou potentiellement, et m\u00eame relativement d\u00e9sormais d&rsquo;une fa\u00e7on av\u00e9r\u00e9e, ordre, harmonie et \u00e9quilibre) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Jacques Derrida speaks about the aggressivity <strong>that is inevitable<\/strong> in the act of deconstruction, and the fear and anxiety that he experiences as he finds himself \u00ab\u00a0aggressing\u00a0\u00bb other texts, persons, or institutions.<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Il y avait 5 591 visions le 25 avril 2015 alors qu&rsquo;il y en avait eu 1 285 lorsque nous le visionn\u00e2mes pour la premi\u00e8re fois, le 12 ao&ucirc;t 2012. Nous l&rsquo;avons consult\u00e9 \u00e0 nouveau, pr\u00e8s de huit ans plus tard, et nous enregistrons 7 631 visions.<\/p>\n<p>&bull; La dur\u00e9e de l&rsquo;interview qui serait mieux qualifi\u00e9e de \u00ab\u00a0confession\u00a0\u00bb venue du fond de l&rsquo;\u00e2me est de 3 minutes 48 secondes. Voici sa transcription (Nous avons mis quelques mots en gras, pour souligner ceux qui sont les plus importants pour notre propos ; le mot \u00ab\u00a0i-na-dmi-ssible\u00a0\u00bb \u00ab\u00a0tron\u00e7onn\u00e9\u00a0\u00bb en tirets retranscrit l&rsquo;intonation de mart\u00e8lement que Derrida d\u00e9clame&#8230;)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\"><em>Derrida&rsquo;s Terror<\/em><\/h2>\n<\/p>\n<p><p>&laquo; &hellip;<em>Chaque fois que j&rsquo;\u00e9cris quelque chose &hellip; Que j&rsquo;avance dans des espaces o&ugrave; je ne m&rsquo;\u00e9tais pas aventur\u00e9, ce qui implique  <strong>des actes qui peuvent sembler agressifs  <\/strong>\u00e0 l&rsquo;\u00e9gard de penseurs, ou de coll\u00e8gues&hellip; C&rsquo;est d\u00e9j\u00e0 arriv\u00e9&hellip; Je ne suis pas \u00ab\u00a0pol\u00e9miqueur\u00a0\u00bb<\/em> [sic] <em>mais il est vrai que les gestes de type d\u00e9constructif ont souvent l&rsquo;apparence de gestes qui vont  <strong>d\u00e9stabiliser, ou angoisser les autres, ou m\u00eame blesser les autres quelquefois<\/strong>&hellip;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Alors, chaque fois que j&rsquo;ai fait ce geste l\u00e0, il y a y eu  <strong>des moments de peur<\/strong>&hellip; Pas au moment o&ugrave; j&rsquo;\u00e9cris, parce qu&rsquo;au moment o&ugrave; j&rsquo;\u00e9cris, il y a une esp\u00e8ce de n\u00e9cessit\u00e9, une esp\u00e8ce de force, plus forte que moi, qui fait que ce que je dois \u00e9crire, je l&rsquo;\u00e9cris, quelles que soient les cons\u00e9quences &hellip; Je n&rsquo;ai jamais renonc\u00e9 \u00e0 \u00e9crire quoi que ce soit parce que les cons\u00e9quences me faisaient peur.  <strong>Rien ne m&rsquo;intimide quand j&rsquo;\u00e9cris. Je dis ce que je pense qui doit \u00eatre dit<\/strong>. Bon<\/em>&hellip;<\/p>\n<\/p>\n<p><p>&raquo; <em>Cela dit, quand je n&rsquo;\u00e9cris pas, quand je ne suis pas en train d&rsquo;\u00e9crire, et \u00e0 un moment tr\u00e8s particulier qui est le moment o&ugrave; je m&rsquo;endors&hellip; When I have a nap and I fall asleep &hellip; A ce moment-l\u00e0, dans un demi-sommeil, <strong>je suis effray\u00e9 par ce que je suis en train de faire<\/strong>, et je me dis \u00ab\u00a0<strong>mais tu es fou<\/strong>, tu es fou d&rsquo;\u00e9crire \u00e7a, tu es fou de t&rsquo;attaquer \u00e0 \u00e7a, tu es fou de critiquer telle ou telle personne, tu es fou de contester telle ou telle autorit\u00e9, que ce soit une autorit\u00e9 textuelle, une autorit\u00e9 institutionnelle, une autorit\u00e9 personnelle\u00a0\u00bb&#8230; Et il y a <strong>une sorte de panique<\/strong>, dans un subconscient, comme \u00e7a, une sorte de panique, comme si &hellip; comme si, \u00e0 quoi est-ce que je peux comparer \u00e7a ? Imaginez un enfant qui fait une chose honteuse, il a fait une chose honteuse, bon&hellip; Il y a les r\u00eaves d&rsquo;enfant de Freud, o&ugrave; l&rsquo;enfant se prom\u00e8ne nu, vous savez les r\u00eaves o&ugrave; l&rsquo;on se prom\u00e8ne tout nu, et puis l&rsquo;on est effray\u00e9 parce que tout le monde voit que vous \u00eates nu &hellip; Bon&hellip; Dans ce demi-sommeil, j&rsquo;ai l&rsquo;impression que j&rsquo;ai fait une  <strong>chose criminelle, honteuse, inavouable<\/strong>, quelque chose que je n&rsquo;aurais  <strong>jamais  <\/strong>d&ucirc; faire&hellip; <strong>Et quelqu&rsquo;un est en train de me dire : \u00ab\u00a0Mais tu es fou de faire \u00e7a !\u00a0\u00bb<\/strong> &hellip; Et c&rsquo;est l&rsquo;\u00e9vidence m\u00eame, je le crois dans mon demi-sommeil, je le crois&hellip; Et donc, l&rsquo;ordre qui est \u00e9vident dans cela, c&rsquo;est \u00ab\u00a0Arr\u00eate tout, retire \u00e7a, br&ucirc;le tes papiers&hellip;  <strong>Ce que tu viens de faire est i-na-dmi-ssible !<\/strong>\u00a0\u00bb Mais d\u00e8s que je me r\u00e9veille, c&rsquo;est fini<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Ca veut dire que&hellip; Je l&rsquo;interpr\u00e8te comme \u00e7a, \u00e7a veut dire que quand je suis \u00e9veill\u00e9, conscient, au travail, etc., je suis d&rsquo;une certaine mani\u00e8re <strong>plus inconscient que dans un demi-sommeil<\/strong>&hellip; Dans un demi-sommeil, je, je&hellip; il y a  <strong>une certaine vigilance qui me dit la v\u00e9rit\u00e9<\/strong>, \u00e0 savoir que ce que je fais c&rsquo;est tr\u00e8s grave, d&rsquo;une certaine mani\u00e8re &hellip; Mais quand je suis \u00e9veill\u00e9 et au travail, <strong>cette vigilance-l\u00e0 est en sommeil<\/strong>. Elle n&rsquo;est pas la plus forte, et donc <strong>je fais ce qui doit \u00eatre fait<\/strong><\/em>&hellip; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Il faut regarder et \u00e9couter Derrida, l&rsquo;esprit d\u00e9gag\u00e9 au moins pour cet instant de tout parti pris, voire m\u00eame d\u00e9gag\u00e9 d&rsquo;une connaissance \u00e9ventuellement critique de ses propres positions fondamentales, &ndash; le regarder et l&rsquo;\u00e9couter disons d&rsquo;humain \u00e0 humain, en connaissance de cause de ce qu&rsquo;est la souffrance intellectuelle et psychologique. Il dit une v\u00e9rit\u00e9 profonde de son \u00eatre, de lui-m\u00eame, qui le tourmente et le torture horriblement et dont on sent qu&rsquo;il ne parviendra jamais \u00e0 la ma&icirc;triser (il mourra deux ann\u00e9es apr\u00e8s cette intervention), <strong>comme s&rsquo;il en \u00e9tait prisonnier<\/strong> ; et cela, n&rsquo;est-ce pas, dont on devine qu&rsquo;il le sait, ou qu&rsquo;il le devine \u00ab\u00a0comme semi-inconsciemment\u00a0\u00bb, comme lorsqu&rsquo;il est dans cet \u00e9tat de demi-sommeil qu&rsquo;il mentionne, o&ugrave; il juge qu&rsquo;alors une vigilance fondamentale contre des forces ext\u00e9rieures mal\u00e9fiques reprend sa place et qu&rsquo;il entend la condamnation de ses \u00e9crits comme une v\u00e9rit\u00e9 qui le remplit de honte.<\/p>\n<\/p>\n<p><p>(En quelque sorte, c&rsquo;est quand il est conscient, <strong>c&rsquo;est quand il est \u00ab\u00a0libre\u00a0\u00bb qu&rsquo;il est prisonnier<\/strong>, car alors le venin des id\u00e9es id\u00e9ologis\u00e9es reprend le dessus.)<\/p>\n<\/p>\n<p><p>Il est difficile de ne pas ressentir le sentiment d&rsquo;une grande compassion, presque un \u00e9lan de solidarit\u00e9 pour ce qu&rsquo;il nous dit de la trag\u00e9die humaine, et comme nous-m\u00eames \u00e0 sa place, n\u00e9cessairement, nous l&rsquo;aurions exp\u00e9riment\u00e9e dans son intensit\u00e9 quoique chacun \u00e0 sa mani\u00e8re et selon l&rsquo;orientation de son esprit. La trag\u00e9die int\u00e9rieure de cet homme se trouve dans cette interrogation : comment surmonter une telle contradiction ? Entre cette \u00ab\u00a0vigilance\u00a0\u00bb qui lui \u00ab\u00a0dit la v\u00e9rit\u00e9\u00a0\u00bb, savoir que ce qu&rsquo;il fait est \u00ab\u00a0i-na-dmi-ssible\u00a0\u00bb et devrait \u00eatre br&ucirc;l\u00e9, et lui-m\u00eame, \u00e9crivant contre cette vigilance qu&rsquo;il a \u00e9cart\u00e9e, estimant qu&rsquo;il \u00ab\u00a0fait ce qui doit \u00eatre fait\u00a0\u00bb ? Entre ceci qui est sa \u00ab\u00a0vigilance\u00a0\u00bb lui disant que ce qu&rsquo;il fait est \u00ab\u00a0i-na-dmi-ssible\u00a0\u00bb et cela qui lui dit \u00ab\u00a0ce qui doit \u00eatre fait\u00a0\u00bb qui est ce que sa \u00ab\u00a0vigilance\u00a0\u00bb d\u00e9nonce ?&#8230; Il faut que l&rsquo;enjeu soit, pour cet esprit, &ndash; mais aussi pour la th\u00e9orie qu&rsquo;il repr\u00e9sente et l&rsquo;influence qu&rsquo;eut et qu&rsquo;a cette th\u00e9orie, &ndash; d&rsquo;une importance vitale <strong>et, surtout, impos\u00e9 par une force irr\u00e9sistible et d&rsquo;une surpuissance exceptionnelle<\/strong>.<\/p>\n<\/p>\n<p><p>(Il faut insister l\u00e0-dessus, dans ce moment de v\u00e9rit\u00e9 : Derrida s&rsquo;explique \u00e0 lui-m\u00eame de ses actes comme s&rsquo;il existait effectivement <strong>quelque chose d&rsquo;ext\u00e9rieur \u00e0 lui, qui le guide et le force, et le contraint<\/strong>&#8230; On ne peut pas ne pas \u00e9voquer cette hypoth\u00e8se que cet homme est effectivement prisonnier d&rsquo;une force mal\u00e9fique qui le contraint \u00e0 poser des actes destructeurs de d\u00e9construction.)<\/p>\n<\/p>\n<p><p>Maintenant, laissons de c\u00f4t\u00e9 l&rsquo;aspect humain pour lequel nous disons notre plus grand respect, et venons-en \u00e0 l&rsquo;aspect disons plus social et symbolique de d\u00e9finition de la philosophie que repr\u00e9sentent Derrida et quelques-uns des philosophes de la m\u00eame \u00e9cole que lui et qui connurent la m\u00eame aventure disons p\u00e9dagogique. Derrida le dit lui-m\u00eame, &ndash; le \u00ab\u00a0geste de type d\u00e9constructif\u00a0\u00bb d\u00e9finit le mouvement philosophique qui se d\u00e9veloppe \u00e0 partir des r\u00e9f\u00e9rences du structuralisme et du poststructuralisme ; on pourrait donc d\u00e9signer ce mouvement comme celui de \u00ab\u00a0la d\u00e9construction\u00a0\u00bb alors que nous serions conduit, pour notre part, \u00e0 voir dans ce m\u00eame mot, en partie l&rsquo;\u00e9quivalent de notre \u00ab\u00a0d\u00e9structuration-dissolution\u00a0\u00bb. Derrida exprime sa \u00ab\u00a0peur\u00a0\u00bb \u00e0 propos de l&rsquo;activation, dont il est lui-m\u00eame l&rsquo;ordonnateur, des \u00ab\u00a0gestes de type d\u00e9constructif\u00a0\u00bb. Il ne peut pr\u00e9tendre parler, disons comme pourrait le faire un isol\u00e9, un non-conformiste, un \u00ab\u00a0po\u00e8te maudit\u00a0\u00bb ou un philosophe rebelle, un homme dress\u00e9 contre les conventions et l&rsquo;ordre \u00e9tabli (effectivement, des positions qui plaisent tant aux \u00ab\u00a0intellectuels\u00a0\u00bb qui se jugent n\u00e9cessairement \u00ab\u00a0en avance\u00a0\u00bb, l\u00e0 o&ugrave; l&rsquo;on peut se sentir isol\u00e9, angoiss\u00e9, expos\u00e9 \u00e0 la vindicte du conformisme, etc., puisqu&rsquo;effectivement \u00ab\u00a0en avance\u00a0\u00bb sur tout cela).<\/p>\n<\/p>\n<p><p>Bien au contraire. Derrida fut, en son temps, avec ses confr\u00e8res du post-structuralisme, un v\u00e9ritable ma&icirc;tre, et reconnu et encens\u00e9 comme tel, de la future pens\u00e9e dominante en train de s&rsquo;\u00e9laborer, &ndash; mais nous devrions dire plut\u00f4t \u00ab\u00a0psychologie dominante\u00a0\u00bb, car peu nous importe le contenu extraordinairement complexe jusqu&rsquo;\u00e0 la micro-conceptualisation, de cette \u00ab\u00a0pens\u00e9e\u00a0\u00bb. Pour nous, cette \u00ab\u00a0future psychologie dominante\u00a0\u00bb fut absolument la matrice implacable de la \u00ab\u00a0pens\u00e9e dominante\u00a0\u00bb (pour le coup, le terme \u00ab\u00a0pens\u00e9e\u00a0\u00bb a sa place), l\u00e0 o&ugrave; cela comptait, comme elle l&rsquo;est absolument aujourd&rsquo;hui de la d\u00e9ferlante progressiste-soci\u00e9tale per\u00e7ue comme une dynamique de la pens\u00e9e dont le cours d\u00e9constructurationniste est trac\u00e9 et absolument inarr\u00eatable.<\/p>\n<\/p>\n<p><p>Le livre  <em>French Theory<\/em>, de Fran\u00e7ois Cusset (La D\u00e9couverte, 2003), nous instruit \u00e0 propos du formidable succ\u00e8s de ces philosophes fran\u00e7ais aux USA dans les ann\u00e9es 1970. Le \u00ab\u00a0quatri\u00e8me de couverture\u00a0\u00bb nous suffit \u00e0 cet \u00e9gard pour avoir une id\u00e9e du cheminement de l&rsquo;influence de cette  <em>French Theory<\/em>, et parce que c&rsquo;est de psychologie et non de pens\u00e9e que nous parlons, &ndash; et cette psychologie \u00e9tant parfaitement celle de la \u00ab\u00a0d\u00e9construction\u00a0\u00bb, ou \u00ab\u00a0d\u00e9structuration-dissolution\u00a0\u00bb, &ndash; ou, si l&rsquo;on veut employer un n\u00e9ologisme d&rsquo;une famille de grand style qu&rsquo;on a d\u00e9j\u00e0 sugg\u00e9r\u00e9e, la \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Sait-on que la science-fiction am\u00e9ricaine, du roman \u00ab\u00a0cyberpunk\u00a0\u00bb \u00e0 la saga \u00ab\u00a0Matrix\u00a0\u00bb, se nourrit largement de Jean Baudrillard ? Que Gilles Deleuze et F\u00e9lix Guattari inspirent aux &Eacute;tats-Unis les pionniers de l&rsquo;internet et de la musique \u00e9lectronique ? Que Michel Foucault y est une r\u00e9f\u00e9rence majeure des luttes communautaires tandis que Jacques Derrida est une star sans \u00e9gale dans l&rsquo;universit\u00e9 ?<\/em> [&#8230;] <em>C&rsquo;est cette histoire, mal connue, de la &lsquo;French Theory&rsquo; que Fran\u00e7ois Cusset retrace ici. Il retrace le succ\u00e8s de cette \u00e9trange &lsquo;th\u00e9orie fran\u00e7aise&rsquo;, &ndash; la d\u00e9construction, le biopouvoir, les micropolitiques ou la simulation [le simulacre], &ndash; jusque dans les tr\u00e9fonds de la sous-culture am\u00e9ricaine. Il restitue l&rsquo;atmosph\u00e8re particuli\u00e8re des ann\u00e9es 1970 et raconte la formidable aventure am\u00e9ricaine, et bient\u00f4t mondiale, d&rsquo;intellectuels fran\u00e7ais marginalis\u00e9s dans l&rsquo;Hexagone<\/em> &#8230;&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Que voil\u00e0 donc des flons-flons triomphants (o&ugrave;, tout de m\u00eame, Baudrillard est mis dans le m\u00eame sac que Foucault, Deleuze, Derrida &#038; Cie, ce qui est pousser le bouchon un peu loin) &#8230; Ils ont la vertu, ces flons-flons, de nous confirmer contrairement \u00e0 ce qu&rsquo;il pr\u00e9tend nous dire, que ces \u00ab\u00a0intellectuels fran\u00e7ais\u00a0\u00bb ne furent jamais vraiment marginalis\u00e9s \u00ab\u00a0dans l&rsquo;Hexagone\u00a0\u00bb&#8230; Finalement, c&rsquo;est cette marginalisation qui a manqu\u00e9 \u00e0 Derrida et ce manque fait comprendre les arcanes de son drame, parce qu&rsquo;il s&rsquo;agit d&rsquo;une \u00e9poque o&ugrave; la c\u00e9l\u00e9brit\u00e9 fait de vous une victime d\u00e9sign\u00e9e et vuln\u00e9rable d&rsquo;un syst\u00e8me mal\u00e9fique d&rsquo;une puissance inou\u00efe.<\/p>\n<\/p>\n<p><p>Ainsi revenons-nous au drame de Derrida que restituent les quelques minutes de confidences qu&rsquo;on a \u00e9cout\u00e9es. Ayant \u00e9cart\u00e9 les occurrences sociales et autres qui figurent au d\u00e9but des confidences, nous revenons au plus profond du secret de l&rsquo;\u00eatre, pour consid\u00e9rer enfin ce qu&rsquo;il nous dit en v\u00e9rit\u00e9, selon notre interpr\u00e9tation. Dans ces moments de semi-conscience que lui-m\u00eame (Derrida) qualifie de la plus grande \u00ab\u00a0vigilance\u00a0\u00bb, c&rsquo;est-\u00e0-dire de la lucidit\u00e9 qui dit \u00ab\u00a0la v\u00e9rit\u00e9\u00a0\u00bb en \u00e9cartant l&rsquo;esp\u00e8ce d&rsquo;opium de la pure sp\u00e9culation intellectuelle, l&rsquo;esprit qui fait \u00ab\u00a0ce qui doit \u00eatre fait\u00a0\u00bb est confront\u00e9 \u00e0 ce jugement terrible : &laquo; <em>Ce que tu viens de faire est i-na-dmi-ssible<\/em> &raquo;&#8230; Non pas \u00ab\u00a0selon ta fonction, ta position sociale, ton respect de la hi\u00e9rarchie\u00a0\u00bb, mais parce qu&rsquo;il s&rsquo;agit de quelque chose d'\u00a0\u00bbi-na-dmi-ssible\u00a0\u00bb en soi, &ndash; et cela ne peut \u00eatre alors que le fait de c\u00e9der \u00e0 la tentation \u00e9pouvantable, de succomber \u00e0 l&rsquo;influence du Mal, d&rsquo;accepter le simulacre que le Mal impose.<\/p>\n<\/p>\n<p><p>Si nous disons cela, c&rsquo;est conduit par la logique autant qu&rsquo;influenc\u00e9 grandement par l&rsquo;intuition, laquelle nous a propos\u00e9 comme \u00e9vidence que le Mal se manifeste essentiellement par ce processus  <em>dd&#038;e<\/em>, ou pour retrouver notre trouvaille de circonstance, par le processus de \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb&#8230; Et l&rsquo;\u00e9tat de semi-conscience o&ugrave; la \u00ab\u00a0vigilance\u00a0\u00bb retrouve sa place naturelle, c&rsquo;est celui o&ugrave; la psychologie, d\u00e9barrass\u00e9e des cha&icirc;nes des id\u00e9es auxquelles l&rsquo;esprit s&rsquo;est attach\u00e9, est capable de percevoir toute la puissance de la v\u00e9rit\u00e9 et de se faire elle-m\u00eame messag\u00e8re de la v\u00e9rit\u00e9 pour admonester le philosophe. Ainsi Derrida se trouverait-il confront\u00e9 \u00e0 la vision affreuse que les id\u00e9es qu&rsquo;il d\u00e9veloppe constitueraient effectivement une transcription socio-intellectuelle de l&rsquo;influence du Mal (ou du Syst\u00e8me pour notre compte, pris dans son sens le plus large d&rsquo;op\u00e9rationnalisation du \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0).<\/p>\n<\/p>\n<p><p>Encore une fois, il ne nous viendrait pas \u00e0 l&rsquo;esprit de d\u00e9velopper cette id\u00e9e mis\u00e9rable et infond\u00e9e de faire un proc\u00e8s \u00e0 Derrida. D&rsquo;ailleurs, sa \u00ab\u00a0confession\u00a0\u00bb quasi-psychanalytique parle pour lui-m\u00eame : il repr\u00e9sente ce cas qu&rsquo;on a d\u00e9j\u00e0 envisag\u00e9 d&rsquo;une intelligence brillante, d&rsquo;un exceptionnel brio intellectuel, trahis par une psychologie trop faible ou affaiblie (elle n&rsquo;est capable de transmettre les messages essentiels venus d&rsquo;un en-dehors ou d&rsquo;un au-del\u00e0 que lorsque l&rsquo;esprit est dans un \u00e9tat de conscience tr\u00e8s amoindrie). Il repr\u00e9sente cette d\u00e9faite permanente des psychologies, depuis le XVIII\u00e8me si\u00e8cle (si\u00e8cle du \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_de_la_raison_humaine_ddecrisis_18_07_2010.html\">persiflage<\/a>\u00a0\u00bb bien entendu), confront\u00e9es aux pressions des salons, de l&rsquo;universit\u00e9, des milieux intellectuels dominants, bref de tout ce qui fait la modernit\u00e9 dans son activit\u00e9 d&rsquo;influence par le syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>(Il ne nous viendrait certes pas \u00e0 l&rsquo;esprit, non plus, d&rsquo;\u00e9carter l&rsquo;id\u00e9e qu&rsquo;un intellectuel, un \u00e9crivain, un penseur, un essayiste, un philosophe, ne conna&icirc;t pas de terribles faiblesses dans son travail sans n\u00e9cessairement avoir sa psychologie affaiblie. S&rsquo;il fallait identifier la principale, ce serait l&rsquo;angoisse avec ses diff\u00e9rents effets [paralysie de la cr\u00e9ation, panique, etc.], et l&rsquo;angoisse \u00e0 cause du doute, mais non la peur, comme le confie Derrida. [L&rsquo;angoisse concerne l&rsquo;inconnu, qui peut \u00eatre dangereux ou amical, faussaire ou vrai ; la peur, elle, concerne ce qui est connu et dont on sait le danger que cette chose repr\u00e9sente, c&rsquo;est-\u00e0-dire la cause de la peur identifi\u00e9e comme mauvaise ou ennemie ; l&rsquo;angoisse r\u00e9clame la v\u00e9rit\u00e9 de l&rsquo;\u00e9nigme qu&rsquo;on affronte pour pouvoir \u00eatre surmont\u00e9e, la peur marque la d\u00e9marche dont on a identifi\u00e9 le danger.] Outre cette diff\u00e9rence entre l&rsquo;angoisse et la peur, il y a ce fait que l&rsquo;angoisse ne vient pas dans les \u00e9tats de semi-conscience, sous le coup d&rsquo;une \u00ab\u00a0vigilance\u00a0\u00bb qui soudain joue son r\u00f4le ; elle marque en toute lucidit\u00e9 le travail de la pens\u00e9e consciente, proc\u00e9dant par \u00e0-coups d&rsquo;incertitudes angoissantes suivies de soudaines certitudes sublimes, suivies \u00e0 nouveau d&rsquo;incertitudes angoissantes, etc., &ndash;une bataille sans fin pour la v\u00e9rit\u00e9, et non pas une avanc\u00e9e sans douter mais transie de peur, pour \u00ab\u00a0faire ce qui doit \u00eatre fait\u00a0\u00bb, \u00ab\u00a0une esp\u00e8ce de n\u00e9cessit\u00e9, une esp\u00e8ce de force, plus forte que moi, qui fait que ce que je dois \u00e9crire je l&rsquo;\u00e9cris, quelles que soient les cons\u00e9quences\u00a0\u00bb, &ndash; cela dont la \u00ab\u00a0v\u00e9rit\u00e9\u00a0\u00bb vous dit par instant que c&rsquo;est \u00ab\u00a0i-na-dmi-ssible\u00a0\u00bb. Nous n&rsquo;\u00e9cartons pas un instant l&rsquo;id\u00e9e que l&rsquo;\u00e9crit est l&rsquo;outil principal de transmission de forces invisibles [voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-du_bon_usage_de_poutine_16_04_2015.html\">16 avril 2015<\/a>] et qu&rsquo;il entra&icirc;ne l&rsquo;\u00e9crivain consid\u00e9r\u00e9 alors comme un \u00ab\u00a0messager\u00a0\u00bb bien plus qu&rsquo;il n&rsquo;est conduit par lui, mais rien n&rsquo;assure bien \u00e9videmment que dans ces forces ne s&rsquo;en glissent pas certaines qui repr\u00e9sentent une influence mal\u00e9fique. C&rsquo;est \u00e0 la vigilance d&rsquo;exercer son office.)<\/p>\n<\/p>\n<p><p>Pour conclure cette analyse de \u00ab\u00a0la confession de Derrida\u00a0\u00bb, nous avancerons l&rsquo;observation que son exceptionnalit\u00e9 se trouve dans ceci que le reproche que lui fait sa \u00ab\u00a0voix\u00a0\u00bb (&laquo; <em>Ce que tu viens de faire est i-na-dmi-ssi-ble<\/em>&#8230; [&#8230;] [&#8230;une] <em>certaine vigilance qui me dit la v\u00e9rit\u00e9, \u00e0 savoir que ce que je fais c&rsquo;est tr\u00e8s grave, d&rsquo;une certaine mani\u00e8re<\/em>&#8230; &raquo;) ne porte pas sur un acte sp\u00e9cifique et tr\u00e8s humain, immoral, pervers, un meurtre, une d\u00e9nonciation, un viol, une diffamation, une id\u00e9ologie fautive, etc. ; non, ce qui lui est reproch\u00e9, c&rsquo;est un \u00ab\u00a0acte intellectuel\u00a0\u00bb, une \u00ab\u00a0forme de la pens\u00e9e\u00a0\u00bb du processus de la d\u00e9construction, c&rsquo;est-\u00e0-dire une d\u00e9marche m\u00e9taphysique et m\u00e9tahistorique dont les effets sont r\u00e9sum\u00e9s par le fait de d\u00e9construire&#8230; Toute la force de cette \u00ab\u00a0confession\u00a0\u00bb est certainement l\u00e0, par rapport \u00e0 l&rsquo;\u00e9poque que nous vivons, o&ugrave; nous observons la d\u00e9construction, non seulement d&rsquo;une civilisation, mais du monde lui-m\u00eame.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb depuis 9\/11<\/h3>\n<\/p>\n<p><p>A partir de notre raisonnement intuitif concernant ce cas tel que nous l&rsquo;identifions, \u00e0 l&rsquo;audition de ce remarquable document de la \u00ab\u00a0confession\u00a0\u00bb de Jacques Derrida, et \u00e0 la lumi\u00e8re de ce qu&rsquo;on sait de l&rsquo;extraordinaire succ\u00e8s de la  <em>French Theory  <\/em>aux USA, il nous semble qu&rsquo;une hypoth\u00e8se op\u00e9rationnelle historique peut \u00eatre d\u00e9velopp\u00e9e. (Nous avons \u00e9galement \u00e9voqu\u00e9 un aspect constitutif de cette th\u00e8se, cette fois \u00e0 la lumi\u00e8re de Foucault plut\u00f4t qu&rsquo;\u00e0 celle de Derrida, le <a href=\"https:\/\/www.dedefensa.org\/article\/puanteur-foucaldienne-des-restes-de-lempire\">24 mai 2019<\/a>.)<\/p>\n<\/p>\n<p><p>Il s&rsquo;agirait de pr\u00e9senter une explication hypoth\u00e9tique pour mieux comprendre notre \u00e9poque pr\u00e9par\u00e9 par la p\u00e9riode de l&rsquo;imm\u00e9diat apr\u00e8s-Guerre froide, et brutalement propuls\u00e9e avec une psychologie influenc\u00e9e par la d\u00e9construction dans sa maturit\u00e9 catastrophique repr\u00e9sent\u00e9e par ce \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/notes-psychanalytiques-et-metaphysiques-sur-911\">trou dans l&rsquo;espace-temps<\/a>\u00a0\u00bb que fut l&rsquo;attaque du 11 septembre 2001 ; et essentiellement \u00e0 partir de l\u00e0, et pour mieux identifier ce dont nous parlons, d\u00e9crire la production de la politique de l&rsquo;am\u00e9ricanisme se d\u00e9voilant finalement elle-m\u00eame comme l&rsquo;op\u00e9rationnalisation de la \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>\u00a0\u00bb dans son sens le plus large, et dont on sait qu&rsquo;elle peut, qu&rsquo;elle doit compl\u00e8tement et parfaitement s&rsquo;identifier \u00e0 elle.<\/p>\n<\/p>\n<p><p>(Le concept de \u00ab\u00a0politiqueSyst\u00e8me\u00a0\u00bb produisant d\u00e9structuration et dissolution doit \u00eatre pris ici dans son sens quasiment absolu, c&rsquo;est-\u00e0-dire embrassant politiques ext\u00e9rieures et situations int\u00e9rieures. Cela va \u00e9videmment et n\u00e9cessairement, \u00f4 combien puisqu&rsquo;il s&rsquo;agit d&rsquo;un paroxysme, jusqu&rsquo;\u00e0 comprendre l&rsquo;irruption depuis 2015-2016 de la grande crise int\u00e9rieure du pouvoir de l&rsquo;am\u00e9ricanisme et du d\u00e9cha&icirc;nement du progressisme-soci\u00e9tal, ou marxisme-culturel comme l&rsquo;identifient nombre d&rsquo;intellectuels conservateurs.)<\/p>\n<\/p>\n<p><p>Ce que nous observons, d&rsquo;abord de la fin de la Guerre froide jusqu&rsquo;\u00e0 l&rsquo;attaque 9\/11, puis \u00e0 partir de 9\/11, c&rsquo;est une \u00e9volution psychologique US caract\u00e9ris\u00e9e par une alternance  <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde-crisis_la_maniaco-d_pression_du_monde_16_03_2015.html\">maniaco-d\u00e9pressive<\/a>, d&rsquo;abord d&rsquo;un \u00e9pisode d\u00e9pressif puis d&rsquo;un \u00e9pisode maniaque (\u00e0 partir de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-d_atlanta-1996_new_orleans-2005_02_09_2005.html\">\u00e9t\u00e9 1996<\/a>), transcend\u00e9 ensuite avec 9\/11 en une sorte d&rsquo;\u00e9pisode hypomaniaque qu&rsquo;on peut ais\u00e9ment int\u00e9grer comme dynamique op\u00e9rationnelle du concept de l'\u00a0\u00bb<a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_id_al_de_puissance_09_04_2014.html\">id\u00e9al de puissance<\/a>\u00ab\u00a0. Quant \u00e0 la politique ext\u00e9rieure extr\u00eamement agressive et belliciste suivie \u00e0 partir de 9\/11, identifi\u00e9e effectivement comme \u00ab\u00a0politiqueSyst\u00e8me\u00a0\u00bb dans son \u00e9pisode \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/lentropisation-de-lentropie-postmoderne\">h\u00e9g\u00e9monisme-chaotique<\/a>\u00ab\u00a0, elle ne pr\u00e9sente aucun caract\u00e8re de coh\u00e9rence lorsqu&rsquo;elle est observ\u00e9e sur le terme de la vingtaine d&rsquo;ann\u00e9es nous s\u00e9parant du 11 septembre 2001 : il appara&icirc;t \u00e9vident que c&rsquo;est exactement le contraire, que plus elle se d\u00e9veloppe plus elle devient incoh\u00e9rente.<\/p>\n<\/p>\n<p><p>Bien entendu, cette politique a un caract\u00e8re de surpuissance \u00e9galement \u00e9vident qui est syst\u00e9matiquement interpr\u00e9t\u00e9 comme une politique de conqu\u00eate h\u00e9g\u00e9monique des USA en g\u00e9n\u00e9ral d&rsquo;une fa\u00e7on avantageuse pour les USA, &ndash; mais cela, \u00e0 notre sens, en compl\u00e8te contradiction avec la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> \u00e0 cet \u00e9gard, au point qu&rsquo;on peut qualifier de simulacre l&rsquo;interpr\u00e9tation favorable aux USA. Sur ce terme de  <a href=\"https:\/\/www.dedefensa.org\/article\/notes-de-2020-a-2002-et-retour\">2002-2020<\/a> on observe que cette conqu\u00eate h\u00e9g\u00e9monique tourne en rond sur des territoires d&rsquo;ores et d\u00e9j\u00e0 conquis (ou sous influence US), si bien qu&rsquo;on finit par s&rsquo;interroger effectivement sur la coh\u00e9rence de la chose :<\/p>\n<\/p>\n<p><p>Combien de fois les USA ne se sont-ils pas lanc\u00e9s \u00e0 l&rsquo;assaut de l&rsquo;Irak depuis 1991, alors qu&rsquo;il s&rsquo;av\u00e8re d\u00e9sormais, depuis janvier 2020, que l&rsquo;affrontement USA-Iran pourrait bien avoir l&rsquo;Irak comme champ de bataille, alors que l&rsquo;Irak exige le retrait des troupes US ?<\/p>\n<p>Pourquoi les USA n&rsquo;ont-ils pas am\u00e9nag\u00e9 leur \u00e9crasante sup\u00e9riorit\u00e9 sur la Russie dans les ann\u00e9es 1990, en pratiquant une politique un peu plus constructive et durable avec un pays qui leur \u00e9tait quasiment acquis (m\u00eame Poutine, \u00e0 ses d\u00e9buts, ne demandaient qu&rsquo;\u00e0 coop\u00e9rer avec les USA) ?<\/p>\n<p>Pourquoi dans ces conditions ouvertes \u00e0 la coop\u00e9ration, \u00e9ventuellement \u00e0 l&rsquo;int\u00e9gration-domination de la Russie dans l&rsquo;OTAN, lancer d\u00e8s 2002 le programme de missiles antimissiles qui n&rsquo;a jusqu&rsquo;ici servi qu&rsquo;\u00e0 s&rsquo;ali\u00e9ner la Russie et \u00e0 pousser Poutine vers une r\u00e9affirmation de la souverainet\u00e9 russe, \u00e0 un r\u00e9armement de son pays, au d\u00e9veloppement d&rsquo;une sup\u00e9riorit\u00e9 strat\u00e9gique via les missiles hypersoniques ? Etc&#8230;<\/p>\n<\/p>\n<p><p>Chacune de ses questions sans r\u00e9ponse accentue le jugement d&rsquo;une politique de complet d\u00e9sordre qui n&rsquo;est conduite que par l&rsquo;effet qu&rsquo;elle produit. Bien entendu, il s&rsquo;agit de l&rsquo;effet de la d\u00e9structuration et de la dissolution, &ndash; la \u00ab\u00a0d\u00e9construction\u00a0\u00bb disent les penseurs de la  <em>French Theory<\/em>.<\/p>\n<\/p>\n<p><p>Certes, les th\u00e9ories et les complots ne manquent pas, mais eux aussi tournent en rond et ne produisent rien. Il y a les  <em>neocons<\/em>  affirmant vouloir refaire les cartes du monde en s&rsquo;appuyant sur Leo Strauss et proclamant l&rsquo;\u00e8re du \u00ab\u00a0chaos cr\u00e9ateur\u00a0\u00bb : il y a l&rsquo;hypercapitalisme et sa r\u00e9f\u00e9rence \u00e0 Friedrich  <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Friedrich_Hayek\">von Hayek<\/a>  et la th\u00e8se de l'\u00a0\u00bb<a href=\"http:\/\/fr.wikipedia.org\/wiki\/Ordre_spontan%C3%A9\">ordre spontan\u00e9<\/a>\u00a0\u00bb aussi vieille que l&rsquo;Empire du Milieu. Mais rien ne sort de tout ce verbiage de communication dont Strauss et Hayek n&rsquo;auraient certainement pas reconnu la paternit\u00e9 s&rsquo;ils en avaient eu connaissance. On passe d&rsquo;une Libye qu&rsquo;on conquiert pour son p\u00e9trole et qui est r\u00e9cup\u00e9r\u00e9e par l&rsquo;anarchie comme l&rsquo;avaient pr\u00e9vu les adversaires de cette exp\u00e9dition, \u00e0 une Syrie qu&rsquo;on ne parvient m\u00eame pas \u00e0 attaquer, \u00e0 une Ukraine qui nous conduit au bord d&rsquo;un conflit aux proportions inimaginables sans se m\u00e9nager la moindre issue de secours avant de sombrer dans la paralysie d&rsquo;un trou noir de gaspillage, de corruption et de d\u00e9sordre, tout cela et dans le m\u00eame temps en lan\u00e7ant au Moyen-Orient la constitution d&rsquo;un pseudo-\u00ab\u00a0&Eacute;tat Islamique\u00a0\u00bb qu&rsquo;on finance et qu&rsquo;on arme tout en le combattant avec fureur, ou en soutenant l&rsquo;attaque du Y\u00e9men par une maison Saoud dont la s\u00e9nilit\u00e9 a produit soudain un vertige interventionniste, sans tr\u00e8s bien savoir contre qui et dans quel but, et qui se trouve soudain \u00e0 d\u00e9couvert, face aux plus grandes menaces pour sa propre survivance.<\/p>\n<\/p>\n<p><p>Bien entendu, \u00e0 partir de 2015 s&rsquo;est ajout\u00e9 le volet int\u00e9rieur, la crise interne du syst\u00e8me de l&rsquo;am\u00e9ricanisme sous la pouss\u00e9e du progressisme-soci\u00e9tal, avatar int\u00e9rieur et effectivement soci\u00e9tal de la m\u00eame politiqueSyst\u00e8me. On a bien vu que cette crise, que les observateurs raisonnables pensaient \u00eatre associ\u00e9e \u00e0 la campagne pr\u00e9sidentielle, et donc conduite \u00e0 cesser d\u00e8s l&rsquo;\u00e9lection faite, n&rsquo;a cess\u00e9 au contraire de s&rsquo;amplifier jusqu&rsquo;\u00e0 une vie politique \u00e9voluant entre les deux p\u00f4les de l&rsquo;ill\u00e9galit\u00e9 syst\u00e9mique et le \u00ab\u00a0coup d&rsquo;&Eacute;tat permanent\u00a0\u00bb. L\u00e0 aussi, les psychologies sont touch\u00e9es en priorit\u00e9 et la pente suivie est, d&rsquo;une fa\u00e7on aveuglante \u00e0 force d&rsquo;\u00eatre \u00e9vidente, celle de la \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb effectivement produite par ces psychologies elles-m\u00eames d\u00e9construites. Les soubresauts colossaux de surpuissance du Syst\u00e8me d\u00e9construisent la plus belle m\u00e9canique d\u00e9velopp\u00e9e pour servir le Syst\u00e8me, c&rsquo;est-\u00e0-dire le superbe ensemble structurel du pouvoir politique du syst\u00e8me de l&rsquo;am\u00e9ricanisme.<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat est toujours et encore un immense d\u00e9sordre qui ne cesse de grandir et de s&rsquo;amplifier selon un \u00e9lan \u00e0 la fois exponentiel et d&rsquo;orientation entropique, et se caract\u00e9risant par une pouss\u00e9e constante, d\u00e9structurante et dissolvante, ou bien \u00ab\u00a0d\u00e9constructurante\u00a0\u00bb apr\u00e8s tout &#8230; L&rsquo;impression, souvent \u00e9mise, est que les intelligences qui m\u00e8nent cette politique sont, \u00e0 l&rsquo;image de la d\u00e9structuration-dissolution du pouvoir en divers centres, compl\u00e8tement d\u00e9structur\u00e9es ou d\u00e9construites, donc elles-m\u00eames transformant la perception du monde qu&rsquo;elles re\u00e7oivent en d\u00e9sordre en restituant \u00e9videmment des politiques qui alimentent ce d\u00e9sordre et l&rsquo;accroissent partout o&ugrave; c&rsquo;est possible ; il n&rsquo;y a qu&rsquo;un pas \u00e0 faire, et nous le faisons plus souvent qu&rsquo;\u00e0 notre tour, pour avancer l&rsquo;hypoth\u00e8se que les psychologies qui sont au service de ces intelligences sont elles-m\u00eames d\u00e9structur\u00e9es et livrent une perception qui l&rsquo;est n\u00e9cessairement. C&rsquo;est bien \u00e9videmment \u00e0 ce point que nous retrouvons Derrida, sa confession extraordinaire et la <em>French Theory<\/em>.<\/p>\n<\/p>\n<p><p>Notre th\u00e8se est que la  <em>French Theory<\/em>, dont on a mesur\u00e9 le triomphe aux USA par les extraits cit\u00e9s plus haut, et qui toucha tous les domaines, constitua un ph\u00e9nom\u00e8ne psychologique d&rsquo;une profondeur consid\u00e9rable (il est question des \u00ab\u00a0tr\u00e9fonds de la sous-culture am\u00e9ricaine\u00a0\u00bb). Ce succ\u00e8s concerna certes bien des id\u00e9es pour ces milieux des \u00e9lites devenues \u00e9lites-Syst\u00e8me qui entretiennent leur vanit\u00e9 intellectuelle s&rsquo;il le faut au prix de la destruction du monde ; mais il eut surtout un impact fondamental sur les psychologies de ces \u00e9lites, d&rsquo;ailleurs \u00e0 partir de conceptions de d\u00e9structuration et de d\u00e9construction correspondant parfaitement \u00e0 l&rsquo;esprit de l&rsquo;am\u00e9ricanisme tel qu&rsquo;on peut le percevoir, notamment dans le flux de ce ph\u00e9nom\u00e8ne historique que nous datons de la fin du XVIII\u00e8me si\u00e8cle et que nous nommons  \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>(On sait combien nous appr\u00e9cions les &Eacute;tats-Unis d&rsquo;Am\u00e9rique comme une construction a-historique, \u00ab\u00a0en-dehors de l&rsquo;Histoire\u00a0\u00bb, donc naturellement productrice d&rsquo;une politique de d\u00e9construction de l&rsquo;Histoire allant jusqu&rsquo;\u00e0 l&rsquo;annonce triomphale quoiqu&rsquo;un peu hasardeuse de la \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_fin_de_l_histoire_i_22_10_2014.html\">fin<\/a> de <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_un_quart_de_si_cle_kidnapp_et_retrouv__09_11_2014.html\">l&rsquo;Histoire<\/a>\u00ab\u00a0, au moment o&ugrave; la  <em>French Theory<\/em>  donne tous ses effets sur la psychologie am\u00e9ricaniste en accentuant d\u00e9cisivement ses caract\u00e8res naturels.)<\/p>\n<\/p>\n<p><p>Cette hypoth\u00e8se donnant un tel effet au constat de l&rsquo;influence de la  <em>French Theory  <\/em>aux USA est largement concevable tant on per\u00e7oit avec quelle force l&rsquo;un des messagers de la \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb lui-m\u00eame, Derrida, est touch\u00e9 au niveau de sa psychologie. La philosophie de la d\u00e9construction et de la d\u00e9structuration (\u00ab\u00a0d\u00e9constructuration\u00a0\u00bb) touche la psychologie autant que l&rsquo;esprit, et elle touche l&rsquo;esprit d&rsquo;une fa\u00e7on radicale parce qu&rsquo;elle a sur la psychologie un effet d\u00e9constructeur et d\u00e9structurant qui agit de toutes les fa\u00e7ons sur l&rsquo;esprit par la voie de la perception ainsi fauss\u00e9e, sans m\u00eame qu&rsquo;il soit n\u00e9cessaire d&rsquo;assimiler les id\u00e9es port\u00e9es par la philosophie elle-m\u00eame.<\/p>\n<\/p>\n<p><p>Les philosophes de la  <em>French Theory<\/em>  eurent un peu le m\u00eame effet que celui qu&rsquo;amena Sigmund Freud en le pressentant largement, lors de son premier voyage aux USA en 1909, lorsqu&rsquo;il s&rsquo;exclama que ce pays-continent \u00e9tait la terre r\u00eav\u00e9e pour la psychanalyse tant il \u00e9tait producteur fondamental de la n\u00e9vrose caract\u00e9ristique de la modernit\u00e9, d\u00e9sign\u00e9e en 1879 par le Dr. Beard comme \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article-les_tyrannies_de_l_id_al_le_mal_am_ricain_14_06_2004.html\">le mal am\u00e9ricain<\/a>\u00ab\u00a0. Simplement, \u00e0 un peu moins d&rsquo;un si\u00e8cle de distance, ils ont d\u00e9cisivement prolong\u00e9 Freud pour porter la psychologie de l&rsquo;am\u00e9ricanisme \u00e0 son point de fusion, lorsqu&rsquo;elle devint le parfait serviteur du Syst\u00e8me en se d\u00e9structurant. La  <em>French Theory<\/em>  servait sur un plateau de fer et de tonnerre le destin des USA d&rsquo;apr\u00e8s la Guerre froide : une psychologie \u00e0 la fois absolument d\u00e9structur\u00e9e et absolument d\u00e9structurante, ou absolument \u00ab\u00a0d\u00e9constructurante\u00a0\u00bb si l&rsquo;on veut, avec des id\u00e9es plus ou moins pr\u00e9cis\u00e9es \u00e0 mesure, qu&rsquo;on peut de temps en temps saupoudrer d&rsquo;un zeste de  <em>neocon<\/em> straussien et d&rsquo;une pinc\u00e9e capitalistique de von Hayek, sans oublier la \u00ab\u00a0d\u00e9mocratie\u00a0\u00bb dont l&rsquo;id\u00e9e port\u00e9e vers des lieux impr\u00e9par\u00e9s pour cela, &ndash; c&rsquo;est-\u00e0-dire quasiment partout, &ndash; enfante elle aussi le d\u00e9sordre par \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Dr\u00f4le d&rsquo;hypoth\u00e8se ou dr\u00f4le de th\u00e9orie finalement, que de proposer un tel r\u00f4le \u00e0 la  <em>French Theory<\/em>, matrice de la postmodernit\u00e9 et dont la position \u00e9pouse parfaitement l&rsquo;invasion universelle du \u00ab\u00a0march\u00e9\u00a0\u00bb et de l&rsquo;effet de d\u00e9construction et de d\u00e9structuration qu&rsquo;il exige pour \u00eatre quitte de toutes les r\u00e8gles et de tous les principes. On retrouve le m\u00eame mouvement dans le monde de l&rsquo;art, avec la d\u00e9construction compl\u00e8te de la notion d'\u00a0\u00bbart\u00a0\u00bb qu&rsquo;implique l'\u00a0\u00bbArt Contemporain\u00a0\u00bb (l&rsquo;AC), lui aussi enti\u00e8rement cr\u00e9ature cr\u00e9\u00e9e par le \u00ab\u00a0march\u00e9\u00a0\u00bb, le  <em>Corporate Power<\/em>  et l&rsquo;hypercapitalisme, &ndash; et tous ces bouleversements pesant affreusement sur les psychologies de leurs principaux acteurs, toujours dans le m\u00eame sens \u00ab\u00a0d\u00e9constructurant\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>On observerait alors plusieurs encha&icirc;nement \u00e0 la fois contradictoires et logiques &#8230; Les USA qui purent se constituer gr\u00e2ce \u00e0 la France et son intervention lors de leur guerre de l&rsquo;ind\u00e9pendance, lanc\u00e9s \u00e0 la conqu\u00eate du monde par l&rsquo;am\u00e9ricanisation (vieux projet \u00e9vident d\u00e8s la moiti\u00e9 du XIX\u00e8me si\u00e8cle et la <em>Manifest Destiny<\/em>) dans un sens qui trahissait \u00e9videmment les conceptions fran\u00e7aises engag\u00e9es lors de l&rsquo;aide aux <em>insurgents<\/em> de 1776 (voir la Deuxi\u00e8me Partie du Tome-I de  <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>) ; les m\u00eames USA recevant en retour, deux si\u00e8cles plus tard, de la m\u00eame France qui est productrice tout au long de son histoire du pire et du meilleur de l&rsquo;esprit dans un affrontement m\u00e9tahistorique colossal, la  <em>French Theory  <\/em>qui pourrait bien \u00eatre la recette pour accomplir le destin annonc\u00e9 par  <a href=\"http:\/\/www.dedefensa.org\/article-la_th_orie_de_l_chec_d_orlov_06_03_2015.html\">Lincoln-1838<\/a>  (&laquo; <em>En tant que nation d&rsquo;hommes libres, nous devons \u00e9ternellement survivre, ou mourir en nous suicidant<\/em> &raquo;) &#8230; Le probl\u00e8me, sans nul doute, est que nous sommes du voyage, et il faut esp\u00e9rer qu&rsquo;il y a plus d&#8217;embarcations de sauvetage qu&rsquo;il n&rsquo;y en avait sur le <em>Titanic<\/em>.<\/p>\n<\/p>\n<p><p>Au reste, on conviendra que ce rangement ne contredit en rien celui, plus g\u00e9n\u00e9ral, que nous proposons avec la th\u00e8se du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb. Il s&rsquo;y ins\u00e8re parfaitement, avec cette proximit\u00e9 jusqu&rsquo;\u00e0 l&rsquo;intimit\u00e9 de la volont\u00e9 de d\u00e9structuration (et la dissolution des esprits et des formes), de d\u00e9structuration-dissolution, de \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb, qui est le caract\u00e8re m\u00eame de la modernit\u00e9, aussi bien que des ph\u00e9nom\u00e8nes que nous observons, en constante progression depuis plus de deux si\u00e8cles et entr\u00e9s dans une phase d&rsquo;acc\u00e9l\u00e9ration foudroyante depuis un quart de si\u00e8cle et particuli\u00e8rement depuis  2001 ; cette \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb passant par l&rsquo;\u00e9volution irr\u00e9sistible de la surpuissance \u00e0 l&rsquo;autodestruction en finissant par une attaque de \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb prenant pour cible ultime, &ndash; puisque rien d&rsquo;autre ne subsiste et que la \u00ab\u00a0d\u00e9constructuration\u00a0\u00bb est la seule activit\u00e9 possible de cette surpuissance, &ndash; les structures et les constructions que le Syst\u00e8me avait \u00e9difi\u00e9es pour d\u00e9structurer et d\u00e9construire le monde.<\/p>\n<\/p>\n<p><p>Ces trois minutes 48 secondes de la \u00ab\u00a0confession\u00a0\u00bb de Derrida, celle-ci avec son caract\u00e8re tragique et sa r\u00e9sonnance path\u00e9tique, nous sugg\u00e8rent effectivement que l&rsquo;on se trouve l\u00e0 devant un ph\u00e9nom\u00e8ne dont la description et la signification touchent aux choses les plus hautes et \u00e0 l&rsquo;inversion la plus basses de ces choses les plus hautes. Comme si s&rsquo;ouvrait soudain, devant nous, une porte d&rsquo;un pan essentiel pour notre contre-civilisation du Grand Myst\u00e8re&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0D\u00e9constructuration\u00a0\u00bb du d\u00e9constructeur 10 f\u00e9vrier 2020 &ndash; Nous avions consacr\u00e9 in illo tempore (le 30 d\u00e9cembre 2017) un F&#038;C s&rsquo;appuyant sur un texte du 21 d\u00e9cembre 2017 que James Edward Kunstler consacrait \u00e0 la situation crisique extraordinaire o&ugrave; se trouve emport\u00e9e l&rsquo;Am\u00e9rique, &ndash; et les 26 mois depuis ce texte n&rsquo;ont fait qu&rsquo;accentuer la tendance&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[18001,13231,7482,13688,13051,11488,17997,3090,2801,12560,18000,11489,2639],"class_list":["post-79100","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-confession","tag-d-c-la-folle","tag-deconstruction","tag-deconstructuration","tag-derrida","tag-french","tag-hegemonisme-chaotique","tag-influence","tag-kunstler","tag-progressisme-societal","tag-structuralisme","tag-theory","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79100"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79100\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}