{"id":79108,"date":"2020-02-14T15:09:37","date_gmt":"2020-02-14T15:09:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/14\/un-virus-des-plus-commodes\/"},"modified":"2020-02-14T15:09:37","modified_gmt":"2020-02-14T15:09:37","slug":"un-virus-des-plus-commodes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/14\/un-virus-des-plus-commodes\/","title":{"rendered":"Un virus des plus commodes"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Un virus des plus commodes<\/h2>\n<\/p>\n<p><p>Je pr\u00e9f\u00e8re \u00e9crire sur des choses que je connais, mais de temps en temps, une occasion se pr\u00e9sente \u00e0 moi de commenter un aspect de la m\u00e9fiance et de la confusion g\u00e9n\u00e9ralis\u00e9es tout en me reposant sur la base solide de ma curiosit\u00e9 professionnelle. C&rsquo;est le cas du nouveau coronavirus 2019-nCoV. Beaucoup d&rsquo;\u00e9l\u00e9ments de l&rsquo;histoire du coronavirus ne sont pas coh\u00e9rents, et c&rsquo;est ce que je veux explorer. D&#8217;embl\u00e9e, je tiens \u00e0 pr\u00e9ciser que je ne suis pas un expert en la mati\u00e8re. Le 2019-nCoV est-il une arme biologique g\u00e9n\u00e9tiquement modifi\u00e9e ou est-ce une souche naturellement \u00e9volu\u00e9e d&rsquo;un virus end\u00e9mique dans la population de chauves-souris en Chine ? Nous ne le savons pas, mais il est int\u00e9ressant d&rsquo;examiner la plausibilit\u00e9 de chacun de ces sc\u00e9narios et de voir si ce que nous observons pourrait \u00eatre une combinaison d&rsquo;un peu des 2.<\/p>\n<\/p>\n<p><p>En tant qu&rsquo;arme biologique de destruction massive, le 2019-nCoV n&rsquo;est pas particuli\u00e8rement bon. D&rsquo;un autre c\u00f4t\u00e9, il est tr\u00e8s contagieux et peut \u00eatre transmis par des personnes infect\u00e9es qui ne pr\u00e9sentent aucun des sympt\u00f4mes, comme la fi\u00e8vre et l&rsquo;essoufflement. En revanche, le taux de mortalit\u00e9 n&rsquo;est que de 2,1 % et devrait baisser car ce taux ne tient pas compte du nombre potentiellement important de jeunes gens en bonne sant\u00e9 qui ont contract\u00e9 le virus mais n&rsquo;ont jamais pr\u00e9sent\u00e9 de sympt\u00f4mes, n&rsquo;ont jamais \u00e9t\u00e9 test\u00e9s et ne sauront jamais qu&rsquo;ils ont surv\u00e9cu. Pour qu&rsquo;un virus soit une arme biologique puissante, son taux de mortalit\u00e9 doit \u00eatre optimis\u00e9 afin de tuer le plus grand nombre possible de ses victimes, mais assez lentement pour que les victimes ne meurent pas avant d&rsquo;avoir eu la possibilit\u00e9 de propager l&rsquo;infection.<\/p>\n<\/p>\n<p><p>Autre point n\u00e9gatif : l&rsquo;\u00e2ge moyen de ceux qui y succombent est d&rsquo;environ 65 ans, ce qui la rend plut\u00f4t inefficace pour affaiblir les capacit\u00e9s productives d&rsquo;une nation, qu&rsquo;elle soit industrielle ou militaire, puisque beaucoup de ceux qui meurent ont d\u00e9pass\u00e9 leur p\u00e9riode de productivit\u00e9 maximale ou sont \u00e0 la retraite. En fait, d&rsquo;un point de vue plut\u00f4t cynique, ce virus pourrait \u00eatre plut\u00f4t utile pour r\u00e9duire le fardeau des malades \u00e9conomiquement improductifs et des personnes \u00e2g\u00e9es qui, dans une population chinoise vieillissante, et compte tenu du respect que la soci\u00e9t\u00e9 chinoise accorde traditionnellement \u00e0 ses a&icirc;n\u00e9s, consomment une part croissante des ressources du pays.<\/p>\n<\/p>\n<p><p>D&rsquo;un autre c\u00f4t\u00e9, ceux qui y succombent sont principalement des Chinois, des hommes, plut\u00f4t \u00e2g\u00e9s, ce qui peut \u00eatre consid\u00e9r\u00e9 comme le signe d&rsquo;un ciblage tr\u00e8s habile. En fait, la s\u00e9lectivit\u00e9 de ce virus peut \u00eatre le signe d&rsquo;un effort visant \u00e0 \u00e9liminer s\u00e9lectivement les membres du parti communiste chinois, afin de d\u00e9stabiliser politiquement la Chine, d&rsquo;y effectuer un changement de r\u00e9gime et d&rsquo;imposer \u00e0 la malheureuse population chinoise un syst\u00e8me politique Libert\u00e9 &#038; D\u00e9mocratie<sup>&reg;  <\/sup>\u00e0 l&rsquo;am\u00e9ricaine. &Eacute;tant donn\u00e9 que les &Eacute;tats-Unis n&rsquo;ont plus la puissance militaire n\u00e9cessaire pour affronter la Chine (et ne peuvent m\u00eame pas r\u00e9pondre aux attaques de missiles iraniens sur leurs bases militaires), et que les &Eacute;tats-Unis ont pratiquement perdu la guerre commerciale contre la Chine, une arme biologique pourrait \u00eatre la seule fl\u00e8che qui leur reste dans leur carquois.<\/p>\n<\/p>\n<p><p>N&rsquo;oublions pas que le Pentagone a construit un certain nombre d&rsquo;installations dans le monde entier pour la recherche de divers agents pathog\u00e8nes. &Eacute;tant donn\u00e9 qu&rsquo;il s&rsquo;agit du Pentagone, dont la t\u00e2che fondamentale consiste \u00e0 tuer des gens, et non de l&rsquo;Organisation mondiale de la sant\u00e9, il semble probable qu&rsquo;il fasse \u00e9galement quelque chose dans le sens du d\u00e9veloppement d&rsquo;armes biologiques efficaces. Il y a quelques ann\u00e9es, des agents am\u00e9ricains ont \u00e9t\u00e9 pris en train de collecter des \u00e9chantillons d&rsquo;ADN aupr\u00e8s de la population russe et ont \u00e9t\u00e9 rapidement escort\u00e9s hors du pays.<\/p>\n<\/p>\n<p><p>La supposition \u00e9vidente est que ces \u00e9chantillons devaient \u00eatre utilis\u00e9s pour d\u00e9velopper des armes biologiques visant sp\u00e9cifiquement la population russe. Je pense que les sp\u00e9cialistes charg\u00e9s de cette t\u00e2che ont \u00e9t\u00e9 tr\u00e8s d\u00e9\u00e7us de d\u00e9couvrir que la grande majorit\u00e9 de la population russe est compos\u00e9e de blancs ordinaires, \u00e0 peu pr\u00e8s les m\u00eames que dans le monde entier, et que les cibler, c&rsquo;est se cibler soi-m\u00eame. Mais ce n&rsquo;est pas le cas des Chinois, dont la constitution g\u00e9n\u00e9tique est plus distinctive. Tout cela est clairement peu concluant, et il se peut tr\u00e8s bien que le programme d&rsquo;armes biologiques du Pentagone ne soit qu&rsquo;une autre partie de sa gigantesque machine \u00e0 produire du cash, ou qu&rsquo;il produise effectivement une arme biologique de temps en temps, et que 2019-nCoV soit le maigre r\u00e9sultat qu&rsquo;il ait r\u00e9ussi \u00e0 produire jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n<\/p>\n<p><p>Mais l\u00e0 encore, la fa\u00e7on dont l&rsquo;\u00e9pid\u00e9mie a commenc\u00e9 n&rsquo;est pas celle \u00e0 laquelle on pourrait s&rsquo;attendre si une souche artificielle \u00e9tait lib\u00e9r\u00e9e \u00e0 un moment et un endroit donn\u00e9s. Dans ce cas, on s&rsquo;attendrait \u00e0 un pic instantan\u00e9 d&rsquo;infections, avec des sympt\u00f4mes apparaissant en grappes serr\u00e9es juste \u00e0 la fin de la p\u00e9riode d&rsquo;incubation. Mais au lieu de cela, nous avons vu des incidents sporadiques d&rsquo;infection li\u00e9s \u00e0 un certain march\u00e9 aux poissons de Wuhan, donnant progressivement naissance \u00e0 une \u00e9pid\u00e9mie. Cela sugg\u00e8re que la source du virus est naturelle, comme les chauves-souris qui \u00e9taient vendues sur ce march\u00e9. Cependant, les Chinois mangent des chauves-souris depuis des milliers d&rsquo;ann\u00e9es (la soupe aux chauves-souris est un mets d\u00e9licat), alors pourquoi ce virus n&rsquo;appara&icirc;trait-il que maintenant ?<\/p>\n<\/p>\n<p><p>La raison de cette synchronisation peut simplement \u00eatre un contact accru. Le virus est apparu aux alentours du nouvel an chinois. Selon le calendrier chinois, c&rsquo;est l&rsquo;ann\u00e9e du rat, et bien que les Chinois mangent aussi des rats, les chauves-souris sont pr\u00e9f\u00e9r\u00e9es. En outre, environ deux tiers de tous les porcs en Chine ont r\u00e9cemment \u00e9t\u00e9 d\u00e9cim\u00e9s \u00e0 cause de la grippe porcine, ce qui a fait grimper les prix du porc et, incidemment, a forc\u00e9 la Chine \u00e0 commencer \u00e0 importer des porcs des &Eacute;tats-Unis, qui \u00e9taient auparavant soumis \u00e0 un embargo. Cela a fait des chauves-souris, naturellement abondantes, une alternative attrayante aux autres sources de prot\u00e9ines animales. Tout aussi fortuitement, la population chinoise de poulets est maintenant ravag\u00e9e par la grippe aviaire, ce qui, comme on peut s&rsquo;y attendre, obligera la Chine \u00e0 commencer \u00e0 importer des poulets des &Eacute;tats-Unis \u00e9galement.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r, tout cela n&rsquo;est pas tr\u00e8s concluant, mais on peut consid\u00e9rer que tous les moyens sont bons en amour et dans la guerre, en particulier en cas de guerre commerciale avec les &Eacute;tats-Unis. Mais ce qui a d\u00e9clench\u00e9 quelques alarmes dans ma t\u00eate, c&rsquo;est la r\u00e9action \u00e0 l&rsquo;\u00e9pid\u00e9mie de coronavirus, tant en Chine qu&rsquo;en Occident, et plus particuli\u00e8rement aux &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Tout d&rsquo;abord, le gouvernement chinois a trait\u00e9 l&rsquo;\u00e9pid\u00e9mie comme un acte de guerre, en d\u00e9ployant tous les moyens \u00e0 sa disposition, y compris l&rsquo;arm\u00e9e, afin de contenir sa propagation, en construisant plusieurs nouveaux grands h\u00f4pitaux, en mettant des villes enti\u00e8res en quarantaine et en prolongeant les vacances nationales. La r\u00e9ponse a \u00e9t\u00e9 bien au-del\u00e0 de ce que ce virus semble justifier, avec son faible taux de mortalit\u00e9. Sans le dire, le gouvernement chinois a trait\u00e9 cette \u00e9pid\u00e9mie comme un acte de guerre biologique &ndash; peut-\u00eatre comme une r\u00e9p\u00e9tition d&rsquo;une \u00e9pid\u00e9mie plus mortelle qui pourrait survenir \u00e0 l&rsquo;avenir. En tout cas, le gouvernement chinois veille \u00e0 ce que personne ne puisse lui reprocher de ne pas prendre le probl\u00e8me suffisamment au s\u00e9rieux, ou de ne pas faire assez pour le r\u00e9soudre.<\/p>\n<\/p>\n<p><p>Deuxi\u00e8mement, la r\u00e9action des m\u00e9dias occidentaux a \u00e9t\u00e9 un effort exemplaire pour semer la panique et salir la Chine, transformant ce qui s&rsquo;y passe en une histoire d&rsquo;horreur. Non seulement les m\u00e9dias ont fait de leur mieux pour attiser l&rsquo;hyst\u00e9rie des masses sur tout ce qui est chinois, mais divers blogueurs et \u00ab\u00a0experts\u00a0\u00bb ind\u00e9pendants se sont mis en quatre pour attiser la panique. Il semble qu&rsquo;il y ait eu une r\u00e9orientation politique de la russophobie (o&ugrave; il \u00e9tait grand temps pour les &Eacute;tats-Unis d&rsquo;admettre silencieusement leur d\u00e9faite et de passer \u00e0 autre chose) \u00e0 la sinophobie (o&ugrave; les &Eacute;tats-Unis n&rsquo;ont pas encore eu \u00e0 baisser leur froc). Les commentateurs th\u00e9oriquement ind\u00e9pendants qui profitent de cette occasion pour attaquer la Chine se comportent comme des idiots utiles dans cette campagne m\u00e9diatique \u00e0 la chor\u00e9graphie centralis\u00e9e.<\/p>\n<\/p>\n<p><p>Troisi\u00e8mement, la Maison Blanche a r\u00e9cemment demand\u00e9 que des experts examinent la possibilit\u00e9 que le 2019-nCoV ait \u00e9t\u00e9 g\u00e9n\u00e9tiquement modifi\u00e9. Il arrive souvent que la personne qui crie \u00ab\u00a0au voleur\u00a0\u00bb le plus fort se trouve \u00eatre le voleur lui-m\u00eame. Je pense que la prochaine \u00e9tape sera de d\u00e9clarer que ce virus est bien une arme biologique d\u00e9velopp\u00e9e par&hellip; pourquoi pas la Russie, bien s&ucirc;r, et Mr. Poutine personnellement.<\/p>\n<\/p>\n<p><p>Compte tenu de tout cela, le sc\u00e9nario qui me semble le plus plausible est que ce virus a \u00e9t\u00e9 g\u00e9n\u00e9tiquement modifi\u00e9 dans l&rsquo;un des laboratoires d&rsquo;armes biologiques du Pentagone et introduit en Chine via des chauves-souris sauvages infect\u00e9es, ayant choisi comme cible Wuhan, la Mecque de la technologie et un grand centre industriel. Le but ultime, on pourrait le supposer, est d&rsquo;inciter les entreprises am\u00e9ricaines \u00e0 rapatrier leur production sur le continent am\u00e9ricain afin de \u00ab\u00a0<em>Make American Great Again<\/em>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>Mais je soup\u00e7onne que cela ne va pas marcher. Le gouvernement chinois parviendra \u00e0 stopper l&rsquo;\u00e9pid\u00e9mie, d\u00e9montrant ainsi qu&rsquo;il se soucie de sa population et qu&rsquo;il la prot\u00e8ge efficacement. D\u00e9j\u00e0, le taux d&rsquo;infection, trac\u00e9 sur une \u00e9chelle logarithmique, commence \u00e0 diminuer avec une inflexion de la tangente, ce qui signifie que l&rsquo;\u00e9pid\u00e9mie perd de sa vigueur. Et puis, en collaboration avec de nombreux autres pays, la Chine va poursuivre la t\u00e2che principale qui consiste \u00e0 \u00e9radiquer l&rsquo;autre parasite, \u00e0 savoir les &Eacute;tats-Unis, un pays qui obtient des choses en \u00e9change de rien, en imprimant simplement des dollars.<\/p>\n<\/p>\n<p><p>Le 8 f\u00e9vrier 2020, <a href=\"http:\/\/cluborlov.blogspot.com\/2020\/02\/a-most-convenient-virus.html\">Club Orlov<\/a>&ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/un-virus-des-plus-commodes\">Sakerfrancophone<\/a>.<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un virus des plus commodes Je pr\u00e9f\u00e8re \u00e9crire sur des choses que je connais, mais de temps en temps, une occasion se pr\u00e9sente \u00e0 moi de commenter un aspect de la m\u00e9fiance et de la confusion g\u00e9n\u00e9ralis\u00e9es tout en me reposant sur la base solide de ma curiosit\u00e9 professionnelle. C&rsquo;est le cas du nouveau coronavirus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[19687,3904,19686,3977,19677,7033,2645,4551,19688,19689],"class_list":["post-79108","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-2019-ncov","tag-biologique","tag-chauve-souris","tag-chine","tag-coronavirus","tag-epidemie","tag-guerre","tag-panique","tag-sinophobie","tag-wuhan"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79108"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79108\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}