{"id":79112,"date":"2020-02-17T10:13:04","date_gmt":"2020-02-17T10:13:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/17\/la-deconstruction-rampante-des-usa\/"},"modified":"2020-02-17T10:13:04","modified_gmt":"2020-02-17T10:13:04","slug":"la-deconstruction-rampante-des-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/02\/17\/la-deconstruction-rampante-des-usa\/","title":{"rendered":"La d\u00e9construction rampante des USA"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">La d\u00e9construction rampante des USA<\/h2>\n<\/p>\n<p><p>Wayne Madsen fait un travail des plus int\u00e9ressants, en pr\u00e9sentant, en comptabilisant et en commentant les conflits existant actuellement entre Trump (Washingtons D.C. et sa bureaucratie, centre f\u00e9d\u00e9ral des USA) et diff\u00e9rents &Eacute;tats de l&rsquo;Union, essentiellement ceux qui ont des gouverneurs d\u00e9mocrates mais aussi quelques-uns avec des gouverneurs r\u00e9publicains (notamment le Maryland, le Massachussetts et le Vermont). Bien entendu, Madsen \u00e9tant ce qu&rsquo;il est, &ndash; un farouche opposant \u00e0 Trump, &ndash; il fait cette description en condamnant l&rsquo;attitude de Washington D.C., mais il le fait \u00e0 bon escient d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale&#8230; De toutes les fa\u00e7ons ce n&rsquo;est pas ce qui nous int\u00e9resse, &ndash; \u00ab\u00a0bon escient\u00a0\u00bb ou pas, &ndash; mais de fa\u00e7on tr\u00e8s diff\u00e9rente la description d&rsquo;une crise interne aux USA d\u00e9j\u00e0 &quot;<a href=\"https:\/\/www.dedefensa.org\/article\/reflexion-sur-leclatement-des-usa\">en marche<\/a>\u00a0\u00bb depuis plusieurs ann\u00e9es, qui s&rsquo;apparente plus \u00e0 une dynamique de \u00ab\u00a0d\u00e9construction\u00a0\u00bb (d\u00e9structuration-dissolution) qu&rsquo;\u00e0 une dynamique de s\u00e9cession.<\/p>\n<\/p>\n<p><p>En effet, l&rsquo;int\u00e9r\u00eat de cette pr\u00e9sentation est de nous faire r\u00e9aliser qu&rsquo;au lieu de nous trouver dans une situation o&ugrave; une grande crise interne US conduit un certain nombre d&rsquo;&Eacute;tats \u00e0 s&rsquo;opposer le plus sopuvent en s&rsquo;unissant entre eux (ph\u00e9nom\u00e8ne pouvant conduire \u00e0 leur s\u00e9cession), il s&rsquo;agit d&rsquo;un certain nombre de conflits entre D.C. et des &Eacute;tats divers selon divers regroupements, sur diff\u00e9rents aspects des politiques f\u00e9d\u00e9rales int\u00e9rieures et ext\u00e9rieures que ces &Eacute;tats refusent d&rsquo;appliquer.<\/p>\n<\/p>\n<p><p>Madsen commence et termine sur des analogies de situations historiques permettant de mesurer la crise qu&rsquo;il d\u00e9crit, et qui pourtant montrent qu&rsquo;il s&rsquo;agit aujourd&rsquo;hui d&rsquo;une crise diff\u00e9rente de celles qui servent de r\u00e9f\u00e9rences :<\/p>\n<p>&bull; en introduction, il signale que c&rsquo;est la crise la plus grave depuis celle des ann\u00e9es 1950-1960, lorsqu&rsquo;il s&rsquo;est agi d&rsquo;imposer le respect des droits civiques constitutionnels pour les Africains-Am\u00e9ricains dans certains &Eacute;tats du Sud : &laquo; <em>Depuis le mouvement pour les droits civiques des ann\u00e9es 1950 et 1960, les tensions n&rsquo;ont jamais \u00e9t\u00e9 aussi fortes entre une administration am\u00e9ricaine et les &Eacute;tats de l&rsquo;Union. Pendant l&rsquo;\u00e8re des droits civiques, c&rsquo;est le gouvernement f\u00e9d\u00e9ral qui jouait le r\u00f4le de protecteur de la Constitution am\u00e9ricaine en faisant pression sur les &Eacute;tats s\u00e9gr\u00e9gationnistes comme l&rsquo;Arkansas, le Mississippi et l&rsquo;Alabama pour qu&rsquo;ils se conforment \u00e0 la loi f\u00e9d\u00e9rale sur les droits civiques. Aujourd&rsquo;hui, les r\u00f4les sont renvers\u00e9s. Une administration f\u00e9d\u00e9rale raciste et x\u00e9nophobe a en fait commenc\u00e9 \u00e0 imposer des sanctions de d\u00e9placement et autres \u00e0 des &Eacute;tats comme New York et la Californie, simplement parce qu&rsquo;ils respectent la l\u00e9gislation am\u00e9ricaine et internationale sur les droits de l&rsquo;homme, en particulier celle qui traite de l&rsquo;asile pour les r\u00e9fugi\u00e9s \u00e9trangers<\/em>. &raquo; ;<\/p>\n<p>&bull; en conclusion, Madsen \u00e9voque la r\u00e9f\u00e9rence la plus importante et la plus tragique de l&rsquo;histoire des USA, bien entendu la Guerre de S\u00e9cession : &laquo; <em>La derni\u00e8re \u00ab\u00a0guerre entre les &Eacute;tats\u00a0\u00bb a oppos\u00e9 le gouvernement f\u00e9d\u00e9ral de DC et les &Eacute;tats rest\u00e9s dans l&rsquo;Union d&rsquo;un c\u00f4t\u00e9 et les &Eacute;tats conf\u00e9d\u00e9r\u00e9s pro-esclavagistes du Sud. Si Trump poursuit sa guerre contre certains &Eacute;tats, cette politique pourrait se transformer en une guerre entre les &Eacute;tats les plus peupl\u00e9s et l&rsquo;administration Trump, avec de nombreux sympathisants des &Eacute;tats au sein du gouvernement f\u00e9d\u00e9ral et de l&rsquo;arm\u00e9e. C&rsquo;est une voie vers un d\u00e9sastre pour Trump et ses loyalistes<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Madsen d\u00e9veloppe consid\u00e9rablement l&rsquo;actuel conflit, qui vient de prendre un tour aigu apr\u00e8s l&rsquo;\u00e9chec d&rsquo;une conciliation le 13 f\u00e9vrier, entre la Maison-Blanche et le gouverneur de l&rsquo;&Eacute;tat de New York, avec divers \u00e0-c\u00f4t\u00e9s peu aimables de Trump pour la personne du gouverneur, de la famille Cuomo, et donc Italien-Am\u00e9ricain. Effectivement comme on pourrait le deviner , la querelle porte sur des processus de d\u00e9placement de personne que l&rsquo;&Eacute;tat de New York veut d\u00e9velopper selon des conventions et programmes internationaux divers, tandis que Washington veut qu&rsquo;on abandonnez ces pratiques. (Tout cela, entrecoup\u00e9 d&rsquo;exigences personnelles de Trump, bien mal accueillies par New York.) Des occurrences semblables existent avec la Californie, d&rsquo;autres territoires et villes auto-d\u00e9clar\u00e9es \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/haine-et-destructuration\">sanctuaires<\/a>\u00ab\u00a0, c&rsquo;est-\u00e0-dire refusant d&rsquo;appliquer les restrictions f\u00e9d\u00e9rales sur l&rsquo;immigration. <\/p>\n<\/p>\n<p><p>&laquo; <em>Trump traite la Californie, New York et Porto Rico comme des nations \u00e9trang\u00e8res avec lesquelles son gouvernement serait en guerre<\/em> &raquo;, observe Madsen, pr\u00e9cisant que des sanctions sont pr\u00e9vues ou prises, comme Washington d\u00e9cide des sanctions contre l&rsquo;Iran, la Russise et une multitude d&rsquo;autres pays. (Voil\u00e0 qui donne une singuli\u00e8re image de l&rsquo;unilat\u00e9ralisme\u00a0\u00bb trumpiste, et de son id\u00e9e venue d'\u00a0\u00bb<em>America First<\/em>\u00ab\u00a0.)<\/p>\n<\/p>\n<p><p>Encore, Madsen qui est tr\u00e8s \u00e0 gauche dans ses positions (mais il reste un ind\u00e9pendant assez libre de jugement) insiste-t-il sur la question de l&rsquo;immigration. Il existe d&rsquo;autres contentieux tr\u00e8s actifs entre des &Eacute;tats et D.C., sur des aspects de politique ext\u00e9rieure. Ainsi, nombre d&rsquo;&Eacute;tats ne veulent pas suivre la politique tarifaire protectionniste de l&rsquo;administration et entretiennent des bureaux qui les repr\u00e9sentent dans des pays \u00e9trangers, comme des sortes d&rsquo;ambassades, et qui cherchent \u00e0 \u00e9tablir directement des accords commerciaux. Vingt-quatre &Eacute;tats de l&rsquo;Union ont refus\u00e9 la d\u00e9cision de Washington de retrait de l&rsquo;Accord de Paris sur le climat et suivent les d\u00e9cisions de cet Accord.<\/p>\n<\/p>\n<p><p>Plus encore, nous voulons dire sur un terrain plus d\u00e9licat directement connect\u00e9s \u00e0 la politique de s\u00e9curit\u00e9 nationale de Washington, diverses entit\u00e9s (&Eacute;tats ou villes) refusent la rupture compl\u00e8te avec l&rsquo;entit\u00e9 palestinienne et poursuivent des relations par divers canaux tout en prenant leurs distances avec la politique pro-sioniste de l&rsquo;administration. Le caract\u00e8re extr\u00eamement politique de ce cas conduit Madsen \u00e0 faire un commentaire particuli\u00e8rement r\u00e9v\u00e9lateur des dynamiques en cours, et des situations auxquelles elles pourraient conduire : &laquo; <em>Si Trump continue \u00e0 attaquer des &Eacute;tats de l&rsquo;Union, en particulier ceux qui ont des gouverneurs d\u00e9mocrates, les missions commerciales<\/em>[\u00e9tablies directement par ces &Eacute;tats dans des capitales \u00e9trang\u00e8res] <em>pourraient facilement \u00eatre transform\u00e9es en bureaux diplomatiques de facto qui pourraient contester dans diverses capitales mondiales des politiques particuli\u00e8rement destructrices de Trump \u00e9manant de Washington<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>On comprend alors combien est justifi\u00e9e la remarque ci-dessus selon laquelle il s&rsquo;agit d'\u00a0\u00bb une crise interne aux USA qui s&rsquo;apparente plus \u00e0 une dynamique de &lsquo;d\u00e9construction&rsquo; (d\u00e9structuration-dissolution) qu&rsquo;\u00e0 une dynamique de s\u00e9cession\u00a0\u00bb puisqu&rsquo;il n&rsquo;y a pas un groupe d&rsquo;&Eacute;tats impliqu\u00e9s dans un seul d\u00e9saccord ou une diversit\u00e9 d&rsquo;&Eacute;tats en d\u00e9saccord avec le centre sur une seule question. Il y a une mosa\u00efque d&rsquo;&Eacute;tats en m\u00e9sentente parfois aigue sur une multitude de d\u00e9cisions et de politiques du centre, et qui refusent effectivement de les appliquer ou de les suivre. Il y a donc bien une dynamique autant qu&rsquo;une logique de d\u00e9construction (d\u00e9structuration-dissolution) de l&rsquo;ensemble am\u00e9ricaniste connu sous le nom des &Eacute;tats-Unis d&rsquo;Am\u00e9rique. Le processus conduit beaucoup plus au d\u00e9sordre, \u00e0 la perte de l\u00e9gitimit\u00e9 et d&rsquo;autorit\u00e9 de centre, qu&rsquo;\u00e0 des oppositions ou des affrontements bien identifi\u00e9s et opposant des blocs.<\/p>\n<\/p>\n<blockquote>\n<p><p>Effectivement, ce qui est en jeu concerne les principes (l\u00e9gitimit\u00e9, autorit\u00e9) qui tiennent ensemble les &Eacute;tats au sein d&rsquo;une f\u00e9d\u00e9ration (d&rsquo;une Union) dont le centre s&rsquo;est hypertrophi\u00e9 jusqu&rsquo;\u00e0 devenir une sorte d&rsquo;entit\u00e9 autoritariste, une structure dictatoriale ou dans tous les cas de plus en plus ressentie comme telle, &ndash; et qui, selon nous, est directement un instrument, une courroie de transmission de l&rsquo;entit\u00e9-ma&icirc;tresse qu&rsquo;est le Syst\u00e8me. Bien entendu, la personnalit\u00e9 de Trump, par sa fa\u00e7on de gouverner, \u00e0 la fois hors des normes, capricieuse et autoritaire, \u00e0 la fois intransigeante et souvent sous forme d&rsquo;ultimatum et de pressions brutales (\u00ab\u00a0<em>The Art of the Deal<\/em>\u00a0\u00bb !), constitue une fois encore l&rsquo;\u00e9l\u00e9ment qui met \u00e0 jour, et m\u00eame au grand jour et d&rsquo;une fa\u00e7on brutale, un conflit latent qui, \u00e0 notre sens, a toujours exist\u00e9 aux USA ; qui a paru r\u00e9gl\u00e9 en 1865 pour n&rsquo;\u00eatre en fait qu&rsquo;exacerb\u00e9.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On comprend \u00e9videmment, parce que c&rsquo;est l&rsquo;\u00e9vidence, que si Trump gagne sa r\u00e9\u00e9lection, il va devenir de plus en plus exigeant et autoritaire, surtout \u00e0 l&rsquo;int\u00e9rieur, contre le parti d\u00e9mocrate certes, mais aussi contre les pouvoirs concurrents. Quant aux &Eacute;tats r\u00e9tifs, ayant constat\u00e9 dans ce cas que la tactique g\u00e9n\u00e9rale du parti d\u00e9mocrate de l&rsquo;\u00e9limination de Trump a \u00e9chou\u00e9, ils vont se trouver de plus en plus tent\u00e9s de jouer leur carte personnelle, et donc d&rsquo;acc\u00e9l\u00e9rer un mouvement vers une certaine autonomie, donc un mouvement de d\u00e9construction. <\/p>\n<\/p>\n<p><p>Bien entendu, si l&rsquo;on \u00e9largit la vision de cette situation avec l&rsquo;assimilation au Syst\u00e8me du pouvoir du centre, on arrive au sch\u00e9ma d\u00e9sormais classique d&rsquo;une structure qui est devenu le constituant d&rsquo;un outil du Syst\u00e8me, donc le Syst\u00e8me lui-m\u00eame. Et la pouss\u00e9e centrifuge d\u00e9constructrice qui s&rsquo;exerce aujourd&rsquo;hui fait du ph\u00e9nom\u00e8ne de la d\u00e9construction qui porte toute la charge de la Grande Crise G\u00e9n\u00e9rale notamment avec son r\u00f4le dans l&rsquo;organisation ultime du Syst\u00e8me, un facteur brusquement vertueux et antiSyst\u00e8me en d\u00e9veloppant l&rsquo;acte de d\u00e9construction de la structure mise en place pour r\u00e9aliser la d\u00e9construction du monde, donc en faisant de la Grande Crise G\u00e9n\u00e9rale la Grande Crise d&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>(Le texte de Wayne Madsen a \u00e9t\u00e9 publi\u00e9 le  <a href=\"https:\/\/www.strategic-culture.org\/news\/2020\/02\/16\/constitutional-tensions-flare-between-trump-and-the-states\/\">16 f\u00e9vrier 2020<\/a> sur le site <em>Strategic-Culture.org<\/em>, sous le titre complet de &laquo; <em>Constitutional Tensions Flare Between Trump and the States<\/em> &raquo;.)<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Tensions Flare Between Trump and the States<\/h2>\n<\/p>\n<p><p>Not since the civil rights movement of the 1950s and 60s have tensions been so high between a U.S. administration and the states of the federal republic. During the civil rights era, it was the federal government that was playing the role of protector of the U.S. Constitution in pressuring segregationist states like Arkansas, Mississippi, and Alabama to comply with federal civil rights law. Today, the shoe is on the other foot. A racist and xenophobic U.S. administration has actually commenced imposing travel and other sanctions on states like New York and California, merely because they are upholding U.S. and international human rights law, particularly that dealing with asylum for foreign refugees.<\/p>\n<\/p>\n<p><p>A major rift has opened up between the Trump White House and the Governor of New York, Andrew Cuomo, over Trump&rsquo;s decision to prohibit residents of New York from participating in Trusted Traveler Programs, including Global Entry, Free and Secure Trade for Commercial Vehicles (FAST), NEXUS, and SENTRI, which speed Americans through immigration controls at airports and land borders with Canada and Mexico. At issue is New York&rsquo;s Green Light Law and more than a dozen other states&rsquo; policies that permit undocumented immigrants to obtain driver&rsquo;s licenses. Acting deputy secretary of Homeland Security Ken Cuccinelli, a racist and xenophobe Republican Party hack from Virginia, banned New York and other states from participation in Global Entry because the states barred U.S. immigration officials of accessing state motor vehicle databases to determine the identities of undocumented immigrants.<\/p>\n<\/p>\n<p><p>Banning New Yorkers from participation in Global Entry will have a drastic effect on New York truck drivers who regularly cross the U.S.-Canadian border. A leaked Department of Homeland Security memo stated that the Trump administration is intent on \u00ab\u00a0punishing\u00a0\u00bb states that refuse federal access to their driver&rsquo;s databases and offer \u00ab\u00a0sanctuary\u00a0\u00bb to undocumented immigrants fearful of arrest and detention by federal law enforcement authorities.<\/p>\n<\/p>\n<p><p>Cuomo offered Trump and compromise, stating that New York could offer federal agencies limited access to New York driver&rsquo;s records in the Department of Motor Vehicles database. That was insufficient for the increasingly authoritarian Trump. Trump tweeted a response to Cuomo&rsquo;s offer on February 13, just prior to a scheduled meeting between the New York governor and impeached president at the White House. The tweet stated: \u00ab\u00a0New York must stop all of its unnecessary lawsuits &#038; harrassment [sic], start cleaning itself up, and lowering taxes. Build relationships, but don&rsquo;t bring Fredo!\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Trump&rsquo;s reference to Fredo, an Italian Mafia character in \u00ab\u00a0The Godfather,\u00a0\u00bb is a bigoted anti-Italian nickname for Chris Cuomo, the governor&rsquo;s brother and an anchor on CNN. The Cuomos&rsquo; father was New York Democratic Governor Mario Cuomo, a major political force in the Democratic Party in the 1980s and 90s.<\/p>\n<\/p>\n<p><p>In an open display of extortion, Trump demanded that New York, through its Attorney General, Letitia James, drop all lawsuits against him in both his role as president and as a principal of the fraudulent Trump Foundation and Trump University. The extortion, which is how Governor Cuomo referred to it, is a clear attempt to run roughshod over a state&rsquo;s independent judicial and law enforcement authority as enshrined in the separation of powers clauses in the U.S. Constitution. The Trump-Cuomo meeting on February 13 yielded no agreement or compromise by Trump.<\/p>\n<\/p>\n<p><p>New York Attorney General James had a pointed response to Trump&rsquo;s extortion tweet. She tweeted back, \u00ab\u00a0When you stop violating the rights and liberties of all New Yorkers, we will stand down. Until then, we have a duty and responsibility to defend the Constitution and the rule of law. BTW [By the way], I file the lawsuits, not the Governor.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Trump&rsquo;s war with New York is not limited to that state. There have been federal threats made to California over everything from environmental protections to that state&rsquo;s sanctuary policies. The Republican Party was once fond of championing states&rsquo; rights. However, as the Trump administration adopts more fascistic policies, states&rsquo; rights has been replaced with the diminution of the authority of state, county, municipal, tribal, and territorial governments and its transfer to the central government.<\/p>\n<\/p>\n<p><p>Trump has been nothing but vicious with California. During Trump&rsquo;s 2020 State of the Union speech to Congress, he singled out California for \u00ab\u00a0costing taxpayers vast and unaffordable amounts of money\u00a0\u00bb and also criticized the state&rsquo;s sanctuary law protecting undocumented immigrants. While cutting massive amounts from the federal budget for firefighting and housing support for the homeless, Trump has lambasted Newsom and California for the state&rsquo;s handling of homelessness and wildfires. Trump treats California, New York, and the Commonwealth of Puerto Rico as foreign nations with whom his government is at war.<\/p>\n<\/p>\n<p><p>States that have been ostracized and alienated by Trump have set forth their own policies, even those affecting U.S. foreign relations. After Trump withdrew the U.S. from the Paris climate agreement, twenty-four states and Puerto Rico joined the U.S. Climate Action Alliance. The state governors vowed to commit to the Paris accord&rsquo;s original carbon emission reduction goals, regardless of Trump pulling out of the agreement while scoffing at climate change as a \u00ab\u00a0Chinese hoax.\u00a0\u00bb To the chagrin of Trump, the alliance includes three Republican governors who oppose Trump: Larry Hogan of Maryland, Charlie Baker of Massachusetts, and Phil Scott of Vermont.<\/p>\n<\/p>\n<p><p>Even municipalities have bolted from the anti-Palestinian and pro-Zionist policies of the Trump administration regarding Palestine. Despite the Trump administration severing all diplomatic links with Palestine, including expelling the Palestinian diplomatic mission in Washington and freezing all aid to the Palestinian Authority, U.S. municipalities have maintained \u00ab\u00a0sister cities\u00a0\u00bb relationships with Palestinian towns and cities. These include Joplin, Missouri; Burlington, Vermont; Sacramento, California; and Orlando, Florida with Bethlehem; Boulder, Colorado with Nablus; Muscatine, Iowa with Ramallah; Camden, New Jersey with Gaza City; and Olympia, Washington and Madison, Wisconsin with Rafah.<\/p>\n<\/p>\n<p><p>While Trump has imposed draconian trade tariffs on China, Canada, Mexico, the European Union, and other nations, U.S. states have opened their own trade offices and missions in capitals around the world, thus bypassing the increasingly feeble U.S. Commerce Secretary Wilbur Ross and Trump&rsquo;s senior trade adviser, Peter Navarro. Twenty-seven U.S. states have trade missions in China, all of which act relatively independent of the U.S. Departments of Commerce and State. The United Kingdom may have exited from the European Union, but that has not deterred U.S. states from opening trade missions to the EU in Brussels. These include Alaska, Ohio, Oregon, and Tennessee. North Dakota maintains its only trade office abroad in Ukraine, wile Maryland&rsquo;s only trade office is in Nigeria. Florida, Iowa, Pennsylvania, Washington state, Maryland, Hawaii, and Missouri have trade missions in both China and Taiwan. If Trump continues to attack individual states, particularly those with Democratic governors, trade missions can easily be turned into de facto diplomatic offices that can challenge in various world capitals particular destructive Trump policies emanating from Washington.<\/p>\n<\/p>\n<p><p>Pushback against Trump&rsquo;s renewed embargo on Cuba has seen pushback from some states, which once sent trade delegations to Cuba and participated in the Havana International Trade Fair. Bolting from Trump&rsquo;s embargo, Virginia Agriculture Secretary Bettina Ring thumbed her nose at the anti-Cuban interests in the White House and led a state trade delegation to the 2019 fair in Cuba. Other states may follow suit in advancing sister cities and other relationships with Palestine and Cuba, regardless of the bluster and chest-beating from the Trump White House.<\/p>\n<\/p>\n<p><p>The last \u00ab\u00a0war between the states\u00a0\u00bb was between the federal government in Washington, DC and the states remaining in the United States on one side and the pro-slavery Confederate states in the South. If Trump continues his war against certain states that policy may develop into a war between the most populous states and Trump&rsquo;s Washington, with a lot of state sympathizers within the federal government and military. That is a recipe for disaster for Mr. Trump and his loyalists.<\/p>\n<\/p>\n<p><h4>Wayne Madsen<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9construction rampante des USA Wayne Madsen fait un travail des plus int\u00e9ressants, en pr\u00e9sentant, en comptabilisant et en commentant les conflits existant actuellement entre Trump (Washingtons D.C. et sa bureaucratie, centre f\u00e9d\u00e9ral des USA) et diff\u00e9rents &Eacute;tats de l&rsquo;Union, essentiellement ceux qui ont des gouverneurs d\u00e9mocrates mais aussi quelques-uns avec des gouverneurs r\u00e9publicains (notamment&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2942,5017,4099,2631,3907,10119,5734,4889,3330,4419,4811,3256,2949,4400,3257],"class_list":["post-79112","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-californie","tag-centre","tag-centrifuge","tag-de","tag-destructuration","tag-dissolution","tag-dynamique","tag-etats","tag-immigration","tag-lunion","tag-madsen","tag-new","tag-secession","tag-wayne","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79112"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79112\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}