{"id":79133,"date":"2020-03-03T08:49:09","date_gmt":"2020-03-03T08:49:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/03\/03\/quatrieme-temps-crisique\/"},"modified":"2020-03-03T08:49:09","modified_gmt":"2020-03-03T08:49:09","slug":"quatrieme-temps-crisique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/03\/03\/quatrieme-temps-crisique\/","title":{"rendered":"Quatri\u00e8me Temps Crisique"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Quatri\u00e8me Temps Crisique<\/h2>\n<\/p>\n<p><p>3 mars 2020 &ndash; Je voudrais faire part \u00e0 celui qui me lit d&rsquo;un sentiment g\u00e9n\u00e9ral qui me semble devoir beaucoup \u00e0 ce ph\u00e9nom\u00e8ne, \u00e0 la fois myst\u00e9rieux et insaisissable mais o&ugrave; l&rsquo;on devine une puissance cach\u00e9e et formidable, qui se nomme \u00ab\u00a0intuition\u00a0\u00bb. C&rsquo;est dire s&rsquo;il ne faut pas attendre de d\u00e9monstration, mais plut\u00f4t une escapade aventureuse et pleine d&rsquo;exhortations. Pour autant, je suis assur\u00e9, je ne sais comment ni par quelle machination, que l&rsquo;escapade n&rsquo;est pas inutile.<\/p>\n<\/p>\n<p><p>J&rsquo;ai pris mon temps avant de mesurer l&rsquo;importance ph\u00e9nom\u00e9nale, avec une cascade d&rsquo;effets ext\u00e9rieurs au domaine, &ndash; j&rsquo;en ai d\u00e9j\u00e0 beaucoup parl\u00e9, &ndash; de cette  <a href=\"https:\/\/www.dedefensa.org\/article\/covid-19-miroir-de-la-crise\">crise-Covid-19<\/a>. Je mesure \u00e9galement l&rsquo;inattention que j&rsquo;ai montr\u00e9e sur l&rsquo;instant \u00e0 la force des symboles qui font correspondre cette crise \u00e0 un changement de d\u00e9cade dont plus d&rsquo;une plume ont signal\u00e9 la r\u00e9f\u00e9rence centenaire et si fortement significative : les <em>Roaring Twenties <\/em>menant \u00e0 la Grande D\u00e9pression, et nous, un  <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-limpeachmentdu-systeme\">si\u00e8cle plus tard exactement<\/a>, avec ce Covid-19, <a href=\"https:\/\/www.dedefensa.org\/article\/un-assassinat-metahistorique\">l&rsquo;assassinat m\u00e9tahistorique<\/a> de Soleimani d\u00e9bouchant dans la m\u00eame zone de tension sur une quasi-guerre Russie-Turquie mesur\u00e9e, elle, \u00e0 la folie m\u00e9galomaniaque d&rsquo;un Erdogan.<\/p>\n<\/p>\n<p><p>Pour compl\u00e9ter  <a href=\"https:\/\/www.dedefensa.org\/article\/tc-87-tourbillon-de-volcans-crisiques\">le tableau<\/a>, on cite l&rsquo;\u00e9ruption sans fin de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb ; je veux dire, pour rassembler les principaux \u00e9v\u00e9nements crisiques, tout cela qui me fait croire que nous avons bascul\u00e9, au changement de d\u00e9cennie, dans un nouveau temps crisique. Il est vrai que, dans les esprits et dans les psychologies, dans une p\u00e9riode crisique si abyssale o&ugrave; la raison est  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-crisis-la-crise-de-la-raison-humaine-1\">si suspecte<\/a> de tant de d\u00e9vergondages de subversion jusqu&rsquo;\u00e0 l&rsquo;inversion de ce qu&rsquo;elle pr\u00e9tend \u00eatre, le symbolisme est d&rsquo;une capitale importance. Il s&rsquo;impose alors de faire un classement o&ugrave; les \u00e9v\u00e9nements terrestres ne seront pas les ordonnateurs, mais le simples cons\u00e9quences en m\u00eame temps que les marqueurs de notre avanc\u00e9e g\u00e9n\u00e9rales, par \u00e9tapes et bonds successifs au c&oelig;ur des t\u00e9n\u00e8bres de ces Derniers Temps.<\/p>\n<\/p>\n<p><p>Il y a eu \u00e0 partir de notre Jour de Gr\u00e2ce, notre 11-septembre, un premier Temps Crisique qui est la premi\u00e8re \u00e9tape dans cet espace de temps des Derniers Temps qui englobe ce que je d\u00e9signe avec une fougue et un optimisme roboratifs la Grande Crise d&rsquo;Effondrement du Syst\u00e8me (GCES). Ce premier Temps Crisique fut celui de l&rsquo;effarement secret et indicible devant les consid\u00e9rables \u00e9v\u00e8nements qui se produisirent, et le peu de sens qu&rsquo;on pouvait leur trouver malgr\u00e9 la joyeuse et roborative  <a href=\"https:\/\/www.dedefensa.org\/article\/aux-sources-du-virtualisme\">ivresse<\/a> <a href=\"https:\/\/www.dedefensa.org\/article\/valsez-mensonges\">am\u00e9ricaniste<\/a>, et pourtant la plupart d&rsquo;entre nous toujours soumis \u00e0 la fascination de cet artefact qui rythme la modernit\u00e9, qu&rsquo;est l&rsquo;Am\u00e9rique : &laquo; <em>Nous sommes un empire maintenant et quand nous agissons nous cr\u00e9ons notre propre r\u00e9alit\u00e9&#8230;<\/em> &raquo;.<\/p>\n<p>La deuxi\u00e8me \u00e9tape, deuxi\u00e8me Temps Crisique, commence avec la fracture de l&rsquo;automne 2008, le spasme de la folie du monde financier cherchant \u00e0 se d\u00e9fausser de ses exc\u00e8s en d\u00e9clenchant un tourbillon crisique qui va accumuler le chaos dans son domaine et lancer de grandes entreprises d\u00e9mocratiques pour justifier nos pr\u00e9tentions mondiales et cosmiques, \u00e0 peu pr\u00e8s comme Mao lan\u00e7ait sa Campagne des Cent-Fleurs (le \u00ab\u00a0printemps arabe\u00a0\u00bb, ou les Cent-Fleurs du Syst\u00e8me). Il s&rsquo;agissait de renouveler le supr\u00e9macisme anglo-saxon (plut\u00f4t que \u00ab\u00a0blanc\u00a0\u00bb) une fois l&rsquo;hypercapitalisme superbement purg\u00e9 et ressourc\u00e9 par cette \u00e9norme crise, et par cons\u00e9quent plus \u00ab\u00a0hyper\u00a0\u00bb que jamais.<\/p>\n<p>La troisi\u00e8me \u00e9tape, je la situe en 2014-2015, en liant la crise ukrainienne et la crise du syst\u00e8me de l&rsquo;am\u00e9ricanisme (Trump \u00e0 partir de 2015, engendrant la haine antiTrump, USA-2016, <em>Russiagate<\/em>, etc.). Son caract\u00e8re principal est une explosion absolument chaotique de la communication, un amoncellement affolant de <em>narrative <\/em>de plus en plus lourdes \u00e0 porter et supporter avec leurs exigence de  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>, une perte totale du sens de la r\u00e9alit\u00e9, voire plus encore, du sens de la n\u00e9cessit\u00e9 de la r\u00e9alit\u00e9, la transformation de la politique en une sorte de gomme mollassonne et qu&rsquo;on peut m\u00e2cher \u00e0 souhait sans en rien faire sortir, le refuge dans le simulacre du simulacre du simulacre&#8230;<\/p>\n<\/p>\n<p><p>Ainsi en vient-on \u00e0 la quatri\u00e8me p\u00e9riode, notre quatri\u00e8me Temps Crisique,  du tournant pr\u00e9cis des deux d\u00e9cennies et notre entr\u00e9e dans nos <em>Roaring Twenties <\/em>du XXI\u00e8me si\u00e8cle. Avec le recul de quelques semaines, cette nouvelle d\u00e9cennie appara&icirc;t comme une rupture formidable et absolument naturelle, comme une tension trop forte qui se rompt avec quelle brutalit\u00e9 ! Et s&rsquo;ouvrent effectivement nos \u00ab\u00a0Vingti\u00e8mes rugissantes\u00a0\u00bb, comme les marins des l\u00e9gendes d&rsquo;antan baptis\u00e8rent les mers furieuses entre les  \u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Quaranti%C3%A8mes_rugissants\">Quaranti\u00e8mes rugissants<\/a>\u00a0\u00bb  et les \u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Cinquanti\u00e8mes_hurlants\">Cinquanti\u00e8mes hurlants<\/a>\u00a0\u00bb des latitudes correspondantes vers le Sud extr\u00eame des \u00e9tendues glac\u00e9es o&ugrave; jamais le vent ne s&rsquo;arr\u00eate de souffler et la mer de d\u00e9ferler, o&ugrave; les marins disent qu&rsquo;au-del\u00e0 vers l&rsquo;au-del\u00e0 du Sud Dieu n&rsquo;est plus.<\/p>\n<\/p>\n<p><p>J&rsquo;ai tent\u00e9 de dire tous les \u00e9v\u00e9nements formidables caract\u00e9risant ce passage \u00e0 2020 mais, apr\u00e8s tout, on pourrait me dire qu&rsquo;il ne s&rsquo;agit que  de quelques crises monstrueuses de plus, et l\u00e0 rien de vraiment nouveau, je veux dire ontologiquement, dans un temps qui est crisique par d\u00e9finition. Pourtant non, un \u00e9v\u00e9nement colossal sans nul doute, ontologique lui, bien que dans le domaine de la perception, &ndash; c&rsquo;est la fin du r\u00eave de la globalisation, &ndash; la fin de la globalisation comme r\u00eave de notre avenir. <\/p>\n<\/p>\n<p><p>Ce poison s&rsquo;est instill\u00e9 partout et partout vous le sentez progresser, ce doute terrible face \u00e0 cette globalisation, laquelle est l&rsquo;\u00e9vidente coupable de la crise-Covid-19 qui nous d\u00e9vaste psychologiquement en faisant entrevoir les m\u00e9canismes de l&rsquo;effondrement, d&rsquo;une \u00e9conomie-monde qui se d\u00e9fait comme un Meccano mal viss\u00e9, qui bascule comme une port\u00e9e de dominos en rang d&rsquo;oignons, inarr\u00eatable, in\u00e9luctable. Il se dit que le virus envahit notre monde-globalis\u00e9 par ce qu&rsquo;il y a de plus globalisant, de plus post-postmoderne, la tr\u00e8s-pollueuse et tr\u00e8s-luxueuse aviation de transport civil qui relie les capitales, les continents et les r\u00e9gions les plus lointaines, dans le vrombissement \u00e9l\u00e9gant des Airbus faisant la courte \u00e9chelle au virus d&rsquo;un a\u00e9roport l&rsquo;autre (les Boeing, c&rsquo;est moins s&ucirc;r, <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-boeingversususa\">on sait pourquoi<\/a>, et Covid-19 s&rsquo;en m\u00e9fie comme de la peste si j&rsquo;ose dire).<\/p>\n<\/p>\n<p><p>Il me semblerait m\u00eame que cela (le r\u00eave fracass\u00e9 de la globalisation) explique la folie qui a transform\u00e9 Washington D.C. en \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, tandis qu&rsquo;appara&icirc;t le second \u00e9v\u00e9nement qui marque cette rupture rugissante&#8230; L&rsquo;outil fantastique de puissance, qui semblait au service de la globalisation, qui chaque jour la trahit un peu plus ! Le syst\u00e8me de la communication triomphant signe son empire sur le monde en apparaissant comme un <em><a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-leffet-janus\">Janus<\/a> <\/em>qui poignarde la globalisation dans le dos, r\u00e9pandant partout les alertes et les fantasmes de Covid-19, rempla\u00e7ant le chaos de 2014-2015 par l&rsquo;attaque de la contagion, cette Grande Peur des Ancien Temps retourn\u00e9e contre la globalisation de l&rsquo;hypermodernit\u00e9 elle-m\u00eame. Les talk-shows et le reste de  <a href=\"https:\/\/www.mintpressnews.com\/the-media-hype-over-coronavirus-spreading-faster-virus-itself\/265440\/\">la caravane m\u00e9diatique<\/a>, fleuron du syst\u00e8me de la communication plong\u00e9 dans la dissection sans fin de la pand\u00e9mie qui nous assaille et de la panique qu&rsquo;il ne faut pas \u00e9prouver, a d\u00e9velopp\u00e9 une pand\u00e9mie pire que Covid-19, &ndash; et ainsi a-t-il mis, ce fleuron de la communication, en \u00e9tat d&rsquo;accusation impitoyable la globalisation elle-m\u00eame&#8230; La globalisation g\u00e9missant de douleur et rugissant de fureur !<\/p>\n<\/p>\n<p><p>On sent bien alors, sans y r\u00e9fl\u00e9chir longtemps, mais prenant plut\u00f4t le ph\u00e9nom\u00e8ne avec son intuition, comme une chose allant de soi, on sent bien qu&rsquo;on se trouve emport\u00e9 dans une m\u00e9canique, un encha&icirc;nement qui porte en lui la mort du Syst\u00e8me&#8230; Je dis bien \u00ab\u00a0encha&icirc;nement\u00a0\u00bb comme avec une cha&icirc;ne : la folie de la surpuissance de ce que nous nommons ici \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0, qui nous a emport\u00e9s jusque dans ces affreuses convulsions de sa folie destructrice, nous conduisant enfin, comme l&rsquo;on se d\u00e9barrasse d&rsquo;un simulacre qui pourrait \u00eatre un masque, \u00e0 l&#8217;emprisonnement qu&rsquo;est l&rsquo;encha&icirc;nement de l&rsquo;effondrement et de la chute, c&rsquo;est-\u00e0-dire \u00e0 l&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>Pour ce qui est de ces \u00ab\u00a0Quaranti\u00e8me rugissants\u00a0\u00bb et de ces \u00ab\u00a0Cinquanti\u00e8mes Hurlants\u00a0\u00bb que j&rsquo;ai \u00e9voqu\u00e9s \u00e0 propos de nos \u00ab\u00a0Vingti\u00e8mes\u00a0\u00bb, un vieux dicton des vieux marins des Temps Anciens disait de ces terribles latitudes d&rsquo;un Sud ressemblant \u00e0 l&rsquo;Enfer glac\u00e9 : &laquo; <em>Sous les 40 degr\u00e9s, il n&rsquo;y a plus de loi, mais sous les 50 degr\u00e9s, il n&rsquo;y a plus de Dieu.<\/em> &raquo; C&rsquo;est comme si nous \u00e9tions arriv\u00e9s au terme de nos temp\u00eates qui balaient le cap ultime de la modernit\u00e9 battu par les vents, ayant bris\u00e9 les lois et chass\u00e9 Dieu, et que nous nous retrouvions plong\u00e9s dans la temp\u00eate ultime mais aussi supr\u00eame, celle qui nous place devant nous-m\u00eames et devant l&rsquo;alchimie saccag\u00e9e de notre simulacre d&rsquo; \u00ab\u00a0&oelig;uvre au noir\u00a0\u00bb si diaboliquement cochonn\u00e9e, pour balayer tout cela et toutes nos illusions, et enfin nous balayer nous-m\u00eames selon ce que nous avons fait pitoyablement de nous-m\u00eames.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatri\u00e8me Temps Crisique 3 mars 2020 &ndash; Je voudrais faire part \u00e0 celui qui me lit d&rsquo;un sentiment g\u00e9n\u00e9ral qui me semble devoir beaucoup \u00e0 ce ph\u00e9nom\u00e8ne, \u00e0 la fois myst\u00e9rieux et insaisissable mais o&ugrave; l&rsquo;on devine une puissance cach\u00e9e et formidable, qui se nomme \u00ab\u00a0intuition\u00a0\u00bb. C&rsquo;est dire s&rsquo;il ne faut pas attendre de d\u00e9monstration,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[11835,3015,12020,19677,5648,2632,10274,6320,19719,12695,19720,12478],"class_list":["post-79133","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-11835","tag-communication","tag-contagion","tag-coronavirus","tag-covid-19","tag-globalisation","tag-janus","tag-pandemie","tag-quarantiemes","tag-roaring","tag-rugissantes","tag-twenties"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79133"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79133\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}