{"id":79147,"date":"2020-03-12T17:00:08","date_gmt":"2020-03-12T17:00:08","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/03\/12\/haine-russo-saoudienne-fracking-the-fracking\/"},"modified":"2020-03-12T17:00:08","modified_gmt":"2020-03-12T17:00:08","slug":"haine-russo-saoudienne-fracking-the-fracking","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/03\/12\/haine-russo-saoudienne-fracking-the-fracking\/","title":{"rendered":"Haine russo-saoudienne :\u00a0<em>Fracking the Fracking<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Haine russo-saoudienne : <em>Fracking the Fracking<\/em><\/h2>\n<\/p>\n<p><p>Cette nouvelle, \u00e0 partir d&rsquo;extraits d&rsquo;une \u00e9lision de RT.com, permet d&rsquo;avoir une bonne id\u00e9e du climat actuel d&rsquo;effondrement g\u00e9n\u00e9ral, de la fa\u00e7on dont les masques tombent et volent dans tous les sens, de la rapidit\u00e9 avec laquelle les simulacres se vident de toute leur fausse substance&#8230; Ici, il s&rsquo;agit du Professeur  <a href=\"https:\/\/en.wikipedia.org\/wiki\/Richard_D._Wolff\">Richard D. Wolff<\/a>, fameux professeur dans toutes les grandes universit\u00e9s US, auteur, \u00e9conomiste, de tendance marxiste, voire <em>Rethinking Marxism<\/em>, fameux \u00e9galement pour son \u00e9mission t\u00e9l\u00e9vis\u00e9e hebdomadaire <em>Economic Update.<\/em><\/p>\n<\/p>\n<p><p>Wolff donne une version qui est de plus en plus favoris\u00e9e sur la crise p\u00e9troli\u00e8re, qui appr\u00e9hende l&rsquo;explication d&rsquo;une complicit\u00e9 dissimul\u00e9e entre les Russes et les Saoudiens, dans :le but de la destruction de l&rsquo;industrie du p\u00e9trole de schiste US, &ndash; l&rsquo;industrie dite du <em>Fracking<\/em>, pour son avidit\u00e9 \u00e0 fracturer les sous-sols \u00e0 la chasse au schiste. &laquo; <em>Ils<\/em>[les Russes et les Saoudiens] <em>ont ha\u00ef cette industrie d\u00e8s le premier jour<\/em> &raquo;<\/p>\n<\/p>\n<p><p>La description de la situation par Wolff est catastrophique, sinon apocalyptique, mais certes sans grande originalit\u00e9 car qui ne flirte pas avec cette perspective aujourd&rsquo;hui ? La crise Covit-19 et la crise de la \u00ab\u00a0guerre du p\u00e9trole\u00a0\u00bb &laquo; <em>sont comme un droite-gauche <\/em>[ass\u00e9n\u00e9 par un boxeur] &raquo;, directement sur le pif de Wall Street, avec suffisamment de force pour dissiper tous les mirages des  <em>narrative <\/em> et faire comprendre que la toute-puissance proclam\u00e9e \u00ab\u00a0premi\u00e8re du monde\u00a0\u00bb de l&rsquo;\u00e9conomie US n&rsquo;est rien de moins qu&rsquo;un simulacre entretenu par les politiciens corrompus et grassement subventionn\u00e9s pour cette t\u00e2che, &ndash; simulacre qui n&rsquo;a pas la moindre base s\u00e9rieuse, la moindre assise, la moindre fondation.<\/p>\n<\/p>\n<blockquote>\n<p><p>Le spectacle est donc horrible, de l&rsquo;effondrement d&rsquo;une civilisation qui a accept\u00e9 de devenir la serveuse ob\u00e9issante du Syst\u00e8me, &ndash; horrible mais \u00e9galement sublime c&rsquo;est selon. Ainsi en est-il de la col\u00e8re des dieux, nous sugg\u00e8re le professeur Wolff, qui nous conduit comme tout expert qui se respecte aujourd&rsquo;hui sur la <em>terra incognita <\/em>de l&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&#8230; Sur RT.com le <a href=\"https:\/\/www.rt.com\/business\/482947-russia-saudi-revenge-shale\/\">12 mars 2020<\/a> : &laquo; [L&rsquo;\u00e9mission] <em>&lsquo;Boom Bust&rsquo; re\u00e7oit le professeur Richard Wolff, de Economic Update, pour discuter de la crise p\u00e9troli\u00e8re en cours. Wolff explique que les &Eacute;tats-Unis, qui voulaient \u00ab\u00a0l&rsquo;ind\u00e9pendance \u00e9nerg\u00e9tique\u00a0\u00bb, ont d\u00e9cid\u00e9 il y a 10-20 ans de se lancer dans l&rsquo;industrie de fracturation simplement parce que cela \u00e9tait jug\u00e9 comme \u00e9tant rentable.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Certes, l&rsquo;industrie de la fracturation est tr\u00e8s co&ucirc;teuse&#8230; mais tout \u00e9tait bas\u00e9 sur l&rsquo;id\u00e9e que le prix du p\u00e9trole resterait tr\u00e8s \u00e9lev\u00e9\u00a0\u00bb, explique Wolff. \u00ab\u00a0Les Saoudiens et les Russes ont \u00e9t\u00e9 touch\u00e9s par l&rsquo;\u00e9mergence de l&rsquo;industrie am\u00e9ricaine de la fracturation ; ils ont ha\u00ef cette industrie d\u00e8s le premier jour parce que c&rsquo;\u00e9tait un concurrent<\/em>[jug\u00e9 d\u00e9loyal]<em>.\u00a0\u00bb<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0L&rsquo;id\u00e9e qu&rsquo;ils se battent entre eux est une illusion\u00a0\u00bb, pr\u00e9cise Wolff. \u00ab\u00a0En fait,  les Russes et les Saoudiens se battent contre les &Eacute;tats-Unis parce qu&rsquo;en faisant baisser le prix du p\u00e9trole, toutes ces compagnies p\u00e9troli\u00e8res am\u00e9ricaines de fracturation vont faire faillite. Elles sont finies\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Il ajoute que les compagnies p\u00e9troli\u00e8res de la fracturation \u00ab\u00a0ne peuvent pas rembourser leurs dettes et cela plonge le march\u00e9 du cr\u00e9dit et les banques dans une nouvelle crise que nous commen\u00e7ons \u00e0 peine \u00e0 comprendre et qui en fait menace l&rsquo;ensemble du syst\u00e8me financier\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Vous mettez le coronavirus avec le p\u00e9trole et vous avez un droite-gauche directement encha&icirc;n\u00e9 qui fait r\u00e9aliser \u00e0 la plupart des gens de Wall Street que la description \u00e9logieuse de l&rsquo;\u00e9conomie am\u00e9ricaine comme la plus grande du monde \u00e9tait une illusion des politiciens et n&rsquo;a aucun fondement&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 12 mars 2020 \u00e0 17H02<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haine russo-saoudienne : Fracking the Fracking Cette nouvelle, \u00e0 partir d&rsquo;extraits d&rsquo;une \u00e9lision de RT.com, permet d&rsquo;avoir une bonne id\u00e9e du climat actuel d&rsquo;effondrement g\u00e9n\u00e9ral, de la fa\u00e7on dont les masques tombent et volent dans tous les sens, de la rapidit\u00e9 avec laquelle les simulacres se vident de toute leur fausse substance&#8230; Ici, il s&rsquo;agit&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[3259,2631,2651,12745,2645,5386,2622,5650,3600,10008,2730,3372,3132,13519],"class_list":["post-79147","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-arabie","tag-de","tag-du","tag-fracturation","tag-guerre","tag-industrie","tag-la","tag-opep","tag-petrole","tag-richard","tag-russie","tag-street","tag-wall","tag-wolff"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79147"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79147\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}