{"id":79172,"date":"2020-03-25T09:39:51","date_gmt":"2020-03-25T09:39:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/03\/25\/covid-19-et-linversion-bresilienne\/"},"modified":"2020-03-25T09:39:51","modified_gmt":"2020-03-25T09:39:51","slug":"covid-19-et-linversion-bresilienne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/03\/25\/covid-19-et-linversion-bresilienne\/","title":{"rendered":"Covid-19 et l&rsquo;inversion br\u00e9silienne"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Covid-19 et l&rsquo;inversion br\u00e9silienne<\/h2>\n<\/p>\n<p><p>Au Br\u00e9sil, la situation des grandes tendances des pouvoirs, &ndash; entre l\u00e9gitimit\u00e9 et ill\u00e9gitimit\u00e9, entre l\u00e9galit\u00e9 et ill\u00e9galit\u00e9, &ndash; sont dans une position d&rsquo;inversion caract\u00e9ristique de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me. Bien s&ucirc;r, la chose est r\u00e9v\u00e9l\u00e9e par la pand\u00e9mie Codiv-19, et porte non sur la pand\u00e9mie elle-m\u00eame mais sur les r\u00e9actions devant elle. D&rsquo;un c\u00f4t\u00e9, le pr\u00e9sident Bolsanaro qui nie la gravit\u00e9 de la pand\u00e9mie sinon la pand\u00e9mie elle-m\u00eame, et \u00e9carte toute mesure importante contre elle ; de l&rsquo;autre les gangs r\u00e9gnant dans les <em>favelas <\/em>des grandes villes, qui instituent le couvre-feu pour prot\u00e9ger les populations.<\/p>\n<\/p>\n<p><p>&bull; Bolsanaro, donc, estime que le Covid-19, \u00ab\u00a0petite grippe\u00a0\u00bb sans importance, <a href=\"https:\/\/sputniknews.com\/viral\/202003231078686588-bolsonaro-is-insane-netizens-lambast-brazilian-president-for-calling-coronavirus-a-media-trick\/\">est repr\u00e9sent\u00e9<\/a> en \u00e9v\u00e9nement exceptionnel par une sorte de \u00ab\u00a0complot des m\u00e9dias\u00a0\u00bb. Il \u00e9carte toute mesure importante comme le confinement qui, selon lui, constitueraient \u00ab\u00a0le suicide \u00e9conomique du Br\u00e9sil\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&laquo; <em>Les m\u00e9dias sociaux ont fustig\u00e9 le pr\u00e9sident br\u00e9silien Jair Bolsonaro pour son r\u00e9cent commentaire sur le coronavirus. Ce dernier, \u00e2g\u00e9 de 65 ans, qui avait auparavant qualifi\u00e9 la maladie de \u00ab\u00a0petite grippe\u00a0\u00bb, a accus\u00e9 les politiciens et les m\u00e9dias d&rsquo;exag\u00e9rer les dangers de COVID-19, sugg\u00e9rant plut\u00f4t qu&rsquo;il s&rsquo;agit d&rsquo;un \u00ab\u00a0coup mont\u00e9 m\u00e9diatique\u00a0\u00bb. Le nombre de cas de coronavirus au Br\u00e9sil s&rsquo;\u00e9l\u00e8ve maintenant \u00e0 1 629 avec 25 d\u00e9c\u00e8s.<\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0Le peuple verra bient\u00f4t qu&rsquo;il a \u00e9t\u00e9 dup\u00e9 par ces gouverneurs et par une grande partie des m\u00e9dias en ce qui concerne les coronavirus\u00a0\u00bb, a d\u00e9clar\u00e9 Bolsonaro dans  <a href=\"https:\/\/recordtv.r7.com\/domingo-espetacular\/videos\/presidente-jair-bolsonaro-fala-sobre-o-coronavirus-em-entrevista-ao-domingo-espetacular-22032020\">une interview<\/a> \u00e0 la cha&icirc;ne de t\u00e9l\u00e9vision locale<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&bull; <a href=\"https:\/\/sputniknews.com\/viral\/202003241078698336-brazilian-gangs-impose-curfew-in-rio-amid-covid-19-pandemic---report\/\">Par contre<\/a>, les gangs br\u00e9siliens (drogue, armes, prostitution, etc.) qui r\u00e8gnent sur les <em>favelas <\/em>(immenses bidonvilles des grandes villes, dont Rio particuli\u00e8rement)  <a href=\"https:\/\/twitter.com\/AndrewCesare\/status\/1242174265547468803?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1242174265547468803&#038;ref_url=https%3A%2F%2Fsputniknews.com%2Fviral%2F202003241078698336-brazilian-gangs-impose-curfew-in-rio-amid-covid-19-pandemic---report%2F\">demandent<\/a> aux habitants de rester chez eux \u00e0 partir de 20H00 jusqu&rsquo;\u00e0 08H00 pour participer massivement \u00e0 un effort de r\u00e9sistance \u00e0 Covid-19. L&rsquo;explication est dite : \u00ab\u00a0nous faisons ce que le gouvernement ne fait pas, vous prot\u00e9ger\u00a0\u00bb&#8230; <\/p>\n<\/p>\n<p><p>&laquo; <em>Les gangs criminels de plusieurs favelas de Rio-de-Janeiro, dont Rio das Pedras, Muzema et Tijuquinha, ont envoy\u00e9 des messages aux habitants pour leur demander de rester \u00e0 l&rsquo;int\u00e9rieur apr\u00e8s 20 heures afin de freiner la propagation de COVID-19, selon le quotidien  <a href=\"https:\/\/g1.globo.com\/rj\/rio-de-janeiro\/noticia\/2020\/03\/23\/coronavirus-traficantes-e-milicianos-impoem-toque-de-recolher-em-comunidades-do-rio.ghtml\">El Globo<\/a>. Leurs messages affirment que les gangs veulent prot\u00e9ger la population et qu&rsquo;ils font ce que le gouvernement aurait d&ucirc; faire et qu&rsquo;il ne fait pas.<\/em><\/p>\n<p>&raquo; <em>Au Br\u00e9sil, les favelas sont les quartiers les plus pauvres de la ville. Selon le Buenos Aires Times, les probl\u00e8mes d&rsquo;approvisionnement en eau et de contr\u00f4le sanitaire rendent les habitants de ces zones particuli\u00e8rement vuln\u00e9rables face \u00e0 la pand\u00e9mie de coronavirus. <\/em><\/p>\n<p>&raquo; <em>\u00ab\u00a0L&rsquo;ironie est que la maladie a \u00e9t\u00e9 amen\u00e9e au Br\u00e9sil par avion, par les riches, mais c&rsquo;est parmi les pauvres qu&rsquo;elle va exploser\u00a0\u00bb, a d\u00e9clar\u00e9 Paulo Buss, directeur du centre des relations internationales de Fiocruz, un centre de recherche de r\u00e9f\u00e9rence en mati\u00e8re de sant\u00e9 publique, cit\u00e9 par le Buenos Aires Times<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Quelles que soient la complexit\u00e9 des positions, les grandes lignes de cette situation mesurent la compl\u00e8te inversion caract\u00e9risant notre Grande Crise G\u00e9n\u00e9rale, jusqu&rsquo;au transfert paradoxal des l\u00e9gitimit\u00e9s vers l&rsquo;ill\u00e9galit\u00e9 institu\u00e9e en tant que pouvoir de fait. Il est vrai que la l\u00e9galit\u00e9 th\u00e9orique au Br\u00e9sil (Bolsanaro), sei elle ne pr\u00e9sente pas les aspects de faiblesse par le politiquement-correct des dirigeants \u00ab\u00a0d\u00e9mocratiques\u00a0\u00bb dans la portion europ\u00e9enne du bloc-BAO, est par contre compl\u00e8tement align\u00e9e sur la non-essence de la l\u00e9gitimit\u00e9 que supposent les positions hyst\u00e9riques du n\u00e9olib\u00e9ralisme darwinien et de la corruption totale, encore plus psychologique que v\u00e9nale, qu&rsquo;il impose.<\/p>\n<\/p>\n<p><p>&#8230; Pour Bolsonaro, disons plut\u00f4t du c\u00f4t\u00e9 de chez Trump mais en beaucoup plus affich\u00e9 et primitif.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 25 mars 2020 \u00e0 09H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Covid-19 et l&rsquo;inversion br\u00e9silienne Au Br\u00e9sil, la situation des grandes tendances des pouvoirs, &ndash; entre l\u00e9gitimit\u00e9 et ill\u00e9gitimit\u00e9, entre l\u00e9galit\u00e9 et ill\u00e9galit\u00e9, &ndash; sont dans une position d&rsquo;inversion caract\u00e9ristique de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me. Bien s&ucirc;r, la chose est r\u00e9v\u00e9l\u00e9e par la pand\u00e9mie Codiv-19, et porte non sur la pand\u00e9mie elle-m\u00eame mais sur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[18781,19762,2631,19763,10629,8741,8740],"class_list":["post-79172","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-bolsonaro","tag-couvre-feu","tag-de","tag-favelas","tag-gangs","tag-janeiro","tag-rio"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79172"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79172\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}