{"id":79219,"date":"2020-04-15T14:17:04","date_gmt":"2020-04-15T14:17:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/04\/15\/covid-19-virus-de-la-secession-usa\/"},"modified":"2020-04-15T14:17:04","modified_gmt":"2020-04-15T14:17:04","slug":"covid-19-virus-de-la-secession-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/04\/15\/covid-19-virus-de-la-secession-usa\/","title":{"rendered":"Covid-19, virus de la s\u00e9cession-USA"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Covid-19, virus de la s\u00e9cession-USA<\/h2>\n<\/p>\n<p><p>14 avril 2020 &ndash; On a d\u00e9j\u00e0 signal\u00e9 combien l&rsquo;actuelle crise-Covid19 ranimait dans l&rsquo;activisme d&rsquo;opportunit\u00e9 l&rsquo;option spectrale et toujours latente de la s\u00e9cession ou de la d\u00e9structuration aux USA, notamment avec deux textes, le  <a href=\"https:\/\/www.dedefensa.org\/article\/la-deconstruction-rampante-des-usa\">17 f\u00e9vrier 2020<\/a>, o&ugrave; \u00e9tait mise en \u00e9vidence (par Wayne Madsen) l&rsquo;opposition entre Trump et le gouverneur de l&rsquo;&Eacute;tat de New York Cuomo, et le  <a href=\"https:\/\/www.dedefensa.org\/article\/la-deconstruction-rampante-des-usa\">26 f\u00e9vrier 2020<\/a>  o&ugrave; \u00e9tait surtout mise en \u00e9vidence le d\u00e9sordre de la m\u00e9sentente entre diverses entit\u00e9s r\u00e9gionales, entre elles et des &Eacute;tats avec le centre washingtonien.<\/p>\n<\/p>\n<p><p>D\u00e9sormais appara&icirc;t un point de fixation de cette querelle tendant \u00e0 \u00ab\u00a0op\u00e9rationnaliser\u00a0\u00bb de fa\u00e7on r\u00e9aliste, sinon pressante, ce ph\u00e9nom\u00e8ne. Il s&rsquo;agit d&rsquo;un \u00e9v\u00e9nement bien pr\u00e9cis de la crise-Covid19, la d\u00e9cision de ralentir ou de cesser le confinement pour la reprise de l&rsquo;activit\u00e9 \u00e9conomique, c&rsquo;est-\u00e0-dire le d\u00e9saccord entre Trump qui veux ordonner la coordination de tous les &Eacute;tats pour cette d\u00e9cision, et des &Eacute;tats voisins tendant \u00e0 se regrouper et \u00e0 prendre en commun cette d\u00e9cision selon leurs situations sp\u00e9cifiques sans tenir compte de la volont\u00e9 de Washington D.C. On a m\u00eame trouv\u00e9 des noms pour caract\u00e9riser deux grands blocs en train de se former, hors de la tutelle de Washington, et bient\u00f4t, \u00e9ventuellement selon certaines circonstances pr\u00e9cises et pressantes, et d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale selon la querelle opposant les d\u00e9mocrates en Trump :<\/p>\n<p>&bull; \u00ab\u00a0<em>Cascadia<\/em>\u00ab\u00a0, regroupant des &Eacute;tats de la c\u00f4te Ouest (Californie, Oregon, &Eacute;tat de Washington), tous trois avec des gouverneurs d\u00e9mocrates ;<\/p>\n<p>&bull; le \u00ab\u00a0<em>territoire d&rsquo;Alcedia<\/em>\u00a0\u00bb (nom temporaire du mouvement), avec les &Eacute;tats de New York, du New Jersey, du Connecticut, de Pennsylvanie, du Delaware et du Rhode Island, et ajout\u00e9 24 heures plus tard, du Massachusetts, &ndash; soit six &Eacute;tats avec des gouverneurs d\u00e9mocrates, et le Massachusetts, venu ensuite, avec un gouverneur r\u00e9publicain.<\/p>\n<\/p>\n<p><p>Nebojsa Malic, de RT.com, d\u00e9veloppe ce ph\u00e9nom\u00e8ne extr\u00eamement actif et pressant en raison des circonstances  <a href=\"https:\/\/www.rt.com\/op-ed\/485725-democrat-governors-coronavirus-lockdowns\/\">le 14 avril 2020<\/a>, en donnant des pr\u00e9cisions sur cet \u00e9v\u00e9nement&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Alors que la Californie et New York ont d\u00e9clar\u00e9 qu&rsquo;ils coordonneraient les r\u00e9ouvertures avec les &Eacute;tats voisins, les grands m\u00e9dias am\u00e9ricains ont soudainement red\u00e9couvert la vertu du f\u00e9d\u00e9ralisme, tandis que certains activistes en ligne ont m\u00eame applaudi la notion de s\u00e9paratisme.<\/em><\/p>\n<p>&raquo; <em>Le gouverneur de Californie, Gavin Newsom, a ouvert le bal lundi, en annon\u00e7ant que son &Eacute;tat coordonnerait la fin de la fermeture de la coronavirus avec l&rsquo;Oregon voisin et Washington plus au nord, &ndash; tous deux dirig\u00e9s par des d\u00e9mocrates \u00e9galement, &ndash; et ne suivrait pas l&rsquo;exemple du pr\u00e9sident Donald Trump et du gouvernement f\u00e9d\u00e9ral \u00e0 Washington<\/em>. <\/p>\n<p>&raquo; <em>De telles th\u00e9ories ont \u00e9t\u00e9 aliment\u00e9es par les commentaires de Newsom la semaine derni\u00e8re, lorsqu&rsquo;il a d\u00e9crit la Californie comme un \u00ab\u00a0&Eacute;tat-nation\u00a0\u00bb. Interrog\u00e9 \u00e0 ce sujet lundi, il l&rsquo;a d\u00e9fendu comme un \u00ab\u00a0choix de mots qui vous donne une id\u00e9e de l&rsquo;ampleur et de la port\u00e9e\u00a0\u00bb, pour un &Eacute;tat qui est \u00ab\u00a0plus grand que 21 &Eacute;tats r\u00e9unis, la 5e plus grande \u00e9conomie du monde, l&rsquo;&Eacute;tat le plus diversifi\u00e9 et le plus d\u00e9mocratique\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Cela a suffi pour que certains militants lib\u00e9raux entendent le sifflet du s\u00e9paratisme et que \u00ab\u00a0Cascadia\u00a0\u00bb, &ndash; un terme d\u00e9signant un r\u00e9gime politique ind\u00e9pendant du nord-ouest du Pacifique, &ndash; se mette au diapason des m\u00e9dias sociaux<\/em>. [&#8230;]<\/p>\n<p>&raquo; <em>Pendant ce temps, sur la c\u00f4te Est, le gouverneur de New York, Andrew Cuomo, a d\u00e9clar\u00e9 qu&rsquo;il travaillerait avec cinq autres &Eacute;tats de la r\u00e9gion pour coordonner \u00e9galement leur r\u00e9ouverture. Cela concernerait le New Jersey, le Connecticut, la Pennsylvanie, le Delaware et le Rhode Island, &ndash; tous gouvern\u00e9s par des d\u00e9mocrates. Plus tard dans la journ\u00e9e, le bloc a atteint une sorte de bipartisme, lorsque le gouverneur du Massachusetts Charlie Baker, un r\u00e9publicain du groupe hostile au POTUS, dit-NeverTrump, l&rsquo;aurait rejoint.<\/em><\/p>\n<p>&raquo; <em>Contrairement \u00e0 \u00ab\u00a0Cascadia\u00a0\u00bb, ce bloc de sept &Eacute;tats n&rsquo;a pas encore trouv\u00e9 d&rsquo;\u00e9tiquette accrocheuse, bien que des propositions aient \u00e9t\u00e9 faites pour cr\u00e9er des \u00ab\u00a0territoires d&rsquo;Acela\u00a0\u00bb d&rsquo;apr\u00e8s la ligne de chemin de fer qui les traverse.<\/em><\/p>\n<p>&raquo; <em>Ces deux agglom\u00e9rations r\u00e9gionales ont suscit\u00e9 des sp\u00e9culations pleines d&rsquo;espoir sur la fa\u00e7on dont \u00ab\u00a0le gouvernement f\u00e9d\u00e9ral am\u00e9ricain perd le contr\u00f4le op\u00e9rationnel de ses deux principaux centres \u00e9conomiques\u00a0\u00bb et \u00ab\u00a0il est possible de faire des choses qui ne sont pas faciles \u00e0 d\u00e9faire\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Il faut \u00e9videmment placer ce (ces) mouvement(s) dans un contexte absolument dramatique, qui s&rsquo;est brutalement aggrav\u00e9 hier alors que la tendance g\u00e9n\u00e9rale \u00e9tait de penser qu&rsquo;on avait atteint aux USA le fameux \u00ab\u00a0plateau\u00a0\u00bb conduisant \u00e0 un recul de la pand\u00e9mie. Comme le d\u00e9taille <em>WSWS.org<\/em>, en donnant des pr\u00e9cisions, y compris hors de l&rsquo;&Eacute;tat de New York jusqu&rsquo;ici centre de la contagion, vers des r\u00e9gions jusqu&rsquo;ici \u00e9pargn\u00e9es ; et l&rsquo;on n&rsquo;est pas sans remarquer, pr\u00e9cision importante, qu&rsquo;une brusque aggravation de la situation avec des perspectives inqui\u00e9tantes dans l&rsquo;&Eacute;tat du Massachusetts intervient alors que son gouverneur, un r\u00e9publicain, s&rsquo;est joint au groupe des cinq &Eacute;tats d\u00e9mocrates dit du \u00ab\u00a0<em>territoire d&rsquo;Alcedia<\/em>\u00a0\u00bb :<\/p>\n<\/p>\n<p><p>&laquo; <em>Mardi, un nombre stup\u00e9fiant de 2 349 personnes ont succomb\u00e9 \u00e0 la COVID-19 aux &Eacute;tats-Unis, ce qui repr\u00e9sente le plus grand nombre de d\u00e9c\u00e8s quotidiens aux Etats-Unis, &ndash; comme dans tout autre pays. Mais comme les m\u00e9dias am\u00e9ricains ont adopt\u00e9 la narrative selon laquelle la pand\u00e9mie laissait voir des \u00ab\u00a0lueurs d&rsquo;espoir\u00a0\u00bb et des \u00ab\u00a0signes d&rsquo;esp\u00e9rance\u00a0\u00bb, ce bilan stup\u00e9fiant n&rsquo;a m\u00eame pas fait l&rsquo;objet d&rsquo;un reportage au journal t\u00e9l\u00e9vis\u00e9 du soir.<\/em><\/p>\n<p>&raquo; <em>Le Wyoming ayant annonc\u00e9 lundi son premier d\u00e9c\u00e8s d&ucirc; au COVID-19, chaque &Eacute;tat du pays a d\u00e9sormais enregistr\u00e9 au moins un d\u00e9c\u00e8s d&ucirc; au virus. L&rsquo;&Eacute;tat de New York a fait \u00e9tat de 778 d\u00e9c\u00e8s mardi, le New Jersey de 362, le Michigan de 166, le Massachusetts de 113 et la Louisiane de 129.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;&Eacute;tat de New York a signal\u00e9 202 208 cas, soit environ un tiers de tous les cas am\u00e9ricains. Le nombre de d\u00e9c\u00e8s s&rsquo;\u00e9l\u00e8ve \u00e0 10 834. Toutefois, ce chiffre ne tient pas compte du fait que la ville de New York a ajout\u00e9 \u00e0 sa liste 3 700 personnes suppl\u00e9mentaires qui sont probablement mortes des suites de la COVID-19 dans des h\u00f4pitaux, des maisons de repos et des \u00e9tablissements de soins de longue dur\u00e9e, mais qui n&rsquo;avaient pas \u00e9t\u00e9 test\u00e9es. Le d\u00e9partement de la sant\u00e9 de la ville de New York a publi\u00e9 des chiffres qui placent maintenant le nombre de d\u00e9c\u00e8s dans la seule ville \u00e0 plus de 10 000.<\/em><\/p>\n<p>&raquo; <em>La pand\u00e9mie a entra&icirc;n\u00e9 une augmentation des d\u00e9c\u00e8s collat\u00e9raux ou des d\u00e9c\u00e8s non directement li\u00e9s \u00e0 la COVID-19 mais dus \u00e0 l&rsquo;incapacit\u00e9 du syst\u00e8me de sant\u00e9 et des urgentistes \u00e0 prendre en charge les besoins sanitaires de base de la population en raison d&rsquo;un manque de ressources. Le maire de New York, Bill de Blasio, a d\u00e9clar\u00e9 la semaine derni\u00e8re : \u00ab\u00a0Le moteur de cette \u00e9norme augmentation des d\u00e9c\u00e8s \u00e0 domicile est COVID-19. Et certaines personnes en meurent directement, d&rsquo;autres indirectement, mais c&rsquo;est le tragique facteur &lsquo;X&rsquo; qui est en cause ici\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Le Massachusetts s&rsquo;est hiss\u00e9 \u00e0 la troisi\u00e8me place gr\u00e2ce \u00e0 l&rsquo;augmentation du nombre de nouveaux cas. Par habitant, il se situe juste derri\u00e8re l&rsquo;&Eacute;tat de Louisiane, qui a enregistr\u00e9 plus de 129 d\u00e9c\u00e8s aujourd&rsquo;hui pour d\u00e9passer la barre des 1 000. Le gouverneur Charlie Baker a d\u00e9clar\u00e9 que le Massachusetts se pr\u00e9pare \u00e0 une augmentation des cas qui devrait se produire entre la mi-avril et la fin avril, avec 2 500 nouveaux cas par jour.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;&Eacute;tat du Michigan, avec plus de 27 000 cas, a un taux de mortalit\u00e9 de 6,5 % et plus de 1 768 d\u00e9c\u00e8s. Hier, l&rsquo;&Eacute;tat a fait \u00e9tat de 166 nouveaux d\u00e9c\u00e8s. Dans une sc\u00e8ne horriblement embl\u00e9matique, les photos prises par le personnel des urgences montrent des corps dans des sacs blancs empil\u00e9s dans des placards et des espaces vides, jonchant le sol, car la morgue \u00e9tait trop pleine pour accueillir davantage de cadavres. Pourtant, un porte-parole de l&rsquo;h\u00f4pital a d\u00e9clar\u00e9 \u00e0 un journaliste de CNN : \u00ab\u00a0Des plans d&rsquo;urgence sont en place dans notre h\u00f4pital pour faire face \u00e0 l&rsquo;augmentation du nombre de patients hospitalis\u00e9s afin de garantir que nous offrons les soins les plus s&ucirc;rs et les plus appropri\u00e9s \u00e0 nos patients\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>On comprend ici que l&rsquo;on se trouve dans une situation exceptionnelle, &ndash; du point de vue de la pand\u00e9mie \u00e9videmment, mais aussi du point de vue de la direction politique et des perspectives de conflits avec le centre, de querelles, d&rsquo;affrontements, de \u00ab\u00a0s\u00e9cession\u00a0\u00bb. En effet, les gouverneurs des &Eacute;tats se trouvent brusquement propuls\u00e9s \u00e0 la t\u00eate de la crise centrale, de la contestation centrifuge, alors qu&rsquo;ils se sont jusqu&rsquo;ici \u00e9videmment tenus \u00e0 l&rsquo;\u00e9cart de tout ce qui pouvait y ressembler.<\/p>\n<\/p>\n<p><p>Les gouverneurs font partie de l&rsquo;<em>establishment<\/em>(du Syst\u00e8me), mais ils d\u00e9pendent ainsi que leurs partis locaux de leurs \u00e9lecteurs et ils ne veulent pas une seconde objectivement laisser aller le carnage au nom de ce qu&rsquo;ils jugent \u00eatre les lubies d&rsquo;un Washington D.C sous la coupe d&rsquo;un pr\u00e9sident tr\u00e8s-souvent consid\u00e9r\u00e9 comme incontr\u00f4lable et souvent appr\u00e9ci\u00e9 comme lunatique. D&rsquo;o&ugrave; ce constat que l&rsquo;on peut d\u00e9sormais envisager une situation o&ugrave; l&rsquo;<em>establishment<\/em>serait coup\u00e9 en deux sur une question \u00e0 la fois fondamentale et urgente, ontologique et catastrophique, qui est la question de la s\u00e9cession.<\/p>\n<\/p>\n<p><p>Il y a aussi des questions de personnes, mais elles ne font qu&rsquo;attiser le feu sans en changer la direction. L&rsquo;inimiti\u00e9 d\u00e9sormais affich\u00e9 entre Trump et le gouverneur de l&rsquo;&Eacute;tat de New York Cuomo, extr\u00eamement actif et extr\u00eamement m\u00e9diatis\u00e9 du fait de sa position \u00e0 la t\u00eate d&rsquo;un des &Eacute;tats les plus importants de l&rsquo;Union, et le centre tragique de la pand\u00e9mie aux USA, joue un r\u00f4le important et a d\u00e9termin\u00e9 l&rsquo;esquisse du bloc des cinq\/six &Eacute;tats de l&rsquo;Est. En m\u00eame temps, qui \u00e0 l&rsquo;int\u00e9rieur du parti d\u00e9mocrate s&rsquo;opposerait \u00e0 Cuomo, qui s&rsquo;oppose \u00e0 l&rsquo;ennemi jur\u00e9 du parti qu&rsquo;est Trump ? (Sa popularit\u00e9 est telle chez les d\u00e9mocrates que certains ont l&rsquo;id\u00e9e d&rsquo;\u00e9liminer le vieux crouton Biden de la course \u00e0 la pr\u00e9sidence et de le remplacer par Cuomo.)<\/p>\n<\/p>\n<p><p>Face \u00e0 ce que l&rsquo;on peut commencer \u00e0 qualifier de \u00ab\u00a0fronde s\u00e9cessionniste\u00a0\u00bb, Trump a une attitude ambigu\u00eb, \u00e0 la fois extr\u00eamement ferme voire totalitaire, \u00e0 la fois laxiste, du type : \u00ab\u00a0C&rsquo;est moi et personne d&rsquo;autre qui d\u00e9cide, et j&rsquo;ai d\u00e9cid\u00e9 de laisser faire les gouverneurs&#8230;\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&laquo; <em>Interrog\u00e9<\/em>[au sujet du mouvement de \u00ab\u00a0fronde s\u00e9cessionniste\u00a0\u00bb] <em>lors de sa conf\u00e9rence de presse quotidienne <\/em>[de mardi]<em>, Trump a balay\u00e9 l&rsquo;id\u00e9e, martelant que le gouvernement f\u00e9d\u00e9ral avait une autorit\u00e9 \u00ab\u00a0totale\u00a0\u00bb mais qu&rsquo;il avait choisi de ne pas l&rsquo;exercer. Il n&rsquo;a pas demand\u00e9 aux gouverneurs de mettre fin au confinement, a-t-il dit, \u00ab\u00a0parce que je n&rsquo;ai pas \u00e0 le faire\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>En attendant, il n&rsquo;est pas certain que l&rsquo;un ou l&rsquo;autre de ces groupements r\u00e9gionaux ait l&rsquo;intention de mettre fin \u00e0 leur verrouillage plus t\u00f4t ou plus tard que ce que Trump pourrait avoir \u00e0 l&rsquo;esprit. Ce d\u00e9tail semble moins important pour eux que leur d\u00e9termination \u00e0 contourner la Maison Blanche<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>On voit dans ces deux paragraphes l&rsquo;ambigu\u00eft\u00e9 des positions des uns et des autres, donc leur d\u00e9sir de ne pas dramatiser les choses, dans tous les cas du point de vue de la communication&#8230; Certains diraient que cela r\u00e9duit \u00e0 peu de choses l&rsquo;hypoth\u00e8se de la s\u00e9cession. Nous disons exactement le contraire.<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">De Trump \u00e0 Lincoln et retour<\/h3>\n<\/p>\n<p><p>Tout le monde conviendra ais\u00e9ment que Trump n&rsquo;est pas Lincoln ; par cons\u00e9quent, entre autres grandes diff\u00e9rences, l&rsquo;une de ses pr\u00e9occupations majeures est de n&rsquo;avoir aucune pr\u00e9occupation concernant la coh\u00e9sion de l&rsquo;Union. Par contre, il se pr\u00e9occupe grandement de l&rsquo;\u00e9tat de l&rsquo;\u00e9conomie, et surtout de sa chute dans le cadre de la crise-Codiv19 mais avec une attention particuli\u00e8re pour la bonne sant\u00e9 du <em>Corporate Power<\/em>, parce qu&rsquo;il pense en toutes choses d&rsquo;un point de vue \u00e9conomiste et d&rsquo;un homme fortun\u00e9, selon la plus pure conception capitalistique et de financiarisation, et parce qu&rsquo;il est persuad\u00e9 qu&rsquo;une bonne perception du public de son action \u00e9conomique est la clef de sa r\u00e9\u00e9lection qu&rsquo;il veut \u00e0 tout prix.<\/p>\n<\/p>\n<p><p>Les gouverneurs, eux, sont \u00e0 peu pr\u00e8s dans le m\u00eame \u00e9tat d&rsquo;esprit. Nul ne songe \u00e0 la s\u00e9cession (<a href=\"https:\/\/www.dedefensa.org\/article\/la-californie-est-un-etat-souverain\">sauf la Californie<\/a>, certes, qui vit dans un \u00e9tat d&rsquo;esprit de s\u00e9cession de fait) et tous songent \u00e0 l&rsquo;\u00e9conomie de leur &Eacute;tat, \u00ab\u00a0et surtout de sa chute dans le cadre de la crise-Codiv19\u00a0\u00bb mais avec une attention plus particuli\u00e8re sur le sort sanitaire et socio-\u00e9conomique de leurs populations, parce que leur plus grande proximit\u00e9 de cette population implique la n\u00e9cessit\u00e9 d&rsquo;une affectivit\u00e9 (et non d&rsquo;affectivisme) pour conqu\u00e9rir les c&oelig;urs autant que les esprits. Eux aussi \u00ab\u00a0pense en toutes choses d&rsquo;un point de vue \u00e9conomiste\u00a0\u00bb, mais selon une vision capitalistique fortement nuanc\u00e9e de populisme, &ndash; parce que les tragiques conditions actuelles favorisent n\u00e9cessairement, du point de vue de la communication politique, le populisme contre le globalisme et la financiarisation..<\/p>\n<\/p>\n<p><p>Bien entendu, ceux que nous nommons \u00ab\u00a0les gouverneurs\u00a0\u00bb, on l&rsquo;a vu, ce sont surtout (pour l&rsquo;instant) des d\u00e9mocrates, conform\u00e9ment \u00e0 la haine du parti d\u00e9mocrate contre Trump. Mais il n&rsquo;y a pas ce seul sentiment, comme on l&rsquo;a vu \u00e9galement, avec ce paradoxe que le soi-disant populiste Trump l&rsquo;est beaucoup moins que les gouverneurs, ce qui fait que certains gouverneurs r\u00e9publicains ne sont nullement adversaires des initiatives des gouverneurs d\u00e9mocrates (voir le Machassusetts). Il y a l\u00e0 un affrontement extr\u00eamement puissant, car plus on approche des pr\u00e9sidentielles et plus Trump voudra qu&rsquo;on passe du sanitaire \u00e0 l&rsquo;\u00e9conomique, alors que les derni\u00e8res nouvelles montrent que le sanitaire est tr\u00e8s, tr\u00e8s loin d&rsquo;\u00eatre r\u00e9solu, ni m\u00eame sur la voie d&rsquo;une r\u00e9solution. C&rsquo;est de cette fa\u00e7on qu&rsquo;on peut brusquement \u00ab\u00a0en venir aux mains\u00a0\u00bb ; c&rsquo;est-\u00e0-dire, si personne ne \u00ab\u00a0c\u00e8de volontairement\u00a0\u00bb (sans affirmation d&rsquo;autorit\u00e9), en venir \u00e0 des positions tranch\u00e9es de refus d&rsquo;alignement, impliquant de la part des gouverneurs une s\u00e9cession <em>de facto<\/em>, dans un cadre r\u00e9gional d\u00e9j\u00e0 pr\u00e9par\u00e9 pour cela avec des \u00ab\u00a0unions\u00a0\u00bb de plusieurs &Eacute;tats coordonnant leur action.<\/p>\n<\/p>\n<p><p>C&rsquo;est pour cette raison que nous disons que l&rsquo;hypoth\u00e8se de la s\u00e9cession est brusquement extr\u00eamement puissante. Nul ne l&rsquo;\u00e9voque, car il s&rsquo;agit d&rsquo;un tabou pour des dirigeants US, mais tous s&rsquo;engagent dans un affrontements de pouvoir qui ne pourra \u00eatre r\u00e9solu dans l&rsquo;urgence que par une rupture de type s\u00e9cessionniste dont la forme m\u00eame de l&rsquo;organisation d&rsquo;urgence est pr\u00eate \u00e0 l&rsquo;accueillir&#8230; Or, il y a deux urgences, deux crises terribles qui s&rsquo;ajoutent, interagissent et interf\u00e8rent, chacune avec leurs \u00ab\u00a0sous-crises\u00a0\u00bb&#8230;<\/p>\n<p>&bull; la crise-Covid19, avec sa dimension sanitaire et, au-del\u00e0 sa dimension \u00e9conomique, et pour l&rsquo;instant la dimension sanitaire \u00e9tant au premier plan ;<\/p>\n<p>&bull; l&rsquo;\u00e9lection pr\u00e9sidentielle USA2020, avec deux candidats extr\u00eames, tr\u00e8s \u00e2g\u00e9s et pleins de mis\u00e8re, \u00e0 la fois ha\u00efs et m\u00e9pris\u00e9s par leurs adversaires, avec ce sentiment g\u00e9n\u00e9ral  <a href=\"https:\/\/caitlinjohnstone.com\/2020\/04\/13\/this-absolute-bullshit-would-not-be-possible-without-propaganda\/\">fort bien exprim\u00e9<\/a>, et fort lestement comme c&rsquo;est justice, par Caitline Johnstone : &laquo; <em>Comment en sommes-nous arriv\u00e9s l\u00e0 ? Comment en sommes-nous arriv\u00e9s au point o&ugrave; la comp\u00e9tition \u00e9lectorale pour diriger le gouvernement le plus puissant de la plan\u00e8te oppose un violeur raciste et d\u00e9mentiel de droite, autoritaire et belliciste, \u00e0 un autre violeur raciste et d\u00e9mentiel de droite, autoritaire et belliciste ? Comment diable cette merde absolue a-t-elle pu se produire ?<\/em> &raquo;&#8230; Eh bien, cette \u00e9lection USA2020 est potentiellement une tr\u00e8s-grave crise qui ne demande qu&rsquo;\u00e0 s&rsquo;ajouter \u00e0 la pr\u00e9c\u00e9dente.<\/p>\n<\/p>\n<p><p>On notera encore divers probl\u00e8mes, interf\u00e9rences, contradictions, dont est grosse cette situation qui, en cas d&rsquo;aggravation, \u00e9voluerait certainement vers des risques de s\u00e9cession\/de fragmentation ; ceux-ci sont donn\u00e9s \u00e0 titre d&rsquo;exemples, pour montrer la complexit\u00e9 du cas et aussi combien les tensions potentielles conduisent tr\u00e8s vite \u00e0 des tensions de type s\u00e9cessionniste, o&ugrave; sont en jeu l&rsquo;autorit\u00e9 et la l\u00e9gitimit\u00e9 :<\/p>\n<p>&bull; comme tout bon acteur de l&rsquo;<em>establishment<\/em>, le parti d\u00e9mocrate est absolument pour l&rsquo;unit\u00e9 des USA, mais sa haine anti-Trump est telle qu&rsquo;il peut en arriver \u00e0 consid\u00e9rer que Trump est effectivement un usurpateur et que les gouverneurs (d\u00e9mocrates) doivent \u00eatre soutenus dans leur fronde ;<\/p>\n<p>&bull; que fera-t-on, dans tel ou tel cas de d\u00e9caccord, de la Garde Nationale des &Eacute;tats ? Elle d\u00e9pend nominalement du Pentagone, donc du pr\u00e9sident, mais les gouverneurs ont aussi une autorit\u00e9 sur elle : qui pr\u00e9vaudra ? On a d\u00e9j\u00e0 vu cette sorte d&rsquo;imbroglio, lors de l&rsquo;ouragan <em>Katrina <\/em>en 2005, o&ugrave; les parlementaires et le gouverneur de Louisiane bataillaient avec les autorit\u00e9s f\u00e9d\u00e9rales pour l&rsquo;intervention urgente de la Garde Nationale. Cette m\u00e9sentente potentielle est lourde de cons\u00e9quences, si des troubles ont lieu dans tel ou tel &Eacute;tat \u00e0 cause de la crise-Covit19.<\/p>\n<\/p>\n<blockquote>\n<p><p>Dans tous les cas, l&rsquo;on sait ici, dans ces colonnes, que nous devons \u00e9videmment en venir \u00e0 une constante de notre analyse qui est d&rsquo;une part la fragilit\u00e9 structurelles des USA, d&rsquo;autre part l&rsquo;importance colossale, apocalyptique et eschatologique, qu&rsquo;aurait un processus de d\u00e9structuration et de parcellisation des USA. Nous en parlons r\u00e9guli\u00e8rement depuis des ann\u00e9es&#8230; Par exemple, ces quelques paragraphes du  <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-lavenir-des-usa\">14 octobre 2009<\/a>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&laquo; <em>Nous l&rsquo;avons d\u00e9j\u00e0 \u00e9crit et nous le r\u00e9p\u00e9tons avec force : il ne peut y avoir, aujourd&rsquo;hui, d&rsquo;\u00e9v\u00e9nements plus important pour la situation du monde qu&rsquo;une dynamique de dislocation des USA. Nous pensons que la crise actuelle est \u00e0 la fois, et contradictoirement, formidablement amplifi\u00e9e et formidablement bloqu\u00e9e dans sa compr\u00e9hension par la puissance de la communication. Ce ph\u00e9nom\u00e8ne ne cesse de dramatiser et d&rsquo;attiser les conditions de la crise tout en renfor\u00e7ant la pression du conformisme de la pens\u00e9e dominante pour ne pas mettre en cause les \u00e9l\u00e9ments qui sont les fondements de cette crise.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;un des fondements est psychologique, avec le ph\u00e9nom\u00e8ne de fascination &ndash; \u00e0 nouveau ce mot &ndash; pour l&rsquo;attraction exerc\u00e9e sur les esprits par le \u00ab\u00a0mod\u00e8le am\u00e9ricaniste\u00a0\u00bb, qui est en fait la repr\u00e9sentation \u00e0 la fois symbolique et onirique de la modernit\u00e9. C&rsquo;est cela qui est r\u00e9sum\u00e9 sous l&rsquo;expression populaire mais tr\u00e8s substantiv\u00e9e de American Dream. Cette repr\u00e9sentation donn\u00e9e comme seule issue possible de notre civilisation (le facteur dit TINA, pour \u00ab\u00a0There Is No Alternative\u00a0\u00bb) infecte la plupart des \u00e9lites en place; elle repr\u00e9sente un verrou d&rsquo;une puissance inou\u00efe, qui compl\u00e8te d&rsquo;une fa\u00e7on tragique la \u00ab\u00a0fascination de l&rsquo;am\u00e9ricanisme pour sa propre destin\u00e9e catastrophique\u00a0\u00bb pour former une situation totalement bloqu\u00e9e emp\u00eachant de chercher une autre voie tout en d\u00e9gringolant vers la catastrophe. La fin de l&rsquo;American Dream, qui interviendrait avec un processus de parcellisation de l&rsquo;Am\u00e9rique, constituerait un facteur d\u00e9cisif pour d\u00e9bloquer notre perception, \u00e0 la fois des conditions de la crise, de la gravit\u00e9 ontologique de la crise et de la n\u00e9cessit\u00e9 de tenter de chercher une autre voie pour la civilisation &ndash; ou, plus radicalement, une autre civilisation.<\/em><\/p>\n<p>&raquo; <em>L&rsquo;alternative n&rsquo;est pas une \u00e9volution des arrangements politiques, \u00e9conomique ou g\u00e9ostrat\u00e9giques (par exemple, la Chine rempla\u00e7ant les USA comme n&deg;1, mais toujours dans le m\u00eame syst\u00e8me). En raison du blocage psychologique ainsi d\u00e9crit et de la pr\u00e9dominance de la communication, parce que nous sommes dans une <\/em><em><a href=\"http:\/\/www.dedefensa.org\/article-politique_d_epoque_l_ere_psychopolitique_rubrique_analyse_volume_22_n07_du_10_decembre_2006_25_12_2006.html\">\u00e8re psychopolitique<\/a><\/em><em> et non plus dans une \u00e9poque g\u00e9opolitique, il n&rsquo;est pas raisonnable d&rsquo;envisager une \u00e9volution \u00ab\u00a0douce\u00a0\u00bb o&ugrave; les USA accepteraient de perdre leur position dirigeante absolue. L&rsquo;alternative est une poursuite catastrophique de la crise vers des situations inconnues de d\u00e9sordre, avec les USA bloquant toute \u00e9volution possible. Mais il y a \u00e9galement de fortes chances que cette alternative renvoie \u00e9videmment \u00e0 la premi\u00e8re hypoth\u00e8se, parce que l&rsquo;entra&icirc;nement \u00ab\u00a0vers des situations inconnues de d\u00e9sordre\u00a0\u00bb affecterait justement, en priorit\u00e9, les USA, vers l&rsquo;\u00e9volution qu&rsquo;on sugg\u00e8re, pr\u00e9datrice et liquidatrice de l&rsquo;American Dream.<\/em><\/p>\n<p>&raquo; <em>Il est \u00e0 noter que les pr\u00e9visionnistes radicaux sont aujourd&rsquo;hui, express\u00e9ment ou pas, ax\u00e9s sur cette perspective. Lorsqu&rsquo;un Celente \u00e9voque une \u00ab\u00a0Great American Renaissance\u00a0\u00bb (GAR) avec un retour \u00e0 un certain \u00ab\u00a0jeffersonisme\u00a0\u00bb, il appara&icirc;t \u00e9vident que la condition sine qua non de cette pr\u00e9vision est la parcellisation de l&rsquo;Am\u00e9rique avec l&rsquo;effondrement du centre comme moteur fondamental de la dynamique actuelle. On voit que les projections utopiques &ndash; car c&rsquo;en est une, bien s&ucirc;r &ndash; rejoignent les appr\u00e9ciations r\u00e9alistes, voire le simple constat de l&rsquo;\u00e9volution de la situation aux USA<\/em>. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Covid-19, virus de la s\u00e9cession-USA 14 avril 2020 &ndash; On a d\u00e9j\u00e0 signal\u00e9 combien l&rsquo;actuelle crise-Covid19 ranimait dans l&rsquo;activisme d&rsquo;opportunit\u00e9 l&rsquo;option spectrale et toujours latente de la s\u00e9cession ou de la d\u00e9structuration aux USA, notamment avec deux textes, le 17 f\u00e9vrier 2020, o&ugrave; \u00e9tait mise en \u00e9vidence (par Wayne Madsen) l&rsquo;opposition entre Trump et le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6718,3037,3228,11618,2604,7997,5099,19816,7865,2936,2937,3256,8284,2949,19260,3257],"class_list":["post-79219","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-centralisme","tag-contre","tag-crise","tag-cuomo","tag-des","tag-dislocation","tag-droits","tag-etzats","tag-faire","tag-garde","tag-nationale","tag-new","tag-sanitaire","tag-secession","tag-usa2020","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79219"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79219\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}