{"id":79220,"date":"2020-04-16T14:11:43","date_gmt":"2020-04-16T14:11:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/04\/16\/covid-19-ne-vois-tu-rien-venir\/"},"modified":"2020-04-16T14:11:43","modified_gmt":"2020-04-16T14:11:43","slug":"covid-19-ne-vois-tu-rien-venir","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/04\/16\/covid-19-ne-vois-tu-rien-venir\/","title":{"rendered":"Covid-19, ne vois-tu rien venir\u00a0?"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Covid-19, ne vois-tu rien venir ?<\/h2>\n<\/p>\n<p><p>A cause de ses in\u00e9vitables r\u00e9f\u00e9rences trotskistes, &ndash;<em>What else ?<\/em>&ndash; il est difficile pour nous de prendre \u00e0 notre compte tout ce qui \u00e9mane du site <em>WSWS.org. <\/em>Simplement \u00e9nonc\u00e9 par l&rsquo;\u00e9vidence, parce que le trotskisme n&rsquo;est en aucun cas, ni notre tasse de th\u00e9, ni notre \u00ab\u00a0feuille de route\u00a0\u00bb, ni notre <em>credo. <\/em>Cela dit, fort solennellement cette fois, il nous faut reconna&icirc;tre et proclamer une fois de plus l&rsquo;excellent travail d&rsquo;information pure et d&rsquo;analyse des faits que r\u00e9alise ce site ; et alors et cela dit et bien compris, il reste \u00e0 chacun et selon son choix le loisir, ou la t\u00e2che s\u00e9rieuse, de laisser de c\u00f4t\u00e9 les susdites r\u00e9f\u00e9rences trotskistes qui sont ais\u00e9ment identifiables, et d&rsquo;ailleurs nullement dissimul\u00e9es.<\/p>\n<\/p>\n<p><p>Il en r\u00e9sulte que <em>WSWS.org <\/em>est souvent une excellente source d&rsquo;information qui, dans nombre de cas, notamment \u00e0 cause de sa d\u00e9termination absolue d&rsquo;opposition au capitalisme (ce que nous nommons le Syst\u00e8me, comprenant notamment et sans aucun doute le capitalisme), est d&rsquo;une aide tr\u00e8s pr\u00e9cieuse pour un antiSyst\u00e8me cons\u00e9quent et responsable.<\/p>\n<\/p>\n<p><p>Cela est dit pour cet article qui analyse pour m\u00e9moire et pour notre bonne m\u00e9moire la position et le comportement de Trump d&rsquo;une part, de la presseSyst\u00e8me (dans le chef du New York <em>Times<\/em>) d&rsquo;autre part, vis-\u00e0-vis de l'\u00a0\u00bbattaque\u00a0\u00bb contre les USA du Coronavirus, entre janvier et mars. L&rsquo;article nous donne de pr\u00e9cieuses indications, une bonne documentation, etc., qui permettent de porter un jugement structur\u00e9 sur le comportement de la direction dans son sens large des USA dans cette affaire. En compl\u00e9ment de cette appr\u00e9ciation, on notera que la politique habituelle de <em>WSWS.org <\/em>vis-\u00e0-vis de la campagne de communication d&rsquo;une puissance inou\u00efe en cours aux USA contre la Chine, sa suppos\u00e9e-responsabilit\u00e9, sinon ses plus noirs desseins contre les USA, est de la plus extr\u00eame r\u00e9serve. Le site, s&rsquo;il signale ici et l\u00e0 les positions exprim\u00e9es publiquement, ne prend lui-m\u00eame pas position sur une question qui est actuellement de pure pol\u00e9mique et affirm\u00e9e pour des causes assez basses d&rsquo;int\u00e9r\u00eat politique partisan sinon politicien, ou d&rsquo;illusions en forme de simulacre.<\/p>\n<\/p>\n<p><p>Si nous nous attardons \u00e0 de telles consid\u00e9rations concernant la source cit\u00e9e, et que nous citons d&rsquo;ailleurs r\u00e9guli\u00e8rement, c&rsquo;est parce que le texte comprend une partie conclusive consacr\u00e9e au rappel, avec citations cons\u00e9quentes, de divers textes de <em>WSWS.org <\/em>avertissant du danger de Codiv-19 tandis que l&rsquo;administration Trump et la presseSyst\u00e8me pensaient \u00e0 autre chose malgr\u00e9 la multitude d&rsquo;informations, aussi bien faites pour d\u00e9noncer la Chine par avance que pour montrer l&rsquo;efficacit\u00e9 des services de renseignement US, dont on nous chuchote aujourd&rsquo;hui qu&rsquo;elles \u00e9taient disponibles hier, bien avant m\u00eame le lancement de l'\u00a0\u00bbattaque\u00a0\u00bb. Nous nous sommes interrog\u00e9s pour savoir s&rsquo;il \u00e9tait utile de garder cette derni\u00e8re partie, qui pouvait appara&icirc;tre comme une promotion de ce site <em>WSWS.org<\/em>. Finalement, l&rsquo;autre argument de la qualit\u00e9 des informations et des analyses du site a pr\u00e9valu, ces citations valant effectivement comme une confirmation \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<blockquote>\n<p><p>Toutes les pr\u00e9cisions contenues dans le texte nous permettent de mieux \u00e9tayer et pr\u00e9ciser ce que nous savons d\u00e9j\u00e0 d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, &ndash; autant par exp\u00e9rience que par intuition, que par information \u00e9vidente et juste conviction, &ndash; des pratiques et des comportements de Trump et de la presseSyst\u00e8me. Dans cette occurrence, il s&rsquo;agit d&rsquo;une comp\u00e9tition de simulacres de ces deux acteurs, \u00e0 l&rsquo;aide de contrev\u00e9rit\u00e9s, de dissimulations, de grossi\u00e8res affirmations, etc., comme un fid\u00e8le reflet des plus flagrantes caricatures. Par ailleurs, on les retrouve sur la m\u00eame ligne de front contre la Chine, plaidant la m\u00eame cause sans la moindre certitude raisonnable, et s&rsquo;insultant parall\u00e8lement l&rsquo;un l&rsquo;autre du coin de l&rsquo;&oelig;il. <\/p>\n<\/p>\n<p><p>Il y a l\u00e0 encore, si besoin en \u00e9tait et m\u00eame si la r\u00e9affirmation des m\u00eames comportements indignes pourrait para&icirc;tre lassante, l&rsquo;exposition d&rsquo;une culpabilit\u00e9 \u00e9gale, d&rsquo;un cynisme \u00e9quivalent m\u00eame si sous des formes diff\u00e9rentes ; d&rsquo;une indiff\u00e9rence compl\u00e8te \u00e0 la  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> refl\u00e9tant la r\u00e9alit\u00e9 hors des d\u00e9formations partisanes, enfin d&rsquo;une corruption de la psychologie d\u00e9terminant comme une pathologie (comme une pand\u00e9mie ?) un comportement pla\u00e7ant les deux acteurs chacun dans leur propre simulacre dont la similitude sugg\u00e8re effectivement, plus le caract\u00e8re de contagiosit\u00e9 que celui de la complicit\u00e9. Ces deux acteurs m\u00e8nent le m\u00eame combat inf\u00e2me, compl\u00e8tement manipul\u00e9s par des forces mal\u00e9fiques qui les d\u00e9passent, se ha\u00efssant avec la plus extr\u00eame vigueur m\u00eame s&rsquo;ils s&rsquo;entendent sur certains mensonges \u00e0 manipuler dans le m\u00eame sens.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Certes, la palme revient, dans le registre du bouffe, au pr\u00e9sident des &Eacute;tats-Unis qui est de plus en plus \u00e9gal \u00e0 lui-m\u00eame, et il ne faut pas l&rsquo;en priver ni nous en priver&#8230; Par exemple, lorsqu&rsquo;on revient rapidement sur quelques-unes de ses d\u00e9clarations concernant Codiv-19, entre fin janvier et mi-mars, &ndash; pour aboutir, hier, \u00e0 la d\u00e9nonciation directe de la Chine, de son laboratoire, de ses mauvaises intentions et de sa machination monstrueuse, &ndash; \u00e0 la grande satisfaction de <em><a href=\"https:\/\/www.zerohedge.com\/political\/watch-live-white-house-coronavirus-task-force-holds-wednesday-briefing\">ZeroHedge.com<\/a>&#8230;<\/em><\/p>\n<\/p>\n<p><p>&bull; 25 janvier : &laquo; <em>La Chine a travaill\u00e9 tr\u00e8s dur pour stopper le Coronavirus. Les USA appr\u00e9cient grandement leurs efforts et leur transparence<\/em>. &raquo;<\/p>\n<p>&bull; 10 f\u00e9vrier : &laquo; <em>En avril, quand il fera plus chaud, le coronavirus dispara&icirc;tra miraculeusement<\/em>. &raquo;<\/p>\n<p>&bull; 26 f\u00e9vrier : &laquo; <em>Quoi qu&rsquo;il arrive, ns sommes compl\u00e8tement pr\u00eats<\/em>. &raquo;<\/p>\n<p>&bull; 27 f\u00e9vrier : &laquo; <em>Les march\u00e9s commencent \u00e0 me sembler vraiment en tr\u00e8s bonne forme. Cela<\/em>[le Coronavirus]<em>va dispara&icirc;tre. Un jour, comme un miracle,  &ndash; il dispara&icirc;tra<\/em>. &raquo;<\/p>\n<p>&bull; 28 f\u00e9vrier : &laquo; <em>Les d\u00e9mocrates politise le Coronavirus. C&rsquo;est une nouvelle mystification, un nouveau simulacre<\/em>. &raquo;<\/p>\n<p>&bull; 7 mars : &laquo; <em>Non, je ne suis pas du tout pr\u00e9occup\u00e9. Non, ns avons fait un sacr\u00e9 travail dans cette affaire<\/em>. &raquo;<\/p>\n<p>&bull; 10 mars : &laquo; <em>Et nous sommes pr\u00eats, et nous faisons un sacr\u00e9 travail avec \u00e7a. Et il s&rsquo;en ira. Restez calmes, il s&rsquo;en ira<\/em>. &raquo;<\/p>\n<p>&bull; 11 mars : &laquo; <em>Nous suspendons les voyages d&rsquo;Europe vers les USA<\/em>. [&#8230;] <em>Nous devons laisser la politique de c\u00f4t\u00e9, arr\u00eater d&rsquo;avoir une attitude partisane, et nous unir tous comme une seule nation<\/em>. &raquo;<\/p>\n<p>&bull; 13 mars : &laquo; <em>Aujourd&rsquo;hui, je d\u00e9clare un \u00e9tat d&rsquo;urgence nationale<\/em>. &raquo;<\/p>\n<p>&bull; 17 mars : &laquo; <em>J&rsquo;ai senti que c&rsquo;\u00e9tait une pand\u00e9mie bien avant qu&rsquo;on l&rsquo;appelle une pand\u00e9mie<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Il nous para&icirc;t manifeste qu&rsquo;une fois encore, le comportement de la direction am\u00e9ricaniste, m\u00eame s&rsquo;il va dans le m\u00eame sens du Syst\u00e8me naturellement et comme il se doit, est d&rsquo;une ontologie diff\u00e9rente de celui des directions des autres entit\u00e9s du  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-bloc-bao-1\">bloc-BAO<\/a>. (Et, sur ce point, bien entendu, nous nous d\u00e9tachons assez radicalement de la perception trotskiste de <em>WSWS.org.<\/em>) Les dirigeants am\u00e9ricanistes sont vraiment dans un autre univers, dans leurs simulacres, avec des insultes des uns pour les autres et vice-versa. Les autres du bloc-BAO, dont nos vaillants archers europ\u00e9ens, sont dans la m\u00eame gal\u00e8re mais ils sont accompagn\u00e9s, et de plus en plus nettement, par des scories de doutes divers, par des incertitudes, par des fragilit\u00e9s et des vuln\u00e9rabilit\u00e9s. On h\u00e9site \u00e0 dire lequel de ces deux comportements m\u00e9rite le plus une certaine compr\u00e9hension, \u00e0 r\u00e9server pour le jour de leur enterrement.<\/p>\n<\/p>\n<p><p>Le texte ci-dessous est du  <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2020\/04\/15\/pers-a15.html\">16 avril 2020<\/a>, sur la page fran\u00e7aise de <em>WSWS.org.<\/em><\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Trump, les m\u00e9dias et la catastrophe du Covid-19<\/h2>\n<\/p>\n<p><p>Samedi, le <em>New York Times <\/em>a publi\u00e9 un long expos\u00e9 sur l&rsquo;incapacit\u00e9 du gouvernement Trump \u00e0 donner suite aux avertissements r\u00e9p\u00e9t\u00e9s, au sein du gouvernement f\u00e9d\u00e9ral, que les &Eacute;tats-Unis faisaient face \u00e0 une catastrophe imminente mena\u00e7ant des centaines de milliers de vies.<\/p>\n<\/p>\n<p><p>Le  <em>Times  <\/em>fait remarquer : &laquo; Le bureau du Conseil national de s\u00e9curit\u00e9 charg\u00e9 de suivre les pand\u00e9mies a re\u00e7u des rapports des renseignements d\u00e9but janvier pr\u00e9disant la propagation du virus aux &Eacute;tats-Unis et, en l&rsquo;espace de quelques semaines, soulevait des options telles que le confinement des Am\u00e9ricains et le verrouillage de villes de la taille de Chicago. M. Trump a \u00e9vit\u00e9 de telles mesures jusqu&rsquo;en mars. &raquo;<\/p>\n<\/p>\n<p><p>Ces avertissements ont \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9s par les National Institutes of Health, les Centers for Disease Control and Prevention et m\u00eame de hauts responsables de la Maison Blanche. Pourtant, malgr\u00e9 ces avertissements, l&rsquo;administration Trump n&rsquo;a pas pris les mesures les plus \u00e9l\u00e9mentaires pour contenir la pand\u00e9mie. Le 2 mars, pr\u00e8s de deux mois apr\u00e8s que Trump a re\u00e7u les premiers avertissements que la pand\u00e9mie frapperait les &Eacute;tats-Unis, moins de 500 personnes avaient \u00e9t\u00e9 test\u00e9es pour le Covid-19 dans tout le pays. &Agrave; ce moment-l\u00e0, il s&rsquo;\u00e9tait propag\u00e9 sans contr\u00f4le depuis plus d&rsquo;un mois.<\/p>\n<\/p>\n<p><p>En public, Trump a d\u00e9lib\u00e9r\u00e9ment minimis\u00e9 la gravit\u00e9 de la maladie, affirmant \u00e0 tort que la pand\u00e9mie n&rsquo;\u00e9tait pas pire que la grippe. Il a fait valoir qu&rsquo;elle dispara&icirc;trait d&rsquo;elle-m\u00eame et a d\u00e9clar\u00e9 que la maladie \u00e9tait une &laquo; mystification &raquo;. Dimanche, Trump a retweet\u00e9 un commentaire le pressant de licencier le Dr Anthony Fauci, son principal conseiller scientifique, qui a d\u00e9clar\u00e9 publiquement que le lancement de mesures plus t\u00f4t aurait sauv\u00e9 des vies.<\/p>\n<\/p>\n<p><p>Clairement \u00e9nerv\u00e9 par la r\u00e9v\u00e9lation de l&rsquo;incomp\u00e9tence de son administration, Trump, comme d&rsquo;habitude, s&rsquo;est d\u00e9cha&icirc;n\u00e9 furieusement contre la presse lundi, insultant les journalistes dans une autre d\u00e9monstration d&rsquo;ignorance, de brutalit\u00e9, d&rsquo;arri\u00e9ration et d&rsquo;auto-glorification. Comme d&rsquo;habitude, Trump a pass\u00e9 la majeure partie de sa conf\u00e9rence de presse \u00e0 se vanter et \u00e0 nier toute responsabilit\u00e9 pour la catastrophe en train de d\u00e9ferler.<\/p>\n<\/p>\n<p><p>Si l&rsquo;article du  <em>Times  <\/em>donne un compte rendu important de la r\u00e9ponse incomp\u00e9tente de l&rsquo;administration Trump \u00e0 la pand\u00e9mie, il \u00e9vite de montrer une partie importante du tableau. Il n&rsquo;explique pas pourquoi la classe dirigeante dans son ensemble n&rsquo;\u00e9tait pas pr\u00e9par\u00e9e \u00e0 faire face \u00e0 la pand\u00e9mie.<\/p>\n<\/p>\n<p><p>La d\u00e9sastreuse suite d&rsquo;erreurs de Trump d\u00e9coule naturellement des politiques adopt\u00e9es par l&rsquo;ensemble de l&rsquo;<em>establishment  <\/em>politique et des administrations ant\u00e9rieures. Les administrations Bush et Obama avaient tout de m\u00eame saccag\u00e9 les capacit\u00e9s pr\u00e9ventives de la sant\u00e9 publique, r\u00e9duisant son financement ann\u00e9e apr\u00e8s ann\u00e9e. Malgr\u00e9 les avertissements sur le danger d&rsquo;une pand\u00e9mie pendant au moins deux d\u00e9cennies, aucune mesure n&rsquo;a \u00e9t\u00e9 prise pour constituer les stocks d&rsquo;\u00e9quipements n\u00e9cessaires.<\/p>\n<\/p>\n<p><p>Par ailleurs, de janvier \u00e0 maintenant, aucune partie de l&rsquo;<em>establishment<\/em>  politique am\u00e9ricain n&rsquo;a s\u00e9rieusement pr\u00e9conis\u00e9 une augmentation importante des d\u00e9penses de sant\u00e9 publique et un vaste programme de tests, de quarantaines et de d\u00e9pistages des contacts qui auraient pu arr\u00eater la pand\u00e9mie et sauver des dizaines de milliers de vies. Et pourtant, en seulement quelques semaines, les deux partis ont pu collaborer pour obtenir un renflouement de Wall Street et des grandes soci\u00e9t\u00e9s de milliards et de milliards de dollars, qui ont fait grimper le march\u00e9 boursier, alors m\u00eame que des millions de personnes perdaient leur emploi.<\/p>\n<\/p>\n<p><p>Le r\u00e9cit du  <em>Times  <\/em>n&rsquo;explique pas non plus le fait que le bilan du  <em>Times  <\/em>et des autres grands m\u00e9dias ait \u00e9t\u00e9 aussi minable que celui de Trump.<\/p>\n<\/p>\n<p><p>Malgr\u00e9 de nombreuses mises en garde \u00e0 partir de d\u00e9but janvier dans les m\u00e9dias internationaux, le  <em>New York Times  <\/em>n&rsquo;a consacr\u00e9 son premier \u00e9ditorial au coronavirus que le 29 janvier. Le journal qui sert si souvent de relais aux &laquo; sources anonymes &raquo; au sein du l&rsquo;appareil de renseignement n&rsquo;a pas rapport\u00e9 les &laquo; rapports des renseignements au d\u00e9but de janvier pr\u00e9disant la propagation du virus aux Etats-Unis &raquo; comme un des <em>scoops  <\/em>qu&rsquo;il a si souvent affich\u00e9es en gros titre.<\/p>\n<\/p>\n<p><p>Dans son \u00e9ditorial du 29 janvier, le journal avertit que la &laquo; m\u00e9fiance &raquo; envers les &laquo; institutions &raquo;, &ndash; un mot que le journal utilise pour parler de lui-m\u00eame et des agences de renseignement am\u00e9ricaines &ndash; est le plus grand facteur de risque li\u00e9 \u00e0 la propagation du Covid-19. Il n&rsquo;a appel\u00e9 \u00e0 aucune mesure d&rsquo;urgence pour lutter contre la maladie, ni \u00e0 une extension des capacit\u00e9s de test, de quarantaine et de d\u00e9pistages des contacts.<\/p>\n<\/p>\n<p><p>Et puis, un silence g\u00e9n\u00e9ral s&rsquo;est install\u00e9 pendant tout un mois, au cours duquel le  <em>New York Times  <\/em>n&rsquo;a pas \u00e9crit un seul \u00e9ditorial sur la pand\u00e9mie. Ce n&rsquo;est que le 29 f\u00e9vrier, alors qu&rsquo;il y avait 63 cas document\u00e9s aux &Eacute;tats-Unis et une transmission communautaire confirm\u00e9e, que le comit\u00e9 de r\u00e9daction du  <em>Times  <\/em>a r\u00e9examin\u00e9 la question.<\/p>\n<\/p>\n<p><p>Dans l&rsquo;intervalle, qui couvre la conclusion des efforts avort\u00e9s pour destituer Trump sur la base de fausses all\u00e9gations de &laquo; collusion &raquo; avec la Russie, le  <em>Times  <\/em>a pr\u00e9sent\u00e9 \u00e0 ses lecteurs le plat habituel des all\u00e9gations &laquo; d&rsquo;ing\u00e9rence russe &raquo; dans la soci\u00e9t\u00e9 am\u00e9ricaine, de propagande pro-guerre, d&rsquo;hyst\u00e9rie #MeToo et de demandes d&rsquo;extension du pouvoir des agences de renseignement am\u00e9ricaines.<\/p>\n<\/p>\n<p><p>Au cours du mois de f\u00e9vrier, le march\u00e9 boursier am\u00e9ricain a continu\u00e9 d&rsquo;atteindre de nouveaux sommets. Trump a clairement indiqu\u00e9 \u00e0 plusieurs reprises que sa principale pr\u00e9occupation face \u00e0 la pand\u00e9mie \u00e9tait son impact sur l&rsquo;\u00e9conomie et en particulier sur les march\u00e9s boursiers. Il n&rsquo;est pas difficile de supposer que des pr\u00e9occupations similaires ont motiv\u00e9 le comit\u00e9 de r\u00e9daction du  <em>Times <\/em>cherchant \u00e0 minimiser les &laquo; mauvaises nouvelles &raquo;.<\/p>\n<\/p>\n<p><p>En fait, lorsque son comit\u00e9 de r\u00e9daction est revenu sur le sujet le 3 mars, c&rsquo;\u00e9tait avec une nouvelle optique : &laquo; Si le gouvernement f\u00e9d\u00e9ral ne parvient pas \u00e0 contenir la propagation du coronavirus et que les perspectives \u00e9conomiques s&rsquo;assombrissent, un tel stimulus de grande envergure pourrait bien devenir n\u00e9cessaire. &raquo;<\/p>\n<\/p>\n<p><p>Alors que le  <em>Times  <\/em>\u00e9tait silencieux sur la pand\u00e9mie de Covid-19, les politiciens d\u00e9mocrates et r\u00e9publicains pr\u00e9paraient un projet de loi de relance bipartite qui comprenait 450 milliards de dollars en renflouements d&rsquo;entreprises et finan\u00e7ait les 5 000 milliards de dollars que la R\u00e9serve f\u00e9d\u00e9rale fournit \u00e0 Wall Street et aux grandes entreprises.<\/p>\n<\/p>\n<p><p>Le silence du gouvernement Trump et du Parti d\u00e9mocrate contraste avec les nombreux avertissements du  <em>World Socialist Web Site<\/em>.<\/p>\n<\/p>\n<p><p>Un  <a href=\"https:\/\/translate.google.com\/translate?hl=fr&#038;prev=_t&#038;sl=en&#038;tl=fr&#038;u=https:\/\/www.wsws.org\/en\/articles\/2020\/01\/24\/viru-j24.html\">article du<\/a>  24 janvier (en anglais) de Benjamin Mateus notait que &laquo; des preuves ont \u00e9merg\u00e9 qu&rsquo;une infection de personne \u00e0 personne se produit &raquo; et que &laquo; des cas ont maintenant \u00e9t\u00e9 confirm\u00e9s en Tha\u00eflande, au Japon, en Cor\u00e9e du Sud, \u00e0 Ta\u00efwan, au Vietnam, \u00e0 Singapour, en Arabie saoudite et Etats-Unis &raquo;.<\/p>\n<\/p>\n<p><p>Dans une perspective du 28 janvier intitul\u00e9e &laquo; L&rsquo;\u00e9pid\u00e9mie de coronavirus de Wuhan et la menace mondiale des maladies infectieuses &raquo;, le WSWS notait : &laquo; L&rsquo;\u00e9pid\u00e9mie a r\u00e9v\u00e9l\u00e9 l&rsquo;\u00e9norme vuln\u00e9rabilit\u00e9 de la soci\u00e9t\u00e9 contemporaine aux nouvelles souches de maladies infectieuses, dangers pour lesquels aucun gouvernement capitaliste ne s&rsquo;est ad\u00e9quatement pr\u00e9par\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>Le WSWS d\u00e9clarait: &laquo; Alors que la situation en Chine est d\u00e9sastreuse, les pays dits avanc\u00e9s ne sont pas pour autant plus pr\u00e9par\u00e9s que la Chine \u00e0 faire face \u00e0 une \u00e9pid\u00e9mie de l&rsquo;ampleur qui se produit actuellement \u00e0 Wuhan. &raquo;<\/p>\n<\/p>\n<p><p>La perspective poursuivait :<\/p>\n<\/p>\n<p><p>&laquo; Autrement dit, alors que les gouvernements du monde, en particulier les &Eacute;tats-Unis, ont \u00e9labor\u00e9 des plans m\u00e9ticuleux pour une guerre \u00e0 grande \u00e9chelle au cours du dernier quart de si\u00e8cle, aucune ressource ni aucune pr\u00e9voyance de ce type n&rsquo;ont \u00e9t\u00e9 consacr\u00e9es \u00e0 la lutte contre la s\u00e9rie d&rsquo;\u00e9pid\u00e9mies qui ont ravag\u00e9 la plan\u00e8te sur la m\u00eame p\u00e9riode. Depuis 1996, il y a eu 67 \u00e9pid\u00e9mies \u00e0 travers le monde, dont l&rsquo;\u00e9pid\u00e9mie de la vache folle de 1996 \u00e0 2001, de grippe en 2009, de Zika en 2015-2016 et l&rsquo;\u00e9pid\u00e9mie de VIH \/ sida qui a tu\u00e9 au moins 30 millions de personnes depuis sa premi\u00e8re apparition en 1960.<\/p>\n<\/p>\n<p><p>Ces catastrophes sont \u00e0 tout moment \u00e9vitables. La science m\u00e9dicale a progress\u00e9 au point o&ugrave; elle est capable d&rsquo;identifier de nouveaux virus en quelques semaines et de d\u00e9velopper des vaccins en quelques mois. Et pourtant, comme l&rsquo;a fait remarquer la directrice g\u00e9n\u00e9rale de l&rsquo;OMS, la Dr Margaret Chan en 2014 \u00e0 propos de l&rsquo;\u00e9pid\u00e9mie d&rsquo;Ebola, &lsquo;une industrie \u00e0 but lucratif n&rsquo;investit pas dans des produits destin\u00e9s \u00e0 des march\u00e9s qui ne peuvent pas payer&hellip;&rsquo; &raquo;<\/p>\n<\/p>\n<p><p>Les projets de profit mercenaire \u00e0 court terme inh\u00e9rents au capitalisme sont incapables d&rsquo;allouer les ressources n\u00e9cessaires pour pr\u00e9venir et se pr\u00e9parer aux risques mondiaux &raquo;.<\/p>\n<\/p>\n<p><p>Au cours du mois suivant, dans la p\u00e9riode de silence du comit\u00e9 de r\u00e9daction du  <em>New York Times<\/em>, le  <em>World Socialist Web Site  <\/em>\u00e9crivait quatre d\u00e9clarations majeures sur la pand\u00e9mie en plus de la couverture quotidienne.<\/p>\n<\/p>\n<p><p>Dans &laquo; La pand\u00e9mie de coronavirus: une catastrophe mondiale &raquo; le 11 f\u00e9vrier, le  <em>World Socialist Web Site  <\/em>a  <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2020\/02\/12\/pers-f12.html\">condamn\u00e9<\/a>  les politiques nationalistes et x\u00e9nophobes de l&rsquo;administration Trump et les d\u00e9clarations du secr\u00e9taire au Commerce Wilbur Ross selon lesquelles la pand\u00e9mie &laquo; acc\u00e9l\u00e9rerait le retour des emplois en Am\u00e9rique du Nord &raquo;. Il a averti : &laquo; Comme pour tout autre probl\u00e8me social, y compris les in\u00e9galit\u00e9s sociales toujours grandissantes, l&rsquo;acc\u00e9l\u00e9ration du changement climatique et la menace accrue de la guerre, l&rsquo;\u00e9pid\u00e9mie de coronavirus est un probl\u00e8me mondial qui n\u00e9cessite une solution internationale. &raquo;<\/p>\n<\/p>\n<p><p>Le 27 f\u00e9vrier, le WSWS a publi\u00e9 une <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2020\/02\/28\/pers-f28.html\">perspective<\/a>  intitul\u00e9e &laquo; La pand\u00e9mie de coronavirus et la n\u00e9cessit\u00e9 d&rsquo;une m\u00e9decine socialis\u00e9e mondiale &raquo;. Alex Lantier y \u00e9crit : &laquo; Il est essentiel que le syst\u00e8me de sant\u00e9 mondial puisse isoler les patients, limiter la vitesse de propagation de la maladie et consacrer les ressources n\u00e9cessaires pour fournir des soins intensifs aux patients qui d\u00e9veloppent une pneumonie \u00e0 la suite de l&rsquo;infection. &raquo;<\/p>\n<\/p>\n<p><p>Le lendemain, le WSWS publiait une <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2020\/02\/29\/pers-f29.html\">d\u00e9claration<\/a>  du Comit\u00e9 international de la Quatri\u00e8me Internationale qui d\u00e9clarait: &laquo; Le gouvernement am\u00e9ricain n&rsquo;est absolument pas pr\u00e9par\u00e9 \u00e0 une \u00e9pid\u00e9mie majeure. Aucun syst\u00e8me n&rsquo;est en place pour tester syst\u00e9matiquement la pr\u00e9sence du virus. &raquo;<\/p>\n<\/p>\n<p><p>Elle concluait: &laquo;La classe ouvri\u00e8re doit exiger que les gouvernements mettent \u00e0 disposition les ressources n\u00e9cessaires pour contenir la propagation de la maladie, traiter et soigner les personnes infect\u00e9es et garantir les moyens de subsistance des centaines de millions de personnes qui seront affect\u00e9es par les retomb\u00e9es \u00e9conomiques. &raquo;<\/p>\n<\/p>\n<p><p>Le  <em>World Socialist Web Site  <\/em>n&rsquo;a pas les vastes ressources financi\u00e8res dont dispose le  <em>New York Times<\/em>. Et pourtant, nous avons pu avertir le public de la catastrophe qui allait se produire.<\/p>\n<\/p>\n<p><p>La raison en est que le WSWS est motiv\u00e9 par une orientation politique enti\u00e8rement \u00e0 l&rsquo;oppos\u00e9 du <em>Times<\/em>. La pr\u00e9occupation de l&rsquo;administration Trump et du <em>New York Times<\/em>, principal m\u00e9dia du Parti d\u00e9mocrate, est la pr\u00e9servation des int\u00e9r\u00eats financiers et \u00e9conomiques de l&rsquo;\u00e9lite dirigeante. La pr\u00e9occupation du WSWS est la d\u00e9fense de la classe ouvri\u00e8re et de la grande masse de la population.<\/p>\n<\/p>\n<p><p>Tout comme ils n&rsquo;ont pas averti le public des dangers pos\u00e9s par le coronavirus alors qu&rsquo;il se propageait dans tout le pays, l&rsquo;administration Trump et le  <em>New York Times  <\/em>cherchent une fois de plus \u00e0 minimiser la pand\u00e9mie pour cr\u00e9er un  <a href=\"https:\/\/www.wsws.org\/fr\/articles\/2020\/03\/25\/pers-m25.html\">climat propice<\/a>  \u00e0 un retour pr\u00e9matur\u00e9 au travail. Le  <em>World Socialist Web Site  <\/em>se concentre sur une mise en garde contre de telles mesures, soutenant que la vie humaine doit l&#8217;emporter sur les profits de l&rsquo;\u00e9lite dirigeante.<\/p>\n<\/p>\n<p><p>Pendant plus de deux d\u00e9cennies, le <em>World Socialist Web Site<\/em>, publication du Comit\u00e9 international de la Quatri\u00e8me Internationale, s&rsquo;est r\u00e9v\u00e9l\u00e9 \u00eatre un outil indispensable pour d\u00e9fendre les int\u00e9r\u00eats sociaux et politiques de la classe ouvri\u00e8re.<\/p>\n<\/p>\n<p><h4>Andre Damon, <em>WSWS.org<\/em><\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Covid-19, ne vois-tu rien venir ? A cause de ses in\u00e9vitables r\u00e9f\u00e9rences trotskistes, &ndash;What else ?&ndash; il est difficile pour nous de prendre \u00e0 notre compte tout ce qui \u00e9mane du site WSWS.org. Simplement \u00e9nonc\u00e9 par l&rsquo;\u00e9vidence, parce que le trotskisme n&rsquo;est en aucun cas, ni notre tasse de th\u00e9, ni notre \u00ab\u00a0feuille de route\u00a0\u00bb,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[11622,19677,2631,2622,3256,19810,6320,12820,2852,2639,5169,3257],"class_list":["post-79220","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-chronologie","tag-coronavirus","tag-de","tag-la","tag-new","tag-pandelie","tag-pandemie","tag-pressesysteme","tag-times","tag-trump","tag-wsws-org","tag-york"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79220"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79220\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}