{"id":79232,"date":"2020-04-23T21:39:25","date_gmt":"2020-04-23T21:39:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/04\/23\/de-lontologie-de-lantisysteme\/"},"modified":"2020-04-23T21:39:25","modified_gmt":"2020-04-23T21:39:25","slug":"de-lontologie-de-lantisysteme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/04\/23\/de-lontologie-de-lantisysteme\/","title":{"rendered":"De l&rsquo;ontologie de l&rsquo;antiSyst\u00e8me"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">De l&rsquo;ontologie de l&rsquo;antiSyst\u00e8me<\/h2>\n<\/p>\n<p><p>23 avril 2020 &ndash; C&rsquo;est un mot, une expression, un n\u00e9ologisme, etc. et que sais-je, qui a une r\u00e9elle fortune depuis quelques ann\u00e9es. Il faut dire qu&rsquo;il d\u00e9signe une cat\u00e9gorie de personnes et d&rsquo;actes d&rsquo;une tr\u00e8s grande importance correspondant \u00e0 la nouvelle situation que nous connaissons notamment depuis 9\/11, et jusqu&rsquo;ici sans rangement sugg\u00e9rant leur rassemblement. On l&rsquo;a beaucoup utilis\u00e9 sur ce site, jusqu&rsquo;\u00e0 en faire le sujet d&rsquo;un concept du <em>Glossaire.dde<\/em>, mais selon une orthographe bien sp\u00e9cifique (l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-lantisysteme-1\">antiSyst\u00e8me<\/a>), qui avait \u00e9t\u00e9 justifi\u00e9e auparavant dans un autre texte, le <a href=\"https:\/\/www.dedefensa.org\/article\/des-antisystemes-aux-antisysteme\">10 d\u00e9cembre 2010<\/a>(&laquo; <em>Des \u00ab\u00a0antisyst\u00e8mes\u00a0\u00bb aux \u00ab\u00a0antiSyst\u00e8me\u00a0\u00bb<\/em> &raquo;), introduisant le concept selon notre entendement bien sp\u00e9cifique.<\/p>\n<\/p>\n<p><p>Avec le <em>Glossaire.dde <\/em>du <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-lantisysteme-1\">27 juillet 2016<\/a>, nous avions franchi un pas important en identifiant une chronologie nous faisant passer d&rsquo;un mod\u00e8le d'\u00a0\u00bbantisyst\u00e8me\u00a0\u00bb (mod\u00e8le-Ron Paul) \u00e0 un autre (mod\u00e8le-Donald Trump). Quelques citations de ce <em>Glossaire.dde <\/em>rappellent de quoi il est pr\u00e9cis\u00e9ment question :<\/p>\n<\/p>\n<p><p>&laquo; [&#8230;] [&#8230;A]<em>insi verrons-nous <strong>qu&rsquo;au bout du compte, franchissant un pas de g\u00e9ant, <\/strong><\/em><strong>[la fonction antiSyst\u00e8me]<em>s&rsquo;est institutionnalis\u00e9e elle-m\u00eame \u00e0 la mesure du Syst\u00e8me lui-m\u00eame, <\/em><\/strong><em>dans le champ de l&rsquo;affrontement avec lui et pour l&rsquo;affronter au plus haut qu&rsquo;il est possible ; <strong>elle s&rsquo;est \u00ab\u00a0ontologis\u00e9e\u00a0\u00bb, pourrait-on dire en se r\u00e9f\u00e9rant au mot grec initial (ontos : \u00eatre)<\/strong>. Il n&rsquo;a donc jamais \u00e9t\u00e9 aussi urgent et n\u00e9cessaire de tenter d&rsquo;en donner une d\u00e9finition la plus compl\u00e8te possible. <\/em>[&#8230;]<\/p>\n<p>&raquo; <em>La premi\u00e8re phase, avec la mise en \u00e9vidence de l'\u00a0\u00bbantisyst\u00e8me\u00a0\u00bb\/\u00a0\u00bbantiSyst\u00e8me\u00a0\u00bb, d\u00e9finit la fonction comme compl\u00e8tement d\u00e9tach\u00e9e du sapiens qui l&rsquo;op\u00e9rationnalise dans la plupart des cas. En un sens, elle est un ph\u00e9nom\u00e8ne ext\u00e9rieur qui fait \u00e9lection dans l&rsquo;un ou l&rsquo;autre, selon les circonstances,&ndash; et cette situation initiale doit rester comme <strong>le fondement du ph\u00e9nom\u00e8ne, m\u00eame dans ses manifestations de plus en sophistiqu\u00e9es, o&ugrave; le sapiens joue un r\u00f4le de messager de plus en plus affirm\u00e9<\/strong>. Durant cette phase originelle que nous pourrions dire \u00ab\u00a0phase de l&rsquo;inconscience compl\u00e8te\u00a0\u00bb, il n&rsquo;est nul besoin, ni d&rsquo;\u00eatre antiSyst\u00e8me, ni d&rsquo;avoir conscience d&rsquo;\u00eatre antiSyst\u00e8me \u00e0 l&rsquo;instant pr\u00e9cis o&ugrave; la fonction vous habite momentan\u00e9ment, pour \u00eatre efficacement antiSyst\u00e8me. Si l&rsquo;on veut traduire cela trivialement, c&rsquo;est la \u00ab\u00a0phase Ron Paul\u00a0\u00bb. (Tout en \u00e9tant formidablement antiSyst\u00e8me, le candidat r\u00e9publicain qui rencontra un tel succ\u00e8s en 2010-2011, puis qui fut litt\u00e9ralement dissous dans les machinations et proc\u00e9dures du parti r\u00e9publicain, pr\u00e9sentait un caract\u00e8re d&rsquo;\u00e9minente honn\u00eatet\u00e9 qui le fit se conformer \u00e0 toutes les proc\u00e9dures auxquelles le soumettait sa culture de constitutionnaliste, bien que cette constitutionnalit\u00e9 f&ucirc;t [ou f&ucirc;t devenue, si l&rsquo;on veut \u00eatre extr\u00eamement compassionnel] de facto celle du Syst\u00e8me.) La deuxi\u00e8me phase baptis\u00e9e tout aussi trivialement, c&rsquo;est la \u00ab\u00a0phase The-Donald\u00a0\u00bb (Trump), celle o&ugrave; le candidat antiSyst\u00e8me affirme l&rsquo;\u00eatre consciemment, se vante de l&rsquo;\u00eatre, et fait de l&rsquo;antiSyst\u00e8me son v\u00e9ritable fond de commerce (cyniquement ou pas, stupidement ou non, que nous importe). <strong>Il n&rsquo;est pas assur\u00e9 que ce soit la phase ultime (celle qui aura la peau du Syst\u00e8me), comme il n&rsquo;est pas assur\u00e9 du tout que cela ne le soit pas <\/strong>; il n&rsquo;est pas assur\u00e9 que cette phase antiSyst\u00e8me soit totalement consciente dans le sens de la lucidit\u00e9, donc elle peut m\u00e9nager des erreurs et des rechutes (dans le Syst\u00e8me)&#8230; Nous en sommes l\u00e0 pour l&rsquo;instant, par exemple en fonction du fait que nous ne savons pas jusqu&rsquo;o&ugrave; ira, ou pourra aller Trump en tant qu&rsquo;antiSyst\u00e8me<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>A cette remarque en forme d&rsquo;interrogation : &laquo; <em>Il n&rsquo;est pas assur\u00e9 que ce soit la phase ultime (celle qui aura la peau du Syst\u00e8me), comme il n&rsquo;est pas assur\u00e9 du tout que cela ne le soit pas<\/em>&#8230; &raquo;, une r\u00e9ponse sans h\u00e9sitation peut \u00eatre apport\u00e9e d\u00e9sormais. La deuxi\u00e8me phase (\u00ab\u00a0phase <em>The-Donald<\/em>\u00ab\u00a0) n&rsquo;est pas la phase ultime ; d&rsquo;abord, pour mon compte, pour l&rsquo;imp\u00e9rative raison que je voudrais en proposer ici une troisi\u00e8me, en m&rsquo;en expliquant bien s&ucirc;r. Il appara&icirc;t assez vite \u00e9vident que cette troisi\u00e8me phase s&rsquo;est form\u00e9e avec les \u00e9v\u00e9nements qui ont \u00e9clat\u00e9 depuis le d\u00e9but pr\u00e9cis\u00e9ment de cette ann\u00e9e, et naturellement avec la crise Covid19. Sans cesse, a \u00e9t\u00e9 identifi\u00e9e et d\u00e9crite la  <a href=\"https:\/\/www.dedefensa.org\/article\/notes-de-2020-a-2002-et-retour\">formidable rupture<\/a> que constituent  <a href=\"https:\/\/www.dedefensa.org\/article\/un-assassinat-metahistorique\">ce d\u00e9but<\/a> d&rsquo;ann\u00e9e 2020,  <a href=\"https:\/\/www.dedefensa.org\/article\/covid-19-miroir-de-la-crise\">ce passage<\/a> entre la deuxi\u00e8me et  <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-limpeachmentdu-systeme\">troisi\u00e8me d\u00e9cennie<\/a> du si\u00e8cle.<\/p>\n<\/p>\n<p><p>On est donc conduit \u00e0 penser comme \u00e0 une \u00e9vidence du sens commun et de la perception sans entrave id\u00e9ologique qu&rsquo;en pr\u00e9sence d&rsquo;un tel \u00e9v\u00e9nement, d&rsquo;un tel bouquet d&rsquo;\u00e9v\u00e9nement transmutant le tourbillon crisique en GCES, d&rsquo;une telle dynamique de rupture, il appara&icirc;t en m\u00eame temps une nouvelle forme d&rsquo;antiSyst\u00e8me. Voil\u00e0 donc l&rsquo;hypoth\u00e8se fondamentale qui guide notre plume et nourrit notre pens\u00e9e (dans cet ordre, comme tout bon  <a href=\"https:\/\/www.dedefensa.org\/article\/ma-verite-de-situation\">logocrate<\/a>)&#8230;<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de situer le ph\u00e9nom\u00e8ne de l&rsquo;antiSyst\u00e8me par rapport \u00e0 son ontologie potentielle. A la relecture du <em>Glossaire.dde<\/em>, \u00e9clair\u00e9 bien entendu par la nouvelle phase de la Grande Crise, je crois qu&rsquo;il \u00e9tait pr\u00e9matur\u00e9 de laisser entendre, &ndash; car cela n&rsquo;est pas dit tout \u00e0 fait explicitement, &ndash; que la \u00ab\u00a0phase <em>The-Donald<\/em>\u00a0\u00bb constituait une \u00ab\u00a0ontologisation\u00a0\u00bb de l&rsquo;antiSyst\u00e8me (&laquo; [la fonction antiSyst\u00e8me]<em>s&rsquo;est \u00ab\u00a0ontologis\u00e9e\u00a0\u00bb, pourrait-on dire en se r\u00e9f\u00e9rant au mot grec initial [ontos : \u00eatre]<\/em> &raquo;). Trump n&rsquo;est pas une ontologisation de l&rsquo;antiSyst\u00e8me ; il a \u00e9t\u00e9 tr\u00e8s utile dans ce sens puisqu&rsquo;il a ouvert une nouvelle phase en \u00ab\u00a0personnalisant\u00a0\u00bb et en officialisant l&rsquo;antiSyst\u00e8me, il l&rsquo;est encore (moins souvent et de moins en moins souvent) mais il n&rsquo;est plus d\u00e9sormais \u00e0 la hauteur de la fonction antiSyst\u00e8me dans cette phase crisique o&ugrave; il se noie avec l&rsquo;industrie p\u00e9troli\u00e8re am\u00e9ricaniste. L&rsquo;antiSyst\u00e8me l&rsquo;a d\u00e9pass\u00e9 et, en le d\u00e9passant pour \u00eatre \u00e0 la hauteur de cette phase crisique, il s&rsquo;est lui-m\u00eame constitu\u00e9 en une nature diff\u00e9rente d&rsquo;une fonction. Alors que le Syst\u00e8me se d\u00e9compose litt\u00e9ralement, l&rsquo;antiSyst\u00e8me s&rsquo;affirme partout dans une forme sp\u00e9cifique et, par cons\u00e9quent, trouve son ontologie.<\/p>\n<\/p>\n<p><p>Pour dire autrement, d\u00e9sormais tout le monde est ou sera antiSyst\u00e8me, et c&rsquo;est justement l\u00e0 qu&rsquo;est le probl\u00e8me car cette avanc\u00e9e d\u00e9cisive de l&rsquo;antiSyst\u00e8me ne r\u00e9sout pas la crise, dans le sens de la d\u00e9nouer, m\u00eame si elle la fait grandement progresser. Cette circonstance conduit \u00e0 poser le probl\u00e8me de la d\u00e9finition de l&rsquo;antiSyst\u00e8me \u00e0 l&rsquo;heure de son ontologisation. Ce n&rsquo;est pas mettre en cause l&rsquo;antiSyst\u00e8me qu&rsquo;\u00e9crire cela, parce qu&rsquo;il y a d\u00e9sormais une ontologie qui est une chose absolue et irr\u00e9versible ; c&rsquo;est mettre en cause la fonction d&rsquo;antiSyst\u00e8me, par rapport \u00e0 tous ceux qui d\u00e9sormais s&rsquo;en r\u00e9clament, dont parmi eux la cohorte de vieux guerriers des \u00ab\u00a0antiSyst\u00e8me de l&rsquo;extr\u00eame\u00a0\u00bb (ou \u00ab\u00a0antiSyst\u00e8me nihilistes\u00a0\u00bb) qui sont \u00e0 l&rsquo;ouvrage depuis si longtemps.<\/p>\n<\/p>\n<p><p>Comment d\u00e9crire ce sentiment que le Syst\u00e8me se d\u00e9compose et que l&rsquo;antiSyst\u00e8me acquiert une ontologie irr\u00e9sistible ? L&rsquo;\u00e9vidence de la chose devrait y suffire, et disons, pour prendre un commentateur ext\u00e9rieur, que les cinq premiers paragraphes de l&rsquo;analyse  <a href=\"http:\/\/charleshughsmith.blogspot.com\/2020\/04\/whats-collapsing-cant-be-saved-our.html\">du 21 avril<\/a> de Charles Hugh Smith font l&rsquo;affaire ; cela est dit, qui plus est, sur le ton du lieu-commun \u00ab\u00a0Plus rien ne sera jamais comme avant\u00a0\u00bb qui irrite tant, dans la cat\u00e9gorie des \u00ab\u00a0antiSyst\u00e8me de l&rsquo;extr\u00eame\u00a0\u00bb, les originaux non-conformistes du nihilisme et les esprits forts qui grillent les feux rouges pour \u00e9viter les lieux communs&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Pour changer un peu de style, que diriez-vous de parler franchement et honn\u00eatement de l&rsquo;\u00e9conomie am\u00e9ricaine ? C&rsquo;est difficile \u00e0 faire car nous avons choisi d&rsquo;ignorer toutes les r\u00e9alit\u00e9s, un peu comme une famille qui cache les d\u00e9pendances, l&rsquo;ivresse et les mensonges dans un m\u00e9nage dysfonctionnel pour maintenir l&rsquo;illusion ext\u00e9rieure d&rsquo;une famille heureuse qui fonctionne.<\/em><\/p>\n<p>&raquo; <em>Il est extraordinairement co&ucirc;teux de maintenir une mascarade aussi exigeante. Le bilan psychologique est terrible et la ruine financi\u00e8re qui menace de faire s&rsquo;effondrer la fa\u00e7ade fragile alimente l&rsquo;adaptation des strat\u00e9gies les plus destructrices.<\/em><\/p>\n<p>&raquo; <em>Ne pr\u00e9tendez pas que papa et maman ne sont pas vraiment des drogu\u00e9s, accros au mensonge, trichant et volant pour financer leur corruption et maintenir l&rsquo;absurde fa\u00e7ade de la normalit\u00e9 d&rsquo;une histoire heureuse.<\/em><\/p>\n<p>&raquo; <em>&Ecirc;tre honn\u00eate est douloureux mais lib\u00e9rateur. Une fois que toute la laideur est expos\u00e9e \u00e0 la lumi\u00e8re du soleil, la gu\u00e9rison devient possible. Tant que la r\u00e9alit\u00e9 est masqu\u00e9e, cach\u00e9e, expliqu\u00e9e, etc., la destruction ne fait que s&rsquo;aggraver jusqu&rsquo;\u00e0 ce que l&rsquo;effondrement complet de la mascarade soit la seule issue possible.<\/em><\/p>\n<p>&raquo; <em>Nous sommes arriv\u00e9s \u00e0 ce point : nous ne pouvons plus nier que l&rsquo;\u00e9conomie am\u00e9ricaine n&rsquo;est gu\u00e8re plus qu&rsquo;un ramassis d&rsquo;escroqueries, d&rsquo;arnaques, de filouteries, de fraudes et de corruptions diverses. M\u00eame si Covid-19 disparaissait de la Terre demain, ou si toute l&rsquo;\u00e9conomie se redressait demain, l&rsquo;effondrement de la bulle de la fraude ne pourrait pas \u00eatre invers\u00e9, pas plus qu&rsquo;on ne peut \u00ab\u00a0gu\u00e9rir\u00a0\u00bb le toxicomane avec un peu de maquillage pour masquer sa d\u00e9vastation et des v\u00eatements propres pour cacher toutes les plaies infect\u00e9es des piqures dans son avant-bras<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cela n&rsquo;implique \u00e9videmment pas que la bataille est finie mais qu&rsquo;elle passe dans une phase nouvelle, dont l&rsquo;essentiel se d\u00e9roulera au sein de l&rsquo;antiSyst\u00e8me puisqu&rsquo;effectivement cette forme d\u00e9sormais tr\u00e8s puissante semble dominer le jeu et le sentiment g\u00e9n\u00e9ral. Ainsi, parmi les plus redoutables combattants d&rsquo;arri\u00e8re-garde du Syst\u00e8me, on trouve ceux que j&rsquo;ai d\u00e9sign\u00e9s comme &laquo; <em>les \u00ab\u00a0antiSyst\u00e8me de l&rsquo;extr\u00eame\u00a0\u00bb (ou \u00ab\u00a0antiSyst\u00e8me nihilistes\u00a0\u00bb) qui sont \u00e0 l&rsquo;ouvrage depuis si longtemps<\/em> &raquo;. (Peut-\u00eatre dirait-on qu&rsquo;il s&rsquo;agit d'\u00a0\u00bbantiSyst\u00e8me r\u00e9volutionnaire\u00a0\u00bb, accomplissant une r\u00e9volution spatiale, avec d\u00e9part du Syst\u00e8me pour en revenir \u00e0 ce qu&rsquo;il reste du Syst\u00e8me ?)<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit de ceux-l\u00e0 qui, en s&rsquo;affirmant antiSyst\u00e8me de l&rsquo;au-del\u00e0 de l&rsquo;antiSyst\u00e8me qui ne peut \u00eatre confondu avec l&rsquo;antiSyst\u00e8me courant et na\u00eff, vous disent que, de toutes les fa\u00e7ons, le Syst\u00e8me sera vainqueur parce qu&rsquo;il est tellement fort. Ils vous le disent sur un ton lugubre et catastroph\u00e9, mais aussi avec une pointe de joie sarcastique et persifleuse qui n&rsquo;est pas pour susciter dans mon chef une tr\u00e8s grande estime pour eux. Argumentez-vous que le Syst\u00e8me s&rsquo;effondre ? Si c&rsquo;est l&rsquo;\u00e9vidence, ils vous r\u00e9pondront, avec un ton condescendant et un bref rire sarcastique quoique nerveux, que c&rsquo;est pour mieux vous tromper et vous attirer dans quelque traquenard odieux. <\/p>\n<\/p>\n<p><p>(On disait la m\u00eame chose dans les ann\u00e9es1985-1990, je m&rsquo;en rappelle bien. Lorsque Gorbatchev alignait ses mesures unilat\u00e9rales, &ndash; retrait de forces sovi\u00e9tiques des pays satellites, toute libert\u00e9 laiss\u00e9e \u00e0 ces pays satellites de se transformer, g\u00e9n\u00e9ralisation de la libert\u00e9 de parole [<em>glasnost<\/em>] en URSS, etc., &ndash; l&rsquo;interpr\u00e9tation de cette sorte de gens \u00e9tait qu&rsquo;il s&rsquo;agissait d&rsquo;une ruse, de la ruse supr\u00eame du KGB : abandonner l&rsquo;Empire, le d\u00e9sint\u00e9grer pour faire croire que l&rsquo;URSS n&rsquo;est plus un Empire, &ndash; alors, hein, ne pas tomber dans le pi\u00e8ge !)<\/p>\n<\/p>\n<p><p>Tout cela d\u00e9crit implicitement les difficult\u00e9s de la situation actuelle, qui se trouvent plus que jamais dans le chaos courant et par cons\u00e9quent la difficult\u00e9 d&rsquo;identifier ses amis et ses adversaires, &ndash; cela, malgr\u00e9 la \u00ab\u00a0reconnaissance faciale\u00a0\u00bb, la \u00ab\u00a0dictature num\u00e9rique\u00a0\u00bb, la \u00ab\u00a0tyrannie polici\u00e8re-sanitaire\u00a0\u00bb et toute cette sorte de promesses qu&rsquo;ion nous fait d&rsquo;un terrible avenir fort bien rang\u00e9 dans les oubliettes du Diable.<\/p>\n<\/p>\n<p><p>Au contraire, il n&rsquo;y a aucun rangement. L&rsquo;effondrement du Syst\u00e8me nous fait passer du d\u00e9sordre au chaos g\u00e9n\u00e9ral. Un signe de ce chaos est l&rsquo;attitude des zombieSyst\u00e8me et des antiSyst\u00e8me vis-\u00e0-vis des mesures \u00e0 prendre dans le cas crisique de Covid19, mesures qui ont \u00e9t\u00e9 imm\u00e9diatement \u00ab\u00a0politis\u00e9es\u00a0\u00bb selon les normes de notre \u00e9trange \u00e9poque. Les partisans du \u00ab\u00a0confinement\u00a0\u00bb (sanitaire d&rsquo;abord) et les partisans du \u00ab\u00a0d\u00e9confinement\u00a0\u00bb (\u00e9conomie d&rsquo;abord) se recrutent dans les deux camps et dans une absence chaotique de sens, sinon au sein de complots sans fin, &ndash; Syst\u00e8me et antiSyst\u00e8me car l&rsquo;on n&rsquo;est pas chien, &ndash; dont on trouve la trace aussi bien dans la d\u00e9cision du \u00ab\u00a0confinement\u00a0\u00bb (et de son maintien) que dans la d\u00e9cision du \u00ab\u00a0d\u00e9confinement\u00a0\u00bb, sinon dans l&rsquo;existence ou pas de Covid19, sinon dans l&rsquo;existence ou pas de la mort elle-m\u00eame, sinon&#8230; etc&#8230;<\/p>\n<\/p>\n<p><p>(Voyez un affrontement entre deux antiSyst\u00e8me pur-jus sur la question du \u00ab\u00a0confinement\u00a0\u00bb, entre <em>The MoonofAlabama <\/em>[MoA] et <em>OffGuardian<\/em>, repris <a href=\"https:\/\/www.moonofalabama.org\/2020\/04\/it-is-not-authoritarian-to-support-quarantine-measures-it-just-makes-sense.html#more\">par MoA<\/a>, publi\u00e9 en adaptation fran\u00e7aise par Le <em><a href=\"https:\/\/lesakerfrancophone.fr\/jjla-quarantaine-nest-pas-autoritaire-juste-sensee\">Sakerfrancophone<\/a><\/em>&#8230; Devinez de quel c\u00f4t\u00e9 je me trouve ?)<\/p>\n<\/p>\n<p><p>Effectivement, tout le monde devient antiSyst\u00e8me et chacun se dit \u00eatre antiSyst\u00e8me dans ce chaos puisque le Syst\u00e8me dans son propre d\u00e9sordre devient ruines &#038; poussi\u00e8res. Il reste \u00e0 lib\u00e9rer les psychologies, ce qui n&rsquo;est pas la moindre des t\u00e2ches, tant il y a chez <em>Sapiens-Sapiens <\/em>le go&ucirc;t de la servilit\u00e9, non pour s&rsquo;y complaire mais pour pouvoir la d\u00e9noncer. Ce n&rsquo;est pas la \u00ab\u00a0servilit\u00e9 volontaire\u00a0\u00bb, qui est une id\u00e9e-juste du temps o&ugrave; elle fut dite (La Bo\u00e9tie), c&rsquo;est-\u00e0-dire une id\u00e9e de moderniste de la Renaissance qui s&rsquo;est lass\u00e9 de la Tradition Primordiale dans laquelle il voit des cha&icirc;nes contraignantes bien plus que des principes vitaux ; c&rsquo;est plut\u00f4t la \u00ab\u00a0servilit\u00e9 comme objet de haine\u00a0\u00bb, qui est une id\u00e9e de nos temps \u00e9tranges pour ceux qui respirent d&rsquo;abord avec la haine au ventre : si la servilit\u00e9 n&rsquo;existe plus, m\u00eame remplac\u00e9e par le chaos, que leur reste-t-il \u00e0 ha\u00efr pour s&rsquo;en lib\u00e9rer et se d\u00e9clarer libres, ces pauvres esprits qui ne peuvent se juger libres que si la servilit\u00e9 existe ?<\/p>\n<\/p>\n<p><p>Pour le reste, c&rsquo;est-\u00e0-dire le redressement n\u00e9cessairement promis par la Fin du Cycle et l&rsquo;Apocalypse, nous saurons de quoi il s&rsquo;agit lorsque les forces du Ciel associ\u00e9es aux dieux auront d\u00e9cid\u00e9 qu&rsquo;ils nous soit permis qu&rsquo;il se fasse.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De l&rsquo;ontologie de l&rsquo;antiSyst\u00e8me 23 avril 2020 &ndash; C&rsquo;est un mot, une expression, un n\u00e9ologisme, etc. et que sais-je, qui a une r\u00e9elle fortune depuis quelques ann\u00e9es. Il faut dire qu&rsquo;il d\u00e9signe une cat\u00e9gorie de personnes et d&rsquo;actes d&rsquo;une tr\u00e8s grande importance correspondant \u00e0 la nouvelle situation que nous connaissons notamment depuis 9\/11, et jusqu&rsquo;ici&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[7029,3238,17879,2631,2651,2803,5428,19830,9187,11306,4079,4457,3014,2639,11216],"class_list":["post-79232","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-assassinat","tag-charles","tag-covid19","tag-de","tag-du","tag-effondrement","tag-hugh","tag-lantisysteme","tag-metahistorique","tag-ontologie","tag-servilite","tag-smith","tag-systeme","tag-trump","tag-volontaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79232"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79232\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}