{"id":79253,"date":"2020-05-08T09:11:48","date_gmt":"2020-05-08T09:11:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/05\/08\/detournement-cognitif-de-covid19\/"},"modified":"2020-05-08T09:11:48","modified_gmt":"2020-05-08T09:11:48","slug":"detournement-cognitif-de-covid19","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/05\/08\/detournement-cognitif-de-covid19\/","title":{"rendered":"D\u00e9tournement cognitif de Covid19"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">D\u00e9tournement cognitif de Covid19<\/h2>\n<\/p>\n<p><p>Ces derniers jours, je me suis retenu de commenter les \u00e9v\u00e9nements actuels, qui tournent tous autour de la panique li\u00e9e au nouveau coronavirus, et de faire autant de recherches que possible parce que le fond de ce qui se passe n&rsquo;est pas clair pour moi.<\/p>\n<\/p>\n<p><p>Pourquoi arr\u00eater l&rsquo;\u00e9conomie mondiale \u00e0 cause d&rsquo;un virus qui n&rsquo;est pas particuli\u00e8rement dangereux et qui n&rsquo;a \u00e9t\u00e9 responsable que d&rsquo;un peu plus de 1% des d\u00e9c\u00e8s jusqu&rsquo;\u00e0 pr\u00e9sent cette ann\u00e9e et qui n&rsquo;a touch\u00e9 que 0,04% de la population et n&rsquo;en a tu\u00e9 que 0,0028% ?<\/p>\n<\/p>\n<p><p>&bull; Pourquoi mettre en quarantaine des personnes en bonne sant\u00e9 au lieu de mettre en quarantaine uniquement les personnes \u00e2g\u00e9es et les malades (en Su\u00e8de, pour prendre un exemple typique, 90% des cas mortels se trouvaient parmi les personnes de plus de 70 ans) ?<\/p>\n<\/p>\n<p><p>&bull; Pourquoi fermer les \u00e9coles et enfermer les enfants \u00e0 l&rsquo;int\u00e9rieur s&rsquo;ils ne tombent m\u00eame pas malades \u00e0 cause de ce virus ?<\/p>\n<\/p>\n<p><p>&bull; Pourquoi dire aux gens de rester \u00e0 l&rsquo;int\u00e9rieur alors que le manque de soleil, d&rsquo;exercice et d&rsquo;exposition \u00e0 une grande vari\u00e9t\u00e9 d&rsquo;antig\u00e8nes entra&icirc;ne un affaiblissement du syst\u00e8me immunitaire et des taux d&rsquo;infection plus \u00e9lev\u00e9s ?<\/p>\n<\/p>\n<p><p>&bull; Pourquoi lutter pour cr\u00e9er un vaccin et vacciner tout le monde alors que ce virus se trouve \u00eatre un inoculant s&ucirc;r, efficace et librement disponible contre lui-m\u00eame pour la grande majorit\u00e9 des personnes en bonne sant\u00e9 ?<\/p>\n<\/p>\n<p><p>&bull; Pourquoi mettre l&rsquo;accent sur la ventilation pulmonaire artificielle alors que (\u00e0 New York, par exemple) 80 % des patients qui sont branch\u00e9s \u00e0 des machines de traitement du VPA meurent ?<\/p>\n<\/p>\n<p><p>&bull; Pourquoi dire \u00e0 tout le monde de porter un masque facial alors qu&rsquo;il n&rsquo;arr\u00eate que 95 % des particules virales (au mieux) et ainsi retarder le temps n\u00e9cessaire pour \u00eatre infect\u00e9 de 10 secondes \u00e0 trois minutes au maximum ?<\/p>\n<\/p>\n<p><p>Apr\u00e8s quelques recherches et r\u00e9flexions, j&rsquo;ai pu arriver \u00e0 une r\u00e9ponse unique \u00e0 toutes ces questions. Mais d&rsquo;abord, examinons certaines d&rsquo;entre elles.<\/p>\n<\/p>\n<p><p>Tout d&rsquo;abord, abordons la question de la  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Controverse_sur_la_vaccination\">vaccination<\/a>. Il existe un vaccin contre la rougeole, mais elle tue 140 000 personnes par an. Il existe un vaccin contre le pneumocoque, mais il tue entre 2 et 2,5 millions de personnes par an. Il existe un vaccin contre l&rsquo;h\u00e9patite B, mais elle tue 140 000 personnes. Il existe un vaccin contre le t\u00e9tanos, mais il tue 89 000 personnes par an. Il existe un vaccin contre le rotavirus, mais il tue 800 000 personnes. Il existe un vaccin contre le  <a href=\"https:\/\/vaccination-info-service.fr\/Les-maladies-et-leurs-vaccins\/Infections-a-Papillomavirus-humains-HPV\">HPV<\/a>, mais il tue 250 000 personnes. Il existe un vaccin contre la tuberculose, mais elle tue 1,5 million de personnes. Il existe un vaccin contre la grippe, mais elle tue entre 650 000 et 1 million de personnes par an. Aucun de ces d\u00e9c\u00e8s n&rsquo;est consid\u00e9r\u00e9 comme une pand\u00e9mie, n&rsquo;entra&icirc;ne la fermeture d&rsquo;\u00e9conomies enti\u00e8res ou ne n\u00e9cessite de mesures extraordinaires.<\/p>\n<\/p>\n<p><p>Et puis il y a le nouveau coronavirus qui a tu\u00e9 218 187 personnes \u00e0 ce jour (la grande majorit\u00e9 d&rsquo;entre elles \u00e9tant tr\u00e8s \u00e2g\u00e9es et\/ou tr\u00e8s malades) &ndash; et on consid\u00e8re que c&rsquo;est un probl\u00e8me \u00e0 r\u00e9soudre avec toute la h\u00e2te possible. Certains experts en maladies infectieuses ont sugg\u00e9r\u00e9 que toute la population pourrait \u00eatre oblig\u00e9e de se confiner en attendant qu&rsquo;un vaccin soit disponible. En attendant, les d\u00e9c\u00e8s dus au nouveau coronavirus s&rsquo;inscrivent largement dans le cadre de la mortalit\u00e9 habituelle de la saison de la grippe. L&rsquo;hiver dans l&rsquo;h\u00e9misph\u00e8re nord a \u00e9t\u00e9 plus chaud que d&rsquo;habitude, et le nouveau coronavirus a provoqu\u00e9 la mort de certaines personnes \u00e2g\u00e9es et malades qui auraient \u00e9t\u00e9 tu\u00e9es par l&rsquo;un des virus grippaux habituels (y compris d&rsquo;autres coronavirus) au cours de l&rsquo;une des trois saisons de la grippe pr\u00e9c\u00e9dentes.<\/p>\n<\/p>\n<p><p>Mais m\u00eame cela est incertain car on ne sait pas si ces 218 187 d\u00e9c\u00e8s ont \u00e9t\u00e9 r\u00e9ellement caus\u00e9s par le coronavirus ou si le coronavirus \u00e9tait simplement pr\u00e9sent dans leur corps au moment du d\u00e9c\u00e8s. En outre, de nombreuses personnes ont \u00e9t\u00e9 diagnostiqu\u00e9es comme souffrant de ce coronavirus sur la base de sympt\u00f4mes qui ne sont pas trop diff\u00e9rents de ceux caus\u00e9s par d&rsquo;autres agents viraux. Enfin, la grande majorit\u00e9 des personnes qui en sont mortes pr\u00e9sentaient ce que l&rsquo;on appelle des comorbidit\u00e9s. Les personnes \u00e2g\u00e9es immunod\u00e9prim\u00e9es, les diab\u00e9tiques ob\u00e8ses morbides souffrant d&rsquo;hypertension, de cancer et d&rsquo;autres affections potentiellement mortelles ont \u00e9t\u00e9 particuli\u00e8rement sensibles. Si vous \u00e9cartez tous les cas mortels de comorbidit\u00e9s et que vous ne prenez en compte que les jeunes en bonne sant\u00e9, le nombre de d\u00e9c\u00e8s dont le nouveau coronavirus est manifestement la cause premi\u00e8re peut s&rsquo;av\u00e9rer aussi bas que z\u00e9ro.<\/p>\n<\/p>\n<p><p>Les cas confirm\u00e9s de nouveaux coronavirus sont moins de 3 147 626 dans le monde, soit 0,04 % de la population mondiale. Cela correspond \u00e0 peine \u00e0 une toux et un \u00e9ternuement. Avec la propagation de ce virus dans le monde, l&rsquo;augmentation du nombre de cas a ralenti, mais le nombre de cas confirm\u00e9s pourrait encore doubler, voire tripler, ce qui repr\u00e9sente jusqu&rsquo;\u00e0 trois toux et trois \u00e9ternuements. Mais c&rsquo;est alors que l&rsquo;Organisation mondiale de la sant\u00e9 entre en jeu. L&rsquo;OMS utilise gratuitement des appellations telles que \u00ab\u00a0monde\u00a0\u00bb et \u00ab\u00a0sant\u00e9\u00a0\u00bb, mais elle est en fait une entit\u00e9 semi-priv\u00e9e, richement financ\u00e9e par Bill Gates et Big Pharma, qui est d\u00e9tenue par une poign\u00e9e d&rsquo;entit\u00e9s oligarchiques tr\u00e8s proches les unes des autres, dont Vanguard, BlackRock, Capital Group, Morgan Stanley, Goldman Sachs, Northern Trust et State Street, qui \u00e0 leur tour se poss\u00e8dent mutuellement de diverses mani\u00e8res alambiqu\u00e9es. La principale fonction de l&rsquo;OMS est d&rsquo;effrayer les gens pour qu&rsquo;ils se fassent vacciner et acceptent des r\u00e9gimes m\u00e9dicamenteux co&ucirc;teux (dont au moins la moiti\u00e9 ne servent \u00e0 rien), canalisant ainsi les ressources vers les grandes entreprises pharmaceutiques.<\/p>\n<\/p>\n<p><p>L&rsquo;Organisation mondiale de la sant\u00e9 \u00e9tablit des seuils pour d\u00e9terminer s&rsquo;il faut d\u00e9clarer comme \u00e9pid\u00e9mie une grippe qui touche entre 2,5 % et 5% de la population. Le nouveau coronavirus rate cette cible de beaucoup, mais l&rsquo;OMS a d\u00e9clar\u00e9 qu&rsquo;il \u00e9tait \u00e0 l&rsquo;origine d&rsquo;une pand\u00e9mie mondiale. Si cela semble \u00eatre une r\u00e9action excessive extr\u00eame, c&rsquo;est qu&rsquo;il s&rsquo;agit d&rsquo;une r\u00e9action excessive extr\u00eame. Certaines personnes ayant l&rsquo;esprit conspirationniste peuvent supposer qu&rsquo;il s&rsquo;agit d&rsquo;une conspiration, mais ce n&rsquo;est pas le cas. Il s&rsquo;agit d&rsquo;une nouvelle tentative flagrante de confisquer une partie de la richesse mondiale en exigeant qu&rsquo;elle ach\u00e8te quelque chose qui n&rsquo;a aucune valeur, tout comme cet ensemble d&rsquo;int\u00e9r\u00eats m\u00e9dicaux\/financiers l&rsquo;ont fait avec le m\u00e9dicament antiviral Tamiflu, relativement sans valeur, lors de la pand\u00e9mie de grippe porcine H1N1 de 2009-2010, qui n&rsquo;a caus\u00e9 que 18 036 d\u00e9c\u00e8s dans le monde. Il s&rsquo;agit d&rsquo;un cas sp\u00e9cifique qui permet la poursuite par un groupe de ses propres int\u00e9r\u00eats.<\/p>\n<\/p>\n<p><p>Il existe d&rsquo;autres int\u00e9r\u00eats disparates qui poursuivent leurs propres objectifs en luttant (ou en essayant, ou en faisant semblant de lutter) contre l&rsquo;horrible, terrible et nouveau fl\u00e9au mondial des coronavirus qui pourrait facilement emporter 0,005% de la population mondiale et jusqu&rsquo;\u00e0 0,05% des septuag\u00e9naires de la plan\u00e8te.<\/p>\n<\/p>\n<p><p>Les Chinois ont saisi l&rsquo;occasion de l&rsquo;\u00e9pid\u00e9mie de ce nouveau coronavirus pour s&rsquo;entra&icirc;ner \u00e0 repousser une attaque de guerre biologique. Pr\u00e9tendre que ce coronavirus est effectivement l&rsquo;agent d&rsquo;une attaque de guerre biologique revient \u00e0 d\u00e9fendre quelque chose d&rsquo;extr\u00eamement stupide, car il n&rsquo;est tout simplement pas efficace en tant qu&rsquo;agent de guerre biologique. Il est presque aussi mauvais que le Novichok, dont on disait qu&rsquo;il pouvait an\u00e9antir des arm\u00e9es enti\u00e8res, mais qui n&rsquo;a r\u00e9ussi \u00e0 rendre malades que cinq personnes et \u00e0 en tuer une seule. Peu importe que ce coronavirus se soit \u00e9chapp\u00e9 d&rsquo;une chauve-souris morte ou d&rsquo;un laboratoire de guerre biologique, ou des deux &ndash; il n&rsquo;est tout simplement pas bon comme arme. Mais le gouvernement chinois a impos\u00e9 des contr\u00f4les extr\u00eames, sans pr\u00e9c\u00e9dent, sur une grande partie de la population et de l&rsquo;\u00e9conomie. Les Russes ont suivi, \u00e0 la diff\u00e9rence que si les Chinois ont consid\u00e9r\u00e9 ces mesures extr\u00eames comme temporaires, en mettant en place des h\u00f4pitaux de fortune, les Russes les ont saisies comme une chance d&rsquo;am\u00e9liorer fondamentalement l&rsquo;ensemble du syst\u00e8me de soins de sant\u00e9, en le mettant en place pour g\u00e9rer efficacement toute future attaque de guerre biologique.<\/p>\n<\/p>\n<p><p>Ce faisant, les Chinois et les Russes ont poursuivi des objectifs diff\u00e9rents. Les Chinois doivent trouver un moyen d&rsquo;arr\u00eater d&rsquo;exp\u00e9dier de v\u00e9ritables produits manufactur\u00e9s physiques aux &Eacute;tats-Unis en \u00e9change de morceaux de papier ou de promesses de paiement, qui sont tous sur le point de devenir sans valeur, sans d\u00e9clencher une dangereuse escalade. La n\u00e9cessit\u00e9 de le faire avec toute la h\u00e2te n\u00e9cessaire est devenue \u00e9vidente \u00e0 la mi-ao&ucirc;t 2019, lorsqu&rsquo;il s&rsquo;est av\u00e9r\u00e9 que les banques ne voulaient plus accepter les titres de cr\u00e9ance du Tr\u00e9sor am\u00e9ricain comme garantie pour les pr\u00eats au jour le jour. Il s&rsquo;agissait soi-disant des investissements les plus s&ucirc;rs au monde qui constituaient le march\u00e9 financier le plus important et le plus liquide du monde &ndash; jusqu&rsquo;\u00e0 ce qu&rsquo;il s&rsquo;av\u00e8re qu&rsquo;ils ne l&rsquo;\u00e9taient plus.<\/p>\n<\/p>\n<p><p>Les exportations de la Chine vers les &Eacute;tats-Unis repr\u00e9sentaient environ 20% de ses exportations totales, et ce chiffre devait \u00eatre r\u00e9duit. Alors que l&rsquo;Occident tout entier se dirige vers une r\u00e9cession \u00e9conomique majeure, la Chine a \u00e9galement d&ucirc; r\u00e9orienter partiellement son \u00e9conomie en abandonnant les exportations au profit de l&rsquo;investissement et de la consommation de capitaux int\u00e9rieurs. La panique mondiale et la relance \u00e9conomique provoqu\u00e9es par le nouveau coronavirus ont contribu\u00e9 \u00e0 r\u00e9duire la d\u00e9pendance de la Chine \u00e0 l&rsquo;\u00e9gard des &Eacute;tats-Unis tout en se cachant derri\u00e8re l&rsquo;\u00e9cran de fum\u00e9e d&rsquo;un incident de force majeur plausible.<\/p>\n<\/p>\n<p><p>Les objectifs de la Russie pour alimenter la panique provoqu\u00e9e par le coronavirus sont quelque peu diff\u00e9rents de ceux de la Chine. Contrairement \u00e0 la Chine, dont l&rsquo;affrontement militaire avec les &Eacute;tats-Unis s&rsquo;est limit\u00e9 \u00e0 des positions autour des routes maritimes et au contr\u00f4le des &icirc;les Spratley, la Russie a \u00e9t\u00e9 contrainte de faire face \u00e0 une tentative plus s\u00e9rieuse du Pentagone de relancer la guerre froide. Des troupes de l&rsquo;OTAN ont organis\u00e9 des exercices d&rsquo;entra&icirc;nement \u00e0 port\u00e9e d&rsquo;artillerie de la deuxi\u00e8me ville de Russie, des instructeurs de l&rsquo;OTAN ont form\u00e9 et arm\u00e9 des nazis ukrainiens qui bombardent des d\u00e9tenteurs de passeports russes habitant les parties orientales de la r\u00e9gion ukrainienne, et le Pentagone a mis en place et fait fonctionner plusieurs laboratoires de guerre biologique am\u00e9ricains dans certains des pays voisins de la Russie.<\/p>\n<\/p>\n<p><p>&Agrave; l&rsquo;heure actuelle, aucune guerre nucl\u00e9aire ou conventionnelle entre la Russie et les &Eacute;tats-Unis n&rsquo;est probable. Les &Eacute;tats-Unis n&rsquo;ont jamais d\u00e9velopp\u00e9 la capacit\u00e9 de gagner un conflit nucl\u00e9aire avec la Russie en utilisant une premi\u00e8re frappe pr\u00e9ventive et les &Eacute;tats-Unis ne pourraient m\u00eame pas r\u00eaver de conqu\u00e9rir la Russie dans une guerre terrestre. La guerre biologique reste donc la seule ligne de conduite possible pour le Pentagone s&rsquo;il d\u00e9cide d&rsquo;attaquer la Russie, et les Russes semblent avoir pris cette menace tr\u00e8s au s\u00e9rieux. En r\u00e9ponse, les &Eacute;tats-Unis ont fait preuve d&rsquo;une f\u00e9brilit\u00e9 abjecte face \u00e0 la pand\u00e9mie de coronavirus, au point d&rsquo;\u00eatre contraints d&rsquo;accepter l&rsquo;aide humanitaire russe achemin\u00e9e par avion de transport militaire, pour ne rien arranger.<\/p>\n<\/p>\n<p><p>Alors que la Chine doit r\u00e9soudre le probl\u00e8me de la r\u00e9orientation de ses flux d&rsquo;exportation pour s&rsquo;\u00e9loigner des &Eacute;tats-Unis, qui sont sur une trajectoire de faillite rapide, et de liquidation de sa r\u00e9serve de papier financier libell\u00e9 en dollars, la Russie n&rsquo;a pas de tels probl\u00e8mes, puisqu&rsquo;elle fait tr\u00e8s peu de commerce avec les &Eacute;tats-Unis et a liquid\u00e9 ses r\u00e9serves libell\u00e9es en dollars. Toutefois, malgr\u00e9 les efforts d\u00e9ploy\u00e9s pour diversifier ses relations commerciales, elle continue \u00e0 faire beaucoup de commerce avec l&rsquo;UE, qui est en pleine crise. Gr\u00e2ce aux sanctions occidentales qui lui ont \u00e9t\u00e9 impos\u00e9es en 2014 \u00e0 l&rsquo;occasion de sa r\u00e9unification avec la Crim\u00e9e, ainsi qu&rsquo;aux contre-sanctions qui ont suivi, elle a mis en &oelig;uvre une politique r\u00e9ussie de remplacement des importations. Maintenant que les \u00e9conomies occidentales sont en faillite, elle doit \u00e9galement mettre en &oelig;uvre une politique de remplacement des exportations, en r\u00e9orientant les flux de ressources et de production vers la consommation int\u00e9rieure, en adoptant davantage le concept d&rsquo;autarcie limit\u00e9e. Ce n&rsquo;est pas une t\u00e2che mineure, et le coronavirus fournit un \u00e9cran de fum\u00e9e utile derri\u00e8re lequel l&rsquo;\u00e9conomie peut \u00eatre mise en mode manuel, de sorte que le gouvernement puisse diriger efficacement le processus de transformation de l&rsquo;\u00e9conomie.<\/p>\n<\/p>\n<p><p>Si la Chine et la Russie semblent pouvoir trouver des utilisations constructives \u00e0 la pand\u00e9mie de coronavirus, ses fonctions pour l&rsquo;UE et pour les &Eacute;tats-Unis semblent enti\u00e8rement destructrices pour ces deux entit\u00e9s politiques. Dans le cas de l&rsquo;UE, la pand\u00e9mie a donn\u00e9 aux nations constitutives une chance de r\u00e9affirmer leur souverainet\u00e9, tandis que la bureaucratie centrale \u00e0 Bruxelles s&rsquo;est r\u00e9v\u00e9l\u00e9e incapable de toute r\u00e9ponse constructive, fermant tardivement les fronti\u00e8res de l&rsquo;UE m\u00eame apr\u00e8s que la plupart des pays l&rsquo;aient d\u00e9j\u00e0 fait de leur propre chef. Le sentiment anti-europ\u00e9en monte en Italie et ailleurs, et il commence \u00e0 sembler plus probable que le Brexit ait d\u00e9clench\u00e9 l&rsquo;effet domino de sorties de l&rsquo;UE par d&rsquo;autres pays. Cela permettra \u00e0 divers pays europ\u00e9ens de se lib\u00e9rer du joug des \u00ab\u00a0valeurs europ\u00e9ennes universelles\u00a0\u00bb et de trouver leur propre voie en formulant des politiques plus saines sur des questions telles que la migration et en n\u00e9gociant des relations commerciales bilat\u00e9rales \u00e0 l&rsquo;int\u00e9rieur et \u00e0 l&rsquo;ext\u00e9rieur de l&rsquo;Europe.<\/p>\n<\/p>\n<p><p>Aux &Eacute;tats-Unis, la pand\u00e9mie est utilis\u00e9e pour poursuivre une sorte de guerre civile, les D\u00e9mocrates essayant de l&rsquo;utiliser, avec le crash \u00e9conomique qui se d\u00e9roule de pair, pour d\u00e9tr\u00f4ner Trump et le remplacer par un autre cadavre politique. Pendant ce temps, les dirigeants des diff\u00e9rents &Eacute;tats trouvent de moins en moins de terrain d&rsquo;entente avec les autorit\u00e9s f\u00e9d\u00e9rales et s&#8217;emparent de plus en plus de pouvoir politique pour eux-m\u00eames, tout en pr\u00e9voyant de suivre des voies diff\u00e9rentes.<\/p>\n<\/p>\n<p><p>La liste des acteurs qui utilisent la pand\u00e9mie de coronavirus pour leurs objectifs tr\u00e8s diff\u00e9rents et souvent contradictoires peut \u00eatre \u00e9tendue pratiquement \u00e0 l&rsquo;infini. Mais qu&rsquo;en est-il si nous essayons d&rsquo;exclure le terme commun, pour utiliser une m\u00e9taphore math\u00e9matique ? Quel facteur appara&icirc;t dans chaque terme de l&rsquo;\u00e9quation et peut donc \u00eatre d\u00e9plac\u00e9 en dehors des parenth\u00e8ses ? C&rsquo;est le facteur de contr\u00f4le absolu : restrictions de mouvement, restrictions de comportement, restrictions de ce que les entreprises peuvent exploiter, et tests m\u00e9dicaux constants.<\/p>\n<\/p>\n<p><p>Comme je l&rsquo;ai \u00e9crit dans mon livre &laquo; <em><a href=\"https:\/\/lesakerfrancophone.fr\/reduire-la-technosphere-note-de-lecture\">R\u00e9duire la Technosphere<\/a><\/em> &raquo;, <em>&laquo; La raison de prolonger la vie le plus longtemps possible, aussi peu logique soit-elle, se trouve dans la t\u00e9l\u00e9ologie abstraite du contr\u00f4le total. La contrainte de la technosph\u00e8re est de tout contr\u00f4ler. Il est inacceptable pour elle que les personnes \u00e2g\u00e9es d\u00e9cident seules du moment de leur mort. La mort ne peut pas \u00eatre laiss\u00e9e \u00e0 un jugement subjectif, elle doit \u00eatre le r\u00e9sultat objectif d&rsquo;un processus technique et mesurable. <\/em>&raquo;Dans ce livre, j&rsquo;ai d\u00e9fini la technosph\u00e8re comme <em>&laquo; &hellip;une intelligence mondiale \u00e9mergente qui d\u00e9teste toutes les formes de vie, aime la physique et la chimie, d\u00e9teste tout ce qu&rsquo;elle ne peut pas dominer ou contr\u00f4ler, est capable d&rsquo;utiliser les humains \u00e0 ses propres fins, mais est tout \u00e0 fait pr\u00eate \u00e0 les tuer quand ils ne sont plus n\u00e9cessaires ou quand ils se mettent en travers de son chemin, ce qu&rsquo;elle peut facilement faire parce que ses technologies les plus avanc\u00e9es et les plus efficaces sont ses technologies de mise \u00e0 mort &ndash; armes conventionnelles, nucl\u00e9aires et chimiques ; guerre bact\u00e9riologique ; et technologies politiques qui envoient les gens au combat<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>&Eacute;tant donn\u00e9 que la r\u00e9action excessivement dure au nouveau coronavirus est un ph\u00e9nom\u00e8ne mondial, l&rsquo;imposition de mesures de contr\u00f4le totalitaires peut \u00eatre consid\u00e9r\u00e9e comme la manifestation d&rsquo;une intelligence mondiale \u00e9mergente qui transcende les int\u00e9r\u00eats \u00e9troits d&rsquo;un pays ou d&rsquo;un groupe de pays mais suit un programme qui lui est propre. Qu&rsquo;est-ce qui pourrait pousser la technosph\u00e8re \u00e0 s&#8217;emporter de la sorte ?<\/p>\n<\/p>\n<p><p>Il existe deux processus mondiaux importants qui, s&rsquo;ils affecteront particuli\u00e8rement les &Eacute;tats-Unis, d\u00e9passent largement leurs fronti\u00e8res g\u00e9ographiques. Le premier est le processus encore relativement progressif de d\u00e9tr\u00f4nement du dollar am\u00e9ricain de sa position dominante. Jusqu&rsquo;\u00e0 ce que la pand\u00e9mie de coronavirus ne perturbe une grande partie de l&rsquo;\u00e9conomie mondiale, la plupart de ses participants \u00e9taient int\u00e9ress\u00e9s par la pr\u00e9servation d&rsquo;une certaine stabilit\u00e9 du syst\u00e8me dollar. Mais maintenant que les \u00e9changes commerciaux ont d\u00e9j\u00e0 \u00e9t\u00e9 perturb\u00e9s, une ouverture a \u00e9t\u00e9 cr\u00e9\u00e9e pour faire baisser le dollar sans n\u00e9cessairement causer de dommages \u00e9conomiques bien pires que ceux qui existent d\u00e9j\u00e0. Les actions de la R\u00e9serve f\u00e9d\u00e9rale, qui est en train de mon\u00e9tiser une grande partie de la dette publique am\u00e9ricaine existante et la quasi-totalit\u00e9 de la nouvelle dette \u00e9mise pour couvrir le d\u00e9ficit budg\u00e9taire sans cesse croissant, sapent \u00e9galement le dollar. Bien que l&rsquo;expression \u00ab\u00a0mon\u00e9tisation de la dette\u00a0\u00bb soit utilis\u00e9e pour d\u00e9crire ce qui se passe, l&rsquo;\u00e9mission d&rsquo;une monnaie avec laquelle on peut acheter des billets \u00e0 ordre sans valeur \u00e9tend la d\u00e9finition de la \u00ab\u00a0dette\u00a0\u00bb au-del\u00e0 de toute limite raisonnable, alors que la \u00ab\u00a0mon\u00e9tisation\u00a0\u00bb est un terme bien trop digne pour une tactique dilatoire aussi d\u00e9sesp\u00e9r\u00e9e. En cons\u00e9quence, certains analystes ne voient pas le syst\u00e8me financier mondial bas\u00e9 sur le dollar am\u00e9ricain tenir trop longtemps au-del\u00e0 de cette ann\u00e9e.<\/p>\n<\/p>\n<p><p>L&rsquo;autre processus est la transition rapide des &Eacute;tats-Unis du plus grand producteur mondial de p\u00e9trole \u00e0 l&rsquo;un des plus petits, parce que la manne de la fracturation a largement suivi son cours. Ce type de production n&rsquo;a jamais vraiment rapport\u00e9 d&rsquo;argent, car le p\u00e9trole issu de la fracturation hydraulique est, pour des raisons technologiques, toujours trop cher pour soutenir la croissance \u00e9conomique. Aujourd&rsquo;hui, alors qu&rsquo;une d\u00e9pression \u00e9conomique s&rsquo;installe, que les \u00e9conomies sont au point mort et que les contrats \u00e0 terme sur le p\u00e9trole se n\u00e9gocient en territoire n\u00e9gatif (o&ugrave; les acteurs du march\u00e9 sont pr\u00eats \u00e0 payer les producteurs pour ne pas prendre livraison du p\u00e9trole \u00e0 l&rsquo;\u00e9ch\u00e9ance du contrat), l&rsquo;industrie de la fracturation fait faillite, la production chute et, dans moins d&rsquo;un an, elle devrait avoir baiss\u00e9 de 70 %. &Agrave; ce moment-l\u00e0, toute tentative de reprise \u00e9conomique aux &Eacute;tats-Unis impliquera de commencer \u00e0 importer de grandes quantit\u00e9s de p\u00e9trole \u00e0 partir d&rsquo;un approvisionnement mondial qui, \u00e0 l&rsquo;exception du p\u00e9trole issu de cette fracturation aux &Eacute;tats-Unis, n&rsquo;a pas beaucoup augment\u00e9 depuis 2005.<\/p>\n<\/p>\n<p><p>De nouveau dans <em>&laquo; <a href=\"https:\/\/lesakerfrancophone.fr\/reduire-la-technosphere-note-de-lecture\">R\u00e9duire la Technosphere<\/a> <\/em>: &laquo;<em> Du point de vue de la technosph\u00e8re, la biosph\u00e8re est simplement l\u00e0 pour lui fournir des ressources et des services. Son point de vue sur la biosph\u00e8re d\u00e9montre le d\u00e9ficit mental frappant de la technosph\u00e8re : elle est incapable de voir les limites. Tant qu&rsquo;elle ne les rencontre pas, elle ne peut pas les voir, et suppose que les ressources naturelles sont infinies. Et lorsqu&rsquo;elle se heurte \u00e0 ces limites, elle traite invariablement le probl\u00e8me comme un probl\u00e8me financier. Par exemple, lorsque les prix du p\u00e9trole ont augment\u00e9, on a automatiquement suppos\u00e9 que le probl\u00e8me n&rsquo;avait rien \u00e0 voir avec l&rsquo;\u00e9puisement des ressources mais qu&rsquo;il \u00e9tait enti\u00e8rement d&ucirc; au manque d&rsquo;investissement dans l&rsquo;industrie p\u00e9troli\u00e8re. Certes, l&rsquo;augmentation des investissements a finalement entra&icirc;n\u00e9 une augmentation de la production et un march\u00e9 p\u00e9trolier satur\u00e9, mais le fait que l&rsquo;augmentation des investissements soit devenue n\u00e9cessaire avait tout \u00e0 voir avec l&rsquo;\u00e9puisement des ressources : les ressources qui pouvaient \u00eatre produites le moins cher ont \u00e9t\u00e9 les premi\u00e8res \u00e0 s&rsquo;\u00e9puiser. De plus, l&rsquo;effet de l&rsquo;augmentation des investissements est temporaire ; comme la rouille, l&rsquo;\u00e9puisement des ressources ne dort jamais, et \u00e0 un moment donn\u00e9, le niveau des d\u00e9penses n\u00e9cessaires pour maintenir la production devient incroyablement \u00e9lev\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Ici, je souhaite me corriger : la technosph\u00e8re peut en effet voir des limites physiques. En 2019, il semble que l&rsquo;on se soit rendu compte que la manne p\u00e9troli\u00e8re aux &Eacute;tats-Unis a pratiquement fait son temps et qu&rsquo;il ne serait plus possible d&rsquo;accro&icirc;tre l&rsquo;utilisation du p\u00e9trole, et donc l&rsquo;expansion \u00e9conomique. Mais un r\u00e9gime mondialis\u00e9 ne peut \u00eatre maintenu sans une expansion constante. La seule solution est que la technosph\u00e8re se fracture en zones, dont certaines peuvent ensuite \u00eatre d\u00e9sengag\u00e9es et priv\u00e9es d&rsquo;acc\u00e8s au p\u00e9trole. Pour r\u00e9aliser ce plan, il a fallu mettre la plan\u00e8te enti\u00e8re sous cl\u00e9, et la seule fa\u00e7on d&rsquo;y parvenir est d&rsquo;effrayer tout le monde avec un virus suppos\u00e9 mortel.<\/p>\n<\/p>\n<p><p>Un dernier extrait de mon livre : &laquo;<em> &hellip; Il devient n\u00e9cessaire pour la technosph\u00e8re d&rsquo;appliquer p\u00e9riodiquement une certaine discipline, afin d&rsquo;\u00e9viter que le r\u00eave d&rsquo;un progr\u00e8s technologique infini au service de l&rsquo;humanit\u00e9 ne commence \u00e0 sembler un peu d\u00e9labr\u00e9. Pour ce faire, il faut pr\u00e9senter toute alternative au progr\u00e8s infini comme un d\u00e9sastre absolu : c&rsquo;est soit le contr\u00f4le total, soit l&rsquo;apocalypse. Il existe de nombreuses variantes de l&rsquo;apocalypse, avec des combinaisons vari\u00e9es d&rsquo;ast\u00e9ro\u00efdes, de zombies, de virus mortels, d&rsquo;extraterrestres, de trombes marines \u00e0 requins au-dessus de Los Angeles&hellip; la liste est infinie<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>La technosph\u00e8re a regard\u00e9 la liste et a choisi des &laquo; <em>virus mortels<\/em> &raquo;. Et voil\u00e0, vous l&rsquo;avez.<\/p>\n<\/p>\n<p><p>Il vous sera peut-\u00eatre difficile d&rsquo;int\u00e9grer le concept d&rsquo;une intelligence mondiale \u00e9mergente qui transcende les limites de chaque nation, continent et civilisation. Vous ne le verrez peut-\u00eatre pas, mais une fois que vous l&rsquo;aurez vu, il est peu probable que vous puissiez l&rsquo;ignorer parce qu&rsquo;elle est trop \u00e9vidente. Elle est plus qu&rsquo;\u00e9vidente : elle vous est directement pr\u00e9sent\u00e9e. Peut-\u00eatre serait-il plus facile pour vous de la consid\u00e9rer comme une sorte de psychose de masse qui a besoin d&rsquo;\u00eatre soign\u00e9e. Ou peut-\u00eatre pr\u00e9f\u00e9reriez-vous la consid\u00e9rer comme un cas de possession d\u00e9moniaque n\u00e9cessitant un exorcisme :<\/p>\n<\/p>\n<blockquote>\n<p><p>&laquo; <em>Et J\u00e9sus lui demanda : \u00ab\u00a0Quel est ton nom ?\u00a0\u00bb Et il dit : \u00ab\u00a0L\u00e9gion\u00a0\u00bb ; car de nombreux d\u00e9mons \u00e9taient entr\u00e9s en lui. Ils l&rsquo;imploraient de ne pas leur ordonner de s&rsquo;en aller dans l&rsquo;ab&icirc;me<\/em>. [&hellip;] <em>Et les d\u00e9mons sortirent de l&rsquo;homme et entr\u00e8rent dans un troupeau de porcs ; et le troupeau se pr\u00e9cipita sur la rive escarp\u00e9e dans le lac et se noya<\/em>. &raquo; (Luc 8:30-31, 33.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Quelle que soit la m\u00e9taphore choisie, la premi\u00e8re \u00e9tape est de lib\u00e9rer son propre esprit. Une fois que vous l&rsquo;aurez fait, vous r\u00e9aliserez peut-\u00eatre que le fiasco mondial des coronavirus de 2020 n&rsquo;a pas \u00e9t\u00e9 sans avantages. Par exemple, de nombreuses personnes dans le monde entier, qui sortent du confinement du au coronavirus, ont certainement pris conscience de certains de ces avantages :<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;internet ne remplace pas les contacts en face \u00e0 face.<\/p>\n<\/p>\n<p><p>&bull; Une ville devient facilement une prison et la campagne est un meilleur choix pour les personnes qui veulent rester libres.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;\u00e9conomie n&rsquo;a pas autant d&rsquo;importance que le fait d&rsquo;\u00eatre parmi des gens qui sont pr\u00eats \u00e0 s&rsquo;entraider.<\/p>\n<\/p>\n<p><p>1er Mai 2020, <a href=\"http:\/\/cluborlov.blogspot.com\/2020\/05\/gaslighting-coronavirus.html\">Club Orlov<\/a>, &ndash; Traduction du <em><a href=\"https:\/\/lesakerfrancophone.fr\/le-detournement-cognitif-du-coronavirus\">Sakerfrancophone<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9tournement cognitif de Covid19 Ces derniers jours, je me suis retenu de commenter les \u00e9v\u00e9nements actuels, qui tournent tous autour de la panique li\u00e9e au nouveau coronavirus, et de faire autant de recherches que possible parce que le fond de ce qui se passe n&rsquo;est pas clair pour moi. Pourquoi arr\u00eater l&rsquo;\u00e9conomie mondiale \u00e0 cause&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3977,19677,2631,5252,4008,2622,3851,2668,6320,2730,19857,13705],"class_list":["post-79253","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-chine","tag-coronavirus","tag-de","tag-dette","tag-intelligence","tag-la","tag-mondiale","tag-orlov","tag-pandemie","tag-russie","tag-technosphere","tag-utilite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79253"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79253\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}