{"id":79291,"date":"2020-06-06T15:17:42","date_gmt":"2020-06-06T15:17:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/06\/06\/esclavage-et-planche-a-billets\/"},"modified":"2020-06-06T15:17:42","modified_gmt":"2020-06-06T15:17:42","slug":"esclavage-et-planche-a-billets","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/06\/06\/esclavage-et-planche-a-billets\/","title":{"rendered":"Esclavage et planche \u00e0 billets"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Esclavage et planche \u00e0 billets<\/h2>\n<\/p>\n<p><p>Dans l&rsquo;esp\u00e8ce de  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Manie_dansante\">chor\u00e9manie<\/a>, ou folle embard\u00e9e de danse de Saint-Guy qui a saisi et qui emporte l&rsquo;Am\u00e9rique en sarabande, &ndash; une &laquo; <em>d\u00e9pression nerveuse nationale<\/em> &raquo; nous dit plus sobrement notre auteur ci-dessous, &ndash; l&rsquo;affaire de la compensation de l&rsquo;esclavage en esp\u00e8ces dissonantes et tr\u00e9buchantes pourrait tenir une place tr\u00e8s singuli\u00e8re. Robert Bridge la pr\u00e9sente dans le texte ci-dessous sous l&rsquo;angle du point de vue du candidat d\u00e9mocrate Joe Biden, qui a \u00e9t\u00e9 l&rsquo;objet d&rsquo;une demande directe d&rsquo;un \u00e9lu Africain-Am\u00e9ricain devant une assembl\u00e9e d\u00e9mocrate de la m\u00eame communaut\u00e9, &ndash; en lui mettant le march\u00e9 en mains sans la moindre ambigu\u00eft\u00e9 : \u00ab\u00a0Si vous voulez que les Noirs votent pour vous, il faut passer \u00e0 la caisse\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Il y a l&rsquo;argument de Biden d\u00e9j\u00e0 d\u00e9velopp\u00e9 dans un instant d&rsquo;\u00e9cole buissonni\u00e8re arros\u00e9 de libations diverses dont le candidat de 77 ans est coutumier, lorsqu&rsquo;il d\u00e9clara \u00e0 un interlocuteur noir, &ndash; un pr\u00e9sentateur-radio fameux du nom de Charlamagne, qui disait ne pas s&rsquo;\u00eatre prononc\u00e9 pour son choix pour la pr\u00e9sidentielle, &ndash; que s&rsquo;il ne votait pas d\u00e9mocrate alors c&rsquo;est qu&rsquo;il n&rsquo;\u00e9tait pas un Noir ; eh bien, cet \u00ab\u00a0argument\u00a0\u00bb qui tendrait \u00e0 (re)faire des Noirs rien de moins apr\u00e8s tout que des \u00ab\u00a0esclaves\u00a0\u00bb du parti d\u00e9mocrate, risque de faire long feu, du type p\u00e9tard mouill\u00e9,  face \u00e0 l&rsquo;argument des r\u00e9parations.<\/p>\n<\/p>\n<p><p>Les riches dirigeants de la communaut\u00e9 noire, ceux qui sont d\u00e9j\u00e0 dans les 1% d&rsquo;au-del\u00e0 de la couleur de peau, comme le milliardaire Robert Johnson, ont d\u00e9j\u00e0 fait leur compte : les 40 millions d&rsquo;Africains-Am\u00e9ricains de la communaut\u00e9 noire s&rsquo;estimeront d\u00e9dommag\u00e9s et enterreront la hache de guerre aussi vite que dispara&icirc;tront, comme par un miracle de la bonne bienpensance, le racisme et les \u00ab\u00a0privil\u00e8ges blancs\u00a0\u00bb, lorsque $14 000 milliards leur seront vers\u00e9s comme d\u00e9dommagement pour les quatre si\u00e8cles d&rsquo;aventure esclavagiste. Comment Johnson a-t-il calcul\u00e9 \u00e7a ? Myst\u00e8re, note Bridge, mais enfin c&rsquo;est le chiffre retenu.<\/p>\n<\/p>\n<p><p>Il est colossal, mais ce n&rsquo;est pas le seul probl\u00e8me, et ce n&rsquo;est d&rsquo;ailleurs peut-\u00eatre pas le plus grave lorsqu&rsquo;on voit la fa\u00e7on dont fonctionne en mode-<em>turbo <\/em>les planches \u00e0 billets dernier-cri de la Fed. La politique de la Fed aujourd&rsquo;hui semblerait \u00eatre l&rsquo;impression des billets \u00e0 l&rsquo;infini&#8230; Alors, $14 000 milliards ?<\/p>\n<\/p>\n<p><p>Non, le probl\u00e8me est d&rsquo;abord politique, psychologique, identitaire, communautariste, etc. Cette demande de r\u00e9parations prend les d\u00e9mocrates de court, dans la mesure o&ugrave; ils tenaient pour acquis que les Africains-Am\u00e9ricains \u00ab\u00a0en majest\u00e9\u00a0\u00bb devraient \u00e9videmment voter, \u00e9videmment d\u00e9mocrate, comme un seul Africain-Am\u00e9ricain ; exactement selon ce que nommerions doctement \u00ab\u00a0<a href=\"https:\/\/www.parismatch.com\/Actu\/International\/Vous-n-etes-pas-noir-si-vous-votez-Trump-l-embarrassante-gaffe-de-Joe-Biden-1686524\">le Principe de Biden<\/a>\u00a0\u00bb : &laquo; <em>Eh bien, je vous dis, <\/em>s&rsquo;\u00e9tait donc \u00e9cri\u00e9 Joe dans un moment d&rsquo;\u00e9garement cognitif<em>, si vous avez un probl\u00e8me pour savoir si vous \u00eates pour moi ou pour Trump, alors vous n&rsquo;\u00eates pas noir<\/em>. &raquo; D&rsquo;o&ugrave; la r\u00e9plique de son interlocuteur Charlamagne, noir et bien noir sans aucun doute, et qui va au c&oelig;ur du probl\u00e8me, notamment m\u00eame si implicitement, au c&oelig;ur br&ucirc;lant de cette question des r\u00e9parations : &laquo; <em>Cela n&rsquo;a rien \u00e0 voir avec Trump. Cela a \u00e0 voir avec le fait que je veux quelque chose pour ma communaut\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>Alors qu&rsquo;avec cette &laquo; <em>d\u00e9pression nerveuse nationale<\/em> &raquo; qui brandit le drapeau de l&rsquo;antiracisme en faveur des Noirs semble triompher la politique communautariste en faveur des minorit\u00e9s pr\u00f4n\u00e9e par le parti d\u00e9mocrate et par sa gauche surtout bien s&ucirc;r, mais tout le monde se trouvant d\u00e9port\u00e9e sur la gauche, curieusement sinon paradoxalement le labyrinthe ainsi cr\u00e9\u00e9 ferait peut-\u00eatre surgir quelques probl\u00e8mes inattendus et d&rsquo;un poids consid\u00e9rable. Alors que les d\u00e9mocrates pensaient disposer dans le chef de la communaut\u00e9 noire d&rsquo;un \u00ab\u00a0\u00e9lectorat captif\u00a0\u00bb, c&rsquo;est peut-\u00eatre le contraire qui se dessine : le parti d\u00e9mocrate devenant un \u00ab\u00a0parti captif\u00a0\u00bb&lsquo; du vote africain-am\u00e9ricain&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La Grande-&Eacute;meute intra-am\u00e9ricaniste donne en effet \u00e0 la communaut\u00e9 noire une position de force, surtout par rapport aux d\u00e9mocrates qui sont leurs alli\u00e9s naturels ; elle bouscule le rapport des forces dans cette alliance essentiellement et donne \u00e0 la communaut\u00e9 africaine-am\u00e9ricaine une position dominante vis-\u00e0-vis de son \u00ab\u00a0alli\u00e9\u00a0\u00bb du parti d\u00e9mocrate (dans lequel on trouve des Africains-Am\u00e9ricains bien entendu, mais il n&rsquo;est pas d\u00e9plac\u00e9 d&rsquo;avoir quelques amis dans la place). Cette communaut\u00e9 peut effectivement demander des promesses fastueuses au vieux Joe, s&rsquo;il veut que les Noirs votent pour lui, parce qu&rsquo;un Noir reste un Noir m\u00eame s&rsquo;il ne vote pas pour Joe, m\u00eame s&rsquo;il d\u00e9cide de ne pas voter pour Joe si Joe ne lui fait pas la promesse r\u00e9clam\u00e9e&#8230;<\/p>\n<\/p>\n<p><p>Cette affaire des r\u00e9parations est un v\u00e9ritable casse-t\u00eate et, potentiellement, une bombe \u00e0 retardement. Bien peu de monde, dans l&rsquo;\u00e9lectorat du parti d\u00e9mocrate, comprendrait qu&rsquo;une telle promesse ne soit pas donn\u00e9e aux Africains-Am\u00e9ricains, dans les circonstances actuelles et si le probl\u00e8me venait \u00e0 prendre une place pr\u00e9pond\u00e9rante. Nous pouvons m\u00eame pr\u00e9sumer que, contrairement \u00e0 ce que suppose Bridge (&laquo; <em>Compte tenu de son soutien douteux \u00e0 la communaut\u00e9 noire dans le pass\u00e9, Biden, fid\u00e8le \u00e0 la tradition politique, pourrait rapidement oublier sa promesse de r\u00e9paration une fois \u00e0 la Maison Blanche<\/em> &raquo;), il est \u00e0 notre sens difficilement envisageable qu&rsquo;un Biden \u00e9lu avec cette promesse, et gr\u00e2ce \u00e0 cette promesse, puisse la faire passer \u00e0 la trappe sans d\u00e9clencher une insurrection qui l&rsquo;am\u00e8nerait \u00e0 demander des conseils \u00e0 Trump.<\/p>\n<\/p>\n<p><p>A notre sens encore, la m\u00eame question se poserait dans les m\u00eames termes de rapports de force avec un autre d\u00e9mocrate que Biden, et m\u00eame, &ndash; et encore plus, &ndash; avec une candidate noire \u00e0 la vice-pr\u00e9sidence, sinon \u00e0 la pr\u00e9sidence, f&ucirc;t-elle Michelle Obama, etc. Si cette affaire est effectivement institutionnalis\u00e9e, elle devient une des poutres-ma&icirc;tresses de la campagne et ne peut \u00eatre trait\u00e9e comme l&rsquo;une de ces vagues promesses qu&rsquo;on s&#8217;empresse d&rsquo;oublier. Que cette hi\u00e9rarchie des priorit\u00e9s pla\u00e7ant la question des r\u00e9parations en t\u00eate de liste soit un constat extr\u00eamement attristant, on peut en juger de la sorte, et c&rsquo;est m\u00eame une sorte de jugement de l&rsquo;\u00e9vidence dont il n&rsquo;est m\u00eame pas n\u00e9cessaire de discuter ; mais c&rsquo;est une question d&rsquo;\u00e9poque, o&ugrave; rien de bon ni de beau ne peut se manifester malgr\u00e9 les valeurs et les vertus innombrables qui se manifestent en tous sens.<\/p>\n<\/p>\n<p><p>Toujours selon les hypoth\u00e8ses envisageables, la derni\u00e8re qu&rsquo;\u00e9voque Bridge dans son texte, d&rsquo;un Trump promettant brusquement \u00e0 la communaut\u00e9 africaine-am\u00e9ricaine d&rsquo;accepter de lui verser ces r\u00e9parations, et renversant ainsi la situation compl\u00e8tement \u00e0 son avantage, est tout \u00e0 fait concevable. Un personnage comme Trump, par ailleurs si prompt \u00e0 faire marcher la planche \u00e0 billets, est bien du genre \u00e0 r\u00e9aliser ce coup de force qui modifierait compl\u00e8tement l'\u00a0\u00bb\u00e9chiquier politique\u00a0\u00bb, &ndash; ou plut\u00f4t le labyrinthe politique am\u00e9ricaniste&#8230;<\/p>\n<\/p>\n<p><p>L&rsquo;op\u00e9rationnalisation de cette affaire des r\u00e9parations du fait de l&rsquo;esclavage est, r\u00e9p\u00e9tons-le, tout \u00e0 fait possible dans le climat actuel, surtout si les super-riches de la communaut\u00e9 (comme Johnson) la prennent en main et la g\u00e8rent comme une op\u00e9ration financi\u00e8re.  Il s&rsquo;agirait alors effectivement d&rsquo;une v\u00e9ritable bombe \u00e0 retardement, car le \u00ab\u00a0rachat\u00a0\u00bb de l&rsquo;esclavage n'\u00a0\u00bbach\u00e8te\u00a0\u00bb pas en prime le racisme comme on l&rsquo;a suppos\u00e9 plus haut en guise de sarcasme ; au contraire il l&rsquo;exacerbe. Une telle perspective, loin d'\u00a0\u00bbacheter\u00a0\u00bb une r\u00e9conciliation, scellerait au contraire une perspective de s\u00e9paration, qui \u00e9tablirait une distance peut-\u00eatre d\u00e9finitive entre les communaut\u00e9s, &ndash; d&rsquo;autant qu&rsquo;existe si fortement cette \u00e9lite noire financi\u00e8re et fortun\u00e9e, entretenant ce que nous avons d\u00e9sign\u00e9 comme une sorte d&rsquo; &laquo; <em>apartheid vertueux<\/em> &raquo;, et qui est bien aussi rou\u00e9e et man&oelig;uvri\u00e8re que l&rsquo;\u00e9lite fortun\u00e9e caucasienne-am\u00e9ricaine, anciennement WASP (<em>White Anglo-Saxon Protestant<\/em>) tout court.<\/p>\n<\/p>\n<p><p>Le texte de Robert Bridge, journaliste et auteur de &lsquo;<em>Midnight in the American Empire, How Corporations and Their Political Servants are Destroying the American Dream<\/em>&lsquo;, est sur RT.com en version originale, le  <a href=\"https:\/\/www.rt.com\/op-ed\/490966-biden-promises-trillions-in-reparations-for-black-americans\/\">5 juin 2020<\/a>.<\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les $14 000 milliards du pr\u00e9sident Biden<\/h2>\n<\/p>\n<p><p>On demande au candidat d\u00e9mocrate \u00e0 la pr\u00e9sidence, Joe Biden, de s&rsquo;engager \u00e0 verser $14 000 milliards de compensation \u00e0 la communaut\u00e9 africaine-am\u00e9ricaine pour les ann\u00e9es d&rsquo;esclavage, s&rsquo;il est \u00e9lu. Fera-t-il cette promesse, pour s&#8217;empresser de l&rsquo;oublier une fois \u00e0 la Maison Blanche ?<\/p>\n<\/p>\n<p><p>S&rsquo;il est un temps o&ugrave; la communaut\u00e9 noire am\u00e9ricaine est en bonne position pour exiger des r\u00e9parations pour avoir \u00e9t\u00e9 soumise \u00e0 la traite des esclaves pendant des si\u00e8cles, c&rsquo;est bien aujourd&rsquo;hui. Suite \u00e0 la mort de George Floyd des mains d&rsquo;un policier blanc, le pays est en proie aux convulsions des feux de la contestation d&rsquo;un oc\u00e9an \u00e0 l&rsquo;autre. Dans le m\u00eame temps, une grande partie de la population, lorsqu&rsquo;elle n&rsquo;ajuste pas ses masques chirurgicaux, geint et se lamente \u00e0 propos de son pr\u00e9tendu \u00ab\u00a0privil\u00e8ge blanc\u00a0\u00bb. Pour compliquer encore cette d\u00e9pression nerveuse nationale, nous sommes \u00e0 cinq mois de ce qui promet d&rsquo;\u00eatre l&rsquo;\u00e9lection pr\u00e9sidentielle am\u00e9ricaine la plus controvers\u00e9e et la plus importante de notre histoire r\u00e9cente.<\/p>\n<\/p>\n<p><p>Parlons donc de Joe Biden, 77 ans, le candidat d\u00e9mocrate pr\u00e9sum\u00e9 \u00e0 la pr\u00e9sidence, qui pourrait \u00eatre tent\u00e9 d&rsquo;ouvrir la pompe \u00e0 billets de banque pour apaiser les Black Lives Matter et mettre fin au pillage, \u00e0 l&rsquo;incendie et au chaos g\u00e9n\u00e9ral qui \u00e9branlent les &Eacute;tats-Unis jusqu&rsquo;en leurs tr\u00e9fonds. De ce point de vue, on n&rsquo;a pas per\u00e7u comme une forme tr\u00e8s subtile de corruption et de chantage l&rsquo;intervention du s\u00e9nateur de l&rsquo;&Eacute;tat du Delaware, Darius Brown, sugg\u00e9rant fortement \u00e0 Biden de faire tout ce qu&rsquo;il pouvait pour financer les r\u00e9parations.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Vous, les gens dans cette salle, nous vous aimons\u00a0\u00bb, a d\u00e9clar\u00e9 M. Brown lors d&rsquo;une c\u00e9r\u00e9monie \u00e0 l&rsquo;\u00e9glise cette semaine, o&ugrave; M. Biden \u00e9tait l&rsquo;invit\u00e9 d&rsquo;honneur. &quot;Mais nous sommes ici non seulement pour vous aimer, mais aussi pour vous pousser &#8230; [\u00e0] soutenir la base d\u00e9mocratique afro-am\u00e9ricaine. Et il ne devrait pas s&rsquo;agir d&rsquo;une \u00e9tude sur les r\u00e9parations, mais bien d&rsquo;un financement des r\u00e9parations.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Le message \u00e9tait aussi clair que troublant : si Biden veut la b\u00e9n\u00e9diction de la communaut\u00e9 noire en novembre, promettre des r\u00e9parations est le moyen le plus rapide de l&rsquo;obtenir. Alors, de combien d&rsquo;argent parlons-nous exactement pour r\u00e9parer l&rsquo;un des chapitres les plus douloureux de l&rsquo;histoire am\u00e9ricaine ? Selon le milliardaire Robert Johnson, le fondateur de Black Entertainment Television (BET), un \u00ab\u00a0transfert de richesse\u00a0\u00bb de l&rsquo;ordre de $14 000 milliards permettrait de remettre les pendules \u00e0 l&rsquo;heure. Curieusement, Johnson n&rsquo;a jamais r\u00e9v\u00e9l\u00e9 comment il est parvenu \u00e0 un tel chiffre, qui s&rsquo;\u00e9l\u00e8ve \u00e0 quelque $350 000 pour chacun des 40 millions de Noirs vivant aux &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>Cette \u00e9valuation astronomique soul\u00e8ve tant de questions qu&rsquo;elle fait tourner la t\u00eate. Tout d&rsquo;abord, de nombreux Am\u00e9ricains, principalement de la droite, feront valoir que le pays a d\u00e9j\u00e0 r\u00e9alis\u00e9 des efforts financiers massifs pour la communaut\u00e9 noire sous la forme de programmes sociaux co&ucirc;teux, &ndash; comme la \u00ab\u00a0discrimination positive\u00a0\u00bb, accordant des avantages particuliers aux minorit\u00e9s pr\u00e9c\u00e9demment discrimin\u00e9es dans des domaines tels que l&rsquo;activit\u00e9 professionnelle et l&rsquo;\u00e9ducation. Tout cela faisait partie du programme national de la \u00ab\u00a0Great Society\u00a0\u00bb de Lyndon Johnson, qui a aussi d\u00e9pens\u00e9 des $milliards pour financer un syst\u00e8me de protection sociale pour les personnes d\u00e9favoris\u00e9es, ainsi que des programmes qui ont b\u00e9n\u00e9fici\u00e9 \u00e0 tous les Am\u00e9ricains, comme Medicaid et Medicare.<\/p>\n<\/p>\n<p><p>En outre, il n&rsquo;y a pas de plus grande ironie que l&rsquo;hypoth\u00e8se d&rsquo;une communaut\u00e9 noire consid\u00e9rant Joe Biden comme son sauveur politique. Apr\u00e8s tout, ce n&rsquo;est un secret pour personne que de nombreux Noirs ont subi des revers financiers majeurs pendant la pr\u00e9sidence d&rsquo;Obama, alors que Biden \u00e9tait vice-pr\u00e9sident. Le pourcentage de propri\u00e9taires noirs qui ont \u00e9t\u00e9 expropri\u00e9s \u00e0 cause du retard sur leur pr\u00eat hypoth\u00e9caire a \u00e9t\u00e9 multipli\u00e9 par 20 entre 2007 et 2013, alors que seuls les 10 % d&rsquo;Am\u00e9ricains les plus riches, &ndash; en grande partie compos\u00e9s de Blancs, &ndash; ont vu leur patrimoine personnel augmenter gr\u00e2ce \u00e0 des plans de sauvetage massifs des banques qui ont permis de maintenir la valeur des actions au-dessus de la moyenne.<\/p>\n<\/p>\n<p><p>En m\u00eame temps, il n&rsquo;est pas pass\u00e9 inaper\u00e7u aux yeux de nombreux Am\u00e9ricains, &ndash; en particulier des membres du parti d\u00e9mocrate, &ndash; que Biden n&rsquo;a pas fait grand-chose pour aider la communaut\u00e9 noire sur le front de la justice tout au long de sa longue carri\u00e8re politique.<\/p>\n<\/p>\n<p><p>&Agrave; l&rsquo;\u00e9poque o&ugrave; Biden \u00e9tait s\u00e9nateur, il a soutenu le projet de loi de 1994 sur la criminalit\u00e9, &ndash; officiellement connu sous le nom de Violent Crime Control and Law Enforcement Act, &ndash; qui frappait les r\u00e9cidivistes de lourdes peines de prison, m\u00eame pour des d\u00e9lits relativement mineurs. En cons\u00e9quence, le syst\u00e8me judiciaire a connu une explosion de la population carc\u00e9rale, principalement compos\u00e9e de Noirs.<\/p>\n<\/p>\n<p><p>Le s\u00e9nateur Kamala D. Harris, qui a \u00e9t\u00e9 nomm\u00e9 comme possible colistier de Biden, a d\u00e9nonc\u00e9 le comportement l\u00e9gislatif de l&rsquo;ancien vice-pr\u00e9sident en mati\u00e8re de criminalit\u00e9. <\/p>\n<\/p>\n<p><p>\u00ab\u00a0Ce projet de loi sur la criminalit\u00e9&#8230; c&rsquo;\u00e9tait la premi\u00e8re fois que nous avions une loi f\u00e9d\u00e9rale structur\u00e9e sur trois d\u00e9lits\u00a0\u00bb, a d\u00e9clar\u00e9 Harris. \u00ab\u00a0Elle a financ\u00e9 la construction d&rsquo;un nombre consid\u00e9rable de prisons dans les &Eacute;tats.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>A part le fait que Biden semble \u00eatre un personnage bien peu qualifi\u00e9 moralement pour distribuer des r\u00e9parations \u00e0 la communaut\u00e9 noire, il y a une question beaucoup plus urgente concernant le montant astronomique demand\u00e9. Quelqu&rsquo;un a-t-il pens\u00e9 qu&rsquo;une somme aussi faramineuse ne signifiera pas grand-chose si les &Eacute;tats-Unis font faillite alors qu&rsquo;ils luttent pour payer une telle dette ? <\/p>\n<\/p>\n<p><p>Ces derniers temps, l&rsquo;id\u00e9e s&rsquo;est impos\u00e9e que l&rsquo;Am\u00e9rique est une source in\u00e9puisable d&rsquo;argent et qu&rsquo;elle peut tout simplement se sortir de tout probl\u00e8me en faisant tourner \u00ab\u00a0sa planche [\u00e9lectronique] \u00e0 billets\u00a0\u00bb. Du renflouement du syst\u00e8me financier \u00e0 hauteur de $700 milliards en 2008, \u00e0 la signature par Trump de la loi CARES de $2 000 milliards pour faire face aux retomb\u00e9es \u00e9conomiques de la pand\u00e9mie Covid-19, il semble que les poches profondes de l&rsquo;Oncle Sam n&rsquo;aient pas de fond. Mais t\u00f4t ou tard et d&rsquo;une fa\u00e7on ou l&rsquo;autre, quelqu&rsquo;un devra payer ces factures impay\u00e9es, et ce \u00ab\u00a0quelqu&rsquo;un\u00a0\u00bb sera le contribuable am\u00e9ricain, &ndash; ce qui inclut la communaut\u00e9 noire.<\/p>\n<\/p>\n<p><p>Compte tenu de son soutien douteux \u00e0 la communaut\u00e9 noire dans le pass\u00e9, Biden, fid\u00e8le \u00e0 la tradition politique, pourrait rapidement oublier sa promesse de r\u00e9paration une fois \u00e0 la Maison Blanche. Ce ne serait certainement pas la premi\u00e8re fois qu&rsquo;un homme politique oublierait une promesse faite en cours de campagne.<\/p>\n<\/p>\n<p><p>Enfin, n&rsquo;oublions pas la possibilit\u00e9, &ndash; m\u00eame si elle est tr\u00e8s hypoth\u00e9tique pour l&rsquo;instant, &ndash; que Trump, qui a montr\u00e9 durant sa pr\u00e9sidence sa tendance \u00e0 ne reculer devant aucune d\u00e9pense, au besoin en faisant follement tourner les imprimeuses \u00e9lectroniques de billets, d\u00e9cide de \u00ab\u00a0conclure un accord\u00a0\u00bb avec la communaut\u00e9 noire, r\u00e9solvant ainsi la question des r\u00e9parations une fois pour toutes. Apr\u00e8s tout, il est connu pour son \u00ab\u00a0<em>art of the deal<\/em>\u00ab\u00a0.<\/p>\n<\/p>\n<p><h4>Robert Bridge<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esclavage et planche \u00e0 billets Dans l&rsquo;esp\u00e8ce de chor\u00e9manie, ou folle embard\u00e9e de danse de Saint-Guy qui a saisi et qui emporte l&rsquo;Am\u00e9rique en sarabande, &ndash; une &laquo; d\u00e9pression nerveuse nationale &raquo; nous dit plus sobrement notre auteur ci-dessous, &ndash; l&rsquo;affaire de la compensation de l&rsquo;esclavage en esp\u00e8ces dissonantes et tr\u00e9buchantes pourrait tenir une place&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[19915,2915,3281,1235,11896,19914,19916,2849,8503,4014,3134,3050,19260],"class_list":["post-79291","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-19915","tag-ans","tag-art","tag-biden","tag-bridge","tag-compensations","tag-desclavage","tag-deal","tag-joe","tag-of","tag-robert","tag-the","tag-usa2020"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79291"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79291\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}