{"id":79307,"date":"2020-06-17T16:29:15","date_gmt":"2020-06-17T16:29:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/06\/17\/en-attendant-le-potus-kerenski\/"},"modified":"2020-06-17T16:29:15","modified_gmt":"2020-06-17T16:29:15","slug":"en-attendant-le-potus-kerenski","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/06\/17\/en-attendant-le-potus-kerenski\/","title":{"rendered":"En attendant le POTUS-Kerenski"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">En attendant le POTUS-Kerenski<\/h2>\n<\/p>\n<p><p>17 juin 2020 &ndash; Nous l&rsquo;avons d\u00e9j\u00e0 dit \u00e0 plusieurs reprises et le r\u00e9p\u00e9tons en guise d&rsquo;introduction, avant de revenir plus loin sur le th\u00e8me d&rsquo;une autre fa\u00e7on, nous estimons bien entendu que, dans la crise globale qui secoue cette ann\u00e9e 2020 entre Covid19 et ses suites \u00e9conomiques-catastrophiques, et ce que nous nommons la Grande-Emeute2020, la place des USA et leur \u00e9volution sont le centre de tout et la matrice de l&rsquo;\u00e9v\u00e9nement global de la Grande Crise. C&rsquo;est-\u00e0-dire que cette crise Grande-Emeute2020 n&rsquo;affecte pas les USA dans la m\u00eame mesure qu&rsquo;elle affecte les autres ; elle affecte \u00ab\u00a0le centre de tout et la matrice\u00a0\u00bb de tout ce qui op\u00e9rationnalise le Syst\u00e8me dans l&rsquo;\u00e9poque actuelle, y compris les facteurs les moins quantifiables et les plus insaisissables comme la culture, la psychologie, le symbolisme, &ndash; et m\u00eame ce que nous nommerions le \u00ab\u00a0mythologisme\u00a0\u00bb, voire le \u00ab\u00a0simulacrisme\u00a0\u00bb (\u00ab\u00a0id\u00e9ologies\u00a0\u00bb de fabrique des mythes et des simulacres). Si les USA \u00ab\u00a0sautent\u00a0\u00bb, d&rsquo;une fa\u00e7on ou de l&rsquo;autre, avec Trump ou contre Trump qu&rsquo;importe, c&rsquo;est tout le Syst\u00e8me qui saute&#8230;<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, une \u00e9tape (plut\u00f4t qu&rsquo;un tournant) notable dans la situation de d\u00e9sordre des USA est importante \u00e0 d\u00e9crire et \u00e0 comprendre pour mieux l&rsquo;interpr\u00e9ter. C&rsquo;est le cas de l&rsquo;EO que vient de signer Trump, hier \u00e0 la Maison-Blanche, sous les applaudissements nourris d&rsquo;un important groupes de hauts-fonctionnaires, d&rsquo;\u00e9lus et de notables concern\u00e9s.<\/p>\n<\/p>\n<p><p>Le pr\u00e9sident Trump a \u00e9dict\u00e9 un <em>Executive Order <\/em>(EO) recommandant aux &Eacute;tats et aux villes de la F\u00e9d\u00e9ration (des USA) certaines mesures pour modifier le comportement de la police. Cette initiative va dans le sens d\u00e9sir\u00e9 unanimement d&rsquo;une r\u00e9duction des violences polici\u00e8res mais n&rsquo;aura, comme l&rsquo;\u00e9crit  <a href=\"https:\/\/www.rt.com\/op-ed\/492066-trump-executive-order-police-riots\/\">Nebojsa Malic<\/a>, aucun effet positif pour la politique de \u00ab\u00a0retour \u00e0 l&rsquo;ordre et \u00e0 la loi\u00a0\u00bb que pr\u00e9tend suivre le pr\u00e9sident. Bien entendu, on comprend pourquoi puisqu&rsquo;il s&rsquo;agit d&rsquo;une \u00e9vidence que nous r\u00e9p\u00e9tons depuis que ces \u00e9v\u00e9nements ont \u00e9clat\u00e9 : ni les violences polici\u00e8res ni le racisme ne sont les causes des mouvements en cours aux USA, mais tout juste des pr\u00e9textes l\u00e9gitimant ces violences pour un autre but, c&rsquo;est-\u00e0-dire des outils manipulateurs.<\/p>\n<\/p>\n<p><p>Au contraire, l&rsquo;initiative de Trump, qui est un cas classique d&rsquo;une erreur du type \u00ab\u00a0trop peu trop tard\u00a0\u00bb d&rsquo;une direction ayant perdu tout contact, &ndash; si elle n&rsquo;en eut jamais, &ndash; avec la v\u00e9ritable situation au c&oelig;ur d&rsquo;une crise de cette sorte, va exacerber cette situation dans un sens favorable aux plus radicaux qui suivent des ambitions du type r\u00e9volutionnaire radical classique et s&rsquo;imaginent faire de la strat\u00e9gie alors qu&rsquo;eux-m\u00eames \u00e9voluent au seul niveau tactique, manipul\u00e9s par les \u00e9v\u00e9nements.<\/p>\n<\/p>\n<p><p>Ainsi Malic r\u00e9sume-t-il la situation aux USA :<\/p>\n<\/p>\n<p><p>&laquo; <em>Le d\u00e9cret du pr\u00e9sident Donald Trump sur la police fait avancer beaucoup de choses dans la bonne direction. Pour autant, cela n&rsquo;a pas  moindre importance sur la situation g\u00e9n\u00e9rale, car le (mauvais) comportement de la police n&rsquo;est que le pr\u00e9texte de la crise actuelle, et nullement sa cause.<\/em><\/p>\n<p>&raquo; <em>Mardi, Trump a pr\u00e9sent\u00e9 des lignes directrices f\u00e9d\u00e9rales destin\u00e9es \u00e0 limiter drastiquement l&rsquo;utilisation de la technique \u00ab\u00a0de l&rsquo;\u00e9tranglement\u00a0\u00bb, \u00e0 donner \u00e0 la police plus d&rsquo;armes non-l\u00e9tales pour r\u00e9duire l&rsquo;utilisation des armes \u00e0 feu, \u00e0 augmenter le nombre de travailleurs sociaux, et en conditionnant l&rsquo;aide f\u00e9d\u00e9rale \u00e0 des certifications de la part des &Eacute;tats et des villes en mati\u00e8re de politiques de d\u00e9sescalade et de bon usage de la force. <\/em><\/p>\n<p>&raquo; <em>Dans des circonstances ordinaires, toutes ces mesures seraient les bienvenues pour r\u00e9duire les brutalit\u00e9s polici\u00e8res et am\u00e9liorer la s\u00e9curit\u00e9 des agents et du public. Mais ce ne sont pas des circonstances ordinaires.<\/em><\/p>\n<p>&raquo; <em>La r\u00e9forme de la police a peut-\u00eatre \u00e9t\u00e9 l&rsquo;une des demandes des manifestants qui ont rempli les rues de Minneapolis il y a trois semaines pour d\u00e9noncer la mort de George Floyd. Depuis lors, les protestations se sont transform\u00e9es en \u00e9meutes, d&rsquo;abord \u00e0 Minneapolis et dans la ville voisine de St. Paul, puis partout aux &Eacute;tats-Unis, y compris \u00e0 Washington. Et ce, m\u00eame apr\u00e8s que les quatre officiers impliqu\u00e9s dans la mort de Floyd aient \u00e9t\u00e9 licenci\u00e9s et inculp\u00e9s, &ndash; puis que leurs charges aient \u00e9t\u00e9 aggrav\u00e9es par le procureur g\u00e9n\u00e9ral de l&rsquo;&Eacute;tat, sous la pression des manifestants. <\/em><\/p>\n<p>&raquo; <em>Pendant ce temps, ces demandes ont augment\u00e9 de fa\u00e7on exponentielle. R\u00e9former la police ne suffisait plus, oh non ; le Police Department devait dispara&icirc;tre compl\u00e8tement, et \u00ab\u00a0d\u00e9budg\u00e9tiser la police\u00a0\u00bb est devenu une demande nationale de Black Lives Matter et de leurs collecteurs de fonds du Parti d\u00e9mocrate. Mais il y a encore bien plus : des noms doivent \u00eatre chang\u00e9s, des statues bris\u00e9es ou d\u00e9figur\u00e9es, les personnes exprimant un z\u00e8le insuffisant pour la Cause en rapide \u00e9volution (et encore moins osant s&rsquo;y opposer) doivent \u00eatre licenci\u00e9es et les salles de r\u00e9daction purg\u00e9es. Il est question de r\u00e9parations de l&rsquo;esclavage aux USA et un groupe de \u00ab\u00a0manifestants pacifiques\u00a0\u00bb a m\u00eame pris des armes et d\u00e9clar\u00e9 une \u00ab\u00a0Zone Autonome\u00a0\u00bb dans le centre-ville de Seattle, \u00e0 Washington.<\/em><\/p>\n<p>&raquo; <em>Pendant tout ce temps, Trump a tweet\u00e9 avec emphase \u00e0 propos de \u00ab\u00a0la loi et l&rsquo;ordre\u00a0\u00bb, mais les responsables locaux des villes touch\u00e9es, &ndash; presque enti\u00e8rement d\u00e9mocrates, &ndash; ont rejet\u00e9 son offre de faire appel \u00e0 la Garde nationale pour r\u00e9primer les \u00e9meutes, l&rsquo;ont d\u00e9nonc\u00e9 comme un tyran, puis se sont retourn\u00e9s et ont exig\u00e9 de l&rsquo;argent f\u00e9d\u00e9ral pour r\u00e9parer les dommages caus\u00e9s par la violence qu&rsquo;ils ont laiss\u00e9 se d\u00e9velopper. Des chefs de la police et des maires ont \u00e9t\u00e9 film\u00e9s en train de se mettre \u00e0 genoux et de ramper devant les \u00ab\u00a0manifestants pacifiques\u00a0\u00bb avant d&rsquo;\u00eatre chass\u00e9s dans l&rsquo;humiliation.<\/em><\/p>\n<p>&raquo; <em>Face \u00e0 ces manifestations de faiblesse, amplifi\u00e9es par la couverture m\u00e9diatique, il est naturel pour les militants d&rsquo;intensifier leurs revendications. Pendant ce temps, les partisans de Trump sont de plus en plus d\u00e9sillusionn\u00e9s par la d\u00e9connexion croissante entre ses tweets au ton martial et l&rsquo;absence de toute action concr\u00e8te pour mettre un terme \u00e0 ce qui semble \u00eatre le r\u00e8gne du d\u00e9sordre et de la mafia..<\/em>. &raquo; <\/p>\n<\/p>\n<p><p>Il est vrai que Trump a beaucoup clam\u00e9 et fait tr\u00e8s peu. Il y a eu l&rsquo;\u00e9pisode de Washington, avec la confusion \u00e0 propos du d\u00e9ploiement de forces militaires (82<sup>\u00e8me<\/sup>division a\u00e9roport\u00e9e), pr\u00e8s ou autour de la ville. L\u00e0-dessus ont aussit\u00f4t encha&icirc;n\u00e9 ses menaces d&rsquo;intervention de l&rsquo;arm\u00e9e \u00e0 Seattle, pour disperser la \u00ab\u00a0Zone d&rsquo;Autonomie\u00a0\u00bb (CHAZ, puis  <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-trotskisme-utile\">CHOP<\/a>), laquelle est toujours l\u00e0, et de plus en plus \u00ab\u00a0autonome\u00a0\u00bb. L&rsquo;arm\u00e9e n&rsquo;est pas intervenue bien que, dans une lettre commune \u00e0 la Commission des forces arm\u00e9es de la Chambre, le ministre et le chef d&rsquo;\u00e9tat-major des forces arm\u00e9es,  <a href=\"https:\/\/www.dedefensa.org\/article\/le-pentagone-a-mutin-mutin-et-demi\">Esper et Milley<\/a>, ait mentionn\u00e9 une possibilit\u00e9 d&rsquo;intervention des forces \u00e0 Seattle si le pr\u00e9sident l&rsquo;estimait n\u00e9cessaire. Le pr\u00e9sident ne l&rsquo;a pas estim\u00e9 n\u00e9cessaire.<\/p>\n<\/p>\n<p><p>Dans un article pour le m\u00eame <a href=\"https:\/\/www.rt.com\/op-ed\/492006-black-votes-matter-election\/\">RT.com<\/a>, le journaliste Nicholas Sheppard (<em>Politico, The Federalist, The Daily Beast, Huffington Post<\/em>, auteur du livre &lsquo;<em>Broken Play<\/em>&lsquo;) estime que Trump, qui avait r\u00e9ussi le remarquable exploit (jamais accompli par aucun pr\u00e9sident r\u00e9publicain) de r\u00e9unir 23% de soutien dans la communaut\u00e9 Africaine-Am\u00e9ricaine en f\u00e9vrier de cette ann\u00e9e, est en passe de perdre ce pr\u00e9cieux apport \u00e9lectoral<em>. <\/em>Sheppard estime que l&rsquo;attitude de Trump durant cette Grande-Emeute2020 est le principal argument qu&rsquo;on peut avancer pour cette pr\u00e9vision qui se traduit dans les chiffres, &ndash; de 23% \u00e0 12%&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Aujourd&rsquo;hui, min\u00e9 par Covid-19 et la d\u00e9t\u00e9rioration des relations entre les races \u00e0 la suite de l&rsquo;assassinat de George Floyd, le soutien fragile mais tangible que le pr\u00e9sident avait recueilli aupr\u00e8s des \u00e9lecteurs noirs s&rsquo;est consid\u00e9rablement effac\u00e9, chutant de pr\u00e8s de la moiti\u00e9 pour atteindre seulement 12 %.<\/em><\/p>\n<p>&raquo; <em>Si la mani\u00e8re dont le pr\u00e9sident a trait\u00e9 le coronavirus peut \u00eatre un facteur contributif, la mort de Floyd a \u00e9t\u00e9 un \u00e9v\u00e9nement dramatique et d\u00e9cisif, et extr\u00eamement cons\u00e9quent, tant sur le plan culturel qu&rsquo;\u00e9lectoral. &Eacute;tant donn\u00e9 les faibles marges probables, c&rsquo;est particuli\u00e8rement vrai dans de nombreux &Eacute;tats tr\u00e8s disput\u00e9s, avec peu d&rsquo;\u00e9lecteurs ind\u00e9pendants \u00e0 rallier et donc la n\u00e9cessit\u00e9 pour les deux partis de consolider leur base.<\/em><\/p>\n<p>&raquo; <em>La r\u00e9ouverture des ranc&oelig;urs culturelles, la rh\u00e9torique antagoniste du pr\u00e9sident Trump sur Floyd et le retour du soutien des Noirs au sein du groupe d\u00e9mocrate ont remodel\u00e9 le paysage politique<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette situation pr\u00e9-\u00e9lectorale est devenue extr\u00eamement diff\u00e9rente pour Trump, qui paraissait il y a quelques mois comme le grand favori pour novembre prochain. &Eacute;videmment, Covid19 et la Grande-Emeute2020 sont des \u00e9v\u00e9nements propres \u00e0 modifier profond\u00e9ment les \u00e9v\u00e9nements \u00e9lectoraux, et encore plus avec l&rsquo;\u00e9volution de la seconde crise tandis que la premi\u00e8re n&rsquo;est pas termin\u00e9e et peut repartir dans une \u00ab\u00a0seconde vague\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Mais il est vrai que c&rsquo;est la crise de protestation et de troubles depuis le 25 mai qui domine l&rsquo;essentiel des analyses et des actes politiques. Le comportement de Trump n&rsquo;a pas \u00e9t\u00e9 particuli\u00e8rement habile, &ndash; d&rsquo;ailleurs sans que tout soit n\u00e9cessairement de sa faute. Comme on l&rsquo;a vu, la position si ambig\u00fce du Pentagone ne permet pas \u00e0 Trump d&rsquo;\u00eatre tr\u00e8s \u00e0 son aise lorsqu&rsquo;il choisit l&rsquo;option de \u00ab\u00a0la loi et l&rsquo;ordre\u00a0\u00bb, avec menaces d&rsquo;intervention \u00e0 l&rsquo;appui. D&rsquo;autre part, peut-il prendre une position inverse ? Alastair Crooke r\u00e9sumais la position de Trump dans un <a href=\"https:\/\/www.strategic-culture.org\/news\/2020\/06\/08\/for-this-to-slip-would-be-the-end-of-empire\/\">texte du 6 juin<\/a>, &ndash; et m\u00eame si les choses vont tr\u00e8s vite, les principaux \u00e9l\u00e9ments du dilemme du pr\u00e9sident US rassembl\u00e9s ici existent toujours et se sont m\u00eame renforc\u00e9s&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Ces derniers jours, Trump est devenu le Pr\u00e9sident de \u00ab\u00a0la loi et l&rsquo;ordre\u00a0\u00bb, &ndash; un changement qu&rsquo;il a explicitement li\u00e9 \u00e0 1968, lorsque, apr\u00e8s la mort de George Floyd du fait de la police de Minneapolis, Trump a tweet\u00e9 : \u00a0\u00bb Quand les pillages commencent, les tirs commencent\u00a0\u00bb. Ce sont les mots utilis\u00e9s par le gouverneur George Wallace, le candidat du parti s\u00e9gr\u00e9gationniste \u00e0 l&rsquo;\u00e9lection pr\u00e9sidentielle de 1968. Les R\u00e9publicains ont lanc\u00e9 leur \u00ab\u00a0strat\u00e9gie du Sud\u00a0\u00bb pour gagner les d\u00e9mocrates blancs m\u00e9contents apr\u00e8s la r\u00e9volution des droits civils et les \u00e9meutes noires.<\/em><\/p>\n<p>&raquo; <em>Trump est d\u00e9termin\u00e9 \u00e0 l&#8217;emporter &ndash; mais aujourd&rsquo;hui, nous ne sommes pas en 1968. Un programme de maintien de l&rsquo;ordre peut-il fonctionner ? La d\u00e9mographie am\u00e9ricaine dans le Sud a chang\u00e9 et il n&rsquo;est pas certain que les \u00e9lecteurs lib\u00e9raux urbains des &Eacute;tats-Unis souscrivent \u00e0 une plate-forme de maintien de l&rsquo;ordre, qui rappelle implicitement leurs aux Blancs.<\/em><\/p>\n<p>&raquo; <em>Dans un sens, le Pr\u00e9sident Trump se retrouve pris entre marteau et enclume. Si les protestations ne sont pas \u00e9touff\u00e9es et \u00ab\u00a0la normalit\u00e9 courante [non] r\u00e9tablie\u00a0\u00bb (selon les termes de Esper), Trump pourrait perdre les derniers conservateurs partisans de \u00ab\u00a0la loi et l&rsquo;ordre\u00a0\u00bb. Si, au contraire, il perdait le contr\u00f4le de la situation et r\u00e9agissant de fa\u00e7on excessive avec l&rsquo;arm\u00e9e, il pourrait avoir sa propre \u00ab\u00a0Place Tiananmen\u00a0\u00bb que <\/em>[le milliardaire chinois anti-PCC]<em> Jimmy Lai avait pr\u00e9dit avec d\u00e9lice dans le cas de Hong Kong, isolant alors la Chine contre le monde : \u00ab\u00a0Hong Kong serait finie, mais &hellip; la Chine aussi\u00a0\u00bb.<\/em><\/p>\n<p>&raquo; <em>Dans notre cas, on dirait que \u00ab\u00a0Trump pourrait \u00eatre fini, mais&hellip; les &Eacute;tats-Unis aussi\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>C&rsquo;est bien entendu \u00e0 cette derni\u00e8re phrase de conclusion de Crooke que nous allons nous attacher, pour examiner le cas, d\u00e9sormais plus envisageable sinon probable pour certains, d&rsquo;une d\u00e9faite de Trump dans les conditions pr\u00e9sentes. Ces conditions, et notamment les troubles de la Grande-Emeute2020, ne pourraient faire que s&rsquo;amplifier parce que c&rsquo;est de l&rsquo;int\u00e9r\u00eat, \u00e0 c\u00f4t\u00e9 de la quasi-paralysie des r\u00e9publicains, de certains des principaux acteurs, &ndash; notamment les activistes d&rsquo;extr\u00eame-gauche et les Noirs, &ndash; mais aussi les d\u00e9mocrates qui ont leur version \u00e0 eux du \u00ab\u00a0Je suis pris entre marteau et enclume\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">O&ugrave; est Black-L\u00e9nine ?<\/h3>\n<\/p>\n<p><p>Comme le laisse deviner notre conclusion de la partie pr\u00e9c\u00e9dente, nous allons nous attacher \u00e0 l&rsquo;hypoth\u00e8se d&rsquo;une victoire d\u00e9mocrate, puisque c&rsquo;est cette possibilit\u00e9 qui est aujourd&rsquo;hui consid\u00e9r\u00e9e avec s\u00e9rieux. C&rsquo;est aussi et surtout une possibilit\u00e9 qui conduira n\u00e9cessairement \u00e0 un changement&#8230;<\/p>\n<\/p>\n<p><p>Certains commentateurs, et nombre de d\u00e9mocrates bien entendu, jugent qu&rsquo;une victoire d\u00e9mocrate apporterait un tel changement qu&rsquo;on verrait le calme se r\u00e9tablir et les fonctions du pouvoir reprendre leur cours normal dans une Am\u00e9rique r\u00e9g\u00e9n\u00e9r\u00e9e. Nous ne donnons pas de nom ici sinon celui de Trump, c&rsquo;est-\u00e0-dire aucun nom d\u00e9mocrate ; car l&rsquo;\u00e9tat d&rsquo;esprit est tel chez certains de ces commentateurs parmi ces \u00ab\u00a0certains commentateurs\u00a0\u00bb \u00e0 pronostiquer un \u00ab\u00a0lendemain qui chante\u00a0\u00bb, que la seule chose qui compte, le seul fait qui importe n&rsquo;est pas de savoir quel d\u00e9mocrate sera \u00e9lu, et comment, et dans quel sens, etc., &ndash; mais ceci : Trump sera battu, \u00e9limin\u00e9, envoy\u00e9 dans le Trou Noir de l&rsquo;Enfer, et le soleil brillera \u00e0 nouveau.<\/p>\n<\/p>\n<p><p>Cette id\u00e9e implique bien entendu son antinomie enti\u00e8rement bas\u00e9e sur une personne (si Trump est r\u00e9\u00e9lu, le d\u00e9sordre continuera, sinon empirera jusqu&rsquo;\u00e0 la catastrophe, &ndash; ce qui est probablement le cas mais n&rsquo;est pas [n&rsquo;est plus] d&ucirc; \u00e0 Trump au point de d\u00e9sordre que nous avons atteint, o&ugrave; le d\u00e9sordre se nourrit de lui-m\u00eame, devenu l&rsquo;\u00e9v\u00e9nement ma&icirc;tre du Temps) ; cela, cette absence d&rsquo;importance des personnages, parce qu&rsquo;il s&rsquo;agit d&rsquo;abord d&rsquo;une situation, d&rsquo;un \u00e9v\u00e9nement qui est aujourd&rsquo;hui d&rsquo;une puissance si consid\u00e9rable qu&rsquo;il peut s&rsquo;identifier au Temps lui-m\u00eame (&laquo; <em>Le Temps n&rsquo;est plus le temps courant, il est  <a href=\"https:\/\/www.dedefensa.org\/article\/notre-chute-de-lempire\">devenu \u00e9v\u00e9nement pur<\/a> qui fabrique son propre temps<\/em> &#8230; &raquo;).<\/p>\n<\/p>\n<p><p>Dans ce cadre, les acteurs sont compl\u00e8tement contraints par le r\u00f4le qui leur est assign\u00e9 dans la situation de l&rsquo;\u00e9v\u00e9nement. Aucune improvisation n&rsquo;est tol\u00e9r\u00e9e, d&rsquo;ailleurs le r\u00e9sultat serait effroyablement pire que le suivi rigoureux du script. Notre perspective, qui ne devrait pas \u00eatre pris comme une prospective qu&rsquo;elle n&rsquo;est pas puisqu&rsquo;elle n&rsquo;a aucune certitude scientifique et de s&ucirc;ret\u00e9, s&rsquo;attache alors au climat, aux tendances, aux m\u00e9canismes collectifs, \u00e0 l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a> r\u00e9gnant et aux simulacres que tout le monde est oblig\u00e9 de suivre et d&rsquo;accepter dans un grand \u00e9lan de  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>.<\/p>\n<\/p>\n<p><p>Dans ce cadre et dans ce cas, si les d\u00e9mocrates l&#8217;emportent, fussent-ils un Biden flanqu\u00e9 par exemple, surprise consid\u00e9rable, d&rsquo;un <a href=\"https:\/\/www.dedefensa.org\/article\/rapsit-usa2020-trotskisme-utile\">Saint-Barack<\/a> Obama d\u00e9guis\u00e9 en VP, ils seront soumis d\u00e8s l&rsquo;instant de l&rsquo;apoth\u00e9ose \u00e0 des pressions encore plus consid\u00e9rables que celles qui s&rsquo;exercent et s&rsquo;exerceraient sur Trump et sur les r\u00e9publicains. Ils subiront encore plus fortement les caract\u00e8res singuliers des us &#038; coutumes de la Grande R\u00e9publique en \u00e9tat r\u00e9volutionnaire, passant par l&rsquo;existence d&rsquo;une puissance consid\u00e9rable (celle du POTUS\/pr\u00e9sident au sommet) soumis \u00e0 des pouvoirs compl\u00e9mentaires et antagonistes d&rsquo;une extraordinaire capacit\u00e9 de nuisance, r\u00e9duisant sa propre puissance \u00e0 mesure, et encore plus dans la <em>samba <\/em>marxiste-gramciste-racis\u00e9e. Plus encore, bien plus encore quand cette puissance est votre amie !<\/p>\n<\/p>\n<p><p>On parle donc ici de cette foule d&rsquo;associations et groupes plus ou moins clandestins, plus ou moins parasites, plus ou moins  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivistes<\/a>, plus ou moins proclamatoires, plus ou moins corrompus, plus ou moins manipul\u00e9s, &ndash; les BLM, les <em>Antifas<\/em>, ceux de l&rsquo;<em>Open Society <\/em>(marque Soros d\u00e9pos\u00e9e), les LGTBQ [VWX], les CHOP et autres \u00ab\u00a0<em>Autonomous Zone<\/em>\u00a0\u00bb ou \u00ab\u00a0<em>Occupied Protest<\/em>\u00ab\u00a0. Tous seront \u00e0 l&rsquo;assaut, r\u00e9clamant, proclamant, occupant, rench\u00e9rissant et radicalisant. La presseSyst\u00e8me se fera un plaisir de professionnel bien huil\u00e9 de la d\u00e9lation \u00e9l\u00e9gante de Park Avenue de tresser des couronnes d&rsquo;\u00e9pines christiques \u00e0 tous ces jeunes gens r\u00e9volutionnaires. Qui suit la rigueur intuitive de l&rsquo;\u00e9v\u00e9nement les voit et les entend d&rsquo;ici, haut et fort, en pleine extase de rapine des pouvoirs puisque leurs hommes et leurs femmes sont au pouvoir.<\/p>\n<\/p>\n<p><p>Cela peut aller loin ! Jusqu&rsquo;o&ugrave;, apr\u00e8s tout ? Jusqu&rsquo;\u00e0 ce que les d\u00e9mocrates au pouvoir ordonnent \u00e0 l&rsquo;arm\u00e9e d&rsquo;intervenir dans telle et telle cit\u00e9 ? Et que fera le Pentagone ? Emprisonner le nouveau pr\u00e9sident ou l&rsquo;hospitaliser vu son \u00e9tat, ou bien monnayer sa mission (\u00ab\u00a0Augmentez le budget du Pentagone de 25% et nous intervenons dans une ville\u00a0\u00bb) ?<\/p>\n<\/p>\n<p><p>Enfin&#8230; Croit-on \u00eatre, rien que cela, dans une structure si superbe et sublime qu&rsquo;elle se d\u00e9forme pour absorber les cahots, pour aussit\u00f4t se reformer, plus puissante et organis\u00e9e qu&rsquo;auparavant ? Non, la souplesse n&rsquo;est pas son fort, non plus que l&rsquo;ordre intelligent. N&rsquo;a-t-on pas remarqu\u00e9 que la Grande R\u00e9publique est devenue un \u00e9norme Barnum, et croit-on alors qu&rsquo;il suffirait d&rsquo;un clown en moins, f&ucirc;t-ce le pr\u00e9sident Trump lui-m\u00eame, pour que les rangs se reforment et qu&rsquo;on ne voit plus qu&rsquo;une seule t\u00eate ? Encore n&rsquo;a-t-on pas envisag\u00e9 le pire, qui est tout proche de nous dans l&rsquo;hypoth\u00e8se qu&rsquo;on \u00e9voque de la victoire d\u00e9mocrate.<\/p>\n<\/p>\n<p><p>Franklin Delano Roosevelt fut \u00e9lu le premier mardi de novembre 1932, battant le pr\u00e9sident sortant Hoover. Le programme de FDR \u00e9tait pr\u00e9sent\u00e9 comme une rupture radicale par rapport \u00e0 la politique de Hoover, alors qu&rsquo;on se trouvait au bord du gouffre du fond de l&rsquo;abysse de la Grande D\u00e9pression. FDR \u00e9lu, il lui fallait attendre le d\u00e9but mars 1933 pour prendre ses fonctions, pendant que son pr\u00e9d\u00e9cesseur continuait \u00e0 assumer les pleins pouvoirs du pr\u00e9sident. Bien entendu, Hoover continua sa politique, FDR se gardant bien d&rsquo;intervenir, par ailleurs occup\u00e9 \u00e0 \u00e9viter les balles puisqu&rsquo;une tentative d&rsquo;assassinat eut lieu contre lui en janvier 1933. Quand FDR prit le pouvoir, l&rsquo;Am\u00e9rique s&rsquo;\u00e9tait compl\u00e8tement effondr\u00e9e par rapport \u00e0 novembre 1932, au bord de la d\u00e9sagr\u00e9gation, de la fin d&rsquo;une civilisation. (*) La premi\u00e8re mesure que prit le nouveau pr\u00e9sident, quatre heures apr\u00e8s son inauguration et apr\u00e8s \u00eatre pass\u00e9 par l&rsquo;\u00e9glise pour prier pour le salut de la Grande R\u00e9publique avec ses ministres, fut d&rsquo;ordonner la fermeture de toutes les banques du pays.<\/p>\n<\/p>\n<p><p>C&rsquo;est cette \u00e9pisode qui poussa le pouvoir am\u00e9ricaniste \u00e0 modifier aussit\u00f4t dans la Constitution sacr\u00e9e et intouchable \u00e0 part les innombrables amendements, le d\u00e9lai du transfert du pouvoir, le raccourcissant de mars \u00e0 janvier de l&rsquo;ann\u00e9e suivant l&rsquo;\u00e9lection. Cela laisse tout de m\u00eame deux mois pendant lesquels le pouvoir est dans les mains d&rsquo;un homme, &ndash; pour le cas qui nous occupe, &ndash; qui a \u00e9t\u00e9 d\u00e9savou\u00e9 par l&rsquo;\u00e9lectorat. Quand nous sommes hors-crise, c&rsquo;est-\u00e0-dire \u00ab\u00a0hors-sol\u00a0\u00bb pour les salons, dans le consensus bipartisan qui est l&rsquo;essence m\u00eame de ce regime, aucun probl\u00e8me qui peut faire t\u00e2che sur l&rsquo;\u00e9l\u00e9gant costume ne se pose ; on reste polis, on se tape dans le dos, on s&#8217;embrasse malgr\u00e9 Covid19, on se sourit et ainsi de suite. Mais quand le pouvoir se transmet dans l&rsquo;antagonisme (FDR-Hoover), et m\u00eame dans l&rsquo;antagonisme surcharg\u00e9 d&rsquo;une haine hyst\u00e9rique et terrible jusqu&rsquo;\u00e0 l&rsquo;explosion nucl\u00e9aire de la psychologie (Trump et son rempla\u00e7ant d\u00e9mocrate dans le cas explor\u00e9) ? <\/p>\n<\/p>\n<p><p>Cela laisse \u00e0 pense de quoi serait fait l&rsquo;interr\u00e8gne dans de telles conditions. La perspective est vertigineuse, la prospective impossible \u00e0 faire parce que la science se m\u00e9fie des vertiges. On aurait tendance \u00e0 envisager, en r\u00e9f\u00e9rence \u00e0 l&rsquo;extraordinaire l\u00e2chet\u00e9-couarde assaisonn\u00e9e de grossi\u00e8re d\u00e9magogie montr\u00e9e par les diff\u00e9rents pouvoirs d\u00e9mocrates confront\u00e9s aux protestations-\u00e9meutes dans la plupart des cas graves, une l\u00e2chet\u00e9-couarde assaisonn\u00e9e de grossi\u00e8re d\u00e9magogie venue du m\u00eame fournisseur. Le r\u00e9sultat serait une implantation consid\u00e9rable des mouvements extr\u00e9mistes, directement ou par le biais des pouvoirs locaux et r\u00e9gionaux qu&rsquo;ils tiendraient par le chantage au Politiquement-Correct (PC) qui semble l&rsquo;arme de d\u00e9structuration massive de notre \u00e9poque toute enti\u00e8re investie par la communication.<\/p>\n<\/p>\n<p><p>(Et encore, dans une telle perspective, n&rsquo;envisage-t-on pas ce qui pourrait se passer du c\u00f4t\u00e9 de Trump, &ndash; trop insaisissable et sans doute soucieux de sauver ses $milliards, &ndash; et surtout de ceux qui ont suivi Trump pour mieux se sentir trahi et cocu par leur POTUS-<a href=\"https:\/\/www.dedefensa.org\/article\/une-election-entre-survie-et-cocktail-molotov\">cocktail-Molotov<\/a>.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Et alors, et ensuite ? Les d\u00e9mocrates auraient accouch\u00e9 d&rsquo;un Kerenski qui ferait le lit de la R\u00e9volution ? Nous referaient-ils le coup d&rsquo;octobre 17, version postmoderne et pleine  de surprises hollywoodiennes de <em>l&rsquo;American<\/em>Dream ? Cela est loin d&rsquo;\u00eatre assur\u00e9, car nous cherchons en vain un L\u00e9nine, f&ucirc;t-il un L\u00e9nine-noir, \u00e0 l&rsquo;heure o&ugrave; plus aucun dirigeant africain-am\u00e9ricain, d\u00e9sormais habitu\u00e9 \u00e0 la bonne vieille corruption des \u00ab\u00a0<em>privilegied Whites people<\/em>\u00ab\u00a0, n&rsquo;arrive \u00e0 la cheville d&rsquo;un Malcolm X ou d&rsquo;un Docteur King. Mais pour nous, l&rsquo;important dans cette perspective qui n&rsquo;est pas une prospective, c&rsquo;est qu&rsquo;elle va, elle aussi certes comme les autres hypoth\u00e8ses envisag\u00e9es, dans le sens de l&rsquo;acc\u00e9l\u00e9ration constante de la  <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GCES<\/a>. Comme \u00e9crit \u00e9galement Alastair dans son texte cit\u00e9, mais lui \u00e0 propos des perspectives mon\u00e9taires et financi\u00e8res aux USA (ce destin fatal est pour tous les domaines) : &laquo; <em>C&rsquo;est-\u00e0-dire que la R\u00e9volution peut venir de l&rsquo;int\u00e9rieur, &ndash; et pas n\u00e9cessairement de l&rsquo;\u00e9tranger<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Pour le reste, il faut garder toute sa confiance, toute sa \u00ab\u00a0foi\u00a0\u00bb. Il faut relire ce livre de circonstance et d&rsquo;une sublime acuit\u00e9 de notre grand Joseph de Maistre, &ndash; ses &lsquo;<em>Consid\u00e9rations sur la France<\/em>&lsquo;, qui nous donnent en 1796 des appr\u00e9ciations sur la R\u00e9volution Fran\u00e7aise qui n&rsquo;ont pas pris une ride&#8230; Tout ce qu&rsquo;il dit pourrait s&rsquo;adapter \u00e0 ce qui est en route aux USA, lui qui savait les connivences entre l&rsquo;Histoire et la providence. Quelques mots du comte Joseph pour clore la r\u00e9flexion du jour sur ce qui est \u00ab\u00a0le centre de tout et la matrice\u00a0\u00bb de tout ce qui s&rsquo;op\u00e9rationnalise \u00e0 partir de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>&bull; Sur l&rsquo;\u00e9v\u00e9nement m\u00e9tahistorique que fut la R\u00e9volution Fran\u00e7aise, comme l&rsquo;est notre GCES aujourd&rsquo;hui, concentr\u00e9e sur l&rsquo;Am\u00e9rique : &laquo; <em>Mais la r\u00e9volution fran\u00e7aise, et tout ce qui se passe en Europe dans ce moment, est tout aussi merveilleux que la fructification instantan\u00e9e d&rsquo;un arbre au mois de janvier ; cependant les hommes, au lieu d&rsquo;admirer, regardent ailleurs ou d\u00e9raisonnent.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>&bull; Sur les r\u00e9volutionnaires maintenant, ceux qui croient faire l&rsquo;\u00e9v\u00e8nement (ils sont si nombreux dans notre \u00e9poque de communication) et qui sont les \u00ab\u00a0idiots utiles\u00a0\u00bb, les figurants plus ou moins habiles, d&rsquo;un \u00e9v\u00e9nement qui les d\u00e9passe et qui les d\u00e9vorera gloutonnement, mais sans y prendre garde, quand leur heure sera venue : &laquo; <em>On a remarqu\u00e9, avec grande raison, que la r\u00e9volution fran\u00e7aise m\u00e8ne les hommes plus que les hommes ne la m\u00e8nent. Cette observation est de la plus grande justesse&#8230;<\/em>[&#8230;] <em>Les sc\u00e9l\u00e9rats m\u00eames qui paraissent conduire la r\u00e9volution, n&rsquo;y entrent que comme de simples instruments ; et d\u00e8s qu&rsquo;ils ont la pr\u00e9tention de la dominer, ils tombent ignoblement.<\/em> &raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Note<\/h2>\n<\/p>\n<p><p>(*) Voir dans <em>&lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/cannes-au-soleil-noir-de-la-beat-generation\">Le soleil noir<\/a> de la Beat Generation&rsquo;<\/em>, un long passage (Chapitre 2) consacr\u00e9 \u00e0 la Grande D\u00e9pression&#8230; Ceci, pour donner le ton et la couleur de l&rsquo;\u00e9poque \u00e9voqu\u00e9e dans le passage qui prend cette note pour r\u00e9f\u00e9rence : &laquo; <em>En septembre 1933, le Fran\u00e7ais Andr\u00e9 Maurois, retour d&rsquo;un s\u00e9jour l\u00e0-bas, rapportait ces remarques dans ses &lsquo;Chantiers am\u00e9ricains&rsquo; : \u00ab\u00a0Si vous aviez fait le voyage vers la fin de l&rsquo;hiver (1932-33), vous auriez trouv\u00e9 un peuple compl\u00e8tement d\u00e9sesp\u00e9r\u00e9. Pendant quelques semaines, l&rsquo;Am\u00e9rique a cru que la fin d&rsquo;un syst\u00e8me, d&rsquo;une civilisation, \u00e9tait tout proche.\u00a0\u00bb<\/em> &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En attendant le POTUS-Kerenski 17 juin 2020 &ndash; Nous l&rsquo;avons d\u00e9j\u00e0 dit \u00e0 plusieurs reprises et le r\u00e9p\u00e9tons en guise d&rsquo;introduction, avant de revenir plus loin sur le th\u00e8me d&rsquo;une autre fa\u00e7on, nous estimons bien entendu que, dans la crise globale qui secoue cette ann\u00e9e 2020 entre Covid19 et ses suites \u00e9conomiques-catastrophiques, et ce que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2664,8138,6917,1235,17431,17879,2665,3009,3083,3184,13053,4481,2891,19927,7745,12582,8624,19948],"class_list":["post-79307","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-alastair","tag-antiracisme","tag-beat","tag-biden","tag-blm","tag-covid19","tag-crooke","tag-democrates","tag-depression","tag-fdr","tag-gces","tag-generation","tag-grande","tag-grande-emeute2020","tag-malic","tag-progressistes-societaux","tag-seattle","tag-sheppard"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79307"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79307\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}