{"id":79331,"date":"2020-07-06T15:29:38","date_gmt":"2020-07-06T15:29:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/06\/zombification-pc-par-le-haut\/"},"modified":"2020-07-06T15:29:38","modified_gmt":"2020-07-06T15:29:38","slug":"zombification-pc-par-le-haut","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2020\/07\/06\/zombification-pc-par-le-haut\/","title":{"rendered":"Zombification-PC \u00a0par le haut"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Zombification-PC  par le haut<\/h2>\n<\/p>\n<p><p>Depuis pas mal d&rsquo;ann\u00e9es s&rsquo;agitent les questions autour de l&rsquo;intelligence artificielle (AI), avec des compl\u00e9ments pr\u00e9occup\u00e9s sur la \u00ab\u00a0robotisation\u00a0\u00bb, etc. ; tout cela conduisant \u00e0 de graves interrogations sur le sort de l&rsquo;homme (ou l&rsquo;Homme ? J&rsquo;h\u00e9site), son libre-arbitre, sa libert\u00e9, la d\u00e9mocratie, nos avanc\u00e9es culturelles ; tout cela (<em>bis<\/em>) menac\u00e9 par l&rsquo;irruption d&rsquo;une machinerie \u00e0 pr\u00e9tention quasi-divine, \u00ab\u00a0issue de nos entrailles\u00a0\u00bb mais pour nous d\u00e9vorer. La machine-Dieu d\u00e9vorant l&rsquo;homme-Dieu qui en a accouch\u00e9, et au-del\u00e0 la manufacture terrible de l&rsquo;atroce \u00ab\u00a0zombification\u00a0\u00bb de l&rsquo;homme, sa si vaste intelligence soumise par cette force devenue ext\u00e9rieure, &ndash; l&rsquo;homme-zombifi\u00e9, et bien selon le sens et \u00e0 l&rsquo;image du titre que Jean-Fran\u00e7ois Mattei donna \u00e0 son dernier livre, publi\u00e9 apr\u00e8s sa mort, &ndash;  &laquo; <em>L&rsquo;homme d\u00e9vast\u00e9<\/em> &raquo;, et ceci \u00e9quivalant \u00e0 cela.<\/p>\n<\/p>\n<p><p>Vaste d\u00e9bat que celui de l&rsquo;IA, et nous nous y sommes mis il y a d\u00e9j\u00e0 longtemps, tout \u00e0 nos fr\u00e9tillantes et angoiss\u00e9es interrogations&#8230; En attendant, il m&rsquo;est venu l&rsquo;impression que, pendant que nous d\u00e9battions, la chose a d\u00e9j\u00e0 \u00e9t\u00e9 tranch\u00e9e, je veux dire pour l'\u00a0\u00bbhomme-zombifi\u00e9\u00a0\u00bb, et plut\u00f4t subrepticement, sans vraiment avertir son monde et surtout sans d\u00e9bat superflu. Nous craignions l&rsquo;IA, c&rsquo;est le PC qui survient et rafle la mise, je veux dire le PC-zombificateur.<\/p>\n<\/p>\n<p><p>PC, on le sait, vaut pour &lsquo;Politiquement Correct&rsquo;, expression dont l&#8217;emploi courant remonte aux premi\u00e8res ann\u00e9es 1980. D&rsquo;autres expressions sont employ\u00e9es, comme \u00ab\u00a0police de la pens\u00e9e\u00a0\u00bb, des choses de ce genre. On a compris ce dont je veux parler. Ce n&rsquo;est pas de l\u00a0\u00bbOrwellisme&rsquo; (de George Orwell) m\u00eame si cela para&icirc;t bien-orwellien dans l&rsquo;esprit de la chose ; parce que ce n&rsquo;est pas syst\u00e9matiquement ni n\u00e9cessairement l&rsquo;inversion en toutes choses (&lsquo;Mensonge = V\u00e9rit\u00e9&rsquo;, &lsquo;Guerre = Paix&rsquo;, etc.). C&rsquo;est une unification extraordinairement r\u00e9ductrice du langage et de la pens\u00e9e selon une tendance au Plus Petit Commun D\u00e9nominateur de la complexit\u00e9 et de la nuance, selon un d\u00e9cha&icirc;nement de l&rsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-laffectivisme-postmoderne\">affectivisme<\/a>, de la moraline, de la bienpensance selon des th\u00e8mes archi-connus et archi-rebattus qui sont d\u00e9velopp\u00e9s pour favoriser la modernit\u00e9 et la position du Syst\u00e8me dans toute sa majest\u00e9.<\/p>\n<\/p>\n<p><p>Je pense que l&rsquo;entreprise (le PC devenue zombificateur) est entr\u00e9e dans sa phase active\/d\u00e9cisive avec la Syrie et surtout d\u00e9cisive avec l&rsquo;Ukraine. (Voir pour l&rsquo;historique et le d\u00e9veloppement analytique les concepts dans notre <em>Glossaire.dde<\/em>, de \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a>\u00a0\u00bb et \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>\u00ab\u00a0.) Bien entendu, &ndash; et cela aussi a \u00e9t\u00e9 souvent \u00e9crit ici, dans ces colonnes, &ndash; le concept de r\u00e9alit\u00e9 est pulv\u00e9ris\u00e9e, comme l&rsquo;ambition sinon l&rsquo;espoir de toute objectivation ; et la &lsquo;V\u00e9rit\u00e9&rsquo;, autre concept mis \u00e0 l&rsquo;index, demande d\u00e9sormais une enqu\u00eate permanente pour \u00eatre reconstitu\u00e9e (par les v\u00e9rit\u00e9s-de-situation \u00e0 d\u00e9terminer), et ce travail devant \u00eatre effectu\u00e9 et cela dans une semi-clandestinit\u00e9, quasiment comme dans le <em><a href=\"https:\/\/www.abebooks.fr\/rechercher-livre\/titre\/m%E9moires-%E9crits-souterrain\/auteur\/dostoievski\/\">souterrain<\/a> <\/em>de Dosto\u00efevski<em>.<\/em><\/p>\n<\/p>\n<p><p>Le PC a \u00e9volu\u00e9 \u00e0 grande allure, sans reprendre son souffle, en pleine extension de surpuissance et sous les applaudissements des \u00e9litesSyst\u00e8me. Il n&rsquo;a l\u00e9sin\u00e9 sur rien, pour survenir avec des effets d\u00e9vastateurs dans les crises (plusieurs) ouvertes avec celle de Covid19, bient\u00f4t renforc\u00e9e par ce qu&rsquo;on nomme dans notre langage cod\u00e9-pour-les-amis &lsquo;Grande-Emeute2020&rsquo; (aux USA et un peu dans le reste, avec BLM apr\u00e8s la mort du 25 mai de George Floyd). Ces deux crises, avec leurs divers appendices, \u00e9taient effectivement le terrain r\u00eav\u00e9 pour le d\u00e9veloppement universel du PC, pour son affirmation totalitaire. Cela fut fait, avec une maestria \u00e0 ne pas croire&#8230;<\/p>\n<\/p>\n<p><p>Mais encore et pour en venir, par le biais du paradoxe \u00e0 mon argument majeur&#8230; Cela fut trop bien fait !<\/p>\n<\/p>\n<p><p>Je veux dire par l\u00e0 que le PC trouva une si vaste \u00e9tendue de la non-pens\u00e9e et de la description-faussaire \u00e0 se mettre sous la dent, pour une exploitation intensive, qu&rsquo;il se mit \u00e0 tourner fou comme des piranhas qui se disputent une proie. Peut-\u00eatre le Politiquement-Correct a-t-il atteint, lui aussi et d&rsquo;ailleurs en toute logique identitaire vu ses liens avec la Modernit\u00e9, son &lsquo;<a href=\"https:\/\/www.dedefensa.org\/article\/la-modernite-en-son-principe-de-peter\">principe de Peter<\/a>&lsquo; ? Toujours est-il que, dans ce d\u00e9cha&icirc;nement de bienpensance et de police de la pens\u00e9e (contre les \u00ab\u00a0brutalit\u00e9s polici\u00e8res\u00a0\u00bb, par exemple), l&rsquo;on vit le PC se d\u00e9velopper jusqu&rsquo;\u00e0 des extr\u00eames inimaginables, avec des affrontements chez ceux-l\u00e0 m\u00eame qui devraient \u00eatre les gardiens vigilants du PC.<\/p>\n<\/p>\n<p><p>(Imaginez l&rsquo;effet que produisit, aux tr\u00e9fonds de nous-m\u00eames et de tous les autres, braves petits soldats du Politiquement Correct de la Science et admirateurs humbles des \u00ab\u00a0sachants\u00a0\u00bb, les cr\u00eapages de chignon entre les sommit\u00e9s, les professeurs, les sp\u00e9cialistes, les pontifiants poseurs de diagnostic&#8230; Malgr\u00e9 le PC, ou plut\u00f4t avec lui apr\u00e8s tout, l&rsquo;entra&icirc;nement vers les radicalisations fut irr\u00e9sistible, dans cette d\u00e9bauche d&rsquo;affectivisme peinturlur\u00e9e en Raison-raisonnante comme un tambour.)<\/p>\n<\/p>\n<p><p>Or, beaucoup de monde, dans le troupeau habituel de l&rsquo;homme-zombifi\u00e9, ne supporte pas cela ; il faut un peu de mod\u00e9ration, au moins dans la forme, dans cette entreprise de n\u00e9antissement de la pens\u00e9e ; il faut n\u00e9antir, certes, mais sans brutalit\u00e9, que cela ne fasse pas trop mal et que cela ne fasse pas de t\u00e2ches. L&rsquo;homme moderne, <em>homo-festivus <\/em>et affectiviste-passionn\u00e9, entend ne pas \u00eatre trop bouscul\u00e9, et tout l&rsquo;art du PC est justement d&rsquo;offrir le confort dans la zombification. Eh bien, je trouve que ce n&rsquo;est pas du tout le cas, que c&rsquo;est m\u00eame un bien grave \u00e9chec.<\/p>\n<\/p>\n<p><p>Les multiples complots en marche aujourd&rsquo;hui, &ndash; innombrables, je vous l&rsquo;assure, et la plupart d&rsquo;entre eux sinon tous dans le mode zombificateur-PC, &ndash; se t\u00e9lescopent et souvent se contredisent, conduisant \u00e0 un d\u00e9sordre consid\u00e9rable et \u00e0 une fatigue bien inutile et d\u00e9plorable. Bien qu&rsquo;il en soit le cause mais qu&rsquo;il n&rsquo;est pas \u00e0 une contradiction pr\u00e8s, le PC n&rsquo;aime pas le d\u00e9sordre et l&rsquo;homme-zombifi\u00e9 est un homme d&rsquo;ordre.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ainsi est-ce juste au moment o&ugrave; l&rsquo;on peut mesurer la prodigieuse puissance du PC, son action subversive quasiment totalitaire que nul ne peut arr\u00eater, sa fa\u00e7on magistrale d&rsquo;anesth\u00e9sier les esprits et de fabriquer des simulacres \u00e0 la cha&icirc;ne, qu&rsquo;on mesure en m\u00eame temps et d&rsquo;une fa\u00e7on brutale ses limites, pouvant aller jusqu&rsquo;\u00e0 la catastrophe d&rsquo;une sorte de paralysie et d&rsquo;impuissance, avec n\u00e9antissement de son programme. En effet, cette radicalisation d\u00e9sordonn\u00e9e, qui semble menacer cette construction-PC mise en place ces derni\u00e8res ann\u00e9es, de mensonges en simulacres et de simulacres en manipulations, ce sont les hommes-zombifi\u00e9s eux-m\u00eames qui la m\u00e8nent au pas de charge ; et plus encore que les \u00ab\u00a0hommes-zombifi\u00e9s\u00a0\u00bb, car il faut \u00eatre pr\u00e9cis : ce sont les \u00e9litesSyst\u00e8me qui emm\u00e8nent ce mouvement, comme c&rsquo;est normal. Ce sont donc elles, les \u00e9litesSyst\u00e8me, qui permettent et favorisent cette radicalisation, et cela par contre est beaucoup moins normal. Les \u00e9litesSyst\u00e8me deviennent donc \u00e9lites-zombifi\u00e9es, responsables du d\u00e9sordre ainsi cr\u00e9\u00e9, qu&rsquo;on peut donc appr\u00e9cier comme des irresponsables.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les escouades-PC, brandissant les slogans de la bienpensance sous les applaudissements prudents du Syst\u00e8me incertain de l&rsquo;issue du mon\u00f4me, s&#8217;emportent de z\u00e8le et foncent vers le <em>tabula rasa <\/em>des r\u00e9volutionnaires du monde entier. Ils ne voient pas l&rsquo;encha&icirc;nement de cause \u00e0 effet, alors que le Syst\u00e8me ne le r\u00e9alise pas encore, puisque les structures du Syst\u00e8me qui compte nous domestiquer fa\u00e7on-IA, sont pos\u00e9es sur la table, et donc promise \u00e0 \u00eatre emport\u00e9es, balay\u00e9es, etc.<\/p>\n<\/p>\n<p><p>Le PC est \u00e9videmment la plus grande entreprise de subversion de l&rsquo;homme de toute son histoire. Elle se fait essentiellement par la communication, l&rsquo;\u00e9crit et l&rsquo;image, le \u00ab\u00a0spectacle\u00a0\u00bb comme dit l&rsquo;autre parce que c&rsquo;est le simulacre de champ de bataille qu&rsquo;a choisi le Syst\u00e8me. Tout \u00e9tait pr\u00eat pour la future IA et puis c&rsquo;est le PC, \u00e9chappant \u00e0 tout contr\u00f4le, qui s&rsquo;est impos\u00e9 comme instrument ultime. On r\u00e9alisera bient\u00f4t, un jour, mais pour moi cela ne fait aucun doute, que si le PC peut jouer ce r\u00f4le de zombification de l&rsquo;homme, il risque de le rendre fou en m\u00eame temps, et si ce n&rsquo;est d\u00e9j\u00e0 fait pour beaucoup d&rsquo;entre nous.<\/p>\n<\/p>\n<p><p>Le PC agit effectivement sur le domaine de la psychologie, qu&rsquo;il adresse, qu&rsquo;il contraint, qu&rsquo;il force et viole, et c&rsquo;est ainsi que la folie vient ; et par cons\u00e9quent, tous les errements, les incompr\u00e9hensions, les erreurs, toutes ces choses que favorise une psychologie \u00ab\u00a0d\u00e9vast\u00e9e\u00a0\u00bb, \u00ab\u00a0zombifi\u00e9e\u00a0\u00bb. Le summum de l&rsquo;ironie dans cette occurrence, c&rsquo;est bien entendu que les \u00e9litesSyst\u00e8me sont les premi\u00e8res touch\u00e9es, les premi\u00e8res zombifi\u00e9es, elles dont la mission \u00e9tait de mener \u00e0 bien la zombification du vulgaire <em>sapiens-sapiens.<\/em><\/p>\n<\/p>\n<p><p>Et quand viendra l&rsquo;IA, elle sera mise sous la censure radicale du PC, et tous les deux se battront en un \u00ab\u00a0combat de chiens\u00a0\u00bb (<em>dogfight<\/em>)  comme des zombies <em>devenus<\/em> fous. Ils en mourront. Nous irons les enterrer joyeusement, comme \u00e0 La Nouvelle Orl\u00e9ans d&rsquo;antan, en swinguant <em>Oh When the Saints Go Marchin&rsquo; in&#8230;<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zombification-PC par le haut Depuis pas mal d&rsquo;ann\u00e9es s&rsquo;agitent les questions autour de l&rsquo;intelligence artificielle (AI), avec des compl\u00e9ments pr\u00e9occup\u00e9s sur la \u00ab\u00a0robotisation\u00a0\u00bb, etc. ; tout cela conduisant \u00e0 de graves interrogations sur le sort de l&rsquo;homme (ou l&rsquo;Homme ? J&rsquo;h\u00e9site), son libre-arbitre, sa libert\u00e9, la d\u00e9mocratie, nos avanc\u00e9es culturelles ; tout cela (bis) menac\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[12153,17879,20011,13828,19927,18234,4008,3341,12652,19426,14083],"class_list":["post-79331","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-artificielle","tag-covid19","tag-elites-zombie","tag-elitessysteme","tag-grande-emeute2020","tag-ia","tag-intelligence","tag-orwell","tag-pc","tag-politiquement-correct","tag-zombification"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=79331"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/79331\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=79331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=79331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=79331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}